{"id":9884,"date":"2022-10-26T17:32:00","date_gmt":"2022-10-26T16:32:00","guid":{"rendered":"https:\/\/legrandcontinent.eu\/es\/?p=9884"},"modified":"2022-10-27T10:34:45","modified_gmt":"2022-10-27T09:34:45","slug":"giorgia-meloni-sateliza-a-sus-socios-de-gobierno","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/es\/2022\/10\/26\/giorgia-meloni-sateliza-a-sus-socios-de-gobierno\/","title":{"rendered":"Giorgia Meloni sateliza a sus socios de gobierno"},"content":{"rendered":"\n<p class=\"has-drop-cap\"><a href=\"https:\/\/legrandcontinent.eu\/es\/2022\/10\/22\/el-nuevo-gobierno-italiano\/\">El nuevo gobierno italiano<\/a> es m\u00e1s equilibrado de lo que parece. Giorgia Meloni y Fratelli d&#8217;Italia contaban con pocos candidatos de alto nivel para posicionarse como ministros. Favoreci\u00f3 la seguridad y evit\u00f3 nombrar a aficionados para no correr riesgos pol\u00edticos en un momento en que su gobierno est\u00e1 siendo evaluado por la comunidad internacional, en medio de una crisis energ\u00e9tica.<\/p>\n\n\n\n<p>Adem\u00e1s, Giorgia Meloni ha conseguido relegar a Matteo Salvini a un ministerio donde deber\u00eda estar tranquilo: el de Infraestructuras y Movilidad Sostenible. Mejor a\u00fan, ha conseguido el nombramiento de Giancarlo Giorgetti, la b\u00eate noire de Salvini dentro de la Lega. Giorgetti representa el ala institucional y gubernamental de la Liga, m\u00e1s \u00abcentrista\u00bb y liberal. Al situar a Giorgetti en el Ministerio de Finanzas, Meloni apuesta por neutralizar a la Lega. Para ello, sin embargo, tuvo que pagar un alto precio al asignar el Ministerio del Interior a Matteo Piantedosi, un estrecho colaborador de Salvini.<\/p>\n\n\n\n<p>Encauzar la Lega y redimensionar pol\u00edticamente el partido era un objetivo prioritario para Giorgia Meloni. Parad\u00f3jicamente, son Forza Italia y Silvio Berlusconi los que m\u00e1s han molestado en las \u00faltimas semanas, sobre todo por las declaraciones pro-Putin del Cavaliere. Forza Italia consigue pocos puestos de alto nivel, aparte del de Asuntos Exteriores, con la nominaci\u00f3n de Antonio Tajani, que ha hecho muchas promesas sobre Ucrania y la integraci\u00f3n atl\u00e1ntica. Esta escasa representaci\u00f3n de FI en puestos importantes es un riesgo para Giorgia Meloni, que sin embargo parece estar m\u00e1s segura de sus relaciones con este partido que con la Liga.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Encauzar la Lega y redimensionar pol\u00edticamente el partido era un objetivo prioritario para Giorgia Meloni.<\/p><cite>JEAN-YVES DORMAGEN<\/cite><\/blockquote><\/figure>\n\n\n\n<p>En cualquier caso, la nueva Presidenta del Consejo se ha asegurado el nombramiento de leales para puestos clave: Adolfo Urso para negocios y Made in Italy; Guido Crosetto para Defensa y Carlo Nordio para Justicia. Estos tres perfiles superiores tienen la funci\u00f3n de tranquilizar a los socios europeos e internacionales. Crosetto fue subsecretario de Defensa entre 2008 y 2011; Urso tiene fuertes v\u00ednculos con los republicanos estadounidenses y est\u00e1 involucrado en las relaciones con los servicios secretos; en cuanto a Nordio, es un magistrado con una larga carrera a sus espaldas que investig\u00f3, entre otras cosas, sobre <em>Tangentopoli<\/em>, los mecanismos de financiaci\u00f3n ilegal de la Democracia Cristiana en los a\u00f1os 1990.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Una prioridad a nivel internacional: evitar el ostracismo y tranquilizar a los mercados<\/h2>\n\n\n\n<p>Por el momento, la apuesta de Giorgia Meloni parece estar funcionando. La prensa internacional se muestra algo esc\u00e9ptica, pero esto parece tener la funci\u00f3n de empujar al gobierno a la moderaci\u00f3n. En cualquier caso, parece claro que la carga medi\u00e1tica es mucho menos violenta que cuando se form\u00f3 el gobierno M5S-Lega en el verano de 2018. Giorgia Meloni tambi\u00e9n se est\u00e1 beneficiando de la actitud cooperativa de Mario Draghi, que est\u00e1 facilitando sus esfuerzos de normalizaci\u00f3n. Hasta ahora, el ex presidente del BCE se ha mostrado muy complaciente. Ha hecho la transici\u00f3n sin problemas, lo que ha tendido a calmar a los mercados. Por otro lado, Giorgia Meloni impuso una dieta medi\u00e1tica a sus tropas tras las elecciones. Por lo tanto, busc\u00f3 met\u00f3dicamente reducir los \u00e1ngulos de ataque de la prensa nacional e internacional.<\/p>\n\n\n\n<p>Cabe destacar que un n\u00famero no despreciable de ministros llamados \u00abt\u00e9cnicos\u00bb env\u00eda una se\u00f1al de moderaci\u00f3n y de voluntad de dar una fuerte dimensi\u00f3n tecnocr\u00e1tica a una agenda pol\u00edtica inicialmente te\u00f1ida de soberan\u00eda. Como s\u00edmbolo de continuidad, Roberto Cingolani, antiguo ministro de Energ\u00eda del Gobierno de Draghi, vuelve como \u00abasesor\u00bb en temas energ\u00e9ticos de la Presidenta del Consejo y del nuevo ministro de Energ\u00eda, Gilberto Pichetto Fachin, de Forza Italia. Preciso es notar que el 58% de los miembros del gobierno proceden del noroeste y noreste del pa\u00eds.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/YiqaS\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>La distribuci\u00f3n est\u00e1 especialmente desequilibrada. Algunos t\u00edtulos ministeriales tambi\u00e9n han cambiado significativamente: soberan\u00eda alimentaria, Made in Italy, natalidad. Un ejemplo interesante es el cambio de \u00abtransici\u00f3n energ\u00e9tica\u00bb a \u00abseguridad energ\u00e9tica\u00bb. Aunque se trata ciertamente de una simple estrategia de comunicaci\u00f3n, estas nuevas etiquetas env\u00edan un mensaje: el gobierno tiene una agenda nacionalista. El tiempo dir\u00e1 si se trata de puros trucos de comunicaci\u00f3n. No olvidemos que el margen de maniobra del Gobierno es especialmente estrecho en el frente econ\u00f3mico, que es una prioridad absoluta en <a href=\"https:\/\/legrandcontinent.eu\/es\/2022\/10\/11\/italia-y-alemania-entraran-en-recesion-en-2023-segun-el-fmi\/\">el contexto de incertidumbre actual<\/a>.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>No olvidemos que el margen de maniobra del Gobierno es especialmente estrecho en el frente econ\u00f3mico, que es una prioridad absoluta en el contexto de incertidumbre actual.<\/p><cite>JEAN-YVES DORMAGEN<\/cite><\/blockquote><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Desaf\u00edos y perspectivas para el gobierno de Meloni<\/h2>\n\n\n\n<p>Aparte del presupuesto y de la renegociaci\u00f3n del plan de recuperaci\u00f3n europeo, la crisis energ\u00e9tica representa sin duda un reto importante para el gobierno de Meloni: la pen\u00ednsula depende especialmente de su suministro de gas. Su econom\u00eda lleva dos d\u00e9cadas estancada en t\u00e9rminos de aumento de la productividad y sufre el aumento de la factura energ\u00e9tica. El gobierno tendr\u00e1 que innovar en este \u00e1mbito, despu\u00e9s de haber atendido la emergencia. No hay que olvidar que Italia cuenta con la segunda industria del continente y que el pa\u00eds alberga muchos sectores intensivos en energ\u00eda, sobre todo en el norte del pa\u00eds: vidrio, aluminio, papel, automoci\u00f3n, etc., muy afectados por la crisis energ\u00e9tica.<\/p>\n\n\n\n<p>Un tema adyacente es, por supuesto, la inflaci\u00f3n. Esto est\u00e1 erosionando r\u00e1pidamente el poder adquisitivo de los hogares, que en la actualidad reciben poco apoyo debido a los limitados m\u00e1rgenes presupuestarios del gobierno. Por lo tanto, la pen\u00ednsula podr\u00eda experimentar una crisis de demanda porque los salarios no se mantienen -y porque el ajuste es brutal-.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/azzFp\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>La justicia civil es otro \u00e1mbito de acci\u00f3n prioritaria. El sistema judicial italiano es especialmente lento y sus procedimientos son complejos, lo que crea un ecosistema poco favorable a la innovaci\u00f3n y la inversi\u00f3n extranjera. El gobierno debe avanzar en esta cuesti\u00f3n si espera mejorar el entorno de los negocios en Italia.<\/p>\n\n\n\n<p>El tercer reto es la digitalizaci\u00f3n, en la que Italia va muy retrasada tanto en el sector p\u00fablico como en el privado. Sin una clara aceleraci\u00f3n de la digitalizaci\u00f3n de la econom\u00eda italiana, Italia tiene pocas esperanzas de beneficiarse de las ganancias de productividad e innovaci\u00f3n en las pr\u00f3ximas oleadas.<\/p>\n\n\n\n<p>Es abordando este tipo de problemas como el gobierno de Meloni puede esperar reforzar la sostenibilidad de la deuda p\u00fablica italiana, que regularmente es objeto de dudas en los mercados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El gobierno de Giorgia Meloni naci\u00f3 finalmente tras varias semanas de intensas negociaciones con sus socios de la Liga y Forza Italia. Mientras la C\u00e1mara de Diputados concedi\u00f3 ayer su confianza al Gobierno y el Senado est\u00e1 a punto de hacerlo, Jean-Yves Dormagen analiza su composici\u00f3n y cu\u00e1les pueden ser sus principales prioridades.<\/p>\n","protected":false},"author":1366,"featured_media":9885,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-angles.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":5,"footnotes":""},"categories":[6],"tags":[],"staff":[294],"editorial_format":[1470],"serie":[],"audience":[],"geo":[177],"class_list":["post-9884","post","type-post","status-publish","format-standard","hentry","category-politica","staff-jean-yves-dormagen","editorial_format-perspectivas-sobre-la-actualidad","geo-europa"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":9885,"excerpt":"El gobierno de Giorgia Meloni naci\u00f3 finalmente tras varias semanas de intensas negociaciones con sus socios de la Liga y Forza Italia. Mientras la C\u00e1mara de Diputados concedi\u00f3 ayer su confianza al Gobierno y el Senado est\u00e1 a punto de hacerlo, Jean-Yves Dormagen analiza su composici\u00f3n y cu\u00e1les pueden ser sus principales prioridades.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Giorgia Meloni sateliza a sus socios de gobierno - El Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/es\/2022\/10\/26\/giorgia-meloni-sateliza-a-sus-socios-de-gobierno\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Giorgia Meloni sateliza a sus socios de gobierno - El Grand Continent\" \/>\n<meta property=\"og:description\" content=\"El gobierno de Giorgia Meloni naci\u00f3 finalmente tras varias semanas de intensas negociaciones con sus socios de la Liga y Forza Italia. Mientras la C\u00e1mara de Diputados concedi\u00f3 ayer su confianza al Gobierno y el Senado est\u00e1 a punto de hacerlo, Jean-Yves Dormagen analiza su composici\u00f3n y cu\u00e1les pueden ser sus principales prioridades.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/es\/2022\/10\/26\/giorgia-meloni-sateliza-a-sus-socios-de-gobierno\/\" \/>\n<meta property=\"og:site_name\" content=\"El Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-26T16:32:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-27T09:34:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2022\/10\/gc-elgobiernomeloni-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1436\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"florent\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2022\/10\/gc-elgobiernomeloni-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"florent\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2022\/10\/26\/giorgia-meloni-sateliza-a-sus-socios-de-gobierno\/\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/2022\/10\/26\/giorgia-meloni-sateliza-a-sus-socios-de-gobierno\/\",\"name\":\"Giorgia Meloni sateliza a sus socios de gobierno - El Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2022\/10\/26\/giorgia-meloni-sateliza-a-sus-socios-de-gobierno\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2022\/10\/26\/giorgia-meloni-sateliza-a-sus-socios-de-gobierno\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2022\/10\/SIPA_01092324_000016-scaled-1.jpg\",\"datePublished\":\"2022-10-26T16:32:00+00:00\",\"dateModified\":\"2022-10-27T09:34:45+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2022\/10\/26\/giorgia-meloni-sateliza-a-sus-socios-de-gobierno\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/es\/2022\/10\/26\/giorgia-meloni-sateliza-a-sus-socios-de-gobierno\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2022\/10\/26\/giorgia-meloni-sateliza-a-sus-socios-de-gobierno\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2022\/10\/SIPA_01092324_000016-scaled-1.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2022\/10\/SIPA_01092324_000016-scaled-1.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Matteo Salvini, Giorgia Meloni, Antonio Tajani, Giuseppe Valditara, Matteo Piantedosi, Guido Crosetto, Roberto Maroni, Luca Cirinai, Maria Elvira Calderone, Adolfo Urso, Francesco Lollobrigida, Orazio Schillaci, Giancarlo Giorgetti, Anna Maria Bernini, during a confidence vote for the new government, at the Chamber of Deputies, the lower house of parliament, in Rome, Italy, 25 October 2022. \/\/AGFEDITORIAL_SEA251022-108\/Credit:Alessandro Serrano'\/AGF\/SIPA\/2210251620\/Credit:Alessandro Serrano'\/AGF\/SIPA\/2210251624\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2022\/10\/26\/giorgia-meloni-sateliza-a-sus-socios-de-gobierno\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/legrandcontinent.eu\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Giorgia Meloni sateliza a sus socios de gobierno\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/\",\"name\":\"El Grand Continent\",\"description\":\"La escala pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\",\"name\":\"florent\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"caption\":\"florent\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Giorgia Meloni sateliza a sus socios de gobierno - El Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/es\/2022\/10\/26\/giorgia-meloni-sateliza-a-sus-socios-de-gobierno\/","og_locale":"es_ES","og_type":"article","og_title":"Giorgia Meloni sateliza a sus socios de gobierno - El Grand Continent","og_description":"El gobierno de Giorgia Meloni naci\u00f3 finalmente tras varias semanas de intensas negociaciones con sus socios de la Liga y Forza Italia. Mientras la C\u00e1mara de Diputados concedi\u00f3 ayer su confianza al Gobierno y el Senado est\u00e1 a punto de hacerlo, Jean-Yves Dormagen analiza su composici\u00f3n y cu\u00e1les pueden ser sus principales prioridades.","og_url":"https:\/\/legrandcontinent.eu\/es\/2022\/10\/26\/giorgia-meloni-sateliza-a-sus-socios-de-gobierno\/","og_site_name":"El Grand Continent","article_published_time":"2022-10-26T16:32:00+00:00","article_modified_time":"2022-10-27T09:34:45+00:00","og_image":[{"width":2560,"height":1436,"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2022\/10\/gc-elgobiernomeloni-scaled.jpg","type":"image\/jpeg"}],"author":"florent","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2022\/10\/gc-elgobiernomeloni-scaled.jpg","twitter_misc":{"Escrito por":"florent","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/es\/2022\/10\/26\/giorgia-meloni-sateliza-a-sus-socios-de-gobierno\/","url":"https:\/\/legrandcontinent.eu\/es\/2022\/10\/26\/giorgia-meloni-sateliza-a-sus-socios-de-gobierno\/","name":"Giorgia Meloni sateliza a sus socios de gobierno - El Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/es\/2022\/10\/26\/giorgia-meloni-sateliza-a-sus-socios-de-gobierno\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/es\/2022\/10\/26\/giorgia-meloni-sateliza-a-sus-socios-de-gobierno\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2022\/10\/SIPA_01092324_000016-scaled-1.jpg","datePublished":"2022-10-26T16:32:00+00:00","dateModified":"2022-10-27T09:34:45+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/es\/2022\/10\/26\/giorgia-meloni-sateliza-a-sus-socios-de-gobierno\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/es\/2022\/10\/26\/giorgia-meloni-sateliza-a-sus-socios-de-gobierno\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/2022\/10\/26\/giorgia-meloni-sateliza-a-sus-socios-de-gobierno\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2022\/10\/SIPA_01092324_000016-scaled-1.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2022\/10\/SIPA_01092324_000016-scaled-1.jpg","width":2560,"height":1707,"caption":"Matteo Salvini, Giorgia Meloni, Antonio Tajani, Giuseppe Valditara, Matteo Piantedosi, Guido Crosetto, Roberto Maroni, Luca Cirinai, Maria Elvira Calderone, Adolfo Urso, Francesco Lollobrigida, Orazio Schillaci, Giancarlo Giorgetti, Anna Maria Bernini, during a confidence vote for the new government, at the Chamber of Deputies, the lower house of parliament, in Rome, Italy, 25 October 2022. \/\/AGFEDITORIAL_SEA251022-108\/Credit:Alessandro Serrano'\/AGF\/SIPA\/2210251620\/Credit:Alessandro Serrano'\/AGF\/SIPA\/2210251624"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/es\/2022\/10\/26\/giorgia-meloni-sateliza-a-sus-socios-de-gobierno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legrandcontinent.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Giorgia Meloni sateliza a sus socios de gobierno"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/es\/#website","url":"https:\/\/legrandcontinent.eu\/es\/","name":"El Grand Continent","description":"La escala pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c","name":"florent","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","caption":"florent"}}]}},"lgc_categories":[{"id":6,"name":"Pol\u00edtica","slug":"politica"}],"lgc_author":{"id":294,"name":"Jean-Yves Dormagen","slug":"jean-yves-dormagen","description":"Jean-Yves Dormagen es presidente y fundador de la encuestadora Cluster17. Tambi\u00e9n es catedr\u00e1tico de Ciencias Pol\u00edticas en la Universidad de Montpellier, donde fue director del Departamento de Ciencias Pol\u00edticas de 2007 a 2014.","first_name":"Jean-Yves","last_name":"Dormagen","picture":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/03\/SUMMIT_GRAND_CONTINENT_0967_Jean-Yves-Dormagen_umbertocostamagna\u00a92023.png","width":1403,"height":1403,"alt":""}},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2022\/10\/SIPA_01092324_000016-scaled-1.jpg","width":2560,"height":1707,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2022\/10\/SIPA_01092324_000016-scaled-1.jpg","width":2560,"height":1707,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/9884","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/users\/1366"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/comments?post=9884"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/9884\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media\/9885"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media?parent=9884"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/categories?post=9884"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/tags?post=9884"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/staff?post=9884"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/editorial_format?post=9884"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/serie?post=9884"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/audience?post=9884"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/geo?post=9884"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}