{"id":94885,"date":"2026-03-31T06:30:00","date_gmt":"2026-03-31T04:30:00","guid":{"rendered":"https:\/\/legrandcontinent.eu\/es\/?p=94885"},"modified":"2026-03-31T04:45:46","modified_gmt":"2026-03-31T02:45:46","slug":"los-paises-del-sur-son-los-mas-afectados-por-la-guerra-contra-iran","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/es\/2026\/03\/31\/los-paises-del-sur-son-los-mas-afectados-por-la-guerra-contra-iran\/","title":{"rendered":"Los pa\u00edses del Sur son los m\u00e1s afectados por la guerra contra Ir\u00e1n"},"content":{"rendered":"\n<p>Tras un mes de guerra librada por Estados Unidos e Israel contra Ir\u00e1n, varios pa\u00edses \u2014en su gran mayor\u00eda de bajos ingresos\u2014 ya se han visto obligados a aplicar medidas excepcionales para hacer frente a las perturbaciones en el suministro y al aumento de los precios de la energ\u00eda.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>En Sri Lanka, el presidente Anura Kumara Dissanayaka decret\u00f3, desde el 16 de marzo, el mi\u00e9rcoles como \u00abd\u00eda festivo\u00bb para el sector p\u00fablico con el fin de limitar el consumo de combustible.<\/li>\n\n\n\n<li>En Egipto, desde el s\u00e1bado 28 de marzo, los centros comerciales, restaurantes y comercios deben cerrar a las 21:00 h cinco d\u00edas a la semana.<\/li>\n\n\n\n<li>En Bangladesh, se han adelantado las vacaciones relacionadas con el Ramad\u00e1n en las universidades, mientras que en Myanmar solo se permite circular a determinados veh\u00edculos cada dos d\u00edas, seg\u00fan su matr\u00edcula.<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/0x8jB\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Los pa\u00edses asi\u00e1ticos y africanos est\u00e1n especialmente expuestos al cierre del estrecho de Ormuz debido a su dependencia del Golfo, y se enfrentan a impactos acumulados, ya que el aumento de los costos de los insumos \u2014energ\u00eda, fertilizantes,<a href=\"https:\/\/legrandcontinent.eu\/es\/2026\/03\/30\/aluminio-el-cierre-del-estrecho-de-ormuz-podria-afectar-sobre-todo-a-las-industrias-estadounidenses\/\"> aluminio<\/a>\u2026\u2014 deber\u00eda afectar a la producci\u00f3n agr\u00edcola, la producci\u00f3n industrial y el poder adquisitivo de los hogares.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>En el caso de la agricultura, la perturbaci\u00f3n provocada por la guerra se produce en<a href=\"https:\/\/legrandcontinent.eu\/es\/2026\/03\/24\/economia-rusa-con-el-cierre-de-ormuz-moscu-refuerza-su-poder-en-el-mercado-de-los-fertilizantes\/\"> un momento especialmente cr\u00edtico<\/a>, ya que coincide con plena temporada de siembra de primavera.<\/li>\n\n\n\n<li>Seg\u00fan el Programa Mundial de Alimentos, cerca de 45 millones de personas m\u00e1s podr\u00edan caer en una situaci\u00f3n de inseguridad alimentaria aguda si el conflicto no termina de aqu\u00ed a mediados de a\u00f1o.&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-94885' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2026\/03\/31\/los-paises-del-sur-son-los-mas-afectados-por-la-guerra-contra-iran\/#easy-footnote-bottom-1-94885' title='&lt;a href=&quot;https:\/\/www.wfp.org\/news\/wfp-projects-food-insecurity-could-reach-record-levels-result-middle-east-escalation&quot;&gt;WFP projects food insecurity could reach record levels as a result of Middle East escalation&lt;\/a&gt;, World Food Programme, 17 de marzo de 2026.'><sup>1<\/sup><\/a><\/span><\/span><\/li>\n<\/ul>\n\n\n\n<p>La guerra tambi\u00e9n afecta directamente a los millones de trabajadores migrantes, que proceden en gran parte del subcontinente indio, del Sudeste Asi\u00e1tico y de \u00c1frica.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Cerca de 35 millones de trabajadores extranjeros viven en los seis pa\u00edses del Consejo de Cooperaci\u00f3n del Golfo: Arabia Saudita, Om\u00e1n, Kuwait, Bar\u00e9in, Emiratos \u00c1rabes Unidos y Qatar.<\/li>\n\n\n\n<li>En los Emiratos, el 80 % de la poblaci\u00f3n est\u00e1 compuesta por extranjeros: estos trabajan principalmente en la construcci\u00f3n, el sector energ\u00e9tico o los servicios.<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/RPLJJ\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Los datos del Banco Mundial indican que, para algunos pa\u00edses del Sur, el importe de los fondos transferidos por estos trabajadores desde el Golfo \u2014que proceden de sus salarios\u2014 representa una parte importante del PIB: hasta un 8 % en el caso de Nepal, y m\u00e1s del 7 % en el de L\u00edbano y Jordania.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La respuesta iran\u00ed, y en particular los ataques contra el sector energ\u00e9tico, que da empleo a varios millones de personas en todo el Golfo, podr\u00eda provocar una disminuci\u00f3n significativa de las remesas.<\/li>\n\n\n\n<li>Esto podr\u00eda reducir los ingresos de los hogares en los pa\u00edses de origen de estos trabajadores y agravar los efectos del aumento de los precios de los alimentos y la energ\u00eda, seg\u00fan la FAO.&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-94885' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2026\/03\/31\/los-paises-del-sur-son-los-mas-afectados-por-la-guerra-contra-iran\/#easy-footnote-bottom-2-94885' title='&lt;a href=&quot;https:\/\/openknowledge.fao.org\/server\/api\/core\/bitstreams\/1aafb5d8-39d1-481a-b1f8-25facaec3051\/content&quot;&gt;GLOBAL AGRIFOOD IMPLICATIONS OF THE 2026 CONFLICT IN THE MIDDLE EAST&lt;\/a&gt;, Food and Agriculture Organization of the United Nations, 15 de mar&amp;lt;o de 2026.'><sup>2<\/sup><\/a><\/span><\/span><\/li>\n<\/ul>\n\n\n\n<p>La crisis de los precios se produce en un momento en que las monedas de varios pa\u00edses del Sur, sometidas a la presi\u00f3n del aumento del costo de las importaciones, han perdido valor frente al d\u00f3lar en los \u00faltimos meses: la rupia india se ha depreciado un 11 % en un a\u00f1o, la libra egipcia un 8 % y el \u0111\u1ed3ng vietnamita un 3 %. El debilitamiento de estas monedas encarece el costo de las importaciones de energ\u00eda denominadas en d\u00f3lares, lo que amplifica las presiones inflacionistas sobre los hogares m\u00e1s vulnerables.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El impacto provocado por la guerra de Israel y Estados Unidos contra Ir\u00e1n es global, pero profundamente asim\u00e9trico.<\/p>\n<p>Si bien los consumidores norteamericanos y europeos se enfrentan a precios m\u00e1s elevados de la energ\u00eda, en los pa\u00edses m\u00e1s pobres \u2014desde el \u00c1frica Subsahariana hasta el sur de Asia\u2014, la guerra podr\u00eda alterar profundamente los equilibrios econ\u00f3micos.<\/p>\n","protected":false},"author":1366,"featured_media":94905,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":true,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":3,"footnotes":""},"categories":[1404],"tags":[],"staff":[],"editorial_format":[1472],"serie":[],"audience":[],"geo":[198],"class_list":["post-94885","post","type-post","status-publish","format-standard","hentry","category-iran-la-guerra-del-cambio-de-regimen","editorial_format-analisis","geo-mundo"],"acf":{"open_in_webview":false,"accent":"default","_thumbnail_id":94905,"excerpt":"El impacto provocado por la guerra de Israel y Estados Unidos contra Ir\u00e1n es global, pero profundamente asim\u00e9trico.\r\n\r\nSi bien los consumidores norteamericanos y europeos se enfrentan a precios m\u00e1s elevados de la energ\u00eda, en los pa\u00edses m\u00e1s pobres \u2014desde el \u00c1frica Subsahariana hasta el sur de Asia\u2014, la guerra podr\u00eda alterar profundamente los equilibrios econ\u00f3micos.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Los pa\u00edses del Sur son los m\u00e1s afectados por la guerra contra Ir\u00e1n - El Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/es\/2026\/03\/31\/los-paises-del-sur-son-los-mas-afectados-por-la-guerra-contra-iran\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los pa\u00edses del Sur son los m\u00e1s afectados por la guerra contra Ir\u00e1n - El Grand Continent\" \/>\n<meta property=\"og:description\" content=\"El impacto provocado por la guerra de Israel y Estados Unidos contra Ir\u00e1n es global, pero profundamente asim\u00e9trico.  Si bien los consumidores norteamericanos y europeos se enfrentan a precios m\u00e1s elevados de la energ\u00eda, en los pa\u00edses m\u00e1s pobres \u2014desde el \u00c1frica Subsahariana hasta el sur de Asia\u2014, la guerra podr\u00eda alterar profundamente los equilibrios econ\u00f3micos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/es\/2026\/03\/31\/los-paises-del-sur-son-los-mas-afectados-por-la-guerra-contra-iran\/\" \/>\n<meta property=\"og:site_name\" content=\"El Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-31T04:30:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2026\/03\/RPLJJ-importe-total-de-las-remesas-recibidas-de-los-paises-del-golfo-.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1104\" \/>\n\t<meta property=\"og:image:height\" content=\"688\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"florent\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"florent\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2026\/03\/31\/los-paises-del-sur-son-los-mas-afectados-por-la-guerra-contra-iran\/\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/2026\/03\/31\/los-paises-del-sur-son-los-mas-afectados-por-la-guerra-contra-iran\/\",\"name\":\"Los pa\u00edses del Sur son los m\u00e1s afectados por la guerra contra Ir\u00e1n - El Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2026\/03\/31\/los-paises-del-sur-son-los-mas-afectados-por-la-guerra-contra-iran\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2026\/03\/31\/los-paises-del-sur-son-los-mas-afectados-por-la-guerra-contra-iran\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2026\/03\/RPLJJ-importe-total-de-las-remesas-recibidas-de-los-paises-del-golfo-.png\",\"datePublished\":\"2026-03-31T04:30:00+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2026\/03\/31\/los-paises-del-sur-son-los-mas-afectados-por-la-guerra-contra-iran\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/es\/2026\/03\/31\/los-paises-del-sur-son-los-mas-afectados-por-la-guerra-contra-iran\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2026\/03\/31\/los-paises-del-sur-son-los-mas-afectados-por-la-guerra-contra-iran\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2026\/03\/RPLJJ-importe-total-de-las-remesas-recibidas-de-los-paises-del-golfo-.png\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2026\/03\/RPLJJ-importe-total-de-las-remesas-recibidas-de-los-paises-del-golfo-.png\",\"width\":1104,\"height\":688},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2026\/03\/31\/los-paises-del-sur-son-los-mas-afectados-por-la-guerra-contra-iran\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/legrandcontinent.eu\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los pa\u00edses del Sur son los m\u00e1s afectados por la guerra contra Ir\u00e1n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/\",\"name\":\"El Grand Continent\",\"description\":\"La escala pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\",\"name\":\"florent\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"caption\":\"florent\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los pa\u00edses del Sur son los m\u00e1s afectados por la guerra contra Ir\u00e1n - El Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/es\/2026\/03\/31\/los-paises-del-sur-son-los-mas-afectados-por-la-guerra-contra-iran\/","og_locale":"es_ES","og_type":"article","og_title":"Los pa\u00edses del Sur son los m\u00e1s afectados por la guerra contra Ir\u00e1n - El Grand Continent","og_description":"El impacto provocado por la guerra de Israel y Estados Unidos contra Ir\u00e1n es global, pero profundamente asim\u00e9trico.  Si bien los consumidores norteamericanos y europeos se enfrentan a precios m\u00e1s elevados de la energ\u00eda, en los pa\u00edses m\u00e1s pobres \u2014desde el \u00c1frica Subsahariana hasta el sur de Asia\u2014, la guerra podr\u00eda alterar profundamente los equilibrios econ\u00f3micos.","og_url":"https:\/\/legrandcontinent.eu\/es\/2026\/03\/31\/los-paises-del-sur-son-los-mas-afectados-por-la-guerra-contra-iran\/","og_site_name":"El Grand Continent","article_published_time":"2026-03-31T04:30:00+00:00","og_image":[{"width":1104,"height":688,"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2026\/03\/RPLJJ-importe-total-de-las-remesas-recibidas-de-los-paises-del-golfo-.png","type":"image\/png"}],"author":"florent","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"florent","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/es\/2026\/03\/31\/los-paises-del-sur-son-los-mas-afectados-por-la-guerra-contra-iran\/","url":"https:\/\/legrandcontinent.eu\/es\/2026\/03\/31\/los-paises-del-sur-son-los-mas-afectados-por-la-guerra-contra-iran\/","name":"Los pa\u00edses del Sur son los m\u00e1s afectados por la guerra contra Ir\u00e1n - El Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/es\/2026\/03\/31\/los-paises-del-sur-son-los-mas-afectados-por-la-guerra-contra-iran\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/es\/2026\/03\/31\/los-paises-del-sur-son-los-mas-afectados-por-la-guerra-contra-iran\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2026\/03\/RPLJJ-importe-total-de-las-remesas-recibidas-de-los-paises-del-golfo-.png","datePublished":"2026-03-31T04:30:00+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/es\/2026\/03\/31\/los-paises-del-sur-son-los-mas-afectados-por-la-guerra-contra-iran\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/es\/2026\/03\/31\/los-paises-del-sur-son-los-mas-afectados-por-la-guerra-contra-iran\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/2026\/03\/31\/los-paises-del-sur-son-los-mas-afectados-por-la-guerra-contra-iran\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2026\/03\/RPLJJ-importe-total-de-las-remesas-recibidas-de-los-paises-del-golfo-.png","contentUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2026\/03\/RPLJJ-importe-total-de-las-remesas-recibidas-de-los-paises-del-golfo-.png","width":1104,"height":688},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/es\/2026\/03\/31\/los-paises-del-sur-son-los-mas-afectados-por-la-guerra-contra-iran\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legrandcontinent.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Los pa\u00edses del Sur son los m\u00e1s afectados por la guerra contra Ir\u00e1n"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/es\/#website","url":"https:\/\/legrandcontinent.eu\/es\/","name":"El Grand Continent","description":"La escala pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c","name":"florent","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","caption":"florent"}}]}},"lgc_categories":[{"id":1404,"name":"Ir\u00e1n: la guerra del cambio de r\u00e9gimen","slug":"iran-la-guerra-del-cambio-de-regimen"}],"lgc_author":null,"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2026\/03\/RPLJJ-importe-total-de-las-remesas-recibidas-de-los-paises-del-golfo-.png","width":1104,"height":688,"alt":""},"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/94885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/users\/1366"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/comments?post=94885"}],"version-history":[{"count":25,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/94885\/revisions"}],"predecessor-version":[{"id":94934,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/94885\/revisions\/94934"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media\/94905"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media?parent=94885"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/categories?post=94885"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/tags?post=94885"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/staff?post=94885"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/editorial_format?post=94885"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/serie?post=94885"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/audience?post=94885"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/geo?post=94885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}