{"id":93509,"date":"2026-03-14T18:30:06","date_gmt":"2026-03-14T17:30:06","guid":{"rendered":"https:\/\/legrandcontinent.eu\/es\/?p=93509"},"modified":"2026-03-14T18:30:09","modified_gmt":"2026-03-14T17:30:09","slug":"el-coste-real-de-produccion-de-un-dron-shahed-136-podria-rondar-los-3-500-euros","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/es\/2026\/03\/14\/el-coste-real-de-produccion-de-un-dron-shahed-136-podria-rondar-los-3-500-euros\/","title":{"rendered":"El coste real de producci\u00f3n de un dron Shahed-136 podr\u00eda rondar los 3.500 euros"},"content":{"rendered":"\n<p>El dron Shahed-136 de fabricaci\u00f3n iran\u00ed es un arma sencilla&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-93509' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/es\/2026\/03\/14\/el-coste-real-de-produccion-de-un-dron-shahed-136-podria-rondar-los-3-500-euros\/#easy-footnote-bottom-1-93509' title='&lt;a href=&quot;https:\/\/osmp.ngo\/collection\/shahed-131-136-uavs-a-visual-guide\/&quot;&gt;Shahed-131 &amp;amp; -136 UAVs\u00a0: a visual guid&lt;\/a&gt;e, Open Source Munitions Portal.'><sup>1<\/sup><\/a><\/span><\/span>. Sus alas en delta, con una envergadura de 2,5 metros, son de fibra de vidrio y terminan en dos estabilizadores verticales fijos. Los alerones de control traseros se accionan mediante simples servomotores.\u00a0<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Est\u00e1 equipado con un sistema de piloto autom\u00e1tico, un receptor GPS y un m\u00f3dulo de datos&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-93509' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/es\/2026\/03\/14\/el-coste-real-de-produccion-de-un-dron-shahed-136-podria-rondar-los-3-500-euros\/#easy-footnote-bottom-2-93509' title='C4ADS, Airborne Axis\u00a0:\u00a0&lt;a href=&quot;https:\/\/c4ads.org\/wp-content\/uploads\/2025\/05\/SaharaThunder-FinalLayout.pdf&quot;&gt;Inside the deal that brought Iranian drone production to Russia&lt;\/a&gt;, 2025.'><sup>2<\/sup><\/a><\/span><\/span>.<\/li>\n\n\n\n<li>La propulsi\u00f3n corre a cargo de un motor de cuatro cilindros de aluminio fundido refrigerado por aire y con una potencia de 50 caballos, que acciona una h\u00e9lice propulsora.\u00a0<\/li>\n\n\n\n<li>Puede volar a una velocidad de 185 kil\u00f3metros por hora mientras transporta una ojiva de 40 kilogramos a una distancia de 2.000 kil\u00f3metros.<\/li>\n<\/ul>\n\n\n\n<p>Es el uso de esta sencilla arma lo que sumerge a la econom\u00eda mundial en el caos.&nbsp;<\/p>\n\n\n\n<p>Como he mostrado en un art\u00edculo reciente para\u00a0<a href=\"https:\/\/www.phenomenalworld.org\/analysis\/cost-of-a-shahed\/\">Phenomenal World<\/a>, para comprender el coste del armamento a\u00e9reo de largo alcance responsable de la creciente devastaci\u00f3n causada por los drones iran\u00edes, los analistas han analizado el precio del Shahed-136. La mayor\u00eda de las estimaciones sit\u00faan el coste de estos drones entre 20.000 y 50.000 d\u00f3lares, lo que supone una fracci\u00f3n del precio de los misiles interceptores, cuyo coste puede alcanzar los 3 millones de d\u00f3lares.\u00a0<\/p>\n\n\n\n<p>\u00bfEs exacta esta comparaci\u00f3n?<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Un an\u00e1lisis del CSIS sobre el precio de la variante rusa del Shahed-136 explica el car\u00e1cter poco cient\u00edfico de estas estimaciones: \u00abEs dif\u00edcil conocer con precisi\u00f3n el coste unitario de los drones del tipo Shahed, que Rusia fabrica localmente bajo el nombre de &#8216;Geran-2&#8217;. En enero de 2023, un experto israel\u00ed en misiles estim\u00f3 este coste en tan s\u00f3lo 20.000-30.000 d\u00f3lares por unidad en un art\u00edculo. Un analista brit\u00e1nico propuso una cifra m\u00e1s cercana a los 80.000 d\u00f3lares, bas\u00e1ndose en la inspecci\u00f3n personal que realiz\u00f3 en octubre de 2022 de los componentes de un Shahed-136 capturado. Forbes Ucrania utiliz\u00f3 un coste unitario de 50.000 d\u00f3lares por Shahed para calcular el coste de los ataques rusos\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-93509' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/es\/2026\/03\/14\/el-coste-real-de-produccion-de-un-dron-shahed-136-podria-rondar-los-3-500-euros\/#easy-footnote-bottom-3-93509' title='Neil Hollenbeck, Muhammed Hamza Altaf, Faith Avila, Javier Ramirez, Anurag Sharma, Benjamin Jensen,\u00a0&lt;a href=&quot;https:\/\/www.csis.org\/analysis\/calculating-cost-effectiveness-russias-drone-strikes&quot;&gt;Calculating the Cost-Effectiveness of Russia\u2019s Drone Strikes&lt;\/a&gt;, 19 de febrero de 2026.'><sup>3<\/sup><\/a><\/span><\/span>.<\/li>\n<\/ul>\n\n\n\n<p>La mayor\u00eda de las estimaciones del coste del Shahed-136 se basan en el an\u00e1lisis de variantes rusas y ninguna de ellas parece proceder de un desglose real de los componentes de un dron de fabricaci\u00f3n iran\u00ed.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Los costes reales de los drones iran\u00edes podr\u00edan ser considerablemente inferiores, lo que har\u00eda que la asimetr\u00eda de los costes de la guerra en el Golfo fuera a\u00fan m\u00e1s extrema que en el caso ucraniano.\u00a0<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>El coste de un Shahed de fabricaci\u00f3n iran\u00ed<\/strong><\/h3>\n\n\n\n<p>Si Ir\u00e1n ensamblara el Shahed-136 a un coste unitario de 35.000 d\u00f3lares, esto constituir\u00eda un gran fracaso para la industria de defensa del pa\u00eds, que ha dado prioridad al desarrollo de sistemas de bajo coste que puedan producirse en serie, con una dependencia limitada de los componentes importados.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Los medios iran\u00edes no han revelado el coste de producci\u00f3n del Shahed-136.\u00a0<\/li>\n\n\n\n<li>Cuando se citan costes en informes en persa, se sit\u00faan en el mismo rango, de 20.000 a 50.000 d\u00f3lares, que el mencionado en los medios occidentales.<\/li>\n<\/ul>\n\n\n\n<p>Estados Unidos ha presentado recientemente su versi\u00f3n del Shahed-136, bautizada como Low-Cost Uncrewed Combat Attack System (LUCAS)&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-4-93509' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/es\/2026\/03\/14\/el-coste-real-de-produccion-de-un-dron-shahed-136-podria-rondar-los-3-500-euros\/#easy-footnote-bottom-4-93509' title='&lt;a href=&quot;https:\/\/www.centcom.mil\/MEDIA\/IMAGERY\/igphoto\/2003834256\/&quot;&gt;U.S. Launches One-Way-Attack Drone Force in the Middle East&lt;\/a&gt;, US Central Command, 23 de noviembre de 2025.'><sup>4<\/sup><\/a><\/span><\/span>.\u00a0<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>El CENTCOM ha indicado que el LUCAS tiene un coste de producci\u00f3n de 35.000 d\u00f3lares.<\/li>\n\n\n\n<li>Esta es la prueba m\u00e1s evidente de que las estimaciones de coste ampliamente difundidas para el Shahed-136 son err\u00f3neas.\u00a0<\/li>\n\n\n\n<li>Aunque es ligeramente m\u00e1s peque\u00f1o, el LUCAS es un dron m\u00e1s avanzado, fabricado con materiales compuestos. Ofrece mayor precisi\u00f3n y m\u00e1s funcionalidades, entre ellas un terminal Starlink integrado.<\/li>\n\n\n\n<li>Aunque el LUCAS fuera m\u00e1s rudimentario y, por lo tanto, m\u00e1s parecido al Shahed-136, las diferencias inherentes a los costes de producci\u00f3n en el \u00e1mbito de la defensa (equipamiento, materiales y mano de obra cualificada) entre Estados Unidos e Ir\u00e1n implican necesariamente que los dos drones no tengan el mismo coste de producci\u00f3n.<\/li>\n<\/ul>\n\n\n\n<p>Fabricar un dron kamikaze en Ir\u00e1n no puede costar lo mismo que fabricar un dron similar en Estados Unidos, donde la mano de obra es m\u00e1s cara, los materiales m\u00e1s sofisticados y la tecnolog\u00eda m\u00e1s avanzada.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Se solicit\u00f3 una estimaci\u00f3n del coste de producci\u00f3n de un Shahed-136 a un acad\u00e9mico de Teher\u00e1n conocedor de la industria de defensa iran\u00ed. Tras su verificaci\u00f3n, la cifra comunicada asciende a unos 6.000 millones de IRR, es decir, aproximadamente 4.000 d\u00f3lares al tipo de cambio actual \u2014lo que equivale a unos 3.500 euros\u2014.\u00a0<\/li>\n\n\n\n<li>Aunque la verificaci\u00f3n de esta cifra no es objeto del presente an\u00e1lisis, esto indica que el Shahed-136 debe ser m\u00e1s barato de producir de lo que se ha informado.<\/li>\n<\/ul>\n\n\n\n<p>Un coste unitario de 4.000 d\u00f3lares es claramente muy inferior a la mayor\u00eda de las estimaciones sobre el coste del Shahed-136.\u00a0<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Por un lado, el precio en d\u00f3lares refleja la significativa devaluaci\u00f3n del rial iran\u00ed, provocada por la presi\u00f3n de las sanciones sobre el mercado de divisas iran\u00ed.<\/li>\n\n\n\n<li>Por un lado, el tipo de cambio podr\u00eda dar la impresi\u00f3n de que los drones son m\u00e1s baratos de lo que realmente son. Por otro lado, este bajo precio podr\u00eda reflejar un alto grado de localizaci\u00f3n de la producci\u00f3n. No reflejar\u00eda las necesidades reales de divisas, sino la disponibilidad relativa de los materiales, los equipos y la mano de obra necesarios para su fabricaci\u00f3n.<\/li>\n\n\n\n<li>La producci\u00f3n del Shahed-136 est\u00e1 ahora totalmente localizada, lo que significa que los componentes esenciales se ensamblan in situ.<\/li>\n<\/ul>\n\n\n\n<p>Se ha informado ampliamente de que el motor MD-550 utilizado en el dron Shahed-136 se fabrica \u00edntegramente en Ir\u00e1n.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Los componentes electr\u00f3nicos podr\u00edan ensamblarse localmente utilizando antenas, microcontroladores, reguladores de tensi\u00f3n y osciladores importados.\u00a0<\/li>\n\n\n\n<li>El ensamblaje local de los componentes electr\u00f3nicos no s\u00f3lo permite reducir los costes, sino que tambi\u00e9n contribuye a mantener las cadenas de suministro frente a las sanciones.<\/li>\n\n\n\n<li>Los componentes completos, como los sistemas de piloto autom\u00e1tico, pueden clasificarse como de \u00abdoble uso\u00bb y resultar dif\u00edciles de adquirir.\u00a0<\/li>\n\n\n\n<li>Expertos iran\u00edes han aportado sus conocimientos para la puesta en marcha de la cadena de producci\u00f3n del dron ruso Geran-2 en el parque industrial de Alabuga, lo que ofrece una visi\u00f3n de las pr\u00e1cticas de producci\u00f3n que probablemente se utilizan en Ir\u00e1n.<\/li>\n\n\n\n<li>El director de la f\u00e1brica rusa ha descrito p\u00fablicamente&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-5-93509' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/es\/2026\/03\/14\/el-coste-real-de-produccion-de-un-dron-shahed-136-podria-rondar-los-3-500-euros\/#easy-footnote-bottom-5-93509' title='Clare Sebastian, Vasco Cotovio, Allegra Goodwin, Daria Tarasova-Markina,\u00a0&lt;a href=&quot;https:\/\/edition.cnn.com\/2025\/07\/25\/europe\/russia-secretive-drone-factory-rapid-expansion-intl&quot;&gt;Russia lifts lid on secretive drone factory as satellite images reveal rapid expansion at key site&lt;\/a&gt;,\u00a0&lt;em&gt;CNN,&lt;\/em&gt;\u00a025 de julio de 2025.'><sup>5<\/sup><\/a><\/span><\/span> un proceso de producci\u00f3n altamente eficiente: \u00abLlegan las barras de aluminio, a partir de ellas se fabrican los motores; los componentes microelectr\u00f3nicos se fabrican a partir de chips electr\u00f3nicos; los fuselajes se fabrican a partir de fibra de carbono y fibra de vidrio: una localizaci\u00f3n completa\u00bb.<\/li>\n\n\n\n<li>Seg\u00fan el Instituto para la Ciencia y la Seguridad Internacional, la f\u00e1brica de Alabuga declara actualmente producir entre 18.540 y 24.460 drones al a\u00f1o.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Un caso de estudio: la producci\u00f3n de tractores<\/strong><\/h3>\n\n\n\n<p>Teniendo en cuenta la din\u00e1mica de los tipos de cambio y la probabilidad de que el Shahed-136 contenga s\u00f3lo una peque\u00f1a proporci\u00f3n de piezas importadas, la mejor manera de comprender la asequibilidad de estos drones en el contexto de la industria de defensa iran\u00ed es comparar su coste de producci\u00f3n con el de otros productos manufacturados, en particular los que tambi\u00e9n se fabrican en Estados Unidos. Este an\u00e1lisis permite poner de relieve las diferencias en los costes de los factores subyacentes a la producci\u00f3n de defensa en Estados Unidos e Ir\u00e1n.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Los pa\u00edses beligerantes cuentan con importantes sectores agr\u00edcolas y ambos producen tractores en su territorio.<\/li>\n\n\n\n<li>Por ejemplo, el tractor John Deere 5075M, fabricado en Augusta, Georgia, presenta caracter\u00edsticas y capacidades similares a las del tractor ITM 475 de la Iran Tractor Company, fabricado en Tabriz, en Ir\u00e1n.\u00a0<\/li>\n\n\n\n<li>Ambos est\u00e1n equipados con un motor de combusti\u00f3n interna de gasolina o di\u00e9sel de unos 75 caballos que impulsa las cuatro ruedas.<\/li>\n\n\n\n<li>El tractor John Deere est\u00e1 equipado con un sistema electr\u00f3nico m\u00e1s avanzado y un motor turboalimentado, pero ambos tienen un tama\u00f1o similar, desarrollan una potencia similar y ofrecen prestaciones similares.\u00a0<\/li>\n<\/ul>\n\n\n\n<p>A principios del a\u00f1o pasado, el precio facturado por el fabricante por el ITM 475 ascend\u00eda a 8.500 millones de IRR.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Tras deducir el IVA y tener en cuenta el margen bruto de la Iran Tractor Company, que suele rondar el 13% seg\u00fan los documentos presentados por la empresa, el coste de producci\u00f3n del ITM 475 puede estimarse en 6.800 millones de IRR.<\/li>\n\n\n\n<li>Utilizando el tipo de cambio principal vigente a principios de 2025, se obtiene un coste de producci\u00f3n del ITM 475 de unos 7.000 d\u00f3lares.\u00a0<\/li>\n\n\n\n<li>A modo de comparaci\u00f3n, el precio de cat\u00e1logo del John Deere 5075M era de unos 50.000 d\u00f3lares en el mismo periodo.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Teniendo en cuenta un margen bruto de alrededor del 25%, tal y como se indica en los documentos de John Deere, y unos m\u00e1rgenes de los concesionarios de alrededor del 8%, el precio facturado por el fabricante es probablemente de unos 35.000 d\u00f3lares.<\/li>\n\n\n\n<li>En otras palabras, el coste de producci\u00f3n de un tractor fabricado en serie es aproximadamente cinco veces mayor en Estados Unidos que en Ir\u00e1n.<\/li>\n<\/ul>\n\n\n\n<p>Los c\u00e1lculos para el tractor y los del dron coinciden perfectamente.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Aplicando la relaci\u00f3n de cinco a uno de los costes de fabricaci\u00f3n revelada por la comparaci\u00f3n de los precios de los tractores y de la plataforma LUCAS, el precio de un Shahed-136 de fabricaci\u00f3n iran\u00ed se sit\u00faa en 7.000 d\u00f3lares.<\/li>\n<\/ul>\n\n\n\n<p>En otras palabras, con los recursos que Estados Unidos dedica a la fabricaci\u00f3n de un LUCAS, Ir\u00e1n puede producir cinco drones Shahed-136.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Debido a la volatilidad de los tipos de cambio, puede resultar enga\u00f1oso citar un precio en d\u00f3lares para explicar el coste de producci\u00f3n de los drones iran\u00edes.<\/li>\n\n\n\n<li>El precio iran\u00ed deber\u00eda compararse con el de un sistema estadounidense similar para poner de manifiesto la diferencia en los costes de los factores de producci\u00f3n.\u00a0<\/li>\n<\/ul>\n\n\n\n<p>En conclusi\u00f3n, la producci\u00f3n de un dron Shahed-136 no requiere m\u00e1s recursos ni mano de obra para Ir\u00e1n que un tractor agr\u00edcola b\u00e1sico.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>En este sentido, la comparaci\u00f3n financiera subestima la capacidad de Ir\u00e1n para continuar la guerra actual.\u00a0<\/li>\n\n\n\n<li>La Iran Tractor Company produce 35.000 tractores al a\u00f1o, a pesar de las restricciones impuestas por las sanciones de \u00abm\u00e1xima presi\u00f3n\u00bb.<\/li>\n\n\n\n<li>Un dron no es mucho m\u00e1s complejo de fabricar que un coche peque\u00f1o. De hecho, el sector automovil\u00edstico iran\u00ed produce m\u00e1s de un mill\u00f3n de veh\u00edculos al a\u00f1o, respaldado por una importante industria del acero y el aluminio, as\u00ed como por numerosos fabricantes nacionales de piezas de recambio.\u00a0<\/li>\n\n\n\n<li>Ir\u00e1n dispone, por tanto, de una capacidad industrial considerable y de existencias de materiales que pueden reorientarse hacia la producci\u00f3n de defensa.<\/li>\n<\/ul>\n\n\n\n<p>Las sanciones econ\u00f3micas y los controles a la exportaci\u00f3n no han logrado obstaculizar la capacidad de Ir\u00e1n para producir drones, dado el bajo coste de la plataforma y la tendencia a la autonomizaci\u00f3n.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Las fuerzas estadounidenses e israel\u00edes no tienen m\u00e1s remedio que recurrir a la fuerza militar para contrarrestar el arsenal de drones iran\u00edes.<\/li>\n\n\n\n<li>Los ataques a\u00e9reos han tenido como objetivo instalaciones pertenecientes al fabricante del Shahed-136, la Iran Aircraft Manufacturing Industrial Company, tambi\u00e9n conocida como HESA&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-6-93509' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/es\/2026\/03\/14\/el-coste-real-de-produccion-de-un-dron-shahed-136-podria-rondar-los-3-500-euros\/#easy-footnote-bottom-6-93509' title='&lt;a href=&quot;https:\/\/x.com\/duitsmanms\/status\/2029755509809836235?s=12&quot;&gt;Ver publicaci\u00f3n en X&lt;\/a&gt;.'><sup>6<\/sup><\/a><\/span><\/span>.\u00a0<\/li>\n\n\n\n<li>Pero Ir\u00e1n podr\u00e1 contraatacar dispersando la producci\u00f3n en numerosas instalaciones, incluidas las subterr\u00e1neas.<\/li>\n\n\n\n<li>Las autoridades estadounidenses tambi\u00e9n est\u00e1n en conversaciones para adquirir drones interceptores ucranianos, que consideran un medio m\u00e1s rentable de defenderse contra el Shahed-136&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-7-93509' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/es\/2026\/03\/14\/el-coste-real-de-produccion-de-un-dron-shahed-136-podria-rondar-los-3-500-euros\/#easy-footnote-bottom-7-93509' title='Charles Clover, Christopher Miller,\u00a0&lt;a href=&quot;https:\/\/www.ft.com\/content\/d077e9c6-1573-46dc-8658-3db3aaf7cdfb&quot;&gt;Pentagon eyes Ukrainian interceptor drones to counter Iran&lt;\/a&gt;,\u00a0&lt;em&gt;Financial Times&lt;\/em&gt;, 5 de marzo de 2026.'><sup>7<\/sup><\/a><\/span><\/span>. Sin embargo, aunque son menos costosos que el uso de bater\u00edas Patriot o THAAD, estos sistemas s\u00f3lo aportar\u00e1n una mejora marginal a las tasas de interceptaci\u00f3n, que ya rondan el 100%.<\/li>\n<\/ul>\n\n\n\n<p>El general Hossein Salami, que dirigi\u00f3 el Cuerpo de la Guardia Revolucionaria Isl\u00e1mica hasta su muerte el verano pasado en un ataque a\u00e9reo israel\u00ed, hab\u00eda declarado en septiembre de 2022 que los avances de la industria de defensa iran\u00ed hac\u00edan que la fabricaci\u00f3n de sistemas de armas fuera \u00abtan sencilla como la producci\u00f3n de bicicletas\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-8-93509' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/es\/2026\/03\/14\/el-coste-real-de-produccion-de-un-dron-shahed-136-podria-rondar-los-3-500-euros\/#easy-footnote-bottom-8-93509' title='&lt;a href=&quot;https:\/\/fa.alalam.ir\/news\/6345803\/%D8%B3%D8%B1%D9%84%D8%B4%DA%A9%D8%B1-%D8%B3%D9%84&amp;#91;%E2%80%A6&amp;#93;%D8%AA-%D8%B3%D8%B1-%DA%AF%D8%B0%D8%A7%D8%B4%D8%AA%DB%8C%D9%85&quot;&gt;\u0633\u0631\u0644\u0634\u06a9\u0631 \u0633\u0644\u0627\u0645\u06cc\u00a0: \u062f\u0631 \u067e\u062f\u0627\u0641\u0646\u062f \u0647\u0648\u0627\u06cc\u06cc \u0642\u062f\u0631\u062a\u200c\u0647\u0627\u06cc \u0628\u0631\u062a\u0631 \u062c\u0647\u0627\u0646 \u0631\u0627 \u067e\u0634\u062a\u200c\u0633\u0631 \u06af\u0630\u0627\u0634\u062a\u06cc\u0645&lt;\/a&gt;, septiembre de 2022.'><sup>8<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>El coste real de producci\u00f3n del Shahed-136 sugiere que la declaraci\u00f3n de Salami podr\u00eda estar mucho m\u00e1s cerca de la realidad.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Seg\u00fan Esfandyar Batmanghelidj, las estimaciones actuales del coste del Shahed-136 se basan en el an\u00e1lisis de variantes rusas, lo que podr\u00eda ocultar el precio real de producci\u00f3n para Ir\u00e1n \u2014y hacer que la guerra en curso en el Golfo resulte muy \u00abbarata \u00bb\u2014.\u00a0<\/p>\n","protected":false},"author":1366,"featured_media":93508,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":true,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":10,"_lgc_tts_audio_url":"","_lgc_tts_voice":"","_lgc_tts_publish":false,"_lgc_tts_history_item_id":"","_lgc_tts_generated_at":"","_lgc_tts_status":"","_lgc_tts_error":"","footnotes":""},"categories":[1404],"tags":[],"staff":[800],"editorial_format":[1472],"serie":[],"audience":[],"geo":[196],"class_list":["post-93509","post","type-post","status-publish","format-standard","hentry","category-iran-la-guerra-del-cambio-de-regimen","staff-esfandyar-batmanghelidj","editorial_format-analisis","geo-asia-central"],"acf":{"open_in_webview":false,"accent":"default","_thumbnail_id":93508,"excerpt":"Seg\u00fan Esfandyar Batmanghelidj, las estimaciones actuales del coste del Shahed-136 se basan en el an\u00e1lisis de variantes rusas, lo que podr\u00eda ocultar el precio real de producci\u00f3n para Ir\u00e1n \u2014y hacer que la guerra en curso en el Golfo resulte muy \u00abbarata \u00bb\u2014.\u00a0","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El coste real de producci\u00f3n de un dron Shahed-136 podr\u00eda rondar los 3.500 euros - El Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/es\/2026\/03\/14\/el-coste-real-de-produccion-de-un-dron-shahed-136-podria-rondar-los-3-500-euros\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El coste real de producci\u00f3n de un dron Shahed-136 podr\u00eda rondar los 3.500 euros - El Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Seg\u00fan Esfandyar Batmanghelidj, las estimaciones actuales del coste del Shahed-136 se basan en el an\u00e1lisis de variantes rusas, lo que podr\u00eda ocultar el precio real de producci\u00f3n para Ir\u00e1n \u2014y hacer que la guerra en curso en el Golfo resulte muy \u00abbarata \u00bb\u2014.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/es\/2026\/03\/14\/el-coste-real-de-produccion-de-un-dron-shahed-136-podria-rondar-los-3-500-euros\/\" \/>\n<meta property=\"og:site_name\" content=\"El Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-14T17:30:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T17:30:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2026\/03\/gc-eldron-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"florent\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2026\/03\/gc-eldron-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"florent\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2026\/03\/14\/el-coste-real-de-produccion-de-un-dron-shahed-136-podria-rondar-los-3-500-euros\/\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/2026\/03\/14\/el-coste-real-de-produccion-de-un-dron-shahed-136-podria-rondar-los-3-500-euros\/\",\"name\":\"El coste real de producci\u00f3n de un dron Shahed-136 podr\u00eda rondar los 3.500 euros - El Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2026\/03\/14\/el-coste-real-de-produccion-de-un-dron-shahed-136-podria-rondar-los-3-500-euros\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2026\/03\/14\/el-coste-real-de-produccion-de-un-dron-shahed-136-podria-rondar-los-3-500-euros\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2026\/03\/Grand-Continent-Drones.png\",\"datePublished\":\"2026-03-14T17:30:06+00:00\",\"dateModified\":\"2026-03-14T17:30:09+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2026\/03\/14\/el-coste-real-de-produccion-de-un-dron-shahed-136-podria-rondar-los-3-500-euros\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/es\/2026\/03\/14\/el-coste-real-de-produccion-de-un-dron-shahed-136-podria-rondar-los-3-500-euros\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2026\/03\/14\/el-coste-real-de-produccion-de-un-dron-shahed-136-podria-rondar-los-3-500-euros\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2026\/03\/Grand-Continent-Drones.png\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2026\/03\/Grand-Continent-Drones.png\",\"width\":1204,\"height\":990},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2026\/03\/14\/el-coste-real-de-produccion-de-un-dron-shahed-136-podria-rondar-los-3-500-euros\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/legrandcontinent.eu\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El coste real de producci\u00f3n de un dron Shahed-136 podr\u00eda rondar los 3.500 euros\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/\",\"name\":\"El Grand Continent\",\"description\":\"La escala pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\",\"name\":\"florent\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"caption\":\"florent\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El coste real de producci\u00f3n de un dron Shahed-136 podr\u00eda rondar los 3.500 euros - El Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/es\/2026\/03\/14\/el-coste-real-de-produccion-de-un-dron-shahed-136-podria-rondar-los-3-500-euros\/","og_locale":"es_ES","og_type":"article","og_title":"El coste real de producci\u00f3n de un dron Shahed-136 podr\u00eda rondar los 3.500 euros - El Grand Continent","og_description":"Seg\u00fan Esfandyar Batmanghelidj, las estimaciones actuales del coste del Shahed-136 se basan en el an\u00e1lisis de variantes rusas, lo que podr\u00eda ocultar el precio real de producci\u00f3n para Ir\u00e1n \u2014y hacer que la guerra en curso en el Golfo resulte muy \u00abbarata \u00bb\u2014.\u00a0","og_url":"https:\/\/legrandcontinent.eu\/es\/2026\/03\/14\/el-coste-real-de-produccion-de-un-dron-shahed-136-podria-rondar-los-3-500-euros\/","og_site_name":"El Grand Continent","article_published_time":"2026-03-14T17:30:06+00:00","article_modified_time":"2026-03-14T17:30:09+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2026\/03\/gc-eldron-scaled.jpg","type":"image\/jpeg"}],"author":"florent","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2026\/03\/gc-eldron-scaled.jpg","twitter_misc":{"Escrito por":"florent","Tiempo de lectura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/es\/2026\/03\/14\/el-coste-real-de-produccion-de-un-dron-shahed-136-podria-rondar-los-3-500-euros\/","url":"https:\/\/legrandcontinent.eu\/es\/2026\/03\/14\/el-coste-real-de-produccion-de-un-dron-shahed-136-podria-rondar-los-3-500-euros\/","name":"El coste real de producci\u00f3n de un dron Shahed-136 podr\u00eda rondar los 3.500 euros - El Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/es\/2026\/03\/14\/el-coste-real-de-produccion-de-un-dron-shahed-136-podria-rondar-los-3-500-euros\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/es\/2026\/03\/14\/el-coste-real-de-produccion-de-un-dron-shahed-136-podria-rondar-los-3-500-euros\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2026\/03\/Grand-Continent-Drones.png","datePublished":"2026-03-14T17:30:06+00:00","dateModified":"2026-03-14T17:30:09+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/es\/2026\/03\/14\/el-coste-real-de-produccion-de-un-dron-shahed-136-podria-rondar-los-3-500-euros\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/es\/2026\/03\/14\/el-coste-real-de-produccion-de-un-dron-shahed-136-podria-rondar-los-3-500-euros\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/2026\/03\/14\/el-coste-real-de-produccion-de-un-dron-shahed-136-podria-rondar-los-3-500-euros\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2026\/03\/Grand-Continent-Drones.png","contentUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2026\/03\/Grand-Continent-Drones.png","width":1204,"height":990},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/es\/2026\/03\/14\/el-coste-real-de-produccion-de-un-dron-shahed-136-podria-rondar-los-3-500-euros\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legrandcontinent.eu\/es\/"},{"@type":"ListItem","position":2,"name":"El coste real de producci\u00f3n de un dron Shahed-136 podr\u00eda rondar los 3.500 euros"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/es\/#website","url":"https:\/\/legrandcontinent.eu\/es\/","name":"El Grand Continent","description":"La escala pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c","name":"florent","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","caption":"florent"}}]}},"lgc_categories":[{"id":1404,"name":"Ir\u00e1n: la guerra del cambio de r\u00e9gimen","slug":"iran-la-guerra-del-cambio-de-regimen"}],"lgc_author":{"id":800,"name":"Esfandyar Batmanghelidj","slug":"esfandyar-batmanghelidj","description":null,"first_name":null,"last_name":null,"picture":null},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2026\/03\/Grand-Continent-Drones.png","width":1204,"height":990,"alt":""},"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/93509","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/users\/1366"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/comments?post=93509"}],"version-history":[{"count":28,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/93509\/revisions"}],"predecessor-version":[{"id":93563,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/93509\/revisions\/93563"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media\/93508"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media?parent=93509"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/categories?post=93509"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/tags?post=93509"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/staff?post=93509"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/editorial_format?post=93509"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/serie?post=93509"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/audience?post=93509"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/geo?post=93509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}