{"id":93409,"date":"2026-03-13T19:30:18","date_gmt":"2026-03-13T18:30:18","guid":{"rendered":"https:\/\/legrandcontinent.eu\/es\/?p=93409"},"modified":"2026-03-13T19:30:21","modified_gmt":"2026-03-13T18:30:21","slug":"peter-thiel-en-roma-un-regime-change-teologico","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/es\/2026\/03\/13\/peter-thiel-en-roma-un-regime-change-teologico\/","title":{"rendered":"Peter Thiel en Roma: un regime change teol\u00f3gico"},"content":{"rendered":"\n<p class=\"has-drop-cap\">No es exactamente el Anticristo quien acaba de anunciar su visita a Roma. Pero quien se dispone a descender sobre la Ciudad Eterna lo teme y profetiza su llegada. \u00bfDe qui\u00e9n se trata, exactamente? \u00bfUn m\u00edstico abrasado por el amor de Dios? \u00bfUn mendigo descalzo, vestido con cilicio? \u00bfUn desequilibrado convertido en obispo por un malentendido?<\/p>\n\n\n\n<p>Todo lo contrario, por desgracia: se trata de Peter Thiel, alias Dr. PayPal o Mr. Palantir.<\/p>\n\n\n\n<p>Thiel es el 103\u00ba hombre m\u00e1s rico del mundo; uno de esos tecnooligarcas cuyas empresas prestan a los Estados y a los ej\u00e9rcitos servicios opacos \u2014<a href=\"https:\/\/legrandcontinent.eu\/es\/2026\/03\/09\/de-iran-a-la-vigilancia-masiva-la-doble-guerra-de-palantir\/\">por no decir inconfesables<\/a>; un inversor avispado que, en 2016, mientras Silicon Valley miraba hacia otro lado, financi\u00f3 la campa\u00f1a electoral de Donald Trump y lanz\u00f3 la carrera pol\u00edtica de un abogado a\u00fan desconocido llamado J. D. Vance.<\/p>\n\n\n\n<p>Thiel es todo eso. Pero es tambi\u00e9n, y sobre todo, uno de los ide\u00f3logos que consideran que el catolicismo romano deber\u00eda transformarse en un hotel de paso tanto para las derechas autorizadas como para las derechas ocultas. Esto explica que vaya a Roma, a visitar a un papa estadounidense, Robert Francis Prevost, por quien tiene muy poca estima, y precedido de un <em>storytelling<\/em> extremadamente h\u00e1bil, hecho de falsa reserva, equ\u00edvocos y ambig\u00fcedades, quiz\u00e1s destinados \u00fanicamente a encubrir ciertas citas m\u00e1s <em>de negocios<\/em> con los sectores de la salud y la inteligencia.&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-93409' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/es\/2026\/03\/13\/peter-thiel-en-roma-un-regime-change-teologico\/#easy-footnote-bottom-1-93409' title='Maria Antonietta Calabr\u00f2, \u00ab&lt;a href=&quot;https:\/\/www.huffingtonpost.it\/cultura\/2026\/03\/07\/news\/lanticristo_nelluniversita_del_papa-21369165\/&quot;&gt;Peter Thiel: l\u2019Anticristo arriva a Roma&lt;\/a&gt;\u00bb, &lt;em&gt;HuffPost Italia, &lt;\/em&gt;9 de marzo de 2026.'><sup>1<\/sup><\/a><\/span><\/span><\/p>\n\n\n\n<p>Como suele ocurrir con Thiel, el relato se ve acompa\u00f1ado de una puesta en escena bastante pesada, llena de giros argumentales previsibles.<\/p>\n\n\n\n<p>Cuando se supo que Peter Thiel iba a dar unas conferencias en la Pontificia Universit\u00e0 San Tommaso d&#8217;Aquino, un escalofr\u00edo recorri\u00f3 inicialmente la espalda de muchos. \u00bfEra posible que la universidad de Juan Pablo II y del propio Prevost acogiera a un personaje tan controvertido? \u00bfHab\u00eda habido una aprobaci\u00f3n del dicasterio para la educaci\u00f3n, del sustituto, del secretario de Estado o del propio papa?<\/p>\n\n\n\n<p>Unos d\u00edas m\u00e1s tarde lleg\u00f3 el desmentido del rector de esta universidad dominica. Recordemos: los dominicos son ciertamente conocidos por ser especialistas en Tom\u00e1s de Aquino; pero en Estados Unidos tambi\u00e9n son m\u00fasicos en el grupo de <em>country<\/em> cristiano con un nombre muy antiguo: <em>The Hillbilly Thomists<\/em>.<\/p>\n\n\n\n<p>Luego se filtr\u00f3 la informaci\u00f3n de que Thiel asistir\u00eda el domingo a una misa en lat\u00edn en la Bas\u00edlica di San Giovanni Battista dei Fiorentini, en via Giulia.<\/p>\n\n\n\n<p>Luego se nos hizo saber que, al igual que sus negocios y su actividad pol\u00edtica, sus conferencias seguir\u00edan siendo extremadamente secretas, reservadas a un p\u00fablico selecto, y no es dif\u00edcil adivinar qui\u00e9nes habr\u00edan deseado asistir a ellas. Del mismo modo que no es dif\u00edcil comprender el alcance general de un gesto que constituye un nuevo desaf\u00edo lanzado al papado por una categor\u00eda particular de cristianos: la de los convertidos a un catolicismo \u00abdiscutible\u00bb, instrumentalizable, puesto al servicio de una ideolog\u00eda MACA, <em>Make Christianity Great Again<\/em>.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Que el catolicismo, anta\u00f1o objeto de desprecio, sea ahora considerado como una tierra de conquista a la vez cercana y lejana \u2014una especie de \u00abGroenlandia moral\u00bb\u2014 sigue siendo una hip\u00f3tesis abierta.<\/p><cite>Alberto Melloni<\/cite><\/blockquote><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Peter y los cat\u00f3licos imaginarios<\/strong><\/h2>\n\n\n\n<p>Peter Thiel pertenece a esta categor\u00eda de conversos.<\/p>\n\n\n\n<p>Subjetivamente, son <em>doblemente renacidos<\/em> \u2014individuos que no solo han vuelto a la pertenencia cristiana, sino que est\u00e1n convencidos, tras una especie de <em>cherry picking<\/em> confesional, de que la Iglesia de Roma ser\u00eda aquella en la que mejor podr\u00edan injertar una teolog\u00eda que refleje la <em>forma mentis<\/em> trumpiana: aquella de la que podr\u00edan extraer mejor un esp\u00edritu agon\u00edstico antimoderno y antilustraci\u00f3n, cuando ese esp\u00edritu ya no tiene ante s\u00ed ning\u00fan enemigo real en el mundo posmoderno y postilustraci\u00f3n, sino solo la posibilidad de imitar sus obsesiones, los antagonismos, los resentimientos, los miedos y los odios.<\/p>\n\n\n\n<p>Thiel forma parte de esos conversos a un catolicismo imaginado \u2014y a menudo imaginario\u2014 m\u00e1s virtual que virtuoso, mezclado con otras ideolog\u00edas reaccionarias de diversa procedencia; un universo poblado de personas que buscan hacer pasar el rayo de luz de la fe a trav\u00e9s de un prisma fan\u00e1tico, pero del que no surge la policrom\u00eda de las m\u00faltiples formas de vida cristiana que conoce cualquiera que viva o conozca realmente el catolicismo, sino una refracci\u00f3n sombr\u00eda. Para continuar con esta met\u00e1fora, se podr\u00eda decir que este prisma fan\u00e1tico transforma el rayo puro de la exigencia de la fe \u2014aquella que deja de prescribir a los dem\u00e1s diciendo \u00ab\u00e9l\u00bb y se dirige al otro diciendo \u00abt\u00fa\u00bb, por retomar una famosa imagen de Martin Buber\u2014 en un haz negro, tanto pol\u00edtica como teol\u00f3gicamente.<\/p>\n\n\n\n<p>No hay que confundir estas figuras con toda una generaci\u00f3n de cat\u00f3licos bautizados en la edad adulta, cada vez m\u00e1s visible en los pa\u00edses donde la pr\u00e1ctica del bautismo de los beb\u00e9s se ha vuelto escasa, ya sea por efecto de la descristianizaci\u00f3n, como en Francia, o de otra hegemon\u00eda cultural, como en China. Estas peque\u00f1as multitudes, que a veces suscitan cierto entusiasmo en unas iglesias a las que la sociolog\u00eda religiosa lleva a\u00f1os inyectando datos deprimentes, no constituyen evidentemente un peligro: simplemente expresan un matiz entre otros en la paleta de sensibilidades contempor\u00e1neas.<\/p>\n\n\n\n<p>Quiz\u00e1 est\u00e9n solo un poquito m\u00e1s expuestas que quienes ven a Thiel como un maestro: aquellos que, en el caos del mundo, no buscan ni al Dios de Abraham, ni al Dios de Mois\u00e9s, ni al Dios de Jes\u00fas, sino a un hipot\u00e9tico guardi\u00e1n de las certezas \u00e9ticas y cultuales, de los exclusivismos simples e inmediatamente movilizables, de los odios y las fobias que esperan encontrar al hacerse cat\u00f3licos.<\/p>\n\n\n\n<p>Estas figuras asocian un gusto tradicionalista o visiones supuestamente apocal\u00edpticas con funciones de poder pol\u00edtico o econ\u00f3mico. M\u00e1s que una simple corriente entre las muchas que conforman la riqueza del catolicismo, representan una opci\u00f3n alternativa a la propia organizaci\u00f3n de la Iglesia latina tal y como la conocemos hoy.<\/p>\n\n\n\n<p>Quieren tomar Roma.<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-medium\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2026\/03\/jd_Vance_2.png\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"1290\"\n        data-pswp-height=\"1920\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2026\/03\/jd_Vance_2-330x491.png\"\r\n                media=\"(max-width:  374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2026\/03\/jd_Vance_2-690x1027.png\"\r\n                media=\"(max-width:  989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2026\/03\/jd_Vance_2-990x1473.png\"\r\n                media=\"(max-width: 1319px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2026\/03\/jd_Vance_2-690x1027.png\"\r\n                media=\"(max-width: 1599px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2026\/03\/jd_Vance_2-990x1473.png\"\r\n                media=\"(min-width: 1600px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2026\/03\/jd_Vance_2-125x186.png\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">J. D. Vance de lansquenet. \u00a9 Tundra Studio para el Grand Continent<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<h2 class=\"wp-block-heading\"><strong>El fracaso de la opci\u00f3n carolingia<\/strong><\/h2>\n\n\n\n<p>Una de ellas es ya conocida por todos: J. D. Vance, vicepresidente de Estados Unidos y posible candidato a las elecciones presidenciales de 2028 o 2032.<\/p>\n\n\n\n<p>En 2025, cuando explicaba en p\u00fablico y en privado que la brutal caza de migrantes lanzada por la administraci\u00f3n de Trump pon\u00eda en pr\u00e1ctica el concepto agustiniano de <em>ordo amoris<\/em>, se gan\u00f3 una seca reacci\u00f3n del cardenal Robert Francis Prevost \u2014el actual papa Le\u00f3n XIV\u2014, ya tan reservado y prudente como se le ve hoy: \u00ab<em>JD Vance <em>is wrong<\/em><\/em>\u00bb.<\/p>\n\n\n\n<p>Durante la agon\u00eda del papa Francisco, Vance acudi\u00f3 a Roma para una visita privada cuyo contenido, por su parte, era perfectamente p\u00fablico y pol\u00edticamente sofisticado: proponer a la Santa Sede una nueva<a href=\"https:\/\/legrandcontinent.eu\/es\/2025\/04\/22\/la-opcion-carolingia-de-j-d-vance\/\"> opci\u00f3n carolingia<\/a>. Se trataba de reconocer a la cultura de las nuevas derechas globales una legitimidad intelectual, de ratificar una nueva <em>translatio imperii<\/em> \u2014el paso cultural de un mundo a otro\u2014 y de coronar una soberan\u00eda que reconocer\u00eda a su vez la autoridad del papa para llevar a cabo este gesto.<\/p>\n\n\n\n<p>Ya moribundo, Francisco no le entreg\u00f3 ninguna corona. En cambio, hizo algo a\u00fan m\u00e1s importante: le regal\u00f3 tres huevos de chocolate Kinder para sus hijos. El propio Donald Trump consider\u00f3 oportuno responder a la Santa Sede tras esta afrenta, declarando que asistir\u00eda al funeral de Francisco en nombre de su victoria en el voto cat\u00f3lico. El resto vino por a\u00f1adidura: rechazo del protocolo \u2014Estados Unidos debe situarse seg\u00fan el orden alfab\u00e9tico del nombre franc\u00e9s\u2014 y rechazo del c\u00f3digo de vestimenta \u2014Trump iba vestido de azul brillante, cuando en los funerales de los papas se acude de negro.<\/p>\n\n\n\n<p>La bofetada bergogliana a Vance no fue repetida por Le\u00f3n, pero tampoco fue desmentida.<\/p>\n\n\n\n<p>Cuando Vance fue recibido de nuevo en Roma por el papa reci\u00e9n elegido, Prevost se mostr\u00f3 cort\u00e9s y silencioso, como con todos sus interlocutores. Pero si hay un terreno en el que su prudencia, habitualmente calcada de la \u2014extrema\u2014 de la Secretar\u00eda de Estado, ha conocido algunas desviaciones, ese es sin duda el terreno estadounidense.<\/p>\n\n\n\n<p>Prueba de ello es la postura de los obispos estadounidenses ante las brutalidades de la Oficina de Inmigraci\u00f3n y Aduanas de EUA (ICE), sin muchos precedentes, su rechazo a la <em>Board of Peace<\/em> propuesta por Trump y, sobre todo, su decisi\u00f3n no solo de declinar, como se esperaba, la invitaci\u00f3n a Washington, D.C. para las celebraciones del 250\u00ba aniversario de la independencia, sino de desplazarse \u2014precisamente el 4 de julio\u2014 a la isla de Lampedusa, capital simb\u00f3lica de los n\u00e1ufragos y los supervivientes de las migraciones.<\/p>\n\n\n\n<p>Esta firmeza vaticana ha provocado cierto alivio. No solo en el catolicismo hostil a cualquier opci\u00f3n carolingia, sino tambi\u00e9n \u2014de manera m\u00e1s inesperada\u2014 en una parte del mundo evang\u00e9lico. No hay que considerar casual la difusi\u00f3n, en marzo de 2026, tras el ataque contra Ir\u00e1n, de un video en el que se ve a varios televangelistas \u2014entre los que destaca de nuevo Paula White\u2014 alineados en el Despacho Oval en torno a Trump, sentado, con las manos sobre sus hombros y pidiendo a Dios que sostenga sus brazos como los de Mois\u00e9s en la lucha contra Amalec.<\/p>\n\n\n\n<p>Esta secuencia tiene un contenido teol\u00f3gico inquietante: sacraliza la guerra. Pero tambi\u00e9n tranquiliza al componente evang\u00e9lico del electorado trumpista: el proyecto MACA (<em>Make America Christian Again<\/em>) sigue firmemente en manos de los WASP blancos y protestantes; a salvo, por tanto, de toda influencia papista.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Francisco no entreg\u00f3 a J. D. Vance ninguna corona. En cambio, hizo algo a\u00fan m\u00e1s importante: le regal\u00f3 tres huevos de chocolate Kinder para sus hijos.<\/p><cite>Alberto Melloni<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Esto no significa que la apuesta de Vance se haya agotado, ni que haya sido aniquilada por la forma en que el secretario de Estado hizo eco de la condena papal de la \u00abl\u00f3gica\u00bb trumpiana de la guerra y la paz. La sustituci\u00f3n del fundamentalismo WASP \u2014que aliment\u00f3 durante tanto tiempo a la derecha estadounidense hasta su transformaci\u00f3n en MAGA\u2014 por un fermento cat\u00f3lico conservador sigue siendo una posibilidad real.<\/p>\n\n\n\n<p>Que el catolicismo, anta\u00f1o objeto de desprecio, se contemple ahora como una tierra de conquista a la vez cercana y lejana \u2014una especie de \u00abGroenlandia moral\u00bb que habr\u00eda que comprar, reclamar o tomar\u2014 sigue siendo una hip\u00f3tesis abierta.<\/p>\n\n\n\n<p>El resultado de esta maniobra depender\u00e1 del episcopado estadounidense, en un di\u00e1logo con Roma totalmente renovado en la era del papa estadounidense. El nombramiento en Washington, D.C. de monse\u00f1or Gabriele Caccia como nuncio apost\u00f3lico \u2014sin duda el mejor diplom\u00e1tico de la Santa Sede, con una distinci\u00f3n al estilo de Pablo VI, que podr\u00eda haber aspirado a muchos otros cargos, desde el sustituto hasta el arzobispado de Mil\u00e1n o la Secretar\u00eda tras Pietro Parolin \u2014muestra que se comprende la delicadeza del momento tanto para la presa \u2014la Iglesia cat\u00f3lica\u2014 como para el depredador \u2014los cat\u00f3-MAGA y sus enlaces en las derechas europeas, visibles o clandestinas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Una Groenlandia confesional: Roma en el <\/strong><strong><em>corpus Thielianum<\/em><\/strong><\/h2>\n\n\n\n<p>En este contexto se inscribe el activismo teol\u00f3gico-pol\u00edtico de Peter Thiel, figura de Silicon Valley catapultada al escaso Olimpo de los ultrarricos por la invenci\u00f3n de PayPal, y que luego se convirti\u00f3 en un actor central gracias a Palantir Technologies.<\/p>\n\n\n\n<p>En un entorno de <em>venture capitalists<\/em> a menudo marcado por una cultura general muy escasa y una superficialidad intelectual y teol\u00f3gica flagrante, Thiel se revel\u00f3 desde el principio como un animal de otra especie. Su catolicismo, as\u00ed como unas lecturas poco comunes en este ecosistema \u2014Ren\u00e9 Girard,<a href=\"https:\/\/legrandcontinent.eu\/es\/2025\/11\/25\/por-que-se-lee-tanto-a-carl-schmitt-una-conversacion-con-jean-francois-kervegan\/\"> Carl Schmitt<\/a>, Vladimir Soloviev y Leo Strauss\u2014 ya lo hab\u00edan situado en el punto de mira de <em>The New Yorker<\/em> en 2011. En <em>No Death, No Taxes<\/em>, George Packer ofrec\u00eda un retrato preciso de su trayectoria intelectual.&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-93409' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/es\/2026\/03\/13\/peter-thiel-en-roma-un-regime-change-teologico\/#easy-footnote-bottom-2-93409' title='George Packer, \u00ab&lt;a href=&quot;https:\/\/www.newyorker.com\/magazine\/2011\/11\/28\/no-death-no-taxes&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;No Death, No Taxes&lt;\/a&gt;\u00bb, &lt;em&gt;The New Yorker, &lt;\/em&gt;20 de noviembre de 2011.'><sup>2<\/sup><\/a><\/span><\/span><\/p>\n\n\n\n<p>Sus libros y conferencias conforman ahora un<a href=\"https:\/\/legrandcontinent.eu\/es\/2025\/10\/24\/peter-thiel-pensamientos-del-anticristo\/\"> <em>corpus Thielianum<\/em><\/a> cuya deconstrucci\u00f3n no presenta ninguna dificultad: en el fondo se esconde un malentendido fundamental sobre el apocalipsis como g\u00e9nero literario y como horizonte intelectual.<\/p>\n\n\n\n<p>En la tradici\u00f3n jud\u00eda, el g\u00e9nero apocal\u00edptico se elabor\u00f3 en primer lugar para consolar a los pobres, los humillados y los perseguidos. En una visi\u00f3n del tiempo orientada hacia la redenci\u00f3n mesi\u00e1nica, se dirige a aquellos a quienes los escombros de la historia han sepultado. Lo hace a trav\u00e9s de figuras que afirman que los invencibles no lo son, y que lo demon\u00edaco que devora a los seres humanos sigue siendo fr\u00e1gil \u2014porque siempre pasa por la indiferencia y la cobard\u00eda de otros seres humanos.<\/p>\n\n\n\n<p>En el <em>corpus Thielianum<\/em>, adquiere un sentido totalmente diferente. Aparece como la culminaci\u00f3n de un camino que comenzar\u00eda con la apolog\u00e9tica girardiana. La teor\u00eda \u2014poderosa\u2014 de Girard sostiene que la religi\u00f3n nace como regulador de la violencia producida por el deseo mim\u00e9tico original, ese deseo que empuja a cada uno a querer lo que posee el otro; la tensi\u00f3n resultante encontrar\u00eda en el chivo expiatorio su v\u00e1lvula de escape necesaria. Este edificio da forma a continuaci\u00f3n a una apolog\u00e9tica cristiana de un g\u00e9nero nuevo: en la cruz, Dios mismo se convertir\u00eda en expiaci\u00f3n, abriendo otra lectura del mundo y del sujeto, donde cobran voz las dimensiones psicoanal\u00edticas magistralmente formuladas en <em>Cosas ocultas desde la fundaci\u00f3n del mundo<\/em>.&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-93409' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/es\/2026\/03\/13\/peter-thiel-en-roma-un-regime-change-teologico\/#easy-footnote-bottom-3-93409' title='Ren\u00e9 Girard, &lt;em&gt;Des choses cach\u00e9es depuis la fondation du monde&lt;\/em&gt;, Par\u00eds, Grasset, 2001.'><sup>3<\/sup><\/a><\/span><\/span><\/p>\n\n\n\n<p>Bas\u00e1ndose en esta lectura y en esta filiaci\u00f3n intelectual, Thiel imagina que el cristianismo puede \u2014y debe\u2014 convertirse en el instrumento capaz de contener una deriva apocal\u00edptica hacia la que, seg\u00fan \u00e9l, la Ilustraci\u00f3n empuja al mundo.<\/p>\n\n\n\n<p>A su juicio, la idea ilustrada de una sabidur\u00eda de los pueblos habr\u00eda desencadenado una espiral regresiva.<\/p>\n\n\n\n<p>Habr\u00eda extinguido progresivamente la audacia del progreso, hasta convertirse en su adversario fatal, produciendo un \u00abestancamiento\u00bb intelectual y moral que acaba identificando con la propia naturaleza: un gato engendra un gato, que engendra un gato, y as\u00ed sucesivamente. A esta naturaleza asimilada al Anticristo, opone una aceleraci\u00f3n en la que la ciencia y la tecnolog\u00eda construyen un futuro alejado de la justicia y la igualdad: una aceleraci\u00f3n tecnol\u00f3gica, tecnocr\u00e1tica y plutocr\u00e1tica, destinada a impedir el advenimiento de un totalitarismo basado en lo que \u00e9l considera pseudovalores pseudouniversales destinados a controlar al hombre.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Thiel no hace Cuaresma: si viene a Roma en marzo, no es por devoci\u00f3n.<\/p><cite>Alberto Melloni<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Pronunciado por el fundador de una empresa que lo sabe casi todo sobre nuestros comportamientos, el argumento podr\u00eda pasar por una iron\u00eda involuntaria. Sin embargo, est\u00e1 revestido de un barniz erudito: para Thiel, el poder del Anticristo se manifestar\u00e1 \u2014o ya se manifiesta\u2014 en esos sentimientos pacifistas, universalistas, filantr\u00f3picos y animalistas que un famoso relato de Soloviev ya hab\u00eda esbozado en 1899, al advertir a la ortodoxia contra la seducci\u00f3n de una teolog\u00eda liberal de la que hoy solo quedan unos p\u00e1lidos vestigios en la ambici\u00f3n de proporcionar \u00abvalores\u00bb en nombre de las religiones.<\/p>\n\n\n\n<p>La conclusi\u00f3n del razonamiento de Thiel \u2014involuntariamente c\u00f3mica, pero formulada expl\u00edcitamente en una larga entrevista concedida a Ross Douthat en el <em>New York Times<\/em> del 26 de junio de 2025\u2014 es que el maestro del big data cree discernir una clara alusi\u00f3n al Anticristo en Greta Thunberg.<\/p>\n\n\n\n<p>\u00daltimo elemento de este mosaico intelectual: la invocaci\u00f3n del <em>kat\u00e9chon<\/em>. Esta figura, procedente de la apocal\u00edptica jud\u00eda y retomada por san Pablo en la segunda carta a los Tesalonicenses, sirve hist\u00f3ricamente, una vez m\u00e1s, para tranquilizar a los creyentes: algo \u2014o alguien\u2014 podr\u00eda a\u00fan impedir el cumplimiento del misterio de la iniquidad y retrasar as\u00ed la irrupci\u00f3n final de la redenci\u00f3n mesi\u00e1nica \u2014abriendo el espacio mismo de la historia y de la libertad.<\/p>\n\n\n\n<p>Un an\u00e1lisis preciso de Francesca Monateri ha recorrido recientemente todos los matices contradictorios de esta figura del <em>kat\u00e9chon<\/em>, que ha atravesado toda la historia de la filosof\u00eda y la teolog\u00eda.&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-4-93409' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/es\/2026\/03\/13\/peter-thiel-en-roma-un-regime-change-teologico\/#easy-footnote-bottom-4-93409' title='Francesca Monateri, &lt;em&gt;Katechon. Filosofia, politica, estetica&lt;\/em&gt;, Tur\u00edn, Bollati Boringhieri, 2023.'><sup>4<\/sup><\/a><\/span><\/span> Entre estas lecturas, Thiel retiene una: para varios autores, a lo largo de dos mil a\u00f1os de ex\u00e9gesis, es la propia comunidad cristiana la que ejercer\u00eda una funci\u00f3n <em>katech\u00f3ntica<\/em>, porque el testimonio, el martirio y el anuncio del Evangelio marcar\u00edan ese breve intervalo entre la primera venida y la segunda.<\/p>\n\n\n\n<p>Thiel tambi\u00e9n parece designar a la Iglesia como <em>kat\u00e9chon<\/em>. Pero en su caso, el sujeto <em>katech\u00f3ntico<\/em> no es la Iglesia como asamblea lit\u00fargica: es la instituci\u00f3n cat\u00f3lica romana, a la que vincula una parte esencial de su proyecto teol\u00f3gico-pol\u00edtico.<\/p>\n\n\n\n<p>La l\u00f3gica thieliana se basa, en el fondo, en una alternativa enga\u00f1osa y bastante simplista.<\/p>\n\n\n\n<p>Si Roma permanece fiel a su universalismo constitutivo, seguir\u00e1 siendo uno de los bastiones del estancamiento y, por tanto, uno de los adversarios a derribar. Como ha demostrado el eco mundial del esc\u00e1ndalo de los abusos sexuales, no es dif\u00edcil golpearla aprovechando su porosidad al mal como instrumento de erosi\u00f3n de su credibilidad.<\/p>\n\n\n\n<p>Si, por el contrario, Roma se adhiriera a una ideolog\u00eda de la aceleraci\u00f3n, renunciara a la teolog\u00eda de la creaci\u00f3n, criminalizara las igualdades consideradas \u00abpecaminosas\u00bb y viera por todas partes ideolog\u00edas colonizadoras del g\u00e9nero o del \u00abwoke\u00bb, entonces podr\u00eda convertirse en un basti\u00f3n del tradicionalismo contracultural antimoderno, funcional a una visi\u00f3n thieliana de la historia cuyo horizonte no es un futuro, sino un presente del que Donald Trump ser\u00eda hoy la encarnaci\u00f3n.<\/p>\n\n\n\n<p>Pero para que eso suceda, es necesario que Roma se convierta en un espacio disputable (<em>contendibile<\/em>), un terreno de posible conquista. Y para ello, se necesita una forma de simplismo teol\u00f3gico; simplismo al que, por razones muy diferentes, tres papas sucesivos se han mostrado inclinados. En este punto, el papa Le\u00f3n XIV solo ofrece por ahora algunos indicios tenues, diseminados en las notas de sus discursos.<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-medium\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2026\/03\/trump_2.png\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"1290\"\n        data-pswp-height=\"1920\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2026\/03\/trump_2-330x491.png\"\r\n                media=\"(max-width:  374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2026\/03\/trump_2-690x1027.png\"\r\n                media=\"(max-width:  989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2026\/03\/trump_2-990x1473.png\"\r\n                media=\"(max-width: 1319px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2026\/03\/trump_2-690x1027.png\"\r\n                media=\"(max-width: 1599px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2026\/03\/trump_2-990x1473.png\"\r\n                media=\"(min-width: 1600px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2026\/03\/trump_2-125x186.png\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">Donald Trump de lansquenet. \u00a9 Tundra Studio para Le Grand Continent<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<h2 class=\"wp-block-heading\"><strong><em>Chi mangia papa crepa<\/em><\/strong><\/h2>\n\n\n\n<p>Thiel no hace Cuaresma: si viene a Roma en marzo, no es por devoci\u00f3n.<\/p>\n\n\n\n<p>Quiere hablar en Roma para dar la impresi\u00f3n de que habr\u00e1 influido en la preparaci\u00f3n de la primera enc\u00edclica program\u00e1tica del papa Le\u00f3n XIV.<\/p>\n\n\n\n<p>Los periodistas mejor informados anuncian su proclamaci\u00f3n para mayo, es decir, m\u00e1s de un a\u00f1o despu\u00e9s de la elecci\u00f3n. Es mucho tiempo. Es m\u00e1s o menos el tiempo que le llev\u00f3 a Pablo VI proclamar tambi\u00e9n su primera enc\u00edclica \u2014pero \u00e9l ten\u00eda que reabrir un concilio y no unos cuantos reajustes de la curia destinados a excitar a los fabricantes y traficantes de chismes por mensajes de texto\u2026 Tambi\u00e9n es casi el doble del tiempo que tardaron los te\u00f3logos de Francisco en proporcionarle <em>Evangelii gaudium<\/em>, su texto program\u00e1tico pontificio, que \u00e9l hab\u00eda elegido sutilmente publicar en forma de exhortaci\u00f3n apost\u00f3lica en lugar de enc\u00edclica.<\/p>\n\n\n\n<p>Sea cual sea la orientaci\u00f3n de esta primera enc\u00edclica de Le\u00f3n XIV \u2014dignidad humana, \u00abalgor-\u00e9tica\u00bb, guerra\u2026\u2014, Thiel quiere una cosa: que se le tome en serio. Poco importa que se le rebata, se le corrija o se le d\u00e9 parcialmente la raz\u00f3n. Lo esencial es que el hombre que financi\u00f3 al vicepresidente que recibi\u00f3 huevos Kinder para sus hijos pueda llevar a cabo esta provocaci\u00f3n preventiva, p\u00fablicamente y sin costo inmediato.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Quiere hablar en Roma para dar la impresi\u00f3n de que habr\u00e1 influido en la preparaci\u00f3n de la primera enc\u00edclica program\u00e1tica del papa Le\u00f3n XIV.<\/p><cite>Alberto Melloni<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Hasta la fecha, nada indica que Peter Thiel haya solicitado una audiencia con el papa o con los responsables de los dicasterios. Pero podr\u00eda hacerlo \u2014y podr\u00eda conseguirla.<\/p>\n\n\n\n<p>Tampoco se sabe si su programa incluye paradas en lugares pol\u00edtico-religiosos situados al margen del Vaticano \u2014los Caballeros de Col\u00f3n o Sant&#8217;Egidio\u2014. Tampoco se sabe a\u00fan d\u00f3nde ha citado a sus oyentes, ni si les impondr\u00e1 esas reglas de discreci\u00f3n \u2014sin tel\u00e9fonos, sin grabadoras, sin cuadernos de notas\u2014, que constituyen el \u00faltimo eslab\u00f3n de una sofisticada estrategia de marketing, pero que ignora que, en Roma, nada estimula tanto las confidencias, los relatos, los entresijos y la creaci\u00f3n de mitos como el propio secreto?<\/p>\n\n\n\n<p>Solo una cosa es segura: Thiel est\u00e1 ah\u00ed.<\/p>\n\n\n\n<p>Hay que saber tambi\u00e9n que ya existe todo un peque\u00f1o mundo impaciente por entrar en ese p\u00fablico cuidadosamente seleccionado, con la misma habilidad comunicativa que rode\u00f3 la (des)informaci\u00f3n sobre el lugar de los encuentros. \u00bfInvitar\u00e1 \u2014o descartar\u00e1\u2014 el te\u00f3rico del tecnoapocalipsis a los representantes del catolicismo tradicional de derecha, aquellos que creen poder elegir entre el papa y los obispos italianos? \u00bfInvitar\u00e1 a los reaccionarios europeos? \u00bfY a los periodistas que tildaban al papa Francisco de hereje y que hoy ronronean alrededor de Le\u00f3n XIV? \u00bfElegir\u00e1 \u00e9l mismo a quienes har\u00e1 pasar, dentro de las derechas, seg\u00fan el famoso recorrido descrito por la genial pluma del escritor italiano Alberto Arbasino, del estatus de \u00abjoven promesa\u00bb al de \u00abmaestro venerable\u00bb, evitando la dram\u00e1tica alternativa que conducir\u00eda al rango de \u00abimb\u00e9cil de servicio\u00bb?<\/p>\n\n\n\n<p>Tambi\u00e9n hay que entender que el contenido de este curso intensivo romano de <em>katech\u00f3ntica <\/em>probablemente no aportar\u00e1 novedades sustanciales en cuanto al fondo con respecto a lo que Thiel ya expuso en sus conferencias en San Francisco el pasado mes de septiembre, <a href=\"https:\/\/legrandcontinent.eu\/es\/2025\/10\/24\/peter-thiel-pensamientos-del-anticristo\/\">conferencias ya analizadas en <em>el Grand Continent<\/em><\/a>.<\/p>\n\n\n\n<p>Porque el objetivo es otro: penetrar en el <em>heartland<\/em> del catolicismo, es decir, su n\u00facleo hist\u00f3rico y doctrinal, y provocar un sismo en la postura teol\u00f3gico-pol\u00edtica de la Iglesia de Roma. A primera vista, tal cambio parece dif\u00edcilmente concebible. Pero quiz\u00e1 sea eso lo que el inversor de Silicon Valley busca en Roma: una resistencia, una reacci\u00f3n, hacer que la Ciudad Eterna se mueva.<\/p>\n\n\n\n<p>Thiel desconoce sin duda el viejo proverbio romano \u00ab<em>chi mangia papa crepa<\/em>\u00bb.&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-5-93409' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/es\/2026\/03\/13\/peter-thiel-en-roma-un-regime-change-teologico\/#easy-footnote-bottom-5-93409' title='\u00abQuien se mete con el papa, sale mal parado\u00bb, literalmente, \u00abquien come papa, muere\u00bb.'><sup>5<\/sup><\/a><\/span><\/span> Pero probablemente ha calculado su riesgo: venir con la ambici\u00f3n de imponer a la Iglesia de Roma un cambio de r\u00e9gimen teol\u00f3gico, y luego marcharse sin que Le\u00f3n XIV le conceda siquiera un tuit similar al que utiliz\u00f3 para liquidar el agustinismo de Vance: \u00ab<em>wrong<\/em>\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para la derecha MAGA, la Santa Sede es una Groenlandia confesional.<\/p>\n<p>Tras el fallido asalto a Roma de J. D. Vance, Peter Thiel ha decidido tomar las riendas.<\/p>\n<p>Para intentar influir en la pr\u00f3xima enc\u00edclica de Le\u00f3n XIV, se dispone a impartir en Roma una serie de conferencias sobre el Anticristo.<\/p>\n","protected":false},"author":17959,"featured_media":93402,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-editorials.php","format":"standard","meta":{"_acf_changed":true,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":17,"_lgc_tts_audio_url":"","_lgc_tts_voice":"","_lgc_tts_publish":false,"_lgc_tts_history_item_id":"","_lgc_tts_generated_at":"","_lgc_tts_status":"","_lgc_tts_error":"","footnotes":""},"categories":[292],"tags":[],"staff":[1044],"editorial_format":[1471],"serie":[],"audience":[],"geo":[177],"class_list":["post-93409","post","type-post","status-publish","format-standard","hentry","category-religion","staff-alberto-melloni","editorial_format-piezas-de-doctrinas","geo-europa"],"acf":{"open_in_webview":false,"accent":"default","_thumbnail_id":93402,"excerpt":"Para la derecha MAGA, la Santa Sede es una Groenlandia confesional.\r\n\r\nTras el fallido asalto a Roma de J. D. Vance, Peter Thiel ha decidido tomar las riendas.\r\n\r\nPara intentar influir en la pr\u00f3xima enc\u00edclica de Le\u00f3n XIV, se dispone a impartir en Roma una serie de conferencias sobre el Anticristo.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Peter Thiel en Roma: un regime change teol\u00f3gico - El Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/es\/2026\/03\/13\/peter-thiel-en-roma-un-regime-change-teologico\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Peter Thiel en Roma: un regime change teol\u00f3gico - El Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Para la derecha MAGA, la Santa Sede es una Groenlandia confesional.  Tras el fallido asalto a Roma de J. D. Vance, Peter Thiel ha decidido tomar las riendas.  Para intentar influir en la pr\u00f3xima enc\u00edclica de Le\u00f3n XIV, se dispone a impartir en Roma una serie de conferencias sobre el Anticristo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/es\/2026\/03\/13\/peter-thiel-en-roma-un-regime-change-teologico\/\" \/>\n<meta property=\"og:site_name\" content=\"El Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-13T18:30:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-13T18:30:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2026\/03\/gc-regimethiel-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"anainesfernandez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2026\/03\/gc-regimethiel-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"anainesfernandez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"17 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2026\/03\/13\/peter-thiel-en-roma-un-regime-change-teologico\/\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/2026\/03\/13\/peter-thiel-en-roma-un-regime-change-teologico\/\",\"name\":\"Peter Thiel en Roma: un regime change teol\u00f3gico - El Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2026\/03\/13\/peter-thiel-en-roma-un-regime-change-teologico\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2026\/03\/13\/peter-thiel-en-roma-un-regime-change-teologico\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2026\/03\/thiel_2-1.png\",\"datePublished\":\"2026-03-13T18:30:18+00:00\",\"dateModified\":\"2026-03-13T18:30:21+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/570398dd8da37ba5d66dec6d242bd33c\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2026\/03\/13\/peter-thiel-en-roma-un-regime-change-teologico\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/es\/2026\/03\/13\/peter-thiel-en-roma-un-regime-change-teologico\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2026\/03\/13\/peter-thiel-en-roma-un-regime-change-teologico\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2026\/03\/thiel_2-1.png\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2026\/03\/thiel_2-1.png\",\"width\":1290,\"height\":1920,\"caption\":\"Peter Thiel en lansquenet. \u00a9 Tundra Studio pour le Grand Continent\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2026\/03\/13\/peter-thiel-en-roma-un-regime-change-teologico\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/legrandcontinent.eu\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Peter Thiel en Roma: un regime change teol\u00f3gico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/\",\"name\":\"El Grand Continent\",\"description\":\"La escala pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/570398dd8da37ba5d66dec6d242bd33c\",\"name\":\"anainesfernandez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/fe25c21e6213f69a683147fabda32586?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/fe25c21e6213f69a683147fabda32586?s=96&d=mm&r=g\",\"caption\":\"anainesfernandez\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Peter Thiel en Roma: un regime change teol\u00f3gico - El Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/es\/2026\/03\/13\/peter-thiel-en-roma-un-regime-change-teologico\/","og_locale":"es_ES","og_type":"article","og_title":"Peter Thiel en Roma: un regime change teol\u00f3gico - El Grand Continent","og_description":"Para la derecha MAGA, la Santa Sede es una Groenlandia confesional.  Tras el fallido asalto a Roma de J. D. Vance, Peter Thiel ha decidido tomar las riendas.  Para intentar influir en la pr\u00f3xima enc\u00edclica de Le\u00f3n XIV, se dispone a impartir en Roma una serie de conferencias sobre el Anticristo.","og_url":"https:\/\/legrandcontinent.eu\/es\/2026\/03\/13\/peter-thiel-en-roma-un-regime-change-teologico\/","og_site_name":"El Grand Continent","article_published_time":"2026-03-13T18:30:18+00:00","article_modified_time":"2026-03-13T18:30:21+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2026\/03\/gc-regimethiel-scaled.jpg","type":"image\/jpeg"}],"author":"anainesfernandez","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2026\/03\/gc-regimethiel-scaled.jpg","twitter_misc":{"Escrito por":"anainesfernandez","Tiempo de lectura":"17 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/es\/2026\/03\/13\/peter-thiel-en-roma-un-regime-change-teologico\/","url":"https:\/\/legrandcontinent.eu\/es\/2026\/03\/13\/peter-thiel-en-roma-un-regime-change-teologico\/","name":"Peter Thiel en Roma: un regime change teol\u00f3gico - El Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/es\/2026\/03\/13\/peter-thiel-en-roma-un-regime-change-teologico\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/es\/2026\/03\/13\/peter-thiel-en-roma-un-regime-change-teologico\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2026\/03\/thiel_2-1.png","datePublished":"2026-03-13T18:30:18+00:00","dateModified":"2026-03-13T18:30:21+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/570398dd8da37ba5d66dec6d242bd33c"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/es\/2026\/03\/13\/peter-thiel-en-roma-un-regime-change-teologico\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/es\/2026\/03\/13\/peter-thiel-en-roma-un-regime-change-teologico\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/2026\/03\/13\/peter-thiel-en-roma-un-regime-change-teologico\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2026\/03\/thiel_2-1.png","contentUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2026\/03\/thiel_2-1.png","width":1290,"height":1920,"caption":"Peter Thiel en lansquenet. \u00a9 Tundra Studio pour le Grand Continent"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/es\/2026\/03\/13\/peter-thiel-en-roma-un-regime-change-teologico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legrandcontinent.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Peter Thiel en Roma: un regime change teol\u00f3gico"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/es\/#website","url":"https:\/\/legrandcontinent.eu\/es\/","name":"El Grand Continent","description":"La escala pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/570398dd8da37ba5d66dec6d242bd33c","name":"anainesfernandez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/fe25c21e6213f69a683147fabda32586?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fe25c21e6213f69a683147fabda32586?s=96&d=mm&r=g","caption":"anainesfernandez"}}]}},"lgc_categories":[{"id":292,"name":"Religi\u00f3n","slug":"religion"}],"lgc_author":{"id":1044,"name":"Alberto Melloni","slug":"alberto-melloni","description":null,"first_name":"Alberto","last_name":"Melloni","picture":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/12\/2025\/03\/melloni.png","width":258,"height":257,"alt":""}},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2026\/03\/thiel_2-1.png","width":1290,"height":1920,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2026\/03\/thiel_2-1.png","width":1290,"height":1920,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/93409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/users\/17959"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/comments?post=93409"}],"version-history":[{"count":22,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/93409\/revisions"}],"predecessor-version":[{"id":93435,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/93409\/revisions\/93435"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media\/93402"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media?parent=93409"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/categories?post=93409"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/tags?post=93409"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/staff?post=93409"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/editorial_format?post=93409"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/serie?post=93409"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/audience?post=93409"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/geo?post=93409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}