{"id":87665,"date":"2026-01-12T10:03:46","date_gmt":"2026-01-12T09:03:46","guid":{"rendered":"https:\/\/legrandcontinent.eu\/es\/?p=87665"},"modified":"2026-01-12T10:03:50","modified_gmt":"2026-01-12T09:03:50","slug":"lo-publico-debe-prevalecer-sobre-la-arbitrariedad-del-presidente-jerome-powell-contra-donald-trump","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/es\/2026\/01\/12\/lo-publico-debe-prevalecer-sobre-la-arbitrariedad-del-presidente-jerome-powell-contra-donald-trump\/","title":{"rendered":"\u00abLo p\u00fablico debe prevalecer sobre la arbitrariedad del presidente\u00bb: Jerome Powell contra Donald Trump\u00a0"},"content":{"rendered":"\n<p class=\"intro\">En Washington, la administraci\u00f3n Trump acelera la transformaci\u00f3n interna. Tras una semana marcada por <a href=\"https:\/\/legrandcontinent.eu\/es\/2026\/01\/05\/venezuela-cuba-groenlandia-trump-ha-actuado-contra-seis-paises-o-ha-amenazado-con-intervenir-en-ellos-desde-el-1-de-enero\/\">un aventurismo geopol\u00edtico sin precedentes<\/a> y por la muerte de Renee Gonz\u00e1lez, abatida por un agente del ICE, el <em>New York Times<\/em> revel\u00f3 que la fiscal\u00eda federal del distrito de Columbia hab\u00eda citado a comparecer ante un gran jurado al presidente de la Reserva Federal, Jerome Powell, amenaz\u00e1ndole con un proceso penal por la renovaci\u00f3n de un edificio hist\u00f3rico.<\/p>\n\n\n\n<p class=\"intro\">Esta investigaci\u00f3n, aprobada en noviembre por la expresentadora de Fox News y aliada de Donald Trump desde hace mucho tiempo, Jeanine Pirro, incluir\u00eda un an\u00e1lisis de las declaraciones p\u00fablicas del presidente de la Reserva Federal y un examen de sus registros de gastos.<\/p>\n\n\n\n<p class=\"intro\">Jerome Powell reaccion\u00f3 inmediatamente a la publicaci\u00f3n del art\u00edculo del <em>New York Times<\/em> sobre la investigaci\u00f3n. En lugar de publicar un comunicado de prensa, grab\u00f3 un v\u00eddeo que ahora se ha vuelto viral.<\/p>\n\n\n\n<p class=\"intro\">Es la primera vez desde el comienzo del segundo mandato que el responsable de una instituci\u00f3n federal independiente \u2014y, por lo tanto, de un contrapoder\u2014 entra p\u00fablicamente en un pulso con el presidente.<\/p>\n\n\n\n<p class=\"intro\">El profesor de Ciencias Pol\u00edticas de Stanford Michael McFaul declar\u00f3: \u00abEs un momento de locura. Los republicanos deben denunciar con vehemencia este ataque contra Powell y la Reserva Federal. No podemos permitir que Trump destruya nuestra democracia. Dirigentes republicanos, nuestra Rep\u00fablica los necesita\u00bb.<\/p>\n\n\n\n<p class=\"intro\">Jason Furman, profesor de Harvard y exvicepresidente del Consejo de Asesores Econ\u00f3micos bajo Barack Obama, escribi\u00f3 en X que el presidente Powell deb\u00eda \u00abresistir este escandaloso intento del presidente de utilizar la judicializaci\u00f3n del derecho para eludir la responsabilidad de la Fed de perseguir los objetivos que le ha fijado la ley: el pleno empleo y la estabilidad de los precios\u00bb.<\/p>\n\n\n\n<p class=\"intro\">Este v\u00eddeo pone de relieve la profundidad del intento de transformaci\u00f3n del r\u00e9gimen emprendido por la administraci\u00f3n Trump, pero tambi\u00e9n la existencia de contrapoderes en Estados Unidos.<\/p>\n\n\n\n<p class=\"intro\">Jerome Powell, uno de los pocos l\u00edderes estadounidenses que, seg\u00fan las \u00faltimas encuestas, goza de la confianza tanto de los republicanos (34%) como de los dem\u00f3cratas (49%) y una de las figuras p\u00fablicas m\u00e1s apreciadas por los estadounidenses (44%), se dirige directamente al pueblo estadounidense y hace un llamamiento a todas las instituciones pol\u00edticas, desde el Senado hasta el Congreso.<\/p>\n\n\n\n<p class=\"intro\">Publicada en v\u00edsperas de la apertura de los mercados, esta declaraci\u00f3n podr\u00eda tensar los bonos del Tesoro estadounidense, ya que el cuestionamiento de la independencia de la Fed aumenta la prima de riesgo institucional y los rendimientos a largo plazo. El d\u00f3lar tambi\u00e9n podr\u00eda debilitarse, ya que la percepci\u00f3n de una erosi\u00f3n de la autonom\u00eda de la Fed socava su credibilidad y su valor como refugio.<\/p>\n\n\n\n<p>Buenas noches.<\/p>\n\n\n\n<p>El viernes, el Departamento de Justicia notific\u00f3 a la Reserva Federal citaciones para comparecer ante un gran jurado, amenazando con iniciar acciones penales relacionadas con mi testimonio ante la comisi\u00f3n bancaria del Senado el pasado mes de junio. Este testimonio se refer\u00eda en parte a un proyecto plurianual de renovaci\u00f3n de los edificios hist\u00f3ricos de la Reserva Federal.<\/p>\n\n\n\n<p class=\"comment\">El proyecto plurianual de renovaci\u00f3n de la Reserva Federal afecta a dos edificios hist\u00f3ricos de su sede en Washington, construidos en la d\u00e9cada de 1930 y que nunca han sido renovados en profundidad. Iniciadas en 2022 y previstas hasta 2027, las obras tienen por objeto modernizar las infraestructuras obsoletas \u2014electricidad, calefacci\u00f3n, seguridad, accesibilidad\u2014 y, al mismo tiempo, retirar el amianto y el plomo y restaurar los elementos arquitect\u00f3nicos originales.<\/p>\n\n\n\n<p class=\"comment\">Estimado actualmente en unos 2.500 millones de d\u00f3lares, el coste del proyecto supera las previsiones iniciales debido a la inflaci\u00f3n posterior a la pandemia, las restricciones relacionadas con la conservaci\u00f3n hist\u00f3rica y las dificultades t\u00e9cnicas imprevistas. La Fed afirma que estos gastos son necesarios y se financian con sus propios recursos, y no con fondos del Congreso, mientras que la magnitud del proyecto y sus sobrecostes alimentan ahora la controversia pol\u00edtica en torno a Jerome Powell.<\/p>\n\n\n\n<p>Tengo un profundo respeto por el Estado de derecho y la responsabilidad en nuestra democracia. Nadie, y desde luego no el presidente de la Reserva Federal, est\u00e1 por encima de la ley. Pero esta acci\u00f3n sin precedentes debe situarse en el contexto m\u00e1s amplio de las amenazas y presiones constantes ejercidas por la Administraci\u00f3n.<\/p>\n\n\n\n<p class=\"comment\">Desde el comienzo del segundo mandato de Donald Trump, la Reserva Federal y su presidente, Jerome Powell, han sido objeto de repetidas presiones p\u00fablicas: ataques personales del presidente, exigencias expl\u00edcitas de recortes agresivos de los tipos de inter\u00e9s, amenazas de destituci\u00f3n, aunque legalmente reguladas, e intentos de debilitar a otros gobernadores de la Fed.<\/p>\n\n\n\n<p class=\"comment\">En este contexto, la acci\u00f3n judicial actual parece una escalada destinada a coaccionar la pol\u00edtica monetaria mediante presiones pol\u00edticas y jur\u00eddicas, lo que pone en tela de juicio un principio fundamental del Estado de derecho estadounidense: la independencia del banco central frente al poder ejecutivo.<\/p>\n\n\n\n<p>Esta nueva amenaza no tiene que ver con mi testimonio del pasado mes de junio ni con la renovaci\u00f3n de los edificios de la Reserva Federal. Tampoco tiene que ver con la funci\u00f3n de control del Congreso; la Fed ha hecho todo lo posible, mediante testimonios y otras medidas de transparencia p\u00fablica, para mantener al Congreso informado sobre el proyecto de renovaci\u00f3n. Son s\u00f3lo pretextos. La amenaza de acciones penales es una consecuencia del hecho de que la Reserva Federal fija los tipos de inter\u00e9s bas\u00e1ndose en nuestra mejor evaluaci\u00f3n de lo que servir\u00e1 lo p\u00fablico, en lugar de seguir las preferencias del presidente.<\/p>\n\n\n\n<p class=\"comment\">La independencia de la Reserva Federal consiste en el derecho y el deber de fijar la pol\u00edtica monetaria sin la intervenci\u00f3n del poder ejecutivo, bas\u00e1ndose en el an\u00e1lisis econ\u00f3mico y en el mandato confiado por el Congreso: la estabilidad de los precios y el pleno empleo. Esto implica que las decisiones sobre los tipos de inter\u00e9s no pueden estar dictadas por preferencias pol\u00edticas ni sancionadas <em>a posteriori<\/em> por presiones legales o personales, siempre que se trate del ejercicio leg\u00edtimo de ese mandato.<\/p>\n\n\n\n<p>Se trata de saber si la Fed podr\u00e1 seguir fijando los tipos de inter\u00e9s bas\u00e1ndose en pruebas y condiciones econ\u00f3micas o si, por el contrario, la pol\u00edtica monetaria estar\u00e1 dictada por presiones pol\u00edticas o intimidaciones.<\/p>\n\n\n\n<p class=\"comment\">Las presiones del ejecutivo para influir o controlar la difusi\u00f3n e interpretaci\u00f3n de los datos econ\u00f3micos \u2014como las acusaciones sin pruebas de manipulaci\u00f3n de las cifras de empleo por parte de la Oficina de Estad\u00edsticas Laborales (BLS) y el despido de su comisionada Erika McEntarfer\u2014 han puesto de manifiesto el riesgo de politizaci\u00f3n de las estad\u00edsticas p\u00fablicas, lo que debilita la confianza en los indicadores oficiales y la base factual sobre la que se fundamentan las decisiones econ\u00f3micas.<\/p>\n\n\n\n<p>He prestado servicio en la Reserva Federal bajo cuatro administraciones, tanto republicanas como dem\u00f3cratas.<\/p>\n\n\n\n<p>En todos los casos, he desempe\u00f1ado mis funciones sin presiones ni favoritismos pol\u00edticos, centr\u00e1ndome \u00fanicamente en nuestro mandato de estabilidad de precios y pleno empleo. El servicio p\u00fablico a veces exige mantenerse firme ante las amenazas. Seguir\u00e9 haciendo el trabajo para el que me confirm\u00f3 el Senado, con integridad y compromiso al servicio del pueblo estadounidense.<\/p>\n\n\n\n<p>Gracias.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por primera vez desde el regreso de Donald Trump a la Casa Blanca, un alto cargo institucional estadounidense ha decidido enfrentarse p\u00fablicamente al presidente de los Estados Unidos.<\/p>\n<p>Publicamos y comentamos el discurso del presidente de la Reserva Federal dirigido al pueblo estadounidense, al Congreso, al Senado y a los inversores internacionales.<\/p>\n","protected":false},"author":1366,"featured_media":87663,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-speeches.php","format":"standard","meta":{"_acf_changed":true,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":6,"footnotes":""},"categories":[6],"tags":[],"staff":[7],"editorial_format":[1474],"serie":[],"audience":[],"geo":[172],"class_list":["post-87665","post","type-post","status-publish","format-standard","hentry","category-politica","staff-el-grand-continent","editorial_format-archivos-y-discursos","geo-americas"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":87663,"excerpt":"Por primera vez desde el regreso de Donald Trump a la Casa Blanca, un alto cargo institucional estadounidense ha decidido enfrentarse p\u00fablicamente al presidente de los Estados Unidos.\r\n\r\nPublicamos y comentamos el discurso del presidente de la Reserva Federal dirigido al pueblo estadounidense, al Congreso, al Senado y a los inversores internacionales.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00abLo p\u00fablico debe prevalecer sobre la arbitrariedad del presidente\u00bb: Jerome Powell contra Donald Trump\u00a0 - El Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/es\/2026\/01\/12\/lo-publico-debe-prevalecer-sobre-la-arbitrariedad-del-presidente-jerome-powell-contra-donald-trump\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00abLo p\u00fablico debe prevalecer sobre la arbitrariedad del presidente\u00bb: Jerome Powell contra Donald Trump\u00a0 - El Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Por primera vez desde el regreso de Donald Trump a la Casa Blanca, un alto cargo institucional estadounidense ha decidido enfrentarse p\u00fablicamente al presidente de los Estados Unidos.  Publicamos y comentamos el discurso del presidente de la Reserva Federal dirigido al pueblo estadounidense, al Congreso, al Senado y a los inversores internacionales.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/es\/2026\/01\/12\/lo-publico-debe-prevalecer-sobre-la-arbitrariedad-del-presidente-jerome-powell-contra-donald-trump\/\" \/>\n<meta property=\"og:site_name\" content=\"El Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-12T09:03:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-12T09:03:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2026\/01\/gc-elpowell-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"florent\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2026\/01\/gc-elpowell-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"florent\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2026\/01\/12\/lo-publico-debe-prevalecer-sobre-la-arbitrariedad-del-presidente-jerome-powell-contra-donald-trump\/\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/2026\/01\/12\/lo-publico-debe-prevalecer-sobre-la-arbitrariedad-del-presidente-jerome-powell-contra-donald-trump\/\",\"name\":\"\u00abLo p\u00fablico debe prevalecer sobre la arbitrariedad del presidente\u00bb: Jerome Powell contra Donald Trump\u00a0 - El Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2026\/01\/12\/lo-publico-debe-prevalecer-sobre-la-arbitrariedad-del-presidente-jerome-powell-contra-donald-trump\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2026\/01\/12\/lo-publico-debe-prevalecer-sobre-la-arbitrariedad-del-presidente-jerome-powell-contra-donald-trump\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2026\/01\/Powell-contre-Trump-.png\",\"datePublished\":\"2026-01-12T09:03:46+00:00\",\"dateModified\":\"2026-01-12T09:03:50+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2026\/01\/12\/lo-publico-debe-prevalecer-sobre-la-arbitrariedad-del-presidente-jerome-powell-contra-donald-trump\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/es\/2026\/01\/12\/lo-publico-debe-prevalecer-sobre-la-arbitrariedad-del-presidente-jerome-powell-contra-donald-trump\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2026\/01\/12\/lo-publico-debe-prevalecer-sobre-la-arbitrariedad-del-presidente-jerome-powell-contra-donald-trump\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2026\/01\/Powell-contre-Trump-.png\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2026\/01\/Powell-contre-Trump-.png\",\"width\":2929,\"height\":1614,\"caption\":\"D\u00e9claration du pr\u00e9sident de la R\u00e9serve f\u00e9d\u00e9rale Jerome H. Powell\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2026\/01\/12\/lo-publico-debe-prevalecer-sobre-la-arbitrariedad-del-presidente-jerome-powell-contra-donald-trump\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/legrandcontinent.eu\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00abLo p\u00fablico debe prevalecer sobre la arbitrariedad del presidente\u00bb: Jerome Powell contra Donald Trump\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/\",\"name\":\"El Grand Continent\",\"description\":\"La escala pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\",\"name\":\"florent\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"caption\":\"florent\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00abLo p\u00fablico debe prevalecer sobre la arbitrariedad del presidente\u00bb: Jerome Powell contra Donald Trump\u00a0 - El Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/es\/2026\/01\/12\/lo-publico-debe-prevalecer-sobre-la-arbitrariedad-del-presidente-jerome-powell-contra-donald-trump\/","og_locale":"es_ES","og_type":"article","og_title":"\u00abLo p\u00fablico debe prevalecer sobre la arbitrariedad del presidente\u00bb: Jerome Powell contra Donald Trump\u00a0 - El Grand Continent","og_description":"Por primera vez desde el regreso de Donald Trump a la Casa Blanca, un alto cargo institucional estadounidense ha decidido enfrentarse p\u00fablicamente al presidente de los Estados Unidos.  Publicamos y comentamos el discurso del presidente de la Reserva Federal dirigido al pueblo estadounidense, al Congreso, al Senado y a los inversores internacionales.","og_url":"https:\/\/legrandcontinent.eu\/es\/2026\/01\/12\/lo-publico-debe-prevalecer-sobre-la-arbitrariedad-del-presidente-jerome-powell-contra-donald-trump\/","og_site_name":"El Grand Continent","article_published_time":"2026-01-12T09:03:46+00:00","article_modified_time":"2026-01-12T09:03:50+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2026\/01\/gc-elpowell-scaled.jpg","type":"image\/jpeg"}],"author":"florent","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2026\/01\/gc-elpowell-scaled.jpg","twitter_misc":{"Escrito por":"florent","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/es\/2026\/01\/12\/lo-publico-debe-prevalecer-sobre-la-arbitrariedad-del-presidente-jerome-powell-contra-donald-trump\/","url":"https:\/\/legrandcontinent.eu\/es\/2026\/01\/12\/lo-publico-debe-prevalecer-sobre-la-arbitrariedad-del-presidente-jerome-powell-contra-donald-trump\/","name":"\u00abLo p\u00fablico debe prevalecer sobre la arbitrariedad del presidente\u00bb: Jerome Powell contra Donald Trump\u00a0 - El Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/es\/2026\/01\/12\/lo-publico-debe-prevalecer-sobre-la-arbitrariedad-del-presidente-jerome-powell-contra-donald-trump\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/es\/2026\/01\/12\/lo-publico-debe-prevalecer-sobre-la-arbitrariedad-del-presidente-jerome-powell-contra-donald-trump\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2026\/01\/Powell-contre-Trump-.png","datePublished":"2026-01-12T09:03:46+00:00","dateModified":"2026-01-12T09:03:50+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/es\/2026\/01\/12\/lo-publico-debe-prevalecer-sobre-la-arbitrariedad-del-presidente-jerome-powell-contra-donald-trump\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/es\/2026\/01\/12\/lo-publico-debe-prevalecer-sobre-la-arbitrariedad-del-presidente-jerome-powell-contra-donald-trump\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/2026\/01\/12\/lo-publico-debe-prevalecer-sobre-la-arbitrariedad-del-presidente-jerome-powell-contra-donald-trump\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2026\/01\/Powell-contre-Trump-.png","contentUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2026\/01\/Powell-contre-Trump-.png","width":2929,"height":1614,"caption":"D\u00e9claration du pr\u00e9sident de la R\u00e9serve f\u00e9d\u00e9rale Jerome H. Powell"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/es\/2026\/01\/12\/lo-publico-debe-prevalecer-sobre-la-arbitrariedad-del-presidente-jerome-powell-contra-donald-trump\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legrandcontinent.eu\/es\/"},{"@type":"ListItem","position":2,"name":"\u00abLo p\u00fablico debe prevalecer sobre la arbitrariedad del presidente\u00bb: Jerome Powell contra Donald Trump\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/es\/#website","url":"https:\/\/legrandcontinent.eu\/es\/","name":"El Grand Continent","description":"La escala pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c","name":"florent","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","caption":"florent"}}]}},"lgc_categories":[{"id":6,"name":"Pol\u00edtica","slug":"politica"}],"lgc_author":{"id":7,"name":"El Grand Continent","slug":"el-grand-continent","description":null,"first_name":null,"last_name":null,"picture":null},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2026\/01\/Powell-contre-Trump-.png","width":2929,"height":1614,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2026\/01\/Powell-contre-Trump-.png","width":2929,"height":1614,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/87665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/users\/1366"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/comments?post=87665"}],"version-history":[{"count":19,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/87665\/revisions"}],"predecessor-version":[{"id":87735,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/87665\/revisions\/87735"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media\/87663"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media?parent=87665"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/categories?post=87665"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/tags?post=87665"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/staff?post=87665"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/editorial_format?post=87665"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/serie?post=87665"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/audience?post=87665"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/geo?post=87665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}