{"id":85252,"date":"2025-12-12T07:19:55","date_gmt":"2025-12-12T06:19:55","guid":{"rendered":"https:\/\/legrandcontinent.eu\/es\/?p=85252"},"modified":"2025-12-12T07:19:59","modified_gmt":"2025-12-12T06:19:59","slug":"debemos-prepararnos-para-una-guerra-de-una-magnitud-comparable-a-la-que-vivieron-nuestros-abuelos-o-bisabuelos-el-discurso-de-mark-rutte","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/es\/2025\/12\/12\/debemos-prepararnos-para-una-guerra-de-una-magnitud-comparable-a-la-que-vivieron-nuestros-abuelos-o-bisabuelos-el-discurso-de-mark-rutte\/","title":{"rendered":"\u00abDebemos prepararnos para una guerra de una magnitud comparable a la que vivieron nuestros abuelos o bisabuelos\u00bb: el discurso de Mark Rutte"},"content":{"rendered":"\n<p>Buenos d\u00edas, querido Johann, querido Detlef, querido Wolfgang, buenos d\u00edas a todos. Gracias por esta c\u00e1lida bienvenida, siempre es un placer estar en Berl\u00edn.<\/p>\n\n\n\n<p>Hace poco m\u00e1s de 36 a\u00f1os, en una noche de noviembre que ahora es famosa, el entonces secretario general de la OTAN, Manfred W\u00f6rner, se subi\u00f3 a su coche y condujo toda la noche hasta Berl\u00edn.<\/p>\n\n\n\n<p>En su prisa, se olvid\u00f3 de informar a su equipo en Bruselas de su destino.<\/p>\n\n\n\n<p>Manfred regresaba a su hogar en Alemania para unirse a la multitud que celebraba la ca\u00edda del Muro de Berl\u00edn.<\/p>\n\n\n\n<p>Hoy en d\u00eda, una parte del muro se encuentra en la sede de la OTAN. Se trataba de una barrera destinada a retener a las personas en el interior e impedir el paso de las ideas; ahora es un monumento a la fuerza de la libertad, un recordatorio del poder de la unidad y una lecci\u00f3n que nos ense\u00f1a que debemos mantenernos fuertes, confiados y decididos. Porque las oscuras fuerzas de la opresi\u00f3n est\u00e1n de nuevo en marcha. Hoy estoy aqu\u00ed para decirles cu\u00e1l es la posici\u00f3n de la OTAN y qu\u00e9 debemos hacer para evitar una guerra antes de que comience.<\/p>\n\n\n\n<p>Debemos ser muy claros sobre la amenaza: somos el pr\u00f3ximo objetivo de Rusia y ya estamos en peligro.<\/p>\n\n\n\n<p>Cuando asum\u00ed el cargo de secretario general de la OTAN el a\u00f1o pasado, advert\u00ed que lo que estaba sucediendo en Ucrania tambi\u00e9n pod\u00eda suceder en los pa\u00edses aliados y que deb\u00edamos adoptar una mentalidad de guerra.<\/p>\n\n\n\n<p>Este a\u00f1o hemos tomado decisiones importantes para reforzar la OTAN.<\/p>\n\n\n\n<p><a href=\"https:\/\/legrandcontinent.eu\/es\/2025\/06\/25\/5-del-pib-compromiso-con-ucrania-y-el-articulo-5-ha-resuelto-la-otan-la-ecuacion-trump-texto-integro-de-la-declaracion-de-la-haya\/\">En la cumbre de La Haya<\/a>, los aliados acordaron invertir el 5 % del PIB anual en defensa de aqu\u00ed a 2035, aumentar la producci\u00f3n de defensa en toda la Alianza y seguir apoyando a Ucrania.<\/p>\n\n\n\n<p>Pero no es momento de felicitarnos.<\/p>\n\n\n\n<p>Me temo que hay mucha gente que se duerme en sus laureles, que no siente la urgencia de la situaci\u00f3n, que piensa que el tiempo juega a nuestro favor.<\/p>\n\n\n\n<p>No es as\u00ed: hay que actuar ahora.<\/p>\n\n\n\n<p>El gasto y la producci\u00f3n de equipamiento de defensa de los pa\u00edses aliados deben aumentar r\u00e1pidamente, nuestras fuerzas armadas deben disponer de lo necesario para garantizar nuestra seguridad, y Ucrania debe disponer de lo necesario para defenderse, ahora mismo.<\/p>\n\n\n\n<p>Nuestros gobiernos, nuestros parlamentos y nuestros ciudadanos deben estar unidos en esta lucha, para que podamos seguir protegiendo la paz, la libertad y la prosperidad, nuestras sociedades abiertas, nuestras elecciones libres y nuestra prensa libre.<\/p>\n\n\n\n<p>Todos debemos aceptar que tenemos que actuar ahora mismo para defender nuestro modo de vida.<\/p>\n\n\n\n<p>Porque este a\u00f1o, Rusia se ha vuelto a\u00fan m\u00e1s descarada, imprudente y despiadada con la OTAN y Ucrania.<\/p>\n\n\n\n<p>Durante la Guerra Fr\u00eda, el presidente Reagan advirti\u00f3 contra los \u00abimpulsos agresivos de un imperio del mal\u00bb. Hoy, el presidente Putin se ha propuesto construir un nuevo imperio.<\/p>\n\n\n\n<p>Est\u00e1 lanzando todas sus fuerzas contra Ucrania, matando a soldados y civiles, destruyendo los refugios de la humanidad: casas, escuelas y hospitales.<\/p>\n\n\n\n<p>Desde principios de a\u00f1o, Rusia ha lanzado m\u00e1s de 46.000 drones y misiles contra Ucrania. Probablemente produce 2.900 drones de ataque al mes, as\u00ed como un n\u00famero similar de se\u00f1uelos destinados a distraer la atenci\u00f3n de las defensas a\u00e9reas.<\/p>\n\n\n\n<p>En 2025, Rusia produjo alrededor de 2.000 misiles de crucero y bal\u00edsticos terrestres, lo que la acerca a su pico de producci\u00f3n.<\/p>\n\n\n\n<p>Mientras Putin intenta destruir Ucrania, tambi\u00e9n est\u00e1 devastando su propio pa\u00eds.<\/p>\n\n\n\n<p>Desde el inicio de la guerra en 2022, se han registrado m\u00e1s de 1,1 millones de v\u00edctimas rusas. Este a\u00f1o, Rusia ha perdido una media de 1.200 soldados al d\u00eda. Pi\u00e9nsenlo: m\u00e1s de un mill\u00f3n de v\u00edctimas hasta la fecha y 1.200 al d\u00eda, muertos o heridos, solo este a\u00f1o.<\/p>\n\n\n\n<p>Putin est\u00e1 pagando su orgullo con la sangre de su propio pueblo: si est\u00e1 dispuesto a sacrificar as\u00ed a los rusos de a pie, \u00bfqu\u00e9 estar\u00e1 dispuesto a hacernos a nosotros?<\/p>\n\n\n\n<p>En su visi\u00f3n distorsionada de la historia y del mundo, Putin cree que nuestra libertad amenaza su control del poder y que queremos destruir Rusia.<\/p>\n\n\n\n<p>Pero Putin se encarga muy bien de ello por s\u00ed mismo.<\/p>\n\n\n\n<p>La econom\u00eda rusa se centra ahora en la guerra, y no en la prosperidad de su pueblo. Rusia dedica casi el 40 % de su presupuesto a la agresi\u00f3n, y alrededor del 70 % de todas las m\u00e1quinas herramienta de Rusia se utilizan en la producci\u00f3n militar. Los impuestos aumentan, la inflaci\u00f3n se ha disparado y la gasolina est\u00e1 racionada.<\/p>\n\n\n\n<p>El pr\u00f3ximo eslogan de la campa\u00f1a presidencial de Putin deber\u00eda ser: \u00ab<em>Make Russia Weak Again<\/em>\u00bb.&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-85252' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/es\/2025\/12\/12\/debemos-prepararnos-para-una-guerra-de-una-magnitud-comparable-a-la-que-vivieron-nuestros-abuelos-o-bisabuelos-el-discurso-de-mark-rutte\/#easy-footnote-bottom-1-85252' title='\u00abDevolverle su debilidad a Rusia\u00bb.'><sup>1<\/sup><\/a><\/span><\/span> Por supuesto, no es que le molesten las elecciones libres y justas.<\/p>\n\n\n\n<p>\u00bfC\u00f3mo puede Putin continuar su guerra contra Ucrania?<\/p>\n\n\n\n<p>La respuesta es sencilla: China.<\/p>\n\n\n\n<p>China es el salvavidas de Rusia. Quiere evitar que su aliado pierda en Ucrania.<\/p>\n\n\n\n<p>Sin su apoyo, Rusia no podr\u00eda seguir librando esta guerra. Por ejemplo, alrededor del 80 % de los componentes electr\u00f3nicos esenciales de los drones rusos y otros sistemas se fabrican en China. Cuando mueren civiles en Kiev o J\u00e1rkov, la tecnolog\u00eda china suele estar presente en las armas que los han matado.<\/p>\n\n\n\n<p>Tampoco olvidemos que Rusia tambi\u00e9n cuenta con Corea del Norte e Ir\u00e1n en su lucha contra la libertad, para obtener municiones y equipo militar.<\/p>\n\n\n\n<p>Hasta ahora, Putin solo ha desempe\u00f1ado el papel de pacificador cuando le ha convenido, con el fin de ganar tiempo para continuar su guerra.<\/p>\n\n\n\n<p>El presidente Trump quiere poner fin al derramamiento de sangre ahora mismo, y es el \u00fanico que puede llevar a Putin a la mesa de negociaciones.<\/p>\n\n\n\n<p>Pongamos a prueba a Putin: veamos si realmente quiere la paz o si prefiere que contin\u00fae la masacre.<\/p>\n\n\n\n<p>Es esencial que todos sigamos presionando a Rusia y apoyando los esfuerzos sinceros para poner fin a esta guerra.<\/p>\n\n\n\n<p>Gracias al apoyo de la OTAN, Ucrania puede ahora defenderse, estar en posici\u00f3n de fuerza para garantizar una paz justa y duradera, y ser capaz de disuadir cualquier agresi\u00f3n rusa en el futuro.<\/p>\n\n\n\n<p>Miles de millones de d\u00f3lares en material militar esencial est\u00e1n llegando a Ucrania, procedentes de Estados Unidos y financiados por los aliados y socios.<\/p>\n\n\n\n<p>Se trata de una potencia de fuego que solo Estados Unidos puede proporcionar; lo hacemos en el marco de una iniciativa de la OTAN denominada PURL.<\/p>\n\n\n\n<p>Desde su lanzamiento este verano, PURL ha suministrado aproximadamente el 75 % de todos los misiles destinados a las bater\u00edas Patriot de Ucrania y el 90 % de la munici\u00f3n utilizada en sus otros sistemas de defensa a\u00e9rea.<\/p>\n\n\n\n<p>Quiero dar las gracias a Alemania y a los dem\u00e1s aliados por su apoyo.<\/p>\n\n\n\n<p>El programa PURL permite a Ucrania seguir luchando y protege a su poblaci\u00f3n. Espero que m\u00e1s aliados contribuyan a \u00e9l y refuercen su apoyo a Ucrania de muchas otras maneras.<\/p>\n\n\n\n<p>Porque debemos fortalecer a Ucrania para que pueda detener el avance de Putin.<\/p>\n\n\n\n<p>Imaginemos por un momento que Putin logra su objetivo: Ucrania bajo el yugo de la ocupaci\u00f3n rusa, sus fuerzas presionando contra una frontera m\u00e1s larga con la OTAN y un riesgo considerablemente mayor de un ataque armado contra nosotros.<\/p>\n\n\n\n<p>Esto requerir\u00eda un cambio verdaderamente gigantesco en nuestra disuasi\u00f3n y defensa.<\/p>\n\n\n\n<p>La OTAN tendr\u00eda que aumentar considerablemente su presencia militar a lo largo de su flanco oriental, y los aliados tendr\u00edan que ir mucho m\u00e1s lejos y m\u00e1s r\u00e1pido en materia de gasto y producci\u00f3n de defensa.<\/p>\n\n\n\n<p>En tal escenario, echar\u00edamos de menos los tiempos en que nos parec\u00eda suficiente dedicar el 3,5 % del PIB a la defensa.<\/p>\n\n\n\n<p>Esta cifra aumentar\u00eda considerablemente y, ante esta amenaza inminente, tendr\u00edamos que actuar con rapidez. Habr\u00eda presupuestos de emergencia, recortes en el gasto p\u00fablico, perturbaciones econ\u00f3micas y una presi\u00f3n financiera adicional.<\/p>\n\n\n\n<p>En este escenario, ser\u00edan inevitables compromisos dolorosos, pero absolutamente necesarios para proteger a nuestras poblaciones.<\/p>\n\n\n\n<p>Por lo tanto, no lo olvidemos: la seguridad de Ucrania es nuestra seguridad.<\/p>\n\n\n\n<p>Las defensas de la OTAN pueden resistir por ahora. Pero con su econom\u00eda dedicada a la guerra, Rusia podr\u00eda estar lista para utilizar la fuerza militar contra la OTAN en un plazo de cinco a\u00f1os.<\/p>\n\n\n\n<p>Ya est\u00e1 intensificando su campa\u00f1a secreta contra nuestras sociedades.<\/p>\n\n\n\n<p>La lista de objetivos de sabotaje de Rusia no se limita a las infraestructuras cr\u00edticas, la industria de defensa y las instalaciones militares. Se han perpetrado ataques contra almacenes y centros comerciales, se han ocultado explosivos en paquetes y Polonia est\u00e1 investigando actualmente actos de sabotaje contra su red ferroviaria.<\/p>\n\n\n\n<p>Este a\u00f1o hemos sido testigos de flagrantes violaciones del espacio a\u00e9reo por parte de Rusia.<\/p>\n\n\n\n<p>Ya se trate de drones sobre Polonia y Ruman\u00eda o de aviones de combate sobre Estonia, este tipo de incidentes ponen en peligro vidas humanas y aumentan el riesgo de escalada.<\/p>\n\n\n\n<p>Aunque a menudo pensamos en el riesgo principalmente en t\u00e9rminos del flanco oriental, el radio de acci\u00f3n de Rusia no se limita a tierra firme.<\/p>\n\n\n\n<p><a href=\"https:\/\/legrandcontinent.eu\/es\/2025\/10\/20\/putin-y-la-guerra-en-europa-el-escenario-del-frente-atlantico\/\">El \u00c1rtico y el Atl\u00e1ntico son v\u00edas adicionales,<\/a> que nos recuerdan una vez m\u00e1s por qu\u00e9 esta Alianza es tan crucial desde hace tantos a\u00f1os, a ambos lados del Atl\u00e1ntico.<\/p>\n\n\n\n<p>Por lo tanto, trabajamos juntos para garantizar la seguridad de todos los Aliados, en tierra, mar y aire. Hemos reforzado nuestra vigilancia, disuasi\u00f3n y defensa a lo largo del flanco oriental con Eastern Sentry, y seguimos protegiendo nuestras infraestructuras cr\u00edticas en el mar con Baltic Sentry.<\/p>\n\n\n\n<p>La respuesta de la OTAN a las provocaciones de Rusia ha sido tranquila, decisiva y proporcionada, pero debemos prepararnos para una nueva escalada y una nueva confrontaci\u00f3n.<\/p>\n\n\n\n<p>Nuestro compromiso inquebrantable con el art\u00edculo 5 del Tratado, seg\u00fan el cual un ataque contra uno es un ataque contra todos, env\u00eda un mensaje contundente.<\/p>\n\n\n\n<p>Cualquier agresor debe saber que podemos responder con fuerza, y que lo haremos. Por eso hemos tomado decisiones cruciales en La Haya: en materia de gasto en defensa, producci\u00f3n y apoyo a Ucrania.<\/p>\n\n\n\n<p>Estamos observando avances importantes. Tomemos como ejemplo la producci\u00f3n de municiones: la producci\u00f3n europea de proyectiles de artiller\u00eda de 155 mil\u00edmetros se ha multiplicado por seis en comparaci\u00f3n con hace dos a\u00f1os.<\/p>\n\n\n\n<p>Este a\u00f1o visit\u00e9 una nueva f\u00e1brica en Alemania, en Unterl\u00fc\u00df, que tiene previsto producir 350.000 proyectiles de artiller\u00eda al a\u00f1o.<\/p>\n\n\n\n<p>Alemania est\u00e1 modificando profundamente su enfoque de la defensa y la industria con el fin de aumentar la producci\u00f3n, y las inversiones que destina a sus fuerzas armadas son extraordinarias. Se han previsto alrededor de 152.000 millones de euros para defensa hasta 2029, lo que representa el 3,5 % de su PIB hasta 2029.<\/p>\n\n\n\n<p>Alemania es una potencia l\u00edder en Europa y una fuerza motriz dentro de la OTAN. El liderazgo alem\u00e1n es esencial para nuestra defensa colectiva. Su compromiso de asumir la parte que le corresponde en nuestra seguridad es un ejemplo para todos los aliados.<\/p>\n\n\n\n<p>Debemos estar preparados. Porque, ahora que el primer cuarto del siglo XXI llega a su fin, los conflictos ya no se libran a distancia: est\u00e1n a nuestras puertas.<\/p>\n\n\n\n<p>Rusia ha tra\u00eddo de vuelta la guerra a Europa y debemos prepararnos para una guerra de una magnitud comparable a la que vivieron nuestros abuelos o bisabuelos.<\/p>\n\n\n\n<p>Imaginemos un conflicto que afecte a todos los hogares, a todos los lugares de trabajo, que provoque destrucci\u00f3n, movilizaci\u00f3n masiva, millones de personas desplazadas, sufrimiento por todas partes y p\u00e9rdidas extremas.<\/p>\n\n\n\n<p>Es una idea terrible.<\/p>\n\n\n\n<p>Pero si cumplimos nuestros compromisos, es una tragedia que podemos evitar.<\/p>\n\n\n\n<p>La OTAN est\u00e1 ah\u00ed para proteger a mil millones de personas a ambos lados del Atl\u00e1ntico.<\/p>\n\n\n\n<p>Nuestra misi\u00f3n es protegerlos a ustedes, a sus familias, a sus amigos y a su futuro.<\/p>\n\n\n\n<p>No podemos bajar la guardia, y no lo haremos.<\/p>\n\n\n\n<p>Cuento con que nuestros gobiernos cumplan sus compromisos y vayan m\u00e1s all\u00e1 y m\u00e1s r\u00e1pido, porque no podemos flaquear ni fracasar.<\/p>\n\n\n\n<p>Escuchen las sirenas que suenan en toda Ucrania, vean los cad\u00e1veres que se retiran de los escombros y piensen en los ucranianos que podr\u00edan acostarse esta noche y no despertarse ma\u00f1ana. \u00bfQu\u00e9 diferencia hay entre lo que les est\u00e1 pasando a ellos y lo que nos podr\u00eda pasar a nosotros?<\/p>\n\n\n\n<p>Solo la OTAN.<\/p>\n\n\n\n<p>Como secretario general, es mi deber decirles lo que nos espera si no actuamos m\u00e1s r\u00e1pidamente, si no invertimos en defensa y si no seguimos apoyando a Ucrania.<\/p>\n\n\n\n<p>S\u00e9 que este mensaje es dif\u00edcil de escuchar ahora que se acercan las fiestas de fin de a\u00f1o, cuando nuestros pensamientos se dirigen hacia la esperanza, la luz y la paz.<\/p>\n\n\n\n<p>Pero podemos sacar valor y fuerza del hecho de que estamos unidos en la OTAN, decididos y conscientes de estar en el lado correcto de la historia.<\/p>\n\n\n\n<p>Tenemos un plan, sabemos lo que hay que hacer, as\u00ed que actuemos.<\/p>\n\n\n\n<p>Debemos hacerlo.<\/p>\n\n\n\n<p>Gracias.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abSomos el pr\u00f3ximo objetivo de Rusia y ya estamos en peligro\u00bb.<\/p>\n<p>Desde Berl\u00edn, el secretario general de la OTAN dirigi\u00f3 un mensaje especialmente grave a los ciudadanos de la Uni\u00f3n.<\/p>\n<p>Lo traducimos.<\/p>\n","protected":false},"author":17959,"featured_media":85233,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-speeches.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":10,"_lgc_tts_audio_url":"","_lgc_tts_voice":"","_lgc_tts_publish":false,"_lgc_tts_history_item_id":"","_lgc_tts_generated_at":"","_lgc_tts_status":"","_lgc_tts_error":"","footnotes":""},"categories":[128],"tags":[],"staff":[],"editorial_format":[1474],"serie":[],"audience":[],"geo":[177],"class_list":["post-85252","post","type-post","status-publish","format-standard","hentry","category-guerra","editorial_format-archivos-y-discursos","geo-europa"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":85233,"excerpt":"\u00abSomos el pr\u00f3ximo objetivo de Rusia y ya estamos en peligro\u00bb.\r\n\r\nDesde Berl\u00edn, el secretario general de la OTAN dirigi\u00f3 un mensaje especialmente grave a los ciudadanos de la Uni\u00f3n.\r\n\r\nLo traducimos.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00abDebemos prepararnos para una guerra de una magnitud comparable a la que vivieron nuestros abuelos o bisabuelos\u00bb: el discurso de Mark Rutte - El Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/es\/2025\/12\/12\/debemos-prepararnos-para-una-guerra-de-una-magnitud-comparable-a-la-que-vivieron-nuestros-abuelos-o-bisabuelos-el-discurso-de-mark-rutte\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00abDebemos prepararnos para una guerra de una magnitud comparable a la que vivieron nuestros abuelos o bisabuelos\u00bb: el discurso de Mark Rutte - El Grand Continent\" \/>\n<meta property=\"og:description\" content=\"\u00abSomos el pr\u00f3ximo objetivo de Rusia y ya estamos en peligro\u00bb.  Desde Berl\u00edn, el secretario general de la OTAN dirigi\u00f3 un mensaje especialmente grave a los ciudadanos de la Uni\u00f3n.  Lo traducimos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/es\/2025\/12\/12\/debemos-prepararnos-para-una-guerra-de-una-magnitud-comparable-a-la-que-vivieron-nuestros-abuelos-o-bisabuelos-el-discurso-de-mark-rutte\/\" \/>\n<meta property=\"og:site_name\" content=\"El Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-12T06:19:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-12T06:19:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/12\/gc-elrutte-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"anainesfernandez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/12\/gc-elrutte-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"anainesfernandez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/12\/12\/debemos-prepararnos-para-una-guerra-de-una-magnitud-comparable-a-la-que-vivieron-nuestros-abuelos-o-bisabuelos-el-discurso-de-mark-rutte\/\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/2025\/12\/12\/debemos-prepararnos-para-una-guerra-de-una-magnitud-comparable-a-la-que-vivieron-nuestros-abuelos-o-bisabuelos-el-discurso-de-mark-rutte\/\",\"name\":\"\u00abDebemos prepararnos para una guerra de una magnitud comparable a la que vivieron nuestros abuelos o bisabuelos\u00bb: el discurso de Mark Rutte - El Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/12\/12\/debemos-prepararnos-para-una-guerra-de-una-magnitud-comparable-a-la-que-vivieron-nuestros-abuelos-o-bisabuelos-el-discurso-de-mark-rutte\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/12\/12\/debemos-prepararnos-para-una-guerra-de-una-magnitud-comparable-a-la-que-vivieron-nuestros-abuelos-o-bisabuelos-el-discurso-de-mark-rutte\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/12\/SIPA_sipahub60095455_000002-scaled.jpg\",\"datePublished\":\"2025-12-12T06:19:55+00:00\",\"dateModified\":\"2025-12-12T06:19:59+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/570398dd8da37ba5d66dec6d242bd33c\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/12\/12\/debemos-prepararnos-para-una-guerra-de-una-magnitud-comparable-a-la-que-vivieron-nuestros-abuelos-o-bisabuelos-el-discurso-de-mark-rutte\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/es\/2025\/12\/12\/debemos-prepararnos-para-una-guerra-de-una-magnitud-comparable-a-la-que-vivieron-nuestros-abuelos-o-bisabuelos-el-discurso-de-mark-rutte\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/12\/12\/debemos-prepararnos-para-una-guerra-de-una-magnitud-comparable-a-la-que-vivieron-nuestros-abuelos-o-bisabuelos-el-discurso-de-mark-rutte\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/12\/SIPA_sipahub60095455_000002-scaled.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/12\/SIPA_sipahub60095455_000002-scaled.jpg\",\"width\":2560,\"height\":1664,\"caption\":\"Mark Rutte, secr\u00e9taire g\u00e9n\u00e9ral de l'OTAN, prononce un discours liminaire \u00e0 l'invitation de la Conf\u00e9rence de Munich sur la s\u00e9curit\u00e9 dans les locaux de la repr\u00e9sentation de l'\u00c9tat de Bavi\u00e8re le 11 d\u00e9cembre 2025 \u00e0 Berlin. \u00a9 Michael Kappeler\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/12\/12\/debemos-prepararnos-para-una-guerra-de-una-magnitud-comparable-a-la-que-vivieron-nuestros-abuelos-o-bisabuelos-el-discurso-de-mark-rutte\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/legrandcontinent.eu\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00abDebemos prepararnos para una guerra de una magnitud comparable a la que vivieron nuestros abuelos o bisabuelos\u00bb: el discurso de Mark Rutte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/\",\"name\":\"El Grand Continent\",\"description\":\"La escala pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/570398dd8da37ba5d66dec6d242bd33c\",\"name\":\"anainesfernandez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/fe25c21e6213f69a683147fabda32586?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/fe25c21e6213f69a683147fabda32586?s=96&d=mm&r=g\",\"caption\":\"anainesfernandez\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00abDebemos prepararnos para una guerra de una magnitud comparable a la que vivieron nuestros abuelos o bisabuelos\u00bb: el discurso de Mark Rutte - El Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/es\/2025\/12\/12\/debemos-prepararnos-para-una-guerra-de-una-magnitud-comparable-a-la-que-vivieron-nuestros-abuelos-o-bisabuelos-el-discurso-de-mark-rutte\/","og_locale":"es_ES","og_type":"article","og_title":"\u00abDebemos prepararnos para una guerra de una magnitud comparable a la que vivieron nuestros abuelos o bisabuelos\u00bb: el discurso de Mark Rutte - El Grand Continent","og_description":"\u00abSomos el pr\u00f3ximo objetivo de Rusia y ya estamos en peligro\u00bb.  Desde Berl\u00edn, el secretario general de la OTAN dirigi\u00f3 un mensaje especialmente grave a los ciudadanos de la Uni\u00f3n.  Lo traducimos.","og_url":"https:\/\/legrandcontinent.eu\/es\/2025\/12\/12\/debemos-prepararnos-para-una-guerra-de-una-magnitud-comparable-a-la-que-vivieron-nuestros-abuelos-o-bisabuelos-el-discurso-de-mark-rutte\/","og_site_name":"El Grand Continent","article_published_time":"2025-12-12T06:19:55+00:00","article_modified_time":"2025-12-12T06:19:59+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/12\/gc-elrutte-scaled.jpg","type":"image\/jpeg"}],"author":"anainesfernandez","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/12\/gc-elrutte-scaled.jpg","twitter_misc":{"Escrito por":"anainesfernandez","Tiempo de lectura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/es\/2025\/12\/12\/debemos-prepararnos-para-una-guerra-de-una-magnitud-comparable-a-la-que-vivieron-nuestros-abuelos-o-bisabuelos-el-discurso-de-mark-rutte\/","url":"https:\/\/legrandcontinent.eu\/es\/2025\/12\/12\/debemos-prepararnos-para-una-guerra-de-una-magnitud-comparable-a-la-que-vivieron-nuestros-abuelos-o-bisabuelos-el-discurso-de-mark-rutte\/","name":"\u00abDebemos prepararnos para una guerra de una magnitud comparable a la que vivieron nuestros abuelos o bisabuelos\u00bb: el discurso de Mark Rutte - El Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/es\/2025\/12\/12\/debemos-prepararnos-para-una-guerra-de-una-magnitud-comparable-a-la-que-vivieron-nuestros-abuelos-o-bisabuelos-el-discurso-de-mark-rutte\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/es\/2025\/12\/12\/debemos-prepararnos-para-una-guerra-de-una-magnitud-comparable-a-la-que-vivieron-nuestros-abuelos-o-bisabuelos-el-discurso-de-mark-rutte\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/12\/SIPA_sipahub60095455_000002-scaled.jpg","datePublished":"2025-12-12T06:19:55+00:00","dateModified":"2025-12-12T06:19:59+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/570398dd8da37ba5d66dec6d242bd33c"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/es\/2025\/12\/12\/debemos-prepararnos-para-una-guerra-de-una-magnitud-comparable-a-la-que-vivieron-nuestros-abuelos-o-bisabuelos-el-discurso-de-mark-rutte\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/es\/2025\/12\/12\/debemos-prepararnos-para-una-guerra-de-una-magnitud-comparable-a-la-que-vivieron-nuestros-abuelos-o-bisabuelos-el-discurso-de-mark-rutte\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/2025\/12\/12\/debemos-prepararnos-para-una-guerra-de-una-magnitud-comparable-a-la-que-vivieron-nuestros-abuelos-o-bisabuelos-el-discurso-de-mark-rutte\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/12\/SIPA_sipahub60095455_000002-scaled.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/12\/SIPA_sipahub60095455_000002-scaled.jpg","width":2560,"height":1664,"caption":"Mark Rutte, secr\u00e9taire g\u00e9n\u00e9ral de l'OTAN, prononce un discours liminaire \u00e0 l'invitation de la Conf\u00e9rence de Munich sur la s\u00e9curit\u00e9 dans les locaux de la repr\u00e9sentation de l'\u00c9tat de Bavi\u00e8re le 11 d\u00e9cembre 2025 \u00e0 Berlin. \u00a9 Michael Kappeler"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/es\/2025\/12\/12\/debemos-prepararnos-para-una-guerra-de-una-magnitud-comparable-a-la-que-vivieron-nuestros-abuelos-o-bisabuelos-el-discurso-de-mark-rutte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legrandcontinent.eu\/es\/"},{"@type":"ListItem","position":2,"name":"\u00abDebemos prepararnos para una guerra de una magnitud comparable a la que vivieron nuestros abuelos o bisabuelos\u00bb: el discurso de Mark Rutte"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/es\/#website","url":"https:\/\/legrandcontinent.eu\/es\/","name":"El Grand Continent","description":"La escala pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/570398dd8da37ba5d66dec6d242bd33c","name":"anainesfernandez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/fe25c21e6213f69a683147fabda32586?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fe25c21e6213f69a683147fabda32586?s=96&d=mm&r=g","caption":"anainesfernandez"}}]}},"lgc_categories":[{"id":128,"name":"Guerra","slug":"guerra"}],"lgc_author":null,"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/12\/SIPA_sipahub60095455_000002-scaled.jpg","width":2560,"height":1664,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/12\/SIPA_sipahub60095455_000002-scaled.jpg","width":2560,"height":1664,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/85252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/users\/17959"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/comments?post=85252"}],"version-history":[{"count":5,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/85252\/revisions"}],"predecessor-version":[{"id":85263,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/85252\/revisions\/85263"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media\/85233"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media?parent=85252"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/categories?post=85252"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/tags?post=85252"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/staff?post=85252"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/editorial_format?post=85252"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/serie?post=85252"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/audience?post=85252"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/geo?post=85252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}