{"id":832,"date":"2021-02-12T18:13:16","date_gmt":"2021-02-12T18:13:16","guid":{"rendered":"https:\/\/legrandcontinent.eu\/es\/?p=832"},"modified":"2022-05-31T15:46:13","modified_gmt":"2022-05-31T14:46:13","slug":"descubramos-a-mario-draghi","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/es\/2021\/02\/12\/descubramos-a-mario-draghi\/","title":{"rendered":"Descubramos a Mario Draghi"},"content":{"rendered":"\n<p class=\"intro\">Hoy Mario Draghi completa su mandato a la cabeza del Banco Central Europeo, despu\u00e9s de ocho a\u00f1os fundamentales en la historia reciente de la Uni\u00f3n Europea. En esta ocasi\u00f3n, les proponemos desplegar el pensamiento (geo)pol\u00edtico del \u00faltimo inquilino de la <em>Skytower <\/em>de Fr\u00e1ncfort.<\/p>\n\n\n\n<p class=\"intro\">Generalmente conocemos algunas grandes l\u00edneas de la vida de Mario Draghi. Ha vivido tres grandes momentos en su carrera: Goldman Sachs (2002-2005), Banco de Italia (2006-2011), Banco Central Europeo (2011-2019). Autor de una tesis en econom\u00eda realizada bajo la direcci\u00f3n de dos de los investigadores del MIT m\u00e1s prominentes del mundo, Robert Solow y Franco Modigliani, \u201cSuper Mario\u201d es ante todo una segunda opci\u00f3n s\u00f3lida en la carrera para suceder a Jean Claude Trichet. Sin embargo, la dimisi\u00f3n de Axel Weber, la primera opci\u00f3n, durante su mandato [como presidente del Bundesbank], le abre a Draghi el camino hacia la presidencia del BCE. No hacen falta m\u00e1s que unos pocos meses para que el romano, llegado a Fr\u00e1ncfort en 2011, se haga famoso por su frasecita \u201ctodo lo que sea necesario\u201d (<em>whatever it takes<\/em>)<em> <\/em>para salvar la zona euro. Y el a\u00f1adido desafiante: \u201cy cr\u00e9anme, ser\u00e1 suficiente\u2026\u201d.<\/p>\n\n\n\n<p class=\"intro\">Sin embargo, \u201cel trabajo, la obra y la acci\u00f3n\u201d de Draghi, por retomar el tr\u00edptico de Arendt, van m\u00e1s all\u00e1 de algunos elementos conocidos y reconocidos. En vez de detenerse en la pol\u00edtica macroecon\u00f3mica y en la pol\u00edtica monetaria, se trata de entender c\u00f3mo un pensamiento geopol\u00edtico y europeo pudo aparecer en los discursos de Draghi desde su acceso a posiciones de poder.<\/p>\n\n\n\n<p class=\"intro\">Les proponemos por tanto descubrir a un Mario Draghi a la vez preocupado por la soberan\u00eda que la Uni\u00f3n Europea puede materializar, inquieto por las relaciones entre la Uni\u00f3n y los Estados en materia de pol\u00edtica presupuestaria y crecimiento, abogando por una cooperaci\u00f3n y gobernanza econ\u00f3mica mundial y, finalmente, ampliamente favorable a la formaci\u00f3n y transmisi\u00f3n de un espacio p\u00fablico y cultural europeo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>I \u2013 Repensar la soberan\u00eda en y a trav\u00e9s de la Uni\u00f3n<\/strong><\/h2>\n\n\n\n<h4 class=\"wp-block-heading\"><a href=\"https:\/\/www.ecb.europa.eu\/press\/key\/date\/2013\/html\/sp131009_1.es.html\"><strong>Europa en pos de una \u201cUni\u00f3n m\u00e1s perfecta\u201d<\/strong><\/a><\/h4>\n\n\n\n<p><em><strong>Conferencia en la Harvard Kennedy School el 9 de octubre de 2013<\/strong><\/em><\/p>\n\n\n\n<p>El pre\u00e1mbulo del Tratado de la Uni\u00f3n Europea establece como objetivo de la UE una \u00abuni\u00f3n cada vez m\u00e1s estrecha\u00bb. Este objetivo genera ansiedad en algunas personas, pues parece prometer un recorrido inexorable hacia un futuro superestado. Muchos europeos, con historias y culturas nacionales diferentes, no se sienten preparados para ello.<\/p>\n\n\n\n<p>Por tanto, es importante entender que la expresi\u00f3n \u201cuna uni\u00f3n cada vez m\u00e1s estrecha\u201d no refleja adecuadamente la agenda que Europa tiene actualmente ante s\u00ed. En mi opini\u00f3n, el establecimiento de una \u201cUni\u00f3n m\u00e1s perfecta\u201d, como dice el texto de la Constituci\u00f3n de Estados Unidos, ilustra mejor este objetivo.<\/p>\n\n\n\n<p>[\u2026]<\/p>\n\n\n\n<p><em>Soberan\u00eda compartida en un mercado \u00fanico<\/em><\/p>\n\n\n\n<p>La cuesti\u00f3n m\u00e1s dif\u00edcil en Europa es [&#8230;] cu\u00e1nta soberan\u00eda debe compartirse.<\/p>\n\n\n\n<p>[\u2026]<\/p>\n\n\n\n<p>La soberan\u00eda puede analizarse de forma normativa, enfoque propugnado hist\u00f3ricamente por absolutistas como Jean Bodin en el siglo XVI. La soberan\u00eda se defin\u00eda en relaci\u00f3n con la potestad de declarar la guerra y negociar las condiciones de la paz, recaudar tributos, acu\u00f1ar moneda y juzgar en \u00faltima instancia.<\/p>\n\n\n\n<p>La soberan\u00eda tambi\u00e9n puede analizarse de manera positiva. En este caso, est\u00e1 relacionada con la capacidad para prestar en la pr\u00e1ctica los servicios esenciales que el pueblo espera del gobierno. Un soberano que no pueda cumplir efectivamente su mandato ser\u00e1 soberano solo nominalmente.<\/p>\n\n\n\n<p>Este segundo enfoque es m\u00e1s coherente con los textos de los fil\u00f3sofos pol\u00edticos que m\u00e1s han influido en nuestras democracias modernas. John Locke, en su segundo tratado sobre el gobierno, afirma que el soberano solo existe como poder fiduciario para actuar con determinados fines. Es la capacidad para lograr esos fines lo que define, y legitima, la soberan\u00eda.<\/p>\n\n\n\n<p>[\u2026]<\/p>\n\n\n\n<p>Considero que esta visi\u00f3n positiva es, en esencia, el camino correcto para analizar la soberan\u00eda y creo que debe servir como principio rector para decidir qu\u00e9 competencias deben ser nacionales y cu\u00e1les europeas. Hemos de fijarnos en la eficacia, no en principios abstractos que pueden resultar vac\u00edos en el mundo de hoy.<\/p>\n\n\n\n<p>[\u2026]<\/p>\n\n\n\n<p class=\"comment\">Esta forma de pensar ya est\u00e1 de hecho consagrada en el Tratado de la Uni\u00f3n Europea bajo la forma del principio de subsidiariedad. Este principio establece que las competencias solo deben transferirse al nivel de la Uni\u00f3n si la acci\u00f3n es m\u00e1s eficaz all\u00ed que en un nivel de gobierno inferior. En otras palabras, se pone claramente el \u00e9nfasis en la efectividad de la pol\u00edtica.<\/p>\n\n\n\n<p class=\"comment\">Preocupado por la evoluci\u00f3n reciente de la geopol\u00edtica internacional, Mario Draghi pretende, tanto en el texto anterior como en el siguiente, estudiar la UE entrando en el campo de la teor\u00eda pol\u00edtica. Se opone, por lo tanto, a dos visiones de la noci\u00f3n de soberan\u00eda. La primera proviene de los <em>Seis Libros de la Rep\u00fablica <\/em>de Jean Bodin&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-832' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/es\/2021\/02\/12\/descubramos-a-mario-draghi\/#easy-footnote-bottom-1-832' title='BODIN J., &lt;em&gt;Les Six Livres de la R\u00e9publique&lt;\/em&gt;, 1576, p. 152.'><sup>1<\/sup><\/a><\/span><\/span>, probablemente uno de los primeros fil\u00f3sofos del Renacimiento en definir este concepto: \u201cLa soberan\u00eda es el poder absoluto y perpetuo de una Rep\u00fablica, que los latinos llaman <em>majestatem<\/em> [\u2026], los hebreos lo llaman <em>tomadchavet<\/em>, es decir, el mayor poder de mando\u201d. La soberan\u00eda, as\u00ed, \u201cno est\u00e1 limitada ni en poder ni en mando\u201d. Una definici\u00f3n bastante vaga, pero que fue importante en el an\u00e1lisis de los Estados durante el Renacimiento y que, sobre todo, como indica el mismo Draghi, floreci\u00f3 cuando se piensa en los Estados llamados \u201csoberanos\u201d: no reciben \u00f3rdenes de nadie, pueden declarar la guerra, acu\u00f1ar su propia moneda, aprobar sus propias leyes, etc. En consecuencia, es una definici\u00f3n que estudia los principios, las reglas que rigen el gobierno de los pueblos.<\/p>\n\n\n\n<p class=\"comment\">A esta definici\u00f3n, Draghi opone otra concepci\u00f3n de la soberan\u00eda, esta vez basada no en la norma sino en la capacidad real de los gobernantes para actuar seg\u00fan las funciones que se les otorgan. Esta es una visi\u00f3n propiamente lockeana&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-832' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/es\/2021\/02\/12\/descubramos-a-mario-draghi\/#easy-footnote-bottom-2-832' title='&amp;nbsp;LOCKE J., &lt;em&gt;Deuxi\u00e8me trait\u00e9 du gouvernement civil&lt;\/em&gt;, 1690'><sup>2<\/sup><\/a><\/span><\/span>, heredera del pensamiento del contrato social, el liberalismo y el constitucionalismo brit\u00e1nico: los gobernantes deben implementar las disposiciones solicitadas por los ciudadanos (que los eligieron) y son soberanos en la medida en que puedan ejercer eficazmente sus funciones y lograr los resultados deseados.<\/p>\n\n\n\n<p class=\"comment\">Draghi toma partido por esta segunda definici\u00f3n. Para el ahora expresidente del BCE, la Uni\u00f3n Europea se construy\u00f3 para hacer posible y eficaz la acci\u00f3n. Seg\u00fan \u00e9l, este es el significado mismo del principio de subsidiariedad: es el nivel relevante m\u00e1s bajo, el m\u00e1s local, en la jerarqu\u00eda el que debe implementar una pol\u00edtica. Pero si no est\u00e1 en condiciones de emprender esta acci\u00f3n, la responsabilidad recae en el escal\u00f3n superior, siendo el \u00faltimo, por supuesto, la propia Uni\u00f3n Europea. El mandato esencial de las instituciones europeas es, por lo tanto, mejorar la acci\u00f3n de los Estados cuando se muestran impotentes para actuar por s\u00ed mismos.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><a href=\"https:\/\/www.ecb.europa.eu\/press\/key\/date\/2019\/html\/ecb.sp190222~fc5501c1b1.fr.html\"><strong>\u201cLa soberan\u00eda en un mundo globalizado\u201d<\/strong><\/a><\/h4>\n\n\n\n<p><strong><em>Intervenci\u00f3n del Sr. Mario Draghi, presidente del Banco Central Europeo, con motivo de la recepci\u00f3n del t\u00edtulo de doctor honoris causa en derecho otorgado por la Universit\u00e0 degli Studi de Bologna, el 22 de febrero de 2019<\/em><\/strong><\/p>\n\n\n\n<p>Esta tensi\u00f3n entre integraci\u00f3n econ\u00f3mica y cooperaci\u00f3n pol\u00edtica est\u00e1 alimentada por una tenaz convicci\u00f3n: es absolutamente necesario elegir entre la pertenencia a la UE y la capacidad de ejercer la soberan\u00eda. Dicho de otra manera, si los ciudadanos quieren ejercer un mayor control sobre su destino, deber\u00edan aflojar el control de las estructuras pol\u00edticas europeas.&nbsp;<\/p>\n\n\n\n<p>Esta creencia es incorrecta porque confunde <em>independencia<\/em> y <em>soberan\u00eda<\/em>.<\/p>\n\n\n\n<p>[\u2026]<\/p>\n\n\n\n<p>La verdadera soberan\u00eda no reside en el poder de hacer la ley, seg\u00fan una definici\u00f3n jur\u00eddica, sino en un mayor control sobre los acontecimientos a fin de satisfacer las necesidades b\u00e1sicas de los ciudadanos, lo que John Locke define como \u201cpaz, seguridad y bien p\u00fablico\u201d. La capacidad de tomar decisiones de manera independiente no asegura dicho control. En otras palabras, la independencia no garantiza la soberan\u00eda.&nbsp;<\/p>\n\n\n\n<p>[\u2026]<\/p>\n\n\n\n<p>En tal entorno, los pa\u00edses deben trabajar juntos para ejercer la soberan\u00eda. Y esto es a\u00fan m\u00e1s cierto dentro de la UE. La cooperaci\u00f3n en Europa ayuda a proteger a los pa\u00edses de las presiones externas y hace que sus pol\u00edticas nacionales sean m\u00e1s eficaces.<\/p>\n\n\n\n<p>[\u2026]<\/p>\n\n\n\n<p>Las estructuras e instituciones europeas comunes limitan los efectos de contagio, garantizan la igualdad de trato y protegen contra comportamientos injustos. Permiten as\u00ed satisfacer las necesidades de los ciudadanos y a los pa\u00edses ejercer su soberan\u00eda.<\/p>\n\n\n\n<p>[\u2026]<\/p>\n\n\n\n<p>El argumento de que la cooperaci\u00f3n refuerza la soberan\u00eda tambi\u00e9n se aplica a la relaci\u00f3n entre la UE y el resto del mundo. Pocos pa\u00edses europeos son lo suficientemente grandes para soportar los efectos secundarios generados por las grandes econom\u00edas o influir en las negociaciones comerciales internacionales. Dentro de la UE, en cambio, su fuerza se multiplica.<\/p>\n\n\n\n<p>[\u2026]<\/p>\n\n\n\n<p>Por todo ello, estar fuera de la UE puede ir de la mano de una mayor independencia en pol\u00edtica econ\u00f3mica, pero no necesariamente de una mayor soberan\u00eda. Lo mismo ocurre con la moneda \u00fanica.<\/p>\n\n\n\n<p>[\u2026]<\/p>\n\n\n\n<p>Del mismo modo, la integraci\u00f3n financiera internacional tambi\u00e9n puede reducir el poder de los pa\u00edses individuales para regular, establecer impuestos y hacer cumplir las normas de protecci\u00f3n social. [\u2026] El hecho de poder disponer de capacidad normativa a nivel de la UE permite a los Estados miembros ejercer una soberan\u00eda real en los \u00e1mbitos de la fiscalidad, protecci\u00f3n del consumidor y normas sociales.<\/p>\n\n\n\n<p class=\"comment\">Tomando la definici\u00f3n de soberan\u00eda como la capacidad de actuar realmente, Draghi considera, en este texto, que el problema surge realmente en el contexto de la globalizaci\u00f3n y, sobre todo, de la reafirmaci\u00f3n de las grandes potencias que ya conocemos. Todav\u00eda es posible que los estados se nieguen a seguir las reglas o leyes decididas a nivel europeo y favorezcan lo nacional. \u00bfPero por esto ser\u00e1n soberanos?<\/p>\n\n\n\n<p class=\"comment\">Para Draghi, estos estados ser\u00e1n independientes \u2013ninguna instituci\u00f3n superior en la jerarqu\u00eda normativa les dicta su conducta\u2013, pero no ser\u00e1n soberanos porque, en virtud de la definici\u00f3n de soberan\u00eda que ha adoptado, corren el riesgo en realidad de ser impedidos en su acci\u00f3n y verse condenados a la impotencia, mientras que una decisi\u00f3n colectiva a nivel de la Uni\u00f3n \u2013que, sin duda, implica una cierta p\u00e9rdida de independencia\u2013 podr\u00eda por el contrario preservar un margen de maniobra y el \u00e9xito efectivo de la acci\u00f3n. Un argumento a favor de la soberan\u00eda compartida a nivel de la Uni\u00f3n, en definitiva.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>II &#8211; \u00bfRigor o expansi\u00f3n?<\/strong><\/h2>\n\n\n\n<h4 class=\"wp-block-heading\"><a href=\"https:\/\/www.ecb.europa.eu\/press\/key\/date\/2011\/html\/sp111215.en.html\"><strong>\u201cEl euro, la pol\u00edtica monetaria y el dise\u00f1o de un <em>fiscal compact\u201d<\/em><\/strong><\/a><\/h4>\n\n\n\n<p><strong><em>Discurso de Mario Draghi, presidente del BCE con ocasi\u00f3n de la Ludwig Erhard Lecture, Berl\u00edn, 15 de diciembre de 2011<\/em><\/strong><\/p>\n\n\n\n<p>El legado de Ludwig Erhard en la reconstrucci\u00f3n de la Alemania de la posguerra se extiende mucho m\u00e1s all\u00e1 de su propio pa\u00eds y mucho m\u00e1s all\u00e1 de su tiempo. Su concepci\u00f3n de la econom\u00eda social de mercado fue visionaria. E incluso ten\u00eda opiniones muy elevadas sobre los banqueros centrales, destacando la importancia de la estabilidad de precios: \u201c<em>Die soziale Marktwirtschaft ist ohne eine konsequente Politik der Preisstabilit\u00e4t nicht denkbar<\/em>\u201d. Creo que hoy no podemos formular mejor esta idea.<\/p>\n\n\n\n<p>[\u2026]<\/p>\n\n\n\n<p>Durante m\u00e1s de 12 a\u00f1os, la Uni\u00f3n Econ\u00f3mica y Monetaria Europea ha estado atormentada por preocupaciones sobre los presupuestos nacionales. En un \u00e1rea monetaria com\u00fan, en tiempos normales, las pol\u00edticas fiscales de diferentes pa\u00edses est\u00e1n generalmente menos sujetas a la presi\u00f3n de los mercados financieros. Es por esta raz\u00f3n que, al comienzo de la moneda \u00fanica europea, se estableci\u00f3 el Pacto de Estabilidad y Crecimiento para proporcionar un mecanismo de seguimiento de la pol\u00edtica fiscal.<\/p>\n\n\n\n<p>[\u2026]<\/p>\n\n\n\n<p>Sin embargo, la aplicaci\u00f3n del Pacto de Estabilidad y Crecimiento no ha sido satisfactoria. Como se\u00f1al\u00f3 recientemente la canciller federal alemana, el pacto se ha roto 60 veces en los \u00faltimos 12 a\u00f1os. As\u00ed que claramente tenemos trabajo que hacer para evitar que esto vuelva a suceder.<\/p>\n\n\n\n<p>[\u2026]<\/p>\n\n\n\n<p>Ahora hemos iniciado el proceso de redefinici\u00f3n del marco fiscal europeo en tres frentes.<\/p>\n\n\n\n<p>[\u2026]<\/p>\n\n\n\n<p>El primero es el de los pa\u00edses afectados: deben volver a asentar sus pol\u00edticas sobre bases s\u00f3lidas. Yo creo que ahora est\u00e1n en el buen camino y que tienen raz\u00f3n en aplicar decididamente la consolidaci\u00f3n fiscal.<\/p>\n\n\n\n<p>[\u2026]El segundo pilar de una respuesta a la crisis consiste en una revisi\u00f3n de la gobernanza fiscal en la zona euro, lo que denomin\u00e9 como el <em>fiscal compact<\/em>. El <em>fiscal compact<\/em> es una reafirmaci\u00f3n fundamental de las reglas a las que deben someterse las pol\u00edticas presupuestarias nacionales para adquirir una credibilidad indudable. (\u2026) M\u00e1s vale prevenir que curar.<\/p>\n\n\n\n<p class=\"comment\">Como testimonio de la preocupaci\u00f3n de Draghi por adaptar en la mayor medida posible la pol\u00edtica monetaria del BCE a las vicisitudes de la econom\u00eda, su posici\u00f3n sobre la disciplina presupuestaria de los Estados miembros ha variado durante su mandato. En el texto anterior, en 2011, reci\u00e9n llegado al frente de la instituci\u00f3n de Fr\u00e1ncfort, ansioso por mantener la credibilidad del BCE y asegurarse el respeto a su mandato, Draghi establece una visi\u00f3n bastante tradicional de la relaci\u00f3n entre pol\u00edtica monetaria y fiscal.<\/p>\n\n\n\n<p class=\"comment\">Rindiendo homenaje al excanciller dem\u00f3crata cristiano de la RFA Ludwig Ehrard, recuerda as\u00ed las reglas del Pacto de Estabilidad y Crecimiento (PEC), cuyas primeras secciones entraron en vigor en 1998. Draghi pronunci\u00f3 su discurso el 15 de diciembre de 2011. Es decir, seis d\u00edas despu\u00e9s de la apertura oficial de las negociaciones sobre el futuro Tratado de Estabilidad, Coordinaci\u00f3n y Gobernanza (TECG), que refuerza la disciplina presupuestaria (tras un per\u00edodo de mayor flexibilidad iniciado en 2005) y que entrar\u00e1 en vigor el 1ero de enero de 2013.<\/p>\n\n\n\n<p class=\"comment\">Su mensaje es doble. Por un lado, los pa\u00edses que no respetan las reglas (especialmente desde la crisis de 2008) del PEC deben reducir r\u00e1pidamente su deuda p\u00fablica y su d\u00e9ficit. Por otro lado, a trav\u00e9s del concepto de <em>fiscal compact<\/em>, la propia UE debe reafirmar estas normas y permanecer muy atenta a su respeto por parte de los Estados, registr\u00e1ndolas a nivel constitucional o equivalente, a fin de evitar un empeoramiento de la econom\u00eda europea, lo que har\u00eda necesarios complejos ajustes <em>a posteriori<\/em>. En resumen, una llamada bastante tradicional a la moderaci\u00f3n presupuestaria. El propio economista K. Rogoff insisti\u00f3 en la imperiosa necesidad de nombrar un \u201cbanquero central conservador\u201d&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-832' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/es\/2021\/02\/12\/descubramos-a-mario-draghi\/#easy-footnote-bottom-3-832' title='Rogoff, Kenneth, \u201cThe Optimal Degree of Commitment to an Intermediate Monetary Target\u201d, 1985, &lt;em&gt;Quarterly Journal of Economics&lt;\/em&gt; 100 : 1169-1189.'><sup>3<\/sup><\/a><\/span><\/span><\/p>\n\n\n\n<p class=\"comment\">Se suele subestimar el grado en que la petici\u00f3n del BCE en 2011 de este famoso <em>fiscal compact <\/em>jug\u00f3 un papel importante en la preparaci\u00f3n y firma del TECG y, sobre todo, en qu\u00e9 medida contribuy\u00f3 a un endurecimiento de la pol\u00edtica fiscal que, en gran medida, ha contribuido a la segunda recesi\u00f3n en Europa. Tambi\u00e9n podemos recordar que Draghi jug\u00f3 un papel importante durante el verano de 2011 en la presi\u00f3n que el BCE ejerci\u00f3 para obligar a Berlusconi a renunciar al poder. De hecho, la famosa carta de Trichet a Berlusconi que eventualmente derrocar\u00e1 su gobierno, est\u00e1 co-firmada por Draghi, todav\u00eda gobernador del Banco de Italia, pero que se prepara para asumir su cargo en Frankfurt a finales de a\u00f1o.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><a href=\"https:\/\/www.ecb.europa.eu\/press\/key\/date\/2014\/html\/sp140822.es.html\"><strong>\u201cEl desempleo en la zona del euro\u201d<\/strong><\/a><\/h4>\n\n\n\n<p><strong><em>Discurso de Mario Draghi, presidente del BCE, Simposio anual de bancos centrales en Jackson Hole, 22 de agosto de 2014<\/em><\/strong><\/p>\n\n\n\n<p>Nadie en la sociedad puede ser indiferente ante una situaci\u00f3n de desempleo elevado. Para los que no tienen trabajo, suele ser una tragedia con efectos duraderos en los ingresos de toda una vida. Para los que s\u00ed lo tienen, aumenta la inseguridad laboral y socava la cohesi\u00f3n social. Para los Gobiernos, supone un lastre para las finanzas p\u00fablicas y da\u00f1a sus perspectivas electorales. El desempleo es un elemento esencial de la din\u00e1mica macroecon\u00f3mica que determina la inflaci\u00f3n a corto y a medio plazo, por lo que tambi\u00e9n afecta a los bancos centrales. De hecho, aun cuando no existen riesgos para la estabilidad de precios, si el desempleo es alto y la cohesi\u00f3n social est\u00e1 en peligro, la presi\u00f3n para que el banco central ofrezca una respuesta aumenta de forma invariable.<\/p>\n\n\n\n<p>[\u2026]<\/p>\n\n\n\n<p>\u00bfQu\u00e9 conclusiones podemos extraer como responsables de las pol\u00edticas? La \u00fanica conclusi\u00f3n que podemos extraer sin temor a equivocarnos es la necesidad de adoptar medidas en ambos lados de la econom\u00eda: las pol\u00edticas de demanda agregada deben acompa\u00f1arse de pol\u00edticas estructurales a nivel nacional.<\/p>\n\n\n\n<p>[\u2026]<\/p>\n\n\n\n<p>Por tanto, ser\u00eda \u00fatil para la orientaci\u00f3n general de la pol\u00edtica que la pol\u00edtica fiscal pudiera tener mayor relevancia junto con la pol\u00edtica monetaria, y considero que existe margen para ello, sin perjuicio de nuestras condiciones espec\u00edficas iniciales y limitaciones legales. Estas condiciones iniciales incluyen niveles de gasto p\u00fablico y tributaci\u00f3n en la zona del euro que, en relaci\u00f3n con el PIB, est\u00e1n ya entre los m\u00e1s altos del mundo. Adem\u00e1s, trabajamos dentro de una normativa fiscal \u2015el Pacto de Estabilidad y Crecimiento\u2015 que act\u00faa como ancla de la confianza y que ser\u00eda contraproducente incumplir.<\/p>\n\n\n\n<p>Perm\u00edtanme destacar cuatro aspectos a este respecto.<\/p>\n\n\n\n<p>En primer lugar, la flexibilidad existente dentro de las reglas podr\u00eda utilizarse para abordar mejor la d\u00e9bil recuperaci\u00f3n y acomodar el coste de las reformas estructurales necesarias.<\/p>\n\n\n\n<p>En segundo lugar, existe margen para una composici\u00f3n de las pol\u00edticas fiscales m\u00e1s favorable al crecimiento. Para empezar, deber\u00eda poder reducirse la carga impositiva de manera que no afecte al presupuesto. [&#8230;]<\/p>\n\n\n\n<p>En tercer lugar, paralelamente, ser\u00eda \u00fatil mantener un debate sobre la orientaci\u00f3n general de la pol\u00edtica fiscal de la zona del euro. [&#8230;]<\/p>\n\n\n\n<p>En cuarto lugar, tambi\u00e9n parecen necesarias medidas complementarias a nivel de la UE que aseguren tanto una posici\u00f3n agregada adecuada como un amplio programa de inversi\u00f3n p\u00fablica, lo que es coherente con las propuestas del presidente de la Comisi\u00f3n Europea reci\u00e9n nombrado.<\/p>\n\n\n\n<p class=\"comment\">En vista del discurso de 2011, es notable observar el cambio de tendencia de 2014 expresado en el texto anterior, en el simposio de Jackson Hola, donde Draghi expone sobre la persistencia del alto desempleo en Europa. En primer lugar, recuerda las pol\u00edticas de apoyo a la demanda implementadas por el BCE, as\u00ed como las pol\u00edticas monetarias no convencionales que conocemos, pero sugiere que esto no ser\u00e1 suficiente sin un mayor papel de las pol\u00edticas presupuestarias nacionales, en ausencia de un presupuesto a nivel europeo. Para ser esquem\u00e1ticos, para que la pol\u00edtica monetaria sea eficaz, es necesario que los presupuestos de los Estados miembros aumenten la demanda dirigida a los bancos y empresas, de manera que estos inviertan y que lleven a los estados al c\u00edrculo virtuoso del crecimiento. Las pol\u00edticas estructurales y la pol\u00edtica monetaria por s\u00ed solas no ser\u00e1n suficientes.<\/p>\n\n\n\n<p class=\"comment\">Recordando la importancia del PEC, que garantiza la credibilidad de la zona euro, Draghi insta a los Estados a aprovechar la flexibilidad de las reglas que la constituyen y a recurrir a pol\u00edticas presupuestarias expansivas para reducir el desempleo y apoyar el crecimiento. No se trata en absoluto de un cuestionamiento del PEC y los acuerdos europeos, ni de una orden dirigida por el BCE a los gobiernos nacionales: es m\u00e1s un llamado a la acci\u00f3n pol\u00edtica cuyas esperadas consecuencias ser\u00e1n favorables para los Estados y para la zona euro en s\u00ed. Por supuesto, esto aliment\u00f3 en gran medida las tensiones entre Berl\u00edn y Fr\u00e1ncfort en los d\u00edas siguientes.<\/p>\n\n\n\n<p class=\"comment\">Por \u00faltimo, cabe destacar que Draghi, durante la \u00faltima rueda de prensa que celebr\u00f3 como presidente del BCE el pasado jueves, volvi\u00f3 a pedir est\u00edmulo fiscal en los estados de la zona euro.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>III &#8211; En busca de gobernanza global o, al menos, cooperaci\u00f3n<\/strong><\/h2>\n\n\n\n<h4 class=\"wp-block-heading\"><a href=\"http:\/\/w2.vatican.va\/content\/osservatore-romano\/it\/comments\/2009\/documents\/155q01b1.html\"><strong>\u201cNo hay desarrollo sin \u00e9tica\u201d<\/strong><\/a><\/h4>\n\n\n\n<p><strong><em>Comentario sobre la enc\u00edclica <\/em>Caritas in Veritate<em> de Mario Draghi, gobernador del Banco de Italia, 9 de julio de 2009<\/em><\/strong><\/p>\n\n\n\n<p>La crisis actual confirma la necesidad de una relaci\u00f3n entre \u00e9tica y econom\u00eda, muestra la fragilidad de un modelo propenso a los excesos que han llevado a su fracaso. [\u2026] Toda decisi\u00f3n econ\u00f3mica tiene consecuencias morales. Esto es tanto m\u00e1s cierto en la era de la globalizaci\u00f3n, que debilita la acci\u00f3n nacional para gobernar la econom\u00eda y, por lo tanto, socava la utilidad de la distinci\u00f3n acad\u00e9mica entre la producci\u00f3n de riqueza y su redistribuci\u00f3n por la esfera p\u00fablica, por razones de justicia.<\/p>\n\n\n\n<p>[\u2026]<\/p>\n\n\n\n<p>La propuesta consiste en confiar la gobernanza de la globalizaci\u00f3n a una autoridad polic\u00e9ntrica (<em>poliarchiste<\/em>) compuesta por varios niveles y planes diferentes y coordinados, fundada no solo en las autoridades p\u00fablicas sino tambi\u00e9n en elementos de la sociedad civil (los \u00f3rganos intermediarios entre el Estado y el mercado, en el enfoque original de P\u00edo XI).<\/p>\n\n\n\n<p>[\u2026]<\/p>\n\n\n\n<p>En este contexto, el Papa recuerda la necesidad de una autoridad pol\u00edtica mundial, ya mencionada por Juan XXIII, as\u00ed como, en otras palabras, por Kant hace m\u00e1s de dos siglos. Este es un indicio consistente con la constataci\u00f3n de que, con la globalizaci\u00f3n, las externalidades se est\u00e1n multiplicando a un ritmo impensable hace solo unas d\u00e9cadas \u2013pensemos en el caso paradigm\u00e1tico del clima\u2013 e imponen un horizonte planetario de gobierno.<\/p>\n\n\n\n<p>[\u2026] El desarrollo a largo plazo no es posible sin \u00e9tica. Esta es una consecuencia fundamental para el economista del \u201camor en la verdad\u201d (<em>caritas in veritate<\/em>) de la que habla el Papa en su enc\u00edclica.<\/p>\n\n\n\n<p class=\"comment\">Mientras era gobernador del Banco de Italia, antes de su llegada al BCE, Mario Draghi se erige, en el texto anterior, en un gran defensor de la cooperaci\u00f3n entre estados m\u00e1s que de la guerra abierta entre estos. Al comentar la enc\u00edclica <em>Caritas in Veritate <\/em>del Papa Benedicto XVI, el entonces gobernador del Banco de Italia, educado por los jesuitas, reconoce los desastres provocados por una globalizaci\u00f3n omnipresente, amoral y en particular financiera, que pone a muchos Estados frente a su impotencia.<\/p>\n\n\n\n<p class=\"comment\">Entonces, \u00bfc\u00f3mo recuperar el control? Sobre esto, Draghi no es muy preciso. Evoca una \u201cautoridad pol\u00edtica mundial\u201d, siguiendo las palabras del Papa en la enc\u00edclica. Sin describir dicha autoridad, Draghi se presenta en cualquier caso favorable a la implementaci\u00f3n de la gobernanza global entre estados como un medio fundamental para restaurar una dimensi\u00f3n \u00e9tica a la devastaci\u00f3n que puede tener el comportamiento econ\u00f3mico \u2013una vez m\u00e1s, el razonamiento parece bastante trivial y poco argumentado\u2013. Lo que es seguro es que podemos ver aqu\u00ed un esbozo de las futuras reflexiones de Draghi sobre la soberan\u00eda, de las que hemos hablado: la globalizaci\u00f3n tambi\u00e9n puede quitarles la soberan\u00eda, en el sentido de eficacia de la acci\u00f3n, a los Estados que solo sufren las consecuencias.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><a href=\"https:\/\/www.bancaditalia.it\/pubblicazioni\/interventi-governatore\/integov2008\/Aspenit_1_07_08.pdf\"><strong>\u00abUna profunda interdependencia: la econom\u00eda transatl\u00e1ntica y sus perspectivas\u00bb<\/strong><\/a><\/h4>\n\n\n\n<p><strong><em>Discurso del gobernador del Banco de Italia, Mario Draghi, ASPEN INSTITUTE ITALIA, Roma, 1ero de julio de 2008<\/em><\/strong><\/p>\n\n\n\n<p>Hoy, la construcci\u00f3n de una Europa econ\u00f3mica se ha consolidado, el antagonista sovi\u00e9tico se ha disuelto, Asia se encuentra en el escenario mundial como coprotagonista, otras zonas geogr\u00e1ficas se muestran reclamando atenci\u00f3n. La supremac\u00eda estadounidense se mantiene, pero dar\u00e1 cabida a una multiplicidad de centros de poder econ\u00f3mico.<\/p>\n\n\n\n<p>[\u2026]<\/p>\n\n\n\n<p>Los hechos estilizados (&#8230;) esbozan un cuadro heter\u00f3clito con el que se se reconoce que los lazos econ\u00f3micos transatl\u00e1nticos siguen siendo importantes, pero menos que en el pasado, en un mundo globalizado y polic\u00e9ntrico. Sin embargo, en el \u00e1mbito de la pol\u00edtica econ\u00f3mica, siguen constituyendo el centro de gravedad del orden internacional y su car\u00e1cter esencial se reafirma con fuerza. Estados Unidos y Europa fueron los primeros y principales int\u00e9rpretes [de las normas de gobernanza econ\u00f3mica, nota del editor] tras la Segunda Guerra Mundial. Todav\u00eda les corresponde dar ejemplos de buena y fruct\u00edfera cooperaci\u00f3n.<\/p>\n\n\n\n<p>[\u2026]<\/p>\n\n\n\n<p>Es dif\u00edcil imaginar que los socios transatl\u00e1nticos no puedan encontrar un compromiso que conduzca a una reducci\u00f3n equilibrada de las barreras arancelarias a las importaciones en Europa y de las subvenciones a los productores nacionales en Estados Unidos.<\/p>\n\n\n\n<p>[\u2026]<\/p>\n\n\n\n<p>El v\u00ednculo transatl\u00e1ntico es valioso y debe cultivarse en el terreno pol\u00edtico. Pronto surgir\u00e1n nuevas perspectivas. Los retos actuales, para ser superados, requieren compartir objetivos y ser solidarios en la toma de decisiones. Estados Unidos y Europa, m\u00e1s unidos, son una garant\u00eda para la estabilidad mundial.<\/p>\n\n\n\n<p class=\"comment\">De manera un poco m\u00e1s concreta que en el texto anterior, Draghi estudia, en su discurso de julio de 2018, la cuesti\u00f3n de la relaci\u00f3n entre Estados Unidos y Europa. En el mundo post-bipolar, Estados Unidos y Europa siguen siendo las potencias dominantes, con un gran inter\u00e9s por colaborar. No son tanto los lazos hist\u00f3ricos y culturales los que le interesan \u2013aunque los desarrolle en la conferencia en cuesti\u00f3n\u2013 como, como buen banquero central, la exigencia de estabilidad macroecon\u00f3mica: resulta necesario mantener una fuerte cooperaci\u00f3n transatl\u00e1ntica para reducir el riesgo macroecon\u00f3mico mundial y permitir que las potencias econ\u00f3micas prosperen sin demasiadas dudas, en particular fomentando el comercio. Once a\u00f1os despu\u00e9s, el discurso de Draghi desentona en el contexto actual de la guerra comercial sino-americano y de las tensiones comerciales entre la Uni\u00f3n y Estados Unidos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>IV &#8211; La formaci\u00f3n y transmisi\u00f3n de un espacio cultural europeo<\/strong><\/h2>\n\n\n\n<h4 class=\"wp-block-heading\"><a href=\"https:\/\/www.bancaditalia.it\/media\/notizia\/inaugurazione-delle-giornate-della-cultura-della-banca-centrale-europea-intervento-del-governatore-mario-draghi\/\"><strong>\u201cInauguraci\u00f3n de las jornadas de cultura del Banco Central Europeo\u201d<\/strong><\/a><\/h4>\n\n\n\n<p><strong><em>Discurso de Mario Draghi, gobernador del Banco de Italia, 19 de octubre de 2011<\/em><\/strong><\/p>\n\n\n\n<p>Las Jornadas Culturales del BCE, dedicadas este a\u00f1o a Italia, se inauguran unos d\u00edas antes de que finalice mi mandato como gobernador del Banco de Italia y comience mi nueva funci\u00f3n al frente del BCE.<\/p>\n\n\n\n<p>Este acontecimiento coincide tambi\u00e9n con el 150\u00ba aniversario de la unificaci\u00f3n de Italia. En Italia se han realizado muchas iniciativas para rememorar los acontecimientos que han marcado la historia de nuestra naci\u00f3n. Es esencial destacar las ra\u00edces socioculturales de Italia, porque un pa\u00eds que ignora su pasado no puede tener futuro. Estoy plenamente convencido de que el fundamento de la identidad com\u00fan europea debe ser, ante todo, el conocimiento de la historia y las tradiciones de los pa\u00edses que componen la Uni\u00f3n. Las Jornadas Culturales responden a este objetivo, ofreciendo la oportunidad de reflexionar sobre nuestras ra\u00edces comunes; son una ocasi\u00f3n para conocer el patrimonio cultural de Europa, apreciar sus fruct\u00edferas diferencias, comprender sus similitudes, captar el sentido profundo de nuestra Europa com\u00fan. La cultura es un factor fundamental para dar vida a la Uni\u00f3n Europea. Fr\u00e1ncfort es la ciudad de Goethe, el hombre universal que, con su \u201cViaje a Italia\u201d (<em>Italienische Reise<\/em>), tendi\u00f3 un puente fundamental entre la cultura alemana y la del \u201cpa\u00eds de los limones\u201d, <em>das Land wo die Zitronen bluehen<\/em>.<\/p>\n\n\n\n<p class=\"comment\">Frente a una visi\u00f3n demasiado tecnocr\u00e1tica de la Presidencia del BCE, para Draghi sentarse en Fr\u00e1ncfort implica ante todo sentarse en el coraz\u00f3n de un espacio cultural europeo con una inmensa historia y que se caracteriza por una verdadera identidad. Antes de dejar su puesto en el Banco de Italia para asumir sus responsabilidades en el BCE, Draghi se complace en anunciar la apertura de las Jornadas Culturales del BCE dedicadas a Italia en 2012. A trav\u00e9s del ejemplo italiano, Draghi subraya un movimiento en tres etapas: todo ciudadano de un Estado europeo debe conocer la historia de su pa\u00eds, interesarse por la historia y las culturas de otros Estados europeos y, por \u00faltimo, tomar conciencia de la existencia de un patrimonio europeo com\u00fan, que constituye la base de una identidad compartida. Por ello, Draghi es partidario de la idea, a veces controvertida, de una civilizaci\u00f3n europea, que surge principalmente de las transferencias entre Estados y que constituye el \u201csuplemento de alma\u201d bergsoniano de una Uni\u00f3n a la que se considera demasiado tecnocr\u00e1tica.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><a href=\"https:\/\/www.ecb.europa.eu\/press\/key\/date\/2012\/html\/sp120906.en.htmlhttps:\/www.ecb.europa.eu\/press\/key\/date\/2012\/html\/sp120906.en.html\"><strong>\u00abPor un espacio p\u00fablico europeo\u00bb<\/strong><\/a><\/h4>\n\n\n\n<p><strong><em>Discurso de Mario Draghi, presidente del BCE, con motivo de la presentaci\u00f3n del premio M100 Media Award 2012, Potsdam, 6 de septiembre de 2012<\/em><\/strong><\/p>\n\n\n\n<p>La zona euro es una uni\u00f3n de Estados nacionales con fuertes tradiciones y preferencias nacionales. Aunque ha habido un consenso suficiente para compartir una moneda, las pol\u00edticas econ\u00f3micas y financieras se han mantenido en gran medida organizadas a nivel nacional. La crisis mundial ha dejado al descubierto las vulnerabilidades de este acuerdo.<\/p>\n\n\n\n<p>[\u2026]<\/p>\n\n\n\n<p>Nuestra visi\u00f3n de la UEM se basa en cuatro pilares: uni\u00f3n fiscal, uni\u00f3n financiera, uni\u00f3n econ\u00f3mica y uni\u00f3n pol\u00edtica. Pero hoy me gustar\u00eda centrarme brevemente en el cuarto pilar, la uni\u00f3n pol\u00edtica. Este pilar es esencial para implicar m\u00e1s a los ciudadanos de la zona euro y legitimar los otros tres pilares.<\/p>\n\n\n\n<p>[\u2026]<\/p>\n\n\n\n<p>Hay que hacer m\u00e1s para que se escuche la voz de los ciudadanos europeos. Necesitamos lo que se conoce en Alemania como<em> Teilhabe demokratisch<\/em>.<\/p>\n\n\n\n<p>Y aqu\u00ed es donde los necesitamos. Me gustar\u00eda pedirles a todos ustedes \u2013periodistas y editores, pero tambi\u00e9n responsables pol\u00edticos y acad\u00e9micos\u2013 que contribuyan al desarrollo de un aut\u00e9ntico espacio p\u00fablico europeo, <em>eine europ\u00e4ische \u00d6ffentlichkeit<\/em>.<\/p>\n\n\n\n<p>[\u2026]<\/p>\n\n\n\n<p>La mayor\u00eda de los europeos estamos expuestos principalmente a nuestros medios de comunicaci\u00f3n nacionales en nuestras lenguas nacionales. Pero esto ya no describe la realidad. Lo que ocurre en otros Estados miembros es importante para todos nosotros.<\/p>\n\n\n\n<p>[\u2026]<\/p>\n\n\n\n<p>Pero tambi\u00e9n hay un lado positivo en la medida en que [un espacio p\u00fablico europeo, nota del editor] lleva a los ciudadanos de la zona euro a desarrollar un sentido com\u00fan de pertenencia y a preocuparse por las decisiones tomadas en otras regiones.<\/p>\n\n\n\n<p>Una forma de reforzar esta tendencia ser\u00eda intercambiando m\u00e1s medios de comunicaci\u00f3n entre pa\u00edses.<\/p>\n\n\n\n<p class=\"comment\">M\u00e1s all\u00e1 del espacio cultural, se trata tambi\u00e9n de manera m\u00e1s general de un espacio p\u00fablico: \u00bfc\u00f3mo podr\u00edan los ciudadanos europeos conocer otros Estados europeos si s\u00f3lo disponen de informaci\u00f3n nacional? En el \u00faltimo texto, dirigido principalmente a periodistas y personalidades de los medios de comunicaci\u00f3n al momento de la ceremonia del Premio M100, Draghi hace un llamamiento para que la difusi\u00f3n de la informaci\u00f3n, todav\u00eda muy compartimentada, trascienda las fronteras nacionales.<\/p>\n\n\n\n<p class=\"comment\">Dado que las consecuencias de las acciones de unos Estados se imponen generalmente a los otros \u2013aqu\u00ed se encuentran las reflexiones sobre la distinci\u00f3n entre independencia y soberan\u00eda\u2013, es absurdo que los ciudadanos de los Estados europeos s\u00f3lo conozcan lo que ocurre en casa. Por lo tanto, es necesario, seg\u00fan Draghi, formar un verdadero espacio p\u00fablico europeo que sea multiling\u00fce, que facilite las transferencias entre Estados y que permita desarrollar, quiz\u00e1s, una mayor interacci\u00f3n por parte de los ciudadanos nacionales con lo que ocurre m\u00e1s all\u00e1 de sus fronteras.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e1s all\u00e1 de las pol\u00edticas monetarias, la geopol\u00edtica de Mario Draghi: una cierta idea de Europa.<\/p>\n","protected":false},"author":1366,"featured_media":839,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-speeches.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":22,"_lgc_tts_audio_url":"","_lgc_tts_voice":"","_lgc_tts_publish":false,"_lgc_tts_history_item_id":"","_lgc_tts_generated_at":"","_lgc_tts_status":"","_lgc_tts_error":"","footnotes":""},"categories":[5],"tags":[],"staff":[49,50],"editorial_format":[1474],"serie":[],"audience":[],"geo":[173],"class_list":["post-832","post","type-post","status-publish","format-standard","hentry","category-economia","staff-olivier-lenoir","staff-shahin-vallee","editorial_format-archivos-y-discursos","geo-mediterraneo"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":839,"excerpt":"M\u00e1s all\u00e1 de las pol\u00edticas monetarias, la geopol\u00edtica de Mario Draghi: una cierta idea de Europa.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Descubramos a Mario Draghi - El Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/es\/2021\/02\/12\/descubramos-a-mario-draghi\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Descubramos a Mario Draghi - El Grand Continent\" \/>\n<meta property=\"og:description\" content=\"M\u00e1s all\u00e1 de las pol\u00edticas monetarias, la geopol\u00edtica de Mario Draghi: una cierta idea de Europa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/es\/2021\/02\/12\/descubramos-a-mario-draghi\/\" \/>\n<meta property=\"og:site_name\" content=\"El Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-12T18:13:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-31T14:46:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2021\/02\/gc-Mario-Draghi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"florent\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2021\/02\/gc-Mario-Draghi.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"florent\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"22 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2021\/02\/12\/descubramos-a-mario-draghi\/\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/2021\/02\/12\/descubramos-a-mario-draghi\/\",\"name\":\"Descubramos a Mario Draghi - El Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2021\/02\/12\/descubramos-a-mario-draghi\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2021\/02\/12\/descubramos-a-mario-draghi\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2021\/02\/Mario-Draghi.jpg\",\"datePublished\":\"2021-02-12T18:13:16+00:00\",\"dateModified\":\"2022-05-31T14:46:13+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2021\/02\/12\/descubramos-a-mario-draghi\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/es\/2021\/02\/12\/descubramos-a-mario-draghi\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2021\/02\/12\/descubramos-a-mario-draghi\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2021\/02\/Mario-Draghi.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2021\/02\/Mario-Draghi.jpg\",\"width\":1000,\"height\":750},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2021\/02\/12\/descubramos-a-mario-draghi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/legrandcontinent.eu\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Descubramos a Mario Draghi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/\",\"name\":\"El Grand Continent\",\"description\":\"La escala pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\",\"name\":\"florent\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"caption\":\"florent\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Descubramos a Mario Draghi - El Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/es\/2021\/02\/12\/descubramos-a-mario-draghi\/","og_locale":"es_ES","og_type":"article","og_title":"Descubramos a Mario Draghi - El Grand Continent","og_description":"M\u00e1s all\u00e1 de las pol\u00edticas monetarias, la geopol\u00edtica de Mario Draghi: una cierta idea de Europa.","og_url":"https:\/\/legrandcontinent.eu\/es\/2021\/02\/12\/descubramos-a-mario-draghi\/","og_site_name":"El Grand Continent","article_published_time":"2021-02-12T18:13:16+00:00","article_modified_time":"2022-05-31T14:46:13+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2021\/02\/gc-Mario-Draghi.jpg","type":"image\/jpeg"}],"author":"florent","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2021\/02\/gc-Mario-Draghi.jpg","twitter_misc":{"Escrito por":"florent","Tiempo de lectura":"22 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/es\/2021\/02\/12\/descubramos-a-mario-draghi\/","url":"https:\/\/legrandcontinent.eu\/es\/2021\/02\/12\/descubramos-a-mario-draghi\/","name":"Descubramos a Mario Draghi - El Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/es\/2021\/02\/12\/descubramos-a-mario-draghi\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/es\/2021\/02\/12\/descubramos-a-mario-draghi\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2021\/02\/Mario-Draghi.jpg","datePublished":"2021-02-12T18:13:16+00:00","dateModified":"2022-05-31T14:46:13+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/es\/2021\/02\/12\/descubramos-a-mario-draghi\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/es\/2021\/02\/12\/descubramos-a-mario-draghi\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/2021\/02\/12\/descubramos-a-mario-draghi\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2021\/02\/Mario-Draghi.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2021\/02\/Mario-Draghi.jpg","width":1000,"height":750},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/es\/2021\/02\/12\/descubramos-a-mario-draghi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legrandcontinent.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Descubramos a Mario Draghi"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/es\/#website","url":"https:\/\/legrandcontinent.eu\/es\/","name":"El Grand Continent","description":"La escala pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c","name":"florent","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","caption":"florent"}}]}},"lgc_categories":[{"id":5,"name":"Econom\u00eda","slug":"economia"}],"lgc_author":{"id":49,"name":"Olivier Lenoir","slug":"olivier-lenoir","description":null,"first_name":null,"last_name":null,"picture":null},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2021\/02\/Mario-Draghi.jpg","width":1000,"height":750,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2021\/02\/Mario-Draghi.jpg","width":1000,"height":750,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/users\/1366"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/comments?post=832"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/832\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media\/839"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media?parent=832"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/categories?post=832"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/tags?post=832"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/staff?post=832"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/editorial_format?post=832"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/serie?post=832"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/audience?post=832"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/geo?post=832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}