{"id":80580,"date":"2025-10-15T17:32:01","date_gmt":"2025-10-15T15:32:01","guid":{"rendered":"https:\/\/legrandcontinent.eu\/es\/?p=80580"},"modified":"2025-10-15T17:32:04","modified_gmt":"2025-10-15T15:32:04","slug":"finanzas-publicas-que-lugar-ocupa-francia-en-la-union","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/es\/2025\/10\/15\/finanzas-publicas-que-lugar-ocupa-francia-en-la-union\/","title":{"rendered":"Finanzas p\u00fablicas: \u00bfqu\u00e9 lugar ocupa Francia en la Uni\u00f3n?"},"content":{"rendered":"\n<p>El presupuesto para 2026 presentado ayer, martes 14 de octubre, por el primer ministro S\u00e9bastien Lecornu tiene como objetivo reducir el d\u00e9ficit p\u00fablico al 4,7 % el pr\u00f3ximo a\u00f1o, frente al 5,4 % de este a\u00f1o. El<a href=\"https:\/\/legrandcontinent.eu\/es\/2025\/10\/13\/prosopografia-del-gobierno-lecornu-ii-menos-parisino-mismos-equilibrios-partidistas\/\"> nuevo gobierno<\/a> se propone as\u00ed volver a situarse por debajo del 3 % en 2029, de conformidad con las normas europeas, lo que tambi\u00e9n deber\u00eda permitir \u00abiniciar una reducci\u00f3n de la proporci\u00f3n de deuda a partir de 2028\u00bb, seg\u00fan el proyecto de ley.&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-80580' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2025\/10\/15\/finanzas-publicas-que-lugar-ocupa-francia-en-la-union\/#easy-footnote-bottom-1-80580' title='&lt;a href=&quot;https:\/\/www.budget.gouv.fr\/documentation\/file-download\/30589&quot;&gt;Projet de loi de finances pour 2026&lt;\/a&gt;, 14 de octubre de 2025.'><sup>1<\/sup><\/a><\/span><\/span><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Francia es uno de los nueve Estados miembros de la Uni\u00f3n sujetos a un procedimiento de d\u00e9ficit excesivo, tras una decisi\u00f3n del Consejo de julio de 2024.<\/li>\n\n\n\n<li>Con una deuda que deber\u00eda alcanzar el 115,9 % del PIB este a\u00f1o (+2,7 puntos con respecto a 2024), Francia es el tercer Estado miembro m\u00e1s endeudado de la Uni\u00f3n, por detr\u00e1s de Grecia (152 % en el primer semestre) e Italia (138 %).<\/li>\n\n\n\n<li>Es el quinto pa\u00eds cuya proporci\u00f3n ha aumentado m\u00e1s (+3,5 puntos) entre el primer trimestre de 2024 y 2025, por detr\u00e1s de Polonia (6,1 puntos), Finlandia (5,1), Austria (4,1) y Ruman\u00eda (4,1).<\/li>\n\n\n\n<li>En la Uni\u00f3n, 13 Estados miembros vieron disminuir su proporci\u00f3n de deuda durante este periodo y 13 aumentarla: Grecia retrocedi\u00f3 9,3 puntos, pasando del 162 % al 152 % del PIB.<\/li>\n\n\n\n<li><a href=\"https:\/\/legrandcontinent.eu\/es\/2025\/10\/06\/caida-del-gobierno-de-lecornu-al-superar-a-italia-francia-se-endeuda-ahora-mas-caro-que-el-resto-de-europa\/\">Tras superar brevemente a Italia tras la ca\u00edda del gobierno de Lecornu I<\/a> el 6 de octubre, las tasas de inter\u00e9s de la deuda francesa vuelven a ser inferiores a las italianas, con un 3,3 % frente al 3,4 % del mi\u00e9rcoles 15 de octubre.<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/vXbPT\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Con el fin de sanear las finanzas p\u00fablicas, el presupuesto para 2026 propuesto por Lecornu cuenta con un equilibrio casi perfecto entre una reducci\u00f3n del gasto p\u00fablico (que representar\u00eda el 55 % del esfuerzo presupuestario total, es decir, unos 17.000 millones de euros) y un aumento de los ingresos fiscales, que deber\u00eda ascender a 14.000 millones de euros (el 45 % del esfuerzo presupuestario).<\/p>\n\n\n\n<p>Con una tasa de retensiones obligatorias \u2014es decir, impuestos y cotizaciones sociales\u2014 estimada en cerca del 44 % del PIB para el pr\u00f3ximo a\u00f1o, Francia ocupar\u00eda el primer lugar en la clasificaci\u00f3n de los Estados miembros.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>En 2023, la Comisi\u00f3n Europea, cuyo m\u00e9todo de c\u00e1lculo difiere del utilizado por el INSEE, estimaba esta cifra en el 45,6 % del PIB, por delante de B\u00e9lgica (44,8 %) y Dinamarca (44,7 %).<\/li>\n\n\n\n<li>Sin embargo, esta cifra ha descendido casi 3 puntos con respecto al m\u00e1ximo alcanzado en 2017.<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/OK5Sq\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Gracias a un crecimiento estimado del 1 % en 2026, una cifra cercana a las<a href=\"https:\/\/legrandcontinent.eu\/es\/2025\/10\/14\/el-fmi-advierte-sobre-el-riesgo-de-una-decepcion-relacionada-con-los-beneficios-de-la-ia-para-la-economia-mundial\/\"> \u00faltimas proyecciones del FMI<\/a> (0,9 %), la proporci\u00f3n del gasto p\u00fablico en relaci\u00f3n con el PIB se reducir\u00eda al 56,4 %, por debajo de su nivel de 2024 (56,6 %). A escala de la Uni\u00f3n, la Comisi\u00f3n estima que Francia es el segundo pa\u00eds que dedica la mayor parte de su PIB al gasto p\u00fablico, despu\u00e9s de Finlandia.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/olRH8\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>En una nota publicada este verano, el Banco de Francia se\u00f1ala que la diferencia entre Par\u00eds y el resto de la zona euro ha aumentado considerablemente desde 2001, pasando de 5,5 a 7,5 puntos.&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-80580' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2025\/10\/15\/finanzas-publicas-que-lugar-ocupa-francia-en-la-union\/#easy-footnote-bottom-2-80580' title='&lt;a href=&quot;https:\/\/www.banque-france.fr\/fr\/publications-et-statistiques\/publications\/ou-la-france-depense-t-elle-davantage-que-ses-voisins-de-la-zone-euro&quot;&gt;O\u00f9 la France d\u00e9pense-t-elle davantage que ses voisins de la zone euro ?&lt;\/a&gt;, Banque de France, 25 de julio de 2025.'><sup>2<\/sup><\/a><\/span><\/span><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Mientras que la proporci\u00f3n de gasto p\u00fablico disminuy\u00f3 4,4 puntos en la zona euro (excluida Francia) entre 2010 y 2019, debido en particular a la consolidaci\u00f3n llevada a cabo tras la crisis de la deuda soberana, esta cifra es de 2,4 puntos para Francia.<\/li>\n\n\n\n<li>Esta diferencia entre Francia y el resto de los Estados miembros se explica principalmente por el elevado nivel de gasto en protecci\u00f3n social, principalmente en pensiones y salud: el 32,2 % del PIB frente al 27,2 % de media en la zona del euro.<\/li>\n\n\n\n<li>En su proyecto de ley de financiaci\u00f3n de la seguridad social para 2026, el gobierno de Lecornu prev\u00e9 medidas de ahorro por valor de 7.100 millones de euros, en particular en productos sanitarios y prestaciones diarias.&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-80580' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2025\/10\/15\/finanzas-publicas-que-lugar-ocupa-francia-en-la-union\/#easy-footnote-bottom-3-80580' title='&lt;a href=&quot;https:\/\/www.assemblee-nationale.fr\/dyn\/17\/textes\/l17b1907_projet-loi.pdf&quot;&gt;Projet de loi de financement de la s\u00e9curit\u00e9 sociale pour 2026&lt;\/a&gt;, 14 de octubre de 2025.'><sup>3<\/sup><\/a><\/span><\/span><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Con una tasa de impuestos obligatorios estimada en cerca del 44 % del PIB en el marco del presupuesto para 2026 presentado ayer, martes 14 de octubre, por S\u00e9bastien Lecornu, Francia ocupar\u00eda probablemente el primer lugar en la clasificaci\u00f3n de los Estados miembros.<\/p>\n<p>Francia es tambi\u00e9n el segundo pa\u00eds de la Uni\u00f3n que dedica la mayor parte de su PIB al gasto p\u00fablico, despu\u00e9s de Finlandia, y el tercer pa\u00eds m\u00e1s endeudado.<\/p>\n","protected":false},"author":17959,"featured_media":80585,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":4,"footnotes":""},"categories":[522],"tags":[],"staff":[],"editorial_format":[1472],"serie":[],"audience":[],"geo":[177],"class_list":["post-80580","post","type-post","status-publish","format-standard","hentry","category-los-datos-que-lo-cambian-todo","editorial_format-analisis","geo-europa"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":80585,"excerpt":"Con una tasa de impuestos obligatorios estimada en cerca del 44 % del PIB en el marco del presupuesto para 2026 presentado ayer, martes 14 de octubre, por S\u00e9bastien Lecornu, Francia ocupar\u00eda probablemente el primer lugar en la clasificaci\u00f3n de los Estados miembros.\r\n\r\nFrancia es tambi\u00e9n el segundo pa\u00eds de la Uni\u00f3n que dedica la mayor parte de su PIB al gasto p\u00fablico, despu\u00e9s de Finlandia, y el tercer pa\u00eds m\u00e1s endeudado.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Finanzas p\u00fablicas: \u00bfqu\u00e9 lugar ocupa Francia en la Uni\u00f3n? - El Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/es\/2025\/10\/15\/finanzas-publicas-que-lugar-ocupa-francia-en-la-union\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Finanzas p\u00fablicas: \u00bfqu\u00e9 lugar ocupa Francia en la Uni\u00f3n? - El Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Con una tasa de impuestos obligatorios estimada en cerca del 44 % del PIB en el marco del presupuesto para 2026 presentado ayer, martes 14 de octubre, por S\u00e9bastien Lecornu, Francia ocupar\u00eda probablemente el primer lugar en la clasificaci\u00f3n de los Estados miembros.  Francia es tambi\u00e9n el segundo pa\u00eds de la Uni\u00f3n que dedica la mayor parte de su PIB al gasto p\u00fablico, despu\u00e9s de Finlandia, y el tercer pa\u00eds m\u00e1s endeudado.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/es\/2025\/10\/15\/finanzas-publicas-que-lugar-ocupa-francia-en-la-union\/\" \/>\n<meta property=\"og:site_name\" content=\"El Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-15T15:32:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-15T15:32:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/10\/OK5Sq-evoluci-n-de-las-tasas-de-retensiones-obligatorias-en-la-uni-n.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1240\" \/>\n\t<meta property=\"og:image:height\" content=\"1110\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"anainesfernandez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"anainesfernandez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/10\/15\/finanzas-publicas-que-lugar-ocupa-francia-en-la-union\/\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/2025\/10\/15\/finanzas-publicas-que-lugar-ocupa-francia-en-la-union\/\",\"name\":\"Finanzas p\u00fablicas: \u00bfqu\u00e9 lugar ocupa Francia en la Uni\u00f3n? - El Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/10\/15\/finanzas-publicas-que-lugar-ocupa-francia-en-la-union\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/10\/15\/finanzas-publicas-que-lugar-ocupa-francia-en-la-union\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/10\/OK5Sq-evoluci-n-de-las-tasas-de-retensiones-obligatorias-en-la-uni-n.png\",\"datePublished\":\"2025-10-15T15:32:01+00:00\",\"dateModified\":\"2025-10-15T15:32:04+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/570398dd8da37ba5d66dec6d242bd33c\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/10\/15\/finanzas-publicas-que-lugar-ocupa-francia-en-la-union\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/es\/2025\/10\/15\/finanzas-publicas-que-lugar-ocupa-francia-en-la-union\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/10\/15\/finanzas-publicas-que-lugar-ocupa-francia-en-la-union\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/10\/OK5Sq-evoluci-n-de-las-tasas-de-retensiones-obligatorias-en-la-uni-n.png\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/10\/OK5Sq-evoluci-n-de-las-tasas-de-retensiones-obligatorias-en-la-uni-n.png\",\"width\":1240,\"height\":1110},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/10\/15\/finanzas-publicas-que-lugar-ocupa-francia-en-la-union\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/legrandcontinent.eu\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Finanzas p\u00fablicas: \u00bfqu\u00e9 lugar ocupa Francia en la Uni\u00f3n?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/\",\"name\":\"El Grand Continent\",\"description\":\"La escala pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/570398dd8da37ba5d66dec6d242bd33c\",\"name\":\"anainesfernandez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/fe25c21e6213f69a683147fabda32586?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/fe25c21e6213f69a683147fabda32586?s=96&d=mm&r=g\",\"caption\":\"anainesfernandez\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Finanzas p\u00fablicas: \u00bfqu\u00e9 lugar ocupa Francia en la Uni\u00f3n? - El Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/es\/2025\/10\/15\/finanzas-publicas-que-lugar-ocupa-francia-en-la-union\/","og_locale":"es_ES","og_type":"article","og_title":"Finanzas p\u00fablicas: \u00bfqu\u00e9 lugar ocupa Francia en la Uni\u00f3n? - El Grand Continent","og_description":"Con una tasa de impuestos obligatorios estimada en cerca del 44 % del PIB en el marco del presupuesto para 2026 presentado ayer, martes 14 de octubre, por S\u00e9bastien Lecornu, Francia ocupar\u00eda probablemente el primer lugar en la clasificaci\u00f3n de los Estados miembros.  Francia es tambi\u00e9n el segundo pa\u00eds de la Uni\u00f3n que dedica la mayor parte de su PIB al gasto p\u00fablico, despu\u00e9s de Finlandia, y el tercer pa\u00eds m\u00e1s endeudado.","og_url":"https:\/\/legrandcontinent.eu\/es\/2025\/10\/15\/finanzas-publicas-que-lugar-ocupa-francia-en-la-union\/","og_site_name":"El Grand Continent","article_published_time":"2025-10-15T15:32:01+00:00","article_modified_time":"2025-10-15T15:32:04+00:00","og_image":[{"width":1240,"height":1110,"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/10\/OK5Sq-evoluci-n-de-las-tasas-de-retensiones-obligatorias-en-la-uni-n.png","type":"image\/png"}],"author":"anainesfernandez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"anainesfernandez","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/es\/2025\/10\/15\/finanzas-publicas-que-lugar-ocupa-francia-en-la-union\/","url":"https:\/\/legrandcontinent.eu\/es\/2025\/10\/15\/finanzas-publicas-que-lugar-ocupa-francia-en-la-union\/","name":"Finanzas p\u00fablicas: \u00bfqu\u00e9 lugar ocupa Francia en la Uni\u00f3n? - El Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/es\/2025\/10\/15\/finanzas-publicas-que-lugar-ocupa-francia-en-la-union\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/es\/2025\/10\/15\/finanzas-publicas-que-lugar-ocupa-francia-en-la-union\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/10\/OK5Sq-evoluci-n-de-las-tasas-de-retensiones-obligatorias-en-la-uni-n.png","datePublished":"2025-10-15T15:32:01+00:00","dateModified":"2025-10-15T15:32:04+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/570398dd8da37ba5d66dec6d242bd33c"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/es\/2025\/10\/15\/finanzas-publicas-que-lugar-ocupa-francia-en-la-union\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/es\/2025\/10\/15\/finanzas-publicas-que-lugar-ocupa-francia-en-la-union\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/2025\/10\/15\/finanzas-publicas-que-lugar-ocupa-francia-en-la-union\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/10\/OK5Sq-evoluci-n-de-las-tasas-de-retensiones-obligatorias-en-la-uni-n.png","contentUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/10\/OK5Sq-evoluci-n-de-las-tasas-de-retensiones-obligatorias-en-la-uni-n.png","width":1240,"height":1110},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/es\/2025\/10\/15\/finanzas-publicas-que-lugar-ocupa-francia-en-la-union\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legrandcontinent.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Finanzas p\u00fablicas: \u00bfqu\u00e9 lugar ocupa Francia en la Uni\u00f3n?"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/es\/#website","url":"https:\/\/legrandcontinent.eu\/es\/","name":"El Grand Continent","description":"La escala pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/570398dd8da37ba5d66dec6d242bd33c","name":"anainesfernandez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/fe25c21e6213f69a683147fabda32586?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fe25c21e6213f69a683147fabda32586?s=96&d=mm&r=g","caption":"anainesfernandez"}}]}},"lgc_categories":[{"id":522,"name":"Los datos que lo cambian todo","slug":"los-datos-que-lo-cambian-todo"}],"lgc_author":null,"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/10\/OK5Sq-evoluci-n-de-las-tasas-de-retensiones-obligatorias-en-la-uni-n.png","width":1240,"height":1110,"alt":""},"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/80580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/users\/17959"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/comments?post=80580"}],"version-history":[{"count":6,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/80580\/revisions"}],"predecessor-version":[{"id":80587,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/80580\/revisions\/80587"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media\/80585"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media?parent=80580"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/categories?post=80580"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/tags?post=80580"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/staff?post=80580"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/editorial_format?post=80580"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/serie?post=80580"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/audience?post=80580"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/geo?post=80580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}