{"id":80265,"date":"2025-10-11T07:00:00","date_gmt":"2025-10-11T05:00:00","guid":{"rendered":"https:\/\/legrandcontinent.eu\/es\/?p=80265"},"modified":"2025-10-11T01:21:08","modified_gmt":"2025-10-10T23:21:08","slug":"economia-rusa-moscu-podria-perder-casi-la-mitad-de-su-flota-aerea-para-2030","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/es\/2025\/10\/11\/economia-rusa-moscu-podria-perder-casi-la-mitad-de-su-flota-aerea-para-2030\/","title":{"rendered":"Econom\u00eda rusa: Mosc\u00fa podr\u00eda perder casi la mitad de su flota a\u00e9rea para 2030"},"content":{"rendered":"\n<p>En su intervenci\u00f3n del martes 7 de octubre en una reuni\u00f3n del Comit\u00e9 de Pol\u00edtica Econ\u00f3mica del Consejo de la Federaci\u00f3n Rusa, el director de la agencia federal de transporte a\u00e9reo (Rosaviatsiya), Dmitri Yadorov, declar\u00f3 que 339 aviones y 200 helic\u00f3pteros podr\u00edan ser retirados del servicio de aqu\u00ed a 2030 \u00abseg\u00fan previsiones pesimistas\u00bb.&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-80265' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2025\/10\/11\/economia-rusa-moscu-podria-perder-casi-la-mitad-de-su-flota-aerea-para-2030\/#easy-footnote-bottom-1-80265' title='\u00ab&lt;a href=&quot;https:\/\/tass.ru\/ekonomika\/25271049&quot;&gt;\u0420\u043e\u0441\u0430\u0432\u0438\u0430\u0446\u0438\u044f \u043d\u0430\u0437\u0432\u0430\u043b\u0430 \u043f\u043e\u0442\u0435\u0440\u0438 \u0430\u0432\u0438\u0430\u043f\u0430\u0440\u043a\u0430 \u0420\u0424 \u0432 \u043f\u0435\u0441\u0441\u0438\u043c\u0438\u0441\u0442\u0438\u0447\u043d\u043e\u043c \u043f\u0440\u043e\u0433\u043d\u043e\u0437\u0435 \u0434\u043e 2030 \u0433\u043e\u0434\u0430&lt;\/a&gt;\u00bb, &lt;em&gt;TASS&lt;\/em&gt;, 7 de octubre de 2025.'><sup>1<\/sup><\/a><\/span><\/span><\/p>\n\n\n\n<p>Desde la imposici\u00f3n de sanciones al sector aeron\u00e1utico ruso tras la invasi\u00f3n a gran escala de Ucrania en 2022, las compa\u00f1\u00edas a\u00e9reas tienen dificultades para importar piezas de repuesto y garantizar el mantenimiento de sus aeronaves.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Seg\u00fan las \u00faltimas cifras disponibles publicadas por el Servicio Federal de Estad\u00edsticas (Rosstat), casi dos tercios (64 %) de los aviones que componen la flota a\u00e9rea rusa son de fabricaci\u00f3n europea o estadounidense.<\/li>\n\n\n\n<li>Solo los aviones de Airbus y Boeing representan m\u00e1s de la mitad de los aviones comerciales en servicio en Rusia.<\/li>\n\n\n\n<li>Ambos fabricantes suministraron 30 de los 52 aviones a\u00f1adidos a las flotas de las compa\u00f1\u00edas Aeroflot, S7, Red Wings, Rossiya o Ural Airlines en 2021.&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-80265' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2025\/10\/11\/economia-rusa-moscu-podria-perder-casi-la-mitad-de-su-flota-aerea-para-2030\/#easy-footnote-bottom-2-80265' title='Gleb Stolyarov y Alexander Marrow, \u00ab&lt;a href=&quot;https:\/\/www.reuters.com\/business\/aerospace-defense\/russias-struggle-build-commercial-jets-reflects-deeper-industrial-malaise-2025-08-08\/&quot;&gt;Russia&amp;#8217;s struggle to build commercial jets reflects deeper industrial malaise&lt;\/a&gt;\u00bb, &lt;em&gt;Reuters&lt;\/em&gt;, 8 de agosto de 2025.'><sup>2<\/sup><\/a><\/span><\/span><\/li>\n\n\n\n<li>Desde el verano de 2024, Rosaviatsiya ha dejado de publicar datos precisos sobre la composici\u00f3n de su flota a\u00e9rea, alegando la \u00abnecesidad de optimizar la informaci\u00f3n publicada\u00bb.&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-80265' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2025\/10\/11\/economia-rusa-moscu-podria-perder-casi-la-mitad-de-su-flota-aerea-para-2030\/#easy-footnote-bottom-3-80265' title='\u00ab&lt;a href=&quot;https:\/\/www.rbc.ru\/business\/25\/06\/2024\/667b00219a7947de5642ddfe&quot;&gt;\u0420\u043e\u0441\u0430\u0432\u0438\u0430\u0446\u0438\u044f \u043f\u0435\u0440\u0435\u0441\u0442\u0430\u043b\u0430 \u043f\u0443\u0431\u043b\u0438\u043a\u043e\u0432\u0430\u0442\u044c \u0442\u043e\u0447\u043d\u044b\u0435 \u0434\u0430\u043d\u043d\u044b\u0435 \u043e \u043f\u0430\u0440\u043a\u0435 \u0430\u0432\u0438\u0430\u043a\u043e\u043c\u043f\u0430\u043d\u0438\u0439&lt;\/a&gt;\u00bb, &lt;em&gt;RBC&lt;\/em&gt;, 25 de junio de 2024.'><sup>3<\/sup><\/a><\/span><\/span><\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/2RHPn\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Al mismo tiempo, los fabricantes rusos tienen dificultades para cumplir con los pedidos. En agosto, solo se hab\u00eda entregado uno de los quince aviones comerciales cuya entrega estaba prevista para este a\u00f1o. Los aviones de transporte regional Sujoi SuperJet, que siguen fabric\u00e1ndose en Rusia \u2014aunque a un ritmo insuficiente\u2014, tambi\u00e9n dependen de piezas importadas que no pueden producirse en el pa\u00eds.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Ante la disminuci\u00f3n del n\u00famero de aviones disponibles para garantizar las conexiones a\u00e9reas, Mosc\u00fa inici\u00f3 conversaciones en oto\u00f1o de 2024 con varios pa\u00edses de Asia Central para que sus compa\u00f1\u00edas a\u00e9reas garantizaran los vuelos nacionales.&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-4-80265' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2025\/10\/11\/economia-rusa-moscu-podria-perder-casi-la-mitad-de-su-flota-aerea-para-2030\/#easy-footnote-bottom-4-80265' title='Gleb Stolyarov, \u00ab&lt;a href=&quot;https:\/\/www.reuters.com\/business\/aerospace-defense\/short-planes-russia-asks-central-asian-airlines-run-domestic-flights-2024-10-23\/&quot;&gt;Short of planes, Russia asks Central Asian airlines to run domestic flights&lt;\/a&gt;\u00bb, &lt;em&gt;Reuters&lt;\/em&gt;, 23 de octubre de 2024.'><sup>4<\/sup><\/a><\/span><\/span><\/li>\n\n\n\n<li>En septiembre, Rusia tambi\u00e9n intent\u00f3 presionar a la Organizaci\u00f3n de Aviaci\u00f3n Civil Internacional (OACI) para que suavizara las sanciones impuestas a su sector aeron\u00e1utico, alegando medidas relacionadas con la seguridad de los vuelos.<\/li>\n\n\n\n<li>Los accidentes a\u00e9reos se han multiplicado en los \u00faltimos a\u00f1os en Rusia, alcanzando los 208 en los primeros once meses de 2024, frente a los 86 de 2021.&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-5-80265' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2025\/10\/11\/economia-rusa-moscu-podria-perder-casi-la-mitad-de-su-flota-aerea-para-2030\/#easy-footnote-bottom-5-80265' title='Maria Erlich y Sofia Kanevskaya, \u00ab&lt;a href=&quot;https:\/\/novayagazeta.eu\/articles\/2024\/11\/28\/v-rossii-vynuzhdeny-idti-na-kompromiss-s-kachestvom-detalei&quot;&gt;\u0412 \u0420\u043e\u0441\u0441\u0438\u0438 \u0432\u044b\u043d\u0443\u0436\u0434\u0435\u043d\u044b \u0438\u0434\u0442\u0438 \u043d\u0430 \u043a\u043e\u043c\u043f\u0440\u043e\u043c\u0438\u0441\u0441 \u0432 \u0432\u043e\u043f\u0440\u043e\u0441\u0435 \u043a\u0430\u0447\u0435\u0441\u0442\u0432\u0430 \u0434\u0435\u0442\u0430\u043b\u0435\u0439&lt;\/a&gt;\u00bb, &lt;em&gt;Nova\u00efa Gazeta&lt;\/em&gt;, 28 de noviembre de 2024.'><sup>5<\/sup><\/a><\/span><\/span><\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/kFrNB\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>El desguace de varios cientos de aviones en los pr\u00f3ximos a\u00f1os, sin visibilidad a mediano y largo plazo sobre su posible sustituci\u00f3n, afectar\u00eda sobre todo al transporte en las regiones m\u00e1s aisladas del pa\u00eds. En las provincias del Lejano Oriente y el distrito siberiano, las conexiones a\u00e9reas se realizan principalmente con aviones Antonov An-2 y An-24, algunos de los cuales tienen m\u00e1s de sesenta a\u00f1os.&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-6-80265' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2025\/10\/11\/economia-rusa-moscu-podria-perder-casi-la-mitad-de-su-flota-aerea-para-2030\/#easy-footnote-bottom-6-80265' title='&lt;a href=&quot;https:\/\/t.me\/malap_ru\/605&quot;&gt;Publicaci\u00f3n en Telegram de \u0410\u0441\u0441\u043e\u0446\u0438\u0430\u0446\u0438\u044f \u041c\u0430\u043b\u0410\u041f&lt;\/a&gt;, 7 de octubre de 2025.'><sup>6<\/sup><\/a><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El sector aeron\u00e1utico ruso es uno de los que m\u00e1s ha sufrido las sanciones impuestas desde el inicio de la invasi\u00f3n a gran escala en 2022.<\/p>\n<p>Seg\u00fan el director de Rosaviatsiya, la agencia federal de transporte a\u00e9reo, esta crisis deber\u00eda acelerarse en los pr\u00f3ximos a\u00f1os, con la p\u00e9rdida prevista de 339 aviones y 200 helic\u00f3pteros para 2030.<\/p>\n","protected":false},"author":17959,"featured_media":80268,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":3,"footnotes":""},"categories":[5],"tags":[],"staff":[],"editorial_format":[1472],"serie":[],"audience":[],"geo":[182],"class_list":["post-80265","post","type-post","status-publish","format-standard","hentry","category-economia","editorial_format-analisis","geo-asia-septentrional"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":80268,"excerpt":"El sector aeron\u00e1utico ruso es uno de los que m\u00e1s ha sufrido las sanciones impuestas desde el inicio de la invasi\u00f3n a gran escala en 2022.\r\n\r\nSeg\u00fan el director de Rosaviatsiya, la agencia federal de transporte a\u00e9reo, esta crisis deber\u00eda acelerarse en los pr\u00f3ximos a\u00f1os, con la p\u00e9rdida prevista de 339 aviones y 200 helic\u00f3pteros para 2030.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Econom\u00eda rusa: Mosc\u00fa podr\u00eda perder casi la mitad de su flota a\u00e9rea para 2030 - El Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/es\/2025\/10\/11\/economia-rusa-moscu-podria-perder-casi-la-mitad-de-su-flota-aerea-para-2030\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Econom\u00eda rusa: Mosc\u00fa podr\u00eda perder casi la mitad de su flota a\u00e9rea para 2030 - El Grand Continent\" \/>\n<meta property=\"og:description\" content=\"El sector aeron\u00e1utico ruso es uno de los que m\u00e1s ha sufrido las sanciones impuestas desde el inicio de la invasi\u00f3n a gran escala en 2022.  Seg\u00fan el director de Rosaviatsiya, la agencia federal de transporte a\u00e9reo, esta crisis deber\u00eda acelerarse en los pr\u00f3ximos a\u00f1os, con la p\u00e9rdida prevista de 339 aviones y 200 helic\u00f3pteros para 2030.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/es\/2025\/10\/11\/economia-rusa-moscu-podria-perder-casi-la-mitad-de-su-flota-aerea-para-2030\/\" \/>\n<meta property=\"og:site_name\" content=\"El Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-11T05:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/10\/2RHPn-composici-n-de-la-flota-de-aviones-de-rosaviatsiya-por-procedencia.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1288\" \/>\n\t<meta property=\"og:image:height\" content=\"748\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"anainesfernandez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"anainesfernandez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/10\/11\/economia-rusa-moscu-podria-perder-casi-la-mitad-de-su-flota-aerea-para-2030\/\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/2025\/10\/11\/economia-rusa-moscu-podria-perder-casi-la-mitad-de-su-flota-aerea-para-2030\/\",\"name\":\"Econom\u00eda rusa: Mosc\u00fa podr\u00eda perder casi la mitad de su flota a\u00e9rea para 2030 - El Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/10\/11\/economia-rusa-moscu-podria-perder-casi-la-mitad-de-su-flota-aerea-para-2030\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/10\/11\/economia-rusa-moscu-podria-perder-casi-la-mitad-de-su-flota-aerea-para-2030\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/10\/2RHPn-composici-n-de-la-flota-de-aviones-de-rosaviatsiya-por-procedencia.png\",\"datePublished\":\"2025-10-11T05:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/570398dd8da37ba5d66dec6d242bd33c\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/10\/11\/economia-rusa-moscu-podria-perder-casi-la-mitad-de-su-flota-aerea-para-2030\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/es\/2025\/10\/11\/economia-rusa-moscu-podria-perder-casi-la-mitad-de-su-flota-aerea-para-2030\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/10\/11\/economia-rusa-moscu-podria-perder-casi-la-mitad-de-su-flota-aerea-para-2030\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/10\/2RHPn-composici-n-de-la-flota-de-aviones-de-rosaviatsiya-por-procedencia.png\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/10\/2RHPn-composici-n-de-la-flota-de-aviones-de-rosaviatsiya-por-procedencia.png\",\"width\":1288,\"height\":748},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/10\/11\/economia-rusa-moscu-podria-perder-casi-la-mitad-de-su-flota-aerea-para-2030\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/legrandcontinent.eu\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Econom\u00eda rusa: Mosc\u00fa podr\u00eda perder casi la mitad de su flota a\u00e9rea para 2030\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/\",\"name\":\"El Grand Continent\",\"description\":\"La escala pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/570398dd8da37ba5d66dec6d242bd33c\",\"name\":\"anainesfernandez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/fe25c21e6213f69a683147fabda32586?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/fe25c21e6213f69a683147fabda32586?s=96&d=mm&r=g\",\"caption\":\"anainesfernandez\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Econom\u00eda rusa: Mosc\u00fa podr\u00eda perder casi la mitad de su flota a\u00e9rea para 2030 - El Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/es\/2025\/10\/11\/economia-rusa-moscu-podria-perder-casi-la-mitad-de-su-flota-aerea-para-2030\/","og_locale":"es_ES","og_type":"article","og_title":"Econom\u00eda rusa: Mosc\u00fa podr\u00eda perder casi la mitad de su flota a\u00e9rea para 2030 - El Grand Continent","og_description":"El sector aeron\u00e1utico ruso es uno de los que m\u00e1s ha sufrido las sanciones impuestas desde el inicio de la invasi\u00f3n a gran escala en 2022.  Seg\u00fan el director de Rosaviatsiya, la agencia federal de transporte a\u00e9reo, esta crisis deber\u00eda acelerarse en los pr\u00f3ximos a\u00f1os, con la p\u00e9rdida prevista de 339 aviones y 200 helic\u00f3pteros para 2030.","og_url":"https:\/\/legrandcontinent.eu\/es\/2025\/10\/11\/economia-rusa-moscu-podria-perder-casi-la-mitad-de-su-flota-aerea-para-2030\/","og_site_name":"El Grand Continent","article_published_time":"2025-10-11T05:00:00+00:00","og_image":[{"width":1288,"height":748,"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/10\/2RHPn-composici-n-de-la-flota-de-aviones-de-rosaviatsiya-por-procedencia.png","type":"image\/png"}],"author":"anainesfernandez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"anainesfernandez","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/es\/2025\/10\/11\/economia-rusa-moscu-podria-perder-casi-la-mitad-de-su-flota-aerea-para-2030\/","url":"https:\/\/legrandcontinent.eu\/es\/2025\/10\/11\/economia-rusa-moscu-podria-perder-casi-la-mitad-de-su-flota-aerea-para-2030\/","name":"Econom\u00eda rusa: Mosc\u00fa podr\u00eda perder casi la mitad de su flota a\u00e9rea para 2030 - El Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/es\/2025\/10\/11\/economia-rusa-moscu-podria-perder-casi-la-mitad-de-su-flota-aerea-para-2030\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/es\/2025\/10\/11\/economia-rusa-moscu-podria-perder-casi-la-mitad-de-su-flota-aerea-para-2030\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/10\/2RHPn-composici-n-de-la-flota-de-aviones-de-rosaviatsiya-por-procedencia.png","datePublished":"2025-10-11T05:00:00+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/570398dd8da37ba5d66dec6d242bd33c"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/es\/2025\/10\/11\/economia-rusa-moscu-podria-perder-casi-la-mitad-de-su-flota-aerea-para-2030\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/es\/2025\/10\/11\/economia-rusa-moscu-podria-perder-casi-la-mitad-de-su-flota-aerea-para-2030\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/2025\/10\/11\/economia-rusa-moscu-podria-perder-casi-la-mitad-de-su-flota-aerea-para-2030\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/10\/2RHPn-composici-n-de-la-flota-de-aviones-de-rosaviatsiya-por-procedencia.png","contentUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/10\/2RHPn-composici-n-de-la-flota-de-aviones-de-rosaviatsiya-por-procedencia.png","width":1288,"height":748},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/es\/2025\/10\/11\/economia-rusa-moscu-podria-perder-casi-la-mitad-de-su-flota-aerea-para-2030\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legrandcontinent.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Econom\u00eda rusa: Mosc\u00fa podr\u00eda perder casi la mitad de su flota a\u00e9rea para 2030"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/es\/#website","url":"https:\/\/legrandcontinent.eu\/es\/","name":"El Grand Continent","description":"La escala pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/570398dd8da37ba5d66dec6d242bd33c","name":"anainesfernandez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/fe25c21e6213f69a683147fabda32586?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fe25c21e6213f69a683147fabda32586?s=96&d=mm&r=g","caption":"anainesfernandez"}}]}},"lgc_categories":[{"id":5,"name":"Econom\u00eda","slug":"economia"}],"lgc_author":null,"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/10\/2RHPn-composici-n-de-la-flota-de-aviones-de-rosaviatsiya-por-procedencia.png","width":1288,"height":748,"alt":""},"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/80265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/users\/17959"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/comments?post=80265"}],"version-history":[{"count":3,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/80265\/revisions"}],"predecessor-version":[{"id":80270,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/80265\/revisions\/80270"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media\/80268"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media?parent=80265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/categories?post=80265"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/tags?post=80265"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/staff?post=80265"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/editorial_format?post=80265"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/serie?post=80265"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/audience?post=80265"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/geo?post=80265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}