{"id":79308,"date":"2025-09-29T09:31:17","date_gmt":"2025-09-29T07:31:17","guid":{"rendered":"https:\/\/legrandcontinent.eu\/es\/?p=79308"},"modified":"2025-09-29T09:31:21","modified_gmt":"2025-09-29T07:31:21","slug":"elecciones-legislativas-en-moldavia-comprender-la-victoria-del-partido-proeuropeo-de-maia-sandu","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/es\/2025\/09\/29\/elecciones-legislativas-en-moldavia-comprender-la-victoria-del-partido-proeuropeo-de-maia-sandu\/","title":{"rendered":"Elecciones legislativas en Moldavia: comprender la victoria del partido proeuropeo de Maia Sandu"},"content":{"rendered":"\n<p class=\"has-drop-cap\">El 28 de septiembre de 2025, la Rep\u00fablica de Moldavia acudi\u00f3 a las urnas en un contexto de polarizaci\u00f3n sin precedentes que trasciende con creces el marco de unas simples elecciones legislativas. Algo m\u00e1s de 1,6 millones de votantes participaron en las elecciones, lo que supone una participaci\u00f3n del 52%, y dieron una escasa mayor\u00eda de esca\u00f1os al partido presidencial. <\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/7ECOK\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>No obstante, este \u00faltimo reuni\u00f3 a casi uno de cada dos votantes al t\u00e9rmino de las elecciones, una cifra notable y cercana al resultado de las anteriores elecciones legislativas de julio de 2021.\u00a0<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/mDAT9\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Si se tiene en cuenta la oferta pol\u00edtica, estas elecciones cristalizan el principal enfrentamiento geopol\u00edtico de la Europa contempor\u00e1nea: por un lado, la Uni\u00f3n Europea y sus valores democr\u00e1ticos; por otro, Rusia y su estrategia de <a href=\"https:\/\/legrandcontinent.eu\/es\/2025\/09\/28\/elecciones-en-moldavia-la-campana-de-injerencia-rusa-se-extiende-desde-lo-digital-hasta-lo-teologico\/\">desestabilizaci\u00f3n h\u00edbrida<\/a>. Para este peque\u00f1o pa\u00eds de 2,6 millones de habitantes, encajonado entre la Ucrania en guerra y la frontera oriental de la Uni\u00f3n, lo que estaba en juego era existencial.<\/p>\n\n\n\n<p>Desde que obtuvo el estatus de candidato a la adhesi\u00f3n a la Uni\u00f3n Europea en junio de 2022, Moldavia se ha convertido en un laboratorio de nuevas formas de confrontaci\u00f3n entre potencias rivales. Mosc\u00fa despliega all\u00ed un sofisticado arsenal de influencia: desinformaci\u00f3n masiva, corrupci\u00f3n electoral a gran escala, formaci\u00f3n paramilitar de agitadores, manipulaci\u00f3n energ\u00e9tica. Por su parte, la Uni\u00f3n Europea responde con un apoyo diplom\u00e1tico y financiero sin precedentes, lo que convierte a Moldavia en una prueba crucial para su pol\u00edtica de ampliaci\u00f3n.<\/p>\n\n\n\n<p>As\u00ed, estas elecciones han trascendido la dimensi\u00f3n nacional para convertirse en un indicador de los profundos cambios que se est\u00e1n produciendo en el orden geopol\u00edtico europeo. Se produce en un contexto en el que las t\u00e9cnicas de injerencia se sofistican \u2014desde las redes sociales potenciadas con inteligencia artificial hasta las operaciones de formaci\u00f3n militar en Serbia\u2014 y en el que las democracias europeas experimentan con nuevos mecanismos de protecci\u00f3n, que van desde la exclusi\u00f3n de partidos por financiaci\u00f3n ilegal hasta sanciones espec\u00edficas contra las redes de influencia.<\/p>\n\n\n\n<p>Para la presidenta proeuropea Maia Sandu, que calific\u00f3 estas elecciones como \u00ablas m\u00e1s importantes de la historia\u00bb del pa\u00eds, la batalla se libr\u00f3 en varios frentes simult\u00e1neamente. Frente a una oposici\u00f3n prorrusa movilizada y financiada por circuitos ocultos, el Partido Acci\u00f3n y Solidaridad (PAS) apost\u00f3 por una estrategia de aislamiento arriesgada, pero finalmente ganadora, rechazando cualquier alianza preelectoral en favor de una movilizaci\u00f3n total del electorado proeuropeo.<\/p>\n\n\n\n\n<div class=\"double-picture my-12 lg:my-20\" \n    data-images-sizes=\"smalldx\"\n    data-same-height=\"true\"\n    data-reference-image=\"left\"\n>    <!-- Images -->\n    <div class=\"lg:flex\">\n        <div class=\"relative lg:pr-2 mb-7 lg:mb-0 lg:w-2\/3\">\n                            <a \n                    href=\"#\"\n                    data-pswp-src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/09\/SIPA_ap22986583_000026-scaled.jpg\" \n                    class=\"gallery-item no-underline  \" \n                    data-pswp-width=\"2560\" \n                    data-pswp-height=\"1707\"\n                >\n                    <figure class=\"wp-block-image h-full -mx-2 lg:mx-0 !my-0\">\n                        <picture class=\"block h-full\">\n                            <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/09\/SIPA_ap22986583_000026-scaled.jpg\" alt=\"La presidenta moldava Maia Sandu, en el centro, habla con los medios de comunicaci\u00f3n tras votar en las elecciones legislativas, en Chisinau, Moldavia, el domingo 28 de septiembre de 2025.\" >\n                        <\/picture>\n                        <figcaption class=\"lg:hidden pswp-caption-content\">La presidenta moldava Maia Sandu, en el centro, habla con los medios de comunicaci\u00f3n tras votar en las elecciones legislativas, en Chisinau, Moldavia, el domingo 28 de septiembre de 2025.<\/figcaption>                    <\/figure>\n                <\/a>\n                    \n        <\/div>\n        <div class=\"relative lg:pl-2 lg:w-1\/3\">\n                            <a\n                    href=\"#\"\n                    data-pswp-src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/09\/SIPA_ap22986583_000027-scaled.jpg\" \n                    class=\"gallery-item no-underline  lg:!absolute lg:h-full lg:right-0 lg:left-2 overflow-hidden\" \n                    data-pswp-width=\"1707\" \n                    data-pswp-height=\"2560\"\n                >\n                    <figure class=\"wp-block-image h-full -mx-2 lg:mx-0 !my-0\">\n                        <picture class=\"block h-full\">\n                            <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/09\/SIPA_ap22986583_000027-scaled.jpg\" alt=\"La presidenta moldava Maia Sandu sostiene un ramo de flores al salir de un colegio electoral.\" class=\"lg:!h-full object-cover\">\n                        <\/picture>\n                        <figcaption class=\"lg:hidden pswp-caption-content\">La presidenta moldava Maia Sandu sostiene un ramo de flores al salir de un colegio electoral.<\/figcaption>                    <\/figure>\n                <\/a>\n                    <\/div>\n    <\/div>\n    <!-- Captions -->\n    <div class=\"hidden lg:flex\">\n        <div class=\"relative lg:pr-2 mb-7 lg:mb-0 lg:w-2\/3\">\n                            <figure class=\"wp-block-image -mx-2 lg:mx-0 !my-0\">\n                    <figcaption>La presidenta moldava Maia Sandu, en el centro, habla con los medios de comunicaci\u00f3n tras votar en las elecciones legislativas, en Chisinau, Moldavia, el domingo 28 de septiembre de 2025.<\/figcaption>                <\/figure>\n                    \n        <\/div>\n        <div class=\"relative lg:pl-2 lg:w-1\/3\">\n                            <figure class=\"wp-block-image -mx-2 lg:mx-0 !my-0\">   \n                    <figcaption>La presidenta moldava Maia Sandu sostiene un ramo de flores al salir de un colegio electoral.<\/figcaption>                <\/figure>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Una democracia en tensi\u00f3n entre las aspiraciones europeas y las resistencias internas<\/h2>\n\n\n\n<p>Estas elecciones se celebraron en un contexto de polarizaci\u00f3n pol\u00edtica sin precedentes en Moldavia. Maia Sandu, en un discurso marcial pronunciado unos d\u00edas antes de las elecciones, hizo un llamamiento para repeler a los \u00abtraidores\u00bb y los \u00abladrones\u00bb. Por su parte, el principal bloque de la oposici\u00f3n, el Bloque de Patriotas, no dud\u00f3 en llamar a sus seguidores a manifestarse para impedir cualquier fraude electoral.<\/p>\n\n\n\n<p>Las elecciones se celebraron seg\u00fan el sistema de representaci\u00f3n proporcional a una vuelta, con umbrales electorales diferenciados: 2% para los candidatos independientes, 5% para los partidos pol\u00edticos y 7% para los bloques electorales (compuestos por varios partidos). Esta arquitectura institucional, concebida para favorecer el pluralismo, revela hoy toda la complejidad del fragmentado panorama pol\u00edtico moldavo.<\/p>\n\n\n\n<p>La campa\u00f1a electoral cristaliz\u00f3 la oposici\u00f3n frontal entre dos visiones irreconciliables del futuro de Moldavia. Por un lado, el Partido Acci\u00f3n y Solidaridad (PAS) de la presidenta Maia Sandu defendi\u00f3 una agenda proeuropea, portadora de reformas democr\u00e1ticas y de la adhesi\u00f3n a la Uni\u00f3n Europea. Por otro lado, la oposici\u00f3n prorrusa, compuesta por comunistas y socialistas, y por partidos sat\u00e9lites agrupados en el Bloque Electoral Popular (BEP), aboga por un acercamiento a Mosc\u00fa. La oposici\u00f3n prorrusa intent\u00f3, sin \u00e9xito, aprovechar el cansancio social y econ\u00f3mico de una poblaci\u00f3n que se enfrenta a reformas exigentes, lo que puso de manifiesto las tensiones entre las aspiraciones europeas y las dif\u00edciles realidades econ\u00f3micas cotidianas.<\/p>\n\n\n\n<p>Sin embargo, esta bipolarizaci\u00f3n no oculta por completo la fragmentaci\u00f3n real del panorama pol\u00edtico. Formaciones como Alternativa, bloque liderado por el alcalde de Chisinau, Ion Ceban, el partido pol\u00edtico <em>Democratia acasa<\/em> (\u00abdemocracia en casa\u00bb, PPDA) de Vasile Costiuc o Nuestro Partido de Renato Usatii, encarnan posiciones intermedias o populistas que complican la lectura puramente geopol\u00edtica de los comicios.<\/p>\n\n\n\n<p>M\u00e1s all\u00e1 de las divisiones partidistas, las elecciones de 2025 ponen de relieve las profundas divisiones que atraviesan la sociedad moldava. Las regiones aut\u00f3nomas de Gagauzia y la cuesti\u00f3n sin resolver de Transnistria constituyen retos identitarios cruciales, en los que la poblaci\u00f3n local expresa su reticencia ante el proyecto europeo, como se vio en el refer\u00e9ndum de octubre de 2024 sobre la inclusi\u00f3n de la referencia a la integraci\u00f3n europea en la Constituci\u00f3n. As\u00ed, s\u00f3lo el 3,19% de los gagauzos votaron al partido presidencial, prefiriendo al Bloque de Patriotas con un 82,35%. En cuanto a Transnistria, las doce mesas electorales dieron una mayor\u00eda al Bloque de Patriotas (51,02%), pero una proporci\u00f3n significativa vot\u00f3 al PAS (29,89%).<\/p>\n\n\n\n<p>Las divisiones entre lo urbano y lo rural y entre generaciones amplifican estas tensiones. Mientras que Chi\u0219in\u0103u y los centros urbanos se inclinan mayoritariamente hacia Europa, las zonas rurales moldavas siguen estando influenciadas por un clero ortodoxo activo y apegadas a los lazos hist\u00f3ricos con Rusia. Si bien es en la capital donde el Bloque Alternativa del alcalde de la ciudad obtuvo sus mejores resultados, con algo menos del 15%, es el PAS el que se lleva la mayor\u00eda de los votos. Por \u00faltimo, el contexto electoral de 2025 se caracteriza por una desconfianza generalizada hacia las \u00e9lites pol\u00edticas tradicionales. Esta desconfianza, alimentada por d\u00e9cadas de corrupci\u00f3n e inestabilidad gubernamental, debilita las alianzas partidistas y genera una movilizaci\u00f3n electoral especialmente vol\u00e1til. Esta inestabilidad democr\u00e1tica explica en parte el surgimiento de formaciones populistas y antisistema, que aprovechan la frustraci\u00f3n popular ante las promesas incumplidas de los partidos establecidos.<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-large\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/09\/SIPA_ap22986583_000003-scaled.jpg\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"2560\"\n        data-pswp-height=\"1707\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/09\/SIPA_ap22986583_000003-330x220.jpg\"\r\n                media=\"(max-width: 374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/09\/SIPA_ap22986583_000003-690x460.jpg\"\r\n                media=\"(max-width: 989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/09\/SIPA_ap22986583_000003-1340x893.jpg\"\r\n                media=\"(min-width: 990px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/09\/SIPA_ap22986583_000003-125x83.jpg\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">Una mujer sale de una cabina electoral durante las elecciones legislativas, en Chisinau, Moldavia, el domingo 28 de septiembre de 2025.<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<h2 class=\"wp-block-heading\">Reformas electorales para hacer frente a los intentos de desestabilizaci\u00f3n<\/h2>\n\n\n\n<p>A ra\u00edz de las elecciones de 2024 y teniendo en cuenta los retos que plantea garantizar la integridad de las elecciones, las autoridades moldavas han emprendido un amplio programa de reformas electorales. As\u00ed, la Ley n.\u00ba 100, de 13 de junio de 2025, reforz\u00f3 significativamente la lucha contra la corrupci\u00f3n electoral, estableciendo sanciones m\u00e1s severas contra la compra de votos y la financiaci\u00f3n oculta de campa\u00f1as. Paralelamente, se han endurecido los requisitos de integridad para los candidatos, con verificaciones m\u00e1s estrictas de sus declaraciones patrimoniales y sus antecedentes penales. Estas medidas tienen por objeto restablecer la confianza de los ciudadanos en el proceso democr\u00e1tico. Por \u00faltimo, tambi\u00e9n se han adaptado las modalidades de votaci\u00f3n para tener en cuenta la realidad migratoria moldava.<\/p>\n\n\n\n<p>La decisi\u00f3n m\u00e1s emblem\u00e1tica de esta ofensiva reformista es la exclusi\u00f3n de las elecciones del bloque \u00abVictoria\u00bb del oligarca exiliado Ilan Shor por financiaci\u00f3n ilegal, una decisi\u00f3n que se inscribe en un contexto m\u00e1s amplio de lucha contra la injerencia rusa. Esta exclusi\u00f3n tiene su eco internacional en la iniciativa del Consejo de la Uni\u00f3n Europea, que el 15 de julio de 2025 incluy\u00f3 a siete personas y tres entidades en la lista por acciones desestabilizadoras de la Rep\u00fablica de Moldavia. Esta coordinaci\u00f3n entre la justicia moldava y las sanciones europeas es prueba de un enfoque integrado de la lucha contra la injerencia, que transforma la exclusi\u00f3n electoral en una herramienta geopol\u00edtica de protecci\u00f3n democr\u00e1tica. Seg\u00fan las autoridades electorales, el partido utiliz\u00f3 recursos financieros no declarados y se sospecha que pag\u00f3 a los votantes para influir en el resultado de las elecciones, lo que ilustra la persistencia de los intentos de eludir las normas democr\u00e1ticas.<\/p>\n\n\n\n<p>La sucesiva exclusi\u00f3n de formaciones prorrusas continu\u00f3 hasta los \u00faltimos d\u00edas de la campa\u00f1a. De hecho, dos d\u00edas antes de la celebraci\u00f3n de las elecciones, la prohibici\u00f3n de dos partidos prorrusos, <em>Moldova mare<\/em> (\u00abGran Moldavia\u00bb) y el de Irina Vlah (\u00abCoraz\u00f3n de Moldavia\u00bb, miembro del Bloque de Patriotas) suscit\u00f3 las cr\u00edticas de la oposici\u00f3n. Parad\u00f3jicamente, la exclusi\u00f3n de las formaciones prorrusas corre el riesgo de acentuar la radicalizaci\u00f3n de la oposici\u00f3n y alimentar las acusaciones de deriva autoritaria. Esta din\u00e1mica podr\u00eda debilitar la legitimidad democr\u00e1tica de las elecciones.<\/p>\n\n\n\n<p>M\u00e1s all\u00e1 de las espectaculares exclusiones, la reforma de 2025 establece requisitos m\u00e1s estrictos de integridad para los candidatos. Estas nuevas disposiciones imponen verificaciones exhaustivas de las declaraciones patrimoniales, las fuentes de financiaci\u00f3n y los antecedentes penales de los candidatos. El objetivo es prevenir la infiltraci\u00f3n de actores comprometidos con intereses extranjeros o actividades ilegales. Estas medidas preventivas van acompa\u00f1adas de un endurecimiento de las sanciones en caso de violaci\u00f3n de las normas de financiaci\u00f3n electoral. La Ley n.\u00ba 100, de 13 de junio de 2025, mencionada anteriormente, establece un arsenal represivo disuasorio, con multas sustanciales y prohibiciones de elegibilidad para los infractores. Este enfoque penal de la integridad electoral tiene por objeto aumentar el coste del incumplimiento de las normas democr\u00e1ticas.<\/p>\n\n\n\n<p>La adaptaci\u00f3n de las modalidades de voto constituye otro aspecto crucial de esta reforma. El control reforzado del voto de la di\u00e1spora responde a una doble exigencia: garantizar el ejercicio democr\u00e1tico de los moldavos residentes en el extranjero y prevenir al mismo tiempo las manipulaciones electorales. Esta poblaci\u00f3n, tradicionalmente proeuropea, representa un reto electoral importante que requiere procedimientos seguros. No obstante, cabe se\u00f1alar que, a pesar de la multiplicaci\u00f3n de los colegios electorales en 41 pa\u00edses (301, de los cuales 75 en Italia, 36 en Alemania y 26 en Francia), Rusia, cuyo electorado es menos favorable al partido en el poder, s\u00f3lo ha acogido dos colegios electorales a pesar de contar con una di\u00e1spora numerosa (estimada en 300.000 personas), lo que plantea dudas sobre la equidad de la votaci\u00f3n en este aspecto.&nbsp;<\/p>\n\n\n\n\n<div class=\"double-picture my-12 lg:my-20\" \n    data-images-sizes=\"half\"\n    data-same-height=\"true\"\n    data-reference-image=\"left\"\n>    <!-- Images -->\n    <div class=\"lg:flex\">\n        <div class=\"relative lg:pr-2 mb-7 lg:mb-0 lg:w-1\/2\">\n                            <a \n                    href=\"#\"\n                    data-pswp-src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/09\/SIPA_01232793_000017-scaled.jpg\" \n                    class=\"gallery-item no-underline  \" \n                    data-pswp-width=\"2560\" \n                    data-pswp-height=\"1707\"\n                >\n                    <figure class=\"wp-block-image h-full -mx-2 lg:mx-0 !my-0\">\n                        <picture class=\"block h-full\">\n                            <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/09\/SIPA_01232793_000017-scaled.jpg\" alt=\"Ciudadanos moldavos residentes en Rusia se re\u00fanen frente a la embajada de Moldavia para votar en las elecciones legislativas moldavas en Mosc\u00fa, Rusia.\" >\n                        <\/picture>\n                        <figcaption class=\"lg:hidden pswp-caption-content\">Ciudadanos moldavos residentes en Rusia se re\u00fanen frente a la embajada de Moldavia para votar en las elecciones legislativas moldavas en Mosc\u00fa, Rusia.<\/figcaption>                    <\/figure>\n                <\/a>\n                    \n        <\/div>\n        <div class=\"relative lg:pl-2 lg:w-1\/2\">\n                            <a\n                    href=\"#\"\n                    data-pswp-src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/09\/SIPA_01232376_000005-scaled.jpg\" \n                    class=\"gallery-item no-underline  lg:!absolute lg:h-full lg:right-0 lg:left-2 overflow-hidden\" \n                    data-pswp-width=\"2560\" \n                    data-pswp-height=\"1642\"\n                >\n                    <figure class=\"wp-block-image h-full -mx-2 lg:mx-0 !my-0\">\n                        <picture class=\"block h-full\">\n                            <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/09\/SIPA_01232376_000005-scaled.jpg\" alt=\"Un manifestante sostiene una pancarta en la que se lee \u00abSalvad Moldavia de la plaga amarilla\u00bb, el color del PAS, el partido de Maia Sandu.\" class=\"lg:!h-full object-cover\">\n                        <\/picture>\n                        <figcaption class=\"lg:hidden pswp-caption-content\">Un manifestante sostiene una pancarta en la que se lee \u00abSalvad Moldavia de la plaga amarilla\u00bb, el color del PAS, el partido de Maia Sandu.<\/figcaption>                    <\/figure>\n                <\/a>\n                    <\/div>\n    <\/div>\n    <!-- Captions -->\n    <div class=\"hidden lg:flex\">\n        <div class=\"relative lg:pr-2 mb-7 lg:mb-0 lg:w-1\/2\">\n                            <figure class=\"wp-block-image -mx-2 lg:mx-0 !my-0\">\n                    <figcaption>Ciudadanos moldavos residentes en Rusia se re\u00fanen frente a la embajada de Moldavia para votar en las elecciones legislativas moldavas en Mosc\u00fa, Rusia.<\/figcaption>                <\/figure>\n                    \n        <\/div>\n        <div class=\"relative lg:pl-2 lg:w-1\/2\">\n                            <figure class=\"wp-block-image -mx-2 lg:mx-0 !my-0\">   \n                    <figcaption>Un manifestante sostiene una pancarta en la que se lee \u00abSalvad Moldavia de la plaga amarilla\u00bb, el color del PAS, el partido de Maia Sandu.<\/figcaption>                <\/figure>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\">La estrategia ganadora del \u00abespl\u00e9ndido aislamiento\u00bb del PAS<\/h2>\n\n\n\n<p>Seguro de su fuerza y de la imagen de su presidenta, el Partido Acci\u00f3n y Solidaridad adopt\u00f3 una estrategia de aislamiento voluntario que constitu\u00eda una apuesta de alto riesgo sobre su capacidad de movilizaci\u00f3n electoral. A pesar de las solicitudes para formar alianzas preelectorales, el PAS opt\u00f3 por mantener su estrategia solitaria, rechazando a todos los dem\u00e1s partidos, considerados prorrusos.<\/p>\n\n\n\n<p>Esta postura de aislamiento estrat\u00e9gico se bas\u00f3 en varios c\u00e1lculos pol\u00edticos. Por un lado, permit\u00eda al PAS preservar la pureza de su mensaje proeuropeo sin diluir su programa, evitando compromisos que pudieran empa\u00f1ar su imagen de partido reformista \u00edntegro. Por otro lado, ten\u00eda como objetivo maximizar la movilizaci\u00f3n del electorado proeuropeo presentando las elecciones como una elecci\u00f3n binaria entre el proyecto europeo y las fuerzas de la oposici\u00f3n. Al rechazar cualquier alianza preelectoral, el PAS se privaba de posibles socios naturales para la formaci\u00f3n de una mayor\u00eda gubernamental, especialmente en un contexto en el que las encuestas suger\u00edan una erosi\u00f3n de su apoyo electoral.<\/p>\n\n\n\n<p>La presidenta Maia Sandu apost\u00f3 por la capacidad del PAS para reproducir la din\u00e1mica de movilizaci\u00f3n que le hab\u00eda permitido obtener el 52,8% de los votos y 63 diputados en julio de 2021. Esta estrategia se basaba en la hip\u00f3tesis de que la polarizaci\u00f3n geopol\u00edtica exacerbada por la guerra en Ucrania reforzar\u00eda la cohesi\u00f3n del electorado proeuropeo en torno al partido gubernamental. En un sistema parlamentario en el que la formaci\u00f3n de coaliciones suele ser la norma, el aislamiento voluntario del PAS result\u00f3, contra todo pron\u00f3stico, rentable. Sin duda, la dramatizaci\u00f3n de los retos tambi\u00e9n contribuy\u00f3 en gran medida a ello.&nbsp;<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-large\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/09\/SIPA_ap22986583_000038-scaled.jpg\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"2560\"\n        data-pswp-height=\"1707\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/09\/SIPA_ap22986583_000038-330x220.jpg\"\r\n                media=\"(max-width: 374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/09\/SIPA_ap22986583_000038-690x460.jpg\"\r\n                media=\"(max-width: 989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/09\/SIPA_ap22986583_000038-1340x893.jpg\"\r\n                media=\"(min-width: 990px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/09\/SIPA_ap22986583_000038-125x83.jpg\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">Soldados esperan frente a un colegio electoral para votar en las elecciones legislativas, en Chisinau, Moldavia, el domingo 28 de septiembre de 2025.<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<h2 class=\"wp-block-heading\">Entre pragmatismo y polarizaci\u00f3n: las contradicciones de la renovaci\u00f3n pol\u00edtica moldava<\/h2>\n\n\n\n<p>Estas elecciones revelaron una transformaci\u00f3n estructural del panorama pol\u00edtico moldavo, marcada por la erosi\u00f3n de los puntos de referencia tradicionales y la aparici\u00f3n de nuevas configuraciones partidistas.<\/p>\n\n\n\n<p>Ciertamente, el Bloque de Patriotas, compuesto por el Partido Socialista del expresidente Igor Dodon (2016-2020), el Partido Comunista de otro expresidente, Vladimir Voronin (2001-2009), y el Partido por el Futuro de Moldavia de Vasile Tarlev (ex primer ministro de 2001 a 2008), sigue siendo un referente pol\u00edtico s\u00f3lido. A pesar de los ajustes impuestos por la Comisi\u00f3n Electoral Central (exclusi\u00f3n de 26 candidatos vinculados a \u00abCoraz\u00f3n de Moldavia\u00bb de Irina Vlah), el bloque respet\u00f3 las cuotas de g\u00e9nero y pudo mantener su participaci\u00f3n. Bajo el lema \u00ab\u00a1Creemos en Moldavia!\u00bb, el BEP se ha afirmado como el principal polo prorruso y soberanista, en oposici\u00f3n frontal al Partido Acci\u00f3n y Solidaridad (PAS) en el poder, proeuropeo. La noche de las elecciones, Vlad Batr\u00eencea, diputado socialista y candidato del BEP, acus\u00f3 al PAS de intimidar a la poblaci\u00f3n e impedir que los ciudadanos votaran. En este contexto, el BEP se posicion\u00f3 como v\u00edctima de obst\u00e1culos y defensor de la unidad nacional, tratando de encarnar la oposici\u00f3n popular frente al poder proeuropeo.<\/p>\n\n\n\n<p>La aparici\u00f3n del Bloque Alternativa, una nueva formaci\u00f3n fundada el 31 de enero de 2025 y liderada por figuras destacadas como el alcalde de Chi\u0219in\u0103u, Ion Ceban, el exfiscal general Alexandre Stoianoglo y el ex primer ministro Ion Chicu, ilustra esta recomposici\u00f3n. Esta formaci\u00f3n pol\u00edtica encarna un intento de superar la polarizaci\u00f3n geopol\u00edtica posicion\u00e1ndose como \u00abni-ni \u00bb (ni Rusia, ni Occidente), aprovechando el cansancio de un electorado fatigado por la confrontaci\u00f3n ideol\u00f3gica permanente. Esta postura \u00abposideol\u00f3gica\u00bb responde a una demanda social real, como lo demuestran las encuestas que indican que una parte significativa de los votantes moldavos da prioridad a las preocupaciones socioecon\u00f3micas frente a las cuestiones geopol\u00edticas. Sin embargo, esta estrategia de superar la polarizaci\u00f3n sufri\u00f3 un importante rev\u00e9s diplom\u00e1tico el 9 de julio de 2025, cuando a Ion Ceban se le prohibi\u00f3 el acceso a Ruman\u00eda y al espacio Schengen por razones de seguridad nacional.<\/p>\n\n\n\n<p>Otro partido que entr\u00f3 en el Parlamento fue el <em>Partidul Nostru<\/em>, liderado por Renato Usat\u00eei, que se present\u00f3 como una formaci\u00f3n populista y antisistema, con el objetivo de captar el voto de protesta. Con un discurso cr\u00edtico hacia la corrupci\u00f3n de las \u00e9lites y las divisiones geopol\u00edticas tradicionales, Usat\u00eei se posicion\u00f3 como una alternativa \u00abni del Este ni del Oeste\u00bb, centrada en la justicia social y la proximidad con los ciudadanos. Durante la campa\u00f1a de septiembre de 2025, el PN intent\u00f3 movilizar a su electorado urbano y joven, apoy\u00e1ndose en el carisma de su l\u00edder y en un estilo directo, a veces provocador. En cuanto al \u00faltimo partido en entrar en el Parlamento, Democra\u021bia Acas\u0103, dirigido por Vasile Costiuc, es una peque\u00f1a formaci\u00f3n pol\u00edtica que se presenta como antisistema y contestataria, y que busca encarnar la voz de los olvidados del sistema. Su ret\u00f3rica destaca la defensa del ciudadano de a pie, el rechazo a la corrupci\u00f3n y la desconfianza hacia las grandes coaliciones dominantes, ya sean proeuropeas o prorrusas. Durante la campa\u00f1a de septiembre de 2025, DA intent\u00f3 hacerse un hueco en un panorama dominado por el duelo entre el PAS y el Bloque de los Patriotas, adoptando un discurso contundente y multiplicando las intervenciones medi\u00e1ticas de Costiuc, conocido por su estilo directo y su gusto por la pol\u00e9mica.<\/p>\n\n\n\n<p>Esta recomposici\u00f3n partidista se articula con divisiones territoriales que fraccionan el espacio nacional moldavo seg\u00fan l\u00edneas geopol\u00edticas e identitarias. La geograf\u00eda electoral moldava opone tradicionalmente Chi\u0219in\u0103u y los centros urbanos, mayoritariamente proeuropeos, a las zonas rurales y las regiones perif\u00e9ricas, m\u00e1s receptivas a los mensajes antioccidentales. La superposici\u00f3n de divisiones \u2014urbanas\/rurales, etnoling\u00fc\u00edsticas, generacionales\u2014 crea un complejo mosaico de identidades y pertenencias que complica la formaci\u00f3n de mayor\u00edas estables y coherentes. Tambi\u00e9n explica por qu\u00e9 ning\u00fan partido logra imponerse de manera hegem\u00f3nica en todo el territorio nacional, lo que alimenta la fragmentaci\u00f3n pol\u00edtica y la inestabilidad gubernamental cr\u00f3nica.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/SqHuW\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Desinformaci\u00f3n e hibridaci\u00f3n del escrutinio<\/h2>\n\n\n\n<p>La campa\u00f1a de desinformaci\u00f3n orquestada por Rusia, de una magnitud sin precedentes en Moldavia, fue uno de los retos de la campa\u00f1a. Mosc\u00fa intensific\u00f3 su ataque h\u00edbrido contra Moldavia antes de las elecciones legislativas, movilizando un sofisticado arsenal digital para desestabilizar el proceso democr\u00e1tico. Seg\u00fan el primer ministro Dorin Recean, las autoridades moldavas han sido objeto de m\u00e1s de 1.000 ciberataques desde principios de a\u00f1o y han logrado eliminar 100.000 cuentas falsas de TikTok que difund\u00edan desinformaci\u00f3n. Esta guerra informativa se basa en una estrategia multiplataforma especialmente eficaz.<\/p>\n\n\n\n<p>Esta batalla informativa se ha enriquecido con una dimensi\u00f3n geopol\u00edtica inesperada con las posiciones adoptadas por figuras emblem\u00e1ticas de la tecnolog\u00eda mundial. El mismo d\u00eda de las elecciones legislativas, Pavel Durov, fundador de Telegram, public\u00f3 una declaraci\u00f3n explosiva en la que acusaba a los servicios secretos franceses de haber intentado, hace un a\u00f1o, obligarle a censurar canales moldavos y transnistrios en su plataforma antes de las elecciones presidenciales. Esta revelaci\u00f3n provoc\u00f3 inmediatamente la reacci\u00f3n de Elon Musk, propietario de X (antes Twitter), que simplemente respondi\u00f3 \u00abWow\u00bb al mensaje de Durov, amplificando as\u00ed el alcance medi\u00e1tico de estas acusaciones. Esta intervenci\u00f3n de Musk, figura controvertida pero influyente del mundo tecnol\u00f3gico, ilustra c\u00f3mo los retos moldavos resuenan ahora en las esferas tecnol\u00f3gicas internacionales, transformando las plataformas digitales en aut\u00e9nticos campos de batalla geopol\u00edticos.<\/p>\n\n\n\n<p>Con motivo de estas elecciones, se puede hablar de un \u00abescrutinio h\u00edbrido\u00bb, en el que los retos nacionales se disuelven en un enfrentamiento geopol\u00edtico directo entre potencias rivales. Moldavia se convierte as\u00ed en un \u00ablaboratorio regional\u00bb de la relaci\u00f3n de fuerzas entre la Uni\u00f3n Europea y Rusia, transformando la expresi\u00f3n democr\u00e1tica en un teatro de operaciones geoestrat\u00e9gicas.<\/p>\n\n\n\n<p>El arsenal ruso de influencia electoral alcanz\u00f3 en 2025 un grado de sofisticaci\u00f3n in\u00e9dito, combinando guerra informativa, corrupci\u00f3n sist\u00e9mica y preparaci\u00f3n de acciones violentas. A menos de una semana de las elecciones se produjo una presunta operaci\u00f3n de injerencia rusa. Moldavos entrenados en Serbia deb\u00edan llevar a cabo acciones y manifestaciones violentas tras la votaci\u00f3n, lo que provoc\u00f3 la detenci\u00f3n de 74 personas. Las autoridades moldavas incautaron armas y dinero en efectivo, lo que demuestra la dimensi\u00f3n paramilitar de esta injerencia. Las actividades llevadas a cabo en Serbia fueron coordinadas por un hombre que se presentaba en nombre de un servicio especial de la Federaci\u00f3n de Rusia, lo que oficializaba <em>de facto<\/em> la implicaci\u00f3n directa de los servicios rusos en la desestabilizaci\u00f3n electoral moldava.<\/p>\n\n\n\n<p>M\u00e1s all\u00e1 de las operaciones directas, la estrategia rusa se basa en el concepto de \u00abcontrol reflexivo\u00bb, una t\u00e9cnica de manipulaci\u00f3n psicol\u00f3gica destinada a empujar al adversario hacia reacciones que sirvan indirectamente a los objetivos de Mosc\u00fa. Este enfoque consiste en crear situaciones en las que las autoridades moldavas y europeas se vean obligadas a adoptar medidas de seguridad que puedan presentarse como antidemocr\u00e1ticas. As\u00ed, la detenci\u00f3n masiva de activistas prorrusos, el refuerzo de los controles en los colegios electorales y las restricciones en determinadas plataformas digitales son elementos que la propaganda rusa puede aprovechar para denunciar una \u00abderiva autoritaria\u00bb del Gobierno proeuropeo. Esta estrategia convierte cada medida de protecci\u00f3n democr\u00e1tica en un argumento de desestabilizaci\u00f3n, atrapando a las autoridades en un dilema de seguridad permanente.<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-large\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/09\/SIPA_sipa60051608_000001-scaled.jpg\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"2560\"\n        data-pswp-height=\"1707\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/09\/SIPA_sipa60051608_000001-330x220.jpg\"\r\n                media=\"(max-width: 374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/09\/SIPA_sipa60051608_000001-690x460.jpg\"\r\n                media=\"(max-width: 989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/09\/SIPA_sipa60051608_000001-1340x893.jpg\"\r\n                media=\"(min-width: 990px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/09\/SIPA_sipa60051608_000001-125x83.jpg\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">Emmanuel Macron, Donald Trusk y Friedrich Merz en Chisinau el 27 de agosto de 2025.<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<h2 class=\"wp-block-heading\">El laboratorio moldavo o la democracia en Europa<\/h2>\n\n\n\n<p>M\u00e1s all\u00e1 de los retos nacionales moldavos, que permiten a Maia Sandu continuar con su agenda de reformas y seguir avanzando hacia la integraci\u00f3n europea de Moldavia, estas elecciones presagian los retos democr\u00e1ticos a los que se enfrentar\u00e1 Europa en los pr\u00f3ximos a\u00f1os. La hibridaci\u00f3n de las campa\u00f1as electorales, la sofisticaci\u00f3n de las t\u00e9cnicas de influencia extranjera y la polarizaci\u00f3n geopol\u00edtica de los debates internos son fen\u00f3menos que pueden extenderse a otras democracias europeas. La dimensi\u00f3n regional de este desaf\u00edo se ha manifestado en las preocupaciones expresadas en Kiev por el resultado de las elecciones, mientras que el expresidente rumano Traian B\u0103sescu evocaba el espectro de un \u00abKaliningrado del Sur\u00bb dotado de una base militar en caso de victoria de las fuerzas prorrusas. Esta ret\u00f3rica alarmista vino acompa\u00f1ada de referencias a manifestaciones violentas por parte del think tank ISW, rompiendo con la tradici\u00f3n moldava de transiciones pac\u00edficas del poder.<\/p>\n\n\n\n<p>Por lo tanto, lo que est\u00e1 en juego en estas elecciones del 28 de septiembre de 2025 va m\u00e1s all\u00e1 de la simple soberan\u00eda moldava y cuestiona el futuro mismo de la autonom\u00eda democr\u00e1tica europea frente a las estrategias de influencia de las potencias rivales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A pesar de la injerencia rusa y la armamentizaci\u00f3n de las redes sociales, la l\u00ednea europea de Maia Sandu obtuvo una mayor\u00eda absoluta en las elecciones legislativas celebradas ayer, domingo 28 de septiembre.<\/p>\n<p>Florent Parmentier analiza los resultados de un laboratorio geopol\u00edtico que revela varios aspectos de la democracia en Europa.<\/p>\n","protected":false},"author":1366,"featured_media":79299,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-studies.php","format":"standard","meta":{"_acf_changed":true,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":15,"footnotes":""},"categories":[232],"tags":[],"staff":[435],"editorial_format":[1469],"serie":[],"audience":[],"geo":[177],"class_list":["post-79308","post","type-post","status-publish","format-standard","hentry","category-elecciones","staff-florent-parmentier","editorial_format-estudios","geo-europa"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":79299,"excerpt":"A pesar de la injerencia rusa y la armamentizaci\u00f3n de las redes sociales, la l\u00ednea europea de Maia Sandu obtuvo una mayor\u00eda absoluta en las elecciones legislativas celebradas ayer, domingo 28 de septiembre.\r\n\r\nFlorent Parmentier analiza los resultados de un laboratorio geopol\u00edtico que revela varios aspectos de la democracia en Europa.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Elecciones legislativas en Moldavia: comprender la victoria del partido proeuropeo de Maia Sandu - El Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/es\/2025\/09\/29\/elecciones-legislativas-en-moldavia-comprender-la-victoria-del-partido-proeuropeo-de-maia-sandu\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Elecciones legislativas en Moldavia: comprender la victoria del partido proeuropeo de Maia Sandu - El Grand Continent\" \/>\n<meta property=\"og:description\" content=\"A pesar de la injerencia rusa y la armamentizaci\u00f3n de las redes sociales, la l\u00ednea europea de Maia Sandu obtuvo una mayor\u00eda absoluta en las elecciones legislativas celebradas ayer, domingo 28 de septiembre.  Florent Parmentier analiza los resultados de un laboratorio geopol\u00edtico que revela varios aspectos de la democracia en Europa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/es\/2025\/09\/29\/elecciones-legislativas-en-moldavia-comprender-la-victoria-del-partido-proeuropeo-de-maia-sandu\/\" \/>\n<meta property=\"og:site_name\" content=\"El Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-29T07:31:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-29T07:31:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/09\/gc-elmoldavia-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"florent\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/09\/gc-elmoldavia-1-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"florent\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"15 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/09\/29\/elecciones-legislativas-en-moldavia-comprender-la-victoria-del-partido-proeuropeo-de-maia-sandu\/\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/2025\/09\/29\/elecciones-legislativas-en-moldavia-comprender-la-victoria-del-partido-proeuropeo-de-maia-sandu\/\",\"name\":\"Elecciones legislativas en Moldavia: comprender la victoria del partido proeuropeo de Maia Sandu - El Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/09\/29\/elecciones-legislativas-en-moldavia-comprender-la-victoria-del-partido-proeuropeo-de-maia-sandu\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/09\/29\/elecciones-legislativas-en-moldavia-comprender-la-victoria-del-partido-proeuropeo-de-maia-sandu\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/09\/SIPA_01232582_000016-scaled.jpg\",\"datePublished\":\"2025-09-29T07:31:17+00:00\",\"dateModified\":\"2025-09-29T07:31:21+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/09\/29\/elecciones-legislativas-en-moldavia-comprender-la-victoria-del-partido-proeuropeo-de-maia-sandu\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/es\/2025\/09\/29\/elecciones-legislativas-en-moldavia-comprender-la-victoria-del-partido-proeuropeo-de-maia-sandu\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/09\/29\/elecciones-legislativas-en-moldavia-comprender-la-victoria-del-partido-proeuropeo-de-maia-sandu\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/09\/SIPA_01232582_000016-scaled.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/09\/SIPA_01232582_000016-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Malgr\u00e9 l'ing\u00e9rence russe et l'arsenalisation des r\u00e9seaux sociaux, la ligne europ\u00e9enne de Maia Sandu a obtenu une majorit\u00e9 absolue lors des \u00e9lections l\u00e9gislatives le dimanche 28 septembre.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/09\/29\/elecciones-legislativas-en-moldavia-comprender-la-victoria-del-partido-proeuropeo-de-maia-sandu\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/legrandcontinent.eu\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Elecciones legislativas en Moldavia: comprender la victoria del partido proeuropeo de Maia Sandu\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/\",\"name\":\"El Grand Continent\",\"description\":\"La escala pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\",\"name\":\"florent\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"caption\":\"florent\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Elecciones legislativas en Moldavia: comprender la victoria del partido proeuropeo de Maia Sandu - El Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/es\/2025\/09\/29\/elecciones-legislativas-en-moldavia-comprender-la-victoria-del-partido-proeuropeo-de-maia-sandu\/","og_locale":"es_ES","og_type":"article","og_title":"Elecciones legislativas en Moldavia: comprender la victoria del partido proeuropeo de Maia Sandu - El Grand Continent","og_description":"A pesar de la injerencia rusa y la armamentizaci\u00f3n de las redes sociales, la l\u00ednea europea de Maia Sandu obtuvo una mayor\u00eda absoluta en las elecciones legislativas celebradas ayer, domingo 28 de septiembre.  Florent Parmentier analiza los resultados de un laboratorio geopol\u00edtico que revela varios aspectos de la democracia en Europa.","og_url":"https:\/\/legrandcontinent.eu\/es\/2025\/09\/29\/elecciones-legislativas-en-moldavia-comprender-la-victoria-del-partido-proeuropeo-de-maia-sandu\/","og_site_name":"El Grand Continent","article_published_time":"2025-09-29T07:31:17+00:00","article_modified_time":"2025-09-29T07:31:21+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/09\/gc-elmoldavia-1-scaled.jpg","type":"image\/jpeg"}],"author":"florent","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/09\/gc-elmoldavia-1-scaled.jpg","twitter_misc":{"Escrito por":"florent","Tiempo de lectura":"15 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/es\/2025\/09\/29\/elecciones-legislativas-en-moldavia-comprender-la-victoria-del-partido-proeuropeo-de-maia-sandu\/","url":"https:\/\/legrandcontinent.eu\/es\/2025\/09\/29\/elecciones-legislativas-en-moldavia-comprender-la-victoria-del-partido-proeuropeo-de-maia-sandu\/","name":"Elecciones legislativas en Moldavia: comprender la victoria del partido proeuropeo de Maia Sandu - El Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/es\/2025\/09\/29\/elecciones-legislativas-en-moldavia-comprender-la-victoria-del-partido-proeuropeo-de-maia-sandu\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/es\/2025\/09\/29\/elecciones-legislativas-en-moldavia-comprender-la-victoria-del-partido-proeuropeo-de-maia-sandu\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/09\/SIPA_01232582_000016-scaled.jpg","datePublished":"2025-09-29T07:31:17+00:00","dateModified":"2025-09-29T07:31:21+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/es\/2025\/09\/29\/elecciones-legislativas-en-moldavia-comprender-la-victoria-del-partido-proeuropeo-de-maia-sandu\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/es\/2025\/09\/29\/elecciones-legislativas-en-moldavia-comprender-la-victoria-del-partido-proeuropeo-de-maia-sandu\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/2025\/09\/29\/elecciones-legislativas-en-moldavia-comprender-la-victoria-del-partido-proeuropeo-de-maia-sandu\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/09\/SIPA_01232582_000016-scaled.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/09\/SIPA_01232582_000016-scaled.jpg","width":2560,"height":1707,"caption":"Malgr\u00e9 l'ing\u00e9rence russe et l'arsenalisation des r\u00e9seaux sociaux, la ligne europ\u00e9enne de Maia Sandu a obtenu une majorit\u00e9 absolue lors des \u00e9lections l\u00e9gislatives le dimanche 28 septembre."},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/es\/2025\/09\/29\/elecciones-legislativas-en-moldavia-comprender-la-victoria-del-partido-proeuropeo-de-maia-sandu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legrandcontinent.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Elecciones legislativas en Moldavia: comprender la victoria del partido proeuropeo de Maia Sandu"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/es\/#website","url":"https:\/\/legrandcontinent.eu\/es\/","name":"El Grand Continent","description":"La escala pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c","name":"florent","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","caption":"florent"}}]}},"lgc_categories":[{"id":232,"name":"Elecciones","slug":"elecciones"}],"lgc_author":{"id":435,"name":"Florent Parmentier","slug":"florent-parmentier","description":null,"first_name":null,"last_name":null,"picture":null},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/09\/SIPA_01232582_000016-scaled.jpg","width":2560,"height":1707,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/09\/SIPA_01232582_000016-scaled.jpg","width":2560,"height":1707,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/79308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/users\/1366"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/comments?post=79308"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/79308\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media\/79299"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media?parent=79308"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/categories?post=79308"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/tags?post=79308"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/staff?post=79308"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/editorial_format?post=79308"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/serie?post=79308"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/audience?post=79308"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/geo?post=79308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}