{"id":73602,"date":"2025-07-25T11:05:38","date_gmt":"2025-07-25T09:05:38","guid":{"rendered":"https:\/\/legrandcontinent.eu\/es\/?p=73602"},"modified":"2025-07-25T11:05:42","modified_gmt":"2025-07-25T09:05:42","slug":"netanyahu-no-quiere-poner-fin-a-la-guerra-una-conversacion-con-ehud-olmert-ex-primer-ministro-de-israel","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/es\/2025\/07\/25\/netanyahu-no-quiere-poner-fin-a-la-guerra-una-conversacion-con-ehud-olmert-ex-primer-ministro-de-israel\/","title":{"rendered":"\u00abNetanyahu no quiere poner fin a la guerra\u00bb, una conversaci\u00f3n con Ehud Olmert, ex primer ministro de Israel"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Un mes despu\u00e9s del fin de la guerra de doce d\u00edas, \u00bfqu\u00e9 lecciones se desprenden de la estrategia Israel\u00ed contra Ir\u00e1n?<\/h3>\n\n\n\n<p>En primer lugar, Israel ha logrado el control absoluto del espacio a\u00e9reo iran\u00ed. Esto ha puesto de manifiesto la vulnerabilidad de Ir\u00e1n y le ha enviado un mensaje claro sobre las opciones de que dispone Israel en caso de una nueva escalada militar.<\/p>\n\n\n\n<p>El ej\u00e9rcito israel\u00ed no ha podido destruir todas las instalaciones nucleares iran\u00edes, algunas de las cuales estaban fuera de su alcance. Pero ha demostrado que es capaz de golpear los puntos m\u00e1s sensibles del territorio iran\u00ed. Ir\u00e1n deber\u00e1 ser plenamente consciente de ello a partir de ahora.<\/p>\n\n\n\n<p>A continuaci\u00f3n, Estados Unidos decidi\u00f3 atacar instalaciones nucleares iran\u00edes. A\u00fan no conocemos el balance exacto de estos ataques. Lo esencial es que, por primera vez, un presidente estadounidense, l\u00edder de un pa\u00eds que lleva veinticinco a\u00f1os afirmando que quiere impedir que Ir\u00e1n adquiera armas nucleares, ha dado el paso y ha llevado a cabo una acci\u00f3n militar directa, con aviones estadounidenses, contra Ir\u00e1n.<\/p>\n\n\n\n<p>Esto tambi\u00e9n recuerda a los dirigentes iran\u00edes que, la pr\u00f3xima vez, la respuesta podr\u00eda ser mucho m\u00e1s severa. Deber\u00e1n tenerlo en cuenta.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>En mi opini\u00f3n, la hip\u00f3tesis de un derrocamiento del r\u00e9gimen nunca fue una opci\u00f3n seria.<\/p><cite>Ehud Olmert<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Al comienzo del ataque, parec\u00eda que Benjamin Netanyahu no solo buscaba la superioridad a\u00e9rea y militar, sino tambi\u00e9n derrocar al r\u00e9gimen iran\u00ed. Por el momento, este objetivo no se ha alcanzado. \u00bfEs un fracaso?<\/h3>\n\n\n\n<p>No hay que tomarse al pie de la letra todas las declaraciones, ni toda la ret\u00f3rica pomposa y grandilocuente que a veces acompa\u00f1a a este tipo de acontecimientos, sobre todo cuando proviene de Netanyahu, que destaca en el arte de decir demasiado.<\/p>\n\n\n\n<p>Dudo que alguien creyera realmente que Israel iba a derrocar al r\u00e9gimen iran\u00ed.<\/p>\n\n\n\n<p>En mi opini\u00f3n, la hip\u00f3tesis de un derrocamiento del r\u00e9gimen nunca fue una opci\u00f3n seria. Por lo tanto, no hay que considerar su no consecuci\u00f3n como un fracaso.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Siria ha experimentado recientemente un cambio de r\u00e9gimen. Desde entonces, Israel se muestra muy activo en ese pa\u00eds, recurriendo incluso a la fuerza para proteger a la poblaci\u00f3n drusa. \u00bfCu\u00e1l es el objetivo de Netanyahu en Siria?<\/h3>\n\n\n\n<p>La cuesti\u00f3n drusa es especialmente compleja y delicada en Israel.<\/p>\n\n\n\n<p>Tenemos una importante comunidad drusa, plenamente comprometida con el Estado de Israel. Son socios leales para su seguridad y se encuentran entre los mejores combatientes del ej\u00e9rcito israel\u00ed. Muchos de ellos han ca\u00eddo recientemente en combate.<\/p>\n\n\n\n<p>Cuando miembros de la comunidad drusa siria, algunos de ellos pertenecientes a familias que viven en Israel, fueron atacados, Israel se encontr\u00f3 ante un dilema. No acudir en su ayuda habr\u00eda sido percibido como una traici\u00f3n por los drusos israel\u00edes. Era necesaria una respuesta militar. Queda la cuesti\u00f3n de la forma que deb\u00eda adoptar.<\/p>\n\n\n\n<p>Mientras la acci\u00f3n militar se concentraba en las zonas donde viven los drusos, con una l\u00f3gica defensiva, era comprensible. Sin embargo, no entiendo por qu\u00e9 atacamos el cuartel general del ej\u00e9rcito sirio en Damasco, o incluso el palacio presidencial. Eso no ten\u00eda nada que ver con la protecci\u00f3n de los drusos. Fue una provocaci\u00f3n innecesaria contra Al-Shaara. Un error.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Estoy a favor de tender la mano a Al-Shaara, pero con la condici\u00f3n de que \u00e9l haga su parte.<\/p><cite>Ehud Olmert<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfCree que Al-Shaara podr\u00eda convertirse en un aliado de Israel? \u00bfC\u00f3mo se explica la decisi\u00f3n de Netanyahu de no aprovechar esta oportunidad?<\/h3>\n\n\n\n<p>Hay que ser cautelosos con Al-Shaara. Proviene de las filas del Estado Isl\u00e1mico. Ha pasado la mayor parte de su vida masacrando y decapitando, al servicio del movimiento religioso fundamentalista m\u00e1s extremo que existe. Hoy es el nuevo presidente de Siria.<\/p>\n\n\n\n<p>Como muchos israel\u00edes, estoy a favor de explorar la posibilidad de un di\u00e1logo con \u00e9l.<\/p>\n\n\n\n<p>Pero hay que hacerlo con extrema cautela, poco a poco. Primero hay que entender si realmente ha cambiado, si est\u00e1 dispuesto a emprender las reformas necesarias para obtener el apoyo israel\u00ed, a riesgo de volver a ser atacado.<\/p>\n\n\n\n<p>Creo que hay que hacer un esfuerzo excepcional para entablar un di\u00e1logo con \u00e9l. Pero eso supone un esfuerzo equivalente por su parte. Ahora bien, atacar a los drusos no va precisamente en esa direcci\u00f3n. Hay que tener presente la extrema sensibilidad de Israel en este tema y velar por que las fuerzas bajo su autoridad act\u00faen con moderaci\u00f3n.<\/p>\n\n\n\n<p>Por lo tanto, estoy a favor de tender la mano a Al-Shaara, pero con la condici\u00f3n de que \u00e9l haga su parte. Por el momento, no es el caso.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfSale Netanyahu reforzado de esta secuencia a ojos de los israel\u00edes?<\/h3>\n\n\n\n<p>Es dif\u00edcil de decir. Las encuestas realizadas desde la guerra en Ir\u00e1n no muestran un cambio radical en la opini\u00f3n p\u00fablica israel\u00ed.<\/p>\n\n\n\n<p>Est\u00e1 dominada por dos tendencias contradictorias.<\/p>\n\n\n\n<p>Por un lado, la operaci\u00f3n militar israel\u00ed en Ir\u00e1n ha recibido un amplio apoyo. Se ha elogiado a la fuerza a\u00e9rea por la calidad de su intervenci\u00f3n. El hecho de que Netanyahu haya tomado esta decisi\u00f3n ha jugado claramente a su favor, de eso no hay duda.<\/p>\n\n\n\n<p>Pero, por otro lado, hay varios elementos que pesan mucho en contra de Netanyahu: la falta de acuerdo sobre los rehenes, la ausencia de un alto al fuego, la continuaci\u00f3n de la guerra en Gaza, que est\u00e1 costando muchas vidas humanas, con soldados israel\u00edes muertos cada d\u00eda, sin un objetivo claro ni una justificaci\u00f3n convincente.<\/p>\n\n\n\n<p>Y luego est\u00e1 ese absurdo proyecto de campamento humanitario en Gaza, que se percibe, en casi todo el mundo, como una medida inaceptable. La perspectiva de expulsar a los palestinos del norte de Gaza para reunirlos en un campamento segregado en el sur empa\u00f1a su imagen.<\/p>\n\n\n\n<p>Por lo tanto, tengo la impresi\u00f3n de que la percepci\u00f3n de Netanyahu en la opini\u00f3n p\u00fablica israel\u00ed se ha mantenido pr\u00e1cticamente sin cambios.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Estados Unidos no abandona la UNESCO para complacer a Israel.<\/p><cite>Ehud Olmert<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfEl apoyo activo de Donald Trump a la guerra en Ir\u00e1n marca un cambio en la pol\u00edtica estadounidense hacia Israel?<\/h3>\n\n\n\n<p>Tambi\u00e9n me gustar\u00eda poder entenderlo, \u00a1pero estoy buscando a alguien que me explique qu\u00e9 est\u00e1 haciendo Trump!<\/p>\n\n\n\n<p>Creo que Israel ha sorprendido a Estados Unidos al atacar Ir\u00e1n. Y que estos \u00faltimos prefirieron unirse a la operaci\u00f3n antes de que la guerra degenerara en un conflicto mucho m\u00e1s importante.<\/p>\n\n\n\n<p>La participaci\u00f3n estadounidense puede entenderse como un intento de contener los acontecimientos antes de que se vuelvan incontrolables. Con su ataque, Estados Unidos ha enviado un mensaje a los dirigentes iran\u00edes, advirti\u00e9ndoles de las posibles consecuencias de una escalada en la respuesta a Israel.<\/p>\n\n\n\n<p>Con su compromiso, Estados Unidos probablemente ha evitado que el ataque israel\u00ed provoque mayores disturbios en todo Medio Oriente.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Si Israel toma conciencia de la magnitud y el impacto de lo que la gente ve cada d\u00eda en Europa o en Estados Unidos y si modifica de alguna manera su rumbo para poner fin a la guerra, entonces s\u00ed, eso tambi\u00e9n podr\u00eda allanar el camino para una rehabilitaci\u00f3n diplom\u00e1tica.<\/p><cite>Ehud Olmert<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">El Departamento de Estado estadounidense ha anunciado la retirada de Estados Unidos de la UNESCO en respuesta al posible reconocimiento del Estado de Palestina por parte de la organizaci\u00f3n internacional. \u00bfEs esto una victoria pol\u00edtica para Netanyahu?<\/h3>\n\n\n\n<p>No lo creo. Estados Unidos ya se hab\u00eda retirado de la UNESCO durante el primer mandato de Trump, antes de que Biden reincorporara al pa\u00eds a la organizaci\u00f3n.<\/p>\n\n\n\n<p>Estados Unidos no abandona la UNESCO para complacer a Israel. Esta nueva retirada forma parte simplemente del programa de Trump y la cuesti\u00f3n de Palestina solo sirve para reforzar sus argumentos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Desde hace dos a\u00f1os, las victorias militares de Israel son innegables. La operaci\u00f3n contra Ir\u00e1n ha sido un \u00e9xito, al igual que la eliminaci\u00f3n de los l\u00edderes de Hezbol\u00e1. Sin embargo, debido a las decisiones del gobierno israel\u00ed en Gaza y tambi\u00e9n en Cisjordania, se observa un creciente rechazo diplom\u00e1tico hacia Israel por parte de los pa\u00edses del \u00abSur global\u00bb. \u00bfCree que esta din\u00e1mica podr\u00e1 invertirse tras la era Netanyahu?<\/h3>\n\n\n\n<p>Es muy probable que cambie tras Netanyahu. De hecho, podr\u00eda cambiar incluso <em>con<\/em> \u00e9l, si aceptara escuchar al mundo y comprendiera que lo que a\u00fan pod\u00eda parecer justificable el 7 de octubre de 2023 ya no lo es necesariamente en julio o agosto de 2025.<\/p>\n\n\n\n<p>Algo profundo ha ocurrido entre esas dos fechas. El 7 de octubre de 2023, unos 1.500 israel\u00edes fueron masacrados, degollados, tomados como rehenes. Pero en julio de 2025, hay m\u00e1s de 60.000 palestinos muertos y alrededor del 60 % de los edificios de Gaza destruidos.<\/p>\n\n\n\n<p>La percepci\u00f3n internacional ha cambiado, no solo por el horror inicial del 7 de octubre, sino tambi\u00e9n por lo que Israel ha hecho desde entonces. Y esa percepci\u00f3n sigue cambiando.<\/p>\n\n\n\n<p>Si Israel toma conciencia de la magnitud y el impacto de lo que la gente ve cada d\u00eda en Europa o en Estados Unidos \u2014las columnas de humo, las explosiones, los ataques a\u00e9reos sobre Gaza\u2014 y si modifica de alguna manera su rumbo para poner fin a la guerra, entonces s\u00ed, eso tambi\u00e9n podr\u00eda allanar el camino para una rehabilitaci\u00f3n diplom\u00e1tica.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">En su opini\u00f3n, \u00bfqu\u00e9 probabilidades hay hoy de que el gobierno de Netanyahu sea derrocado en las pr\u00f3ximas semanas o meses?<\/h3>\n\n\n\n<p>El deseo de Netanyahu de permanecer en el poder es lo que ha motivado sus acciones desde el primer d\u00eda. No lo mueven los intereses de Israel, ni la respuesta a las dificultades que hemos atravesado en los \u00faltimos dos a\u00f1os.<\/p>\n\n\n\n<p>Incluso en el contexto muy dif\u00edcil de la guerra, Netanyahu har\u00e1 todo lo posible por mantenerse al frente de Israel. Y nosotros debemos seguir haciendo todo lo posible para deshacernos de \u00e9l.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>En primer lugar, hay que recordar con claridad y firmeza una evidencia: Gaza forma parte de Palestina y debe seguir formando parte de ella.<\/p><cite>Ehud Olmert<\/cite><\/blockquote><\/figure>\n\n\n\n<p>No creo que Netanyahu sea derrocado por una votaci\u00f3n en la Knesset, ya que actualmente no hay suficientes votos para apoyar a un primer ministro alternativo, condici\u00f3n necesaria para derrocar a un gobierno.<\/p>\n\n\n\n<p>Dicho esto, observo que su gobierno se est\u00e1 debilitando y perdiendo popularidad progresivamente.<\/p>\n\n\n\n<p>Por lo tanto, es probable que se convoquen elecciones anticipadas, quiz\u00e1 a finales de marzo de 2026. Estas elecciones podr\u00edan marcar el fin de la era Netanyahu.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfDeber\u00edan, en su opini\u00f3n, emprenderse acciones legales contra Benjamin Netanyahu y otros responsables israel\u00edes por la forma en que han llevado esta guerra?<\/h3>\n\n\n\n<p>Netanyahu solo puede ser procesado si hay pruebas de que es responsable individual y directamente de haber abusado de sus prerrogativas como primer ministro para cometer lo que se define en t\u00e9rminos jur\u00eddicos como un delito.<\/p>\n\n\n\n<p>Si, por un lado, la CPI ha dictado \u00f3rdenes de detenci\u00f3n contra Benjam\u00edn Netanyahu y el exministro de Defensa Yoav Gallant, por otro, la CIJ de La Haya ha concedido medidas provisionales en favor de la protecci\u00f3n de los palestinos, al tiempo que se ha negado a suspender las operaciones militares israel\u00edes.<\/p>\n\n\n\n<p>Por lo tanto, el debate jur\u00eddico sobre esta cuesti\u00f3n sigue abierto.<\/p>\n\n\n\n<p>Por mi parte, espero sinceramente que sea juzgado en Israel por los cr\u00edmenes que ha cometido contra el Estado de Israel, contra su estabilidad y contra la solidaridad de la sociedad israel\u00ed, lo que provocar\u00eda su ca\u00edda pol\u00edtica.<\/p>\n\n\n\n<p>Por otra parte, espero que Netanyahu no sea procesado a nivel internacional, ya que un juicio contra el primer ministro israel\u00ed se convertir\u00eda en un juicio contra el Estado de Israel. Y creo que eso podr\u00eda crear una situaci\u00f3n en la que ser\u00eda a\u00fan m\u00e1s dif\u00edcil avanzar hacia la paz.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfC\u00f3mo ve el futuro de Gaza a corto plazo?<\/h3>\n\n\n\n<p>En primer lugar, hay que recordar con claridad y firmeza una evidencia: Gaza forma parte de Palestina y debe seguir formando parte de ella.<\/p>\n\n\n\n<p>Hist\u00f3ricamente, Israel siempre ha tenido una actitud ambivalente hacia el enclave. Gaza nunca ha formado parte del Estado de Israel y nunca ha estado destinada a formar parte de \u00e9l. Sin embargo, a lo largo de los procesos hist\u00f3ricos de negociaci\u00f3n que hemos mantenido con los pa\u00edses \u00e1rabes sobre Gaza, en particular con Egipto, la postura israel\u00ed siempre ha sido mantener la posibilidad de controlar Gaza de una forma u otra.<\/p>\n\n\n\n<p>En 2005, cuando era viceprimer ministro de Sharon, hicimos lo que entonces era una primicia para un gobierno israel\u00ed al decidir retirarnos completamente de la Franja de Gaza y desmantelar todos los asentamientos israel\u00edes situados al otro lado de lo que se consideraba la frontera. Y aplicamos esa decisi\u00f3n.<\/p>\n\n\n\n<p>Un aspecto esencial es la conexi\u00f3n f\u00edsica entre Gaza y Cisjordania. Este v\u00ednculo nunca ha existido, pero lo considero esencial. No me cansar\u00e9 de repetirlo: Gaza no es parte de Israel, es parte de Palestina. Y si Gaza es parte de Palestina, entonces Palestina debe participar en su reconstrucci\u00f3n y administraci\u00f3n.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfQu\u00e9 escenarios podr\u00edan permitir poner fin a esta guerra?<\/h3>\n\n\n\n<p>La \u00fanica salida posible hoy es poner fin inmediatamente a la guerra, repatriar a todos los rehenes, liberar a los prisioneros palestinos en el marco de un acuerdo y establecer una fuerza de seguridad provisional compuesta por palestinos, egipcios, jordanos, emirat\u00edes, bahrein\u00edes \u2014y quiz\u00e1s tambi\u00e9n soldados saud\u00edes\u2014 que asumir\u00edan el control efectivo de Gaza. Esta fuerza permitir\u00eda una retirada completa de Israel, al tiempo que impedir\u00eda que Ham\u00e1s volviera a tomar el control.<\/p>\n\n\n\n<p>Al mismo tiempo, es necesario establecer una administraci\u00f3n encargada de gobernar Gaza en lugar de Ham\u00e1s. Esta estar\u00eda vinculada org\u00e1nicamente a la Autoridad Palestina, el \u00fanico \u00f3rgano representativo global de los palestinos, reconocido por la comunidad internacional, las Naciones Unidas, la Uni\u00f3n Europea, etc.<\/p>\n\n\n\n<p>El problema es que el balance de la Autoridad Palestina en materia de gobernanza, en particular en Gaza, es mediocre.<\/p>\n\n\n\n<p>Por lo tanto, proponemos que exista un v\u00ednculo jur\u00eddico con la Autoridad Palestina, pero que el \u00f3rgano rector de Gaza disponga de poderes ejecutivos independientes para poder controlar el territorio y aplicar las medidas necesarias para la reconstrucci\u00f3n.<\/p>\n\n\n\n<p>Este es el plan que he presentado, junto con el exministro de Asuntos Exteriores de la Autoridad Palestina, Nasser Al-Qidwa.<\/p>\n\n\n\n<p>Creemos que hoy en d\u00eda es la \u00fanica v\u00eda posible.<\/p>\n\n\n\n<p>Por supuesto, si se quiere ir m\u00e1s all\u00e1 y transformar profundamente la situaci\u00f3n regional, habr\u00e1 que abrir una nueva era. Se necesitar\u00e1 una decisi\u00f3n pol\u00edtica firme para iniciar negociaciones serias con la Autoridad Palestina en torno a una soluci\u00f3n de dos Estados.<\/p>\n\n\n\n<p>A escala regional, esto permitir\u00eda reanudar las relaciones con Arabia Saudita y, potencialmente, con Indonesia y otros pa\u00edses \u00e1rabes y musulmanes.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Israel no quiere poner fin a la guerra.<\/p><cite>Ehud Olmert<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Esto supondr\u00eda un cambio estrat\u00e9gico importante, capaz de modificar profundamente los equilibrios en Medio Oriente. Ser\u00eda un punto de inflexi\u00f3n radical.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfQui\u00e9n podr\u00eda obligar a todas las partes implicadas a dar un paso importante hacia el inicio de una soluci\u00f3n pac\u00edfica?<\/h3>\n\n\n\n<p>Si se pregunta a los actores implicados qu\u00e9 necesitan para llegar a una soluci\u00f3n, o al menos al inicio de las negociaciones, todos responder\u00e1n: \u00abNecesitamos que el presidente estadounidense dirija una petici\u00f3n muy firme a las partes implicadas\u00bb.<\/p>\n\n\n\n<p>En este sentido, esperamos que Trump convoque a Netanyahu al lugar que m\u00e1s les gusta a ambos: el Despacho Oval, ante las c\u00e1maras. All\u00ed, el presidente Trump podr\u00eda decirle teatralmente a Netanyahu: \u00abBibi, ya basta. Ya es demasiado. Tienes que pasar la p\u00e1gina\u00bb.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfPodr\u00eda ser tambi\u00e9n determinante el papel de Arabia Saudita?<\/h3>\n\n\n\n<p>Creo que los saud\u00edes se enfrentan a un dilema.<\/p>\n\n\n\n<p>Por un lado, est\u00e1n ansiosos por avanzar hacia la normalizaci\u00f3n con Israel, en el marco de una nueva estrategia destinada a reunir a todos los pa\u00edses moderados potencialmente opuestos a los iran\u00edes. Han repetido en numerosas ocasiones que est\u00e1n listos y dispuestos a normalizar sus relaciones.<\/p>\n\n\n\n<p>Al mismo tiempo, los saud\u00edes no est\u00e1n dispuestos a avanzar sin que se produzca una evoluci\u00f3n en la cuesti\u00f3n palestino-israel\u00ed. Como MBS repite constantemente a aquellos con quienes discute estas cuestiones: \u00abEn Arabia Saudita hay millones de ciudadanos que no me perdonar\u00e1n que ignore las necesidades de los palestinos\u00bb.<\/p>\n\n\n\n<p>Por lo tanto, la posici\u00f3n de Arabia Saudita es un factor importante que influir\u00e1 en los acontecimientos que puedan producirse.<\/p>\n\n\n\n<p>Creo que los saud\u00edes han presentado opciones positivas para Israel, mostrando las ventajas potenciales de dar un paso adelante hacia los palestinos y garantizando que ello conducir\u00e1 a la normalizaci\u00f3n con Arabia Saudita. Esto situar\u00eda al Estado de Israel en una situaci\u00f3n totalmente diferente a la que ha conocido hasta ahora.<\/p>\n\n\n\n<p>Los saud\u00edes est\u00e1n aportando su contribuci\u00f3n y debemos aprovechar el potencial que esto representa.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfQu\u00e9 papel desempe\u00f1a Qatar actualmente en las negociaciones para la liberaci\u00f3n de los rehenes y un posible alto al fuego con Ham\u00e1s? \u00bfEn qu\u00e9 punto se encuentran estas negociaciones y qu\u00e9 es lo que, en su opini\u00f3n, impide llegar a un acuerdo de alto al fuego?<\/h3>\n\n\n\n<p>No conozco todos los detalles del proceso de negociaci\u00f3n que se est\u00e1 llevando a cabo actualmente en Qatar, ni todas las din\u00e1micas en juego. Pero, en general, el n\u00facleo del desacuerdo es bastante sencillo.<\/p>\n\n\n\n<p>Ham\u00e1s afirma \u2014y yo tiendo a creerlo\u2014 que est\u00e1 dispuesto a liberar a todos los rehenes si Israel acepta poner fin a la guerra y que este fin sea supervisado y garantizado de forma cre\u00edble por Estados Unidos.<\/p>\n\n\n\n<p>Sin embargo, Israel no quiere poner fin a la guerra. Por lo tanto, en este momento no existe una base real para un acuerdo.<\/p>\n\n\n\n<p>No pretendo en absoluto minimizar la naturaleza de Ham\u00e1s. Son asesinos, extremistas, una organizaci\u00f3n absolutamente intolerable. De eso no tengo ninguna duda. Pero no son est\u00fapidos. Y no creo que vayan a renunciar a su \u00fanica carta en la negociaci\u00f3n \u2014los rehenes\u2014 sin obtener a cambio lo que consideran esencial: el fin de las hostilidades.<\/p>\n\n\n\n<p>La cuesti\u00f3n ahora es si Israel est\u00e1 dispuesto a poner fin a la guerra para conseguir la liberaci\u00f3n de todos los rehenes.<\/p>\n\n\n\n<p>Hasta la fecha, la opini\u00f3n p\u00fablica israel\u00ed parece mayoritariamente favorable a un alto al fuego inmediato, sean cuales sean las circunstancias, si ello permite el regreso de los rehenes.<\/p>\n\n\n\n<p>Pero una parte significativa del gobierno israel\u00ed se opone expl\u00edcitamente al fin de la guerra, incluso si ello implica la muerte de algunos rehenes. Est\u00e1n dispuestos a sacrificar a los rehenes antes que poner fin a la guerra.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfDeber\u00eda Israel participar financieramente en la reconstrucci\u00f3n de Gaza?<\/h3>\n\n\n\n<p>Esta reconstrucci\u00f3n deber\u00e1 correr a cargo, en primer lugar, de la comunidad internacional.<\/p>\n\n\n\n<p>Es cierto que Israel puede ser considerado responsable de la destrucci\u00f3n. Pero el Estado israel\u00ed tambi\u00e9n podr\u00eda formular reclamaciones por la destrucci\u00f3n de colonias y ciudades israel\u00edes dentro de su territorio, perpetrada por Ham\u00e1s al comienzo de la guerra, el 7 de octubre de 2023.<\/p>\n\n\n\n<p>Por lo tanto, me parece contraproducente centrarse en obtener la participaci\u00f3n financiera de Israel en la reconstrucci\u00f3n. Hay suficientes pa\u00edses \u00e1rabes que disponen de los medios necesarios y que, dadas las circunstancias, estar\u00edan dispuestos a hacerse cargo de las necesidades de reconstrucci\u00f3n en Gaza.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Usted es un firme partidario de la soluci\u00f3n de dos Estados. Sin embargo, con cada nueva crisis, esta perspectiva parece alejarse. \u00bfC\u00f3mo convencer de que sigue siendo una opci\u00f3n cre\u00edble, realista y concretamente viable?<\/h3>\n\n\n\n<p>En el fondo, solo hay dos opciones.<\/p>\n\n\n\n<p>La primera es seguir luchando indefinidamente. Es lo que llevamos haciendo israel\u00edes y palestinos desde hace unos 77 a\u00f1os. Podemos continuar por este camino durante mucho tiempo. Esto conducir\u00e1 a m\u00e1s derramamiento de sangre, a m\u00e1s israel\u00edes y palestinos muertos, sin que ning\u00fan cambio radical abra un nuevo horizonte.<\/p>\n\n\n\n<p>La otra opci\u00f3n es intentar alcanzar la paz. Sin embargo, en mi opini\u00f3n, solo hay un camino hacia una paz duradera: la soluci\u00f3n de dos Estados.<\/p>\n\n\n\n<p>Aunque pueda llevar tiempo, tarde o temprano todos acabar\u00e1n reconociendo esta realidad ineludible: no hay una alternativa cre\u00edble a la soluci\u00f3n de dos Estados.<\/p>\n\n\n\n<p>Est\u00e1 claro que el actual gobierno se basa en la oposici\u00f3n a esta soluci\u00f3n pol\u00edtica. No se opone solo a alg\u00fan aspecto concreto, sino que se opone ferozmente a su esencia misma.<\/p>\n\n\n\n<p>Por eso, para avanzar, Netanyahu debe ser destituido.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abBibi, ya basta. Tienes que pasar la p\u00e1gina\u00bb.<\/p>\n<p>Un mes despu\u00e9s de la ofensiva en Ir\u00e1n, Israel se encuentra en un punto de inflexi\u00f3n.<\/p>\n<p>Para Ehud Olmert, hay que pensar el despu\u00e9s de Netanyahu. <\/p>\n<p>Nos reunimos con \u00e9l.<\/p>\n","protected":false},"author":17959,"featured_media":73553,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-interviews.php","format":"standard","meta":{"_acf_changed":true,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":15,"footnotes":""},"categories":[6],"tags":[],"staff":[93,122],"editorial_format":[1473],"serie":[],"audience":[],"geo":[173],"class_list":["post-73602","post","type-post","status-publish","format-standard","hentry","category-politica","staff-florian-louis","staff-matheo-malik","editorial_format-entrevistas","geo-mediterraneo"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":73553,"excerpt":"\u00abBibi, ya basta. Tienes que pasar la p\u00e1gina\u00bb.\r\n\r\nUn mes despu\u00e9s de la ofensiva en Ir\u00e1n, Israel se encuentra en un punto de inflexi\u00f3n.\r\n\r\nPara Ehud Olmert, hay que pensar el despu\u00e9s de Netanyahu. \r\n\r\nNos reunimos con \u00e9l.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00abNetanyahu no quiere poner fin a la guerra\u00bb, una conversaci\u00f3n con Ehud Olmert, ex primer ministro de Israel - El Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/es\/2025\/07\/25\/netanyahu-no-quiere-poner-fin-a-la-guerra-una-conversacion-con-ehud-olmert-ex-primer-ministro-de-israel\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00abNetanyahu no quiere poner fin a la guerra\u00bb, una conversaci\u00f3n con Ehud Olmert, ex primer ministro de Israel - El Grand Continent\" \/>\n<meta property=\"og:description\" content=\"\u00abBibi, ya basta. Tienes que pasar la p\u00e1gina\u00bb.  Un mes despu\u00e9s de la ofensiva en Ir\u00e1n, Israel se encuentra en un punto de inflexi\u00f3n.  Para Ehud Olmert, hay que pensar el despu\u00e9s de Netanyahu.   Nos reunimos con \u00e9l.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/es\/2025\/07\/25\/netanyahu-no-quiere-poner-fin-a-la-guerra-una-conversacion-con-ehud-olmert-ex-primer-ministro-de-israel\/\" \/>\n<meta property=\"og:site_name\" content=\"El Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-25T09:05:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-25T09:05:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/07\/gc-elolmert-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"anainesfernandez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/07\/gc-elolmert-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"anainesfernandez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"15 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/07\/25\/netanyahu-no-quiere-poner-fin-a-la-guerra-una-conversacion-con-ehud-olmert-ex-primer-ministro-de-israel\/\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/2025\/07\/25\/netanyahu-no-quiere-poner-fin-a-la-guerra-una-conversacion-con-ehud-olmert-ex-primer-ministro-de-israel\/\",\"name\":\"\u00abNetanyahu no quiere poner fin a la guerra\u00bb, una conversaci\u00f3n con Ehud Olmert, ex primer ministro de Israel - El Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/07\/25\/netanyahu-no-quiere-poner-fin-a-la-guerra-una-conversacion-con-ehud-olmert-ex-primer-ministro-de-israel\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/07\/25\/netanyahu-no-quiere-poner-fin-a-la-guerra-una-conversacion-con-ehud-olmert-ex-primer-ministro-de-israel\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/07\/SIPA_ap22428855_000004-scaled.jpg\",\"datePublished\":\"2025-07-25T09:05:38+00:00\",\"dateModified\":\"2025-07-25T09:05:42+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/570398dd8da37ba5d66dec6d242bd33c\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/07\/25\/netanyahu-no-quiere-poner-fin-a-la-guerra-una-conversacion-con-ehud-olmert-ex-primer-ministro-de-israel\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/es\/2025\/07\/25\/netanyahu-no-quiere-poner-fin-a-la-guerra-una-conversacion-con-ehud-olmert-ex-primer-ministro-de-israel\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/07\/25\/netanyahu-no-quiere-poner-fin-a-la-guerra-una-conversacion-con-ehud-olmert-ex-primer-ministro-de-israel\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/07\/SIPA_ap22428855_000004-scaled.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/07\/SIPA_ap22428855_000004-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Ehud Olmert Grand Continent \u00a9 AP Photo\/Seth Wenig\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/07\/25\/netanyahu-no-quiere-poner-fin-a-la-guerra-una-conversacion-con-ehud-olmert-ex-primer-ministro-de-israel\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/legrandcontinent.eu\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00abNetanyahu no quiere poner fin a la guerra\u00bb, una conversaci\u00f3n con Ehud Olmert, ex primer ministro de Israel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/\",\"name\":\"El Grand Continent\",\"description\":\"La escala pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/570398dd8da37ba5d66dec6d242bd33c\",\"name\":\"anainesfernandez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/fe25c21e6213f69a683147fabda32586?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/fe25c21e6213f69a683147fabda32586?s=96&d=mm&r=g\",\"caption\":\"anainesfernandez\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00abNetanyahu no quiere poner fin a la guerra\u00bb, una conversaci\u00f3n con Ehud Olmert, ex primer ministro de Israel - El Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/es\/2025\/07\/25\/netanyahu-no-quiere-poner-fin-a-la-guerra-una-conversacion-con-ehud-olmert-ex-primer-ministro-de-israel\/","og_locale":"es_ES","og_type":"article","og_title":"\u00abNetanyahu no quiere poner fin a la guerra\u00bb, una conversaci\u00f3n con Ehud Olmert, ex primer ministro de Israel - El Grand Continent","og_description":"\u00abBibi, ya basta. Tienes que pasar la p\u00e1gina\u00bb.  Un mes despu\u00e9s de la ofensiva en Ir\u00e1n, Israel se encuentra en un punto de inflexi\u00f3n.  Para Ehud Olmert, hay que pensar el despu\u00e9s de Netanyahu.   Nos reunimos con \u00e9l.","og_url":"https:\/\/legrandcontinent.eu\/es\/2025\/07\/25\/netanyahu-no-quiere-poner-fin-a-la-guerra-una-conversacion-con-ehud-olmert-ex-primer-ministro-de-israel\/","og_site_name":"El Grand Continent","article_published_time":"2025-07-25T09:05:38+00:00","article_modified_time":"2025-07-25T09:05:42+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/07\/gc-elolmert-scaled.jpg","type":"image\/jpeg"}],"author":"anainesfernandez","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/07\/gc-elolmert-scaled.jpg","twitter_misc":{"Escrito por":"anainesfernandez","Tiempo de lectura":"15 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/es\/2025\/07\/25\/netanyahu-no-quiere-poner-fin-a-la-guerra-una-conversacion-con-ehud-olmert-ex-primer-ministro-de-israel\/","url":"https:\/\/legrandcontinent.eu\/es\/2025\/07\/25\/netanyahu-no-quiere-poner-fin-a-la-guerra-una-conversacion-con-ehud-olmert-ex-primer-ministro-de-israel\/","name":"\u00abNetanyahu no quiere poner fin a la guerra\u00bb, una conversaci\u00f3n con Ehud Olmert, ex primer ministro de Israel - El Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/es\/2025\/07\/25\/netanyahu-no-quiere-poner-fin-a-la-guerra-una-conversacion-con-ehud-olmert-ex-primer-ministro-de-israel\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/es\/2025\/07\/25\/netanyahu-no-quiere-poner-fin-a-la-guerra-una-conversacion-con-ehud-olmert-ex-primer-ministro-de-israel\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/07\/SIPA_ap22428855_000004-scaled.jpg","datePublished":"2025-07-25T09:05:38+00:00","dateModified":"2025-07-25T09:05:42+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/570398dd8da37ba5d66dec6d242bd33c"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/es\/2025\/07\/25\/netanyahu-no-quiere-poner-fin-a-la-guerra-una-conversacion-con-ehud-olmert-ex-primer-ministro-de-israel\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/es\/2025\/07\/25\/netanyahu-no-quiere-poner-fin-a-la-guerra-una-conversacion-con-ehud-olmert-ex-primer-ministro-de-israel\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/2025\/07\/25\/netanyahu-no-quiere-poner-fin-a-la-guerra-una-conversacion-con-ehud-olmert-ex-primer-ministro-de-israel\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/07\/SIPA_ap22428855_000004-scaled.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/07\/SIPA_ap22428855_000004-scaled.jpg","width":2560,"height":1707,"caption":"Ehud Olmert Grand Continent \u00a9 AP Photo\/Seth Wenig"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/es\/2025\/07\/25\/netanyahu-no-quiere-poner-fin-a-la-guerra-una-conversacion-con-ehud-olmert-ex-primer-ministro-de-israel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legrandcontinent.eu\/es\/"},{"@type":"ListItem","position":2,"name":"\u00abNetanyahu no quiere poner fin a la guerra\u00bb, una conversaci\u00f3n con Ehud Olmert, ex primer ministro de Israel"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/es\/#website","url":"https:\/\/legrandcontinent.eu\/es\/","name":"El Grand Continent","description":"La escala pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/570398dd8da37ba5d66dec6d242bd33c","name":"anainesfernandez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/fe25c21e6213f69a683147fabda32586?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fe25c21e6213f69a683147fabda32586?s=96&d=mm&r=g","caption":"anainesfernandez"}}]}},"lgc_categories":[{"id":6,"name":"Pol\u00edtica","slug":"politica"}],"lgc_author":{"id":93,"name":"Florian Louis","slug":"florian-louis","description":null,"first_name":null,"last_name":null,"picture":null},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/07\/SIPA_ap22428855_000004-scaled.jpg","width":2560,"height":1707,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/07\/SIPA_ap22428855_000004-scaled.jpg","width":2560,"height":1707,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/73602","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/users\/17959"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/comments?post=73602"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/73602\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media\/73553"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media?parent=73602"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/categories?post=73602"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/tags?post=73602"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/staff?post=73602"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/editorial_format?post=73602"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/serie?post=73602"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/audience?post=73602"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/geo?post=73602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}