{"id":69859,"date":"2025-06-10T12:00:27","date_gmt":"2025-06-10T10:00:27","guid":{"rendered":"https:\/\/legrandcontinent.eu\/es\/?p=69859"},"modified":"2025-06-10T12:00:30","modified_gmt":"2025-06-10T10:00:30","slug":"la-ia-no-se-estrella-contra-un-muro-pero-los-llm-si-gary-marcus-sobre-la-ultima-investigacion-de-apple","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/es\/2025\/06\/10\/la-ia-no-se-estrella-contra-un-muro-pero-los-llm-si-gary-marcus-sobre-la-ultima-investigacion-de-apple\/","title":{"rendered":"\u00abLa IA no se estrella contra un muro. Pero los LLM s\u00ed\u00bb: Gary Marcus sobre la \u00faltima investigaci\u00f3n de Apple"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Un art\u00edculo publicado este fin de semana por Apple propone una cuantificaci\u00f3n de las capacidades de razonamiento de los LLM, que parecen colapsar m\u00e1s all\u00e1 de un cierto nivel de complejidad de las tareas. Varios observadores hablan de un duro golpe, un muro de complejidad con el que se enfrenta la actual generaci\u00f3n de grandes modelos de lenguaje (LLM).&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-69859' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2025\/06\/10\/la-ia-no-se-estrella-contra-un-muro-pero-los-llm-si-gary-marcus-sobre-la-ultima-investigacion-de-apple\/#easy-footnote-bottom-1-69859' title='Los &lt;em&gt;Large Language Models&lt;\/em&gt; son modelos de inteligencia artificial entrenados con grandes corpus de textos para generar, completar o analizar el lenguaje humano, bas\u00e1ndose en correlaciones estad\u00edsticas entre las palabras.'><sup>1<\/sup><\/a><\/span><\/span> \u00bfQu\u00e9 opina?<\/h3>\n\n\n\n<p>No se trata de un simple golpe duro, sino de un golpe de gracia, sobre todo porque este art\u00edculo no es un caso aislado. Es la continuaci\u00f3n de otra investigaci\u00f3n publicada el a\u00f1o pasado por varios de los mismos autores, que ya demostraba que es imposible construir agentes fiables sin un razonamiento formal y abstracto suficientemente desarrollado.&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-69859' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2025\/06\/10\/la-ia-no-se-estrella-contra-un-muro-pero-los-llm-si-gary-marcus-sobre-la-ultima-investigacion-de-apple\/#easy-footnote-bottom-2-69859' title='Mirzadeh, Iman, Oncel Tuzel, Keivan Alizadeh, Samy Bengio, Hooman Shahrokhi y Mehrdad Farajtabar. GSM-Symbolic: Understanding the Limitations of Mathematical Reasoning in Large Language Models. Apple, s. f.'><sup>2<\/sup><\/a><\/span><\/span><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfPodr\u00eda resumir brevemente el argumento del art\u00edculo?<\/h3>\n\n\n\n<p>Apple ha probado las capacidades de \u00abrazonamiento\u00bb de las inteligencias artificiales actuales, como ChatGPT, Claude o DeepSeek. Si bien todos estos modelos parecen inteligentes a primera vista, fracasan por completo en cuanto aumenta la complejidad. La fuerza global del argumento es innegable: aunque hay una debilidad interesante en el nuevo razonamiento, la conclusi\u00f3n es inequ\u00edvoca.<\/p>\n\n\n\n<p>Ninguno de los modelos basados en LLM muestra un razonamiento verdadero. Se trata simplemente de sistemas de reconocimiento de patrones extremadamente costosos que se derrumban en cuanto se enfrentan a situaciones fuera de su \u00e1mbito de entrenamiento.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfSe trata de un callej\u00f3n sin salida estructural de los LLM para determinadas aplicaciones?<\/h3>\n\n\n\n<p>De hecho, todas las investigaciones serias demuestran ahora que los grandes modelos de lenguaje no razonan de la misma manera que los humanos. Pueden \u00abpensar m\u00e1s\u00bb, pero solo hasta cierto punto.<\/p>\n\n\n\n<p>M\u00e1s all\u00e1 de un umbral determinado, se rinden r\u00e1pidamente, incluso si a\u00fan disponen de recursos computacionales m\u00e1s que suficientes.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Ninguno de los modelos basados en MLL muestra un razonamiento verdadero.<\/p><cite>Gary Marcus<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Incluso cuando se les proporciona el algoritmo exacto a seguir \u2014las reglas para resolver una tarea compleja\u2014, estos modelos tienden a ejecutarlo muy mal. Esto pone de relieve una distinci\u00f3n esencial: ejecutar no significa comprender.<\/p>\n\n\n\n<p>El problema no radica en la falta de creatividad, sino en un fallo l\u00f3gico fundamental. Los modelos tienden a \u00abpensar demasiado\u00bb en problemas sencillos y a probar respuestas err\u00f3neas incluso despu\u00e9s de haber encontrado la correcta. Y ante problemas m\u00e1s dif\u00edciles, piensan menos. El resultado es un desperdicio de recursos inform\u00e1ticos por un lado y un abandono prematuro por otro.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfC\u00f3mo encaja, en su opini\u00f3n, este nuevo estudio \u2014que prolonga el an\u00e1lisis cr\u00edtico del paradigma actual<a href=\"https:\/\/legrandcontinent.eu\/es\/2023\/04\/28\/limites-de-un-sistema-desbloquear-la-ia\/\"> que ya publicamos en 2023 en nuestras p\u00e1ginas<\/a>\u2014 en el debate sobre la capacidad de los LLM para generalizar a situaciones radicalmente nuevas?<\/h3>\n\n\n\n<p>Por un lado, esta investigaci\u00f3n hace eco y ampl\u00eda el argumento sobre la distribuci\u00f3n del entrenamiento que vengo desarrollando desde 1998: las redes neuronales, en diversas formas, pueden generalizar dentro de la distribuci\u00f3n de datos con la que han sido entrenadas, pero sus generalizaciones tienden a colapsar fuera de esa distribuci\u00f3n.<\/p>\n\n\n\n<p>Este era el n\u00facleo de un art\u00edculo que publiqu\u00e9 en 1998, en el que criticaba los perceptrones multicapa (<em>multilayer perceptrons<\/em>), los antecesores de los modelos de lenguaje actuales, mostrando sus fallos fuera de la distribuci\u00f3n en tareas sencillas de c\u00e1lculo y predicci\u00f3n de frases.&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-69859' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2025\/06\/10\/la-ia-no-se-estrella-contra-un-muro-pero-los-llm-si-gary-marcus-sobre-la-ultima-investigacion-de-apple\/#easy-footnote-bottom-3-69859' title='Gary F. Marcus, \u00abRethinking Eliminative Connectionism\u00bb, &lt;a href=&quot;https:\/\/www.sciencedirect.com\/science\/article\/pii\/S0010028598906946&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;Cognitive Psychology&lt;\/a&gt;, Volumen 37, no. 3, 1998, pp. 243-282, ISSN 0010-0285.'><sup>3<\/sup><\/a><\/span><\/span><\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Existe una distinci\u00f3n esencial en la IA generativa: ejecutar no significa comprender.<\/p><cite>Gary Marcus<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Este fue tambi\u00e9n el eje central de mi primer libro, <em>The Algebraic Mind<\/em> (2001),&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-4-69859' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2025\/06\/10\/la-ia-no-se-estrella-contra-un-muro-pero-los-llm-si-gary-marcus-sobre-la-ultima-investigacion-de-apple\/#easy-footnote-bottom-4-69859' title='Gary F. Marcus, &lt;em&gt;The Algebraic Mind Integrating Connectionism and Cognitive Science&lt;\/em&gt;, MIT Press, 2001.'><sup>4<\/sup><\/a><\/span><\/span> que ampliaba esta cr\u00edtica, as\u00ed como de mi primer art\u00edculo en <em>Science<\/em> (1999),&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-5-69859' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2025\/06\/10\/la-ia-no-se-estrella-contra-un-muro-pero-los-llm-si-gary-marcus-sobre-la-ultima-investigacion-de-apple\/#easy-footnote-bottom-5-69859' title='Marcus, Gary F., S. Vijayan, S. Bandi Rao y Peter M. Vishton. \u00abRule Learning by Seven-Month-Old Infants.\u00bb &lt;em&gt;Science&lt;\/em&gt; 283, no. 5398 (1999): 77\u201380.'><sup>5<\/sup><\/a><\/span><\/span> donde demostr\u00e9, mediante un experimento, que los beb\u00e9s de siete meses pod\u00edan extrapolar de una manera que las redes neuronales de la \u00e9poca eran incapaces de replicar. Esta fue tambi\u00e9n la motivaci\u00f3n principal de <em>Deep Learning: Critical Appraisal<\/em> (2018)&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-6-69859' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2025\/06\/10\/la-ia-no-se-estrella-contra-un-muro-pero-los-llm-si-gary-marcus-sobre-la-ultima-investigacion-de-apple\/#easy-footnote-bottom-6-69859' title='Gary Marcus, &lt;a href=&quot;https:\/\/www.researchgate.net\/publication\/322220859_Deep_Learning_A_Critical_Appraisal&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;&lt;em&gt;Deep Learning: Critical Appraisal&lt;\/em&gt;&lt;\/a&gt;, 2018&lt;em&gt;.&lt;\/em&gt;'><sup>6<\/sup><\/a><\/span><\/span> y, posteriormente, de <em>Deep Learning is Hitting a Wall<\/em> (2022).&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-7-69859' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2025\/06\/10\/la-ia-no-se-estrella-contra-un-muro-pero-los-llm-si-gary-marcus-sobre-la-ultima-investigacion-de-apple\/#easy-footnote-bottom-7-69859' title='Gary Marcus, \u00abDeep Learning Is Hitting a Wall. What would it take for artificial intelligence to make real progress?\u00bb, &lt;a href=&quot;https:\/\/nautil.us\/deep-learning-is-hitting-a-wall-238440\/&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;Nautilus&lt;\/a&gt;, 10 mars 2022.'><sup>7<\/sup><\/a><\/span><\/span> El a\u00f1o pasado identifiqu\u00e9 esta limitaci\u00f3n como la debilidad m\u00e1s importante \u2014y la m\u00e1s importante de comprender\u2014 de los LLM.<\/p>\n\n\n\n<p>As\u00ed que llevo bastante tiempo trabajando en este tema&#8230;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>El art\u00edculo tambi\u00e9n se basa en el trabajo de<\/strong><a href=\"https:\/\/cotopaxi.eas.asu.edu\/\"> <strong>Subbarao Kambhampati<\/strong><\/a><strong>, investigador inform\u00e1tico de la Universidad Estatal de Arizona.<\/strong><\/h3>\n\n\n\n<p>S\u00ed, y quiero subrayarlo. Esta investigaci\u00f3n no solo hace eco de los argumentos que Rao lleva desarrollando desde hace varios a\u00f1os, sino que los refuerza.<\/p>\n\n\n\n<p>Se trata de las cr\u00edticas a los modelos denominados de \u00abrazonamiento\u00bb y las famosas \u00abcadenas de pensamiento\u00bb (<em>CoT<\/em>) que producen, que parecen mucho menos s\u00f3lidas de lo que se afirma.<\/p>\n\n\n\n<p>Para quienes no est\u00e9n familiarizados con el concepto, una \u00abcadena de pensamiento\u00bb es, a grandes rasgos, lo que el sistema pretende haber \u00abrazonado\u00bb para llegar a una respuesta, en los casos en que realiza varios pasos de reflexi\u00f3n. Los \u00abmodelos de razonamiento\u00bb, por su parte, se refieren a la nueva generaci\u00f3n de intentos de eludir las limitaciones estructurales de los LLM, oblig\u00e1ndolos a \u00abrazonar\u00bb en el tiempo, mediante una t\u00e9cnica denominada <em>inference-time compute<\/em> (c\u00e1lculo en el momento de la inferencia).<\/p>\n\n\n\n<p>Rao nunca ha estado convencido de este argumento.<\/p>\n\n\n\n<p>Escribi\u00f3 una serie de brillantes art\u00edculos en los que demostraba, entre otras cosas, que las cadenas de pensamiento generadas por los LLM no siempre se corresponden con lo que estos modelos hacen realmente. Recientemente, por ejemplo, observ\u00f3 que tendemos a antropomorfizar en exceso los rastros de razonamiento de los LLM, hablando de \u00abpensamiento\u00bb cuando este t\u00e9rmino no parece adecuado.&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-8-69859' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2025\/06\/10\/la-ia-no-se-estrella-contra-un-muro-pero-los-llm-si-gary-marcus-sobre-la-ultima-investigacion-de-apple\/#easy-footnote-bottom-8-69859' title='Subbarao Kambhampati et al. &lt;em&gt;Stop Anthropomorphizing Intermediate Tokens as Reasoning\/Thinking Traces!&lt;\/em&gt; School of Computing &amp;amp; AI, &lt;a href=&quot;https:\/\/arxiv.org\/pdf\/2504.09762&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;Arizona State University&lt;\/a&gt;.'><sup>8<\/sup><\/a><\/span><\/span><\/p>\n\n\n\n<p>Otro de sus art\u00edculos recientes muestra que, incluso cuando las cadenas de razonamiento parecen correctas, las respuestas finales no siempre lo son.&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-9-69859' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2025\/06\/10\/la-ia-no-se-estrella-contra-un-muro-pero-los-llm-si-gary-marcus-sobre-la-ultima-investigacion-de-apple\/#easy-footnote-bottom-9-69859' title='Bhambri Siddhant, Upasana Biswas y Subbarao Kambhampati, &lt;a href=&quot;https:\/\/arxiv.org\/pdf\/2505.13792&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;Interpretable Traces, Unexpected Outcomes: Investigating the Disconnect in Trace-Based Knowledge Distillation&lt;\/a&gt;.'><sup>9<\/sup><\/a><\/span><\/span><\/p>\n\n\n\n<p>De hecho, Rao fue sin duda el primero en demostrar que uno de estos \u00abmodelos de razonamiento\u00bb \u2014en este caso, o1\u2014 adolec\u00eda del tipo de problema que documenta hoy el informe de Apple.&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-10-69859' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2025\/06\/10\/la-ia-no-se-estrella-contra-un-muro-pero-los-llm-si-gary-marcus-sobre-la-ultima-investigacion-de-apple\/#easy-footnote-bottom-10-69859' title='Valmeekam Karthik, Kaya Stechly, Atharva Gundawar y Subbarao Kambhampati. \u00abA Systematic Evaluation of the Planning and Scheduling Abilities of the Reasoning Model o1.\u00bb &lt;em&gt;Transactions on Machine Learning Research&lt;\/em&gt;, abril de 2025.'><sup>10<\/sup><\/a><\/span><\/span> Recomiendo a todo el mundo que lea su trabajo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">El documento de Apple retoma la cr\u00edtica de Rao y la suya, centr\u00e1ndose en particular en un problema cl\u00e1sico bastante sencillo: la torre de Hanoi. \u00bfDe qu\u00e9 se trata?<\/h3>\n\n\n\n<p>Se trata de un juego cl\u00e1sico compuesto por tres varillas y varios discos de diferentes tama\u00f1os.&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-11-69859' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2025\/06\/10\/la-ia-no-se-estrella-contra-un-muro-pero-los-llm-si-gary-marcus-sobre-la-ultima-investigacion-de-apple\/#easy-footnote-bottom-11-69859' title='Juega a la Torre de Hanoi &lt;a href=&quot;https:\/\/www.mathsisfun.com\/games\/towerofhanoi.html&quot;&gt;aqu\u00ed&lt;\/a&gt;.'><sup>11<\/sup><\/a><\/span><\/span> El objetivo es mover todos los discos de la varilla izquierda a la derecha, respetando una regla esencial: no se puede colocar un disco m\u00e1s grande sobre otro m\u00e1s peque\u00f1o.<\/p>\n\n\n\n<p>Si a\u00fan no conoce este juego, solo le llevar\u00e1 un momento entender c\u00f3mo funciona.<\/p>\n\n\n\n<p>Con un poco de pr\u00e1ctica, un ni\u00f1o inteligente y paciente de siete a\u00f1os puede lograrlo, y para una computadora es un ejercicio que no presenta ninguna dificultad. Cualquier estudiante de primer a\u00f1o de inform\u00e1tica deber\u00eda ser capaz de crear un programa que resolviera sistem\u00e1ticamente el juego.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>La probabilidad de que modelos como Claude u o3 alcancen alg\u00fan d\u00eda la inteligencia artificial general (AGI) parece, en el mejor de los casos, muy remota.<\/p><cite>Gary Marcus<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Sin embargo, los modelos m\u00e1s recientes, como Claude, ya tienen dificultades para resolver el problema con 7 discos, alcanzando menos del 80 % de precisi\u00f3n, y son pr\u00e1cticamente incapaces de hacerlo con 8 discos.<\/p>\n\n\n\n<p>Apple ha constatado que ni siquiera el muy apreciado o3-min (high) lo hace mejor y ha observado resultados similares en otras tareas.<\/p>\n\n\n\n<p>Es realmente vergonzoso que los LLM sigan sin poder resolver de forma fiable un problema tan trivial como la torre de Hanoi. \u00a1Y eso que hay numerosas bibliotecas de c\u00f3digo fuente disponibles gratuitamente en internet!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfQu\u00e9 dice esto de la inteligencia de los LLM?<\/h3>\n\n\n\n<p>Si no se puede utilizar un sistema de IA de miles de millones de d\u00f3lares para resolver un problema que Herbert Simon, uno de los verdaderos \u00abpadres fundadores\u00bb de la IA\u2014 resolvi\u00f3 en 1957 y que los estudiantes de primer a\u00f1o de inteligencia artificial resuelven sin problemas, entonces la probabilidad de que modelos como Claude u o3 alcancen alg\u00fan d\u00eda la inteligencia artificial general (AGI)&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-12-69859' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2025\/06\/10\/la-ia-no-se-estrella-contra-un-muro-pero-los-llm-si-gary-marcus-sobre-la-ultima-investigacion-de-apple\/#easy-footnote-bottom-12-69859' title='La AGI (Inteligencia Artificial General) se refiere a una forma de inteligencia artificial capaz de comprender, aprender y realizar cualquier tarea cognitiva que un ser humano pueda realizar, con un nivel de rendimiento igual o superior.'><sup>12<\/sup><\/a><\/span><\/span> parece, en el mejor de los casos, muy remota.<\/p>\n\n\n\n<p>Uno de los coautores de la investigaci\u00f3n, Iman Mirzadeh, me llam\u00f3 la atenci\u00f3n sobre la secci\u00f3n 4.4 del art\u00edculo<\/p>\n\n\n\n<p>Los investigadores hab\u00edan proporcionado el algoritmo de soluci\u00f3n al modelo, que solo ten\u00eda que seguir los pasos para resolver el problema. Sin embargo, incluso en este contexto, su rendimiento no hab\u00eda mejorado. Mirzadeh coment\u00f3 esta paradoja de la siguiente manera: \u00abPor lo tanto, nuestro argumento no es: \u2018Los seres humanos no tienen l\u00edmites, pero los modelos de razonamiento ling\u00fc\u00edstico (LRM) s\u00ed los tienen, por lo que no son inteligentes.\u2019 Sino m\u00e1s bien: \u2018lo que observamos en su razonamiento no se parece ni a un proceso l\u00f3gico ni a una forma de inteligencia\u2019\u00bb.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>El objetivo de la AGI no deber\u00eda ser replicar perfectamente al ser humano, sino combinar lo mejor de ambos mundos: la adaptabilidad humana con la fuerza bruta y la fiabilidad computacional.<\/p><cite>Gary Marcus<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Usted dice haber observado un punto cr\u00edtico en el art\u00edculo, \u00bfcu\u00e1l es?<\/h3>\n\n\n\n<p>Se trata de una debilidad que ha sido bien expuesta por una cuenta an\u00f3nima en X, que, en general, no es una fuente conocida por sus buenos argumentos&#8230;<\/p>\n\n\n\n<p>Es la siguiente: los seres humanos comunes tambi\u00e9n tienen una serie de limitaciones, similares a las que ha puesto de manifiesto el equipo de Apple para los LLM. Muchas personas, aunque no todas, se equivocan al intentar resolver versiones de la torre de Hanoi con ocho discos.<\/p>\n\n\n\n<p>Pero precisamente tenemos una respuesta a esta deficiencia. Inventamos las computadoras, y antes las calculadoras, precisamente para resolver de forma fiable problemas complejos, tediosos o de mayor o menor envergadura, como la torre de Hanoi.<\/p>\n\n\n\n<p>El objetivo de la AGI no deber\u00eda ser replicar perfectamente a los humanos, sino \u2014como yo mismo he dicho a menudo\u2014 combinar lo mejor de ambos mundos: la adaptabilidad humana con la fuerza bruta y la fiabilidad computacional.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfCree que con los LLM corremos el riesgo de combinar lo peor de ambos mundos?<\/h3>\n\n\n\n<p>La visi\u00f3n que siempre he tenido de la AGI es la de un sistema que combina las fuerzas humanas y las de la m\u00e1quina, al tiempo que supera las debilidades humanas. No me interesa una AGI incapaz de hacer una suma correcta. Y desde luego no querr\u00eda confiar la infraestructura mundial o el futuro de la humanidad a un sistema as\u00ed.<\/p>\n\n\n\n<p>No queremos una AGI que se olvide de sumar una unidad en una operaci\u00f3n elemental con el pretexto de que los humanos a veces cometen el mismo error. \u00a1Buena suerte en ese caso para conseguir una verdadera \u00abalineaci\u00f3n\u00bb o \u00abseguridad\u00bb sin fiabilidad!&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-13-69859' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2025\/06\/10\/la-ia-no-se-estrella-contra-un-muro-pero-los-llm-si-gary-marcus-sobre-la-ultima-investigacion-de-apple\/#easy-footnote-bottom-13-69859' title='La alineaci\u00f3n en inteligencia artificial se refiere a garantizar que un sistema de IA persiga objetivos compatibles con las intenciones, los valores y los intereses de los seres humanos que lo utilizan o implementan.'><sup>13<\/sup><\/a><\/span><\/span><\/p>\n\n\n\n<p>Por cierto, los modelos como o3 cometen errores mucho m\u00e1s a menudo debido a alucinaciones y tienen grandes dificultades para dibujar patrones fiables. Comparten algunas debilidades humanas, pero simplemente son peores en varios aspectos. Y si los humanos fallan, a menudo es por falta de memoria; los LLM, por su parte, disponen de gigabytes de memoria, por lo que no tienen excusa.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfCree que el entusiasmo por los LLM est\u00e1 desviando a la IA de su verdadero potencial cient\u00edfico, en particular, el de una alianza entre el razonamiento causal y la potencia de c\u00e1lculo?<\/h3>\n\n\n\n<p>Lo que es evidente es que no vamos a \u00abextraer el cono de luz\u00bb de la Tierra ni a \u00abresolver la f\u00edsica\u00bb, sea lo que sea lo que signifiquen estas pretenciosas declaraciones de Sam Altman, con sistemas incapaces de jugar al juego de la torre de Hanoi con ocho discos.<\/p>\n\n\n\n<p>Cuando me preguntan por qu\u00e9, al contrario de lo que se dice, me gusta la IA, y por qu\u00e9 creo que la IA \u2014pero no la IA generativa\u2014 podr\u00eda, a largo plazo, beneficiar profundamente a la humanidad, siempre cito el potencial de progreso cient\u00edfico y tecnol\u00f3gico que podr\u00edamos lograr si logr\u00e1ramos combinar las capacidades de razonamiento causal de nuestros mejores cient\u00edficos con la potencia de c\u00e1lculo bruta de las computadoras digitales modernas.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>No queremos una IA que se olvide de sumar uno en una operaci\u00f3n aritm\u00e9tica elemental con el pretexto de que los humanos a veces cometen el mismo error.<\/p><cite>Gary Marcus<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfCu\u00e1les ser\u00e1n las consecuencias de esta progresiva toma de conciencia de los l\u00edmites de la actual generaci\u00f3n de modelos?<\/h3>\n\n\n\n<p>Lo que muestra el documento de Apple, de manera fundamental \u2014independientemente de c\u00f3mo se defina la AGI\u2014, es que los LLM no son un sustituto de los buenos algoritmos convencionales bien especificados.<\/p>\n\n\n\n<p>Los LLM no saben jugar al ajedrez tan bien como los algoritmos cl\u00e1sicos, no pueden plegar prote\u00ednas tan eficazmente como algunos h\u00edbridos neurosimb\u00f3licos especializados, no gestionan las bases de datos tan bien como los motores dise\u00f1ados para ello&#8230; En el mejor de los casos, que no siempre se alcanza, pueden escribir c\u00f3digo Python, bas\u00e1ndose en bloques de c\u00f3digo simb\u00f3lico externos para compensar sus propias debilidades, pero incluso eso no es fiable.<\/p>\n\n\n\n<p>La principal consecuencia para las empresas y la sociedad que veo es la siguiente: no se puede simplemente \u00abconectar\u00bb o3 o Claude a un problema complejo y esperar que funcione de forma robusta.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfNo estamos tratando de tranquilizarnos? El uso de los LLM nunca hab\u00eda sido tan grande.<a href=\"https:\/\/legrandcontinent.eu\/es\/2025\/06\/05\/en-estados-unidos-chatgpt-se-utiliza-mas-que-wikipedia\/\"> Ahora hay m\u00e1s gente usando ChatGPT que Wikipedia<\/a>&#8230;<\/h3>\n\n\n\n<p>Como muestra el \u00faltimo art\u00edculo de Apple, los LLM pueden tener mucho \u00e9xito en una serie de pruebas sencillas, como la Torre de Hanoi con 4 discos, y dar la impresi\u00f3n de haber aprendido una soluci\u00f3n generalizable, cuando en realidad no es as\u00ed.<\/p>\n\n\n\n<p>Al menos durante la pr\u00f3xima d\u00e9cada, los LLM, con o sin \u00abrazonamiento\u00bb en el momento de la inferencia, seguir\u00e1n siendo \u00fatiles, especialmente para el c\u00f3digo, la lluvia de ideas y la redacci\u00f3n de textos. Y como me dec\u00eda recientemente Rao: \u00abEl hecho de que los LLM\/LRM no aprendan de forma fiable un \u00fanico algoritmo subyacente no es un obst\u00e1culo absoluto para su uso. Veo los LRM como sistemas que aprenden a aproximarse al funcionamiento de un algoritmo ampliando progresivamente el razonamiento hasta la inferencia\u00bb. En algunos contextos, esto es suficiente. En otros, no.<\/p>\n\n\n\n<p>Pero cualquiera que piense que los LLM representan un camino directo hacia una AGI capaz de transformar radicalmente la sociedad para el bien com\u00fan se enga\u00f1a a s\u00ed mismo.<\/p>\n\n\n\n<p>Esto no significa que las redes neuronales hayan muerto, ni que el <em>deep learning<\/em> haya llegado a su fin.<\/p>\n\n\n\n<p>Los LLM son solo una forma posible de <em>deep learning<\/em>, y tal vez otras, especialmente aquellas que colaboran mejor con representaciones simb\u00f3licas, funcionen mejor en el futuro. El tiempo lo dir\u00e1.<\/p>\n\n\n\n<p>Pero este enfoque actual tiene l\u00edmites que cada d\u00eda son m\u00e1s evidentes.<\/p>\n\n\n\n<p>La IA no se est\u00e1 estrellando contra un muro.<\/p>\n\n\n\n<p>Pero los LLM probablemente s\u00ed, o al menos est\u00e1n llegando a un punto de rendimientos decrecientes.<\/p>\n\n\n\n<p>Necesitamos nuevos enfoques y diversificar las v\u00edas que se est\u00e1n explorando activamente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un art\u00edculo publicado por Apple acaba de revolucionar la inteligencia artificial.<\/p>\n<p>Las capacidades de razonamiento de los modelos actuales pueden colapsar por completo m\u00e1s all\u00e1 de un cierto nivel de dificultad. Estos modelos parecen \u00ababandonar\u00bb el esfuerzo de razonamiento cuando la tarea se vuelve demasiado dif\u00edcil, incluso si disponen de los recursos necesarios.<\/p>\n<p>Gary Marcus sit\u00faa estas limitaciones en la prolongaci\u00f3n de sus an\u00e1lisis anteriores y expone algunas de sus causas profundas.<\/p>\n","protected":false},"author":17959,"featured_media":69846,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-interviews.php","format":"standard","meta":{"_acf_changed":true,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":12,"footnotes":""},"categories":[464],"tags":[],"staff":[1217,154],"editorial_format":[1473],"serie":[],"audience":[],"geo":[172],"class_list":["post-69859","post","type-post","status-publish","format-standard","hentry","category-poderes-de-la-ia","staff-gary-marcus","staff-victor-storchan","editorial_format-entrevistas","geo-americas"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":69846,"excerpt":"Un art\u00edculo publicado por Apple acaba de revolucionar la inteligencia artificial.\r\n\r\nLas capacidades de razonamiento de los modelos actuales pueden colapsar por completo m\u00e1s all\u00e1 de un cierto nivel de dificultad. Estos modelos parecen \u00ababandonar\u00bb el esfuerzo de razonamiento cuando la tarea se vuelve demasiado dif\u00edcil, incluso si disponen de los recursos necesarios.\r\n\r\nGary Marcus sit\u00faa estas limitaciones en la prolongaci\u00f3n de sus an\u00e1lisis anteriores y expone algunas de sus causas profundas.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00abLa IA no se estrella contra un muro. Pero los LLM s\u00ed\u00bb: Gary Marcus sobre la \u00faltima investigaci\u00f3n de Apple - El Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/es\/2025\/06\/10\/la-ia-no-se-estrella-contra-un-muro-pero-los-llm-si-gary-marcus-sobre-la-ultima-investigacion-de-apple\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00abLa IA no se estrella contra un muro. Pero los LLM s\u00ed\u00bb: Gary Marcus sobre la \u00faltima investigaci\u00f3n de Apple - El Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Un art\u00edculo publicado por Apple acaba de revolucionar la inteligencia artificial.  Las capacidades de razonamiento de los modelos actuales pueden colapsar por completo m\u00e1s all\u00e1 de un cierto nivel de dificultad. Estos modelos parecen \u00ababandonar\u00bb el esfuerzo de razonamiento cuando la tarea se vuelve demasiado dif\u00edcil, incluso si disponen de los recursos necesarios.  Gary Marcus sit\u00faa estas limitaciones en la prolongaci\u00f3n de sus an\u00e1lisis anteriores y expone algunas de sus causas profundas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/es\/2025\/06\/10\/la-ia-no-se-estrella-contra-un-muro-pero-los-llm-si-gary-marcus-sobre-la-ultima-investigacion-de-apple\/\" \/>\n<meta property=\"og:site_name\" content=\"El Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-10T10:00:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-10T10:00:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/06\/gc-elmarcus-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"anainesfernandez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/06\/gc-elmarcus-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"anainesfernandez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/06\/10\/la-ia-no-se-estrella-contra-un-muro-pero-los-llm-si-gary-marcus-sobre-la-ultima-investigacion-de-apple\/\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/2025\/06\/10\/la-ia-no-se-estrella-contra-un-muro-pero-los-llm-si-gary-marcus-sobre-la-ultima-investigacion-de-apple\/\",\"name\":\"\u00abLa IA no se estrella contra un muro. Pero los LLM s\u00ed\u00bb: Gary Marcus sobre la \u00faltima investigaci\u00f3n de Apple - El Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/06\/10\/la-ia-no-se-estrella-contra-un-muro-pero-los-llm-si-gary-marcus-sobre-la-ultima-investigacion-de-apple\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/06\/10\/la-ia-no-se-estrella-contra-un-muro-pero-los-llm-si-gary-marcus-sobre-la-ultima-investigacion-de-apple\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/06\/PSM_V26_D464_The_tower_of_hanoi.jpg\",\"datePublished\":\"2025-06-10T10:00:27+00:00\",\"dateModified\":\"2025-06-10T10:00:30+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/570398dd8da37ba5d66dec6d242bd33c\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/06\/10\/la-ia-no-se-estrella-contra-un-muro-pero-los-llm-si-gary-marcus-sobre-la-ultima-investigacion-de-apple\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/es\/2025\/06\/10\/la-ia-no-se-estrella-contra-un-muro-pero-los-llm-si-gary-marcus-sobre-la-ultima-investigacion-de-apple\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/06\/10\/la-ia-no-se-estrella-contra-un-muro-pero-los-llm-si-gary-marcus-sobre-la-ultima-investigacion-de-apple\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/06\/PSM_V26_D464_The_tower_of_hanoi.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/06\/PSM_V26_D464_The_tower_of_hanoi.jpg\",\"width\":1167,\"height\":1728,\"caption\":\"Grabado del juego de la Torre de Hanoi inventado por el matem\u00e1tico \u00c9douard Lucas.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/06\/10\/la-ia-no-se-estrella-contra-un-muro-pero-los-llm-si-gary-marcus-sobre-la-ultima-investigacion-de-apple\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/legrandcontinent.eu\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00abLa IA no se estrella contra un muro. Pero los LLM s\u00ed\u00bb: Gary Marcus sobre la \u00faltima investigaci\u00f3n de Apple\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/\",\"name\":\"El Grand Continent\",\"description\":\"La escala pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/570398dd8da37ba5d66dec6d242bd33c\",\"name\":\"anainesfernandez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/fe25c21e6213f69a683147fabda32586?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/fe25c21e6213f69a683147fabda32586?s=96&d=mm&r=g\",\"caption\":\"anainesfernandez\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00abLa IA no se estrella contra un muro. Pero los LLM s\u00ed\u00bb: Gary Marcus sobre la \u00faltima investigaci\u00f3n de Apple - El Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/es\/2025\/06\/10\/la-ia-no-se-estrella-contra-un-muro-pero-los-llm-si-gary-marcus-sobre-la-ultima-investigacion-de-apple\/","og_locale":"es_ES","og_type":"article","og_title":"\u00abLa IA no se estrella contra un muro. Pero los LLM s\u00ed\u00bb: Gary Marcus sobre la \u00faltima investigaci\u00f3n de Apple - El Grand Continent","og_description":"Un art\u00edculo publicado por Apple acaba de revolucionar la inteligencia artificial.  Las capacidades de razonamiento de los modelos actuales pueden colapsar por completo m\u00e1s all\u00e1 de un cierto nivel de dificultad. Estos modelos parecen \u00ababandonar\u00bb el esfuerzo de razonamiento cuando la tarea se vuelve demasiado dif\u00edcil, incluso si disponen de los recursos necesarios.  Gary Marcus sit\u00faa estas limitaciones en la prolongaci\u00f3n de sus an\u00e1lisis anteriores y expone algunas de sus causas profundas.","og_url":"https:\/\/legrandcontinent.eu\/es\/2025\/06\/10\/la-ia-no-se-estrella-contra-un-muro-pero-los-llm-si-gary-marcus-sobre-la-ultima-investigacion-de-apple\/","og_site_name":"El Grand Continent","article_published_time":"2025-06-10T10:00:27+00:00","article_modified_time":"2025-06-10T10:00:30+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/06\/gc-elmarcus-scaled.jpg","type":"image\/jpeg"}],"author":"anainesfernandez","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/06\/gc-elmarcus-scaled.jpg","twitter_misc":{"Escrito por":"anainesfernandez","Tiempo de lectura":"12 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/es\/2025\/06\/10\/la-ia-no-se-estrella-contra-un-muro-pero-los-llm-si-gary-marcus-sobre-la-ultima-investigacion-de-apple\/","url":"https:\/\/legrandcontinent.eu\/es\/2025\/06\/10\/la-ia-no-se-estrella-contra-un-muro-pero-los-llm-si-gary-marcus-sobre-la-ultima-investigacion-de-apple\/","name":"\u00abLa IA no se estrella contra un muro. Pero los LLM s\u00ed\u00bb: Gary Marcus sobre la \u00faltima investigaci\u00f3n de Apple - El Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/es\/2025\/06\/10\/la-ia-no-se-estrella-contra-un-muro-pero-los-llm-si-gary-marcus-sobre-la-ultima-investigacion-de-apple\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/es\/2025\/06\/10\/la-ia-no-se-estrella-contra-un-muro-pero-los-llm-si-gary-marcus-sobre-la-ultima-investigacion-de-apple\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/06\/PSM_V26_D464_The_tower_of_hanoi.jpg","datePublished":"2025-06-10T10:00:27+00:00","dateModified":"2025-06-10T10:00:30+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/570398dd8da37ba5d66dec6d242bd33c"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/es\/2025\/06\/10\/la-ia-no-se-estrella-contra-un-muro-pero-los-llm-si-gary-marcus-sobre-la-ultima-investigacion-de-apple\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/es\/2025\/06\/10\/la-ia-no-se-estrella-contra-un-muro-pero-los-llm-si-gary-marcus-sobre-la-ultima-investigacion-de-apple\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/2025\/06\/10\/la-ia-no-se-estrella-contra-un-muro-pero-los-llm-si-gary-marcus-sobre-la-ultima-investigacion-de-apple\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/06\/PSM_V26_D464_The_tower_of_hanoi.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/06\/PSM_V26_D464_The_tower_of_hanoi.jpg","width":1167,"height":1728,"caption":"Grabado del juego de la Torre de Hanoi inventado por el matem\u00e1tico \u00c9douard Lucas."},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/es\/2025\/06\/10\/la-ia-no-se-estrella-contra-un-muro-pero-los-llm-si-gary-marcus-sobre-la-ultima-investigacion-de-apple\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legrandcontinent.eu\/es\/"},{"@type":"ListItem","position":2,"name":"\u00abLa IA no se estrella contra un muro. Pero los LLM s\u00ed\u00bb: Gary Marcus sobre la \u00faltima investigaci\u00f3n de Apple"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/es\/#website","url":"https:\/\/legrandcontinent.eu\/es\/","name":"El Grand Continent","description":"La escala pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/570398dd8da37ba5d66dec6d242bd33c","name":"anainesfernandez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/fe25c21e6213f69a683147fabda32586?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fe25c21e6213f69a683147fabda32586?s=96&d=mm&r=g","caption":"anainesfernandez"}}]}},"lgc_categories":[{"id":464,"name":"Poderes de la IA","slug":"poderes-de-la-ia"}],"lgc_author":{"id":1217,"name":"Gary Marcus","slug":"gary-marcus","description":null,"first_name":null,"last_name":null,"picture":null},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/06\/PSM_V26_D464_The_tower_of_hanoi.jpg","width":1167,"height":1728,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/06\/PSM_V26_D464_The_tower_of_hanoi.jpg","width":1167,"height":1728,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/69859","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/users\/17959"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/comments?post=69859"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/69859\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media\/69846"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media?parent=69859"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/categories?post=69859"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/tags?post=69859"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/staff?post=69859"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/editorial_format?post=69859"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/serie?post=69859"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/audience?post=69859"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/geo?post=69859"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}