{"id":69832,"date":"2025-06-09T19:19:40","date_gmt":"2025-06-09T17:19:40","guid":{"rendered":"https:\/\/legrandcontinent.eu\/es\/?p=69832"},"modified":"2025-06-09T19:19:43","modified_gmt":"2025-06-09T17:19:43","slug":"en-los-angeles-tras-la-intervencion-de-la-guardia-nacional-donald-trump-amenaza-con-enviar-al-ejercito-contra-los-manifestantes","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/es\/2025\/06\/09\/en-los-angeles-tras-la-intervencion-de-la-guardia-nacional-donald-trump-amenaza-con-enviar-al-ejercito-contra-los-manifestantes\/","title":{"rendered":"En Los \u00c1ngeles, tras la intervenci\u00f3n de la Guardia Nacional, Donald Trump amenaza con enviar al ej\u00e9rcito contra los manifestantes"},"content":{"rendered":"\n<p>El viernes 6 de junio por la tarde, agentes federales llevaron a cabo una operaci\u00f3n para detener a trabajadores presuntamente indocumentados en el barrio de la moda, al norte de Los \u00c1ngeles. Esta operaci\u00f3n, que se sald\u00f3 con la detenci\u00f3n de un centenar de personas, contribuy\u00f3 a reunir a numerosos activistas que se manifestaban en contra de la pol\u00edtica migratoria represiva de la administraci\u00f3n Trump.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Durante las horas posteriores a la operaci\u00f3n, los enfrentamientos entre manifestantes y fuerzas del orden se intensificaron en el condado de Los \u00c1ngeles, especialmente en las ciudades de Compton y Paramount.<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/sm91e\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Las im\u00e1genes difundidas por los participantes y los periodistas en las redes sociales contribuyeron a aumentar el n\u00famero de manifestantes y, al d\u00eda siguiente, miles de personas m\u00e1s tomaron las calles de la ciudad.<\/li>\n\n\n\n<li>En respuesta a los enfrentamientos entre la polic\u00eda y los manifestantes, Donald Trump firm\u00f3 el s\u00e1bado por la noche un controvertido decreto ejecutivo que autoriza el despliegue de 2.000 soldados de la Guardia Nacional de California.<\/li>\n\n\n\n<li>Es la primera vez desde 1965 que un presidente estadounidense autoriza el despliegue de miembros de las fuerzas armadas sin la cooperaci\u00f3n del gobernador del estado, en este caso el dem\u00f3crata Gavin Newsom. Este \u00faltimo pidi\u00f3 formalmente a Trump que retirara la Guardia Nacional ayer, 8 de junio, y ha anunciado hoy que California va a llevar al presidente ante los tribunales.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">This is exactly what Donald Trump wanted.<br><br>He flamed the fires and illegally acted to federalize the National Guard.<br><br>The order he signed doesn\u2019t just apply to CA.<br><br>It will allow him to go into ANY STATE and do the same thing.<br><br>We\u2019re suing him.<a href=\"https:\/\/t.co\/O3RAGlp2zo\">pic.twitter.com\/O3RAGlp2zo<\/a><\/p>&mdash; Gavin Newsom (@GavinNewsom) <a href=\"https:\/\/twitter.com\/GavinNewsom\/status\/1932058650006417825?ref_src=twsrc%5Etfw\">June 9, 2025<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p>M\u00e1s all\u00e1 del rechazo a Trump y a su agenda \u2014el 65% de los 2,5 millones de habitantes del condado de Los \u00c1ngeles votaron a Kamala Harris en 2024\u2014, los manifestantes se oponen sobre todo a los m\u00e9todos utilizados por el Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE), la agencia del Departamento de Seguridad Nacional dirigida por\u00a0<a href=\"https:\/\/legrandcontinent.eu\/es\/2025\/01\/15\/kristi-noem-la-conservadora-de-las-praderas-de-donald-trump\/\">Kristi Noem<\/a>, para detener a personas en situaci\u00f3n irregular.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Desde el regreso al poder de Trump, las redadas en lugares de trabajo (en Los \u00c1ngeles, se trataba de un mayorista de ropa y una tienda de bricolaje) se han multiplicado en todo el pa\u00eds, especialmente en las grandes ciudades con mayor\u00eda dem\u00f3crata&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-69832' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2025\/06\/09\/en-los-angeles-tras-la-intervencion-de-la-guardia-nacional-donald-trump-amenaza-con-enviar-al-ejercito-contra-los-manifestantes\/#easy-footnote-bottom-1-69832' title='Russell Contreras y Brittany Gibson, \u00ab\u00a0&lt;a href=&quot;https:\/\/www.axios.com\/2025\/06\/03\/immigration-enforcement-ice-deportations-states-trump&quot;&gt;Where the hot spots are for immigration enforcement&lt;\/a&gt;\u00a0\u00bb,\u00a0&lt;em&gt;Axios&lt;\/em&gt;, 3 de junio de 2025.'><sup>1<\/sup><\/a><\/span><\/span>.<\/li>\n\n\n\n<li>Durante estas operaciones, los trabajadores identificados como indocumentados son subidos a coches y autobuses y trasladados a centros de detenci\u00f3n en funci\u00f3n de su estatus y sus antecedentes penales.<\/li>\n\n\n\n<li>Adem\u00e1s de las detenciones en los lugares de trabajo, el ICE tambi\u00e9n recurre a pr\u00e1cticas a\u00fan m\u00e1s controvertidas, como el uso de pretextos falsos (por ejemplo, \u00abcontroles rutinarios\u00bb) para atraer a personas en situaci\u00f3n irregular y proceder a su detenci\u00f3n&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-69832' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2025\/06\/09\/en-los-angeles-tras-la-intervencion-de-la-guardia-nacional-donald-trump-amenaza-con-enviar-al-ejercito-contra-los-manifestantes\/#easy-footnote-bottom-2-69832' title='Billal Rahman, \u00ab\u00a0&lt;a href=&quot;https:\/\/www.newsweek.com\/ice-arrests-multiple-people-chicago-after-tricking-them-turn-2081246&quot;&gt;ICE Arrests Multiple People in Chicago After Tricking Them to Turn Up&lt;\/a&gt;\u00a0\u00bb,\u00a0&lt;em&gt;Newsweek&lt;\/em&gt;, 5 de junio de 2025.'><sup>2<\/sup><\/a><\/span><\/span>.<\/li>\n<\/ul>\n\n\n\n<p>Por el momento, Trump no ha invocado la Ley de Insurrecci\u00f3n. Si lo hiciera, ser\u00eda la primera vez desde 1992 \u2014tras la absoluci\u00f3n de los cuatro polic\u00edas que golpearon al activista Rodney King un a\u00f1o antes\u2014 que un presidente estadounidense utilizar\u00eda esta ley de 1807 para reprimir las manifestaciones.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Trump\u00a0<a href=\"https:\/\/legrandcontinent.eu\/es\/2025\/04\/05\/en-estados-unidos-la-oposicion-a-trump-organiza-su-mayor-movilizacion-desde-el-20-de-enero\/\">ya hab\u00eda amenazado<\/a>\u00a0durante su primer mandato con recurrir al ej\u00e9rcito para reprimir las manifestaciones tras el asesinato de George Floyd a manos de la polic\u00eda de Minneapolis en mayo de 2020&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-69832' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2025\/06\/09\/en-los-angeles-tras-la-intervencion-de-la-guardia-nacional-donald-trump-amenaza-con-enviar-al-ejercito-contra-los-manifestantes\/#easy-footnote-bottom-3-69832' title='Michael S. Schmidt et Maggie Haberman, \u00ab\u00a0&lt;a href=&quot;https:\/\/www.nytimes.com\/2021\/06\/25\/us\/politics\/trump-insurrection-act-protests.html&quot;&gt;Trump Aides Prepared Insurrection Act Order During Debate Over Protests&lt;\/a&gt;\u00a0\u00bb,\u00a0&lt;em&gt;The New York Times&lt;\/em&gt;, 25 de junio de 2021.'><sup>3<\/sup><\/a><\/span><\/span>.<\/li>\n\n\n\n<li>Adem\u00e1s, a principios de junio orden\u00f3 a su gabinete que preparara un decreto ejecutivo invocando la Ley de Insurrecci\u00f3n, quej\u00e1ndose de que su administraci\u00f3n \u00abparec\u00eda d\u00e9bil\u00bb, pero no lleg\u00f3 a aplicarlo.<\/li>\n\n\n\n<li>Sin embargo, esta decisi\u00f3n habr\u00eda sido considerada muy controvertida, ya que la respuesta a los movimientos de protesta suele dejarse en manos de las autoridades locales, que disponen de medios suficientes para gestionar las manifestaciones.<\/li>\n\n\n\n<li>El Estado, los condados y las ciudades de California emplean a m\u00e1s de 75.000 agentes de las fuerzas del orden&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-4-69832' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2025\/06\/09\/en-los-angeles-tras-la-intervencion-de-la-guardia-nacional-donald-trump-amenaza-con-enviar-al-ejercito-contra-los-manifestantes\/#easy-footnote-bottom-4-69832' title='Magnus Lofstrom, Brandon Martin, y Andrew Skelton,\u00a0&lt;a href=&quot;https:\/\/www.ppic.org\/publication\/law-enforcement-staffing-in-california\/&quot;&gt;Law Enforcement Staffing in California&lt;\/a&gt;, Public Policy Institute of California, febrero de 2025.'><sup>4<\/sup><\/a><\/span><\/span>. S\u00f3lo el departamento de polic\u00eda de Los \u00c1ngeles cuenta con cerca de 9.000 agentes.<\/li>\n<\/ul>\n\n\n\n<p>En lugar de la Ley de Insurrecci\u00f3n, el presidente estadounidense ha recurrido a un art\u00edculo del C\u00f3digo de los Estados Unidos que permite \u00abfederalizar\u00bb los recursos de las guardias nacionales de los estados para \u00abhacer cumplir las leyes\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-5-69832' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2025\/06\/09\/en-los-angeles-tras-la-intervencion-de-la-guardia-nacional-donald-trump-amenaza-con-enviar-al-ejercito-contra-los-manifestantes\/#easy-footnote-bottom-5-69832' title='&lt;a href=&quot;https:\/\/www.whitehouse.gov\/presidential-actions\/2025\/06\/department-of-defense-security-for-the-protection-of-department-of-homeland-security-functions\/&quot;&gt;Department of Defense Security for the Protection of Department of Homeland Security Functions&lt;\/a&gt;, Casa Blanca, 7 de junio de 2025.'><sup>5<\/sup><\/a><\/span><\/span>. Sin embargo, la presencia en las calles de Los \u00c1ngeles de varios miles de soldados podr\u00eda aumentar el riesgo de escalada de los enfrentamientos&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-6-69832' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2025\/06\/09\/en-los-angeles-tras-la-intervencion-de-la-guardia-nacional-donald-trump-amenaza-con-enviar-al-ejercito-contra-los-manifestantes\/#easy-footnote-bottom-6-69832' title='Steve Vladeck, \u00ab\u00a0&lt;a href=&quot;https:\/\/www.stevevladeck.com\/p\/156-federalizing-the-california-national&quot;&gt;Federalizing the California National Guard&lt;\/a&gt;\u00a0\u00bb,\u00a0&lt;em&gt;One First&lt;\/em&gt;, 8 de junio de 2025.'><sup>6<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<p>Seg\u00fan David Frum, uno de los firmantes m\u00e1s respetados de\u00a0<em>The Atlantic<\/em>, las medidas adoptadas por Trump no s\u00f3lo sirven para poner a prueba los l\u00edmites del poder presidencial, obligando a los estados dem\u00f3cratas a acatar los decretos federales, sino que podr\u00edan revelar una estrategia pol\u00edtica radical de cara a las elecciones de mitad de mandato de 2026&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-7-69832' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2025\/06\/09\/en-los-angeles-tras-la-intervencion-de-la-guardia-nacional-donald-trump-amenaza-con-enviar-al-ejercito-contra-los-manifestantes\/#easy-footnote-bottom-7-69832' title='David Frum,\u00a0&lt;a href=&quot;https:\/\/www.theatlantic.com\/ideas\/archive\/2025\/06\/los-angeles-dress-rehearsal-trump\/683078\/&quot;&gt;For Trump, This Is a Dress Rehearsal&lt;\/a&gt;, The Atlantic, 8 de junio de 2025.'><sup>7<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Utilizar los poderes federales para provocar una perturbaci\u00f3n espectacular; invocar esta perturbaci\u00f3n para declarar el estado de emergencia y desplegar las tropas federales; tomar el control de las operaciones locales del Gobierno \u2014la polic\u00eda en junio de 2025\u2014 y las elecciones en noviembre de 2026.<\/li>\n<\/ul>\n\n\n\n<p>Este in\u00e9dito reajuste ejecutivo se produce en una semana en la que se producir\u00e1 una concentraci\u00f3n excepcional de tropas estadounidenses en Washington con motivo de un desfile solicitado por el presidente estadounidense.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>El s\u00e1bado 14 de junio, el presidente Donald Trump organizar\u00e1 por primera vez un desfile militar en Washington para conmemorar los 250 a\u00f1os de la creaci\u00f3n del Ej\u00e9rcito de los Estados Unidos. Ese d\u00eda tambi\u00e9n es su 79.\u00ba cumplea\u00f1os.<\/li>\n\n\n\n<li>El \u00faltimo gran desfile de este tipo en Washington tuvo lugar el 8 de junio de 1991 para celebrar el fin de la primera Guerra del Golfo.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Las manifestaciones contra la pol\u00edtica migratoria de la Casa Blanca continuaron por tercer d\u00eda consecutivo en el condado de Los \u00c1ngeles.<\/p>\n<p>Por primera vez desde 1965, el presidente estadounidense ha decidido desplegar a la Guardia Nacional sin el consentimiento del gobernador Newsom, quien ha anunciado que llevar\u00e1 a la administraci\u00f3n ante los tribunales.<\/p>\n<p>En respuesta a la pregunta de una periodista, el presidente declar\u00f3 que \u00e9l era el \u00fanico que pod\u00eda fijar el umbral \u00aba partir del cual enviar\u00e1 a los marines\u00bb (\u00abThe bar is what I think it is\u00bb).<\/p>\n","protected":false},"author":1366,"featured_media":69833,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":true,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":5,"footnotes":""},"categories":[6],"tags":[],"staff":[],"editorial_format":[1472],"serie":[],"audience":[],"geo":[172],"class_list":["post-69832","post","type-post","status-publish","format-standard","hentry","category-politica","editorial_format-analisis","geo-americas"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":69833,"excerpt":"Las manifestaciones contra la pol\u00edtica migratoria de la Casa Blanca continuaron por tercer d\u00eda consecutivo en el condado de Los \u00c1ngeles.\r\n\r\nPor primera vez desde 1965, el presidente estadounidense ha decidido desplegar a la Guardia Nacional sin el consentimiento del gobernador Newsom, quien ha anunciado que llevar\u00e1 a la administraci\u00f3n ante los tribunales.\r\n\r\nEn respuesta a la pregunta de una periodista, el presidente declar\u00f3 que \u00e9l era el \u00fanico que pod\u00eda fijar el umbral \u00aba partir del cual enviar\u00e1 a los marines\u00bb (\u00abThe bar is what I think it is\u00bb).","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>En Los \u00c1ngeles, tras la intervenci\u00f3n de la Guardia Nacional, Donald Trump amenaza con enviar al ej\u00e9rcito contra los manifestantes - El Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/es\/2025\/06\/09\/en-los-angeles-tras-la-intervencion-de-la-guardia-nacional-donald-trump-amenaza-con-enviar-al-ejercito-contra-los-manifestantes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En Los \u00c1ngeles, tras la intervenci\u00f3n de la Guardia Nacional, Donald Trump amenaza con enviar al ej\u00e9rcito contra los manifestantes - El Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Las manifestaciones contra la pol\u00edtica migratoria de la Casa Blanca continuaron por tercer d\u00eda consecutivo en el condado de Los \u00c1ngeles.  Por primera vez desde 1965, el presidente estadounidense ha decidido desplegar a la Guardia Nacional sin el consentimiento del gobernador Newsom, quien ha anunciado que llevar\u00e1 a la administraci\u00f3n ante los tribunales.  En respuesta a la pregunta de una periodista, el presidente declar\u00f3 que \u00e9l era el \u00fanico que pod\u00eda fijar el umbral \u00aba partir del cual enviar\u00e1 a los marines\u00bb (\u00abThe bar is what I think it is\u00bb).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/es\/2025\/06\/09\/en-los-angeles-tras-la-intervencion-de-la-guardia-nacional-donald-trump-amenaza-con-enviar-al-ejercito-contra-los-manifestantes\/\" \/>\n<meta property=\"og:site_name\" content=\"El Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-09T17:19:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-09T17:19:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/06\/gc-elenfrentamientos-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"florent\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/06\/gc-elenfrentamientos-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"florent\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/06\/09\/en-los-angeles-tras-la-intervencion-de-la-guardia-nacional-donald-trump-amenaza-con-enviar-al-ejercito-contra-los-manifestantes\/\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/2025\/06\/09\/en-los-angeles-tras-la-intervencion-de-la-guardia-nacional-donald-trump-amenaza-con-enviar-al-ejercito-contra-los-manifestantes\/\",\"name\":\"En Los \u00c1ngeles, tras la intervenci\u00f3n de la Guardia Nacional, Donald Trump amenaza con enviar al ej\u00e9rcito contra los manifestantes - El Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/06\/09\/en-los-angeles-tras-la-intervencion-de-la-guardia-nacional-donald-trump-amenaza-con-enviar-al-ejercito-contra-los-manifestantes\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/06\/09\/en-los-angeles-tras-la-intervencion-de-la-guardia-nacional-donald-trump-amenaza-con-enviar-al-ejercito-contra-los-manifestantes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/06\/sm91e-enfrentamientos-entre-manifestantes-y-autoridades-en-los-ngeles-.png\",\"datePublished\":\"2025-06-09T17:19:40+00:00\",\"dateModified\":\"2025-06-09T17:19:43+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/06\/09\/en-los-angeles-tras-la-intervencion-de-la-guardia-nacional-donald-trump-amenaza-con-enviar-al-ejercito-contra-los-manifestantes\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/es\/2025\/06\/09\/en-los-angeles-tras-la-intervencion-de-la-guardia-nacional-donald-trump-amenaza-con-enviar-al-ejercito-contra-los-manifestantes\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/06\/09\/en-los-angeles-tras-la-intervencion-de-la-guardia-nacional-donald-trump-amenaza-con-enviar-al-ejercito-contra-los-manifestantes\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/06\/sm91e-enfrentamientos-entre-manifestantes-y-autoridades-en-los-ngeles-.png\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/06\/sm91e-enfrentamientos-entre-manifestantes-y-autoridades-en-los-ngeles-.png\",\"width\":1564,\"height\":1492},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/06\/09\/en-los-angeles-tras-la-intervencion-de-la-guardia-nacional-donald-trump-amenaza-con-enviar-al-ejercito-contra-los-manifestantes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/legrandcontinent.eu\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En Los \u00c1ngeles, tras la intervenci\u00f3n de la Guardia Nacional, Donald Trump amenaza con enviar al ej\u00e9rcito contra los manifestantes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/\",\"name\":\"El Grand Continent\",\"description\":\"La escala pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\",\"name\":\"florent\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"caption\":\"florent\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"En Los \u00c1ngeles, tras la intervenci\u00f3n de la Guardia Nacional, Donald Trump amenaza con enviar al ej\u00e9rcito contra los manifestantes - El Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/es\/2025\/06\/09\/en-los-angeles-tras-la-intervencion-de-la-guardia-nacional-donald-trump-amenaza-con-enviar-al-ejercito-contra-los-manifestantes\/","og_locale":"es_ES","og_type":"article","og_title":"En Los \u00c1ngeles, tras la intervenci\u00f3n de la Guardia Nacional, Donald Trump amenaza con enviar al ej\u00e9rcito contra los manifestantes - El Grand Continent","og_description":"Las manifestaciones contra la pol\u00edtica migratoria de la Casa Blanca continuaron por tercer d\u00eda consecutivo en el condado de Los \u00c1ngeles.  Por primera vez desde 1965, el presidente estadounidense ha decidido desplegar a la Guardia Nacional sin el consentimiento del gobernador Newsom, quien ha anunciado que llevar\u00e1 a la administraci\u00f3n ante los tribunales.  En respuesta a la pregunta de una periodista, el presidente declar\u00f3 que \u00e9l era el \u00fanico que pod\u00eda fijar el umbral \u00aba partir del cual enviar\u00e1 a los marines\u00bb (\u00abThe bar is what I think it is\u00bb).","og_url":"https:\/\/legrandcontinent.eu\/es\/2025\/06\/09\/en-los-angeles-tras-la-intervencion-de-la-guardia-nacional-donald-trump-amenaza-con-enviar-al-ejercito-contra-los-manifestantes\/","og_site_name":"El Grand Continent","article_published_time":"2025-06-09T17:19:40+00:00","article_modified_time":"2025-06-09T17:19:43+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/06\/gc-elenfrentamientos-scaled.jpg","type":"image\/jpeg"}],"author":"florent","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/06\/gc-elenfrentamientos-scaled.jpg","twitter_misc":{"Escrito por":"florent","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/es\/2025\/06\/09\/en-los-angeles-tras-la-intervencion-de-la-guardia-nacional-donald-trump-amenaza-con-enviar-al-ejercito-contra-los-manifestantes\/","url":"https:\/\/legrandcontinent.eu\/es\/2025\/06\/09\/en-los-angeles-tras-la-intervencion-de-la-guardia-nacional-donald-trump-amenaza-con-enviar-al-ejercito-contra-los-manifestantes\/","name":"En Los \u00c1ngeles, tras la intervenci\u00f3n de la Guardia Nacional, Donald Trump amenaza con enviar al ej\u00e9rcito contra los manifestantes - El Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/es\/2025\/06\/09\/en-los-angeles-tras-la-intervencion-de-la-guardia-nacional-donald-trump-amenaza-con-enviar-al-ejercito-contra-los-manifestantes\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/es\/2025\/06\/09\/en-los-angeles-tras-la-intervencion-de-la-guardia-nacional-donald-trump-amenaza-con-enviar-al-ejercito-contra-los-manifestantes\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/06\/sm91e-enfrentamientos-entre-manifestantes-y-autoridades-en-los-ngeles-.png","datePublished":"2025-06-09T17:19:40+00:00","dateModified":"2025-06-09T17:19:43+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/es\/2025\/06\/09\/en-los-angeles-tras-la-intervencion-de-la-guardia-nacional-donald-trump-amenaza-con-enviar-al-ejercito-contra-los-manifestantes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/es\/2025\/06\/09\/en-los-angeles-tras-la-intervencion-de-la-guardia-nacional-donald-trump-amenaza-con-enviar-al-ejercito-contra-los-manifestantes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/2025\/06\/09\/en-los-angeles-tras-la-intervencion-de-la-guardia-nacional-donald-trump-amenaza-con-enviar-al-ejercito-contra-los-manifestantes\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/06\/sm91e-enfrentamientos-entre-manifestantes-y-autoridades-en-los-ngeles-.png","contentUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/06\/sm91e-enfrentamientos-entre-manifestantes-y-autoridades-en-los-ngeles-.png","width":1564,"height":1492},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/es\/2025\/06\/09\/en-los-angeles-tras-la-intervencion-de-la-guardia-nacional-donald-trump-amenaza-con-enviar-al-ejercito-contra-los-manifestantes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legrandcontinent.eu\/es\/"},{"@type":"ListItem","position":2,"name":"En Los \u00c1ngeles, tras la intervenci\u00f3n de la Guardia Nacional, Donald Trump amenaza con enviar al ej\u00e9rcito contra los manifestantes"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/es\/#website","url":"https:\/\/legrandcontinent.eu\/es\/","name":"El Grand Continent","description":"La escala pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c","name":"florent","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","caption":"florent"}}]}},"lgc_categories":[{"id":6,"name":"Pol\u00edtica","slug":"politica"}],"lgc_author":null,"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/06\/sm91e-enfrentamientos-entre-manifestantes-y-autoridades-en-los-ngeles-.png","width":1564,"height":1492,"alt":""},"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/69832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/users\/1366"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/comments?post=69832"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/69832\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media\/69833"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media?parent=69832"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/categories?post=69832"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/tags?post=69832"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/staff?post=69832"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/editorial_format?post=69832"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/serie?post=69832"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/audience?post=69832"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/geo?post=69832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}