{"id":64296,"date":"2025-04-21T13:37:43","date_gmt":"2025-04-21T11:37:43","guid":{"rendered":"https:\/\/legrandcontinent.eu\/es\/?p=64296"},"modified":"2025-04-21T13:37:48","modified_gmt":"2025-04-21T11:37:48","slug":"geopolitica-del-papa-francisco-de-ucrania-a-las-periferias-10-puntos-sobre-su-balance-internacional","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/es\/2025\/04\/21\/geopolitica-del-papa-francisco-de-ucrania-a-las-periferias-10-puntos-sobre-su-balance-internacional\/","title":{"rendered":"Geopol\u00edtica del papa Francisco: de Ucrania a las periferias, 10 puntos sobre su balance internacional"},"content":{"rendered":"\n<p class=\"has-drop-cap\">Jorge Bergoglio, fallecido este lunes 21 de abril de 2025, no conoc\u00eda apenas las sutilezas del lenguaje diplom\u00e1tico. El argentino, <a href=\"https:\/\/legrandcontinent.eu\/es\/2025\/04\/21\/ha-fallecido-el-papa-francisco-historia-de-un-pontifice-revolucionario-1936-2025\/\">pastor antes que estratega<\/a>, fue sin embargo escuchado como ning\u00fan otro l\u00edder religioso en el mundo. Como todos sus predecesores desde el Concilio Vaticano II, Francisco fue una autoridad moral e imparcial a la que muchos recurr\u00edan en busca de mediaci\u00f3n en el caos del mundo \u2014y su debilitamiento en los \u00faltimos meses hab\u00eda dejado un vac\u00edo\u2014.<\/p>\n\n\n\n<p>A la hora de hacer balance, una de las expresiones clave de Francisco resulta especialmente esclarecedora para comprender este pontificado fuera de lo com\u00fan: \u00ab<a href=\"https:\/\/legrandcontinent.eu\/es\/2024\/06\/14\/multilateralismo-desde-abajo-diplomacia-por-la-tierra\/\">ir a las periferias<\/a>\u00bb. Se trata de la defensa de los pueblos pobres, los sin voz, los invisibles, los rechazados, los inmigrantes, y de la cercan\u00eda con ellos. Es tambi\u00e9n un enfoque muy jesuita el de arriesgarse lejos del centro. Este papa, formado en cuestiones sociales y ecolog\u00eda, que como arzobispo de Buenos Aires se enfrent\u00f3 a obispos de todo signo, rompi\u00f3 con muchos c\u00f3digos e hipocres\u00edas romanas. Interesado por la diversidad del mundo, vio la imperiosa necesidad de que los sacerdotes, los obispos y \u00e9l mismo \u00absalieran\u00bb de las iglesias y dejaran entrar \u00abaire fresco\u00bb. Y tambi\u00e9n \u00abbajar del balc\u00f3n\u00bb para encontrarse con el hombre de igual a igual e impregnarse del \u00abolor del reba\u00f1o\u00bb de los creyentes. En 2013, dijo con humor a los j\u00f3venes brasile\u00f1os: \u00abNo se queden en el balc\u00f3n de la vida. \u00a1Armen jaleo, pero ayuden a ordenar!\u00bb. Hasta tal punto que algunos tradicionalistas, escandalizados, llegaron a cuestionar su legitimidad, viendo en \u00e9l a un papa infiel a los dogmas que precipitar\u00eda a la Iglesia hacia el abismo de la secularizaci\u00f3n.<\/p>\n\n\n\n<p>Su pontificado estuvo marcado por gestos fuertes y simb\u00f3licos, como el de inaugurar el a\u00f1o jubilar de la \u00abmisericordia\u00bb en 2016 en la peque\u00f1a catedral de Bangui, en plena guerra civil centroafricana, o el de viajar a Irak como peregrino de la paz a la llanura de N\u00ednive, a las puertas del infierno del Daesh.&nbsp;&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Jorge Bergoglio no conoc\u00eda bien las sutilezas del lenguaje diplom\u00e1tico.<\/p><cite>Jean-Louis de la Vaissi\u00e8re<\/cite><\/blockquote><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">1 \u2014 Los ocho postulados de Francisco<\/h2>\n\n\n\n<p>Durante doce a\u00f1os, Francisco repiti\u00f3 con constancia ocho prioridades que forman un todo. Era su programa para el mundo, revelador de una personalidad que nunca dud\u00f3 en romper con los usos y costumbres del papado y con el pensamiento dominante de los poderosos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">La causa de la migraci\u00f3n<\/h3>\n\n\n\n<p>La inmigraci\u00f3n fue la primera, la m\u00e1s destacada y tambi\u00e9n la m\u00e1s divisiva dentro del mundo cat\u00f3lico. Una obsesi\u00f3n para este hijo de inmigrantes italianos que, al llegar a Estados Unidos procedente de Cuba en 2015, se present\u00f3 a Barack Obama como \u00abhijo de inmigrantes\u00bb. Un conflicto abierto <a href=\"https:\/\/legrandcontinent.eu\/es\/2025\/02\/13\/el-papa-contra-j-d-vance-la-carta-de-francisco-a-los-obispos-estadounidenses\/\">no tard\u00f3 en estallar con Trump<\/a>, cuando Francisco conden\u00f3 el muro que el presidente republicano estaba construyendo. El papa acababa de abandonar Ciudad Ju\u00e1rez, ciudad fronteriza mexicana, para expresar su repulsa. Durante el segundo mandato de Trump, el conflicto se recrudeci\u00f3.&nbsp;<\/p>\n\n\n\n<p>Desde la isla de Lampedusa hasta Marsella, Francisco no dej\u00f3 de denunciar \u00abla globalizaci\u00f3n de la indiferencia\u00bb y de afirmar el derecho a salvarse y a salvar a la familia frente a las guerras, los desastres clim\u00e1ticos y la miseria. Subray\u00f3 que los migrantes tienen derechos y deberes. Fran\u00e7ois arremeti\u00f3 contra todo tipo de tr\u00e1fico de seres humanos convertidos en \u00abmercanc\u00edas\u00bb, una de sus grandes causas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">La paz \u2014a cualquier precio\u2014<\/h3>\n\n\n\n<p>Negociar, evitar v\u00edctimas civiles, escuchar los puntos de vista, escuchar lo que quieren los pueblos para lograr una paz justa: todo ello ser\u00e1 tambi\u00e9n otra constante en Francisco, a riesgo de ser incomprendido.<\/p>\n\n\n\n<p>Para \u00e9l, \u00abtoda guerra es una derrota\u00bb y \u00abno existe la guerra justa\u00bb.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Francisco cuestion\u00f3 en su enc\u00edclica <em>Fratelli Tutti<\/em> este concepto, sin embargo recogido en el catecismo cat\u00f3lico y procedente de San Agust\u00edn y Santo Tom\u00e1s, especialmente en caso de leg\u00edtima defensa: \u00abHoy es muy dif\u00edcil \u2014escrib\u00eda Francisco\u2014 defender los criterios racionales, madurados en otros tiempos, para hablar de una posible guerra justa\u00bb.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Desde la isla de Lampedusa hasta Marsella, Francisco no dej\u00f3 de denunciar \u00abla globalizaci\u00f3n de la indiferencia\u00bb y de afirmar el derecho a salvarse y a salvar a la familia frente a las guerras, los desastres clim\u00e1ticos y la miseria.<\/p><cite>Jean-Louis de la Vaissi\u00e8re<\/cite><\/blockquote><\/figure>\n\n\n\n<p>El papa Francisco critic\u00f3 duramente la fabricaci\u00f3n y el comercio de armas. Consideraba que estas industrias eran en gran medida responsables de la multiplicaci\u00f3n de las guerras, al alentar a Estados delincuentes que se inventan todo tipo de pretextos para justificar sus depredaciones. Y el actual rearme europeo y mundial no le satisfac\u00eda. El recurso a las armas nucleares, que podr\u00edan provocar la destrucci\u00f3n de pueblos enteros, era para el pont\u00edfice un argumento adicional.<\/p>\n\n\n\n<p>\u00abDebemos desarmar las palabras, para desarmar las mentes y desarmar la tierra\u00bb, escribi\u00f3 el 18 de marzo desde su habitaci\u00f3n de hospital, en una s\u00faplica por la paz, el d\u00eda de la reuni\u00f3n entre Trump y Putin. Y su secretario de Estado, Pietro Parolin, subray\u00f3: \u00abNo podemos estar satisfechos con la direcci\u00f3n que estamos tomando. La pol\u00edtica de la Santa Sede siempre ha sido insistir a nivel internacional en un desarme general y controlado\u00bb.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Di\u00e1logo interreligioso<\/h3>\n\n\n\n<p>El di\u00e1logo interreligioso, esencial como fundamento de la paz, fue el tercer pilar de su programa. Consciente de los conflictos, incluso de los odios seculares que separan a las religiones, tuvo cuidado de no provocar con sus palabras, como le hab\u00eda sucedido a Benedicto XVI con el islam. El respeto por las otras religiones se basa en el texto conciliar <em>Nostra Aetate<\/em>; para Francisco, Dios puede ser descubierto a trav\u00e9s de otros enfoques religiosos, pero esta apertura mental es sospechosa para algunos tradicionalistas.<\/p>\n\n\n\n<p>Lo m\u00e1s esencial para Francisco es que Dios no puede alentar la guerra en su nombre.&nbsp;<\/p>\n\n\n\n<p>Sin embargo, muchas guerras se libran en nombre de supuestos valores religiosos. En general, el di\u00e1logo interreligioso ha avanzado, especialmente con la Universidad Al-Azhar de El Cairo y su gran im\u00e1n Ahmed et-Tayeb. Continuar\u00e1 los esfuerzos de entendimiento con la religi\u00f3n madre del cristianismo, el juda\u00edsmo. Dar\u00e1 testimonio de su inter\u00e9s por el budismo en un templo de Sri Lanka.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">El papa de la ecolog\u00eda<\/h3>\n\n\n\n<p>La protecci\u00f3n del planeta, la \u00abCasa Com\u00fan\u00bb, expresada en su enc\u00edclica m\u00e1s conocida, <em>Laudato si&#8217;<\/em>, y reafirmada en un mensaje a la COP24 en Dub\u00e1i, es sin duda, junto con la inmigraci\u00f3n, la postura que m\u00e1s ha impactado m\u00e1s all\u00e1 de los c\u00edrculos cristianos: lo que le ha enfrentado una vez m\u00e1s a Donald Trump, pero le ha hecho popular entre los ecologistas de todo el mundo. \u00abTodo est\u00e1 relacionado\u00bb, el hombre no debe agotar la naturaleza, sino ser su \u00abjardinero\u00bb, su protector. Denunciar\u00e1 la agricultura intensiva e industrial, especialmente durante el s\u00ednodo sobre la Amazonia, muy lejos del \u00ab<em>drill, baby drill<\/em>\u00bb del 47\u00ba presidente estadounidense. Sus posiciones le valieron s\u00f3lidas enemistades en las empresas de energ\u00edas f\u00f3siles.<\/p>\n\n\n\n<p>Por otra parte, Jorge Bergoglio, en l\u00ednea con los papas que le precedieron, siempre ha apoyado el papel de las organizaciones internacionales \u2014ONU, FAO\u2014 o regionales, hoy muy criticadas. Pero al mismo tiempo se ha querido ser el defensor de las tradiciones locales amenazadas por una globalizaci\u00f3n inhumana, siempre que no sean identitarias. Ha defendido una laicidad benevolente con las religiones populares.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Un pontificado social<\/h3>\n\n\n\n<p>Francisco fue un papa social, socialista en algunos aspectos, pero sin duda no marxista: la \u00abteolog\u00eda del pueblo\u00bb ya formaba parte de su programa cuando era obispo en una Iglesia latinoamericana muy dividida. El papa supo trazar una l\u00ednea media, tanto contra un conservadurismo cercano a las dictaduras como contra ciertas teolog\u00edas de la liberaci\u00f3n que predicaban la lucha armada.&nbsp;<\/p>\n\n\n\n<p>En largos discursos ante los \u00abmovimientos populares\u00bb, llam\u00f3 a los pobres a organizarse para defender sus derechos, pero de forma pac\u00edfica. Fue acusado sucesivamente de marxista por los conservadores y de demasiado blando con el gran capital por los radicales.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Una continuidad matizada en materia de \u00absalud materna y reproductiva\u00bb<\/h3>\n\n\n\n<p>Francisco continu\u00f3 adem\u00e1s la lucha de sus predecesores por \u00abla salud materna y reproductiva\u00bb en sus discursos, en particular ante la ONU.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>El papa supo trazar una l\u00ednea media, tanto contra un conservadurismo cercano a las dictaduras como contra ciertas teolog\u00edas de la liberaci\u00f3n que abogaban por la lucha armada.\u00a0<\/p><cite>Jean-Louis de la Vaissi\u00e8re<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Pero ya no volvi\u00f3 a mencionar el rechazo de la anticoncepci\u00f3n recomendado por Pablo VI en la enc\u00edclica <em>Humanae Vitae<\/em>.<\/p>\n\n\n\n<p>A su regreso de Filipinas, consciente de la miseria social y la emigraci\u00f3n en ese pa\u00eds, lleg\u00f3 incluso a afirmar que los cat\u00f3licos no ten\u00edan que \u00abreproducirse como conejos\u00bb.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Una doctrina de firmeza, sin estigmatizaci\u00f3n individual de las personas<\/h3>\n\n\n\n<p>Contrariamente a algunas opiniones compartidas curiosamente por tradicionalistas y cristianos de izquierda, los primeros para criticar, los segundos para imaginarse al papa a su lado, el discurso de Francisco sobre el final de la vida y el aborto fue todo menos relativista. Incluso utiliz\u00f3 f\u00f3rmulas provocadoras.<\/p>\n\n\n\n<p>En particular, cuando en 2024, a su regreso de B\u00e9lgica, respondiendo a una pregunta sobre el aborto, reproch\u00f3 a los m\u00e9dicos que lo practicaban que actuaran como \u00abasesinos en serie\u00bb. En cambio, y esto es nuevo, siempre mostr\u00f3 su rechazo a condenar a las mujeres que recurren a ella, como hombre de campo familiarizado con las \u00abvillas miseria\u00bb, los barrios marginales de la aglomeraci\u00f3n de Buenos Aires, consciente de las situaciones de angustia. Del mismo modo, cuando dijo \u00ab\u00bfqui\u00e9n soy yo para juzgar?\u00bb en referencia a los homosexuales. Si bien el acto se califica de \u00abdesordenado\u00bb en el catecismo, los homosexuales, tanto hombres como mujeres, deben ser acogidos plenamente y sin prejuicios en la Iglesia. En cambio, denunci\u00f3 en\u00e9rgicamente la teor\u00eda de g\u00e9nero.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">La apertura a las artes, las letras y las ciencias&nbsp;<\/h3>\n\n\n\n<p>Un \u00faltimo pilar de su pensamiento le ven\u00eda de su formaci\u00f3n jesuita: <a href=\"https:\/\/legrandcontinent.eu\/es\/2025\/04\/20\/el-papa-francisco-es-el-loco-de-dios-por-antonomasia-y-este-es-el-libro-mas-loco-que-he-escrito-una-conversacion-con-javier-cercas\/\">muy abierto a la cultura<\/a>, subray\u00f3 que la filosof\u00eda, la psicolog\u00eda, las ciencias humanas, la novela y la poes\u00eda pueden ayudar a los cat\u00f3licos a comprender mejor al hombre. Les invit\u00f3 a sumergirse en ellas, a no tener miedo de ampliar sus horizontes y, por ello, ser\u00e1 acusado de relativismo, un juicio injusto para un jesuita que rechazaba todo sincretismo.<\/p>\n\n\n\n<p>Por todas estas razones, Francisco ha sido, desde la India hasta Sud\u00e1frica, muy popular m\u00e1s all\u00e1 de las comunidades cristianas. \u00bfHa sido mejor comprendido y querido fuera o dentro de la Iglesia? A menudo ha sido percibido por los pueblos pobres como su defensor, incluso como el l\u00edder espiritual del \u00abSur global\u00bb.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">2 \u2014 La maquinaria diplom\u00e1tica del Vaticano: en el coraz\u00f3n del sistema Francisco<\/h2>\n\n\n\n<p>Si bien este papa no fue un maquiav\u00e9lico diplom\u00e1tico y estratega y a menudo decidi\u00f3 solo, estuvo bien rodeado de expertos competentes y dedicados: adem\u00e1s del cardenal Parolin y su c\u00edrculo m\u00e1s cercano de asesores, el brit\u00e1nico Paul Richard Gallagher fue su \u00abministro de Asuntos Exteriores\u00bb. Cabe mencionar tambi\u00e9n al cardenal Claudio Maria Celli para China o al \u00abjoven\u00bb cardenal Matteo Maria Zuppi para los asuntos humanitarios en el conflicto entre Rusia y Ucrania.<\/p>\n\n\n\n<p>El Estado m\u00e1s peque\u00f1o del planeta cuenta con una de las redes diplom\u00e1ticas m\u00e1s extensas del mundo: observador permanente en la ONU y en sus principales agencias, miembro de pleno derecho de la OSCE, representado por 120 embajadores y nuncios, con relaciones diplom\u00e1ticas con 184 Estados, el Vaticano mantiene una red impresionante y costosa que se caracteriza por su discreci\u00f3n y que, a trav\u00e9s de las di\u00f3cesis y las redes de C\u00e1ritas, dispone de un conocimiento \u00fanico del terreno que resulta \u00fatil para otros. S\u00f3lo trece pa\u00edses a\u00fan no han establecido relaciones diplom\u00e1ticas con la Santa Sede, entre ellos dos gigantes como China y Arabia Saud\u00ed.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Muy abierto a la cultura, destacaba que la filosof\u00eda, la psicolog\u00eda, las ciencias humanas, la novela y la poes\u00eda pueden ayudar a los cat\u00f3licos a comprender mejor al ser humano.<\/p><cite>Jean-Louis de la Vaissi\u00e8re<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Esta red le ha permitido y le sigue permitiendo intervenir en favor del libre ejercicio de la religi\u00f3n cristiana y de los derechos universales, as\u00ed como estar en contacto con numerosos medios de comunicaci\u00f3n, universidades y escuelas cat\u00f3licas que existen incluso all\u00ed donde los cristianos son minoritarios, formando a veces las \u00e9lites. Los nuncios pueden actuar, en nombre de Francisco, como mediadores en conflictos y guiar misiones delicadas destinadas a obtener la liberaci\u00f3n de prisioneros o rehenes. A veces, esto se mantiene en total secreto. El Vaticano se ha apoyado especialmente en Sant&#8217;Egidio, una comunidad de laicos cat\u00f3licos que lucha contra la pobreza y por la paz en el mundo y que cuenta con una excepcional agenda de contactos entre los movimientos rebeldes. Bajo Francisco, las reticencias del pasado hacia esta organizaci\u00f3n desaparecieron y la Secretar\u00eda de Estado trabaj\u00f3 codo con codo con Sant&#8217;Egidio.&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Los mundos de Francisco<\/h4>\n\n\n\n<h2 class=\"wp-block-heading\">3 \u2014 En las Am\u00e9ricas: mediaciones eficaces frente a la competencia de los evang\u00e9licos<\/h2>\n\n\n\n<p>Francisco, primer pont\u00edfice latinoamericano de la historia, se esforz\u00f3 por no parecer \u00abel papa latino\u00bb en Roma y por no centrarse demasiado en este continente que conoce de memoria y del que percibe todas las turbulencias y contradicciones. Del mismo modo, no volver\u00e1, como papa, a su pa\u00eds, Argentina. \u00bfQuiz\u00e1s huy\u00f3 del riesgo de un culto a la personalidad?&nbsp;<\/p>\n\n\n\n<p>Cuando a\u00fan era arzobispo en las conferencias del CELAM (Consejo Pontificio Latinoamericano), adopt\u00f3 una posici\u00f3n intermedia entre los progresistas, puestos a raya por Juan Pablo II y Benedicto XVI, y los conservadores. La dictadura de Videla en Argentina fue para \u00e9l un trauma revelador de los compromisos con los gobernantes y de las profundas divisiones entre los obispos.&nbsp;<\/p>\n\n\n\n<p>Trabaj\u00f3 por el acercamiento hist\u00f3rico entre Cuba y Estados Unidos. Tambi\u00e9n se moviliz\u00f3 por la reconciliaci\u00f3n en Colombia y por la democracia en Venezuela y Nicaragua, donde el r\u00e9gimen de Daniel Ortega oblig\u00f3 a los religiosos a exiliarse, llegando incluso a expulsar al nuncio.&nbsp;&nbsp;<\/p>\n\n\n\n<p>El auge de los protestantes evang\u00e9licos muy conservadores es uno de los grandes retos del catolicismo en todo el mundo, pero especialmente en Am\u00e9rica Latina y, en particular, en Brasil, donde los protestantes representan ya el 31% de la poblaci\u00f3n. Francisco se encontr\u00f3 con el mismo reto en Estados Unidos, donde los evang\u00e9licos y una parte de los cat\u00f3licos siguieron a Trump cuando este enarbol\u00f3 la bandera de la fe.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>S\u00f3lo trece pa\u00edses a\u00fan no han establecido relaciones diplom\u00e1ticas con la Santa Sede, entre ellos dos gigantes como China y Arabia Saud\u00ed.<\/p><cite>Jean-Louis de la Vaissi\u00e8re<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Si Francisco encontr\u00f3 aliados en Obama y Biden, hoy el vicepresidente James David Vance, un cat\u00f3lico muy conservador, se opone virulentamente a su l\u00ednea proinmigrante. Sin embargo, durante su viaje a Roma, <a href=\"https:\/\/legrandcontinent.eu\/es\/2025\/04\/18\/j-d-vance-en-el-vaticano-la-iglesia-frente-al-imperio-y-contra-el-separatismo-cristiano\/\">fue la \u00faltima autoridad pol\u00edtica de primer orden en reunirse con el papa<\/a>. Frente al d\u00fao Trump-Vance, el papa nombr\u00f3 en Washington a un cardenal, Robert McElroy, defensor de la inclusi\u00f3n y la acogida de los migrantes.&nbsp;&nbsp;<\/p>\n\n\n\n<p>En cuanto a la relaci\u00f3n con los ricos donantes estadounidenses que financian las obras caritativas de la Santa Sede, esta se ha visto afectada por su desconfianza hacia <em>Laudato si&#8217; <\/em>y el tema, incomprendido en suelo estadounidense, del decrecimiento.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">4 \u2014 Europa: una \u00ababuela\u00bb a la que hay que despertar<\/h2>\n\n\n\n<p>Con Europa se ha establecido una relaci\u00f3n parad\u00f3jica con este papa de ascendencia italiana, hasta el punto de que algunos franceses dir\u00e1n: \u00abeste Papa no nos quiere\u00bb. Sin duda, esto no es cierto, pero es un hecho que no ha visitado oficialmente ninguno de los grandes pa\u00edses europeos de tradici\u00f3n cat\u00f3lica, como Francia, Espa\u00f1a o Alemania.&nbsp;<\/p>\n\n\n\n<p>De ascendencia italiana, no comprend\u00eda bien a las antiguas naciones de tradici\u00f3n cristiana con sus disputas sectarias, y lamentaba cierto elitismo, una falta de entusiasmo y el olvido de la riqueza de su patrimonio espiritual. Estaba m\u00e1s alejado de Europa <a href=\"https:\/\/legrandcontinent.eu\/es\/2022\/12\/31\/muerte-de-benedicto-xvi-papa-emerito\/\">que Benedicto XVI<\/a>, aunque estaba muy impregnado de las culturas europeas y le gustaba citar a sus autores, hasta el fil\u00f3sofo Blaise Pascal.<\/p>\n\n\n\n<p>En Europa, Francisco tuvo enfrentamientos tanto con los tradicionalistas como con los progresistas alemanes que quer\u00edan modificar la doctrina en el pa\u00eds de Lutero. Se opuso a la ordenaci\u00f3n de las mujeres. Estos progresistas descubrieron de repente que no era el papa de izquierdas que hab\u00edan imaginado.<\/p>\n\n\n\n<p>Ante el Parlamento Europeo, Francisco exhort\u00f3 a la \u00ababuela\u00bb Europa, anta\u00f1o lugar de expansi\u00f3n del cristianismo, reservorio de santos y te\u00f3logos, ahora envejecida y encerrada en s\u00ed misma, a un despertar moral\u2026 y demogr\u00e1fico.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">5 \u2014 En \u00c1frica: paz, dignidad y malentendidos<\/h2>\n\n\n\n<p>En este continente, que por el contrario est\u00e1 experimentando un fuerte crecimiento demogr\u00e1fico y registra el mayor aumento de cat\u00f3licos, multitudes inmensas y j\u00f3venes acud\u00edan cada vez a escuchar su mensaje de paz.<\/p>\n\n\n\n<p>Desde la Rep\u00fablica Centroafricana hasta Uganda y la Rep\u00fablica Democr\u00e1tica del Congo, su forma de se\u00f1alar los problemas concretos y de escuchar atentamente los testimonios de las v\u00edctimas de violaciones masivas y guerras internas conquist\u00f3 los corazones. Anim\u00f3 a los obispos y a las fuerzas vivas de la Iglesia a tomar posici\u00f3n pol\u00edticamente contra las injusticias y la corrupci\u00f3n, a trabajar, junto con las m\u00faltiples asociaciones cat\u00f3licas, contra las divisiones tribales y la esclavitud moderna. En la Rep\u00fablica Centroafricana, y en particular en la Rep\u00fablica Democr\u00e1tica del Congo, la Iglesia se implic\u00f3 as\u00ed en los procesos de transici\u00f3n democr\u00e1tica.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Francisco trabaj\u00f3 personalmente en algunas mediaciones: as\u00ed ocurri\u00f3 en 2019, cuando el presidente de Sud\u00e1n del Sur, Salvi Kiir, y el l\u00edder rebelde \u2014desde entonces vicepresidente\u2014 Riek Machar, fueron invitados al Vaticano para hacer un \u00abretiro\u00bb con el fin de emprender el camino de la paz.<\/p>\n\n\n\n<p>Pero una crisis ensombreci\u00f3 este acuerdo entre el papa y los africanos.<\/p>\n\n\n\n<p>La declaraci\u00f3n <em>Fiducia Supplicans<\/em> de 2024, que propon\u00eda una bendici\u00f3n no sacramental a las parejas no casadas, incluidas las homosexuales, fue totalmente incomprendida, hasta el punto de que el cardenal de Kinshasa, Fridolin Ambongo, que preside la conferencia episcopal del continente, la rechaz\u00f3 de plano. El papa accedi\u00f3 a que <em>Fiducia Supplicans<\/em> no se dirigiera a los africanos, pero esta rebeli\u00f3n conservadora contra lo que se percibi\u00f3 como una problem\u00e1tica occidental \u2014y que se suma a la lucha del muy conservador cardenal guineano Robert Sarah, muy popular en Francia por sus duras posiciones sobre estas cuestiones\u2014 marc\u00f3 la relaci\u00f3n del Vaticano con \u00c1frica durante su pontificado.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Ante el Parlamento Europeo, Francisco exhort\u00f3 a la \u00ababuela\u00bb Europa, anta\u00f1o lugar de expansi\u00f3n del cristianismo, reservorio de santos y te\u00f3logos, ahora envejecida y encerrada en s\u00ed misma, a un despertar moral\u2026 y demogr\u00e1fico.<\/p><cite>Jean-Louis de la Vaissi\u00e8re<\/cite><\/blockquote><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">6 \u2014 Apoyar la presencia cristiana en Oriente Pr\u00f3ximo y Oriente Medio<\/h2>\n\n\n\n<p>Para Oriente Pr\u00f3ximo y Oriente Medio, el momento m\u00e1s emotivo de los a\u00f1os de Francisco fue su visita a Irak, cuna de la Biblia. Un viaje marcado, en particular, por su encuentro con el ayatol\u00e1 Ali Husseini al-Sistani, l\u00edder espiritual de los chi\u00edtas iraqu\u00edes, algo nunca visto.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Tambi\u00e9n perpetu\u00f3 con numerosos gestos la especial atenci\u00f3n de los papas por el L\u00edbano, \u00abpa\u00eds mensaje\u00bb \u2014seg\u00fan la f\u00f3rmula de Juan Pablo II\u2014 con sus dieciocho confesiones religiosas. Un mensaje que hoy se encuentra en grandes dificultades.&nbsp;<\/p>\n\n\n\n<p>La tragedia siria perturbar\u00e1 su pontificado, ya que Francisco se mostr\u00f3 hostil a una intervenci\u00f3n occidental en 2013 contra el r\u00e9gimen de Bashar al-Assad tras el ataque con gas sar\u00edn en el barrio de Guta, en Damasco. El papa mantuvo permanentemente un nuncio en Damasco, no por simpat\u00eda hacia el dictador, sino para proteger a los cristianos. La idea central de la diplomacia vaticana en Siria era mantener el di\u00e1logo con el r\u00e9gimen y estar presente sobre el terreno, lo m\u00e1s cerca posible de las comunidades.<\/p>\n\n\n\n<p>En cuanto al conflicto israel\u00ed-palestino, puso de manifiesto \u2014volveremos sobre ello\u2014 el margen de maniobra cada vez m\u00e1s reducido del papa y de la Santa Sede en Tierra Santa, donde los cristianos son cada vez menos numerosos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">7 \u2014 Asia, continente de todas las promesas<\/h2>\n\n\n\n<p>Es sabido que, en su juventud, Francisco so\u00f1aba con ser misionero en Jap\u00f3n. A menudo elogi\u00f3 una peque\u00f1a iglesia de las catacumbas que, en Nagasaki, sobrevivi\u00f3 sin sacerdote durante siglos durante la era Edo.<\/p>\n\n\n\n<p>Asia represent\u00f3 para Francisco el continente del futuro, donde los cat\u00f3licos, aunque minoritarios, avanzan constantemente. Fue recibido triunfalmente en Filipinas, Corea del Sur, Timor, <a href=\"https:\/\/legrandcontinent.eu\/es\/2024\/09\/06\/el-papa-entre-los-papues-10-puntos-sobre-la-visita-del-papa-francisco-a-papua-nueva-guinea\/\">Pap\u00faa Nueva Guinea<\/a>&#8230; Lleg\u00f3 hasta <a href=\"https:\/\/legrandcontinent.eu\/es\/2025\/04\/20\/el-papa-francisco-es-el-loco-de-dios-por-antonomasia-y-este-es-el-libro-mas-loco-que-he-escrito-una-conversacion-con-javier-cercas\/\">Mongolia<\/a>, donde s\u00f3lo hay mil cat\u00f3licos y donde el prefecto apost\u00f3lico de Ul\u00e1n Bator, Giorgio Marengo, se convirti\u00f3 en el cardenal m\u00e1s joven. A Francisco le gustaban estas Iglesias porque reclutaban en los c\u00edrculos m\u00e1s pobres.<\/p>\n\n\n\n<p>La hostilidad contra las minor\u00edas cristianas en tierra isl\u00e1mica no pas\u00f3 desapercibida para el papa, que moviliz\u00f3 sus servicios para que la cristiana Asia Bibi, condenada a muerte por blasfemia en Pakist\u00e1n, pudiera abandonar su pa\u00eds.<\/p>\n\n\n\n<p>Queda China.&nbsp;<\/p>\n\n\n\n<p>Si bien eran bien conocidos el sue\u00f1o de su evangelizaci\u00f3n y la fascinaci\u00f3n personal de Francisco por el Imperio Medio, hay que reconocer que el objetivo no se alcanz\u00f3 realmente.&nbsp;<\/p>\n\n\n\n<p>Los esfuerzos de acercamiento hab\u00edan comenzado antes de \u00e9l. Pero fue durante su pontificado, en 2018, cuando se firm\u00f3 un \u00abacuerdo provisional\u00bb entre Pek\u00edn y la Santa Sede que preve\u00eda el nombramiento de com\u00fan acuerdo de los obispos, con el fin de que los cat\u00f3licos chinos dejaran de estar divididos entre la Iglesia clandestina y la Iglesia oficial. Este acuerdo se ha renovado tres veces, en 2020, 2022 y 2024.<\/p>\n\n\n\n<p>Admirador del misionero jesuita Matteo Ricci, fallecido en Pek\u00edn en 1610 y precursor de la inculturaci\u00f3n del cristianismo en las realidades locales, Jorge Bergoglio so\u00f1aba con conocer a los cerca de 12 millones de cat\u00f3licos chinos. El cardenal Parolin calific\u00f3 en una ocasi\u00f3n el acuerdo de 2018 como \u00abel menos malo posible\u00bb, lo que lo dice todo sobre la satisfacci\u00f3n que hab\u00eda en Roma. Porque algunos obispos siguen siendo nombrados sin el acuerdo de la Santa Sede. Y el anciano cardenal de Hong Kong Joseph Zen, partidario del movimiento prodemocr\u00e1tico y de una l\u00ednea dura con Pek\u00edn, acus\u00f3 abiertamente a Francisco de \u00abcapitulaci\u00f3n\u00bb ante el r\u00e9gimen comunista.<\/p>\n\n\n\n<p>Para unos, el acuerdo de 2018 permiti\u00f3 a los cat\u00f3licos practicar m\u00e1s libremente su fe; para otros, la Santa Sede cedi\u00f3 ingenuamente a Xi Jinping con la esperanza de una gran expansi\u00f3n del cristianismo. Minimiz\u00f3 los peligros de la \u00absinizaci\u00f3n\u00bb de las religiones y de una relectura ideol\u00f3gicamente correcta de los textos de la Biblia.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Jorge Bergoglio so\u00f1aba con ir a conocer a los cerca de 12 millones de cat\u00f3licos chinos.<\/p><cite>Jean-Louis de la Vaissi\u00e8re<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Durante <a href=\"https:\/\/legrandcontinent.eu\/es\/2025\/04\/20\/el-papa-francisco-es-el-loco-de-dios-por-antonomasia-y-este-es-el-libro-mas-loco-que-he-escrito-una-conversacion-con-javier-cercas\/\">su viaje a Mongolia en 2024<\/a>, Francisco dirigi\u00f3 esta sorprendente recomendaci\u00f3n a los cat\u00f3licos chinos, dejando entrever lo delicada que segu\u00eda siendo su situaci\u00f3n: \u00abPido a los cat\u00f3licos chinos que sean buenos cristianos y buenos ciudadanos\u00bb.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Dos guerras, dos pruebas<\/h4>\n\n\n\n<h2 class=\"wp-block-heading\">8 \u2014 El Papa entre Israel y los palestinos: la palabra imposible<\/h2>\n\n\n\n<p>La relaci\u00f3n de la Santa Sede con Israel y Palestina siempre ha estado en una l\u00ednea muy delicada.<\/p>\n\n\n\n<p>Despu\u00e9s de detenerse a rezar en 2014 ante el muro de separaci\u00f3n cerca de Bel\u00e9n, Francisco invit\u00f3 a Shimon Peres y Mahmoud Abbas a plantar un olivo de la paz en los jardines del Vaticano. A\u00fan quedaba la esperanza de una paz entre dos Estados. Cuando en 2015 se firm\u00f3 un acuerdo global con la Autoridad Palestina, percibido por los palestinos como el reconocimiento de su Estado, no fue bien recibido en Tel Aviv.<\/p>\n\n\n\n<p>Desde la masacre del 7 de octubre de 2023, las relaciones entre la Santa Sede e Israel se hab\u00edan vuelto cada vez m\u00e1s dif\u00edciles.<\/p>\n\n\n\n<p>Al papa se le reproch\u00f3, en particular, haber tardado en expresar su horror ante la masacre perpetrada por Ham\u00e1s.&nbsp;<\/p>\n\n\n\n<p>Al mismo tiempo, los esfuerzos de la Iglesia para aliviar el sufrimiento de los habitantes de Gaza nunca cesaron. El patriarca latino de Jerusal\u00e9n, Gianbattista Pizzaballa, envi\u00f3 ayuda a la poblaci\u00f3n de Gaza. Y Francisco llam\u00f3 d\u00eda tras d\u00eda, incluso recientemente desde su lecho de hospital, al p\u00e1rroco de Gaza Gabriel Romanelli, argentino como \u00e9l.<\/p>\n\n\n\n<p>El papa hab\u00eda denunciado \u00abla arrogancia del invasor\u00bb en Palestina y expresado su emoci\u00f3n por \u00ablos ni\u00f1os acribillados\u00bb de Gaza. Estas repetidas condenas de los bombardeos israel\u00edes \u2014aunque Francisco reiter\u00f3 su reprobaci\u00f3n de la masacre del 7 de octubre\u2014 habr\u00e1n acentuado en Israel la idea de un sesgo pro\u00e1rabe del papa.&nbsp;<\/p>\n\n\n\n<p>\u00abLas cr\u00edticas s\u00f3lo deber\u00edan dirigirse a los terroristas, no a la democracia que se defiende frente a ellos. Hay que acabar con la condena del Estado hebreo\u00bb, hab\u00eda criticado secamente el Ministerio de Asuntos Exteriores israel\u00ed. Esta reacci\u00f3n recordaba las acusaciones de antijuda\u00edsmo que hab\u00edan lastrado las relaciones entre la Santa Sede e Israel tras su fundaci\u00f3n en 1948.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Desde la masacre del 7 de octubre de 2023, las relaciones entre la Santa Sede e Israel se hab\u00edan vuelto cada vez m\u00e1s dif\u00edciles.<\/p><cite>Jean-Louis de la Vaissi\u00e8re<\/cite><\/blockquote><\/figure>\n\n\n\n<p>En un libro de entrevistas, <em>La esperanza no defrauda nunca<\/em>, recomendaba un estudio \u00abminucioso\u00bb para determinar si la situaci\u00f3n en el enclave asediado \u00abse ajustaba a la definici\u00f3n t\u00e9cnica\u00bb de genocidio.&nbsp; As\u00ed, la vieja sospecha de antijuda\u00edsmo pod\u00eda resurgir, aunque Francisco \u2014al igual que Juan Pablo II y Benedicto XVI\u2014 no puede ser acusado de antisemitismo ni de antijuda\u00edsmo, habiendo demostrado con numerosos gestos contundentes todo lo contrario.&nbsp;<\/p>\n\n\n\n<p>Desde la llegada al poder del Gobierno de Netanyahu y el auge de los sionistas extremistas, se han multiplicado los incidentes anticristianos. Los cristianos son objeto de humillaciones y presiones inmobiliarias por parte de los jud\u00edos ortodoxos en Jerusal\u00e9n. Pero la postura del Vaticano, que ha defendido constantemente la soluci\u00f3n de dos Estados y ha pedido un estatus internacional para los lugares sagrados de Jerusal\u00e9n, ha sido cada vez m\u00e1s inaudible, y el margen del Vaticano para actuar como mediador es pr\u00e1cticamente nulo.<\/p>\n\n\n\n<p>En este sentido, lo que ha sido cierto para Francisco lo seguir\u00e1 siendo sin duda para su sucesor.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">9 \u2014 Sobre la guerra de Ucrania, intervenciones criticadas<\/h2>\n\n\n\n<p>Al afirmar que hab\u00eda que \u00abtener el valor de negociar\u00bb con todas las partes beligerantes, el pacifismo radical del papa Francisco se manifest\u00f3 en el conflicto ucraniano y le vali\u00f3 cr\u00edticas. Sin embargo, calificarlo de pont\u00edfice \u00abmuniqu\u00e9s\u00bb ser\u00eda demasiado simplista: simplemente se mantuvo fiel a la exhortaci\u00f3n evang\u00e9lica \u00abbienaventurados los pacificadores\u00bb.&nbsp;<\/p>\n\n\n\n<p>Al d\u00eda siguiente de la agresi\u00f3n, se apresur\u00f3 a acudir a la embajada rusa ante la Santa Sede para abogar por su cese inmediato. Un episodio que dice mucho de su forma de actuar, a la vez emotiva y en\u00e9rgica.<\/p>\n\n\n\n<p>El papa tard\u00f3 en se\u00f1alar al agresor, dando la impresi\u00f3n de que pon\u00eda a Mosc\u00fa y Kiev en el mismo saco. Algunas declaraciones causaron m\u00e1s esc\u00e1ndalo que otras, incluso en la Iglesia greco-cat\u00f3lica ucraniana, sobre todo cuando exhort\u00f3 a los soldados del pa\u00eds agredido a \u00abizar la bandera blanca\u00bb.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Preocupado por llevar a buen t\u00e9rmino el laborioso camino del di\u00e1logo con la Iglesia ortodoxa rusa, Francisco <a href=\"https:\/\/legrandcontinent.eu\/es\/2022\/03\/08\/la-guerra-santa-de-putin\/\">tard\u00f3 en distanciarse de Kirill<\/a>, exagente del KGB y gran apoyo de Putin. Este acercamiento ecum\u00e9nico, iniciado con un encuentro en Cuba en 2015, era un reto considerable para Francisco, ya que el patriarcado de Mosc\u00fa representa geogr\u00e1ficamente la parte m\u00e1s importante de la ortodoxia. Tras mantener un di\u00e1logo de sordos por videoconferencia con \u00e9l en 2022, Francisco necesit\u00f3 tiempo para llegar a la conclusi\u00f3n de que \u00abel patriarca no puede convertirse en el monaguillo de Putin\u00bb y criticar \u00abla instrumentalizaci\u00f3n de lo sagrado\u00bb. Un vago proyecto de cumbre entre Francisco y Kirill qued\u00f3 aplazado <em>sine die<\/em>.<\/p>\n\n\n\n<p>Al igual que en Oriente Pr\u00f3ximo, la acci\u00f3n humanitaria de la Santa Sede, a pesar de la desconfianza, ha sido real y consistente. As\u00ed, favoreci\u00f3 el intercambio de prisioneros y el regreso de 388 ni\u00f1os ucranianos llevados a la fuerza a Rusia.<\/p>\n\n\n\n<p>Convencido de que Kiev no pod\u00eda ganar con fuerzas desiguales, el Vaticano abog\u00f3 por \u00abnegociaciones honestas\u00bb y \u00abcompromisos honorables\u00bb, sugiriendo mediadores neutrales, como Turqu\u00eda. \u00abNegociar no es un signo de debilidad, sino de valent\u00eda\u00bb, repet\u00edan el Papa y el cardenal Parolin: Volod\u00edmir Zelinski hab\u00eda rechazado en\u00e9rgicamente \u00abuna mediaci\u00f3n virtual entre alguien que quiere vivir y alguien que quiere destruirte\u00bb.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>El sucesor de Pedro se burlaba de los defectos del clericalismo en su propia Iglesia, y parte del clero se lo reproch\u00f3 amargamente.\u00a0<\/p><cite>Jean-Louis de la Vaissi\u00e8re<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Otros \u00abdeslices\u00bb no mejoraron las cosas en el V\u00eda Crucis en el Coliseo, como una madre rusa y una madre ucraniana llevando juntas la cruz, o un elogio ante estudiantes rusos de \u00abla gran Rusia\u00bb de los zares; una cr\u00edtica a Occidente, en la l\u00ednea del discurso del Kremlin, fustigando los \u00abladridos de la OTAN a las puertas de Rusia\u00bb; su emoci\u00f3n expresada tras un atentado en Mosc\u00fa contra la hija de Alexander Dugin, un ultranacionalista partidario de la agresi\u00f3n rusa\u2026<\/p>\n\n\n\n<p>Con el tiempo, Francisco acab\u00f3 reconociendo una \u00abagresi\u00f3n militar a gran escala\u00bb contra \u00abla martirizada Ucrania\u00bb.<\/p>\n\n\n\n<p>Aunque en un momento dado expres\u00f3 su deseo de visitar el pa\u00eds, muchos ucranianos no estaban dispuestos a recibirlo. En Kiev se afirmaba incluso que la Santa Sede \u00abno hab\u00eda aprendido las lecciones\u00bb de la Segunda Guerra Mundial, en referencia a P\u00edo XII, que no se posicion\u00f3 firmemente contra el nazismo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">10 \u2014 Continuidad diplom\u00e1tica o geopol\u00edtica revolucionaria<\/h2>\n\n\n\n<p>Las palabras directas de Francisco fueron tan diferentes del \u00ablenguaje diplom\u00e1tico\u00bb del Vaticano que este papa, marcado por el peronismo, fue tildado de populista e impredecible.<\/p>\n\n\n\n<p>Un pontificado confuso, p\u00e9rdida de referencias, pasos adelante y pasos atr\u00e1s, alejamiento de la firmeza doctrinal de sus predecesores: estas fueron algunas de las cr\u00edticas.&nbsp;<\/p>\n\n\n\n<p>Fran\u00e7ois Mabille, en una reciente entrevista en <em>Le Monde<\/em>, se preguntaba incluso por \u00abuna diplomacia cercana a la de Trump\u00bb, \u00abuna diplomacia de la connivencia\u00bb por el simple hecho de haber aceptado hablar con Putin o Bashar al-Assad. El papa argentino habr\u00eda as\u00ed frustrado en m\u00e1s de una ocasi\u00f3n los esfuerzos de la diplomacia m\u00e1s discreta del microestado que dirig\u00eda. Sin embargo, aparte de la impulsividad, una man\u00eda por sacudir el orden diplom\u00e1tico establecido para hacer surgir nuevas soluciones, nada une a Francisco y Trump. Por sus convicciones m\u00e1s arraigadas, Francisco fue el anti-Trump por excelencia.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Desde 1978 se sucedieron tres fases: el papado extremadamente popular de Juan Pablo II, que inaugur\u00f3 las Jornadas Mundiales de la Juventud y transmiti\u00f3 mensajes contundentes sobre los derechos fundamentales y la democracia. Un peso geopol\u00edtico real, que contribuy\u00f3 a la ca\u00edda del Tel\u00f3n de Acero. Luego vino la de <a href=\"https:\/\/legrandcontinent.eu\/es\/2022\/12\/31\/muerte-de-benedicto-xvi-papa-emerito\/\">Benedicto XVI, brillante te\u00f3logo, pero secreto y t\u00edmido<\/a>. Un per\u00edodo de repliegue, tensiones y malentendidos con los musulmanes. Por \u00faltimo, lleg\u00f3 la era de Francisco, un papa cercano, que se dirigi\u00f3 a las multitudes de una manera diferente a la de Juan Pablo II.&nbsp;<\/p>\n\n\n\n<p>Con el papa Francisco, se ha producido un acercamiento indudable entre los pueblos y una Iglesia m\u00e1s accesible, menos vertical y m\u00e1s sinodal. Aunque este pontificado se ha topado con las artima\u00f1as de los poderosos. Aunque ha estado marcado por fracasos, abandonos y, en ocasiones, enredos. Como, por ejemplo, en el caso de Nagorno Karabaj: los armenios, pueblo cristiano, se sintieron muy decepcionados por la d\u00e9bil reacci\u00f3n de la Santa Sede ante la expulsi\u00f3n de 100.000 habitantes de este territorio del C\u00e1ucaso el a\u00f1o pasado. \u00bfSer\u00edan las presiones del r\u00e9gimen de Bak\u00fa, la proximidad de Azerbaiy\u00e1n a Turqu\u00eda y las donaciones que este pa\u00eds ha hecho al Vaticano las causas de esta amarga p\u00edldora?<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Por sus convicciones m\u00e1s arraigadas, Francisco fue el anti-Trump por excelencia.\u00a0\u00a0<\/p><cite>Jean-Louis de la Vaissi\u00e8re<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Francisco no era el carism\u00e1tico \u00abatleta de Dios\u00bb que era Juan Pablo II. Adem\u00e1s, no le gustaban los honores, criticaba a los \u00abobispos de aeropuerto\u00bb y prefer\u00eda visitar prisiones, hospicios y barrios marginales, hablar con la gente humilde. El sucesor de Pedro se burlaba de los defectos del clericalismo en su propia Iglesia, y parte del clero se lo reproch\u00f3 amargamente.<\/p>\n\n\n\n<p>Un ejemplo caracter\u00edstico de sus preferencias proviene de la actualidad reciente en Francia, en oto\u00f1o de 2024.<\/p>\n\n\n\n<p>Francisco fue a C\u00f3rcega para pasar un d\u00eda en esta peque\u00f1a isla donde la devoci\u00f3n cristiana sigue muy viva. A sus 88 a\u00f1os, se sent\u00eda como en casa, feliz. Se notaba en sus palabras, en su rostro. Diez d\u00edas antes no hab\u00eda querido acudir a la reapertura de Notre-Dame de Par\u00eds, en medio de los jefes de Estado. Para quienes lo conoc\u00edan, era evidente: no le gustaba mezclar la pol\u00edtica y la religi\u00f3n.&nbsp;<\/p>\n\n\n\n<p>Al desacralizar su funci\u00f3n, Francisco \u2014que, por otra parte, ten\u00eda una forma autoritaria de gobernar\u2014 fue acusado de hacer perder prestigio al papado y de debilitar la unidad de la Iglesia. La rigidez, el arribismo, las intrigas, la jerarqu\u00eda, las mundanidades, la ambici\u00f3n y los honores eran para \u00e9l trampas mortales, las famosas \u00abenfermedades de la Curia\u00bb.<\/p>\n\n\n\n<p>Sin duda, un error de este papa \u2014que se reconoc\u00eda constantemente \u00abpecador\u00bb\u2014 fue haber confiado a los medios de comunicaci\u00f3n, bajo el impulso de la emoci\u00f3n, m\u00e1s de lo que deb\u00eda decir. Sus numerosas declaraciones a veces sembraron la confusi\u00f3n, incluso en el propio Vaticano, lo que en ocasiones requiri\u00f3 aclaraciones. Pero este aspecto negativo se ve compensado por sus numerosos ba\u00f1os de multitudes y sus gestos contundentes y emp\u00e1ticos.&nbsp;<\/p>\n\n\n\n<p>Muchos en todo el mundo, tanto cat\u00f3licos como no cat\u00f3licos, lo recordar\u00e1n, y Francisco seguir\u00e1 siendo el papa que supo hablar a todo el mundo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfSale debilitado o reforzado el poder blando de la Santa Sede tras los doce a\u00f1os del primer papa latinoamericano en el trono de Pedro?\u00a0<\/p>\n<p>Jean-Louis de la Vaissi\u00e8re, que lo ha seguido para la AFP en Roma, hace un balance en 10 puntos de un pontificado con un nuevo estilo diplom\u00e1tico \u2014atravesado por las grandes crisis geopol\u00edticas del siglo\u2014.<\/p>\n","protected":false},"author":1366,"featured_media":64299,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-studies.php","format":"standard","meta":{"_acf_changed":true,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":24,"footnotes":""},"categories":[616],"tags":[],"staff":[1064],"editorial_format":[1469],"serie":[],"audience":[],"geo":[198],"class_list":["post-64296","post","type-post","status-publish","format-standard","hentry","category-in-memoriam","staff-jean-louis-de-la-vaissiere","editorial_format-estudios","geo-mundo"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":64299,"excerpt":"\u00bfSale debilitado o reforzado el poder blando de la Santa Sede tras los doce a\u00f1os del primer papa latinoamericano en el trono de Pedro?\u00a0\r\n\r\nJean-Louis de la Vaissi\u00e8re, que lo ha seguido para la AFP en Roma, hace un balance en 10 puntos de un pontificado con un nuevo estilo diplom\u00e1tico \u2014atravesado por las grandes crisis geopol\u00edticas del siglo\u2014.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Geopol\u00edtica del papa Francisco: de Ucrania a las periferias, 10 puntos sobre su balance internacional - El Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/es\/2025\/04\/21\/geopolitica-del-papa-francisco-de-ucrania-a-las-periferias-10-puntos-sobre-su-balance-internacional\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Geopol\u00edtica del papa Francisco: de Ucrania a las periferias, 10 puntos sobre su balance internacional - El Grand Continent\" \/>\n<meta property=\"og:description\" content=\"\u00bfSale debilitado o reforzado el poder blando de la Santa Sede tras los doce a\u00f1os del primer papa latinoamericano en el trono de Pedro?\u00a0  Jean-Louis de la Vaissi\u00e8re, que lo ha seguido para la AFP en Roma, hace un balance en 10 puntos de un pontificado con un nuevo estilo diplom\u00e1tico \u2014atravesado por las grandes crisis geopol\u00edticas del siglo\u2014.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/es\/2025\/04\/21\/geopolitica-del-papa-francisco-de-ucrania-a-las-periferias-10-puntos-sobre-su-balance-internacional\/\" \/>\n<meta property=\"og:site_name\" content=\"El Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-21T11:37:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-21T11:37:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/04\/gc-elpapa-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"florent\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/04\/gc-elpapa-1-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"florent\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"24 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/04\/21\/geopolitica-del-papa-francisco-de-ucrania-a-las-periferias-10-puntos-sobre-su-balance-internacional\/\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/2025\/04\/21\/geopolitica-del-papa-francisco-de-ucrania-a-las-periferias-10-puntos-sobre-su-balance-internacional\/\",\"name\":\"Geopol\u00edtica del papa Francisco: de Ucrania a las periferias, 10 puntos sobre su balance internacional - El Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/04\/21\/geopolitica-del-papa-francisco-de-ucrania-a-las-periferias-10-puntos-sobre-su-balance-internacional\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/04\/21\/geopolitica-del-papa-francisco-de-ucrania-a-las-periferias-10-puntos-sobre-su-balance-internacional\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/04\/SIPA_ap22671531_000006-scaled-1.jpg\",\"datePublished\":\"2025-04-21T11:37:43+00:00\",\"dateModified\":\"2025-04-21T11:37:48+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/04\/21\/geopolitica-del-papa-francisco-de-ucrania-a-las-periferias-10-puntos-sobre-su-balance-internacional\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/es\/2025\/04\/21\/geopolitica-del-papa-francisco-de-ucrania-a-las-periferias-10-puntos-sobre-su-balance-internacional\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/04\/21\/geopolitica-del-papa-francisco-de-ucrania-a-las-periferias-10-puntos-sobre-su-balance-internacional\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/04\/SIPA_ap22671531_000006-scaled-1.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/04\/SIPA_ap22671531_000006-scaled-1.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"El papa Francisco, a bordo de su papam\u00f3vil, atraviesa la multitud de fieles al t\u00e9rmino de la misa cat\u00f3lica del Domingo de Pascua, que ha celebrado en la plaza de San Pedro del Vaticano, el domingo 17 de abril de 2022. Para muchos cristianos, este fin de semana supone la primera vez en tres a\u00f1os que se re\u00fanen en persona para celebrar el Domingo de Pascua.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/04\/21\/geopolitica-del-papa-francisco-de-ucrania-a-las-periferias-10-puntos-sobre-su-balance-internacional\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/legrandcontinent.eu\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Geopol\u00edtica del papa Francisco: de Ucrania a las periferias, 10 puntos sobre su balance internacional\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/\",\"name\":\"El Grand Continent\",\"description\":\"La escala pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\",\"name\":\"florent\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"caption\":\"florent\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Geopol\u00edtica del papa Francisco: de Ucrania a las periferias, 10 puntos sobre su balance internacional - El Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/es\/2025\/04\/21\/geopolitica-del-papa-francisco-de-ucrania-a-las-periferias-10-puntos-sobre-su-balance-internacional\/","og_locale":"es_ES","og_type":"article","og_title":"Geopol\u00edtica del papa Francisco: de Ucrania a las periferias, 10 puntos sobre su balance internacional - El Grand Continent","og_description":"\u00bfSale debilitado o reforzado el poder blando de la Santa Sede tras los doce a\u00f1os del primer papa latinoamericano en el trono de Pedro?\u00a0  Jean-Louis de la Vaissi\u00e8re, que lo ha seguido para la AFP en Roma, hace un balance en 10 puntos de un pontificado con un nuevo estilo diplom\u00e1tico \u2014atravesado por las grandes crisis geopol\u00edticas del siglo\u2014.","og_url":"https:\/\/legrandcontinent.eu\/es\/2025\/04\/21\/geopolitica-del-papa-francisco-de-ucrania-a-las-periferias-10-puntos-sobre-su-balance-internacional\/","og_site_name":"El Grand Continent","article_published_time":"2025-04-21T11:37:43+00:00","article_modified_time":"2025-04-21T11:37:48+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/04\/gc-elpapa-1-scaled.jpg","type":"image\/jpeg"}],"author":"florent","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/04\/gc-elpapa-1-scaled.jpg","twitter_misc":{"Escrito por":"florent","Tiempo de lectura":"24 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/es\/2025\/04\/21\/geopolitica-del-papa-francisco-de-ucrania-a-las-periferias-10-puntos-sobre-su-balance-internacional\/","url":"https:\/\/legrandcontinent.eu\/es\/2025\/04\/21\/geopolitica-del-papa-francisco-de-ucrania-a-las-periferias-10-puntos-sobre-su-balance-internacional\/","name":"Geopol\u00edtica del papa Francisco: de Ucrania a las periferias, 10 puntos sobre su balance internacional - El Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/es\/2025\/04\/21\/geopolitica-del-papa-francisco-de-ucrania-a-las-periferias-10-puntos-sobre-su-balance-internacional\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/es\/2025\/04\/21\/geopolitica-del-papa-francisco-de-ucrania-a-las-periferias-10-puntos-sobre-su-balance-internacional\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/04\/SIPA_ap22671531_000006-scaled-1.jpg","datePublished":"2025-04-21T11:37:43+00:00","dateModified":"2025-04-21T11:37:48+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/es\/2025\/04\/21\/geopolitica-del-papa-francisco-de-ucrania-a-las-periferias-10-puntos-sobre-su-balance-internacional\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/es\/2025\/04\/21\/geopolitica-del-papa-francisco-de-ucrania-a-las-periferias-10-puntos-sobre-su-balance-internacional\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/2025\/04\/21\/geopolitica-del-papa-francisco-de-ucrania-a-las-periferias-10-puntos-sobre-su-balance-internacional\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/04\/SIPA_ap22671531_000006-scaled-1.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/04\/SIPA_ap22671531_000006-scaled-1.jpg","width":2560,"height":1707,"caption":"El papa Francisco, a bordo de su papam\u00f3vil, atraviesa la multitud de fieles al t\u00e9rmino de la misa cat\u00f3lica del Domingo de Pascua, que ha celebrado en la plaza de San Pedro del Vaticano, el domingo 17 de abril de 2022. Para muchos cristianos, este fin de semana supone la primera vez en tres a\u00f1os que se re\u00fanen en persona para celebrar el Domingo de Pascua."},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/es\/2025\/04\/21\/geopolitica-del-papa-francisco-de-ucrania-a-las-periferias-10-puntos-sobre-su-balance-internacional\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legrandcontinent.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Geopol\u00edtica del papa Francisco: de Ucrania a las periferias, 10 puntos sobre su balance internacional"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/es\/#website","url":"https:\/\/legrandcontinent.eu\/es\/","name":"El Grand Continent","description":"La escala pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c","name":"florent","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","caption":"florent"}}]}},"lgc_categories":[{"id":616,"name":"In Memoriam","slug":"in-memoriam"}],"lgc_author":{"id":1064,"name":"Jean-Louis de la Vaissi\u00e8re","slug":"jean-louis-de-la-vaissiere","description":"Jean-Louis de la Vaissi\u00e8re es periodista, corresponsal de la AFP en Roma.\r\n","first_name":"Jean-Louis ","last_name":"de la Vaissi\u00e8re","picture":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/02\/jean-louis-de-la-vaissiere-copie.png","width":674,"height":674,"alt":""}},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/04\/SIPA_ap22671531_000006-scaled-1.jpg","width":2560,"height":1707,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/04\/SIPA_ap22671531_000006-scaled-1.jpg","width":2560,"height":1707,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/64296","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/users\/1366"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/comments?post=64296"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/64296\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media\/64299"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media?parent=64296"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/categories?post=64296"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/tags?post=64296"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/staff?post=64296"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/editorial_format?post=64296"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/serie?post=64296"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/audience?post=64296"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/geo?post=64296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}