{"id":62909,"date":"2025-04-05T07:00:00","date_gmt":"2025-04-05T05:00:00","guid":{"rendered":"https:\/\/legrandcontinent.eu\/es\/?p=62909"},"modified":"2025-04-04T23:41:24","modified_gmt":"2025-04-04T21:41:24","slug":"en-estados-unidos-la-oposicion-a-trump-organiza-su-mayor-movilizacion-desde-el-20-de-enero","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/es\/2025\/04\/05\/en-estados-unidos-la-oposicion-a-trump-organiza-su-mayor-movilizacion-desde-el-20-de-enero\/","title":{"rendered":"En Estados Unidos, la oposici\u00f3n a Trump organiza su mayor movilizaci\u00f3n desde el 20 de enero"},"content":{"rendered":"\n<p>La oposici\u00f3n dem\u00f3crata a las acciones de la administraci\u00f3n Trump ha sido en gran medida inaudible desde la investidura del presidente estadounidense el pasado 20 de enero. Sin mayor\u00eda en el Congreso ni figura de consenso entre el electorado, el Partido ha sido objeto durante varias semanas de luchas internas entre una retaguardia que se presenta como moderada, deseosa de trabajar con el Partido Republicano en ciertos temas, y una nueva generaci\u00f3n que aspira a una postura m\u00e1s combativa.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/IIZBp\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>La primera gran oposici\u00f3n a Trump, \u00abHands Off!\u00bb, que hoy organiza m\u00e1s de 1.100 m\u00edtines y eventos en todo Estados Unidos, espera reunir a algunas de estas figuras emergentes \u2014desde Alexandria Ocasio-Cortez hasta Pete Buttigieg\u2014 para movilizar a la base dem\u00f3crata, a\u00f1o y medio antes de las elecciones de mitad de mandato.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La iniciativa denuncia la \u00abtoma de poder m\u00e1s descarada de la historia moderna\u00bb de Estados Unidos, as\u00ed como un \u00abasalto total contra nuestro gobierno, nuestra econom\u00eda y nuestros derechos fundamentales\u00bb orquestado por Trump, Elon Musk \u00aby sus ac\u00f3litos multimillonarios con la ayuda del Congreso\u00bb.<\/li>\n\n\n\n<li>En menos de tres meses, m\u00e1s de 120.000 funcionarios federales han sido despedidos bajo el impulso del DOGE dirigido por Musk y Trump ha desafiado abiertamente la autoridad del Congreso al decidir retener el desembolso de fondos asignados por el poder legislativo a ciertos programas y agencias, lo cual es contrario a la ley.<\/li>\n\n\n\n<li>Las numerosas acciones emprendidas por la administraci\u00f3n republicana desde el 20 de enero, muchas de las cuales se perciben como controvertidas, fueron objeto de 166 recursos ante los tribunales el 4 de abril, es decir, m\u00e1s de dos al d\u00eda desde la toma de posesi\u00f3n.<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/ncWrt\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Los organizadores del movimiento <em>Hands Off!<\/em> afirmaron el 3 de abril que podr\u00edan reunir a 400.000 personas en los 50 estados del pa\u00eds&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-62909' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2025\/04\/05\/en-estados-unidos-la-oposicion-a-trump-organiza-su-mayor-movilizacion-desde-el-20-de-enero\/#easy-footnote-bottom-1-62909' title='&lt;a href=&quot;https:\/\/www.facebook.com\/indivisibleguide\/posts\/pfbid02GQLB46QNBGs9Pzpr1bzvthRtGhmeSJcAPAqrmhmSLCp3k6GJte3s1MAxcHZpVKPBl&quot;&gt;Publicaci\u00f3n de Indivisible Guide&lt;\/a&gt;, Facebook, 3 de abril de 2025.'><sup>1<\/sup><\/a><\/span><\/span>. En Washington D. C., el anuncio de una manifestaci\u00f3n oblig\u00f3 a la primera dama, Melania Trump, a posponer las visitas a los jardines de la Casa Blanca previstas inicialmente para el 5 de abril&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-62909' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2025\/04\/05\/en-estados-unidos-la-oposicion-a-trump-organiza-su-mayor-movilizacion-desde-el-20-de-enero\/#easy-footnote-bottom-2-62909' title='April Rubin, \u00ab\u00a0&lt;a href=&quot;https:\/\/www.axios.com\/2025\/04\/03\/white-house-garden-tour-postponed-protests-dc-melania-trump&quot;&gt;Protests force rescheduling of Saturday White House tours&lt;\/a&gt;\u00a0\u00bb,\u00a0&lt;em&gt;Axios&lt;\/em&gt;, 3 de abril de 2025.'><sup>2<\/sup><\/a><\/span><\/span>. Aunque el presidente no se ha pronunciado por el momento sobre el movimiento, este hab\u00eda considerado durante su primer mandato recurrir al ej\u00e9rcito para reprimir las manifestaciones.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/XCwaz\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La Ley de Insurrecci\u00f3n de 1807 permite al presidente de Estados Unidos desplegar la Guardia Nacional o las Fuerzas Armadas contra la poblaci\u00f3n estadounidense en caso de \u00abdisturbios civiles\u00bb. La ley se invoc\u00f3 por \u00faltima vez en 1992 para reprimir los disturbios de Los \u00c1ngeles.<\/li>\n\n\n\n<li>El primer d\u00eda de su mandato, Trump orden\u00f3 a los secretarios de Defensa y Seguridad Nacional, <a href=\"https:\/\/legrandcontinent.eu\/es\/2025\/01\/13\/pete-hegseth-el-hombre-fiel-dispuesto-a-emprender-una-cruzada-por-trump\/\">Pete Hegseth<\/a> y <a href=\"https:\/\/legrandcontinent.eu\/es\/2025\/01\/15\/kristi-noem-la-conservadora-de-las-praderas-de-donald-trump\/\">Kristi Noem<\/a>, que presentaran en un plazo de 90 d\u00edas un informe con recomendaciones sobre \u00ablas medidas adicionales que podr\u00edan ser necesarias para obtener el control operativo completo de la frontera sur, incluida la cuesti\u00f3n de si es apropiado invocar la Ley de Insurrecci\u00f3n de 1807\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-62909' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2025\/04\/05\/en-estados-unidos-la-oposicion-a-trump-organiza-su-mayor-movilizacion-desde-el-20-de-enero\/#easy-footnote-bottom-3-62909' title='&lt;a href=&quot;https:\/\/www.whitehouse.gov\/presidential-actions\/2025\/01\/declaring-a-national-emergency-at-the-southern-border-of-the-united-states\/&quot;&gt;DECLARING A NATIONAL EMERGENCY AT THE SOUTHERN BORDER OF THE UNITED STATES&lt;\/a&gt;, Casa Blanca, 20 de enero de 2025.'><sup>3<\/sup><\/a><\/span><\/span>.<\/li>\n\n\n\n<li>Si bien Trump no ha mencionado desde el 20 de enero el uso de esta ley para reprimir manifestaciones, hab\u00eda ordenado a su Fiscal General, a su Secretario de Defensa y a su Jefe de Estado Mayor del Ej\u00e9rcito desplegar miles de soldados en las calles de la capital durante su primer mandato, en junio de 2020, tras las manifestaciones que ped\u00edan justicia para George Floyd, asesinado por un polic\u00eda un mes antes&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-4-62909' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2025\/04\/05\/en-estados-unidos-la-oposicion-a-trump-organiza-su-mayor-movilizacion-desde-el-20-de-enero\/#easy-footnote-bottom-4-62909' title='Michael S. Schmidt y Maggie Haberman, \u00ab\u00a0&lt;a href=&quot;https:\/\/www.nytimes.com\/2021\/06\/25\/us\/politics\/trump-insurrection-act-protests.html&quot;&gt;Trump Aides Prepared Insurrection Act Order During Debate Over Protests&lt;\/a&gt;\u00a0\u00bb,\u00a0&lt;em&gt;The New York Times&lt;\/em&gt;, 25 de junio de 2021.'><sup>4<\/sup><\/a><\/span><\/span>.<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/5q4CR\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Si bien los organizadores de Hands Off! afirman querer llevar a cabo acciones no violentas, el desprecio de Trump por cualquier forma de contrapoder podr\u00eda incitarlo a tratar de sofocar cualquier protesta si percibiera estos movimientos de oposici\u00f3n como una amenaza. En el entorno de Trump, varias voces, como las de Elon Musk o Charlie Kirk, intentan presentar al Partido Dem\u00f3crata como el bando de \u00abla violencia y el odio\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy, s\u00e1bado 5 de abril, varios cientos de miles de estadounidenses se reunir\u00e1n y manifestar\u00e1n en todo el pa\u00eds, desde Haw\u00e1i hasta Alaska, contra el \u00abasalto al gobierno\u00bb estadounidense orquestado por Donald Trump y Elon Musk. La jornada de protesta, organizado por el movimiento \u00abHands Off!\u00bb, ser\u00e1 la m\u00e1s importante desde que Trump volvi\u00f3 al poder el 20 de enero.<\/p>\n","protected":false},"author":1366,"featured_media":62896,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":true,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":4,"footnotes":""},"categories":[6],"tags":[],"staff":[],"editorial_format":[1472],"serie":[],"audience":[],"geo":[172],"class_list":["post-62909","post","type-post","status-publish","format-standard","hentry","category-politica","editorial_format-analisis","geo-americas"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":62896,"excerpt":"Hoy, s\u00e1bado 5 de abril, varios cientos de miles de estadounidenses se reunir\u00e1n y manifestar\u00e1n en todo el pa\u00eds, desde Haw\u00e1i hasta Alaska, contra el \u00abasalto al gobierno\u00bb estadounidense orquestado por Donald Trump y Elon Musk. La jornada de protesta, organizado por el movimiento \u00abHands Off!\u00bb, ser\u00e1 la m\u00e1s importante desde que Trump volvi\u00f3 al poder el 20 de enero.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>En Estados Unidos, la oposici\u00f3n a Trump organiza su mayor movilizaci\u00f3n desde el 20 de enero - El Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/es\/2025\/04\/05\/en-estados-unidos-la-oposicion-a-trump-organiza-su-mayor-movilizacion-desde-el-20-de-enero\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En Estados Unidos, la oposici\u00f3n a Trump organiza su mayor movilizaci\u00f3n desde el 20 de enero - El Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Hoy, s\u00e1bado 5 de abril, varios cientos de miles de estadounidenses se reunir\u00e1n y manifestar\u00e1n en todo el pa\u00eds, desde Haw\u00e1i hasta Alaska, contra el \u00abasalto al gobierno\u00bb estadounidense orquestado por Donald Trump y Elon Musk. La jornada de protesta, organizado por el movimiento \u00abHands Off!\u00bb, ser\u00e1 la m\u00e1s importante desde que Trump volvi\u00f3 al poder el 20 de enero.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/es\/2025\/04\/05\/en-estados-unidos-la-oposicion-a-trump-organiza-su-mayor-movilizacion-desde-el-20-de-enero\/\" \/>\n<meta property=\"og:site_name\" content=\"El Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-05T05:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/04\/gc-elop-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"florent\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/04\/gc-elop-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"florent\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/04\/05\/en-estados-unidos-la-oposicion-a-trump-organiza-su-mayor-movilizacion-desde-el-20-de-enero\/\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/2025\/04\/05\/en-estados-unidos-la-oposicion-a-trump-organiza-su-mayor-movilizacion-desde-el-20-de-enero\/\",\"name\":\"En Estados Unidos, la oposici\u00f3n a Trump organiza su mayor movilizaci\u00f3n desde el 20 de enero - El Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/04\/05\/en-estados-unidos-la-oposicion-a-trump-organiza-su-mayor-movilizacion-desde-el-20-de-enero\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/04\/05\/en-estados-unidos-la-oposicion-a-trump-organiza-su-mayor-movilizacion-desde-el-20-de-enero\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/04\/gc-manifestations-hands-off.png\",\"datePublished\":\"2025-04-05T05:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/04\/05\/en-estados-unidos-la-oposicion-a-trump-organiza-su-mayor-movilizacion-desde-el-20-de-enero\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/es\/2025\/04\/05\/en-estados-unidos-la-oposicion-a-trump-organiza-su-mayor-movilizacion-desde-el-20-de-enero\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/04\/05\/en-estados-unidos-la-oposicion-a-trump-organiza-su-mayor-movilizacion-desde-el-20-de-enero\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/04\/gc-manifestations-hands-off.png\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/04\/gc-manifestations-hands-off.png\",\"width\":1894,\"height\":1058},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/04\/05\/en-estados-unidos-la-oposicion-a-trump-organiza-su-mayor-movilizacion-desde-el-20-de-enero\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/legrandcontinent.eu\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En Estados Unidos, la oposici\u00f3n a Trump organiza su mayor movilizaci\u00f3n desde el 20 de enero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/\",\"name\":\"El Grand Continent\",\"description\":\"La escala pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\",\"name\":\"florent\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"caption\":\"florent\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"En Estados Unidos, la oposici\u00f3n a Trump organiza su mayor movilizaci\u00f3n desde el 20 de enero - El Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/es\/2025\/04\/05\/en-estados-unidos-la-oposicion-a-trump-organiza-su-mayor-movilizacion-desde-el-20-de-enero\/","og_locale":"es_ES","og_type":"article","og_title":"En Estados Unidos, la oposici\u00f3n a Trump organiza su mayor movilizaci\u00f3n desde el 20 de enero - El Grand Continent","og_description":"Hoy, s\u00e1bado 5 de abril, varios cientos de miles de estadounidenses se reunir\u00e1n y manifestar\u00e1n en todo el pa\u00eds, desde Haw\u00e1i hasta Alaska, contra el \u00abasalto al gobierno\u00bb estadounidense orquestado por Donald Trump y Elon Musk. La jornada de protesta, organizado por el movimiento \u00abHands Off!\u00bb, ser\u00e1 la m\u00e1s importante desde que Trump volvi\u00f3 al poder el 20 de enero.","og_url":"https:\/\/legrandcontinent.eu\/es\/2025\/04\/05\/en-estados-unidos-la-oposicion-a-trump-organiza-su-mayor-movilizacion-desde-el-20-de-enero\/","og_site_name":"El Grand Continent","article_published_time":"2025-04-05T05:00:00+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/04\/gc-elop-scaled.jpg","type":"image\/jpeg"}],"author":"florent","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/04\/gc-elop-scaled.jpg","twitter_misc":{"Escrito por":"florent","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/es\/2025\/04\/05\/en-estados-unidos-la-oposicion-a-trump-organiza-su-mayor-movilizacion-desde-el-20-de-enero\/","url":"https:\/\/legrandcontinent.eu\/es\/2025\/04\/05\/en-estados-unidos-la-oposicion-a-trump-organiza-su-mayor-movilizacion-desde-el-20-de-enero\/","name":"En Estados Unidos, la oposici\u00f3n a Trump organiza su mayor movilizaci\u00f3n desde el 20 de enero - El Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/es\/2025\/04\/05\/en-estados-unidos-la-oposicion-a-trump-organiza-su-mayor-movilizacion-desde-el-20-de-enero\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/es\/2025\/04\/05\/en-estados-unidos-la-oposicion-a-trump-organiza-su-mayor-movilizacion-desde-el-20-de-enero\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/04\/gc-manifestations-hands-off.png","datePublished":"2025-04-05T05:00:00+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/es\/2025\/04\/05\/en-estados-unidos-la-oposicion-a-trump-organiza-su-mayor-movilizacion-desde-el-20-de-enero\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/es\/2025\/04\/05\/en-estados-unidos-la-oposicion-a-trump-organiza-su-mayor-movilizacion-desde-el-20-de-enero\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/2025\/04\/05\/en-estados-unidos-la-oposicion-a-trump-organiza-su-mayor-movilizacion-desde-el-20-de-enero\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/04\/gc-manifestations-hands-off.png","contentUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/04\/gc-manifestations-hands-off.png","width":1894,"height":1058},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/es\/2025\/04\/05\/en-estados-unidos-la-oposicion-a-trump-organiza-su-mayor-movilizacion-desde-el-20-de-enero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legrandcontinent.eu\/es\/"},{"@type":"ListItem","position":2,"name":"En Estados Unidos, la oposici\u00f3n a Trump organiza su mayor movilizaci\u00f3n desde el 20 de enero"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/es\/#website","url":"https:\/\/legrandcontinent.eu\/es\/","name":"El Grand Continent","description":"La escala pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c","name":"florent","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","caption":"florent"}}]}},"lgc_categories":[{"id":6,"name":"Pol\u00edtica","slug":"politica"}],"lgc_author":null,"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/04\/gc-manifestations-hands-off.png","width":1894,"height":1058,"alt":""},"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/62909","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/users\/1366"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/comments?post=62909"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/62909\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media\/62896"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media?parent=62909"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/categories?post=62909"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/tags?post=62909"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/staff?post=62909"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/editorial_format?post=62909"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/serie?post=62909"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/audience?post=62909"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/geo?post=62909"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}