{"id":61590,"date":"2025-03-31T11:04:13","date_gmt":"2025-03-31T09:04:13","guid":{"rendered":"https:\/\/legrandcontinent.eu\/es\/?p=61590"},"modified":"2025-03-31T13:25:11","modified_gmt":"2025-03-31T11:25:11","slug":"el-giro-de-berlin-hacer-funcionar-la-geopolitica-europea","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/es\/2025\/03\/31\/el-giro-de-berlin-hacer-funcionar-la-geopolitica-europea\/","title":{"rendered":"El giro de Berl\u00edn: hacer funcionar la geopol\u00edtica europea"},"content":{"rendered":"\n<p><em><a href=\"https:\/\/geopolitique.eu\/en\/2025\/03\/31\/europe-steps-up-a-turning-point-in-berlin\/\" target=\"_blank\" rel=\"noreferrer noopener\">English version available at this link<\/a><\/em><\/p>\n\n\n\n<p class=\"has-drop-cap\">En las \u00faltimas semanas, un t\u00e9rmino t\u00e9cnico alem\u00e1n, <a href=\"https:\/\/legrandcontinent.eu\/es\/2025\/01\/29\/la-mayoria-de-los-alemanes-esta-a-favor-de-reformar-el-freno-al-endeudamiento-encuestas-y-graficos-exclusivos\/\"><em>Schuldenbremse<\/em> \u2014o freno al endeudamiento<\/a>\u2014, ha dado la vuelta al mundo, mientras que Berl\u00edn se ha convertido en el punto de convergencia de decisiones capitales que configuran el futuro de Europa.&nbsp;<\/p>\n\n\n\n<p>La semana pasada, en una votaci\u00f3n hist\u00f3rica, <a href=\"https:\/\/legrandcontinent.eu\/es\/2025\/03\/18\/alemania-el-bundestag-aprueba-la-reforma-constitucional-del-freno-de-la-deuda\/\">las dos c\u00e1maras legislativas alemanas adoptaron textos legislativos esenciales<\/a> destinados a reformar el freno de la deuda para permitir un aumento de los gastos de defensa, as\u00ed como un presupuesto especial para infraestructuras, que se han finalizado y aprobado. La rapidez con la que se han tomado estas medidas, cuando se est\u00e1 formando un nuevo gobierno, no tiene precedentes, pero era necesaria.<\/p>\n\n\n\n<p>Las circunstancias excepcionales exigen respuestas excepcionales.<\/p>\n\n\n\n<p>Durante demasiado tiempo, Europa y Alemania se han hecho ilusiones. Si el supuesto \u00abfin de la historia\u00bb era esencialmente una idea estadounidense, tambi\u00e9n era una realidad europea \u2014y sobre todo alemana\u2014.&nbsp;<\/p>\n\n\n\n<p>Hace tiempo que vivimos en un mundo diferente, pero s\u00f3lo ahora lo aceptamos.<\/p>\n\n\n\n<p>Los acontecimientos de las \u00faltimas semanas \u2014<a href=\"https:\/\/legrandcontinent.eu\/es\/2025\/02\/14\/cambio-de-regimen-el-discurso-completo-de-j-d-vance-en-munich\/\">desde el discurso de confrontaci\u00f3n de J. D. Vance hasta la Conferencia de Seguridad de M\u00fanich<\/a>, pasando por <a href=\"https:\/\/legrandcontinent.eu\/es\/2025\/03\/01\/el-intercambio-entre-trump-y-zelenski-transcripcion-completa\/\">la humillaci\u00f3n p\u00fablica del presidente Zelenski en el Despacho Oval<\/a> y <a href=\"https:\/\/legrandcontinent.eu\/es\/2025\/03\/11\/propuesta-de-alto-el-fuego-inmediato-en-ucrania-el-texto-completo-de-la-declaracion-conjunta-con-estados-unidos\/\">la negociaci\u00f3n de cuestiones de seguridad europea en Arabia Saud\u00ed sin la participaci\u00f3n de Europa<\/a>\u2014 han hecho a\u00f1icos cualquier atisbo de complacencia que pudiera quedar. La realidad es brutal: durante d\u00e9cadas, Europa ha jugado muy por debajo de su rango. Ha luchado como un peso pluma geopol\u00edtico a pesar de su estatus de gigante econ\u00f3mico. En una era cuyos t\u00e9rminos est\u00e1n definidos por Trump, Xi y Putin, esta situaci\u00f3n ya no es sostenible.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Si el supuesto \u00abfin de la historia\u00bb era esencialmente una idea estadounidense, tambi\u00e9n era una realidad europea \u2014y sobre todo alemana\u2014.\u00a0<\/p><cite>NATHANIEL LIMINSKI<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Las decisiones tomadas en Berl\u00edn en las \u00faltimas semanas, como las conclusiones adoptadas en la \u00faltima cumbre del Consejo Europeo en Bruselas, env\u00edan una se\u00f1al clara: Europa est\u00e1 pasando a la velocidad superior.&nbsp;<\/p>\n\n\n\n<p>Y, por una vez, no es ret\u00f3rica: estamos tomando medidas concretas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">El dinero por s\u00ed s\u00f3lo no resolver\u00e1 el problema<\/h2>\n\n\n\n<p>El compromiso financiero es colosal: se habla de gastos potencialmente ilimitados en defensa e inteligencia, as\u00ed como de una inversi\u00f3n de 500.000 millones de euros en infraestructuras e iniciativas a favor del clima. Si bien este dinero es esencial, no es suficiente: sin una preocupaci\u00f3n por la productividad y la eficacia, estos miles de millones se desperdiciar\u00e1n.<\/p>\n\n\n\n<p>Para garantizar que este dinero se gaste de manera eficiente, tendremos que aligerar dr\u00e1sticamente la proverbial pesadez burocr\u00e1tica alemana.<\/p>\n\n\n\n<p>Hist\u00f3ricamente, el gobierno federal se ha mostrado demasiado prudente y ha establecido mecanismos de control excesivos sobre el gasto. Aunque est\u00e1n destinados a garantizar la responsabilidad fiscal, estos mecanismos a menudo han sofocado las inversiones. Durante las dif\u00edciles negociaciones sobre esta legislaci\u00f3n, se han eliminado con \u00e9xito algunos de estos obst\u00e1culos. Ahora es el momento de ir m\u00e1s all\u00e1: m\u00e1s confianza; menos aversi\u00f3n al riesgo; un compromiso firme contra la par\u00e1lisis burocr\u00e1tica.<\/p>\n\n\n\n<p>La eficacia es igualmente crucial.<\/p>\n\n\n\n<p>Las sumas asignadas son importantes, pero siguen siendo modestas en comparaci\u00f3n con nuestras necesidades. En ausencia de objetivos claros y reformas estructurales, este dinero se desperdiciar\u00e1. De hecho, ya ha ocurrido antes: el presupuesto especial de defensa de 100.000 millones de euros de 2022 tras el famoso <em>Zeitenwende<\/em> \u2014el cambio de \u00e9poca\u2014 se ha evaporado en gran medida sin dar resultados significativos. Esta vez no podremos permitirnos repetir el mismo error.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Una nueva era para la defensa europea<\/h2>\n\n\n\n<p>Para que el gasto en defensa sea realmente eficaz, deben cumplirse dos condiciones.<\/p>\n\n\n\n<p>En primer lugar, Europa debe dar prioridad a los proyectos comunes en lugar de a los intereses nacionales. Debe ponerse fin a la \u00e9poca en que los Estados-naci\u00f3n se aferraban a sus industrias de defensa nacionales en detrimento de la seguridad colectiva. Necesitamos recursos comunes y esfuerzos coordinados para desarrollar las capacidades europeas. Es alentador ver que actualmente existe una verdadera din\u00e1mica en este sentido, especialmente en Par\u00eds, Varsovia y Berl\u00edn, con el fin de establecer un marco de defensa europeo unificado, en estrecha colaboraci\u00f3n con Londres.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Las sumas asignadas son importantes, pero siguen siendo modestas en comparaci\u00f3n con nuestras necesidades. En ausencia de objetivos claros y reformas estructurales, este dinero se desperdiciar\u00e1.<\/p><cite>NATHANIEL LIMINSKI<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Luego, debemos <a href=\"https:\/\/legrandcontinent.eu\/es\/2025\/03\/21\/notas-para-un-ejercito-nuevo\/\">reformar en profundidad nuestras estructuras de mando<\/a>. No basta con desarrollar las fuerzas armadas nacionales; debemos ser capaces de llevar a cabo operaciones conjuntas, incluso sin el apoyo de Estados Unidos si es necesario. Como ha se\u00f1alado recientemente Herfried M\u00fcnkler, la interoperabilidad militar europea y la garant\u00eda de una disuasi\u00f3n nuclear cre\u00edble son objetivos vitales. No se trata de consideraciones presupuestarias. Se trata de voluntad pol\u00edtica.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Reforzar la competitividad europea<\/h2>\n\n\n\n<p>M\u00e1s all\u00e1 de la defensa, es necesario reforzar la competitividad econ\u00f3mica de Europa, no s\u00f3lo mediante el gasto, sino tambi\u00e9n mediante una reforma regulatoria inteligente.<\/p>\n\n\n\n<p><a href=\"https:\/\/legrandcontinent.eu\/es\/category\/economia\/informe-draghi-un-debate-europeo\/\">El reciente informe de Mario Draghi<\/a> \u2014que, lamentablemente, ha recibido&nbsp; muy poca atenci\u00f3n en Alemania\u2014 se\u00f1ala importantes defectos estructurales&nbsp; en el mercado \u00fanico de la Uni\u00f3n.&nbsp;<\/p>\n\n\n\n<p>Si bien nuestra Uni\u00f3n sigue siendo su principal socio comercial, las barreras internas \u2014como las diferencias entre las normativas nacionales y los tipos del IVA\u2014 <a href=\"https:\/\/legrandcontinent.eu\/es\/2025\/03\/18\/mario-draghi-construir-a-la-escala-superior-el-discurso-de-roma-en-su-totalidad\/\">representan el equivalente a aranceles del 45% sobre las mercanc\u00edas y del 110% sobre los servicios<\/a>. Es imprescindible eliminar estos obst\u00e1culos, sobre todo en un momento en el que la pol\u00edtica comercial de los Estados Unidos se est\u00e1 volviendo cada vez m\u00e1s proteccionista. As\u00ed, el <em>Financial Times<\/em> estima que un aumento de s\u00f3lo el 2,4% en el comercio intraeuropeo podr\u00eda compensar una ca\u00edda del 20% en las exportaciones estadounidenses. Sin embargo, desbloquear esta situaci\u00f3n requiere ante todo voluntad pol\u00edtica \u2014no gastos adicionales\u2014.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Mantener el apoyo de la opini\u00f3n p\u00fablica<\/h2>\n\n\n\n<p><a href=\"https:\/\/legrandcontinent.eu\/es\/2025\/03\/24\/que-piensan-los-alemanes-en-la-era-merz-medir-una-opinion-publica-en-movimiento-encuestas-exclusivas\/\">Como muestra un estudio reciente publicado en estas p\u00e1ginas<\/a>, el giro alem\u00e1n cuenta con un fuerte apoyo de la opini\u00f3n p\u00fablica. Eso es bueno, pero nada garantiza que dure.&nbsp;<\/p>\n\n\n\n<p>Ante la creciente incertidumbre, los l\u00edderes deben ser honestos sobre las medidas que deben tomarse y los costes que implican.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Europa asume por fin el papel geopol\u00edtico que su poder econ\u00f3mico le exige.<\/p><cite>NATHANIEL LIMINSKI<\/cite><\/blockquote><\/figure>\n\n\n\n<p><a href=\"https:\/\/legrandcontinent.eu\/es\/2025\/03\/20\/frente-a-la-guerra-y-trump-medir-la-opinion-publica-europea-10-puntos-sobre-una-encuesta-exclusiva\/\">Los ciudadanos europeos comprenden la gravedad del momento<\/a>. Est\u00e1n dispuestos a asumir una mayor responsabilidad en la defensa de la libertad, la prosperidad y la seguridad. Pero esta ayuda nunca debe darse por sentada. La transparencia, la responsabilidad y los resultados son esenciales.<\/p>\n\n\n\n<p>Europa se encuentra en un punto de inflexi\u00f3n.<\/p>\n\n\n\n<p>La complacencia de las \u00faltimas d\u00e9cadas ya no es apropiada. Las medidas adoptadas en Berl\u00edn y Bruselas marcan el comienzo de una nueva era \u2014Europa asume por fin el papel geopol\u00edtico que su poder econ\u00f3mico le exige\u2014.&nbsp;<\/p>\n\n\n\n<p>Ha llegado el momento de garantizar que nuestra determinaci\u00f3n se traduzca en cambios duraderos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alemania acelera la transici\u00f3n geopol\u00edtica de Europa.<\/p>\n<p>\u00bfC\u00f3mo hacer para que este nuevo <em>Zeitenwende<\/em> sea realmente operativo?<\/p>\n<p>El ministro Nathaniel Liminski, la voz emergente de la CDU en el coraz\u00f3n del giro europeo de Alemania dirigido por Merz, formula una propuesta.<\/p>\n","protected":false},"author":1366,"featured_media":61573,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-editorials.php","format":"standard","meta":{"_acf_changed":true,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":5,"_lgc_tts_audio_url":"","_lgc_tts_voice":"","_lgc_tts_publish":false,"_lgc_tts_history_item_id":"","_lgc_tts_generated_at":"","_lgc_tts_status":"","_lgc_tts_error":"","footnotes":""},"categories":[6],"tags":[],"staff":[1055],"editorial_format":[1471],"serie":[],"audience":[],"geo":[177],"class_list":["post-61590","post","type-post","status-publish","format-standard","hentry","category-politica","staff-nathanael-liminski","editorial_format-piezas-de-doctrinas","geo-europa"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":61573,"excerpt":"Alemania acelera la transici\u00f3n geopol\u00edtica de Europa.\r\n\r\n\u00bfC\u00f3mo hacer para que este nuevo <em>Zeitenwende<\/em> sea realmente operativo?\r\n\r\nEl ministro Nathaniel Liminski, la voz emergente de la CDU en el coraz\u00f3n del giro europeo de Alemania dirigido por Merz, formula una propuesta.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El giro de Berl\u00edn: hacer funcionar la geopol\u00edtica europea - El Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/es\/2025\/03\/31\/el-giro-de-berlin-hacer-funcionar-la-geopolitica-europea\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El giro de Berl\u00edn: hacer funcionar la geopol\u00edtica europea - El Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Alemania acelera la transici\u00f3n geopol\u00edtica de Europa.  \u00bfC\u00f3mo hacer para que este nuevo Zeitenwende sea realmente operativo?  El ministro Nathaniel Liminski, la voz emergente de la CDU en el coraz\u00f3n del giro europeo de Alemania dirigido por Merz, formula una propuesta.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/es\/2025\/03\/31\/el-giro-de-berlin-hacer-funcionar-la-geopolitica-europea\/\" \/>\n<meta property=\"og:site_name\" content=\"El Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-31T09:04:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-31T11:25:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/03\/gc-elleminski-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"florent\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/03\/gc-elleminski-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"florent\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/03\/31\/el-giro-de-berlin-hacer-funcionar-la-geopolitica-europea\/\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/2025\/03\/31\/el-giro-de-berlin-hacer-funcionar-la-geopolitica-europea\/\",\"name\":\"El giro de Berl\u00edn: hacer funcionar la geopol\u00edtica europea - El Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/03\/31\/el-giro-de-berlin-hacer-funcionar-la-geopolitica-europea\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/03\/31\/el-giro-de-berlin-hacer-funcionar-la-geopolitica-europea\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/03\/Anselm_Kieffer_-_Glaube__Hoffnung_Liebe-scaled.jpg\",\"datePublished\":\"2025-03-31T09:04:13+00:00\",\"dateModified\":\"2025-03-31T11:25:11+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/03\/31\/el-giro-de-berlin-hacer-funcionar-la-geopolitica-europea\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/es\/2025\/03\/31\/el-giro-de-berlin-hacer-funcionar-la-geopolitica-europea\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/03\/31\/el-giro-de-berlin-hacer-funcionar-la-geopolitica-europea\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/03\/Anselm_Kieffer_-_Glaube__Hoffnung_Liebe-scaled.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/03\/Anselm_Kieffer_-_Glaube__Hoffnung_Liebe-scaled.jpg\",\"width\":1857,\"height\":2560,\"caption\":\"Anselm Kieffer, 'Glaube, Hoffnung, Liebe' (Foi, esp\u00e9rance, charit\u00e9), 1984-86\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/03\/31\/el-giro-de-berlin-hacer-funcionar-la-geopolitica-europea\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/legrandcontinent.eu\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El giro de Berl\u00edn: hacer funcionar la geopol\u00edtica europea\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/\",\"name\":\"El Grand Continent\",\"description\":\"La escala pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\",\"name\":\"florent\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"caption\":\"florent\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El giro de Berl\u00edn: hacer funcionar la geopol\u00edtica europea - El Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/es\/2025\/03\/31\/el-giro-de-berlin-hacer-funcionar-la-geopolitica-europea\/","og_locale":"es_ES","og_type":"article","og_title":"El giro de Berl\u00edn: hacer funcionar la geopol\u00edtica europea - El Grand Continent","og_description":"Alemania acelera la transici\u00f3n geopol\u00edtica de Europa.  \u00bfC\u00f3mo hacer para que este nuevo Zeitenwende sea realmente operativo?  El ministro Nathaniel Liminski, la voz emergente de la CDU en el coraz\u00f3n del giro europeo de Alemania dirigido por Merz, formula una propuesta.","og_url":"https:\/\/legrandcontinent.eu\/es\/2025\/03\/31\/el-giro-de-berlin-hacer-funcionar-la-geopolitica-europea\/","og_site_name":"El Grand Continent","article_published_time":"2025-03-31T09:04:13+00:00","article_modified_time":"2025-03-31T11:25:11+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/03\/gc-elleminski-scaled.jpg","type":"image\/jpeg"}],"author":"florent","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/03\/gc-elleminski-scaled.jpg","twitter_misc":{"Escrito por":"florent","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/es\/2025\/03\/31\/el-giro-de-berlin-hacer-funcionar-la-geopolitica-europea\/","url":"https:\/\/legrandcontinent.eu\/es\/2025\/03\/31\/el-giro-de-berlin-hacer-funcionar-la-geopolitica-europea\/","name":"El giro de Berl\u00edn: hacer funcionar la geopol\u00edtica europea - El Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/es\/2025\/03\/31\/el-giro-de-berlin-hacer-funcionar-la-geopolitica-europea\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/es\/2025\/03\/31\/el-giro-de-berlin-hacer-funcionar-la-geopolitica-europea\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/03\/Anselm_Kieffer_-_Glaube__Hoffnung_Liebe-scaled.jpg","datePublished":"2025-03-31T09:04:13+00:00","dateModified":"2025-03-31T11:25:11+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/es\/2025\/03\/31\/el-giro-de-berlin-hacer-funcionar-la-geopolitica-europea\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/es\/2025\/03\/31\/el-giro-de-berlin-hacer-funcionar-la-geopolitica-europea\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/2025\/03\/31\/el-giro-de-berlin-hacer-funcionar-la-geopolitica-europea\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/03\/Anselm_Kieffer_-_Glaube__Hoffnung_Liebe-scaled.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/03\/Anselm_Kieffer_-_Glaube__Hoffnung_Liebe-scaled.jpg","width":1857,"height":2560,"caption":"Anselm Kieffer, 'Glaube, Hoffnung, Liebe' (Foi, esp\u00e9rance, charit\u00e9), 1984-86"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/es\/2025\/03\/31\/el-giro-de-berlin-hacer-funcionar-la-geopolitica-europea\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legrandcontinent.eu\/es\/"},{"@type":"ListItem","position":2,"name":"El giro de Berl\u00edn: hacer funcionar la geopol\u00edtica europea"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/es\/#website","url":"https:\/\/legrandcontinent.eu\/es\/","name":"El Grand Continent","description":"La escala pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c","name":"florent","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","caption":"florent"}}]}},"lgc_categories":[{"id":6,"name":"Pol\u00edtica","slug":"politica"}],"lgc_author":{"id":1055,"name":"Nathanael Liminski","slug":"nathanael-liminski","description":"Nathanael Liminski es ministro de Asuntos Federales, Europeos, Internacionales y de Medios de Comunicaci\u00f3n del Estado federado de Renania del Norte-Westfalia desde el 29 de junio de 2022 y jefe de la Canciller\u00eda del Estado federado de Renania del Norte-Westfalia desde junio de 2017.","first_name":"Nathanael","last_name":"Liminski","picture":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/03\/MKr350463_Nathanael_Liminski_2024.png","width":2762,"height":2838,"alt":""}},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/03\/Anselm_Kieffer_-_Glaube__Hoffnung_Liebe-scaled.jpg","width":1857,"height":2560,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/03\/Anselm_Kieffer_-_Glaube__Hoffnung_Liebe-scaled.jpg","width":1857,"height":2560,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/61590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/users\/1366"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/comments?post=61590"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/61590\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media\/61573"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media?parent=61590"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/categories?post=61590"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/tags?post=61590"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/staff?post=61590"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/editorial_format?post=61590"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/serie?post=61590"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/audience?post=61590"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/geo?post=61590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}