{"id":60554,"date":"2025-03-18T19:07:16","date_gmt":"2025-03-18T18:07:16","guid":{"rendered":"https:\/\/legrandcontinent.eu\/es\/?p=60554"},"modified":"2025-03-18T19:07:19","modified_gmt":"2025-03-18T18:07:19","slug":"llamada-trump-putin-rusia-exige-el-cese-total-de-la-ayuda-militar-a-kiev-como-condicion-para-el-cese-de-los-combates","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/es\/2025\/03\/18\/llamada-trump-putin-rusia-exige-el-cese-total-de-la-ayuda-militar-a-kiev-como-condicion-para-el-cese-de-los-combates\/","title":{"rendered":"Llamada Trump-Putin: Rusia exige \u00abel cese total de la ayuda militar a Kiev\u00bb como condici\u00f3n para el cese de los combates"},"content":{"rendered":"\n<p>Ayer mismo, lunes 17 de marzo, el portavoz del Kremlin, Dmitri Peskov, confirm\u00f3 que hoy martes 18 se producir\u00eda una llamada directa entre Trump y Putin.<\/p>\n\n\n\n<p>Durante la llamada, Trump y Putin acordaron seguir trabajando en favor de <a href=\"https:\/\/legrandcontinent.eu\/es\/2025\/02\/18\/la-administracion-trump-quiere-normalizar-sus-relaciones-con-la-rusia-de-putin\/\">la normalizaci\u00f3n de las relaciones bilaterales<\/a>, tras un primer encuentro entre una delegaci\u00f3n estadounidense y una delegaci\u00f3n rusa en Yeda, en Arabia Saud\u00ed, el 18 de febrero.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Putin inform\u00f3 a Trump de un intercambio de 175 prisioneros ucranianos por 175 prisioneros rusos que deber\u00eda tener lugar ma\u00f1ana, mi\u00e9rcoles 19 de marzo; adem\u00e1s, 23 soldados ucranianos \u00abgravemente heridos\u00bb ser\u00e1n entregados a Kiev, \u00abcomo gesto de buena voluntad\u00bb;<\/li>\n\n\n\n<li>Los dos l\u00edderes acordaron \u00abestablecer grupos de expertos para la resoluci\u00f3n del conflicto ucraniano\u00bb y un alto el fuego de 30 d\u00edas en los ataques a las infraestructuras energ\u00e9ticas;<\/li>\n\n\n\n<li>Putin plante\u00f3 durante la llamada \u00abcomo condici\u00f3n esencial para la resoluci\u00f3n del conflicto en Ucrania, el cese total de la ayuda militar a Kiev\u00bb.<\/li>\n<\/ul>\n\n\n\n<p>El comunicado publicado por la Casa Blanca especifica que uno de los pr\u00f3ximos pasos consistir\u00e1 en la apertura de \u00abnegociaciones t\u00e9cnicas sobre la aplicaci\u00f3n de un alto el fuego mar\u00edtimo en el Mar Negro, un alto el fuego total y una paz permanente\u00bb. Estas conversaciones deber\u00edan \u00abcomenzar inmediatamente en Oriente Medio\u00bb. Los dos l\u00edderes tambi\u00e9n discutieron la futura organizaci\u00f3n de partidos de hockey de la NHL y la KHL en Rusia.<\/p>\n\n\n\n<p>Se trataba de la segunda conversaci\u00f3n telef\u00f3nica entre Putin y Trump desde su regreso al poder el 20 de enero, la primera tuvo lugar el 12 de febrero. El intercambio de hoy habr\u00eda durado aproximadamente dos horas y media seg\u00fan la Casa Blanca y el Kremlin, en comparaci\u00f3n con una hora y media en la conversaci\u00f3n anterior.<\/p>\n\n\n\n<p>La discusi\u00f3n entre Washington y Mosc\u00fa sin la presencia de representantes de Ucrania o de la Uni\u00f3n Europea es un factor de preocupaci\u00f3n para los europeos.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Trump se ha mostrado mucho m\u00e1s cercano a Rusia que a Ucrania en las \u00faltimas semanas. Despu\u00e9s de atribuir la responsabilidad de la invasi\u00f3n rusa a Kiev, el presidente estadounidense ha repetido en varias ocasiones elementos del lenguaje de la propaganda rusa.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>El viernes 14 de marzo, <a href=\"https:\/\/legrandcontinent.eu\/es\/2025\/03\/16\/en-kursk-el-repliegue-de-las-tropas-ucranianas-continua-sin-que-se-haya-producido-el-cerco-anunciado-por-trump-y-putin\/\">Trump retom\u00f3 en Truth Social una vez m\u00e1s la narrativa del Kremlin<\/a> al hablar de \u00abmiles de soldados ucranianos completamente rodeados por el ej\u00e9rcito ruso\u00bb que estar\u00edan en \u00abuna posici\u00f3n muy mala y vulnerable\u00bb.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>En Telegram, ninguno de estos <em>milblogueros<\/em> pro-rusos \u2014que suelen presentar al ej\u00e9rcito ucraniano como un ej\u00e9rcito derrotado\u2014 hab\u00eda compartido informaci\u00f3n relativa a ning\u00fan tipo de cerco. Adem\u00e1s, varios de estos comentaristas han desmentido abiertamente las \u00abinformaciones\u00bb de Putin y Trump.<\/li>\n<\/ul>\n\n\n\n<p>La alta representante de la Uni\u00f3n para Asuntos Exteriores, Kaja Kallas, y el presidente franc\u00e9s, Emmanuel Macron, han criticado abiertamente en los \u00faltimos d\u00edas la falta de voluntad real por parte de Rusia para sentarse a la mesa de negociaciones. Putin pretende aprovechar su ventaja sobre el terreno para seguir avanzando en el este y el sur de Ucrania. El presidente ruso teme las consecuencias que tendr\u00e1 en la sociedad rusa el regreso a la vida civil de decenas o incluso cientos de miles de soldados.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">We had very good and productive discussions with President Vladimir Putin of Russia yesterday, and there is a very good chance that this horrible, bloody war can finally come to an end \u2014 BUT, AT THIS VERY MOMENT, THOUSANDS OF UKRAINIAN TROOPS ARE COMPLETELY SURROUNDED BY THE\u2026<\/p>&mdash; Donald J. Trump Posts From His Truth Social (@TrumpDailyPosts) <a href=\"https:\/\/twitter.com\/TrumpDailyPosts\/status\/1900692849668059451?ref_src=twsrc%5Etfw\">March 14, 2025<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p>Antes de su llamada con el presidente estadounidense, Vladimir Putin declar\u00f3 ante la Uni\u00f3n de Industriales y Empresarios de Rusia que la \u00abdominaci\u00f3n occidental se estaba desmoronando\u00bb y que estaban \u00absurgiendo nuevos centros de crecimiento mundial\u00bb, y a\u00f1adi\u00f3 que se trataba de \u00abuna tendencia a largo plazo\u00bb.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Al referirse al G7, apodado en ruso el \u00abGran Siete\u00bb (formato en el que Trump hab\u00eda mencionado la posibilidad de reintegrar a Rusia), Putin ironiz\u00f3: \u00ab\u00bfPor qu\u00e9 grande? No importa d\u00f3nde mires en el mapa, no lo ves\u00bb.<\/li>\n<\/ul>\n\n\n\n<p>La participaci\u00f3n de Vladimir Putin en este evento parec\u00eda perfectamente calculada.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>El presidente ruso lleg\u00f3 al lugar poco antes de la hora prevista para su conversaci\u00f3n telef\u00f3nica con Donald Trump, fijada entre las 14:00 y las 16:00 (hora central europea), seg\u00fan el portavoz del Kremlin, Dmitri Peskov. A las 14:52, la agencia TASS anunci\u00f3 su partida. Un gesto que parece una se\u00f1al: Trump tendr\u00e1 que esperar.<\/li>\n\n\n\n<li>Este tipo de puesta en escena no es inusual. La semana anterior, el enviado estadounidense para Oriente Medio, Steve Witkoff, que lleg\u00f3 a Mosc\u00fa a primera hora de la tarde, s\u00f3lo obtuvo audiencia al final del d\u00eda.<\/li>\n\n\n\n<li>Desde que el presidente estadounidense volvi\u00f3 al poder el 20 de enero, ha sido sobre todo la Casa Blanca la que ha se\u00f1alado su deseo de abrir r\u00e1pidamente una l\u00ednea de contacto directo entre los dos presidentes. Trump, convencido de que es el \u00fanico l\u00edder capaz de tratar con Putin, tambi\u00e9n est\u00e1 presionando para que se organice un encuentro en persona.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Informe de la Casa Blanca<\/h3>\n\n\n\n<p><em>Hoy, el presidente Trump y el presidente Putin han hablado de la necesidad de paz y de un alto el fuego en la guerra en Ucrania. Ambos l\u00edderes han acordado que este conflicto debe terminar con una paz duradera. Tambi\u00e9n han subrayado la necesidad de mejorar las relaciones bilaterales entre Estados Unidos y Rusia. La sangre y los recursos que Ucrania y Rusia han gastado en esta guerra se utilizar\u00edan mejor para satisfacer las necesidades de sus poblaciones.<\/em><\/p>\n\n\n\n<p><em>Este conflicto nunca deber\u00eda haber estallado y deber\u00eda haberse resuelto hace mucho tiempo mediante esfuerzos de paz sinceros y de buena fe. Los l\u00edderes acordaron que el movimiento hacia la paz comenzar\u00eda con un alto el fuego energ\u00e9tico y de infraestructura, as\u00ed como con negociaciones t\u00e9cnicas sobre la implementaci\u00f3n de un alto el fuego mar\u00edtimo en el Mar Negro, un alto el fuego total y una paz permanente. Estas negociaciones comenzar\u00e1n de inmediato en el Medio Oriente.<\/em><\/p>\n\n\n\n<p><em>Los l\u00edderes hablaron ampliamente sobre Oriente Medio como una regi\u00f3n de cooperaci\u00f3n potencial para prevenir futuros conflictos. Tambi\u00e9n discutieron la necesidad de poner fin a la proliferaci\u00f3n de armas estrat\u00e9gicas y se comprometer\u00e1n con otros pa\u00edses para asegurar la aplicaci\u00f3n m\u00e1s amplia posible. Ambos l\u00edderes compartieron la opini\u00f3n de que Ir\u00e1n nunca deber\u00eda ser capaz de destruir Israel.<\/em><\/p>\n\n\n\n<p><em>Los dos l\u00edderes convinieron en que una futura mejora de las relaciones bilaterales entre Estados Unidos y Rusia presenta enormes ventajas. Esto incluye enormes acuerdos econ\u00f3micos y estabilidad geopol\u00edtica una vez que se logre la paz.<\/em><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Informe del Kremlin<\/h3>\n\n\n\n<p><em>Los l\u00edderes mantuvieron un intercambio detallado y franco de puntos de vista sobre la situaci\u00f3n en Ucrania. Vladimir Putin expres\u00f3 su gratitud a Donald Trump por su compromiso de contribuir al noble objetivo de poner fin a las hostilidades y las p\u00e9rdidas humanas.<\/em><\/p>\n\n\n\n<p><em>Al reafirmar su compromiso de principio con una resoluci\u00f3n pac\u00edfica del conflicto, el presidente ruso declar\u00f3 que estaba dispuesto a trabajar con sus socios estadounidenses para examinar detenidamente las opciones de resoluci\u00f3n. Este enfoque debe ser global, estable y a largo plazo, y tener en cuenta la necesidad absoluta de eliminar las causas profundas de la crisis, as\u00ed como los leg\u00edtimos intereses de Rusia en materia de seguridad.<\/em><\/p>\n\n\n\n<p><em>En el contexto de la iniciativa del presidente estadounidense de un alto el fuego de 30 d\u00edas, la parte rusa ha subrayado varios puntos esenciales relacionados con el establecimiento de un control eficaz sobre un posible cese de los disparos a lo largo de toda la l\u00ednea de frente, la necesidad de detener la movilizaci\u00f3n forzada en Ucrania y el rearme de las fuerzas armadas ucranianas. Tambi\u00e9n se mencionaron riesgos graves, en particular la incapacidad del r\u00e9gimen de Kiev para respetar los acuerdos, que ya ha saboteado y violado en varias ocasiones los compromisos adquiridos. Se llam\u00f3 la atenci\u00f3n sobre los cr\u00edmenes b\u00e1rbaros de naturaleza terrorista cometidos por combatientes ucranianos contra la poblaci\u00f3n civil de la regi\u00f3n de Kursk.<\/em><\/p>\n\n\n\n<p><em>Se ha subrayado que las condiciones clave para evitar una escalada del conflicto y trabajar para su resoluci\u00f3n por medios pol\u00edtico-diplom\u00e1ticos incluyen el cese total del apoyo militar occidental a Ucrania y el fin de la transmisi\u00f3n de informaci\u00f3n a Kiev.<\/em><\/p>\n\n\n\n<p><em>En respuesta al reciente llamamiento de Donald Trump para salvar la vida de los militares ucranianos rodeados en la regi\u00f3n de Kursk, Vladimir Putin confirm\u00f3 que las autoridades rusas est\u00e1n dispuestas a considerar medidas humanitarias, siempre que las fuerzas armadas ucranianas cesen todo combate y depongan las armas, de conformidad con las leyes y normas del derecho internacional.<\/em><\/p>\n\n\n\n<p><em>Durante la conversaci\u00f3n, Donald Trump propuso un cese mutuo de los ataques a las infraestructuras energ\u00e9ticas durante 30 d\u00edas. Vladimir Putin acogi\u00f3 favorablemente esta iniciativa e inmediatamente dio las instrucciones necesarias a las fuerzas rusas.<\/em><\/p>\n\n\n\n<p><em>El presidente ruso tambi\u00e9n reaccion\u00f3 de manera constructiva a la idea de Donald Trump de poner en pr\u00e1ctica una iniciativa existente sobre la seguridad de la navegaci\u00f3n en el Mar Negro. Se acord\u00f3 iniciar negociaciones para desarrollar m\u00e1s los detalles concretos de este acuerdo.<\/em><\/p>\n\n\n\n<p><em>Vladimir Putin inform\u00f3 de que el 19 de marzo se llevar\u00eda a cabo un intercambio de prisioneros entre Rusia y Ucrania, en el que participar\u00edan 175 prisioneros de cada lado. Adem\u00e1s, como muestra de buena voluntad, se entregar\u00e1n a Ucrania 23 soldados ucranianos gravemente heridos, que est\u00e1n siendo tratados en centros m\u00e9dicos rusos.<\/em><\/p>\n\n\n\n<p><em>Los l\u00edderes confirmaron su intenci\u00f3n de continuar los esfuerzos para lograr una soluci\u00f3n al conflicto de Ucrania en un marco bilateral, teniendo en cuenta tambi\u00e9n las propuestas del presidente estadounidense. Con este fin, se crear\u00e1n grupos de expertos rusos y estadounidenses.<\/em><\/p>\n\n\n\n<p><em>Vladimir Putin y Donald Trump tambi\u00e9n abordaron otros asuntos internacionales, en particular la situaci\u00f3n en Oriente Medio y la regi\u00f3n del Mar Rojo. Se realizar\u00e1n esfuerzos conjuntos para estabilizar las zonas de crisis, mejorar la cooperaci\u00f3n en materia de no proliferaci\u00f3n nuclear y garantizar la seguridad mundial. Entre otras cosas, esto deber\u00eda favorecer la reanudaci\u00f3n del di\u00e1logo entre las fuerzas armadas rusas y estadounidenses. Un ejemplo positivo reciente ha sido la votaci\u00f3n conjunta en las Naciones Unidas de una resoluci\u00f3n relacionada con el conflicto de Ucrania.<\/em><\/p>\n\n\n\n<p><em>Ambas partes expresaron su inter\u00e9s com\u00fan en normalizar las relaciones bilaterales, dada la responsabilidad particular de Rusia y Estados Unidos en el mantenimiento de la seguridad y la estabilidad mundiales. En este contexto, se examin\u00f3 una amplia gama de posibles \u00e1mbitos de cooperaci\u00f3n. Se debatieron varias ideas con miras al futuro desarrollo de una colaboraci\u00f3n mutuamente beneficiosa en los \u00e1mbitos de la econom\u00eda y la energ\u00eda.<\/em><\/p>\n\n\n\n<p><em>Donald Trump apoy\u00f3 la idea de Vladimir Putin de organizar partidos de hockey entre Rusia y Estados Unidos, en los que participen jugadores rusos y estadounidenses de la NHL y la KHL.<\/em><\/p>\n\n\n\n<p><em>Los presidentes acordaron mantenerse en contacto sobre todas las cuestiones abordadas.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una semana despu\u00e9s de que Ucrania aceptara la propuesta de alto el fuego estadounidense, Donald Trump habl\u00f3 hoy, martes 18 de marzo, con Vladimir Putin por tel\u00e9fono durante unas dos horas y media, seg\u00fan la Casa Blanca y el Kremlin. Rusia ha aceptado un alto el fuego de 30 d\u00edas en relaci\u00f3n con los ataques a las infraestructuras energ\u00e9ticas.<\/p>\n","protected":false},"author":1366,"featured_media":60546,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":true,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":8,"footnotes":""},"categories":[216],"tags":[],"staff":[],"editorial_format":[1472],"serie":[],"audience":[],"geo":[177],"class_list":["post-60554","post","type-post","status-publish","format-standard","hentry","category-la-guerra-en-ucrania-dia-a-dia","editorial_format-analisis","geo-europa"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":60546,"excerpt":"Una semana despu\u00e9s de que Ucrania aceptara la propuesta de alto el fuego estadounidense, Donald Trump habl\u00f3 hoy, martes 18 de marzo, con Vladimir Putin por tel\u00e9fono durante unas dos horas y media, seg\u00fan la Casa Blanca y el Kremlin. Rusia ha aceptado un alto el fuego de 30 d\u00edas en relaci\u00f3n con los ataques a las infraestructuras energ\u00e9ticas.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Llamada Trump-Putin: Rusia exige \u00abel cese total de la ayuda militar a Kiev\u00bb como condici\u00f3n para el cese de los combates - El Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/es\/2025\/03\/18\/llamada-trump-putin-rusia-exige-el-cese-total-de-la-ayuda-militar-a-kiev-como-condicion-para-el-cese-de-los-combates\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Llamada Trump-Putin: Rusia exige \u00abel cese total de la ayuda militar a Kiev\u00bb como condici\u00f3n para el cese de los combates - El Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Una semana despu\u00e9s de que Ucrania aceptara la propuesta de alto el fuego estadounidense, Donald Trump habl\u00f3 hoy, martes 18 de marzo, con Vladimir Putin por tel\u00e9fono durante unas dos horas y media, seg\u00fan la Casa Blanca y el Kremlin. Rusia ha aceptado un alto el fuego de 30 d\u00edas en relaci\u00f3n con los ataques a las infraestructuras energ\u00e9ticas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/es\/2025\/03\/18\/llamada-trump-putin-rusia-exige-el-cese-total-de-la-ayuda-militar-a-kiev-como-condicion-para-el-cese-de-los-combates\/\" \/>\n<meta property=\"og:site_name\" content=\"El Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-18T18:07:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-18T18:07:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/03\/gc-elllamada-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"florent\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/03\/gc-elllamada-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"florent\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/03\/18\/llamada-trump-putin-rusia-exige-el-cese-total-de-la-ayuda-militar-a-kiev-como-condicion-para-el-cese-de-los-combates\/\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/2025\/03\/18\/llamada-trump-putin-rusia-exige-el-cese-total-de-la-ayuda-militar-a-kiev-como-condicion-para-el-cese-de-los-combates\/\",\"name\":\"Llamada Trump-Putin: Rusia exige \u00abel cese total de la ayuda militar a Kiev\u00bb como condici\u00f3n para el cese de los combates - El Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/03\/18\/llamada-trump-putin-rusia-exige-el-cese-total-de-la-ayuda-militar-a-kiev-como-condicion-para-el-cese-de-los-combates\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/03\/18\/llamada-trump-putin-rusia-exige-el-cese-total-de-la-ayuda-militar-a-kiev-como-condicion-para-el-cese-de-los-combates\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/03\/SIPA_ap22929033_000009-scaled.jpg\",\"datePublished\":\"2025-03-18T18:07:16+00:00\",\"dateModified\":\"2025-03-18T18:07:19+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/03\/18\/llamada-trump-putin-rusia-exige-el-cese-total-de-la-ayuda-militar-a-kiev-como-condicion-para-el-cese-de-los-combates\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/es\/2025\/03\/18\/llamada-trump-putin-rusia-exige-el-cese-total-de-la-ayuda-militar-a-kiev-como-condicion-para-el-cese-de-los-combates\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/03\/18\/llamada-trump-putin-rusia-exige-el-cese-total-de-la-ayuda-militar-a-kiev-como-condicion-para-el-cese-de-los-combates\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/03\/SIPA_ap22929033_000009-scaled.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/03\/SIPA_ap22929033_000009-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Russian President Vladimir Putin speaks on the phone with Arina Porkhal, a 15-year-old girl from the Donetsk in Russian-controlled Donetsk region, as part of the New Year Tree of Wishes nationwide charity campaign, at the Kremlin in Moscow, Russia, Tuesday, Jan. 7, 2025. (Alexander Kazakov, Sputnik, Kremlin Pool Photo via AP)\/XAZ219\/25007456773284\/POOL PHOTO ALTERNATIVE CROP\/2501071346\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2025\/03\/18\/llamada-trump-putin-rusia-exige-el-cese-total-de-la-ayuda-militar-a-kiev-como-condicion-para-el-cese-de-los-combates\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/legrandcontinent.eu\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Llamada Trump-Putin: Rusia exige \u00abel cese total de la ayuda militar a Kiev\u00bb como condici\u00f3n para el cese de los combates\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/\",\"name\":\"El Grand Continent\",\"description\":\"La escala pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\",\"name\":\"florent\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"caption\":\"florent\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Llamada Trump-Putin: Rusia exige \u00abel cese total de la ayuda militar a Kiev\u00bb como condici\u00f3n para el cese de los combates - El Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/es\/2025\/03\/18\/llamada-trump-putin-rusia-exige-el-cese-total-de-la-ayuda-militar-a-kiev-como-condicion-para-el-cese-de-los-combates\/","og_locale":"es_ES","og_type":"article","og_title":"Llamada Trump-Putin: Rusia exige \u00abel cese total de la ayuda militar a Kiev\u00bb como condici\u00f3n para el cese de los combates - El Grand Continent","og_description":"Una semana despu\u00e9s de que Ucrania aceptara la propuesta de alto el fuego estadounidense, Donald Trump habl\u00f3 hoy, martes 18 de marzo, con Vladimir Putin por tel\u00e9fono durante unas dos horas y media, seg\u00fan la Casa Blanca y el Kremlin. Rusia ha aceptado un alto el fuego de 30 d\u00edas en relaci\u00f3n con los ataques a las infraestructuras energ\u00e9ticas.","og_url":"https:\/\/legrandcontinent.eu\/es\/2025\/03\/18\/llamada-trump-putin-rusia-exige-el-cese-total-de-la-ayuda-militar-a-kiev-como-condicion-para-el-cese-de-los-combates\/","og_site_name":"El Grand Continent","article_published_time":"2025-03-18T18:07:16+00:00","article_modified_time":"2025-03-18T18:07:19+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/03\/gc-elllamada-scaled.jpg","type":"image\/jpeg"}],"author":"florent","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2025\/03\/gc-elllamada-scaled.jpg","twitter_misc":{"Escrito por":"florent","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/es\/2025\/03\/18\/llamada-trump-putin-rusia-exige-el-cese-total-de-la-ayuda-militar-a-kiev-como-condicion-para-el-cese-de-los-combates\/","url":"https:\/\/legrandcontinent.eu\/es\/2025\/03\/18\/llamada-trump-putin-rusia-exige-el-cese-total-de-la-ayuda-militar-a-kiev-como-condicion-para-el-cese-de-los-combates\/","name":"Llamada Trump-Putin: Rusia exige \u00abel cese total de la ayuda militar a Kiev\u00bb como condici\u00f3n para el cese de los combates - El Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/es\/2025\/03\/18\/llamada-trump-putin-rusia-exige-el-cese-total-de-la-ayuda-militar-a-kiev-como-condicion-para-el-cese-de-los-combates\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/es\/2025\/03\/18\/llamada-trump-putin-rusia-exige-el-cese-total-de-la-ayuda-militar-a-kiev-como-condicion-para-el-cese-de-los-combates\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/03\/SIPA_ap22929033_000009-scaled.jpg","datePublished":"2025-03-18T18:07:16+00:00","dateModified":"2025-03-18T18:07:19+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/es\/2025\/03\/18\/llamada-trump-putin-rusia-exige-el-cese-total-de-la-ayuda-militar-a-kiev-como-condicion-para-el-cese-de-los-combates\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/es\/2025\/03\/18\/llamada-trump-putin-rusia-exige-el-cese-total-de-la-ayuda-militar-a-kiev-como-condicion-para-el-cese-de-los-combates\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/2025\/03\/18\/llamada-trump-putin-rusia-exige-el-cese-total-de-la-ayuda-militar-a-kiev-como-condicion-para-el-cese-de-los-combates\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/03\/SIPA_ap22929033_000009-scaled.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/03\/SIPA_ap22929033_000009-scaled.jpg","width":2560,"height":1707,"caption":"Russian President Vladimir Putin speaks on the phone with Arina Porkhal, a 15-year-old girl from the Donetsk in Russian-controlled Donetsk region, as part of the New Year Tree of Wishes nationwide charity campaign, at the Kremlin in Moscow, Russia, Tuesday, Jan. 7, 2025. (Alexander Kazakov, Sputnik, Kremlin Pool Photo via AP)\/XAZ219\/25007456773284\/POOL PHOTO ALTERNATIVE CROP\/2501071346"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/es\/2025\/03\/18\/llamada-trump-putin-rusia-exige-el-cese-total-de-la-ayuda-militar-a-kiev-como-condicion-para-el-cese-de-los-combates\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legrandcontinent.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Llamada Trump-Putin: Rusia exige \u00abel cese total de la ayuda militar a Kiev\u00bb como condici\u00f3n para el cese de los combates"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/es\/#website","url":"https:\/\/legrandcontinent.eu\/es\/","name":"El Grand Continent","description":"La escala pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c","name":"florent","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","caption":"florent"}}]}},"lgc_categories":[{"id":216,"name":"La guerra en Ucrania d\u00eda a d\u00eda","slug":"la-guerra-en-ucrania-dia-a-dia"}],"lgc_author":null,"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/03\/SIPA_ap22929033_000009-scaled.jpg","width":2560,"height":1707,"alt":""},"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/60554","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/users\/1366"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/comments?post=60554"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/60554\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media\/60546"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media?parent=60554"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/categories?post=60554"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/tags?post=60554"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/staff?post=60554"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/editorial_format?post=60554"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/serie?post=60554"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/audience?post=60554"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/geo?post=60554"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}