{"id":5146,"date":"2022-06-23T18:30:00","date_gmt":"2022-06-23T17:30:00","guid":{"rendered":"https:\/\/legrandcontinent.eu\/es\/?p=5146"},"modified":"2022-06-24T09:23:17","modified_gmt":"2022-06-24T08:23:17","slug":"comienza-la-14a-cumbre-de-los-brics","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/es\/2022\/06\/23\/comienza-la-14a-cumbre-de-los-brics\/","title":{"rendered":"Comienza la 14\u00aa Cumbre de los BRICS"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li>El foro de los BRICS es un grupo de cinco pa\u00edses que re\u00fane a las principales \u00abeconom\u00edas emergentes\u00bb y que pretende luchar contra la influencia econ\u00f3mica de los pa\u00edses del G7, que agrupa a las siete mayores potencias econ\u00f3micas del mundo occidental: Estados Unidos, Jap\u00f3n, Alemania, Reino Unido, Francia, Italia y Canad\u00e1. Con el tel\u00f3n de fondo de la guerra en Ucrania y las sanciones masivas impuestas a Rusia por los Estados occidentales, esta 14\u00aa Cumbre de los BRICS se inaugura en un clima particularmente tenso.<\/li><\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-large  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/54JRK\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<ul class=\"wp-block-list\"><li>Antes de la cumbre, Vladimir Putin critic\u00f3 las sanciones occidentales y dijo que Rusia estaba reorientando sus intercambios comerciales con los BRICS, a los que considera m\u00e1s \u00abfiables\u00bb que Europa y Estados Unidos, pues estos \u00faltimos se est\u00e1n alejando progresivamente de los productos rusos, especialmente en el sector energ\u00e9tico&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-5146' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2022\/06\/23\/comienza-la-14a-cumbre-de-los-brics\/#easy-footnote-bottom-1-5146' title='\u201c&lt;a href=&quot;https:\/\/www.themoscowtimes.com\/2022\/06\/22\/putin-pushes-for-stronger-ties-with-brics-nations-a78073&quot;&gt;Putin Pushes for Stronger Ties with BRICS Nations&lt;\/a&gt;\u201d, &lt;em&gt;The Moscow Times&lt;\/em&gt;, 22 de junio de 2022.'><sup>1<\/sup><\/a><\/span><\/span>. Es la primera vez que Putin asiste a una cumbre internacional desde que comenz\u00f3 la guerra en Ucrania el 24 de febrero.<\/li><\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-large  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/bFTHf\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<ul class=\"wp-block-list\"><li>Seg\u00fan un informe de la Agencia Internacional de la Energ\u00eda (AIE), las exportaciones de petr\u00f3leo ruso a China aumentaron un 55% en mayo de 2022 respecto al a\u00f1o anterior, lo que convierte a Mosc\u00fa en el mayor proveedor de petr\u00f3leo de China, por delante de Arabia Saudita&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-5146' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2022\/06\/23\/comienza-la-14a-cumbre-de-los-brics\/#easy-footnote-bottom-2-5146' title='Agencia internacional de la Energ\u00eda,&lt;a href=&quot;https:\/\/www.iea.org\/reports\/oil-market-report-june-2022&quot;&gt; Oil Market Report &amp;#8211; June 2022&lt;\/a&gt;.'><sup>2<\/sup><\/a><\/span><\/span>. Al mismo tiempo, las exportaciones rusas de petr\u00f3leo por barco a la India han aumentado considerablemente, y alcanzan ahora los 760 mil barriles diarios. Estas ventas tienen un descuento \u2014de unos 70-80 d\u00f3lares por barril\u2014 respecto al precio del petr\u00f3leo Brent en los mercados internacionales. En mayo de este a\u00f1o, el 16.5% de las importaciones de petr\u00f3leo de India proced\u00edan de Rusia, frente al 1% del a\u00f1o anterior&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-5146' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2022\/06\/23\/comienza-la-14a-cumbre-de-los-brics\/#easy-footnote-bottom-3-5146' title='\u00a0Nidhi Verma y Jonathan Saul&lt;em&gt;,&lt;\/em&gt;&lt;a href=&quot;https:\/\/www.reuters.com\/article\/ukraine-crisis-india-certification-idAFL8N2Y8474&quot;&gt; EXCLUSIVE-Russian oil tankers get India safety cover via Dubai company&lt;\/a&gt;, &lt;em&gt;Reuters, &lt;\/em&gt;22 de junio de 2022.'><sup>3<\/sup><\/a><\/span><\/span>.<\/li><\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-large  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/eCgkY\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<ul class=\"wp-block-list\"><li>En declaraciones previas a la cumbre, Vladimir Putin tambi\u00e9n expres\u00f3 su deseo de crear una nueva cesta de divisas \u2014yuan, rublo, real brasile\u00f1o, rupia india y rand sudafricano\u2014 como nueva moneda de reserva com\u00fan, para dejar atr\u00e1s los Derechos Especiales de Giro (DEG) del FMI. Dado que un n\u00famero importante de bancos rusos se han visto privados de la mayor\u00eda de las transacciones en d\u00f3lares estadounidenses debido a las sanciones, Putin tiene un gran inter\u00e9s en convencer a las dem\u00e1s potencias de los BRICS de que aprovechen este contexto para empezar a alejarse de las monedas occidentales, encabezadas por el d\u00f3lar y el euro.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li>El presidente chino, Xi Jinping, ha calificado las sanciones occidentales de \u00abartiller\u00eda\u00bb de la econom\u00eda mundial. Aunque la posici\u00f3n de China ha sido m\u00e1s bien ambigua desde el comienzo de la guerra en Ucrania, poco a poco se est\u00e1 convirtiendo en <a href=\"https:\/\/legrandcontinent.eu\/es\/2022\/06\/16\/china-muestra-un-mayor-apoyo-a-rusia\/\">un apoyo cada vez m\u00e1s firme para Rusia<\/a>. En el mismo discurso, Xi Jinping se refiri\u00f3 a la \u00abcrisis ucraniana\u00bb (evitando el t\u00e9rmino guerra) como el resultado de un intento de \u00abampliar las alianzas militares\u00bb que s\u00f3lo puede conducir a un \u00abdilema de seguridad\u00bb. En una cr\u00edtica apenas velada a la OTAN, haciendo eco del argumento del Kremlin, Xi Jinping hace eco tambi\u00e9n de la situaci\u00f3n de Taiw\u00e1n, que sigue recibiendo equipamiento militar occidental&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-4-5146' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2022\/06\/23\/comienza-la-14a-cumbre-de-los-brics\/#easy-footnote-bottom-4-5146' title='\u201c&lt;a href=&quot;https:\/\/www.nytimes.com\/2022\/05\/24\/us\/politics\/china-taiwan-military.html&quot;&gt;Edward Wong et Eric Schmitt, U.S. Speeds Up Reshaping of Taiwan\u2019s Defenses to Deter China&lt;\/a&gt;\u00ab, &lt;em&gt;The New York Times&lt;\/em&gt;, 24 de mayo de 2022.'><sup>4<\/sup><\/a><\/span><\/span>.<\/li><\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-large  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/EsC5n\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<ul class=\"wp-block-list\"><li>Para India, la cumbre de los BRICS es una oportunidad para mostrar su posici\u00f3n de no alineaci\u00f3n. Por un lado, India, al igual que China, se neg\u00f3 a condenar a Rusia en el Consejo de Seguridad de la ONU y luego en la Asamblea General. Por otra parte, la rivalidad entre India y China en torno a Cachemira y la presencia de Nueva Delhi como eslab\u00f3n clave en la estrategia Indo-Pac\u00edfica de Estados Unidos empujar\u00e1n con toda seguridad a India a rechazar la promoci\u00f3n de mensajes demasiado en\u00e9rgicos contra Estados Unidos en esta Cumbre&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-5-5146' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2022\/06\/23\/comienza-la-14a-cumbre-de-los-brics\/#easy-footnote-bottom-5-5146' title='\u00a0Sudhi Ranjan Sen, \u201c&lt;a href=&quot;https:\/\/www.bloomberg.com\/news\/articles\/2022-06-21\/india-to-resist-anti-us-messaging-at-brics-summit-with-xi-putin&quot;&gt;India to Resist Anti-US Messaging at BRICS Summit With Xi, Putin&lt;\/a&gt;\u00ab, &lt;em&gt;Bloomberg&lt;\/em&gt;, 21 de junio de 2022.'><sup>5<\/sup><\/a><\/span><\/span>.<\/li><\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-large  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/zDbXz\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<ul class=\"wp-block-list\"><li>Para el Brasil de Jair Bolsonaro, la situaci\u00f3n es bastante confusa. Aunque Brasil conden\u00f3 la agresi\u00f3n militar rusa en las Naciones Unidas el 2 de marzo, el presidente brasile\u00f1o declar\u00f3 desde el principio del conflicto que su pa\u00eds se mantendr\u00eda \u00abneutral\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-6-5146' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2022\/06\/23\/comienza-la-14a-cumbre-de-los-brics\/#easy-footnote-bottom-6-5146' title='Gabriel Stargardter, \u201c&lt;a href=&quot;https:\/\/www.reuters.com\/world\/bolsonaro-wont-condemn-putin-says-brazil-will-remain-neutral-over-invasion-2022-02-27\/&quot;&gt;Bolsonaro won&amp;#8217;t condemn Putin, says Brazil will remain neutral over invasion&lt;\/a&gt;\u00ab, &lt;em&gt;Reuters&lt;\/em&gt;, 28 de febrero de 2022.'><sup>6<\/sup><\/a><\/span><\/span>. Brasil, que depende de los fertilizantes rusos para su econom\u00eda agr\u00edcola, tampoco quiere oponerse frontalmente a Estados Unidos, pues Bolsonaro se reuni\u00f3 por primera vez con Joe Biden a pocos meses de las pr\u00f3ximas elecciones presidenciales brasile\u00f1as. Por \u00faltimo, el presidente de Sud\u00e1frica, Cyril Ramaphosa, asegur\u00f3 antes de la cumbre que las relaciones econ\u00f3micas entre su pa\u00eds y el resto de los miembros de los BRICS eran fundamentales, y anunci\u00f3 que quer\u00eda seguir trabajando por el acercamiento econ\u00f3mico con Brasil, Rusia, India y China&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-7-5146' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2022\/06\/23\/comienza-la-14a-cumbre-de-los-brics\/#easy-footnote-bottom-7-5146' title='&lt;a href=&quot;https:\/\/presidency.click.bulkmailapp.co.za\/social\/s_enc\/DfzQjO8MTJYuj9LZOBq8r35NfApNkW-2N-tsthofjHw&quot;&gt;BRICS partnership has great value for South Africa&lt;\/a&gt;, Presidencia sudafricana, 20 de junio de 2022.'><sup>7<\/sup><\/a><\/span><\/span>.<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Los miembros de los BRICS \u2014Brasil, Rusia, India, China y Sud\u00e1frica\u2014 se re\u00fanen hoy en la 14\u00aa edici\u00f3n de esta cumbre en formato virtual, bajo la presidencia de Xi Jinping. Sometida a sanciones occidentales durante varios meses, Rusia jugar\u00e1 la carta de la \u00abdesvinculaci\u00f3n\u00bb de Occidente y ampliar\u00e1 sus esfuerzos de acercamiento con China.<\/p>\n","protected":false},"author":1366,"featured_media":5147,"comment_status":"open","ping_status":"open","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":4,"footnotes":""},"categories":[6],"tags":[],"staff":[],"editorial_format":[1472],"serie":[],"audience":[],"geo":[197],"class_list":["post-5146","post","type-post","status-publish","format-standard","hentry","category-politica","editorial_format-analisis","geo-asia-oriental"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":5147,"excerpt":"Los miembros de los BRICS \u2014Brasil, Rusia, India, China y Sud\u00e1frica\u2014 se re\u00fanen hoy en la 14\u00aa edici\u00f3n de esta cumbre en formato virtual, bajo la presidencia de Xi Jinping. Sometida a sanciones occidentales durante varios meses, Rusia jugar\u00e1 la carta de la \"desvinculaci\u00f3n\" de Occidente y ampliar\u00e1 sus esfuerzos de acercamiento con China.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Comienza la 14\u00aa Cumbre de los BRICS - El Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/es\/2022\/06\/23\/comienza-la-14a-cumbre-de-los-brics\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comienza la 14\u00aa Cumbre de los BRICS - El Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Los miembros de los BRICS \u2014Brasil, Rusia, India, China y Sud\u00e1frica\u2014 se re\u00fanen hoy en la 14\u00aa edici\u00f3n de esta cumbre en formato virtual, bajo la presidencia de Xi Jinping. Sometida a sanciones occidentales durante varios meses, Rusia jugar\u00e1 la carta de la &quot;desvinculaci\u00f3n&quot; de Occidente y ampliar\u00e1 sus esfuerzos de acercamiento con China.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/es\/2022\/06\/23\/comienza-la-14a-cumbre-de-los-brics\/\" \/>\n<meta property=\"og:site_name\" content=\"El Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-23T17:30:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-24T08:23:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2022\/06\/gc-elbrics.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"809\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"florent\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2022\/06\/gc-elbrics.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"florent\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2022\/06\/23\/comienza-la-14a-cumbre-de-los-brics\/\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/2022\/06\/23\/comienza-la-14a-cumbre-de-los-brics\/\",\"name\":\"Comienza la 14\u00aa Cumbre de los BRICS - El Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2022\/06\/23\/comienza-la-14a-cumbre-de-los-brics\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2022\/06\/23\/comienza-la-14a-cumbre-de-los-brics\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2022\/06\/SIPA_AP22692733_000002-scaled-1.jpeg\",\"datePublished\":\"2022-06-23T17:30:00+00:00\",\"dateModified\":\"2022-06-24T08:23:17+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2022\/06\/23\/comienza-la-14a-cumbre-de-los-brics\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/es\/2022\/06\/23\/comienza-la-14a-cumbre-de-los-brics\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2022\/06\/23\/comienza-la-14a-cumbre-de-los-brics\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2022\/06\/SIPA_AP22692733_000002-scaled-1.jpeg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2022\/06\/SIPA_AP22692733_000002-scaled-1.jpeg\",\"width\":2560,\"height\":1707,\"caption\":\"In this photo released by Xinhua News Agency, Chinese President Xi Jinping delivers a keynote speech in virtual format at the opening ceremony of the BRICS Business Forum on Wednesday, June 22, 2022. The conflict in Ukraine has \\\"sounded an alarm for humanity,\\\" Chinese leader Xi Jinping said Wednesday, as China continues to assume a position of neutrality while backing its ally Russia. (Yin Bogu\/Xinhua via AP)\/XIN801\/22173543254377\/NO SALES, PHOTO RELEASED BY XINHUA NEWS AGENCY\/2206221710\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2022\/06\/23\/comienza-la-14a-cumbre-de-los-brics\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/legrandcontinent.eu\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comienza la 14\u00aa Cumbre de los BRICS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/\",\"name\":\"El Grand Continent\",\"description\":\"La escala pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\",\"name\":\"florent\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"caption\":\"florent\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comienza la 14\u00aa Cumbre de los BRICS - El Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/es\/2022\/06\/23\/comienza-la-14a-cumbre-de-los-brics\/","og_locale":"es_ES","og_type":"article","og_title":"Comienza la 14\u00aa Cumbre de los BRICS - El Grand Continent","og_description":"Los miembros de los BRICS \u2014Brasil, Rusia, India, China y Sud\u00e1frica\u2014 se re\u00fanen hoy en la 14\u00aa edici\u00f3n de esta cumbre en formato virtual, bajo la presidencia de Xi Jinping. Sometida a sanciones occidentales durante varios meses, Rusia jugar\u00e1 la carta de la \"desvinculaci\u00f3n\" de Occidente y ampliar\u00e1 sus esfuerzos de acercamiento con China.","og_url":"https:\/\/legrandcontinent.eu\/es\/2022\/06\/23\/comienza-la-14a-cumbre-de-los-brics\/","og_site_name":"El Grand Continent","article_published_time":"2022-06-23T17:30:00+00:00","article_modified_time":"2022-06-24T08:23:17+00:00","og_image":[{"width":1440,"height":809,"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2022\/06\/gc-elbrics.jpg","type":"image\/jpeg"}],"author":"florent","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2022\/06\/gc-elbrics.jpg","twitter_misc":{"Escrito por":"florent","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/es\/2022\/06\/23\/comienza-la-14a-cumbre-de-los-brics\/","url":"https:\/\/legrandcontinent.eu\/es\/2022\/06\/23\/comienza-la-14a-cumbre-de-los-brics\/","name":"Comienza la 14\u00aa Cumbre de los BRICS - El Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/es\/2022\/06\/23\/comienza-la-14a-cumbre-de-los-brics\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/es\/2022\/06\/23\/comienza-la-14a-cumbre-de-los-brics\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2022\/06\/SIPA_AP22692733_000002-scaled-1.jpeg","datePublished":"2022-06-23T17:30:00+00:00","dateModified":"2022-06-24T08:23:17+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/es\/2022\/06\/23\/comienza-la-14a-cumbre-de-los-brics\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/es\/2022\/06\/23\/comienza-la-14a-cumbre-de-los-brics\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/2022\/06\/23\/comienza-la-14a-cumbre-de-los-brics\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2022\/06\/SIPA_AP22692733_000002-scaled-1.jpeg","contentUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2022\/06\/SIPA_AP22692733_000002-scaled-1.jpeg","width":2560,"height":1707,"caption":"In this photo released by Xinhua News Agency, Chinese President Xi Jinping delivers a keynote speech in virtual format at the opening ceremony of the BRICS Business Forum on Wednesday, June 22, 2022. The conflict in Ukraine has \"sounded an alarm for humanity,\" Chinese leader Xi Jinping said Wednesday, as China continues to assume a position of neutrality while backing its ally Russia. (Yin Bogu\/Xinhua via AP)\/XIN801\/22173543254377\/NO SALES, PHOTO RELEASED BY XINHUA NEWS AGENCY\/2206221710"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/es\/2022\/06\/23\/comienza-la-14a-cumbre-de-los-brics\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legrandcontinent.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Comienza la 14\u00aa Cumbre de los BRICS"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/es\/#website","url":"https:\/\/legrandcontinent.eu\/es\/","name":"El Grand Continent","description":"La escala pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c","name":"florent","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","caption":"florent"}}]}},"lgc_categories":[{"id":6,"name":"Pol\u00edtica","slug":"politica"}],"lgc_author":null,"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2022\/06\/SIPA_AP22692733_000002-scaled-1.jpeg","width":2560,"height":1707,"alt":""},"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/5146","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/users\/1366"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/comments?post=5146"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/5146\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media\/5147"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media?parent=5146"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/categories?post=5146"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/tags?post=5146"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/staff?post=5146"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/editorial_format?post=5146"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/serie?post=5146"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/audience?post=5146"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/geo?post=5146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}