{"id":50879,"date":"2024-12-16T15:55:34","date_gmt":"2024-12-16T14:55:34","guid":{"rendered":"https:\/\/legrandcontinent.eu\/es\/?p=50879"},"modified":"2024-12-16T15:55:39","modified_gmt":"2024-12-16T14:55:39","slug":"alemania-en-la-macrocrisis-autopsia-de-un-pais-roto","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/es\/2024\/12\/16\/alemania-en-la-macrocrisis-autopsia-de-un-pais-roto\/","title":{"rendered":"Alemania en la macrocrisis: autopsia de un pa\u00eds roto"},"content":{"rendered":"\n<p class=\"has-drop-cap\"><a href=\"https:\/\/legrandcontinent.eu\/es\/2024\/11\/07\/la-situacion-es-grave-scholz-expone-la-crisis-politica-en-alemania\/\">Derrumbe de la coalici\u00f3n tripartita en el poder<\/a>, recesi\u00f3n, r\u00e1pida ca\u00edda de la producci\u00f3n industrial y de las exportaciones, infraestructuras en estado deplorable&#8230; Sin duda no es la \u00fanica en Europa, pero Alemania se hunde actualmente en una profunda crisis.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Todos los fundamentos de su modelo social y pol\u00edtico est\u00e1n en entredicho, mientras que las tensiones geopol\u00edticas mundiales ponen en peligro un modelo econ\u00f3mico basado principalmente en las exportaciones. Alemania, primera potencia econ\u00f3mica y demogr\u00e1fica de la Uni\u00f3n Europea, ha desempe\u00f1ado desde el principio un papel decisivo en la integraci\u00f3n europea \u2014papel que se ha visto reforzado desde la ampliaci\u00f3n de la Uni\u00f3n hacia el Este, que la ha situado en el coraz\u00f3n de la Uni\u00f3n\u2014.&nbsp;&nbsp;<\/p>\n\n\n\n<p>\u00bfQu\u00e9 impacto tendr\u00e1 la crisis alemana en el resto del continente? \u00bfAcelerar\u00e1 la integraci\u00f3n europea, a la que los alemanes se han resistido a menudo hasta ahora? \u00bfO, por el contrario, la bloquear\u00e1 a\u00fan m\u00e1s, al replegarse Alemania sobre s\u00ed misma en un reflejo soberanista de salvaci\u00f3n? Antes de plantear cualquier hip\u00f3tesis al respecto, es necesario apreciar plenamente la profundidad de la triple crisis que atraviesa Alemania: una crisis del sistema pol\u00edtico, una crisis de identidad y una crisis econ\u00f3mica. Las distintas dimensiones de esta macrocrisis est\u00e1n estrechamente interconectadas. Sin embargo, es necesario analizarlas por separado si queremos calibrar el alcance de la crisis en cada una de estas dimensiones.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Un sistema pol\u00edtico cada vez m\u00e1s fracturado<\/h2>\n\n\n\n<p>La primera de estas dimensiones se refiere a la crisis del sistema pol\u00edtico alem\u00e1n.&nbsp;<\/p>\n\n\n\n<p>\u00c9ste se ha caracterizado durante mucho tiempo por un sistema bipartidista. Por un lado, los democristianos de la CDU-CSU, que dirigieron el pa\u00eds durante toda la fase de reconstrucci\u00f3n posterior a la Segunda Guerra Mundial. Contrariamente a la creencia popular, la famosa \u00abeconom\u00eda social de mercado\u00bb \u2014que tanto \u00e9xito ha dado a Alemania\u2014 no fue en realidad concebida y aplicada por la socialdemocracia, sino por los democristianos seg\u00fan una l\u00f3gica ordoliberal, una forma de liberalismo que, por supuesto, trata de limitar el papel del Estado \u2014que es el principal responsable de dictar normas y hacerlas cumplir\u2014 pero que, a diferencia de su equivalente anglosaj\u00f3n, tolera la negociaci\u00f3n colectiva entre empresarios y sindicatos y las salvaguardias que pueden establecer. Los Dem\u00f3crata-Cristianos segu\u00edan la misma l\u00f3gica que hab\u00eda impulsado al Canciller conservador Bismarck a crear un sistema avanzado de seguridad social a finales del siglo XIX: el objetivo era contrarrestar el riesgo del comunismo, tanto m\u00e1s presente en la mente de los dirigentes de Alemania Occidental cuanto que el propio pa\u00eds estaba dividido por el Tel\u00f3n de Acero.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Todos los fundamentos del modelo social y pol\u00edtico de Alemania est\u00e1n en entredicho, mientras que las tensiones geopol\u00edticas mundiales ponen en peligro un modelo econ\u00f3mico basado principalmente en las exportaciones.<\/p><cite>GUILLAUME DUVAL<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Frente a ellos estaba el SPD, el Partido Socialdem\u00f3crata. Desde el principio, el SPD hab\u00eda sido el mayor partido socialista de Europa Occidental. Contaba con el apoyo de un movimiento sindical unificado tambi\u00e9n muy poderoso. Sin embargo, no lleg\u00f3 al poder hasta mayo del 68, de la mano del canciller Willy Brandt. Hasta los a\u00f1os 80, el \u00fanico partido que pod\u00eda diversificar la oferta pol\u00edtica y alternar coaliciones era el FDP, un partido peque\u00f1o bisagra, liberal \u2014tanto en lo econ\u00f3mico como en los valores\u2014 y proeuropeo. Desde los a\u00f1os 90, sin embargo, este partido ha ido perdiendo cada vez m\u00e1s su liberalismo social y su car\u00e1cter proeuropeo para convertirse en un verdadero partido thatcheriano en t\u00e9rminos econ\u00f3micos y soberanista en t\u00e9rminos europeos.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Este panorama pol\u00edtico empez\u00f3 a complicarse a finales de los a\u00f1os 70 con la aparici\u00f3n de los Verdes. Desde entonces, esta fuerza pol\u00edtica ha progresado lenta pero constantemente, accediendo poco a poco al gobierno de los L\u00e4nder e incluso dirigiendo ella misma uno de ellos, el de Baden-W\u00fcrttemberg, la regi\u00f3n de Stuttgart, antes de participar en el gobierno federal a principios de la d\u00e9cada de 2000 con el gobierno de Gerhard Schr\u00f6der y actualmente bajo el gobierno de Scholz.<\/p>\n\n\n\n<p>En ocasiones, a principios de la d\u00e9cada de 2000, se pens\u00f3 que el ascenso de los Verdes podr\u00eda haber compensado el declive gradual del SPD en la izquierda, y que los Verdes acabar\u00edan sustituyendo al SPD como uno de los dos partidos dominantes del sistema pol\u00edtico alem\u00e1n. Pero el avance del partido se ha estancado en los \u00faltimos a\u00f1os: en los sondeos para las elecciones de 2025, a los Verdes s\u00f3lo se les atribuye el 10% de los votos. Al igual que en Francia, pero a un nivel superior, su base social, centrada en los alemanes con mayor nivel educativo, sigue siendo demasiado estrecha, y los Verdes alemanes a\u00fan no han conseguido transformarse en un aut\u00e9ntico \u00ab<em>Volkspartei<\/em>\u00bb \u2014un partido del pueblo, como dicen al otro lado del Rin\u2014.&nbsp;<\/p>\n\n\n\n<p>A diferencia de su hom\u00f3logo franc\u00e9s, los Verdes alemanes no son, en t\u00e9rminos econ\u00f3micos, un partido de ruptura con el capitalismo. Tambi\u00e9n forman parte del consenso general alem\u00e1n a favor de las pol\u00edticas de austeridad \u2014aunque con algunas reservas\u2014. Nacido del movimiento antinuclear y pacifista, este partido apoya sin embargo una pol\u00edtica exterior alemana m\u00e1s activa, en particular desde que Joschka Fischer se convirti\u00f3 en Ministro de Asuntos Exteriores del pa\u00eds bajo el Canciller Schr\u00f6der a principios de la d\u00e9cada de 2000. No s\u00f3lo es ahora uno de los partidos alemanes m\u00e1s favorables al apoyo militar a Ucrania, sino que en los \u00faltimos meses, a trav\u00e9s de la ministra de Asuntos Exteriores de los Verdes, Annalena Baerbock, tambi\u00e9n ha sido un firme partidario del gobierno israel\u00ed de Benjamin Netanyahu, en nombre de la responsabilidad hist\u00f3rica de Alemania hacia Israel.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Los Verdes alemanes se han estancado en los \u00faltimos a\u00f1os, con s\u00f3lo un 10% de los votos en las encuestas para las elecciones de 2025.<\/p><cite>GUILLAUME DUVAL<\/cite><\/blockquote><\/figure>\n\n\n\n<p>A principios de los a\u00f1os 90, a este panorama se uni\u00f3 lo que hoy es Die Linke, el partido heredero del Partido Comunista de Alemania Oriental que, a pesar del descr\u00e9dito de la dictadura, hab\u00eda logrado mantener una fuerte presencia en la antigua RDA debido a las frustraciones causadas por una persistente divisi\u00f3n Este-Oeste, con un Este que se despoblaba y segu\u00eda siendo significativamente m\u00e1s pobre que el Oeste del pa\u00eds. Sin embargo, desde principios de la d\u00e9cada de 2000, este anclaje se ha ido erosionando gradualmente debido al envejecimiento del electorado. Desde hace una d\u00e9cada, el partido se encuentra en una crisis permanente y existencial.<\/p>\n\n\n\n<p>M\u00e1s recientemente, la oferta pol\u00edtica se ha diversificado a\u00fan m\u00e1s con <a href=\"https:\/\/legrandcontinent.eu\/es\/2024\/03\/24\/que-significa-la-afd-en-alemania-una-conversacion-con-johann-chapoutot\/\">la aparici\u00f3n en 2013 de Alternative f\u00fcr Deutschland (AfD)<\/a>. Este partido naci\u00f3 como disidencia antieuro del <em>establishment<\/em> liberal alem\u00e1n a ra\u00edz de la crisis griega. A trav\u00e9s de una serie de revueltas a menudo violentas, acab\u00f3 evolucionando hasta convertirse en un poderoso partido de aut\u00e9ntica extrema derecha \u2014con verdaderos neonazis en su seno\u2014 y que ahora sit\u00faa la xenofobia en el centro de su proyecto pol\u00edtico.<\/p>\n\n\n\n<p>El sistema pol\u00edtico alem\u00e1n, basado en la representaci\u00f3n proporcional plena, le ha dado r\u00e1pidamente una visibilidad de la que el Rassemblement National ha carecido durante mucho tiempo en Francia. Con el 10,3% de los votos en 2021, las \u00faltimas elecciones legislativas, cuenta con 83 esca\u00f1os en el Bundestag. Actualmente se le atribuye el 19% de los votos en los sondeos para las elecciones legislativas de 2025. Dada la historia del pa\u00eds en el siglo XX, el resurgimiento de la extrema derecha en Alemania despierta obviamente una gran emoci\u00f3n y preocupaci\u00f3n en el resto de Europa. Sin embargo, no hay que perder de vista que, incluso con un 16,5% en las \u00faltimas elecciones europeas, la extrema derecha sigue siendo en Alemania menos de la mitad de poderosa que en Francia o Italia.<\/p>\n\n\n\n<p>No obstante, est\u00e1 alcanzando niveles \u00abfranceses\u00bb \u2014es decir, por encima del 30% de los votos\u2014 en el este del pa\u00eds. Por supuesto, esto est\u00e1 relacionado con una situaci\u00f3n social y econ\u00f3mica deteriorada, similar a la que se observa en Francia en las zonas m\u00e1s afectadas por la desindustrializaci\u00f3n. Pero tambi\u00e9n est\u00e1 estrechamente relacionado con la historia particular del este de Alemania. En Occidente, el ajuste de cuentas con el pasado nazi del pa\u00eds fue esencialmente el resultado de un profundo movimiento dentro de la sociedad alemana: a ra\u00edz de mayo de 1968, los hijos del baby boom pidieron cuentas a sus padres por el periodo 1933-1945. No ocurri\u00f3 lo mismo en el Este. El antinazismo sigui\u00f3 siendo principalmente un discurso propagand\u00edstico impuesto desde arriba a la sociedad germano-oriental por la dictadura comunista y los ocupantes rusos. Este antinazismo oficial hac\u00eda poco hincapi\u00e9 en el racismo y el antisemitismo del r\u00e9gimen de Hitler, subrayando en cambio los v\u00ednculos de los nazis con los grandes capitalistas alemanes y su imperialismo. Adem\u00e1s, dado que el avance del Ej\u00e9rcito Rojo al final de la Segunda Guerra Mundial vino acompa\u00f1ado de multitud de cr\u00edmenes de guerra \u2014violaciones, limpieza \u00e9tnica, masacres de civiles, saqueos, etc.\u2014, la tendencia de los alemanes del Este a considerar el 8 de mayo de 1945 como una \u00abliberaci\u00f3n\u00bb y no como una derrota fue siempre mucho m\u00e1s limitada que en Alemania Occidental, donde esa idea lleg\u00f3 a dominar. No es de extra\u00f1ar, por tanto, que sea en el este del pa\u00eds donde la extrema derecha xen\u00f3foba haya encontrado el caldo de cultivo m\u00e1s propicio para resurgir de sus cenizas.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>En el Este, el antinazismo sigui\u00f3 siendo principalmente un discurso propagand\u00edstico impuesto desde arriba a la sociedad germano-oriental por la dictadura comunista y los ocupantes rusos.<\/p><cite>GUILLAUME DUVAL<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Dada esta historia, lo que puede parecer m\u00e1s sorprendente a primera vista es que esta extrema derecha sea tambi\u00e9n uno de los apoyos m\u00e1s decididos de Vladimir Putin en la opini\u00f3n p\u00fablica alemana. Aunque tambi\u00e9n juega con el registro poscomunista al afirmar que quiere \u00abdesnazificar\u00bb Ucrania, Putin encarna hoy sobre todo todo lo que m\u00e1s atrae a la extrema derecha en Europa y, por tanto, tambi\u00e9n en Alemania: el racismo, el masculinismo, la exaltaci\u00f3n de la violencia, el autoritarismo y el desprecio por el Estado de derecho.<\/p>\n\n\n\n<p>A esto hay que a\u00f1adir, sin duda, una resonancia con el viejo trasfondo imperial alem\u00e1n que ya hab\u00eda constituido la base del pacto germano-sovi\u00e9tico en los a\u00f1os 30: en esta visi\u00f3n del mundo, el espacio que separa Alemania de Rusia s\u00f3lo estar\u00eda ocupado b\u00e1sicamente por Estados ileg\u00edtimos. Alemanes y rusos tendr\u00edan que ponerse de acuerdo para compartirlo. No hay que olvidar, en particular, que una parte sustancial del territorio de la Polonia posterior a 1945 est\u00e1 formada por tierras que hab\u00edan sido alemanas durante mucho tiempo.&nbsp;<\/p>\n\n\n\n<p>La \u00faltima incorporaci\u00f3n al paisaje cada vez m\u00e1s fragmentado de la pol\u00edtica alemana es la <em>B\u00fcndnis Sara Wagenknecht<\/em> (BSW), que apareci\u00f3 la primavera pasada \u2014un ovni pol\u00edtico\u2014. Este partido, surgido de una escisi\u00f3n de Die Linke, es a la vez conservador en cuestiones sociales \u2014en particular la inmigraci\u00f3n\u2014 y bastante radical en cuestiones sociales y econ\u00f3micas. Tambi\u00e9n es pro-Putin en pol\u00edtica exterior. Sara Wagenknecht, de 55 a\u00f1os, naci\u00f3 y se educ\u00f3 en Alemania del Este. En la d\u00e9cada de 2000, se convirti\u00f3 en una de las figuras m\u00e1s destacadas de Die Linke, en particular presidiendo su grupo parlamentario en el Bundestag, al tiempo que se convert\u00eda en compa\u00f1era de Oskar Lafontaine, antiguo Secretario General del SPD y antiguo candidato del SPD a la Canciller\u00eda, cofundador de Die Linke tras romper con el gobierno de Gerhard Schr\u00f6der.<\/p>\n\n\n\n<p>Poco a poco se fue distanciando de Die Linke \u2014principalmente en el tema de la migraci\u00f3n, oponi\u00e9ndose a la pol\u00edtica de acogida aplicada por el gobierno de Angela Merkel en el momento de la crisis de 2015\u2014 para finalmente crear su propio movimiento pol\u00edtico este a\u00f1o. Con relativa sencillez, le dio su propio nombre, un gesto sin precedentes en la historia pol\u00edtica de Alemania, un pa\u00eds que hasta ahora se hab\u00eda librado en gran medida de la deriva individualista inducida en Francia o Estados Unidos por las elecciones presidenciales. Ni siquiera En Marche se llam\u00f3 Alianza Emmanuel Macron en Francia, ni La France Insoumise Alianza Jean-Luc M\u00e9lenchon, aunque ambos movimientos est\u00e9n muy personalizados&#8230; BSW cuenta actualmente con un 8% de los votos en las encuestas y acaba de lograr <a href=\"https:\/\/legrandcontinent.eu\/es\/2024\/09\/02\/la-afd-se-impone-en-turingia-por-un-amplio-margen\/\">resultados de dos d\u00edgitos al entrar en liza en las elecciones regionales de Turingia<\/a>, <a href=\"https:\/\/legrandcontinent.eu\/es\/2024\/09\/22\/record-de-participacion-en-brandeburgo-la-extrema-derecha-no-logra-superar-al-spd-pero-entre-los-jovenes-la-afd-es-el-partido-lider\/\">Brandeburgo<\/a> y <a href=\"https:\/\/legrandcontinent.eu\/es\/2024\/09\/01\/ganara-la-afd-en-sajonia-y-turingia\/\">Sajonia<\/a>, en el este del pa\u00eds.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/M2Dil\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Pero el hecho m\u00e1s llamativo de la crisis pol\u00edtica alemana es el hundimiento del SPD, principal partido socialdem\u00f3crata de Europa occidental desde finales del siglo XIX.<\/p>\n\n\n\n<p>Tras haber alcanzado un m\u00e1ximo del 45% de los votos en 1972 y haber superado a\u00fan el 40% en 1998, cuando la era Helmut Kohl lleg\u00f3 a su fin, el SPD cuenta ahora con s\u00f3lo el 16% en las encuestas para las elecciones generales de 2025. Despu\u00e9s de 1989, se pod\u00eda pensar que la ca\u00edda del Muro de Berl\u00edn beneficiar\u00eda a los socialdem\u00f3cratas en Europa. <a href=\"https:\/\/legrandcontinent.eu\/es\/2024\/05\/28\/la-nueva-cuestion-alemana\/\">Treinta y cinco a\u00f1os m\u00e1s tarde<\/a>, hay que decir que Alemania no es una excepci\u00f3n: la ca\u00edda del Muro parece haberse llevado consigo a la socialdemocracia al mismo tiempo que el comunismo.<\/p>\n\n\n\n<p>Como en otras partes, el ascenso al poder dentro del partido y de sus estructuras dirigentes de clases medias con formaci\u00f3n universitaria ha alejado a los trabajadores y a las clases trabajadoras, que se decantan cada vez m\u00e1s hacia la derecha y la extrema derecha. Este fen\u00f3meno se vio exacerbado en Alemania por la elecci\u00f3n de una orientaci\u00f3n social-liberal muy agresiva durante el gobierno de Gerhard Schr\u00f6der entre 1998 y 2005. Durante este periodo, Schr\u00f6der llev\u00f3 a cabo un replanteamiento bastante radical del Estado del bienestar alem\u00e1n, que dividi\u00f3 y debilit\u00f3 profunda y permanentemente a su partido, provocando en particular la salida de Oskar Lafontaine, antiguo Secretario General del SPD y antiguo candidato a la Canciller\u00eda.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>La ca\u00edda del Muro parece haberse llevado consigo a la socialdemocracia al mismo tiempo que el comunismo.<\/p><cite>GUILLAUME DUVAL<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Aunque desde entonces se ha llevado a cabo una especie de balance en el seno del SPD, sigue habiendo mucha desconfianza en la opini\u00f3n p\u00fablica, sobre todo porque Olaf Scholz, actual Canciller del pa\u00eds, y Frank-Walter Steinmeier, Presidente de la Rep\u00fablica alemana, encarnan a\u00fan la continuidad con la era Schr\u00f6der. Tras casi excluirlo hace unos a\u00f1os, el SPD, que atraviesa grandes dificultades, rehabilit\u00f3 hace unos d\u00edas a Gerhard Schr\u00f6der, esperando beneficiarse del aura de hombre fuerte que conserva en ciertos sectores de la poblaci\u00f3n alemana.&nbsp;<\/p>\n\n\n\n<p>Una parte importante de esta continuidad con la era Schr\u00f6der se refiere tambi\u00e9n a las relaciones con Rusia. En los a\u00f1os 70, durante la Guerra Fr\u00eda, cuando el SPD lleg\u00f3 al poder de la mano del Canciller Willy Brandt, se distingui\u00f3 de los Dem\u00f3crata-Cristianos, muy alineados con los estadounidenses, por seguir una Ostpolitik din\u00e1mica de apertura hacia la Uni\u00f3n Sovi\u00e9tica y Alemania del Este. Sin embargo, desde entonces, el SPD sigue siendo el partido alem\u00e1n m\u00e1s favorable al acercamiento a Rusia, con el apoyo de un poderoso grupo de presi\u00f3n industrial. Aunque este lobby tambi\u00e9n era muy activo frente a los democristianos.<\/p>\n\n\n\n<p>El canciller Gerhard Schr\u00f6der, en particular, opt\u00f3 por abrazar plenamente esta continuidad lanzando en 1998 el gasoducto Nord-Stream 1, dise\u00f1ado para llevar el gas ruso a Alemania evitando Polonia y Ucrania a trav\u00e9s del mar B\u00e1ltico. Se hizo tan amigo de Vladimir Putin que, tras su mandato, se convirti\u00f3 en Presidente de la empresa que gestiona el gasoducto con Gazprom. Incluso hoy en d\u00eda, aunque el Gobierno de Olaf Scholz est\u00e1 plenamente comprometido a apoyar a Ucrania \u2014proporcionando al pa\u00eds m\u00e1s ayuda militar que Francia\u2014, es en el seno del SPD donde la reticencia hacia esta guerra sigue siendo m\u00e1s fuerte entre los partidos gobernantes alemanes \u2014aparte de Die Linke, BSW y la AfD\u2014. Esto se refleja en la negativa de Olaf Scholz a entregar misiles Taurus a Ucrania, contrariamente a lo que han hecho brit\u00e1nicos y franceses con sus sistemas de armas equivalentes.<\/p>\n\n\n\n<p>Por el contrario, aunque son considerablemente m\u00e1s d\u00e9biles que su dominio de la pol\u00edtica alemana hasta el final de la era Kohl, raramente disputado, los democristianos parecen haberse recuperado del accidente industrial de 2021 que puso fin a la era Merkel. Est\u00e1n consiguiendo mantenerse en este panorama cada vez m\u00e1s fragmentado y se les atribuye el 31% de los votos en las encuestas \u2014el doble que al SPD\u2014 tras pasar p\u00e1gina a Merkel <a href=\"https:\/\/legrandcontinent.eu\/es\/2024\/11\/30\/friedrich-merz-el-canciller-que-viene\/\">eligiendo a Friedrich Merz, uno de sus cr\u00edticos m\u00e1s ac\u00e9rrimos, como l\u00edder de la CDU<\/a>. Tras las pol\u00edticas econ\u00f3micas y sociales relativamente moderadas de Angela Merkel, que incluso repararon parte del da\u00f1o causado por Gerhard Schr\u00f6der al modelo social alem\u00e1n, Friedrich Merz ha vuelto a poner a la CDU en una senda ultraliberal y de austeridad, sobre todo a costa de los liberales. Con cierto \u00e9xito.<\/p>\n\n\n\n<p>Esta creciente fragmentaci\u00f3n del paisaje pol\u00edtico hace que el pa\u00eds sea cada vez m\u00e1s dif\u00edcil de gobernar. Hasta 2021, siempre hab\u00eda sido posible construir coaliciones bipartidistas para gobernar el pa\u00eds con una mayor\u00eda estable en el Bundestag \u2014formado por representaci\u00f3n proporcional plena con un umbral del 5%\u2014. Construir estas coaliciones siempre ha sido un ejercicio complicado que llevaba varios meses, pero que ten\u00eda \u00e9xito porque estos gobiernos sol\u00edan durar toda una legislatura. Desde 1958, a pesar de la representaci\u00f3n proporcional plena, Alemania s\u00f3lo ha tenido 28 gobiernos y 9 jefes de gobierno, mientras que Francia, con su sistema de mayor\u00edas a dos vueltas que supuestamente garantiza una mayor estabilidad, ha tenido 48 gobiernos y 27 jefes de gobierno.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Con Merz, los democristianos parecen haberse recuperado del accidente industrial de 2021 que puso fin a la era Merkel.<\/p><cite>GUILLAUME DUVAL<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Pero desde 2021 se necesitan tres partidos para formar una coalici\u00f3n mayoritaria. Y la durabilidad de la coalici\u00f3n tripartita formada por el SPD, los Verdes y los Liberales \u2014<a href=\"https:\/\/legrandcontinent.eu\/es\/2024\/11\/07\/la-situacion-es-grave-scholz-expone-la-crisis-politica-en-alemania\/\">que acaba de romperse<\/a>\u2014 se hab\u00eda visto constantemente amenazada por las rencillas internas del Gobierno, por lo que su acci\u00f3n ha quedado en gran medida paralizada. Estas tensiones se han visto exacerbadas en particular por el extremismo del peque\u00f1o partido liberal, que, amenazado de extinci\u00f3n, juega a la austeridad sin cuartel para intentar satisfacer a su base.<\/p>\n\n\n\n<p>Esta par\u00e1lisis tambi\u00e9n afecta principalmente a la forma en que las autoridades alemanas intervienen en el marco europeo.<\/p>\n\n\n\n<p>Pero las pr\u00f3ximas elecciones podr\u00edan poner fin a esta creciente fragmentaci\u00f3n del panorama pol\u00edtico alem\u00e1n, con la probable desaparici\u00f3n del Bundestag tanto del FDP como de Die Linke. De ser as\u00ed, volver\u00edamos a un sistema de cinco partidos, como en la d\u00e9cada de 1990. Parad\u00f3jicamente, este proceso de creciente fragmentaci\u00f3n del sistema pol\u00edtico alem\u00e1n, si bien podr\u00eda tener efectos estabilizadores, se debe al ascenso de dos fuerzas pol\u00edticas de derecha e izquierda, cuyas banderas son la xenofobia, el apoyo a Putin y la desconfianza en la integraci\u00f3n europea. As\u00ed que no hay nada prometedor \u2014ni alentador\u2014.<\/p>\n\n\n<section class=\"dive print-block my-16\" style=\"background-color:;\">\n\t<div class=\"wrapper\">\n\t\t<div class=\"container mx-auto \">\n\t\t\t<div class=\"row flex flex-wrap relative pt-6 pb-16 lg:py-8\">\n\t\t\t\t<div class=\"col w-full xl:ml-1\/10\n\t\t\t\t\t md:w-2\/5 xl:w-2\/5 \t\t\t\t\t\">\n\t\t\t\t\t<a href=\"https:\/\/legrandcontinent.eu\/es\/ofiertas-new\/\" style=\"color:#0a0a0a;\" class=\"font-display font-normal text-4xl leading-9 mb-5 text-white no-underline\">\n\t\t\t\t\t\tRetrato de un mundo roto\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<div style=\"color:#0a0a0a;\" class=\"text-base leading-none font-sans\">\n\t\t\t\t\t\t\t<p>Bajo la direcci\u00f3n de Giuliano da Empoli.<\/p>\n<p>Con contribuciones de Josep Borrell, Lea Ypi, Niall Ferguson, Timothy Garton Ash, Anu Bradford, Jean-Yves Dormagen, Aude Darnal, Branko Milanovi\u0107, Julia Cag\u00e9, Vladislav Surkov o Isabella Weber.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"mt-12 dive-list\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a  style=\"color:#dd203c;\" class=\"no-underline block border-t border-grey-darker py-2 flex\"\n\t\t\t\t\t\t\t\t   href=\"https:\/\/legrandcontinent.eu\/shop\/es\/producto\/el-grand-continent-vol-3-retrato-de-un-mundo-roto\/\"><span class=\"font-sans font-semibold pr-4\">\u2192<\/span> Pedir el volumen<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a  style=\"color:#dd203c;\" class=\"no-underline block border-t border-grey-darker py-2 flex\"\n\t\t\t\t\t\t\t\t   href=\"https:\/\/legrandcontinent.eu\/es\/ofiertas-new\/\"><span class=\"font-sans font-semibold pr-4\">\u2192<\/span> Descubra nuestras ofertas<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div style=\"color:#0a0a0a;\" class=\"dive-footer font-sans text-xs border-t border-grey-darker py-2 leading-4\">\n\t\t\t\t\t\t\t<p><em>Retrato de un mundo roto<\/em>, el nuevo volumen en papel del Grand Continent publicado por Arpa. Est\u00e1 disponible para <a href=\"https:\/\/legrandcontinent.eu\/shop\/es\/producto\/el-grand-continent-vol-3-retrato-de-un-mundo-roto\/\">su compra<\/a> e incluido en nuestra <a href=\"https:\/\/legrandcontinent.eu\/es\/ofiertas-new\/\">oferta de lanzamiento<\/a>.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"col w-full md:w-3\/5 xl:w-2\/5  md:px-0 relative overflow-hidden mt-8 md:mt-0 macron-img\">\n\t\t\t\t\t\t\t\t<a class=\"!absolute !bg-none w-full h-full pin-t pin-l\" href=\"https:\/\/legrandcontinent.eu\/es\/ofiertas-new\/\" class=\"no-underline\">\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" style=\"object-fit: contain; width: 100%; height: 100%;\" src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/09\/mediamodifier_image-128-990x660.png\" \/>\n\t\t\t\t\t\t\t\t<\/a> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n\n<h2 class=\"wp-block-heading\">La muerte de la Alemania abierta y liberal de la posguerra<\/h2>\n\n\n\n<p>Esta crisis del sistema pol\u00edtico alem\u00e1n refleja \u2014y va de la mano con\u2014 una crisis de identidad.<\/p>\n\n\n\n<p>La Alemania posterior a 1968, abierta al mundo, liberal, antirracista y que hab\u00eda aprendido las lecciones del periodo nazi, ha sido barrida en el espacio de una d\u00e9cada por la combinaci\u00f3n de las heridas mal cicatrizadas dejadas por una reunificaci\u00f3n inacabada y la desestabilizaci\u00f3n vinculada a una importante oleada de inmigraci\u00f3n.&nbsp;<\/p>\n\n\n\n<p>Aunque la inmigraci\u00f3n ha sido de hecho una bendici\u00f3n econ\u00f3mica y social para una Alemania envejecida y con una baja tasa de natalidad, ha sacudido a la sociedad alemana. Ochenta a\u00f1os despu\u00e9s del final de la Segunda Guerra Mundial, las \u00fanicas fuerzas pol\u00edticas que tienen el viento a favor en Alemania son, una vez m\u00e1s, las que enarbolan la bandera del nacionalismo y la xenofobia&#8230;&nbsp;&nbsp;<\/p>\n\n\n\n<p>Por eso hay que matizar las similitudes entre las situaciones francesa y alemana \u2014en realidad, las similitudes son s\u00f3lo superficiales\u2014. Las din\u00e1micas demogr\u00e1ficas de Francia y Alemania \u2014y m\u00e1s ampliamente su relaci\u00f3n con el resto del mundo\u2014 son profundamente diferentes. Las razones por las que la inmigraci\u00f3n se ha convertido en un tema central en los dos pa\u00edses no son las mismas.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Ochenta a\u00f1os despu\u00e9s del final de la Segunda Guerra Mundial, las \u00fanicas fuerzas pol\u00edticas que tienen el viento a favor en Alemania son, una vez m\u00e1s, las que enarbolan la bandera del nacionalismo y la xenofobia&#8230;\u00a0\u00a0<\/p><cite>GUILLAUME DUVAL<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Alemania ha sido durante mucho tiempo un pa\u00eds con una tasa de natalidad muy alta. Por esta raz\u00f3n, tambi\u00e9n ha sido un pa\u00eds de emigraci\u00f3n masiva desde el siglo XVIII. Numerosas comunidades alemanas se han asentado en toda Europa del Este y en lugares tan lejanos como Rusia. Y si tantos nazis emigraron a Am\u00e9rica Latina tras la Segunda Guerra Mundial, fue porque ya hab\u00eda grandes comunidades alemanas en Argentina, Chile y Brasil. En cuanto a Estados Unidos, cuando se les pregunta por su ascendencia, 43 millones de estadounidenses dicen ser de origen alem\u00e1n, incluido Donald Trump. Eso es m\u00e1s que, por ejemplo, los 31 millones que dicen ser de origen irland\u00e9s, los 25 millones de origen ingl\u00e9s o los 16 millones de origen italiano&#8230; No se puede entender la profundidad del apoyo al atlantismo en Alemania si se pierde de vista la cuesti\u00f3n de la emigraci\u00f3n: por decirlo r\u00e1pidamente, todo alem\u00e1n tiene un t\u00edo de Estados Unidos. Del mismo modo, no se puede entender la fuerza del comercio exterior alem\u00e1n sin medir el importante papel que desempe\u00f1a la emigraci\u00f3n alemana en su sostenimiento: la industria del otro lado del Rin depende en gran medida de un \u00abefecto di\u00e1spora\u00bb que un pa\u00eds como Francia no tiene.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/tUzdN\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>El hecho de que Alemania haya sido un pa\u00eds de emigraci\u00f3n durante tanto tiempo est\u00e1 estrechamente relacionado con el hecho de que el derecho alem\u00e1n de nacionalidad sigui\u00f3 siendo esencialmente un derecho de sangre durante mucho tiempo. No fue hasta principios de la d\u00e9cada de 2000, bajo el gobierno del Canciller Gerhard Schr\u00f6der, cuando esta ley \u2014por fin\u2014 evolucion\u00f3 para dar a los inmigrantes y a los extranjeros nacidos en suelo alem\u00e1n un acceso m\u00e1s f\u00e1cil a la nacionalidad.&nbsp;<\/p>\n\n\n\n<p>Alemania, que no se unific\u00f3 hasta 1871, hab\u00eda perdido el tren de la colonizaci\u00f3n europea en el siglo XIX, y s\u00f3lo consigui\u00f3 apoderarse de Camer\u00fan y Namibia muy temporalmente, para cometer all\u00ed un genocidio poco despu\u00e9s. Esta falta de colonias, y el deseo de compensarla, hab\u00eda sido uno de los principales motores de la Primera Guerra Mundial. Por ello, los alemanes emigraron en masa durante los dos \u00faltimos siglos, no a colonias alemanas, sino a pa\u00edses extranjeros no controlados por Alemania. Combinado con el desplazamiento forzoso de unos doce millones de alemanes de Europa del Este expulsados de sus hogares tras la Segunda Guerra Mundial, esto ayuda a explicar la actitud generalmente positiva adoptada por la opini\u00f3n p\u00fablica alemana y el Gobierno conservador de Angela Merkel en 2015 hacia la crisis de los refugiados sirios.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/PeWHv\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Las dos guerras mundiales tuvieron, por supuesto, un coste humano muy elevado para Alemania, pero no fue hasta hace relativamente poco \u2014a partir de los a\u00f1os 70\u2014 cuando la din\u00e1mica demogr\u00e1fica alemana se invirti\u00f3 de verdad, con una fuerte ca\u00edda de la natalidad inmediatamente despu\u00e9s de mayo de 1968. Esta brusca ca\u00edda se debi\u00f3 principalmente a la combinaci\u00f3n de dos fen\u00f3menos distintos.&nbsp;<\/p>\n\n\n\n<p>En primer lugar, un poderoso movimiento feminista \u2014mayor que en Francia\u2014 que sacudi\u00f3 una sociedad que hasta entonces hab\u00eda permanecido muy conservadora bajo la \u00e9gida de los democristianos, que hab\u00edan dominado durante toda la posguerra. El lugar de la mujer en la sociedad hab\u00eda seguido estando definido por el viejo tr\u00edptico <em>Kinder, K\u00fcche, Kirche<\/em> \u2014ni\u00f1os, cocina, iglesia\u2014 durante mucho m\u00e1s tiempo que en Francia.<\/p>\n\n\n\n<p>Este desaf\u00edo ha ido acompa\u00f1ado de la progresiva incorporaci\u00f3n de la mujer al mercado de trabajo remunerado. Pero este movimiento se produjo en un contexto en el que las infraestructuras colectivas \u2014guarder\u00edas, escuelas infantiles, etc.\u2014 para ayudar a conciliar la vida laboral y la maternidad segu\u00edan siendo muy insuficientes. Es m\u00e1s, los alemanes \u2014incluso los de izquierdas\u2014 siguen considerando a menudo que una mujer es una mala madre \u2014una <em>Rabenmutter<\/em>, \u00abmadre cuervo\u00bb\u2014 cuando los ni\u00f1os peque\u00f1os van a guarder\u00edas o escuelas infantiles.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>No fue hasta hace relativamente poco \u2014a partir de los a\u00f1os 70\u2014 cuando la din\u00e1mica demogr\u00e1fica alemana se invirti\u00f3 de verdad, con una fuerte ca\u00edda de la natalidad inmediatamente despu\u00e9s de mayo de 1968.<\/p><cite>GUILLAUME DUVAL<\/cite><\/blockquote><\/figure>\n\n\n\n<p>A ello se a\u00f1ade una toma de conciencia m\u00e1s temprana y generalizada que en Francia de la gravedad de la crisis ecol\u00f3gica y de sus posibles consecuencias, aunque al mismo tiempo Alemania sigue siendo un para\u00edso para los grandes autom\u00f3viles y un gran consumidor de carb\u00f3n. La combinaci\u00f3n de estos dos factores hizo que la fecundidad descendiera a 1,4 hijos por mujer en el pa\u00eds ya en 1975, hace cincuenta a\u00f1os, en lugar de los 2,1 que habr\u00edan podido estabilizar la poblaci\u00f3n. Es interesante constatar que esta tasa ha aumentado ligeramente desde 2010, fruto de una salud econ\u00f3mica relativamente buena combinada con un gran esfuerzo para dotar por fin al pa\u00eds de guarder\u00edas y servicios de cuidado de ni\u00f1os despu\u00e9s de la escuela, dirigido por Angela Merkel \u2014una mujer originaria de Alemania del Este que se socializ\u00f3 en un pa\u00eds donde, a diferencia de Alemania Occidental, todas las mujeres ten\u00edan trabajo\u2014.&nbsp;<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/M6hcY\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Por el contrario, mucho antes de la invenci\u00f3n de los anticonceptivos modernos, Francia hab\u00eda estado a la vanguardia de la transici\u00f3n demogr\u00e1fica, con una tasa de natalidad relativamente baja. Desde el siglo XVIII, su poblaci\u00f3n ha crecido mucho menos que la de sus vecinos. Adem\u00e1s, los franceses viven en un pa\u00eds todav\u00eda poco poblado, lo que es una de las razones por las que nunca han emigrado en masa. Tambi\u00e9n es una de las razones por las que los franceses perdieron sus colonias en Norteam\u00e9rica, donde los colonos franceses se vieron r\u00e1pidamente desbordados por las continuas oleadas de emigrantes que llegaban en masa desde la superpoblada Inglaterra. A diferencia de Alemania, Francia conquist\u00f3 un vasto imperio colonial, sobre todo en \u00c1frica, durante el siglo XIX. Pero en lugar de ser el motor de un vasto movimiento de emigraci\u00f3n, como hab\u00eda sido el caso de los anglosajones en Norteam\u00e9rica o de los ib\u00e9ricos en Sudam\u00e9rica, este imperio colonial convirti\u00f3 de hecho a Francia en un pa\u00eds de inmigraci\u00f3n antes que la mayor\u00eda de sus vecinos europeos. As\u00ed, hubo que esperar a los a\u00f1os 70 para que la din\u00e1mica demogr\u00e1fica entre Francia y Alemania se invirtiera brutalmente: Francia se convirti\u00f3 en uno de los pa\u00edses de Europa con la tasa de natalidad m\u00e1s elevada, mientras que en Alemania \u00e9sta disminu\u00eda r\u00e1pidamente.&nbsp;<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/sVp7E\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Por eso, aunque la cuesti\u00f3n de la inmigraci\u00f3n est\u00e1 en el centro de la crisis pol\u00edtica de ambos pa\u00edses, esta centralidad es en realidad el resultado de din\u00e1micas muy diferentes. Aparte de Grecia, Francia es el pa\u00eds de Europa Occidental donde los nuevos flujos de inmigraci\u00f3n han sido m\u00e1s bajos desde 2010, seg\u00fan datos de Eurostat, muy por debajo de la media europea.&nbsp;<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/PSTxE\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>La cuesti\u00f3n pol\u00edtica en Francia s\u00f3lo est\u00e1 superficialmente vinculada a las migraciones: de hecho, se refiere principalmente a la integraci\u00f3n de los descendientes de emigrantes, la mayor\u00eda de los cuales son ahora franceses. Este estado de cosas tiene poco que ver con los flujos migratorios de los \u00faltimos a\u00f1os, que han seguido siendo muy limitados.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/juIaw\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Alemania, en cambio, es uno de los pa\u00edses europeos con mayores flujos de inmigrantes en los \u00faltimos diez a\u00f1os, despu\u00e9s de Suecia y Austria. Actualmente, en Francia, el 13,1% de la poblaci\u00f3n ha nacido en el extranjero, proporci\u00f3n que se ha mantenido pr\u00e1cticamente estable en las \u00faltimas d\u00e9cadas. En Alemania, sin embargo, la proporci\u00f3n es del 19,5%, un 50% m\u00e1s. Aparte de para\u00edsos fiscales como Malta y Luxemburgo, es una de las m\u00e1s altas de Europa. Francia cuenta ahora con un 8,2% de extranjeros en su poblaci\u00f3n, apenas m\u00e1s que hace diez a\u00f1os, mientras que Alemania tiene un 14,6% \u2014casi el doble que en 2013\u2014.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/CMBGg\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Gracias a esta elevada inmigraci\u00f3n, que no solo procede de fuera de Europa, Alemania ha logrado frenar su declive demogr\u00e1fico: desde 2013, su poblaci\u00f3n ha crecido un 4,8%, casi el triple que la media de la Uni\u00f3n y bastante m\u00e1s que en Francia (3,9%). La poblaci\u00f3n alemana, que hab\u00eda empezado a caer, ha comenzado a crecer de nuevo desde 2015 y se sit\u00faa ahora 1,3 millones por encima de su m\u00e1ximo de 2007.<\/p>\n\n\n\n<p>En t\u00e9rminos estrictamente econ\u00f3micos, esta gran afluencia de inmigrantes es una bendici\u00f3n para el pa\u00eds \u2014tanto para su sistema de producci\u00f3n como para su sistema social\u2014. La mayor\u00eda de los reci\u00e9n llegados son j\u00f3venes ya formados y, a menudo, cualificados, lo que ha permitido limitar la escasez de mano de obra, que de otro modo habr\u00eda sido a\u00fan mayor debido a la baj\u00edsima tasa de natalidad, y <a href=\"https:\/\/legrandcontinent.eu\/es\/2022\/11\/23\/el-fracaso-del-consenso-aleman-sobre-las-pensiones\/\">financiar las pensiones de la creciente proporci\u00f3n de poblaci\u00f3n mayor de 65 a\u00f1os<\/a>.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/JJ868\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Alemania se ha beneficiado enormemente de la crisis de la eurozona. No s\u00f3lo han emigrado a Alemania personas de fuera de Europa: la proporci\u00f3n de personas nacidas en otros lugares de Europa casi se ha duplicado en Alemania entre 2011 y 2023 \u2014del 3,8% en 2011 al 7,4% en 2023\u2014. En Francia, s\u00f3lo representan el 2,9% de la poblaci\u00f3n. Cada vez que Alemania acogi\u00f3 a un joven italiano, griego o espa\u00f1ol de 20 a\u00f1os que dej\u00f3 su pa\u00eds tras la crisis de la eurozona por falta de perspectivas laborales, en realidad debe al menos 200.000 euros a su pa\u00eds de origen si estimamos \u2014de forma conservadora\u2014 el coste, privado y p\u00fablico, pagado para criar a este joven en 10.000 euros al a\u00f1o. 3,2 millones de europeos se trasladaron a Alemania entre 2013 y 2023. Esto significa que Alemania debe te\u00f3ricamente 640.000 millones de euros al resto de la Uni\u00f3n, una suma que no ha tenido que gastar en alimentarlos, cuidarlos, alojarlos y educarlos&#8230; Se lo debe en particular a los pa\u00edses del sur de Europa que atravesaron una crisis en la d\u00e9cada de 2010 y de los que procede la mayor\u00eda de estos migrantes intraeuropeos. La proporci\u00f3n de la poblaci\u00f3n alemana nacida fuera de Europa tambi\u00e9n ha aumentado significativamente, aunque de forma menos acusada: del 7,3% en 2013 al 12,1% en 2023.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>La poblaci\u00f3n alemana, que hab\u00eda comenzado a disminuir, ha empezado a crecer de nuevo desde 2015, y se sit\u00faa ahora 1,3 millones por encima de su m\u00e1ximo de 2007.\u00a0<\/p><cite>GUILLAUME DUVAL<\/cite><\/blockquote><\/figure>\n\n\n\n<p>La sociedad alemana, que durante dos siglos hab\u00eda sido una de las principales fuentes de emigraci\u00f3n en Europa, se ha convertido as\u00ed en el espacio de unas pocas d\u00e9cadas, y en particular desde la crisis financiera de 2008, en uno de los pa\u00edses europeos con mayor proporci\u00f3n de extranjeros en su poblaci\u00f3n. Esto ha desestabilizado profundamente el pa\u00eds, sobre todo en el este de Alemania, donde durante cuarenta y cinco a\u00f1os pr\u00e1cticamente no hab\u00eda extranjeros, aparte de los soldados del ej\u00e9rcito ruso de ocupaci\u00f3n, y algunos trabajadores vietnamitas. Esto es tanto m\u00e1s cierto cuanto que, por lo que respecta a los solicitantes de asilo, Alemania, a diferencia de Francia, impone un reparto estricto de las llegadas entre todos los municipios del pa\u00eds.<\/p>\n\n\n\n<p>En Alemania, donde eran hasta hace poco mucho m\u00e1s bajos que en Francia, los precios de la vivienda y los alquileres han subido mucho en los \u00faltimos a\u00f1os. Esta subida est\u00e1 vinculada, por una parte, a la pol\u00edtica monetaria muy acomodaticia del BCE frente a la crisis de la zona euro y, por otra, a la pandemia del Covid-19 que, en Alemania como en otras partes, provoc\u00f3 una inflaci\u00f3n importante de los precios de los activos, tanto de las acciones como de los bienes inmuebles. Sin embargo, como esta inflaci\u00f3n coincidi\u00f3 con la llegada de inmigrantes, resulta tentador achacar la subida principalmente al gran n\u00famero de inmigrantes que acaban de entrar en el pa\u00eds. Adem\u00e1s, Alemania no es un pa\u00eds laico. Se considera en gran medida un pa\u00eds cristiano, dirigido adem\u00e1s durante gran parte de la posguerra por personas que se definen a s\u00ed mismas como dem\u00f3cratas cristianos. En las escuelas p\u00fablicas se impart\u00edan clases de religi\u00f3n protestante y cat\u00f3lica y el Estado recaudaba impuestos en nombre de las iglesias cristianas. En este contexto, la llegada de un gran n\u00famero de musulmanes suscita a menudo rechazo. Sobre todo porque, a diferencia de protestantes y cat\u00f3licos, la fe musulmana carece de estructura jer\u00e1rquica y es, por tanto, dif\u00edcil de integrar en el marco existente.<\/p>\n\n\n\n<p>A ello se han sumado una serie de cr\u00edmenes o atentados en los que se han visto implicados extranjeros musulmanes residentes en Alemania. La noche del 31 de diciembre de 2015, migrantes cometieron numerosas agresiones sexuales en Colonia. En julio de 2016, un islamista se inmol\u00f3 en un restaurante de Anspach, en Baviera, y en diciembre de 2016, un atentado con un cami\u00f3n apisonadora mat\u00f3 a 12 personas en el mercado navide\u00f1o de Berl\u00edn. En 2020, un iraqu\u00ed sembr\u00f3 el terror en una autopista y un ataque con cuchillo mat\u00f3 a dos personas en Solingen el pasado agosto. Todos estos sucesos fueron ampliamente cubiertos por los medios de comunicaci\u00f3n y explotados, en particular por <em>Bild<\/em>, el principal diario popular de derechas de Alemania. Al mismo tiempo, numerosos albergues de refugiados han sido atacados en los \u00faltimos a\u00f1os, sobre todo en el este de Alemania.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>La sociedad alemana, que durante dos siglos fue una de las principales fuentes de emigraci\u00f3n de Europa, se ha convertido en pocas d\u00e9cadas, y sobre todo desde la crisis financiera de 2008, en uno de los pa\u00edses de Europa donde los extranjeros representan la mayor proporci\u00f3n de la poblaci\u00f3n.<\/p><cite>GUILLAUME DUVAL<\/cite><\/blockquote><\/figure>\n\n\n\n<p>En 2015, una Alemania humanista, desprovista en gran medida de los prejuicios dejados en Francia por el colonialismo y decidida a luchar contra todas las formas de racismo que hab\u00edan estado en el coraz\u00f3n del nazismo, acogi\u00f3 a un mill\u00f3n de refugiados sirios casi sin pesta\u00f1ear, mientras que Francia s\u00f3lo acogi\u00f3 a 30.000. Su primera ministra conservadora se hab\u00eda arremangado para declarar con orgullo \u00ab<em>wir schaffen das<\/em>\u00bb \u2014\u00abvamos a lograrlo\u00bb\u2014, acompa\u00f1ada de una extraordinaria movilizaci\u00f3n de la sociedad civil, que respondi\u00f3 masivamente a su llamamiento para hacer frente a la afluencia.<\/p>\n\n\n\n<p>Sin embargo, diez a\u00f1os despu\u00e9s, Alemania se ha convertido en una de esas sociedades europeas fr\u00edas y encerradas en s\u00ed mismas, mientras el Gobierno alem\u00e1n de izquierdas promueve una pol\u00edtica migratoria europea m\u00e1s dura \u2014ya planificada y organizada por la Comisaria europea alemana, la Presidenta de la Comisi\u00f3n Ursula von der Leyen, en estrecha consulta con la extrema derecha europea\u2014.&nbsp;<\/p>\n\n\n\n<p>Sin embargo, si miramos fr\u00edamente las cosas, la afluencia de inmigrantes que ha experimentado Alemania en los \u00faltimos diez a\u00f1os ha sido una gran oportunidad tanto para su sistema productivo como para su sistema social. Pero las pasiones pol\u00edticas y las realidades econ\u00f3micas obedecen a menudo a l\u00f3gicas diferentes\u2026<\/p>\n\n\n\n<p>Hay, sin embargo, un tema en el que el consenso alem\u00e1n posterior a 1968 se ha mantenido firme: el sentimiento compartido de culpa colectiva hacia el pueblo jud\u00edo \u2014lo que resulta tranquilizador\u2014. Sin embargo, en el contexto del conflicto en Oriente Pr\u00f3ximo y de la guerra que estall\u00f3 tras la masacre del 7 de octubre de 2023, este comprensible sentimiento ha tenido la consecuencia negativa de convertir a la opini\u00f3n y al gobierno alemanes de izquierdas \u2014sobre todo a trav\u00e9s de la voz de Annalena Baerbock, la ministra de Asuntos Exteriores de los Verdes\u2014 en uno de los m\u00e1s firmes defensores en Europa, junto a Viktor Orban, de la guerra emprendida por el gobierno de Benjamin Netanyahu contra los palestinos y de los m\u00faltiples cr\u00edmenes de guerra que ha provocado. Con ello, est\u00e1 contribuyendo activamente a distanciar a Europa de la mayor\u00eda de los pa\u00edses del Sur, <a href=\"https:\/\/legrandcontinent.eu\/es\/2023\/10\/12\/los-paises-arabes-y-musulmanes-en-la-guerra-de-sucot-cartografiar-una-ruptura\/\">no s\u00f3lo de los pa\u00edses musulmanes<\/a>. A largo plazo, esta posici\u00f3n representa una amenaza existencial para el futuro de la Uni\u00f3n.&nbsp;&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Un modelo econ\u00f3mico gravemente amenazado<\/h2>\n\n\n\n<p>Estas crisis pol\u00edtica e identitaria se entrelazan con una profunda crisis del modelo econ\u00f3mico alem\u00e1n, de la que los signos actuales son con toda probabilidad s\u00f3lo los proleg\u00f3menos.&nbsp;<\/p>\n\n\n\n<p>Todos los motores que hab\u00edan hecho de Alemania la potencia econ\u00f3mica dominante de la Uni\u00f3n Europea se han detenido. La relativa buena salud econ\u00f3mica de Alemania tras la crisis financiera de 2008 y luego durante la crisis de la eurozona llev\u00f3 a nuestros vecinos a erigirse en maestros de escuela dentro de la Uni\u00f3n Europea. Pero esos d\u00edas han pasado, y ahora Alemania parece abocada a convertirse en <a href=\"https:\/\/legrandcontinent.eu\/es\/2024\/02\/09\/la-alemania-de-scholz-el-corazon-enfermo-de-europa\/\">el \u00abenfermo\u00bb de Europa<\/a>.&nbsp;<\/p>\n\n\n\n<p>El modelo econ\u00f3mico alem\u00e1n se basa en la fortaleza industrial del pa\u00eds y en su capacidad para exportar. De hecho, Alemania s\u00f3lo se ve a s\u00ed misma como un \u00ab<em>Exportweltmeister<\/em>\u00bb, campeona del mundo de la exportaci\u00f3n. Y lo ha conseguido de forma impresionante: en 2023, las exportaciones de China y sus 1.400 millones de habitantes representaban 3,380 billones de d\u00f3lares seg\u00fan la Organizaci\u00f3n Mundial del Comercio, y las de Estados Unidos y sus 335 millones de habitantes 2,020 billones. Alemania, con 84 millones de habitantes, se situ\u00f3 justo detr\u00e1s con 1,690 billones de d\u00f3lares. Estas exportaciones duplican con creces las de Jap\u00f3n o Corea, y casi triplican las de Francia, Italia o el Reino Unido.&nbsp;<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/cgxyb\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Sin embargo, despu\u00e9s de 1991, la reunificaci\u00f3n alemana fren\u00f3 esta din\u00e1mica, obligando a Alemania a dar prioridad a la inversi\u00f3n interna para reconstruir el Este del pa\u00eds. Como consecuencia, Alemania registr\u00f3 un d\u00e9ficit exterior durante toda la d\u00e9cada de 1990, importando m\u00e1s de lo que exportaba. En aquel momento, los alemanes lo consideraron una tragedia nacional y un signo de una profunda crisis de la competitividad alemana. Hab\u00eda que recuperar la condici\u00f3n de \u00ab<em>Exportweltmeister<\/em>\u00bb a toda costa. De ah\u00ed los grandes esfuerzos del Canciller Gerhard Schr\u00f6der a principios de los a\u00f1os 90 para reducir los costes laborales y reactivar las famosas exportaciones.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Todos los motores que hab\u00edan hecho de Alemania la potencia econ\u00f3mica dominante de la Uni\u00f3n Europea se han detenido.<\/p><cite>GUILLAUME DUVAL<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Las reformas de Schr\u00f6der, y en particular la llamada reforma Hartz IV, que endureci\u00f3 las condiciones para obtener una ayuda social equivalente al Ingreso m\u00ednimo de inserci\u00f3n (RMI) franc\u00e9s, y la reforma destinada a desarrollar los \u00ab<em>minijobs<\/em>\u00bb, empleos precarios sin protecci\u00f3n social, provocaron un fuerte aumento de la pobreza en general y de la pobreza en el trabajo en particular. Esto condujo a un aumento significativo de las desigualdades.&nbsp;<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/Q1eRu\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Lo parad\u00f3jico es que, tras la purga impuesta por el socialdem\u00f3crata Gerhard Schr\u00f6der, la democristiana Angela Merkel recibi\u00f3 el encargo de reparar gran parte del da\u00f1o social causado por su predecesor, ajustando la dur\u00edsima reforma de las pensiones decidida en 2004 e introduciendo un salario m\u00ednimo en 2015 en un pa\u00eds que carec\u00eda de \u00e9l hasta entonces. Como resultado, combinado con una econom\u00eda alemana relativamente saneada, la pobreza baj\u00f3 en Alemania en los \u00faltimos a\u00f1os. Su tasa es ahora inferior a la tasa de pobreza francesa, que ha aumentado considerablemente bajo la presidencia de Emmanuel Macron. As\u00ed que no es, estrictamente hablando, el deterioro de las condiciones sociales y el aumento de las desigualdades lo que est\u00e1 en el coraz\u00f3n de la crisis del sistema pol\u00edtico alem\u00e1n que hemos descrito anteriormente.&nbsp;<\/p>\n\n\n\n<p>La agresiva pol\u00edtica de dumping social de Gerhard Schr\u00f6der en relaci\u00f3n con los vecinos europeos de Alemania hab\u00eda permitido un r\u00e1pido retorno a unos super\u00e1vits exteriores colosales. Esto reforz\u00f3 la creencia de los dirigentes alemanes de que \u00e9sa era la receta milagrosa que hab\u00eda que imponer a todos los dem\u00e1s europeos para sacar al Viejo Continente del marasmo. Esto es lo que hicieron durante la crisis de la eurozona, en particular con respecto a Grecia. Una pol\u00edtica que, como era de esperar, ha sido muy perjudicial para la econom\u00eda europea.&nbsp;<\/p>\n\n\n\n<p>Si la pol\u00edtica de Gerhard Schr\u00f6der no tuvo efectos a\u00fan m\u00e1s negativos para Alemania y Europa a principios de la d\u00e9cada de 2000, fue porque los vecinos de Alemania aplicaban entonces una pol\u00edtica diferente, que les permit\u00eda comprar las exportaciones alemanas. Si todos en Europa aplican simult\u00e1neamente pol\u00edticas de restricci\u00f3n de la demanda interna similares a la aplicada por Gerhard Schr\u00f6der s\u00f3lo en Alemania a principios de la d\u00e9cada de 2000, el resultado final es, sin sorpresas, lo que hemos presenciado desde 2008: el estancamiento prolongado de la econom\u00eda europea y <a href=\"https:\/\/legrandcontinent.eu\/es\/category\/economia\/informe-draghi-un-debate-europeo\/\">su rezago con respecto a la econom\u00eda estadounidense<\/a>. Este estancamiento ha ido acompa\u00f1ado de un aumento de las entradas de capital chino, ya que los gobiernos del sur de Europa se han visto obligados a vender sus \u00abjoyas familiares\u00bb para pagar sus deudas.&nbsp;<\/p>\n\n\n\n<p>La compresi\u00f3n de la demanda interna debida a las reformas Schr\u00f6der ha contribuido innegablemente a mejorar la balanza exterior de Alemania \u2014al tiempo que ha debilitado la econom\u00eda europea\u2014. Pero son de hecho otros factores los principales responsables de la recuperaci\u00f3n de las exportaciones alemanas. Desde principios de la d\u00e9cada de 2000, la demanda china de grandes berlinas se ha disparado, impulsada por la aparici\u00f3n de una nueva clase acomodada en China, mientras que la demanda de maquinaria, vinculada a la r\u00e1pida industrializaci\u00f3n del pa\u00eds, tambi\u00e9n se ha disparado. En ambos casos, se trataba de productos en los que la oferta alemana ten\u00eda en aquel momento una innegable ventaja competitiva.&nbsp;<\/p>\n\n\n\n<p>Adem\u00e1s, durante los a\u00f1os 90, la industria alemana tambi\u00e9n hab\u00eda aprovechado los restos de Europa del Este, <a href=\"https:\/\/legrandcontinent.eu\/es\/category\/politica\/ampliacion\/\">sacando el m\u00e1ximo partido de la ampliaci\u00f3n de la Uni\u00f3n<\/a>. Esto le proporcion\u00f3 salidas adicionales para sus propias exportaciones, al tiempo que le permiti\u00f3 reducir significativamente sus costes de producci\u00f3n mediante el desarrollo de la subcontrataci\u00f3n en Europa del Este. En particular, esto le permiti\u00f3 evitar los efectos nocivos de la subida masiva del euro frente al d\u00f3lar, de 0,9 d\u00f3lares en 2000 a 1,6 d\u00f3lares en 2008 \u2014casi el doble\u2014, que hab\u00eda perjudicado gravemente a las industrias francesa e italiana durante la d\u00e9cada de 2000.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>La compresi\u00f3n de la demanda interna debida a las reformas Schr\u00f6der ha contribuido innegablemente a mejorar la balanza exterior de Alemania \u2014al tiempo que ha debilitado la econom\u00eda europea\u2014.<\/p><cite>GUILLAUME DUVAL<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Alemania exporta mucho m\u00e1s que Francia, 2,1 veces m\u00e1s en 2023, pero tambi\u00e9n importa mucho m\u00e1s, 1,8 veces m\u00e1s en el mismo a\u00f1o. Antes de la ca\u00edda del Muro de Berl\u00edn, Francia era el primer pa\u00eds de bajo coste en el que Alemania subcontrataba; tras la ca\u00edda del Muro, y especialmente en la d\u00e9cada de 2000, el testigo pas\u00f3 a Polonia, la Rep\u00fablica Checa\u2026 En el proceso, los costes laborales se dividieron por 4 y los costes totales de producci\u00f3n cayeron en picado, independientemente de lo que ocurriera en la propia Alemania. Como resultado, las exportaciones alemanas se dispararon, casi duplic\u00e1ndose como proporci\u00f3n del PIB alem\u00e1n entre los a\u00f1os 90 y finales de los 2000. Y a finales de la d\u00e9cada de 2000, Alemania volv\u00eda a registrar super\u00e1vits exteriores superiores a 6 puntos porcentuales del PIB.&nbsp;<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/jxkuI\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>La propia crisis financiera de 2008, y la posterior crisis de la eurozona, s\u00f3lo frenaron muy temporalmente esta din\u00e1mica.&nbsp;<\/p>\n\n\n\n<p>Como consecuencia de la f\u00e9rrea austeridad que Wolfgang Sch\u00e4uble, ministro de Finanzas alem\u00e1n, impuso entonces a los pa\u00edses del sur de Europa afectados por la crisis, Alemania vio disminuir sus exportaciones al resto de la Uni\u00f3n Europea, pero consigui\u00f3 compensar estas p\u00e9rdidas aumentando sus exportaciones fuera de la Uni\u00f3n, principalmente a China.&nbsp;<\/p>\n\n\n\n<p>Esta buena salud industrial y exportadora mantenida durante la tormenta europea de 2008-2013 reforz\u00f3 en gran medida la arrogancia de los dirigentes alemanes y su intransigencia en sus fundamentos ordo-liberales y austeritarios, impidiendo a la Uni\u00f3n Europea aplicar las reformas necesarias tras la crisis de la eurozona.&nbsp;<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/wUVir\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Pero desde la pandemia del COVID-19 y la guerra en Ucrania, las cosas han ido de mal en peor. La industria alemana ha aparecido de repente como un coloso con pies de barro. La producci\u00f3n industrial est\u00e1 cayendo muy r\u00e1pidamente, al igual que las exportaciones fuera de la Uni\u00f3n Europea, y todo hace pensar que esto es s\u00f3lo el principio de un proceso que probablemente se acelerar\u00e1 a\u00fan m\u00e1s.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/YN6WI\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>La industria alemana es evidentemente mucho m\u00e1s fuerte que la francesa, ya que representa el doble del PIB de nuestro vecino que del nuestro, pero sigue produciendo m\u00e1s o menos lo mismo que hace cien a\u00f1os: autom\u00f3viles, productos qu\u00edmicos y m\u00e1quinas-herramienta. En ausencia de cualquier tipo de pol\u00edtica industrial europea, a la que los dirigentes alemanes siempre se han opuesto con firmeza, Alemania, como Francia y el resto de Europa, ha perdido el tren de la microelectr\u00f3nica, los tel\u00e9fonos m\u00f3viles, las redes sociales y los gigantes de Internet&#8230; Si China, Corea, Jap\u00f3n y Estados Unidos se han llevado la parte del le\u00f3n en estos campos, en detrimento sobre todo de Europa, ello est\u00e1 estrechamente ligado a pol\u00edticas industriales p\u00fablicas muy activas, en particular a trav\u00e9s de la pol\u00edtica de defensa en el caso de Estados Unidos.&nbsp;<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/E98SB\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Y hoy, <a href=\"https:\/\/legrandcontinent.eu\/es\/2023\/08\/30\/byd-y-catl-dentro-de-las-cabezas-de-los-prometeos-chinos-de-la-electricidad\/\">la revoluci\u00f3n tecnol\u00f3gica en curso en la industria del autom\u00f3vil amenaza el futuro de un sector que es la columna vertebral de la industria alemana<\/a>. El fin previsto de los motores de combusti\u00f3n interna pone en entredicho una de las principales ventajas competitivas de la industria de nuestros vecinos, basada en siglos de excelencia en este campo. Al mismo tiempo, una parte esencial del valor a\u00f1adido de los autom\u00f3viles se est\u00e1 transfiriendo a los fabricantes de bater\u00edas, un sector en el que Alemania est\u00e1 tan mal situada como el resto de Europa, y a los gigantes del software y los datos, sectores en los que nuestros vecinos est\u00e1n tan atrasados como el resto de Europa.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>La industria alemana es evidentemente mucho m\u00e1s fuerte que la francesa. Pero sigue produciendo m\u00e1s o menos lo mismo que hace cien a\u00f1os: autom\u00f3viles, productos qu\u00edmicos y m\u00e1quinas-herramienta.<\/p><cite>GUILLAUME DUVAL<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Alemania se caracteriza sobre todo por la cogesti\u00f3n, un sistema de relaciones laborales que confiere a los trabajadores y a sus representantes poderes muy amplios dentro de las empresas, a un nivel sin parang\u00f3n en el mundo capitalista: no se consulta a los comit\u00e9s de empresa para que asesoren, como en Francia, sino que tienen poder de veto sobre la mayor\u00eda de las grandes decisiones de gesti\u00f3n a nivel de establecimiento y de empresa. Y en las grandes empresas, los representantes de los trabajadores ocupan la mitad de los puestos en los Consejos de Supervisi\u00f3n, junto con los representantes de los accionistas.&nbsp;<\/p>\n\n\n\n<p>Esta forma tan especial de gobernanza ha desempe\u00f1ado un papel fundamental en la resistencia de la industria alemana. A diferencia de Francia, ha frenado el deseo de la direcci\u00f3n de externalizar y deslocalizar, y ha permitido alcanzar compromisos pragm\u00e1ticos, as\u00ed como un fuerte compromiso de los empleados alemanes con sus empresas porque se sienten escuchados y respetados. Pero si bien esta cogesti\u00f3n ha sido una baza para la industria alemana en periodos de innovaci\u00f3n incremental, ya no lo es realmente ante innovaciones disruptivas que exigen cambios masivos y r\u00e1pidos. En tal contexto, dicha gobernanza se convierte m\u00e1s bien en un freno debido a la inercia que necesariamente implica.&nbsp;<\/p>\n\n\n\n<p>Para colmo, la industria alemana lleva 25 a\u00f1os apostando fuerte por China. Tanto para los autom\u00f3viles como para la maquinaria, sus dos principales bazas. Era este mercado, en particular, el que le hab\u00eda permitido compensar los efectos negativos sobre sus exportaciones del prolongado estancamiento de la econom\u00eda europea derivado de las pol\u00edticas de austeridad impuestas por el Gobierno alem\u00e1n tras la crisis de 2008. Pero una vez adquiridos los conocimientos t\u00e9cnicos, gracias sobre todo a los fabricantes alemanes, los fabricantes chinos empezaron a competir con ellos en la propia China, pero tambi\u00e9n en el resto del mundo, tanto en autom\u00f3viles como en maquinaria. Al mismo tiempo, el espectacular ascenso de los actores chinos en el campo de los veh\u00edculos el\u00e9ctricos, <a href=\"https:\/\/legrandcontinent.eu\/es\/2023\/08\/30\/byd-y-catl-dentro-de-las-cabezas-de-los-prometeos-chinos-de-la-electricidad\/\">fuertemente apoyados por el Estado<\/a>, ha provocado un hundimiento de la cuota de mercado de los fabricantes alemanes en la propia China, que lleg\u00f3 a ser con diferencia el mayor mercado automovil\u00edstico mundial antes de que estos coches empezaran a inundar el mundo.&nbsp;<\/p>\n\n\n\n<p>Por \u00faltimo, pero no por ello menos importante, el otro gran mercado de exportaci\u00f3n de Alemania, sobre todo en el sector del autom\u00f3vil, es Estados Unidos. Con el regreso de Donald Trump a la Casa Blanca, los excedentes europeos, principalmente alemanes, en el comercio entre la Uni\u00f3n y Estados Unidos estar\u00e1n en el centro de dif\u00edciles negociaciones. Al mismo tiempo, es probable que aumente la presi\u00f3n para que Europa se alinee con la dura postura de Estados Unidos respecto a China. Por lo tanto, es probable que la industria alemana sea una de las principales v\u00edctimas de la guerra comercial entre China y Estados Unidos, obligada a adoptar una postura m\u00e1s dura con China con la esperanza de calmar el ardor de Trump, a riesgo de perder definitivamente su posici\u00f3n en este gigantesco mercado, al tiempo que se ve obligada a deslocalizar su producci\u00f3n a Estados Unidos bajo la presi\u00f3n de las medidas proteccionistas estadounidenses.&nbsp;<\/p>\n\n\n\n<p>A ello se a\u00f1aden las dificultades causadas en los sectores intensivos en energ\u00eda, principalmente la siderurgia y la industria qu\u00edmica, por la guerra de agresi\u00f3n de Rusia contra Ucrania y el corte del suministro de combustibles f\u00f3siles, en particular gas, procedentes de Rusia. Este corte provoc\u00f3 una fuerte subida de los precios de la energ\u00eda en toda Europa, y especialmente en Alemania. La fuerte dependencia alemana de los combustibles f\u00f3siles rusos es el resultado de la <em>Ostpolitik<\/em> iniciada por el canciller del SPD Willy Brandt en la d\u00e9cada de 1970 y relanzada por el canciller del SPD Gerhard Schr\u00f6der a principios de la d\u00e9cada de 2000 con la construcci\u00f3n del gasoducto Nord Stream. En ambos casos, sin embargo, esta pol\u00edtica fue continuada ininterrumpidamente por sus sucesores dem\u00f3cratas-cristianos Helmut Kohl y Angela Merkel.&nbsp;&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>La fuerte competitividad de la industria alemana nunca se ha basado principalmente en los bajos costes.\u00a0<\/p><cite>GUILLAUME DUVAL<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Esta dimensi\u00f3n energ\u00e9tica de la crisis industrial alemana es a menudo destacada por el lobby nuclear franc\u00e9s, muy cr\u00edtico con la pol\u00edtica energ\u00e9tica alemana desde que el pa\u00eds opt\u00f3 por abandonar la energ\u00eda nuclear en 2002 y luego por acelerar este abandono en 2011 tras la cat\u00e1strofe de Fukushima, con el cierre de los \u00faltimos reactores a\u00fan en servicio en Alemania en 2023. Sin embargo, esta dificultad adicional y muy real a la que se enfrenta la industria alemana parece tener una importancia secundaria en comparaci\u00f3n con los problemas estructurales mucho m\u00e1s graves mencionados anteriormente.&nbsp;<\/p>\n\n\n\n<p>Si en Francia el bajo coste de la electricidad procedente de reactores nucleares viejos y amortizados fuera una ventaja competitiva tan decisiva como pretende ahora el lobby pro-nuclear, la industria francesa no deber\u00eda estar en tan mal estado en comparaci\u00f3n con la de nuestros vecinos del otro lado del Rin, incluso en los sectores m\u00e1s intensivos en energ\u00eda. Y no olvidemos que, de cara al futuro, la nueva energ\u00eda nuclear post-Chernobil y Fukushima es m\u00e1s cara que la solar o la e\u00f3lica, incluso teniendo en cuenta la necesidad de almacenamiento para las fuentes intermitentes. En realidad, la fuerte competitividad de la industria alemana nunca se ha basado principalmente en los bajos costes. Alemania produce casi tres veces m\u00e1s coches que Francia, a pesar de que, seg\u00fan datos de Eurostat, los costes laborales en este sector son un 54% m\u00e1s altos que en Francia.&nbsp;&nbsp;<\/p>\n\n\n\n<p>En cualquier caso, el declive de la industria alemana desde la pandemia del COVID-19 ha sido impresionante, y hay pocas razones para creer que este descenso a los infiernos no vaya a continuar, o incluso acelerarse. En las \u00faltimas d\u00e9cadas ha habido ocasiones en las que se ha pensado que la industria alemana estaba condenada al fracaso, sobre todo con las dificultades surgidas tras la reunificaci\u00f3n, pero en todas ellas se ha recuperado, demostrando una resistencia impresionante. Esta vez, sin embargo, es dif\u00edcil ver de d\u00f3nde puede venir el rebote.&nbsp;<\/p>\n\n\n\n<p>Finalmente, el \u00faltimo factor que agrava la crisis econ\u00f3mica alemana es puramente interno, <em>home-made<\/em>, como dicen los anglosajones. Alemania ha hecho de la austeridad fiscal permanente un elemento central de su identidad nacional. Esta pol\u00edtica goza de un ampl\u00edsimo consenso entre la poblaci\u00f3n alemana. Ya se trate de la AfD, los dem\u00f3cratas-cristianos, los liberales, los verdes o los socialdem\u00f3cratas, todos comparten esta religi\u00f3n, cuyo sumo sacerdote m\u00e1s conocido en la escena europea de las \u00faltimas d\u00e9cadas ha sido Wolfgang Scha\u00fcble, antiguo ministro alem\u00e1n de Finanzas en los gobiernos de Angela Merkel.&nbsp;<\/p>\n\n\n\n<p>El punto \u00e1lgido de este enfoque casi religioso de las finanzas p\u00fablicas se alcanz\u00f3 en 2009 con la introducci\u00f3n en la Constituci\u00f3n alemana del llamado <em>Schuldenbremse<\/em>, o freno a la deuda. Este freno proh\u00edbe a los Estados federales incurrir en d\u00e9ficit, aunque sea c\u00edclico, y limita el d\u00e9ficit estructural del Gobierno federal (excluyendo los efectos del ciclo econ\u00f3mico) a un m\u00e1ximo del 0,35%. Esta disposici\u00f3n fue adoptada por el Parlamento alem\u00e1n por una mayor\u00eda superior al 60%, con los votos del SPD y la CDU.&nbsp;<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/OqYys\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Esta pol\u00edtica de austeridad permanente, impuesta en toda Europa por el Gobierno alem\u00e1n a ra\u00edz de la crisis financiera de 2008, ha tenido un impacto muy negativo en el conjunto de la econom\u00eda europea. Tiene una gran responsabilidad en su prolongado estancamiento durante los \u00faltimos quince a\u00f1os. Pero a largo plazo, este enfoque tambi\u00e9n ha tenido efectos negativos masivos para la propia econom\u00eda alemana. Ciertamente, ha permitido reducir la ratio de deuda p\u00fablica del pa\u00eds del 80% del PIB en 2009 al 63% en 2023, a pesar de la pandemia del COVID-19. Pero al mismo tiempo ha impedido al pa\u00eds invertir y modernizar sus infraestructuras. Alemania es el \u00fanico pa\u00eds de la OCDE, el mundo desarrollado en su conjunto, donde la inversi\u00f3n p\u00fablica neta acumulada (una vez tenido en cuenta el desgaste de los equipos existentes) ha sido pr\u00e1cticamente nula en los \u00faltimos 25 a\u00f1os. En particular, esta pol\u00edtica ha impedido a las autoridades p\u00fablicas aprovechar las condiciones extremadamente favorables que pudieron obtener en los mercados financieros cuando los tipos de inter\u00e9s de la deuda alemana eran casi nulos, o incluso negativos en determinados periodos. El resultado es una red ferroviaria totalmente deteriorada que provoca perturbaciones permanentes en el tr\u00e1fico ferroviario, una situaci\u00f3n que se ha convertido en legendaria en toda Europa; unas infraestructuras viarias en desorden, con numerosos puentes que amenazan con derrumbarse; una cobertura de telefon\u00eda m\u00f3vil y banda ancha que figura entre las m\u00e1s deficientes de Europa; y grandes dificultades para la transici\u00f3n energ\u00e9tica\u2026<\/p>\n\n\n\n<p>La naturaleza contraproducente e impracticable del <em>Schuldenbremse<\/em> est\u00e1 ahora ampliamente aceptada en Alemania, pero como disposici\u00f3n constitucional, su derogaci\u00f3n es muy dif\u00edcil en el contexto de la creciente fragmentaci\u00f3n del panorama pol\u00edtico descrito anteriormente: requerir\u00eda un voto de m\u00e1s del 60% en el Bundestag. Para sortear este obst\u00e1culo, el gobierno alem\u00e1n ha tomado la costumbre de crear fondos extrapresupuestarios cuya deuda no se incluye en el 0,35% del PIB. Esto es lo que se hizo para hacer frente a la pandemia del COVID-19, y lo que Olaf Scholz hizo despu\u00e9s cuando, tras la invasi\u00f3n rusa de Ucrania, anunci\u00f3 un <em>Zeitenwende<\/em>, un cambio de \u00e9poca, acompa\u00f1ado de una inversi\u00f3n de 100.000 millones de euros en el rearme de Alemania. Esto tambi\u00e9n se hizo para ayudar a financiar la transici\u00f3n energ\u00e9tica. Pero es precisamente esta pr\u00e1ctica la que est\u00e1 en el centro de la actual crisis pol\u00edtica.&nbsp;<\/p>\n\n\n\n<p>En noviembre de 2023, el Tribunal Constitucional de Karlsruhe desencaden\u00f3 un terremoto pol\u00edtico cuyas r\u00e9plicas a\u00fan se sienten hoy. Anul\u00f3 una decisi\u00f3n del Gobierno alem\u00e1n de transferir 60.000 millones de euros de un fondo extrapresupuestario creado para hacer frente a la pandemia del COVID-19 a otro destinado a financiar la lucha contra el cambio clim\u00e1tico. El Tribunal dictamin\u00f3 que esta pr\u00e1ctica poco ortodoxa infring\u00eda las normas presupuestarias alemanas.&nbsp;<\/p>\n\n\n\n<p>Fueron las medidas de austeridad adicionales necesarias para cumplir esta sentencia las que provocaron la ruptura de la coalici\u00f3n tripartita del SPD, los Liberales y los Verdes.&nbsp;<\/p>\n\n\n\n<p>Parad\u00f3jicamente, Friedrich Merz, l\u00edder de los democristianos, el partido que introdujo esta disposici\u00f3n en la Constituci\u00f3n alemana y que previsiblemente ganar\u00e1 las pr\u00f3ximas elecciones, <a href=\"https:\/\/legrandcontinent.eu\/es\/2024\/11\/30\/friedrich-merz-el-canciller-que-viene\/\">ha enviado se\u00f1ales de que est\u00e1 dispuesto a cuestionar el <em>Schuldenbremse<\/em><\/a>. Tal desaf\u00edo ser\u00eda m\u00e1s f\u00e1cil para la derecha que para la izquierda, siempre sospechosa <em>a priori <\/em>de laxismo presupuestario. Sin embargo, esto sigue siendo una perspectiva lejana y muy incierta \u2014por desgracia para Alemania y para Europa\u2014. En cierto modo, la propia identidad de la Alemania de posguerra tambi\u00e9n est\u00e1 en crisis en lo que respecta a la gesti\u00f3n de las finanzas p\u00fablicas.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfCu\u00e1les son las consecuencias para la Uni\u00f3n Europea?\u00a0<\/h2>\n\n\n\n<p>Dado el peso demogr\u00e1fico y econ\u00f3mico de Alemania y su posici\u00f3n ahora central en el coraz\u00f3n de una Uni\u00f3n Europea ampliada hacia el Este, esta profunda crisis del \u00abmodelo alem\u00e1n\u00bb ya ha tenido, y probablemente tendr\u00e1 a\u00fan m\u00e1s en el futuro, profundas consecuencias para la construcci\u00f3n europea. No todas est\u00e1n claras en esta fase preliminar de la crisis alemana, pero ya se pueden identificar algunas tendencias.&nbsp;<\/p>\n\n\n\n<p>Las profundas dificultades a las que se enfrenta Alemania con su <em>Schuldenbremse<\/em> y sus deficientes infraestructuras deber\u00edan llevar a las autoridades alemanas a suavizar su postura sobre la austeridad presupuestaria generalizada en Europa y la cuesti\u00f3n de la deuda com\u00fan para financiar los bienes comunes europeos.&nbsp;<\/p>\n\n\n\n<p>Ya se percibi\u00f3 un movimiento en esta direcci\u00f3n en 2020, en la \u00e9poca de la pandemia de COVID-19. Aunque nunca lo admitir\u00eda p\u00fablicamente, Angela Merkel hab\u00eda comprendido sin duda para entonces hasta qu\u00e9 punto la pol\u00edtica de austeridad impuesta por las autoridades alemanas tras la crisis de 2008 hab\u00eda sido contraproducente. Por eso tom\u00f3 la iniciativa de promover la emisi\u00f3n de una deuda com\u00fan de 750.000 millones de euros para hacer frente a las consecuencias de la pandemia y acelerar al mismo tiempo las transiciones ecol\u00f3gica y digital.&nbsp;<\/p>\n\n\n\n<p>Desgraciadamente, el gobierno de Olaf Scholz, presionado sobre todo por los liberales alemanes que ostentaban el ministerio de Finanzas y las llaves de la coalici\u00f3n, volvi\u00f3 posteriormente a posiciones m\u00e1s ortodoxas, <a href=\"https:\/\/legrandcontinent.eu\/es\/2023\/12\/15\/alemania-contra-europa\/\">impidiendo una nueva emisi\u00f3n de deuda com\u00fan para hacer frente a las consecuencias de la guerra de agresi\u00f3n de Rusia contra Ucrania<\/a>. Tambi\u00e9n hab\u00eda desempe\u00f1ado un papel activo para impedir que la reforma del Pacto de Estabilidad y Crecimiento decidida en 2022 cambiara sustancialmente las reglas del juego presupuestario europeo. Tal vez podamos esperar que los dem\u00f3cratas-cristianos, si vuelven al poder como se espera, adopten \u2014por fin\u2014 una actitud m\u00e1s pragm\u00e1tica y proactiva en estas cuestiones, aunque por supuesto no hagan campa\u00f1a con esas ideas.&nbsp;<\/p>\n\n\n\n<p>Del mismo modo, las profundas dificultades industriales de Alemania ya han llevado a las autoridades del pa\u00eds a suavizar su vehemente oposici\u00f3n a cualquier forma de pol\u00edtica industrial europea. El gobierno alem\u00e1n ha apoyado activamente las recientes medidas de revisi\u00f3n de la inversi\u00f3n extranjera, lucha contra el <em>dumping<\/em> y las subvenciones excesivas, y control de las exportaciones de doble uso.&nbsp;<\/p>\n\n\n\n<p>Pero, \u00bfir\u00e1 el Gobierno alem\u00e1n m\u00e1s all\u00e1, en particular apoyando la aplicaci\u00f3n de importantes recursos p\u00fablicos a escala de la Uni\u00f3n para recuperar el retraso tecnol\u00f3gico de Europa e impulsar la inversi\u00f3n, como se pide en <a href=\"https:\/\/legrandcontinent.eu\/es\/2024\/09\/09\/el-informe-draghi-la-fuerza-para-reformar\/\">el informe Draghi<\/a>? Esto es dudoso. Lo que el Gobierno alem\u00e1n se dispone a hacer en su lugar es aprovechar la posici\u00f3n relativamente buena del pa\u00eds en t\u00e9rminos de deuda p\u00fablica para invertir m\u00e1s en la propia Alemania con el fin de apoyar a la industria alemana, como ya ha hecho a gran escala durante la pandemia de COVID-19.&nbsp;<\/p>\n\n\n\n<p>En cambio, todav\u00eda no hay indicios de que el Gobierno se plantee hacer un esfuerzo similar a escala europea. Lo mismo puede decirse de la industria de defensa, un \u00e1mbito en el que los actores alemanes han saboteado regularmente todos los proyectos de cooperaci\u00f3n internacional emprendidos en los \u00faltimos a\u00f1os, especialmente con Francia. En resumen, s\u00ed a una pol\u00edtica industrial mucho m\u00e1s activa, pero ante todo en Alemania en beneficio de los actores alemanes.&nbsp;<\/p>\n\n\n\n<p>En materia de pol\u00edtica exterior, la desestabilizaci\u00f3n de la sociedad alemana bajo el impacto de una importante afluencia de inmigrantes durante las dos \u00faltimas d\u00e9cadas ya ha hecho que las autoridades alemanas se pasen al bando de los partidarios de una pol\u00edtica de \u00abEuropa Fortaleza\u00bb. Prueba de ello es la pol\u00edtica tan agresiva que promueve ahora a escala de la Uni\u00f3n la comisaria alemana y presidenta de la Comisi\u00f3n, Ursula von der Leyen, en estrecha coordinaci\u00f3n con el gobierno italiano de extrema derecha de Georgia Meloni.&nbsp;<\/p>\n\n\n\n<p>Esta pol\u00edtica antimigratoria se combina con el apoyo incondicional de Alemania al gobierno israel\u00ed de Netanyahu despu\u00e9s del 7 de octubre, incluso en el frente militar, ya que Alemania suministra el 30% de las armas importadas por Israel. Esta combinaci\u00f3n explosiva convierte ahora a Alemania en uno de los principales pa\u00edses responsables, aunque ni mucho menos el \u00fanico, de la creciente fractura entre la Uni\u00f3n Europea y lo que ahora se conoce como el \u00abSur Global\u00bb. Este creciente aislamiento de Europa es una de las amenazas m\u00e1s graves para su futuro, como ya hemos visto en el Sahel en los \u00faltimos meses y en <a href=\"https:\/\/legrandcontinent.eu\/es\/2024\/10\/27\/las-12-tesis-de-kazan-la-retorica-del-nuevo-orden-de-los-brics\/\">la cumbre de los BRICS en Kaz\u00e1n, en Rusia, el pasado mes de octubre<\/a>. Desgraciadamente, hay pocas razones para creer que la vuelta al poder de los Dem\u00f3cratas-Cristianos vaya a conducir en el futuro a una pol\u00edtica menos contraproducente hacia el Sur Global. M\u00e1s bien al contrario.&nbsp;<\/p>\n\n\n\n<p>En materia de defensa, la primera presidencia de Trump, seguida de la guerra de agresi\u00f3n de Rusia contra Ucrania, sac\u00f3 a Alemania del largo letargo en el que la hab\u00eda sumido el improbable binomio formado por un movimiento pacifista muy poderoso y un atlantismo f\u00e9rreo que hab\u00eda delegado toda la defensa del pa\u00eds en Estados Unidos. Esto desencaden\u00f3 el famoso <em>Zeitenwende<\/em>, el cambio de era, anunciado por Olaf Scholz en febrero de 2022, acompa\u00f1ado de un gran esfuerzo de rearme por valor de 100.000 millones de euros.&nbsp;<\/p>\n\n\n\n<p>Aunque la aplicaci\u00f3n de este Zeitenwende ha sido bastante lenta hasta ahora, debido sobre todo a la austeridad presupuestaria, todo hace pensar que este esfuerzo continuar\u00e1. \u00bfFavorecer\u00e1 este cambio de orientaci\u00f3n el surgimiento de una verdadera pol\u00edtica com\u00fan de defensa? Eso est\u00e1 por ver, ya que por el momento las autoridades alemanas no han enviado ninguna se\u00f1al significativa en este sentido. La mayor\u00eda de los proyectos de cooperaci\u00f3n en el \u00e1mbito del equipamiento militar se han estancado, y cuando Alemania propuso construir un escudo antimisiles europeo, lo hizo excluyendo a Francia e Italia, que ya hab\u00edan desarrollado conjuntamente sistemas que habr\u00edan encajado perfectamente.<\/p>\n\n\n\n<p>Adem\u00e1s, en lo que respecta a Rusia y China, los movimientos pacifistas y los lobbies industriales que defienden las pol\u00edticas mercantilistas tradicionales siguen pesando mucho en las decisiones alemanas, a pesar de que el pa\u00eds se ha comprometido firmemente a apoyar a Ucrania desde 2022, incluso militarmente, lo que no era nada evidente al principio. Aunque los dem\u00f3cratas-cristianos de Friedrich Merz tienen una postura m\u00e1s firme en este asunto que el canciller Olaf Scholz, la sociedad alemana es y seguir\u00e1 siendo un eslab\u00f3n d\u00e9bil en Europa a la hora de enfrentarse al imperialismo de Vladimir Putin. Las fuerzas pol\u00edticas con el viento a favor en Alemania, la AfD en la extrema derecha y el BSW en la izquierda, son las m\u00e1s hostiles a Ucrania.&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>Alemania tambi\u00e9n estar\u00e1 en primera l\u00ednea a la hora de enfrentarse a Donald Trump y sus pol\u00edticas abiertamente antieuropeas, dados los excedentes comerciales de Alemania con Estados Unidos. Alemania, que ha sido proestadounidense y superatlantista desde el final de la Segunda Guerra Mundial, \u00bfest\u00e1 ahora preparada para enfrentarse a Trump y contraatacar? Incluso si eso significa que Europa tendr\u00e1 que cortar el cord\u00f3n y confiar principalmente en sus propias fuerzas en el futuro, incluso en t\u00e9rminos de su propia defensa. Esta es una de las grandes inc\u00f3gnitas del periodo que se avecina.&nbsp;<\/p>\n\n\n\n<p>Sin embargo, ello no est\u00e1 totalmente descartado.&nbsp;<\/p>\n\n\n\n<p>En 2002, el canciller Gerhard Schr\u00f6der, a la cabeza de una Alemania que hab\u00eda recuperado la confianza en s\u00ed misma, hizo un gesto que entonces parec\u00eda casi impensable para un canciller alem\u00e1n: se uni\u00f3 a la Francia de Jacques Chirac para oponerse a la intervenci\u00f3n estadounidense en Irak. Una intervenci\u00f3n que posteriormente result\u00f3 catastr\u00f3fica. Pero esta vez es la derecha alemana, con fama de ser a\u00fan m\u00e1s atlantista que los socialdem\u00f3cratas, la que tendr\u00e1 que asumir esta confrontaci\u00f3n. Ya sea Friedrich Merz al frente del pa\u00eds o Ursula von der Leyen al frente de la Comisi\u00f3n y Manfred Weber, l\u00edder del PPE en el Parlamento Europeo, a nivel europeo. Pero, parad\u00f3jicamente, probablemente ser\u00eda m\u00e1s f\u00e1cil romper con Estados Unidos para los l\u00edderes alemanes de derechas que para los de izquierdas, siempre sospechosos de antiamericanismo<em> a priori<\/em>.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>La sociedad alemana es y seguir\u00e1 siendo un eslab\u00f3n d\u00e9bil en Europa a la hora de enfrentarse al imperialismo de Vladimir Putin.<\/p><cite>GUILLAUME DUVAL<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Cruzada por la austeridad presupuestaria, rechazo de toda pol\u00edtica industrial, pacifismo y atlantismo estrechamente imbricados&#8230; las crisis alemanas obligan a nuestros vecinos a poner en tela de juicio dogmas hasta ahora intangibles y muy perjudiciales para la construcci\u00f3n europea. Sin embargo, no es seguro que estos desaf\u00edos basten para que Alemania vuelva a ser un motor de la integraci\u00f3n europea. Sobre todo porque estas crisis tambi\u00e9n est\u00e1n reforzando otras convicciones al otro lado del Rin, especialmente contra la inmigraci\u00f3n y a favor de una \u00abEuropa Fortaleza\u00bb, que tambi\u00e9n entra\u00f1an enormes riesgos para el futuro de la integraci\u00f3n europea.&nbsp;<\/p>\n\n\n\n<p>Sobre todo, esta crisis multiforme del \u00abmodelo alem\u00e1n\u00bb, al desestabilizar profundamente la sociedad y la econom\u00eda de nuestros vecinos, les incita sin duda a mirarse el ombligo y a dar prioridad a la b\u00fasqueda de soluciones a escala nacional. En lugar de animarles a desempe\u00f1ar el papel que el liderazgo alem\u00e1n requerir\u00eda en Europa para hacer avanzar la integraci\u00f3n al ritmo acelerado que ahora exigen tanto un entorno geopol\u00edtico que se ha vuelto mucho m\u00e1s peligroso como unos retos globales, en particular ecol\u00f3gicos, que s\u00f3lo podemos esperar afrontar juntos.&nbsp;&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante mucho tiempo, tres elementos estabilizadores mantuvieron a Alemania: su sistema pol\u00edtico, su identidad, su modelo econ\u00f3mico.<\/p>\n<p>Ahora que Scholz est\u00e1 a punto de caer, esas tres dimensiones han estallado, sumiendo al pa\u00eds en una crisis sin precedentes que lo ha convertido en el enfermo de Europa.<\/p>\n<p>Desde la industria y la natalidad hasta las finanzas p\u00fablicas y los ferrocarriles, Guillaume Duval disecciona este persistente malestar \u2014y las consecuencias que podr\u00eda tener para el resto del continente\u2014.<\/p>\n","protected":false},"author":1366,"featured_media":50882,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-angles.php","format":"standard","meta":{"_acf_changed":true,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":48,"footnotes":""},"categories":[955],"tags":[],"staff":[966],"editorial_format":[1470],"serie":[],"audience":[],"geo":[177],"class_list":["post-50879","post","type-post","status-publish","format-standard","hentry","category-alemania-en-el-interregno","staff-guillaume-duval","editorial_format-perspectivas-sobre-la-actualidad","geo-europa"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":50882,"excerpt":"Durante mucho tiempo, tres elementos estabilizadores mantuvieron a Alemania: su sistema pol\u00edtico, su identidad, su modelo econ\u00f3mico.\r\n\r\nAhora que Scholz est\u00e1 a punto de caer, esas tres dimensiones han estallado, sumiendo al pa\u00eds en una crisis sin precedentes que lo ha convertido en el enfermo de Europa.\r\n\r\nDesde la industria y la natalidad hasta las finanzas p\u00fablicas y los ferrocarriles, Guillaume Duval disecciona este persistente malestar \u2014y las consecuencias que podr\u00eda tener para el resto del continente\u2014.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Alemania en la macrocrisis: autopsia de un pa\u00eds roto - El Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/es\/2024\/12\/16\/alemania-en-la-macrocrisis-autopsia-de-un-pais-roto\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alemania en la macrocrisis: autopsia de un pa\u00eds roto - El Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Durante mucho tiempo, tres elementos estabilizadores mantuvieron a Alemania: su sistema pol\u00edtico, su identidad, su modelo econ\u00f3mico.  Ahora que Scholz est\u00e1 a punto de caer, esas tres dimensiones han estallado, sumiendo al pa\u00eds en una crisis sin precedentes que lo ha convertido en el enfermo de Europa.  Desde la industria y la natalidad hasta las finanzas p\u00fablicas y los ferrocarriles, Guillaume Duval disecciona este persistente malestar \u2014y las consecuencias que podr\u00eda tener para el resto del continente\u2014.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/es\/2024\/12\/16\/alemania-en-la-macrocrisis-autopsia-de-un-pais-roto\/\" \/>\n<meta property=\"og:site_name\" content=\"El Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-16T14:55:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-16T14:55:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/12\/gc-elscholz-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"florent\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/12\/gc-elscholz-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"florent\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"48 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/12\/16\/alemania-en-la-macrocrisis-autopsia-de-un-pais-roto\/\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/2024\/12\/16\/alemania-en-la-macrocrisis-autopsia-de-un-pais-roto\/\",\"name\":\"Alemania en la macrocrisis: autopsia de un pa\u00eds roto - El Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/12\/16\/alemania-en-la-macrocrisis-autopsia-de-un-pais-roto\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/12\/16\/alemania-en-la-macrocrisis-autopsia-de-un-pais-roto\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/12\/SIPA_ap22855753_000026-scaled-1.jpg\",\"datePublished\":\"2024-12-16T14:55:34+00:00\",\"dateModified\":\"2024-12-16T14:55:39+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/12\/16\/alemania-en-la-macrocrisis-autopsia-de-un-pais-roto\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/es\/2024\/12\/16\/alemania-en-la-macrocrisis-autopsia-de-un-pais-roto\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/12\/16\/alemania-en-la-macrocrisis-autopsia-de-un-pais-roto\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/12\/SIPA_ap22855753_000026-scaled-1.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/12\/SIPA_ap22855753_000026-scaled-1.jpg\",\"width\":2560,\"height\":1800,\"caption\":\"Il cancelliere tedesco Olaf Scholz ispeziona un pezzo nello stabilimento di produzione dell'azienda orologiera Nomos Glashutte a Glashuette, in Germania, gioved\u00ec 29 febbraio 2024. \u00a9 Jens Schlueter\/Pool photo via AP\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/12\/16\/alemania-en-la-macrocrisis-autopsia-de-un-pais-roto\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/legrandcontinent.eu\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alemania en la macrocrisis: autopsia de un pa\u00eds roto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/\",\"name\":\"El Grand Continent\",\"description\":\"La escala pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\",\"name\":\"florent\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"caption\":\"florent\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alemania en la macrocrisis: autopsia de un pa\u00eds roto - El Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/es\/2024\/12\/16\/alemania-en-la-macrocrisis-autopsia-de-un-pais-roto\/","og_locale":"es_ES","og_type":"article","og_title":"Alemania en la macrocrisis: autopsia de un pa\u00eds roto - El Grand Continent","og_description":"Durante mucho tiempo, tres elementos estabilizadores mantuvieron a Alemania: su sistema pol\u00edtico, su identidad, su modelo econ\u00f3mico.  Ahora que Scholz est\u00e1 a punto de caer, esas tres dimensiones han estallado, sumiendo al pa\u00eds en una crisis sin precedentes que lo ha convertido en el enfermo de Europa.  Desde la industria y la natalidad hasta las finanzas p\u00fablicas y los ferrocarriles, Guillaume Duval disecciona este persistente malestar \u2014y las consecuencias que podr\u00eda tener para el resto del continente\u2014.","og_url":"https:\/\/legrandcontinent.eu\/es\/2024\/12\/16\/alemania-en-la-macrocrisis-autopsia-de-un-pais-roto\/","og_site_name":"El Grand Continent","article_published_time":"2024-12-16T14:55:34+00:00","article_modified_time":"2024-12-16T14:55:39+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/12\/gc-elscholz-scaled.jpg","type":"image\/jpeg"}],"author":"florent","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/12\/gc-elscholz-scaled.jpg","twitter_misc":{"Escrito por":"florent","Tiempo de lectura":"48 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/es\/2024\/12\/16\/alemania-en-la-macrocrisis-autopsia-de-un-pais-roto\/","url":"https:\/\/legrandcontinent.eu\/es\/2024\/12\/16\/alemania-en-la-macrocrisis-autopsia-de-un-pais-roto\/","name":"Alemania en la macrocrisis: autopsia de un pa\u00eds roto - El Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/es\/2024\/12\/16\/alemania-en-la-macrocrisis-autopsia-de-un-pais-roto\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/es\/2024\/12\/16\/alemania-en-la-macrocrisis-autopsia-de-un-pais-roto\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/12\/SIPA_ap22855753_000026-scaled-1.jpg","datePublished":"2024-12-16T14:55:34+00:00","dateModified":"2024-12-16T14:55:39+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/es\/2024\/12\/16\/alemania-en-la-macrocrisis-autopsia-de-un-pais-roto\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/es\/2024\/12\/16\/alemania-en-la-macrocrisis-autopsia-de-un-pais-roto\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/2024\/12\/16\/alemania-en-la-macrocrisis-autopsia-de-un-pais-roto\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/12\/SIPA_ap22855753_000026-scaled-1.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/12\/SIPA_ap22855753_000026-scaled-1.jpg","width":2560,"height":1800,"caption":"Il cancelliere tedesco Olaf Scholz ispeziona un pezzo nello stabilimento di produzione dell'azienda orologiera Nomos Glashutte a Glashuette, in Germania, gioved\u00ec 29 febbraio 2024. \u00a9 Jens Schlueter\/Pool photo via AP"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/es\/2024\/12\/16\/alemania-en-la-macrocrisis-autopsia-de-un-pais-roto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legrandcontinent.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Alemania en la macrocrisis: autopsia de un pa\u00eds roto"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/es\/#website","url":"https:\/\/legrandcontinent.eu\/es\/","name":"El Grand Continent","description":"La escala pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c","name":"florent","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","caption":"florent"}}]}},"lgc_categories":[{"id":955,"name":"Alemania en el interregno","slug":"alemania-en-el-interregno"}],"lgc_author":{"id":966,"name":"Guillaume Duval","slug":"guillaume-duval","description":"Guillaume Duval es antiguo redactor jefe de Alternatives \u00c9conomiques. Es autor de \u00abMade in Germany, le mod\u00e8le allemand au del\u00e0 des mythes\u00bb, publicado por Seuil.\r\n","first_name":"Guillaume","last_name":"Duval","picture":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/12\/gc-GuillaumeDuval-1.png","width":222,"height":222,"alt":""}},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/12\/SIPA_ap22855753_000026-scaled-1.jpg","width":2560,"height":1800,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/12\/SIPA_ap22855753_000026-scaled-1.jpg","width":2560,"height":1800,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/50879","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/users\/1366"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/comments?post=50879"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/50879\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media\/50882"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media?parent=50879"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/categories?post=50879"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/tags?post=50879"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/staff?post=50879"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/editorial_format?post=50879"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/serie?post=50879"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/audience?post=50879"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/geo?post=50879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}