{"id":49335,"date":"2024-11-21T06:30:00","date_gmt":"2024-11-21T05:30:00","guid":{"rendered":"https:\/\/legrandcontinent.eu\/es\/?p=49335"},"modified":"2024-11-21T12:10:46","modified_gmt":"2024-11-21T11:10:46","slug":"el-regreso-de-trump-amenaza-los-esfuerzos-por-hacer-mas-segura-la-ia","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/es\/2024\/11\/21\/el-regreso-de-trump-amenaza-los-esfuerzos-por-hacer-mas-segura-la-ia\/","title":{"rendered":"El regreso de Trump amenaza los esfuerzos por hacer m\u00e1s segura la IA"},"content":{"rendered":"\n<p>El pasado mes de mayo, <a href=\"https:\/\/legrandcontinent.eu\/es\/2024\/05\/21\/hoy-se-inaugura-en-seul-una-cumbre-sobre-ia\/\">Se\u00fal acogi\u00f3 una importante cumbre internacional sobre IA<\/a>, organizada conjuntamente por el Reino Unido y Corea del Sur. Esta cumbre sigui\u00f3 a la primera cumbre internacional sobre la seguridad de la inteligencia artificial celebrada 6 meses antes <a href=\"https:\/\/legrandcontinent.eu\/es\/2023\/11\/01\/elon-musk-en-el-reino-unido-hoy-se-inaugura-la-primera-cumbre-internacional-sobre-seguridad-de-la-ia\/\">en Bletchley Park<\/a>, lugar famoso por haber sido el centro neur\u00e1lgico de las operaciones de descifrado durante la Segunda Guerra Mundial.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Seg\u00fan Bain &amp; Co, el mercado mundial de la IA tendr\u00e1 un valor de casi 1 bill\u00f3n de d\u00f3lares en 2027&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-49335' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2024\/11\/21\/el-regreso-de-trump-amenaza-los-esfuerzos-por-hacer-mas-segura-la-ia\/#easy-footnote-bottom-1-49335' title='Saritha Rai, \u00ab\u00a0&lt;a href=&quot;https:\/\/www.bloomberg.com\/news\/articles\/2024-09-25\/ai-market-will-surge-to-near-1-trillion-by-2027-bain-says&quot;&gt;AI Market Will Surge to Near $1 Trillion by 2027, Bain Says&lt;\/a&gt;\u00a0\u00bb,\u00a0&lt;em&gt;Bloomberg&lt;\/em&gt;, 25 de septiembre de 2024.'><sup>1<\/sup><\/a><\/span><\/span>.<\/li>\n\n\n\n<li>En su punto \u00e1lgido, alcanzado en abril de 2023 tras la introducci\u00f3n de GPT-4, el agente conversacional de OpenAI, ChatGPT, atra\u00eda 1.800 millones de visitas al mes.<\/li>\n\n\n\n<li>Sin embargo, el creciente uso de diversos servicios de inteligencia artificial conlleva un importante n\u00famero de riesgos, que van desde los <em>deepfakes<\/em> hasta el bioterrorismo, que los gobiernos quieren comprender mejor y prevenir.<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/P4orn\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Este es el objetivo de la reuni\u00f3n que se celebra actualmente en San Francisco. Organizada conjuntamente por el Departamento de Estado y el Departamento de Comercio de Estados Unidos, tiene por objeto inaugurar el lanzamiento de la Red Internacional de Institutos de Seguridad de la IA&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-49335' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2024\/11\/21\/el-regreso-de-trump-amenaza-los-esfuerzos-por-hacer-mas-segura-la-ia\/#easy-footnote-bottom-2-49335' title='&lt;a href=&quot;https:\/\/www.commerce.gov\/news\/press-releases\/2024\/09\/us-secretary-commerce-raimondo-and-us-secretary-state-blinken-announce&quot;&gt;U.S. Secretary of Commerce Raimondo and U.S. Secretary of State Blinken Announce Inaugural Convening of International Network of AI Safety Institutes in San Francisco&lt;\/a&gt;, 18 de septiembre de 2024.'><sup>2<\/sup><\/a><\/span><\/span>. Esta iniciativa, que re\u00fane actualmente a 35 pa\u00edses (incluidos los 27 miembros de la Uni\u00f3n Europea), consiste en una red de institutos cuya funci\u00f3n es elaborar una hoja de ruta para hacer m\u00e1s seguro el uso de la IA.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/QmVxe\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>La \u00abseguridad de la IA\u00bb es un campo de investigaci\u00f3n por derecho propio, dividido en dos \u00e1mbitos principales: la seguridad t\u00e9cnica y la seguridad de los procesos&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-49335' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2024\/11\/21\/el-regreso-de-trump-amenaza-los-esfuerzos-por-hacer-mas-segura-la-ia\/#easy-footnote-bottom-3-49335' title='Gregory C. Allen y Georgia Adamson,\u00a0&lt;a href=&quot;https:\/\/www.csis.org\/analysis\/ai-safety-institute-international-network-next-steps-and-recommendations&quot;&gt;The AI Safety Institute International Network\u00a0: Next Steps and Recommendations&lt;\/a&gt;, CSIS, octubre de 2024'><sup>3<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>El aspecto t\u00e9cnico busca que los modelos de inteligencia artificial sean m\u00e1s fiables y coherentes con el uso previsto por sus desarrolladores. En San Francisco, los expertos de la Red debatir\u00e1n sobre c\u00f3mo hacer la IA m\u00e1s robusta, definir mejor sus objetivos y controlar mejor la actividad de los <em>chatbots<\/em>&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-4-49335' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2024\/11\/21\/el-regreso-de-trump-amenaza-los-esfuerzos-por-hacer-mas-segura-la-ia\/#easy-footnote-bottom-4-49335' title='Pedro A. Ortega y Vishal Maini,\u00a0&lt;a href=&quot;https:\/\/deepmindsafetyresearch.medium.com\/building-safe-artificial-intelligence-52f5f75058f1&quot;&gt;Building safe artificial intelligence\u00a0: specification, robustness, and assurance&lt;\/a&gt;,\u00a0&lt;em&gt;Medium&lt;\/em&gt;, 27 de septiembre de 2018.'><sup>4<\/sup><\/a><\/span><\/span>.<\/li>\n\n\n\n<li>El aspecto de los procesos, por su parte, es m\u00e1s operativo y se refiere a las pol\u00edticas y procedimientos que rodean el uso de la IA. Debe permitir a los desarrolladores construir y gestionar mejor los modelos de IA para garantizar un uso seguro.<\/li>\n<\/ul>\n\n\n\n<p>A dos meses de su investidura, la reuni\u00f3n se celebra a la sombra de Donald Trump. Durante la campa\u00f1a, Trump prometi\u00f3 anular la orden ejecutiva firmada por Biden en noviembre de 2023 por la que se imponen normas a las empresas que desarrollan modelos de IA. La <a href=\"https:\/\/legrandcontinent.eu\/es\/2024\/11\/11\/el-programa-de-donald-trump-que-nadie-en-europa-ha-leido-realmente\/\">plataforma del Partido Republicano<\/a> aprobada en julio afirma que el presidente electo, una vez en la Casa Blanca, derogar\u00e1 \u00abel peligroso <a href=\"https:\/\/legrandcontinent.eu\/es\/2023\/10\/30\/regulacion-de-la-ia-joe-biden-firma-un-decreto-presidencial-decisivo\/\">decreto de Joe Biden<\/a> que obstaculiza la innovaci\u00f3n en IA e impone ideas radicales de izquierdas al desarrollo de esta tecnolog\u00eda\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-5-49335' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2024\/11\/21\/el-regreso-de-trump-amenaza-los-esfuerzos-por-hacer-mas-segura-la-ia\/#easy-footnote-bottom-5-49335' title='&lt;a href=&quot;https:\/\/s3.documentcloud.org\/documents\/24795758\/read-the-2024-republican-party-platform.pdf&quot;&gt;2024 GOP PLATFORM MAKE AMERICA GREAT AGAIN\u00a0!&lt;\/a&gt;'><sup>5<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/94C5u\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>La postura general de Trump sobre la inteligencia artificial est\u00e1 menos clara. Aunque podr\u00eda mantener la red de institutos de IA, que la futura administraci\u00f3n considera importante, <a href=\"https:\/\/legrandcontinent.eu\/es\/2024\/11\/15\/que-puede-hacer-el-doge-de-musk-y-ramaswamy-como-trump-quiere-reforzar-su-poder-ejecutivo-y-debilitar-el-papel-del-congreso\/\">su estrecho aliado Elon Musk<\/a> se muestra m\u00e1s esc\u00e9ptico sobre el uso de la tecnolog\u00eda por parte de algunos actores importantes, como la empresa OpenAI, contra la que present\u00f3 una demanda en agosto&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-6-49335' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2024\/11\/21\/el-regreso-de-trump-amenaza-los-esfuerzos-por-hacer-mas-segura-la-ia\/#easy-footnote-bottom-6-49335' title='Sarah Parvini, \u00ab\u00a0&lt;a href=&quot;https:\/\/apnews.com\/article\/elon-musk-open-ai-sam-altman-artificial-intelligence-6b734fe41cc24cb3029a0a863e73f190&quot;&gt;Elon Musk sues OpenAI, renewing claims ChatGPT-maker put profits before \u2018the benefit of humanity\u2019&lt;\/a&gt;\u00a0\u00bb,\u00a0&lt;em&gt;Associated Press&lt;\/em&gt;, 6 de agosto de 2024.'><sup>6<\/sup><\/a><\/span><\/span>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Funcionarios de Estados Unidos, Europa, Canad\u00e1, Singapur, Reino Unido y Kenia est\u00e1n reunidos estos d\u00edas en San Francisco para la inauguraci\u00f3n de la Red Internacional de Institutos de Seguridad de la IA. Esta iniciativa, lanzada el pasado mes de mayo tras la cumbre sobre IA de Se\u00fal, busca crear un enfoque com\u00fan ante los nuevos riesgos que plantea la inteligencia artificial. Sin embargo, el regreso de Trump a la Casa Blanca amenaza esta ambici\u00f3n.<\/p>\n","protected":false},"author":1366,"featured_media":49338,"comment_status":"closed","ping_status":"","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":true,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":3,"footnotes":""},"categories":[123],"tags":[],"staff":[],"editorial_format":[1472],"serie":[],"audience":[],"geo":[172],"class_list":["post-49335","post","type-post","status-publish","format-standard","hentry","category-digital","editorial_format-analisis","geo-americas"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":49338,"excerpt":"Funcionarios de Estados Unidos, Europa, Canad\u00e1, Singapur, Reino Unido y Kenia est\u00e1n reunidos estos d\u00edas en San Francisco para la inauguraci\u00f3n de la Red Internacional de Institutos de Seguridad de la IA. Esta iniciativa, lanzada el pasado mes de mayo tras la cumbre sobre IA de Se\u00fal, busca crear un enfoque com\u00fan ante los nuevos riesgos que plantea la inteligencia artificial. Sin embargo, el regreso de Trump a la Casa Blanca amenaza esta ambici\u00f3n.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El regreso de Trump amenaza los esfuerzos por hacer m\u00e1s segura la IA - El Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/es\/2024\/11\/21\/el-regreso-de-trump-amenaza-los-esfuerzos-por-hacer-mas-segura-la-ia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El regreso de Trump amenaza los esfuerzos por hacer m\u00e1s segura la IA - El Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Funcionarios de Estados Unidos, Europa, Canad\u00e1, Singapur, Reino Unido y Kenia est\u00e1n reunidos estos d\u00edas en San Francisco para la inauguraci\u00f3n de la Red Internacional de Institutos de Seguridad de la IA. Esta iniciativa, lanzada el pasado mes de mayo tras la cumbre sobre IA de Se\u00fal, busca crear un enfoque com\u00fan ante los nuevos riesgos que plantea la inteligencia artificial. Sin embargo, el regreso de Trump a la Casa Blanca amenaza esta ambici\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/es\/2024\/11\/21\/el-regreso-de-trump-amenaza-los-esfuerzos-por-hacer-mas-segura-la-ia\/\" \/>\n<meta property=\"og:site_name\" content=\"El Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-21T05:30:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-21T11:10:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/11\/QmVxe-miembros-de-la-red-internacional-de-institutos-de-seguridad-de-la-ia-.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1348\" \/>\n\t<meta property=\"og:image:height\" content=\"794\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"florent\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"florent\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/11\/21\/el-regreso-de-trump-amenaza-los-esfuerzos-por-hacer-mas-segura-la-ia\/\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/2024\/11\/21\/el-regreso-de-trump-amenaza-los-esfuerzos-por-hacer-mas-segura-la-ia\/\",\"name\":\"El regreso de Trump amenaza los esfuerzos por hacer m\u00e1s segura la IA - El Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/11\/21\/el-regreso-de-trump-amenaza-los-esfuerzos-por-hacer-mas-segura-la-ia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/11\/21\/el-regreso-de-trump-amenaza-los-esfuerzos-por-hacer-mas-segura-la-ia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/11\/QmVxe-miembros-de-la-red-internacional-de-institutos-de-seguridad-de-la-ia-.png\",\"datePublished\":\"2024-11-21T05:30:00+00:00\",\"dateModified\":\"2024-11-21T11:10:46+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/11\/21\/el-regreso-de-trump-amenaza-los-esfuerzos-por-hacer-mas-segura-la-ia\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/es\/2024\/11\/21\/el-regreso-de-trump-amenaza-los-esfuerzos-por-hacer-mas-segura-la-ia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/11\/21\/el-regreso-de-trump-amenaza-los-esfuerzos-por-hacer-mas-segura-la-ia\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/11\/QmVxe-miembros-de-la-red-internacional-de-institutos-de-seguridad-de-la-ia-.png\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/11\/QmVxe-miembros-de-la-red-internacional-de-institutos-de-seguridad-de-la-ia-.png\",\"width\":1348,\"height\":794},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/11\/21\/el-regreso-de-trump-amenaza-los-esfuerzos-por-hacer-mas-segura-la-ia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/legrandcontinent.eu\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El regreso de Trump amenaza los esfuerzos por hacer m\u00e1s segura la IA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/\",\"name\":\"El Grand Continent\",\"description\":\"La escala pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\",\"name\":\"florent\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"caption\":\"florent\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El regreso de Trump amenaza los esfuerzos por hacer m\u00e1s segura la IA - El Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/es\/2024\/11\/21\/el-regreso-de-trump-amenaza-los-esfuerzos-por-hacer-mas-segura-la-ia\/","og_locale":"es_ES","og_type":"article","og_title":"El regreso de Trump amenaza los esfuerzos por hacer m\u00e1s segura la IA - El Grand Continent","og_description":"Funcionarios de Estados Unidos, Europa, Canad\u00e1, Singapur, Reino Unido y Kenia est\u00e1n reunidos estos d\u00edas en San Francisco para la inauguraci\u00f3n de la Red Internacional de Institutos de Seguridad de la IA. Esta iniciativa, lanzada el pasado mes de mayo tras la cumbre sobre IA de Se\u00fal, busca crear un enfoque com\u00fan ante los nuevos riesgos que plantea la inteligencia artificial. Sin embargo, el regreso de Trump a la Casa Blanca amenaza esta ambici\u00f3n.","og_url":"https:\/\/legrandcontinent.eu\/es\/2024\/11\/21\/el-regreso-de-trump-amenaza-los-esfuerzos-por-hacer-mas-segura-la-ia\/","og_site_name":"El Grand Continent","article_published_time":"2024-11-21T05:30:00+00:00","article_modified_time":"2024-11-21T11:10:46+00:00","og_image":[{"width":1348,"height":794,"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/11\/QmVxe-miembros-de-la-red-internacional-de-institutos-de-seguridad-de-la-ia-.png","type":"image\/png"}],"author":"florent","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"florent","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/es\/2024\/11\/21\/el-regreso-de-trump-amenaza-los-esfuerzos-por-hacer-mas-segura-la-ia\/","url":"https:\/\/legrandcontinent.eu\/es\/2024\/11\/21\/el-regreso-de-trump-amenaza-los-esfuerzos-por-hacer-mas-segura-la-ia\/","name":"El regreso de Trump amenaza los esfuerzos por hacer m\u00e1s segura la IA - El Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/es\/2024\/11\/21\/el-regreso-de-trump-amenaza-los-esfuerzos-por-hacer-mas-segura-la-ia\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/es\/2024\/11\/21\/el-regreso-de-trump-amenaza-los-esfuerzos-por-hacer-mas-segura-la-ia\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/11\/QmVxe-miembros-de-la-red-internacional-de-institutos-de-seguridad-de-la-ia-.png","datePublished":"2024-11-21T05:30:00+00:00","dateModified":"2024-11-21T11:10:46+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/es\/2024\/11\/21\/el-regreso-de-trump-amenaza-los-esfuerzos-por-hacer-mas-segura-la-ia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/es\/2024\/11\/21\/el-regreso-de-trump-amenaza-los-esfuerzos-por-hacer-mas-segura-la-ia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/2024\/11\/21\/el-regreso-de-trump-amenaza-los-esfuerzos-por-hacer-mas-segura-la-ia\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/11\/QmVxe-miembros-de-la-red-internacional-de-institutos-de-seguridad-de-la-ia-.png","contentUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/11\/QmVxe-miembros-de-la-red-internacional-de-institutos-de-seguridad-de-la-ia-.png","width":1348,"height":794},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/es\/2024\/11\/21\/el-regreso-de-trump-amenaza-los-esfuerzos-por-hacer-mas-segura-la-ia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legrandcontinent.eu\/es\/"},{"@type":"ListItem","position":2,"name":"El regreso de Trump amenaza los esfuerzos por hacer m\u00e1s segura la IA"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/es\/#website","url":"https:\/\/legrandcontinent.eu\/es\/","name":"El Grand Continent","description":"La escala pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c","name":"florent","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","caption":"florent"}}]}},"lgc_categories":[{"id":123,"name":"Digital","slug":"digital"}],"lgc_author":null,"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/11\/QmVxe-miembros-de-la-red-internacional-de-institutos-de-seguridad-de-la-ia-.png","width":1348,"height":794,"alt":""},"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/49335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/users\/1366"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/comments?post=49335"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/49335\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media\/49338"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media?parent=49335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/categories?post=49335"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/tags?post=49335"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/staff?post=49335"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/editorial_format?post=49335"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/serie?post=49335"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/audience?post=49335"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/geo?post=49335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}