{"id":49015,"date":"2024-11-15T13:04:00","date_gmt":"2024-11-15T12:04:00","guid":{"rendered":"https:\/\/legrandcontinent.eu\/es\/?p=49015"},"modified":"2024-11-26T19:13:16","modified_gmt":"2024-11-26T18:13:16","slug":"que-puede-hacer-el-doge-de-musk-y-ramaswamy-como-trump-quiere-reforzar-su-poder-ejecutivo-y-debilitar-el-papel-del-congreso","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/es\/2024\/11\/15\/que-puede-hacer-el-doge-de-musk-y-ramaswamy-como-trump-quiere-reforzar-su-poder-ejecutivo-y-debilitar-el-papel-del-congreso\/","title":{"rendered":"\u00bfQu\u00e9 podr\u00e1 hacer el DOGE de Musk y Ramaswamy? C\u00f3mo Trump quiere reforzar su poder ejecutivo y debilitar el papel del Congreso"},"content":{"rendered":"\n<p>La cartera de la nueva comisi\u00f3n \u2014el Departamento de Eficiencia Gubernamental (DOGE)\u2014, cuya creaci\u00f3n anunci\u00f3 Trump el martes 12 de noviembre, es muy amplia, hasta el punto de que Trump declar\u00f3 que podr\u00eda convertirse en \u00abel Proyecto Manhattan de nuestro tiempo\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-49015' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2024\/11\/15\/que-puede-hacer-el-doge-de-musk-y-ramaswamy-como-trump-quiere-reforzar-su-poder-ejecutivo-y-debilitar-el-papel-del-congreso\/#easy-footnote-bottom-1-49015' title='&lt;a href=&quot;https:\/\/djt.nucleusemail.com\/amplify\/v\/7RdtJGTKeA&quot;&gt;STATEMENT FROM PRESIDENT DONALD J. TRUMP&lt;\/a&gt;, 12 de noviembre de 2024.'><sup>1<\/sup><\/a><\/span><\/span>. En concreto, el DOGE se encargar\u00e1 de \u00abdesmantelar la burocracia gubernamental, eliminar la regulaci\u00f3n excesiva, reducir el gasto superfluo y reestructurar las agencias federales\u00bb.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>El DOGE no ser\u00e1 un nuevo departamento federal de Estado, sino que probablemente adoptar\u00e1 la forma de una comisi\u00f3n presidencial cuyo prop\u00f3sito ser\u00e1 \u00abproporcionar asesoramiento y orientaci\u00f3n desde fuera del gobierno\u00bb.<\/li>\n\n\n\n<li>A diferencia de un departamento propiamente dicho, cuya creaci\u00f3n requiere el acuerdo de las dos c\u00e1maras del Congreso, una comisi\u00f3n presidencial puede crearse mediante una simple orden ejecutiva firmada por el presidente&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-49015' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2024\/11\/15\/que-puede-hacer-el-doge-de-musk-y-ramaswamy-como-trump-quiere-reforzar-su-poder-ejecutivo-y-debilitar-el-papel-del-congreso\/#easy-footnote-bottom-2-49015' title='El \u00faltimo departamento estadounidense en crearse fue el Departamento de Seguridad Nacional (2002), creado tras los atentados del 11 de septiembre de 2001. Fue creado por la Ley de Seguridad Interior de 2002, que fue aprobada por la C\u00e1mara de Representantes con 295 votos (de 435) y por el Senado con 90 (de 100).'><sup>2<\/sup><\/a><\/span><\/span>.<\/li>\n\n\n\n<li>En 2017, Trump cre\u00f3 la Comisi\u00f3n de Lucha contra la Drogadicci\u00f3n y la Crisis de los Opioides y la Comisi\u00f3n Asesora Presidencial sobre Integridad Electoral. En abril de 2021, Biden cre\u00f3 una comisi\u00f3n para explorar formas de reformar el Tribunal Supremo.<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/a0UTk\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Aunque Trump podr\u00eda conseguir que el Congreso aprobara la creaci\u00f3n del DOGE, la probabilidad de que Vivek Ramaswamy y Elon Musk sean aprobados por el Senado para dirigirlo es muy escasa.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>El nombramiento de los dos empresarios presentar\u00eda importantes conflictos de intereses debido a sus carteras de acciones.<\/li>\n\n\n\n<li>Musk tambi\u00e9n participa en contratos gubernamentales a trav\u00e9s de su empresa SpaceX. Su empresa de veh\u00edculos el\u00e9ctricos, Tesla, se beneficia de importantes incentivos fiscales del Gobierno federal.<\/li>\n\n\n\n<li>Sin embargo, podr\u00eda negociar con la Oficina de \u00c9tica Gubernamental (OGE) para eliminar temporalmente estos conflictos de intereses.<\/li>\n<\/ul>\n\n\n\n<p>Seg\u00fan las leyes actualmente en vigor, la OGE no podr\u00e1 introducir cambios en la forma en que el Gobierno gasta y gestiona los cr\u00e9ditos concedidos por el Congreso, que, seg\u00fan declaraciones y comunicados de prensa de la campa\u00f1a de Trump, es su \u00fanica raz\u00f3n de ser. Sin embargo, para garantizar a la comisi\u00f3n un cierto grado de libertad de maniobra, el Presidente electo podr\u00eda tratar de derogar ciertas disposiciones de la Ley de Control del Presupuesto y de los Embargos del Congreso de 1974&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-49015' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2024\/11\/15\/que-puede-hacer-el-doge-de-musk-y-ramaswamy-como-trump-quiere-reforzar-su-poder-ejecutivo-y-debilitar-el-papel-del-congreso\/#easy-footnote-bottom-3-49015' title='Jeff Stein, Elizabeth Dwoskin, Cat Zakrzewski y Jacob Bogage, \u00ab\u00a0&lt;a href=&quot;https:\/\/www.washingtonpost.com\/business\/2024\/11\/13\/elon-musk-government-efficiency-congress-budget-law\/&quot;&gt;Trump aides explore plans to boost Musk effort by wresting control from Congress&lt;\/a&gt;\u00a0\u00bb,\u00a0&lt;em&gt;The Washington Post&lt;\/em&gt;, 13 de noviembre de 2024.'><sup>3<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/BSPE1\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Esta ley federal refuerza el papel del Congreso en el proceso de gasto de los fondos asignados en la legislaci\u00f3n y establece procedimientos para impedir que el Presidente bloquee o retrase la asignaci\u00f3n de fondos.<\/li>\n\n\n\n<li>Se promulg\u00f3 tras la negativa de Richard Nixon a liberar fondos asignados por el Congreso para determinados programas a los que se opon\u00eda, algo que Trump tambi\u00e9n podr\u00eda verse tentado a hacer a su regreso a la Casa Blanca.<\/li>\n<\/ul>\n\n\n\n<p>En la p\u00e1gina web de su campa\u00f1a, Trump declar\u00f3 p\u00fablicamente que tomar\u00eda medidas \u00abpara impugnar la constitucionalidad de los l\u00edmites al poder de incautaci\u00f3n impuestos por la Ley de Presupuesto del Congreso y Control de Embargos de 1974 (CBA), que est\u00e1 en el origen de la usurpaci\u00f3n de poderes ejecutivos por parte del Congreso\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-4-49015' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2024\/11\/15\/que-puede-hacer-el-doge-de-musk-y-ramaswamy-como-trump-quiere-reforzar-su-poder-ejecutivo-y-debilitar-el-papel-del-congreso\/#easy-footnote-bottom-4-49015' title='&lt;a href=&quot;https:\/\/www.donaldjtrump.com\/agenda47\/agenda47-using-impoundment-to-cut-waste-stop-inflation-and-crush-the-deep-state&quot;&gt;Agenda47\u00a0: Using Impoundment to Cut Waste, Stop Inflation, and Crush the Deep State&lt;\/a&gt;, 20 de junio de 2023.'><sup>4<\/sup><\/a><\/span><\/span>. Durante su campa\u00f1a para las primarias republicanas, Ramaswamy tambi\u00e9n hab\u00eda declarado que \u00abpedir\u00eda al Congreso que derogara o modificara la ley de 1974 y dejara de financiar organismos que despilfarran dinero o ya no sirven para nada\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-5-49015' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2024\/11\/15\/que-puede-hacer-el-doge-de-musk-y-ramaswamy-como-trump-quiere-reforzar-su-poder-ejecutivo-y-debilitar-el-papel-del-congreso\/#easy-footnote-bottom-5-49015' title='Vivek Ramaswamy, \u00ab\u00a0&lt;a href=&quot;https:\/\/www.wsj.com\/articles\/why-im-running-for-president-c4a8ea7&quot;&gt;Why I\u2019m Running for President&lt;\/a&gt;\u00a0\u00bb,\u00a0&lt;em&gt;The Wall Street Journal&lt;\/em&gt;, 21 de febrero de 2023.'><sup>5<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium \">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/flo.uri.sh\/visualisation\/20295162\/embed\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>A pesar de <a href=\"https:\/\/legrandcontinent.eu\/es\/2024\/11\/12\/trump-obtiene-una-comoda-mayoria-de-53-escanos-en-el-senado\/\">una c\u00f3moda mayor\u00eda republicana en el Senado<\/a> y una estrecha mayor\u00eda en la C\u00e1mara de Representantes, Trump teme enfrentarse a la oposici\u00f3n de algunos legisladores en su segundo mandato.<\/li>\n\n\n\n<li>En el Senado, \u00e9sta podr\u00eda venir de republicanos moderados \u2014como Susan Collins, Lisa Murkowski e incluso John Curtis\u2014 y esc\u00e9pticos, como el senador por Indiana Todd Young y el l\u00edder saliente del GOP, Mitch McConnell.<\/li>\n<\/ul>\n\n\n\n<p>Reforzar el poder ejecutivo es un objetivo que Trump se ha marcado y que cuenta con un amplio apoyo de su entorno. Tras su victoria en las elecciones presidenciales, el presidente del think-tank conservador Center for Renewing America, exdirector de la Oficina de Gesti\u00f3n y Presupuesto (OMB) de Trump y tambi\u00e9n <a href=\"https:\/\/legrandcontinent.eu\/es\/2023\/12\/05\/proyecto-2025-como-trump-quiere-deconstruir-el-estado-federal\/\">coautor del Proyecto 2025<\/a>, Russell Vought, declar\u00f3 que \u00abnosotros [los aliados de Trump] debemos armar al presidente con todos los poderes constitucionales a su disposici\u00f3n\u00bb \u2014incluyendo \u00abrestaurar la autoridad del presidente para retener fondos innecesarios del Congreso\u00bb\u2014&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-6-49015' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2024\/11\/15\/que-puede-hacer-el-doge-de-musk-y-ramaswamy-como-trump-quiere-reforzar-su-poder-ejecutivo-y-debilitar-el-papel-del-congreso\/#easy-footnote-bottom-6-49015' title='&lt;a href=&quot;https:\/\/mailchi.mp\/citizensrenewingamerica.com\/were-on-the-offensive-10707360&quot;&gt;Newsletter du Center for Renewing America sign\u00e9e par Russell Vought&lt;\/a&gt;, 6 de noviembre de 2024.'><sup>6<\/sup><\/a><\/span><\/span>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Donald Trump ha anunciado que nombrar\u00e1 a Elon Musk y Vivek Ramaswamy para dirigir un Departamento de Eficiencia Gubernamental (DOGE, en referencia al famoso meme adaptado posteriormente a criptomoneda) una vez que tome posesi\u00f3n en enero. Para dotar a esta comisi\u00f3n de un papel concreto, el equipo del candidato electo est\u00e1 explorando v\u00edas para reforzar el papel del Presidente en la gesti\u00f3n y asignaci\u00f3n de los fondos votados por el Congreso.<\/p>\n","protected":false},"author":1366,"featured_media":49016,"comment_status":"closed","ping_status":"","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":true,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":4,"footnotes":""},"categories":[6],"tags":[],"staff":[],"editorial_format":[1472],"serie":[],"audience":[],"geo":[172],"class_list":["post-49015","post","type-post","status-publish","format-standard","hentry","category-politica","editorial_format-analisis","geo-americas"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":49016,"excerpt":"Donald Trump ha anunciado que nombrar\u00e1 a Elon Musk y Vivek Ramaswamy para dirigir un Departamento de Eficiencia Gubernamental (DOGE, en referencia al famoso meme adaptado posteriormente a criptomoneda) una vez que tome posesi\u00f3n en enero. Para dotar a esta comisi\u00f3n de un papel concreto, el equipo del candidato electo est\u00e1 explorando v\u00edas para reforzar el papel del Presidente en la gesti\u00f3n y asignaci\u00f3n de los fondos votados por el Congreso.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfQu\u00e9 podr\u00e1 hacer el DOGE de Musk y Ramaswamy? C\u00f3mo Trump quiere reforzar su poder ejecutivo y debilitar el papel del Congreso - El Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/es\/2024\/11\/15\/que-puede-hacer-el-doge-de-musk-y-ramaswamy-como-trump-quiere-reforzar-su-poder-ejecutivo-y-debilitar-el-papel-del-congreso\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 podr\u00e1 hacer el DOGE de Musk y Ramaswamy? C\u00f3mo Trump quiere reforzar su poder ejecutivo y debilitar el papel del Congreso - El Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Donald Trump ha anunciado que nombrar\u00e1 a Elon Musk y Vivek Ramaswamy para dirigir un Departamento de Eficiencia Gubernamental (DOGE, en referencia al famoso meme adaptado posteriormente a criptomoneda) una vez que tome posesi\u00f3n en enero. Para dotar a esta comisi\u00f3n de un papel concreto, el equipo del candidato electo est\u00e1 explorando v\u00edas para reforzar el papel del Presidente en la gesti\u00f3n y asignaci\u00f3n de los fondos votados por el Congreso.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/es\/2024\/11\/15\/que-puede-hacer-el-doge-de-musk-y-ramaswamy-como-trump-quiere-reforzar-su-poder-ejecutivo-y-debilitar-el-papel-del-congreso\/\" \/>\n<meta property=\"og:site_name\" content=\"El Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-15T12:04:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-26T18:13:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/11\/a0UTk-evoluci-n-del-precio-de-dogecoin-diciembre-2023-noviembre-2024-.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1540\" \/>\n\t<meta property=\"og:image:height\" content=\"1306\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"florent\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"florent\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/11\/15\/que-puede-hacer-el-doge-de-musk-y-ramaswamy-como-trump-quiere-reforzar-su-poder-ejecutivo-y-debilitar-el-papel-del-congreso\/\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/2024\/11\/15\/que-puede-hacer-el-doge-de-musk-y-ramaswamy-como-trump-quiere-reforzar-su-poder-ejecutivo-y-debilitar-el-papel-del-congreso\/\",\"name\":\"\u00bfQu\u00e9 podr\u00e1 hacer el DOGE de Musk y Ramaswamy? C\u00f3mo Trump quiere reforzar su poder ejecutivo y debilitar el papel del Congreso - El Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/11\/15\/que-puede-hacer-el-doge-de-musk-y-ramaswamy-como-trump-quiere-reforzar-su-poder-ejecutivo-y-debilitar-el-papel-del-congreso\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/11\/15\/que-puede-hacer-el-doge-de-musk-y-ramaswamy-como-trump-quiere-reforzar-su-poder-ejecutivo-y-debilitar-el-papel-del-congreso\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/11\/a0UTk-evoluci-n-del-precio-de-dogecoin-diciembre-2023-noviembre-2024-.png\",\"datePublished\":\"2024-11-15T12:04:00+00:00\",\"dateModified\":\"2024-11-26T18:13:16+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/11\/15\/que-puede-hacer-el-doge-de-musk-y-ramaswamy-como-trump-quiere-reforzar-su-poder-ejecutivo-y-debilitar-el-papel-del-congreso\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/es\/2024\/11\/15\/que-puede-hacer-el-doge-de-musk-y-ramaswamy-como-trump-quiere-reforzar-su-poder-ejecutivo-y-debilitar-el-papel-del-congreso\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/11\/15\/que-puede-hacer-el-doge-de-musk-y-ramaswamy-como-trump-quiere-reforzar-su-poder-ejecutivo-y-debilitar-el-papel-del-congreso\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/11\/a0UTk-evoluci-n-del-precio-de-dogecoin-diciembre-2023-noviembre-2024-.png\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/11\/a0UTk-evoluci-n-del-precio-de-dogecoin-diciembre-2023-noviembre-2024-.png\",\"width\":1540,\"height\":1306},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/11\/15\/que-puede-hacer-el-doge-de-musk-y-ramaswamy-como-trump-quiere-reforzar-su-poder-ejecutivo-y-debilitar-el-papel-del-congreso\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/legrandcontinent.eu\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQu\u00e9 podr\u00e1 hacer el DOGE de Musk y Ramaswamy? C\u00f3mo Trump quiere reforzar su poder ejecutivo y debilitar el papel del Congreso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/\",\"name\":\"El Grand Continent\",\"description\":\"La escala pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\",\"name\":\"florent\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"caption\":\"florent\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 podr\u00e1 hacer el DOGE de Musk y Ramaswamy? C\u00f3mo Trump quiere reforzar su poder ejecutivo y debilitar el papel del Congreso - El Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/es\/2024\/11\/15\/que-puede-hacer-el-doge-de-musk-y-ramaswamy-como-trump-quiere-reforzar-su-poder-ejecutivo-y-debilitar-el-papel-del-congreso\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQu\u00e9 podr\u00e1 hacer el DOGE de Musk y Ramaswamy? C\u00f3mo Trump quiere reforzar su poder ejecutivo y debilitar el papel del Congreso - El Grand Continent","og_description":"Donald Trump ha anunciado que nombrar\u00e1 a Elon Musk y Vivek Ramaswamy para dirigir un Departamento de Eficiencia Gubernamental (DOGE, en referencia al famoso meme adaptado posteriormente a criptomoneda) una vez que tome posesi\u00f3n en enero. Para dotar a esta comisi\u00f3n de un papel concreto, el equipo del candidato electo est\u00e1 explorando v\u00edas para reforzar el papel del Presidente en la gesti\u00f3n y asignaci\u00f3n de los fondos votados por el Congreso.","og_url":"https:\/\/legrandcontinent.eu\/es\/2024\/11\/15\/que-puede-hacer-el-doge-de-musk-y-ramaswamy-como-trump-quiere-reforzar-su-poder-ejecutivo-y-debilitar-el-papel-del-congreso\/","og_site_name":"El Grand Continent","article_published_time":"2024-11-15T12:04:00+00:00","article_modified_time":"2024-11-26T18:13:16+00:00","og_image":[{"width":1540,"height":1306,"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/11\/a0UTk-evoluci-n-del-precio-de-dogecoin-diciembre-2023-noviembre-2024-.png","type":"image\/png"}],"author":"florent","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"florent","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/es\/2024\/11\/15\/que-puede-hacer-el-doge-de-musk-y-ramaswamy-como-trump-quiere-reforzar-su-poder-ejecutivo-y-debilitar-el-papel-del-congreso\/","url":"https:\/\/legrandcontinent.eu\/es\/2024\/11\/15\/que-puede-hacer-el-doge-de-musk-y-ramaswamy-como-trump-quiere-reforzar-su-poder-ejecutivo-y-debilitar-el-papel-del-congreso\/","name":"\u00bfQu\u00e9 podr\u00e1 hacer el DOGE de Musk y Ramaswamy? C\u00f3mo Trump quiere reforzar su poder ejecutivo y debilitar el papel del Congreso - El Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/es\/2024\/11\/15\/que-puede-hacer-el-doge-de-musk-y-ramaswamy-como-trump-quiere-reforzar-su-poder-ejecutivo-y-debilitar-el-papel-del-congreso\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/es\/2024\/11\/15\/que-puede-hacer-el-doge-de-musk-y-ramaswamy-como-trump-quiere-reforzar-su-poder-ejecutivo-y-debilitar-el-papel-del-congreso\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/11\/a0UTk-evoluci-n-del-precio-de-dogecoin-diciembre-2023-noviembre-2024-.png","datePublished":"2024-11-15T12:04:00+00:00","dateModified":"2024-11-26T18:13:16+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/es\/2024\/11\/15\/que-puede-hacer-el-doge-de-musk-y-ramaswamy-como-trump-quiere-reforzar-su-poder-ejecutivo-y-debilitar-el-papel-del-congreso\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/es\/2024\/11\/15\/que-puede-hacer-el-doge-de-musk-y-ramaswamy-como-trump-quiere-reforzar-su-poder-ejecutivo-y-debilitar-el-papel-del-congreso\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/2024\/11\/15\/que-puede-hacer-el-doge-de-musk-y-ramaswamy-como-trump-quiere-reforzar-su-poder-ejecutivo-y-debilitar-el-papel-del-congreso\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/11\/a0UTk-evoluci-n-del-precio-de-dogecoin-diciembre-2023-noviembre-2024-.png","contentUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/11\/a0UTk-evoluci-n-del-precio-de-dogecoin-diciembre-2023-noviembre-2024-.png","width":1540,"height":1306},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/es\/2024\/11\/15\/que-puede-hacer-el-doge-de-musk-y-ramaswamy-como-trump-quiere-reforzar-su-poder-ejecutivo-y-debilitar-el-papel-del-congreso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legrandcontinent.eu\/es\/"},{"@type":"ListItem","position":2,"name":"\u00bfQu\u00e9 podr\u00e1 hacer el DOGE de Musk y Ramaswamy? C\u00f3mo Trump quiere reforzar su poder ejecutivo y debilitar el papel del Congreso"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/es\/#website","url":"https:\/\/legrandcontinent.eu\/es\/","name":"El Grand Continent","description":"La escala pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c","name":"florent","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","caption":"florent"}}]}},"lgc_categories":[{"id":6,"name":"Pol\u00edtica","slug":"politica"}],"lgc_author":null,"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/11\/a0UTk-evoluci-n-del-precio-de-dogecoin-diciembre-2023-noviembre-2024-.png","width":1540,"height":1306,"alt":""},"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/49015","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/users\/1366"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/comments?post=49015"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/49015\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media\/49016"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media?parent=49015"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/categories?post=49015"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/tags?post=49015"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/staff?post=49015"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/editorial_format?post=49015"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/serie?post=49015"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/audience?post=49015"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/geo?post=49015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}