{"id":48809,"date":"2024-11-09T11:55:21","date_gmt":"2024-11-09T10:55:21","guid":{"rendered":"https:\/\/legrandcontinent.eu\/es\/?p=48809"},"modified":"2024-11-09T11:55:23","modified_gmt":"2024-11-09T10:55:23","slug":"el-verdadero-manifiesto-del-movimiento-trumpista","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/es\/2024\/11\/09\/el-verdadero-manifiesto-del-movimiento-trumpista\/","title":{"rendered":"El verdadero manifiesto del movimiento trumpista"},"content":{"rendered":"\n<p class=\"intro\">Hace poco m\u00e1s de un a\u00f1o, el 8 de agosto de 2023, Oliver Anthony public\u00f3 en su canal de YouTube el video de una canci\u00f3n original titulada <em>Rich Men North of Richmond<\/em>. De pie en un bosque, rodeado de sus perros, este antiguo trabajador temporal \u2014que acababa de mudarse unos meses antes con su familia a una parcela de 36 hect\u00e1reas para criar ganado\u2014 era el portavoz de un Estados Unidos oprimido, condenado a trabajar muchas horas por un salario que apenas le alcanzaba para sobrevivir. En aquel momento, la inflaci\u00f3n estaba en su nivel m\u00e1s bajo de los \u00faltimos dos a\u00f1os y medio, pero millones de estadounidenses segu\u00edan sufriendo los efectos de la fuerte subida de los precios en 2021 y 2022.<\/p>\n\n\n\n<p class=\"intro\"><em>Rich Men North of Richmond <\/em>fue un \u00e9xito inmediato. La m\u00fasica, que se reprodujo cientos de millones de veces, impulsando a Oliver al n\u00famero uno de la lista Billboard Hot 100, reson\u00f3 especialmente entre la clase trabajadora estadounidense. Los temas de las letras, el perfil de Oliver Anthony \u2014un completo desconocido hasta entonces\u2014, la coyuntura econ\u00f3mica y las crecientes dificultades de decenas de millones de estadounidenses para llegar a fin de mes han convertido esta m\u00fasica en el himno de todo un movimiento. Ahora que Donald Trump acaba de ser elegido presidente para un segundo mandato, <em>Rich Men North of Richmond<\/em> vuelve a escucharse en streaming y resurge entre los votantes republicanos.<\/p>\n\n\n\n<p class=\"intro\">En gran parte olvidada por la mayor\u00eda de los votantes durante una campa\u00f1a trastocada por el intento de asesinato de Trump y la retirada tard\u00eda de Biden, <em>Rich Men North of<\/em> <em>Richmond <\/em>resurgi\u00f3 en octubre en un <em>town hall <\/em>del entonces candidato republicano en Oaks, Pensilvania. Dos personas acababan de desmayarse entre el p\u00fablico debido al calor, y Trump se qued\u00f3 en el escenario tras sugerir que se cambiara la tradicional sesi\u00f3n de preguntas y respuestas por una de sus actividades favoritas: o\u00edr m\u00fasica. Durante 39 minutos, Trump se balance\u00f3 en silencio al ritmo de sus canciones favoritas. Al mismo tiempo, los param\u00e9dicos intervinieron en la sala para evacuar a las dos personas que se hab\u00edan desmayado.<\/p>\n\n\n\n<p class=\"intro\"><em>Rich Men North of Richmond <\/em>ocup\u00f3 un lugar destacado en la lista de reproducci\u00f3n del republicano, intercalada entre <em>An American Trilogy<\/em>, de Elvis Presley, y <em>November Rain<\/em>, de Gun N&#8217; Roses, al son de la cual Trump decidi\u00f3 finalmente abandonar el escenario. La m\u00fasica de Oliver Anthony fue tambi\u00e9n el \u00fanico tema contempor\u00e1neo, la \u00fanica canci\u00f3n cuya letra iba unida a un significado eminentemente pol\u00edtico a s\u00f3lo 22 d\u00edas de las elecciones. Tras su victoria en las urnas, es muy probable que <em>Rich Men North of Richmond <\/em>sea a\u00f1adida por Trump a la lista de canciones que reserva para sus invitados en las recepciones de Mar-a-Lago, Florida, o en su club de golf de Bedminster, Nueva Jersey.<\/p>\n\n\n\n<p class=\"intro\">Aunque la letra de Anthony no es aplicable a Trump \u2014que recibi\u00f3 de su padre el equivalente a unos 400 millones de d\u00f3lares al comienzo de su carrera\u2014, se ha convertido en el himno de gran parte de su electorado. En su mayor\u00eda blancos \u2014aunque Trump ha mejorado notablemente su puntuaci\u00f3n entre los votantes hispanos y afroamericanos\u2014 que viven en zonas rurales, desindustrializadas y alejadas de los centros econ\u00f3micos que son el verdadero pulm\u00f3n de Estados Unidos, los votantes de Trump eligieron al candidato republicano no porque pueda presumir de ser \u00abuno de ellos\u00bb, sino porque se han dejado seducir por su ret\u00f3rica de ruptura. El Estados Unidos de Oliver es tambi\u00e9n el Estados Unidos de Vance, el primero de la generaci\u00f3n <em>millennial<\/em> en ser elegido vicepresidente. En <em>Hillbilly Elegy<\/em>, Vance retrat\u00f3 a una sociedad olvidada, desatendida por las \u00e9lites de Washington, dem\u00f3cratas y republicanos por igual. Inicialmente opuesto a Trump, Vance, por su parte de extracci\u00f3n popular, se ha rendido desde entonces al candidato republicano, reconociendo su capacidad casi m\u00edstica para hablar a un Estados Unidos que descubri\u00f3 por primera vez en 2015, a sus casi 70 a\u00f1os.<\/p>\n\n\n\n<p class=\"intro\">Al \u00absalario sin valor\u00bb denunciado por Anthony, Trump promete un retorno a la prosperidad econ\u00f3mica de los a\u00f1os cincuenta y sesenta. Frente a esa clase que \u00abquiere controlarnos a todos\u00bb, anuncia su intenci\u00f3n de desmantelar el Estado federal y \u00abdrenar el pantano\u00bb de Washington y sus \u00e9lites corruptas. Frente a los \u00abimpuestos hasta el final\u00bb de los dem\u00f3cratas, el presidente electo promete aplicar \u00abimportantes recortes fiscales para los trabajadores\u00bb y acabar con los impuestos sobre las propinas. Por \u00faltimo, mientras Anthony se ve obligado a \u00abvivir en un mundo nuevo con el alma antigua\u00bb, Trump promete una vuelta a los valores tradicionalistas y el fin del \u00abwokismo\u00bb propugnado por los dem\u00f3cratas.<\/p>\n\n\n\n<p>Vendo mi alma; trabajo todo el d\u00eda;<\/p>\n\n\n\n<p>Horas extra por un sueldo sin valor,<\/p>\n\n\n\n<p>Para sentarme ah\u00ed, a perder el tiempo,<\/p>\n\n\n\n<p>Y llegar a casa para ahogar todos mis tormentos.<\/p>\n\n\n\n<p class=\"comment\">La m\u00fasica\u00a0<em>country<\/em>\u00a0suele presentar a personajes de clases trabajadoras, ya sea en primera o tercera persona. En una publicaci\u00f3n de Facebook del cantante, la informaci\u00f3n filtrada sobre su vida reforz\u00f3 la sensaci\u00f3n de que se trataba de una canci\u00f3n autobiogr\u00e1fica. Tras dejar la escuela en 2010, a los 17 a\u00f1os, Anthony obtuvo un diploma de bachillerato (GED). Trabaj\u00f3 en el sector industrial en Carolina del Norte y Virginia. En 2013, sufri\u00f3 un accidente laboral, en una f\u00e1brica de papel de Carolina del Norte, que le fractur\u00f3 el cr\u00e1neo y lo dej\u00f3 incapacitado para trabajar durante seis meses. Desde 2014 hasta 2023, trabaj\u00f3 en ventas externas en el sector manufacturero visitando f\u00e1bricas y obras de construcci\u00f3n. Durante este tiempo, sufri\u00f3 varios periodos de alcoholismo. En 2023, se instal\u00f3 con su mujer y sus dos hijos en varias hect\u00e1reas de terreno para criar ganado.\u00a0<\/p>\n\n\n\n<p>Es una pena que el mundo haya llegado a esto,<\/p>\n\n\n\n<p>Para gente como t\u00fa, para gente como yo.<\/p>\n\n\n\n<p>Si tan s\u00f3lo pudiera despertar y ver que no es cierto,<\/p>\n\n\n\n<p>Pero lo es, oh, s\u00ed, lo es.<\/p>\n\n\n\n<p>Vivir en un mundo nuevo<\/p>\n\n\n\n<p>Con un alma antigua:<\/p>\n\n\n\n<p>Los ricos al norte de Richmond.<\/p>\n\n\n\n<p class=\"comment\">La referencia a Richmond no es al azar. Durante la Guerra Civil (1861-1865), Richmond fue la capital de la Confederaci\u00f3n. Si el mensaje de Oliver Anthony va dirigido a las \u00e9lites adineradas que no se preocupan por los verdaderos americanos, es sintom\u00e1tico que se encuentren \u00abal norte\u00bb de la capital confederada. Aunque canta con un marcado acento sure\u00f1o, est\u00e1 claro que juega con un intertexto hist\u00f3rico muy cargado. En t\u00e9rminos m\u00e1s generales, la imagen de sencillez arraigada en la Am\u00e9rica rural y en la religi\u00f3n (cosa que retomaremos m\u00e1s adelante) que propone es una forma de reactivar el estereotipo de un Sur profundamente decente y cort\u00e9s (\u00ablos modales sure\u00f1os\u00bb han sido objeto de numerosas apropiaciones, desde la Guerra de Secesi\u00f3n hasta nuestros d\u00edas), totalmente opuesto a un Norte urbano, perturbador y violento. Cierto pensamiento paleoconservador ha hecho hincapi\u00e9 en el tradicionalismo sure\u00f1o \u2013o confederado\u2013 como forma de defender el localismo y los derechos de los Estados frente al desarrollo tir\u00e1nico del Estado federal tras la Guerra Civil.\u00a0<\/p>\n\n\n\n<p>Dios sabe que todos quieren controlarnos.<\/p>\n\n\n\n<p>Quieren saber lo que piensas, lo que haces&#8230;<\/p>\n\n\n\n<p>Creen que no lo sabes, pero yo s\u00e9 que s\u00ed.<\/p>\n\n\n\n<p>Tu d\u00f3lar no vale nada y te cobran impuestos hasta el cuello<\/p>\n\n\n\n<p>Por estos ricos al norte de Richmond.<\/p>\n\n\n\n<p class=\"comment\">Si el minarquismo \u2013la idea de una limitaci\u00f3n absoluta del Estado\u2013 est\u00e1 en el coraz\u00f3n del pensamiento libertario, tambi\u00e9n existe en la nebulosa paleoconservadora: en cualquier caso, los dos movimientos tienen varios puntos de convergencia. Uno de los temas m\u00e1s recurrentes en este discurso, destacado en la canci\u00f3n, es el de la opresi\u00f3n fiscal, decidida por personalidades distantes. A menudo, se presenta como una lucha, esencialmente, americana y lo ha sido desde la Guerra de Independencia: es bastante revelador que el movimiento populista insurrecto que transform\u00f3 el partido republicano a partir de 2009 se llamara\u00a0<em>Tea Party<\/em>.\u00a0<\/p>\n\n\n\n<p>Si los pol\u00edticos pensaran en los menores<\/p>\n\n\n\n<p>Y no en menores en una isla remota\u2026<\/p>\n\n\n\n<p>Se\u00f1or, hay gente en la calle que no tiene nada que comer<\/p>\n\n\n\n<p>Y los obesos que se atiborran de prestaciones sociales\u2026<\/p>\n\n\n\n<p class=\"comment\">Este fragmento ha sido el m\u00e1s debatido en Estados Unidos. Las dos primeras l\u00edneas juegan con una homonimia m\u00e1s clara en ingl\u00e9s:\u00a0<em>miner<\/em>\u00a0y\u00a0<em>minor<\/em>. Es una referencia muy expl\u00edcita al caso de Jeffrey Epstein, propietario de una isla privada en las Islas V\u00edrgenes americanas, donde abus\u00f3 sexualmente de numerosas adolescentes. La prolongada protecci\u00f3n concedida para el financiero, as\u00ed como su suicidio en prisi\u00f3n han alimentado un fuerte resentimiento contra las \u00e9lites, presentadas como criminales e intocables. Algunos comentaristas tambi\u00e9n han sugerido que Oliver Anthony se refer\u00eda, impl\u00edcitamente, a las teor\u00edas conspiracionistas de\u00a0<em>QAnon<\/em>, que explicaban que ciertos l\u00edderes dem\u00f3cratas secuestraban a ni\u00f1os para extraerles sangre.<\/p>\n\n\n\n<p>Dios, si mides 1.60 m y pesas 136 kilos,<\/p>\n\n\n\n<p>Los impuestos no deber\u00edan pagar tus bolsas de caramelos.<\/p>\n\n\n\n<p>Los j\u00f3venes se meten seis pies bajo tierra<\/p>\n\n\n\n<p>Porque este maldito pa\u00eds no deja de aplastarlos.<\/p>\n\n\n\n<p class=\"comment\">Aqu\u00ed, Oliver Anthony se refiere, posiblemente, a la epidemia de sobredosis de opi\u00e1ceos y de suicidios que afecta a Estados Unidos desde hace varias d\u00e9cadas. Sin embargo, la canci\u00f3n tambi\u00e9n critica el Estado de bienestar por convertir a los americanos en beneficiarios de ayudas sociales. Aqu\u00ed, encontramos un tema com\u00fan en todo el partido republicano: el dinero p\u00fablico gravar\u00eda injustamente la espalda de los trabajadores americanos y contribuir\u00eda a borrar el valor del trabajo.\u00a0<\/p>\n\n\n\n<p>Se\u00f1or, \u00a1qu\u00e9 verg\u00fcenza que el mundo haya llegado a esto!<\/p>\n\n\n\n<p>Para gente como t\u00fa, para gente como yo,<\/p>\n\n\n\n<p>Si tan s\u00f3lo pudiera despertar y ver que no es cierto,<\/p>\n\n\n\n<p>Pero lo es, oh, s\u00ed, lo es.<\/p>\n\n\n\n<p class=\"comment\">Esta referencia a Dios \u2013la segunda de la canci\u00f3n\u2013 tampoco es aleatoria. En su autobiograf\u00eda, Oliver Anthony explicaba que, hac\u00eda muy poco, hab\u00eda redescubierto su fe. Pocos d\u00edas despu\u00e9s de que \u00ab<em>Rich Men North of Richmond<\/em>\u00bb se hiciera viral, dio un concierto en un mercado cerca de su casa, ante un p\u00fablico mucho m\u00e1s numeroso de lo habitual. Para abrir el espect\u00e1culo, Oliver Anthony sac\u00f3 una Biblia y ley\u00f3 el salmo 37 (sobre la redenci\u00f3n de los pecados). Este regreso al cristianismo fue muy comentado en el \u00e1mbito conservador, que lo vio como una se\u00f1al m\u00e1s de que el cantante pod\u00eda encajar en su mundo.\u00a0<\/p>\n\n\n\n<p>Vivir en un mundo nuevo<\/p>\n\n\n\n<p>Con un alma antigua:<\/p>\n\n\n\n<p>Los ricos al norte de Richmond.<\/p>\n\n\n\n<p>Dios sabe que todos quieren controlarnos.<\/p>\n\n\n\n<p>Quieren saber lo que piensas, lo que haces&#8230;<\/p>\n\n\n\n<p>Creen que no lo sabes, pero yo s\u00e9 que s\u00ed.<\/p>\n\n\n\n<p>Tu d\u00f3lar no vale nada y te cobran impuestos hasta el cuello<\/p>\n\n\n\n<p>Por estos ricos al norte de Richmond.<\/p>\n\n\n\n<p class=\"comment\">Una vez m\u00e1s, este fragmento hace eco de las teor\u00edas libertarias y paleoconservadoras. A partir de la Guerra de Secesi\u00f3n y, m\u00e1s a\u00fan, despu\u00e9s de la Segunda Guerra Mundial, el Estado americano habr\u00eda abandonado los valores sobre los que se fund\u00f3 a favor del control y de la vigilancia de sus ciudadanos. Estas ideas fueron objeto del libro de Robert Nozick de 1974:\u00a0<em>Anarchy, State, and Utopia<\/em>. Con la afirmaci\u00f3n de estar influido por Locke, Kant y Hayek, defendi\u00f3 una visi\u00f3n de la reducci\u00f3n del Estado a\u00fan m\u00e1s radical que la de Hayek. Las \u00faltimas p\u00e1ginas del libro elogian a las comunidades que logran ser completamente aut\u00f3nomas de un Estado opresor. En su m\u00fasica, como en lo que describe de su vida, Oliver Anthony parece ser bastante cercano a esta aspiraci\u00f3n.\u00a0<\/p>\n\n\n\n<p>Vendo mi alma; trabajo todo el d\u00eda.<\/p>\n\n\n\n<p>Horas extras por un sueldo sin valor.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abVivir en un nuevo mundo\/Con un alma antigua\u00bb.<\/p>\n<p>El manifiesto del movimiento que acaba de llevar a Donald Trump a la Casa Blanca no es un art\u00edculo de peri\u00f3dico ni un gran discurso, sino una canci\u00f3n country \u2014 <em>Rich Men North of Richmond<\/em>\u2014 publicada en Youtube por un cantante casi an\u00f3nimo en aquel momento, Oliver Anthony, hace poco m\u00e1s de un a\u00f1o. Escuchada millones de veces, casi desconocida en Europa, re\u00fane todos los temas que estructuran la nueva coalici\u00f3n trumpista.<\/p>\n<p>Para comprender a Trump en 2024, hay que escucharla y leer entre l\u00edneas.<\/p>\n","protected":false},"author":1366,"featured_media":48770,"comment_status":"closed","ping_status":"","sticky":false,"template":"templates\/post-speeches.php","format":"standard","meta":{"_acf_changed":true,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":9,"_lgc_tts_audio_url":"","_lgc_tts_voice":"","_lgc_tts_publish":false,"_lgc_tts_history_item_id":"","_lgc_tts_generated_at":"","_lgc_tts_status":"","_lgc_tts_error":"","footnotes":""},"categories":[956],"tags":[],"staff":[57,192],"editorial_format":[1474],"serie":[],"audience":[],"geo":[172],"class_list":["post-48809","post","type-post","status-publish","format-standard","hentry","category-trump-fuentes-intelectuales-de-una-revolucion-cultural","staff-baptiste-roger-lacan","staff-marin-saillofest","editorial_format-archivos-y-discursos","geo-americas"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":48770,"excerpt":"\u00abVivir en un nuevo mundo\/Con un alma antigua\u00bb.\r\n\r\nEl manifiesto del movimiento que acaba de llevar a Donald Trump a la Casa Blanca no es un art\u00edculo de peri\u00f3dico ni un gran discurso, sino una canci\u00f3n country \u2014 <em>Rich Men North of Richmond<\/em>\u2014 publicada en Youtube por un cantante casi an\u00f3nimo en aquel momento, Oliver Anthony, hace poco m\u00e1s de un a\u00f1o. Escuchada millones de veces, casi desconocida en Europa, re\u00fane todos los temas que estructuran la nueva coalici\u00f3n trumpista.\r\n\r\nPara comprender a Trump en 2024, hay que escucharla y leer entre l\u00edneas.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El verdadero manifiesto del movimiento trumpista - El Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/es\/2024\/11\/09\/el-verdadero-manifiesto-del-movimiento-trumpista\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El verdadero manifiesto del movimiento trumpista - El Grand Continent\" \/>\n<meta property=\"og:description\" content=\"\u00abVivir en un nuevo mundo\/Con un alma antigua\u00bb.  El manifiesto del movimiento que acaba de llevar a Donald Trump a la Casa Blanca no es un art\u00edculo de peri\u00f3dico ni un gran discurso, sino una canci\u00f3n country \u2014 Rich Men North of Richmond\u2014 publicada en Youtube por un cantante casi an\u00f3nimo en aquel momento, Oliver Anthony, hace poco m\u00e1s de un a\u00f1o. Escuchada millones de veces, casi desconocida en Europa, re\u00fane todos los temas que estructuran la nueva coalici\u00f3n trumpista.  Para comprender a Trump en 2024, hay que escucharla y leer entre l\u00edneas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/es\/2024\/11\/09\/el-verdadero-manifiesto-del-movimiento-trumpista\/\" \/>\n<meta property=\"og:site_name\" content=\"El Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-09T10:55:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-09T10:55:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/11\/gc-elanthony-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"florent\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/11\/gc-elanthony-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"florent\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/11\/09\/el-verdadero-manifiesto-del-movimiento-trumpista\/\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/2024\/11\/09\/el-verdadero-manifiesto-del-movimiento-trumpista\/\",\"name\":\"El verdadero manifiesto del movimiento trumpista - El Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/11\/09\/el-verdadero-manifiesto-del-movimiento-trumpista\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/11\/09\/el-verdadero-manifiesto-del-movimiento-trumpista\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/11\/oliver-anthony-press-credit-Draven-Riffe-2023-billboard-1548.jpg\",\"datePublished\":\"2024-11-09T10:55:21+00:00\",\"dateModified\":\"2024-11-09T10:55:23+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/11\/09\/el-verdadero-manifiesto-del-movimiento-trumpista\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/es\/2024\/11\/09\/el-verdadero-manifiesto-del-movimiento-trumpista\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/11\/09\/el-verdadero-manifiesto-del-movimiento-trumpista\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/11\/oliver-anthony-press-credit-Draven-Riffe-2023-billboard-1548.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/11\/oliver-anthony-press-credit-Draven-Riffe-2023-billboard-1548.jpg\",\"width\":1548,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/11\/09\/el-verdadero-manifiesto-del-movimiento-trumpista\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/legrandcontinent.eu\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El verdadero manifiesto del movimiento trumpista\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/\",\"name\":\"El Grand Continent\",\"description\":\"La escala pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\",\"name\":\"florent\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"caption\":\"florent\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El verdadero manifiesto del movimiento trumpista - El Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/es\/2024\/11\/09\/el-verdadero-manifiesto-del-movimiento-trumpista\/","og_locale":"es_ES","og_type":"article","og_title":"El verdadero manifiesto del movimiento trumpista - El Grand Continent","og_description":"\u00abVivir en un nuevo mundo\/Con un alma antigua\u00bb.  El manifiesto del movimiento que acaba de llevar a Donald Trump a la Casa Blanca no es un art\u00edculo de peri\u00f3dico ni un gran discurso, sino una canci\u00f3n country \u2014 Rich Men North of Richmond\u2014 publicada en Youtube por un cantante casi an\u00f3nimo en aquel momento, Oliver Anthony, hace poco m\u00e1s de un a\u00f1o. Escuchada millones de veces, casi desconocida en Europa, re\u00fane todos los temas que estructuran la nueva coalici\u00f3n trumpista.  Para comprender a Trump en 2024, hay que escucharla y leer entre l\u00edneas.","og_url":"https:\/\/legrandcontinent.eu\/es\/2024\/11\/09\/el-verdadero-manifiesto-del-movimiento-trumpista\/","og_site_name":"El Grand Continent","article_published_time":"2024-11-09T10:55:21+00:00","article_modified_time":"2024-11-09T10:55:23+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/11\/gc-elanthony-scaled.jpg","type":"image\/jpeg"}],"author":"florent","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/11\/gc-elanthony-scaled.jpg","twitter_misc":{"Escrito por":"florent","Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/es\/2024\/11\/09\/el-verdadero-manifiesto-del-movimiento-trumpista\/","url":"https:\/\/legrandcontinent.eu\/es\/2024\/11\/09\/el-verdadero-manifiesto-del-movimiento-trumpista\/","name":"El verdadero manifiesto del movimiento trumpista - El Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/es\/2024\/11\/09\/el-verdadero-manifiesto-del-movimiento-trumpista\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/es\/2024\/11\/09\/el-verdadero-manifiesto-del-movimiento-trumpista\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/11\/oliver-anthony-press-credit-Draven-Riffe-2023-billboard-1548.jpg","datePublished":"2024-11-09T10:55:21+00:00","dateModified":"2024-11-09T10:55:23+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/es\/2024\/11\/09\/el-verdadero-manifiesto-del-movimiento-trumpista\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/es\/2024\/11\/09\/el-verdadero-manifiesto-del-movimiento-trumpista\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/2024\/11\/09\/el-verdadero-manifiesto-del-movimiento-trumpista\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/11\/oliver-anthony-press-credit-Draven-Riffe-2023-billboard-1548.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/11\/oliver-anthony-press-credit-Draven-Riffe-2023-billboard-1548.jpg","width":1548,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/es\/2024\/11\/09\/el-verdadero-manifiesto-del-movimiento-trumpista\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legrandcontinent.eu\/es\/"},{"@type":"ListItem","position":2,"name":"El verdadero manifiesto del movimiento trumpista"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/es\/#website","url":"https:\/\/legrandcontinent.eu\/es\/","name":"El Grand Continent","description":"La escala pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c","name":"florent","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","caption":"florent"}}]}},"lgc_categories":[{"id":956,"name":"Trump: fuentes intelectuales de una revoluci\u00f3n cultural","slug":"trump-fuentes-intelectuales-de-una-revolucion-cultural"}],"lgc_author":{"id":57,"name":"Baptiste Roger-Lacan","slug":"baptiste-roger-lacan","description":null,"first_name":null,"last_name":null,"picture":null},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/11\/oliver-anthony-press-credit-Draven-Riffe-2023-billboard-1548.jpg","width":1548,"height":1024,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/11\/oliver-anthony-press-credit-Draven-Riffe-2023-billboard-1548.jpg","width":1548,"height":1024,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/48809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/users\/1366"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/comments?post=48809"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/48809\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media\/48770"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media?parent=48809"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/categories?post=48809"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/tags?post=48809"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/staff?post=48809"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/editorial_format?post=48809"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/serie?post=48809"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/audience?post=48809"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/geo?post=48809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}