{"id":47465,"date":"2024-10-23T10:00:00","date_gmt":"2024-10-23T08:00:00","guid":{"rendered":"https:\/\/legrandcontinent.eu\/es\/?p=47465"},"modified":"2024-10-23T13:08:10","modified_gmt":"2024-10-23T11:08:10","slug":"a-menos-de-dos-semanas-de-las-elecciones-cuales-son-las-estrategias-de-trump-y-harris","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/es\/2024\/10\/23\/a-menos-de-dos-semanas-de-las-elecciones-cuales-son-las-estrategias-de-trump-y-harris\/","title":{"rendered":"A menos de dos semanas de las elecciones: \u00bfcu\u00e1les son las estrategias de Trump y Harris?"},"content":{"rendered":"\n<p>Kamala Harris participa hoy en un <em>town hall<\/em> del condado de Delaware, en Pensilvania (un suburbio del suroeste de Filadelfia). La candidata dem\u00f3crata, cuyo bando est\u00e1 preocupado por el ligero ascenso de Trump en las encuestas, ha empezado a cambiar su estrategia de campa\u00f1a en los \u00faltimos d\u00edas para dirigirse a los votantes republicanos, sobre todo a los hombres&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-47465' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2024\/10\/23\/a-menos-de-dos-semanas-de-las-elecciones-cuales-son-las-estrategias-de-trump-y-harris\/#easy-footnote-bottom-1-47465' title='Jeff Mason y Nandita Bose, \u00ab\u00a0&lt;a href=&quot;https:\/\/www.reuters.com\/world\/us\/harris-campaign-shifts-strategy-anxiety-rises-over-trump-gains-2024-10-17\/&quot;&gt;Harris campaign shifts strategy as anxiety rises over Trump gains&lt;\/a&gt;\u00a0\u00bb,\u00a0&lt;em&gt;Reuters&lt;\/em&gt;, 17 de octubre de 2024.'><sup>1<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Aunque Trump se neg\u00f3 a participar en un segundo debate televisado contra Harris, previsto inicialmente para el 23 de octubre, la campa\u00f1a republicana no es menos activa.<\/li>\n\n\n\n<li>Hasta el 16 de octubre, Trump hab\u00eda aparecido 28 veces en televisi\u00f3n, frente a las 12 de Harris \u2014que, sin embargo, fue nominada tres semanas despu\u00e9s\u2014.<\/li>\n\n\n\n<li>En total, el candidato republicano est\u00e1 2,3 veces m\u00e1s presente en los medios (59 apariciones entre su nominaci\u00f3n republicana y el 16 de octubre) que su oponente dem\u00f3crata (26 apariciones).<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/TpPmg\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>La campa\u00f1a dem\u00f3crata, que ha dado a su candidata la mitad de presencia en los medios de comunicaci\u00f3n, intenta consolidar su base electoral ante el debilitamiento del apoyo de ciertos grupos demogr\u00e1ficos. El partido se ha visto <a href=\"https:\/\/legrandcontinent.eu\/es\/2024\/10\/16\/esta-kamala-harris-perdiendo-la-campana\/\">afectado recientemente por una oleada de p\u00e1nico<\/a> cuando varias encuestas apuntan a una intenci\u00f3n de voto hist\u00f3ricamente baja entre los hombres afroamericanos.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/kiOqb\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La campa\u00f1a de Trump, por su parte, apela principalmente a los votantes MAGA que ya son leales a Trump, sin hacer concesiones en su programa.<\/li>\n\n\n\n<li>Sobre el terreno, la situaci\u00f3n es m\u00e1s sorprendente: el candidato republicano ha celebrado m\u00edtines en varios estados azules que seguramente no ganar\u00e1 (California, Colorado, Nueva York, etc.).<\/li>\n\n\n\n<li>En Colorado, Trump anunci\u00f3 el lanzamiento de <a href=\"https:\/\/legrandcontinent.eu\/es\/2024\/10\/14\/para-combatir-a-los-inmigrantes-criminales-trump-anuncia-la-operacion-aurora\/\">la \u00abOperaci\u00f3n Aurora\u00bb<\/a>: un plan para deportar a millones de inmigrantes ilegales durante un potencial segundo mandato.<\/li>\n<\/ul>\n\n\n\n<p>La literatura cient\u00edfica sobre el tema arroja algo de luz sobre esta elecci\u00f3n: John McCain fue el \u00faltimo candidato que hizo campa\u00f1a en estados que no iba a ganar, en 2008. Seg\u00fan el polit\u00f3logo de la Universidad de Dayton Christopher Devine, el impacto de las visitas en el voto a nivel de condado es infinitesimal (cercano a 0 para la mayor\u00eda de los candidatos, hasta 0,77 puntos por condado visitado para Obama en 2008)&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-47465' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2024\/10\/23\/a-menos-de-dos-semanas-de-las-elecciones-cuales-son-las-estrategias-de-trump-y-harris\/#easy-footnote-bottom-2-47465' title='Christopher J. Devine,\u00a0&lt;em&gt;I\u2019m Here to Ask for Your Vote. How Presidential Campaign Visits Influence Voters&lt;\/em&gt;, Columbia University Press, 2023.'><sup>2<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/fPVJA\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>En lugar de hacer una campa\u00f1a muy local dirigida a un n\u00famero limitado de condados, como hacen los dem\u00f3cratas, Trump busca ocupar el mayor espacio medi\u00e1tico nacional posible: un mitin en California proporciona mucha m\u00e1s exposici\u00f3n que en las peque\u00f1as ciudades de los estados rojos.<\/li>\n\n\n\n<li>Ocupar el terreno que se considera \u00abganado\u00bb por el otro bando tambi\u00e9n significa que no se puede abandonar la guerra de narrativas, crucial para la campa\u00f1a de Trump, sobre todo en lo que respecta a la inmigraci\u00f3n.<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/dpH6P\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Seg\u00fan los datos hist\u00f3ricos de las encuestas agregados por FiveThirtyEight, Trump ha obtenido tradicionalmente mejores resultados en las \u00faltimas semanas de la campa\u00f1a en 2016 y 2020&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-47465' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2024\/10\/23\/a-menos-de-dos-semanas-de-las-elecciones-cuales-son-las-estrategias-de-trump-y-harris\/#easy-footnote-bottom-3-47465' title='Seth Masket,\u00a0&lt;a href=&quot;https:\/\/smotus.substack.com\/p\/trumps-a-strong-closer&quot;&gt;Trump\u2019s a strong closer&lt;\/a&gt;, 22 de octubre de 2024.'><sup>3<\/sup><\/a><\/span><\/span>. Sin embargo, la intenci\u00f3n de voto media sigue estando dentro del margen de error, sobre todo en los estados indecisos m\u00e1s favorecidos por ambos bandos en esta campa\u00f1a: <a href=\"https:\/\/legrandcontinent.eu\/es\/2024\/08\/30\/harris-o-trump-quien-ganara-pensilvania\/\">Pensilvania<\/a> y <a href=\"https:\/\/legrandcontinent.eu\/es\/2024\/10\/22\/se-decantara-carolina-del-norte-por-los-democratas-en-noviembre\/\">Carolina del Norte<\/a>, en particular.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con m\u00e1s de 17 millones de papeletas ya emitidas, los agregadores de sondeos muestran una ligera subida para Trump y una ligera bajada para Harris. A falta de 13 d\u00edas, los dos candidatos entran en el sprint final de la campa\u00f1a codo con codo, un momento en el que tradicionalmente Trump ha sido mejor en 2016 y 2020.<\/p>\n","protected":false},"author":1366,"featured_media":47452,"comment_status":"closed","ping_status":"","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":true,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":3,"footnotes":""},"categories":[724],"tags":[],"staff":[],"editorial_format":[1472],"serie":[],"audience":[],"geo":[172],"class_list":["post-47465","post","type-post","status-publish","format-standard","hentry","category-trump-contra-biden-por-la-casa-blanca-seguir-las-elecciones-estadounidenses-de-2024","editorial_format-analisis","geo-americas"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":47452,"excerpt":"Con m\u00e1s de 17 millones de papeletas ya emitidas, los agregadores de sondeos muestran una ligera subida para Trump y una ligera bajada para Harris. A falta de 13 d\u00edas, los dos candidatos entran en el sprint final de la campa\u00f1a codo con codo, un momento en el que tradicionalmente Trump ha sido mejor en 2016 y 2020.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>A menos de dos semanas de las elecciones: \u00bfcu\u00e1les son las estrategias de Trump y Harris? - El Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/es\/2024\/10\/23\/a-menos-de-dos-semanas-de-las-elecciones-cuales-son-las-estrategias-de-trump-y-harris\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A menos de dos semanas de las elecciones: \u00bfcu\u00e1les son las estrategias de Trump y Harris? - El Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Con m\u00e1s de 17 millones de papeletas ya emitidas, los agregadores de sondeos muestran una ligera subida para Trump y una ligera bajada para Harris. A falta de 13 d\u00edas, los dos candidatos entran en el sprint final de la campa\u00f1a codo con codo, un momento en el que tradicionalmente Trump ha sido mejor en 2016 y 2020.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/es\/2024\/10\/23\/a-menos-de-dos-semanas-de-las-elecciones-cuales-son-las-estrategias-de-trump-y-harris\/\" \/>\n<meta property=\"og:site_name\" content=\"El Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-23T08:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-23T11:08:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/10\/gc-strategie-campagne-US.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1908\" \/>\n\t<meta property=\"og:image:height\" content=\"1072\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"florent\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"florent\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/10\/23\/a-menos-de-dos-semanas-de-las-elecciones-cuales-son-las-estrategias-de-trump-y-harris\/\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/2024\/10\/23\/a-menos-de-dos-semanas-de-las-elecciones-cuales-son-las-estrategias-de-trump-y-harris\/\",\"name\":\"A menos de dos semanas de las elecciones: \u00bfcu\u00e1les son las estrategias de Trump y Harris? - El Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/10\/23\/a-menos-de-dos-semanas-de-las-elecciones-cuales-son-las-estrategias-de-trump-y-harris\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/10\/23\/a-menos-de-dos-semanas-de-las-elecciones-cuales-son-las-estrategias-de-trump-y-harris\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/10\/gc-strategie-campagne-US.jpg\",\"datePublished\":\"2024-10-23T08:00:00+00:00\",\"dateModified\":\"2024-10-23T11:08:10+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/10\/23\/a-menos-de-dos-semanas-de-las-elecciones-cuales-son-las-estrategias-de-trump-y-harris\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/es\/2024\/10\/23\/a-menos-de-dos-semanas-de-las-elecciones-cuales-son-las-estrategias-de-trump-y-harris\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/10\/23\/a-menos-de-dos-semanas-de-las-elecciones-cuales-son-las-estrategias-de-trump-y-harris\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/10\/gc-strategie-campagne-US.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/10\/gc-strategie-campagne-US.jpg\",\"width\":1908,\"height\":1072},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/10\/23\/a-menos-de-dos-semanas-de-las-elecciones-cuales-son-las-estrategias-de-trump-y-harris\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/legrandcontinent.eu\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A menos de dos semanas de las elecciones: \u00bfcu\u00e1les son las estrategias de Trump y Harris?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/\",\"name\":\"El Grand Continent\",\"description\":\"La escala pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\",\"name\":\"florent\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"caption\":\"florent\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A menos de dos semanas de las elecciones: \u00bfcu\u00e1les son las estrategias de Trump y Harris? - El Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/es\/2024\/10\/23\/a-menos-de-dos-semanas-de-las-elecciones-cuales-son-las-estrategias-de-trump-y-harris\/","og_locale":"es_ES","og_type":"article","og_title":"A menos de dos semanas de las elecciones: \u00bfcu\u00e1les son las estrategias de Trump y Harris? - El Grand Continent","og_description":"Con m\u00e1s de 17 millones de papeletas ya emitidas, los agregadores de sondeos muestran una ligera subida para Trump y una ligera bajada para Harris. A falta de 13 d\u00edas, los dos candidatos entran en el sprint final de la campa\u00f1a codo con codo, un momento en el que tradicionalmente Trump ha sido mejor en 2016 y 2020.","og_url":"https:\/\/legrandcontinent.eu\/es\/2024\/10\/23\/a-menos-de-dos-semanas-de-las-elecciones-cuales-son-las-estrategias-de-trump-y-harris\/","og_site_name":"El Grand Continent","article_published_time":"2024-10-23T08:00:00+00:00","article_modified_time":"2024-10-23T11:08:10+00:00","og_image":[{"width":1908,"height":1072,"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/10\/gc-strategie-campagne-US.jpg","type":"image\/jpeg"}],"author":"florent","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"florent","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/es\/2024\/10\/23\/a-menos-de-dos-semanas-de-las-elecciones-cuales-son-las-estrategias-de-trump-y-harris\/","url":"https:\/\/legrandcontinent.eu\/es\/2024\/10\/23\/a-menos-de-dos-semanas-de-las-elecciones-cuales-son-las-estrategias-de-trump-y-harris\/","name":"A menos de dos semanas de las elecciones: \u00bfcu\u00e1les son las estrategias de Trump y Harris? - El Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/es\/2024\/10\/23\/a-menos-de-dos-semanas-de-las-elecciones-cuales-son-las-estrategias-de-trump-y-harris\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/es\/2024\/10\/23\/a-menos-de-dos-semanas-de-las-elecciones-cuales-son-las-estrategias-de-trump-y-harris\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/10\/gc-strategie-campagne-US.jpg","datePublished":"2024-10-23T08:00:00+00:00","dateModified":"2024-10-23T11:08:10+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/es\/2024\/10\/23\/a-menos-de-dos-semanas-de-las-elecciones-cuales-son-las-estrategias-de-trump-y-harris\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/es\/2024\/10\/23\/a-menos-de-dos-semanas-de-las-elecciones-cuales-son-las-estrategias-de-trump-y-harris\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/2024\/10\/23\/a-menos-de-dos-semanas-de-las-elecciones-cuales-son-las-estrategias-de-trump-y-harris\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/10\/gc-strategie-campagne-US.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/10\/gc-strategie-campagne-US.jpg","width":1908,"height":1072},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/es\/2024\/10\/23\/a-menos-de-dos-semanas-de-las-elecciones-cuales-son-las-estrategias-de-trump-y-harris\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legrandcontinent.eu\/es\/"},{"@type":"ListItem","position":2,"name":"A menos de dos semanas de las elecciones: \u00bfcu\u00e1les son las estrategias de Trump y Harris?"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/es\/#website","url":"https:\/\/legrandcontinent.eu\/es\/","name":"El Grand Continent","description":"La escala pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c","name":"florent","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","caption":"florent"}}]}},"lgc_categories":[{"id":724,"name":"Elecciones estadounidenses 2024","slug":"trump-contra-biden-por-la-casa-blanca-seguir-las-elecciones-estadounidenses-de-2024"}],"lgc_author":null,"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/10\/gc-strategie-campagne-US.jpg","width":1908,"height":1072,"alt":""},"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/47465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/users\/1366"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/comments?post=47465"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/47465\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media\/47452"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media?parent=47465"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/categories?post=47465"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/tags?post=47465"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/staff?post=47465"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/editorial_format?post=47465"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/serie?post=47465"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/audience?post=47465"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/geo?post=47465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}