{"id":46850,"date":"2024-10-13T10:59:53","date_gmt":"2024-10-13T08:59:53","guid":{"rendered":"https:\/\/legrandcontinent.eu\/es\/?p=46850"},"modified":"2024-10-13T11:00:39","modified_gmt":"2024-10-13T09:00:39","slug":"karaganov-por-que-no-enviar-un-misil-al-reichstag","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/es\/2024\/10\/13\/karaganov-por-que-no-enviar-un-misil-al-reichstag\/","title":{"rendered":"Karaganov: \u00ab\u00bfPor qu\u00e9 no enviar un misil al Reichstag?\u00bb"},"content":{"rendered":"\n<p class=\"intro\">\u00bfEst\u00e1 la \u00e9lite pol\u00edtica que rodea a Vladimir Putin preparada para cualquier cosa, incluso para una guerra nuclear? Durante las \u00faltimas semanas, los cambios en la doctrina nuclear rusa han sido objeto de muchos comentarios, al menos en los c\u00edrculos pol\u00edticos y diplom\u00e1ticos, y de una indiferencia bastante marcada por parte de la opini\u00f3n p\u00fablica europea, que todav\u00eda no parece tener una idea clara de cu\u00e1l es su posici\u00f3n en medio de las cabezas nucleares estadounidenses y rusas.<\/p>\n\n\n\n<p class=\"intro\">Las autoridades rusas actuales ponen todo su inter\u00e9s en llamar la atenci\u00f3n sobre estos debates, por lo que se empe\u00f1aron en retransmitir en directo, el 25 de septiembre, la reuni\u00f3n del Consejo de Seguridad de la Federaci\u00f3n Rusa dedicada a la doctrina nuclear. A pesar del pesimismo que pueden haber inspirado estas discusiones, de ellas han surgido pocas ideas concretas. La mayor\u00eda de los escenarios en los que Rusia podr\u00eda lanzar ataques nucleares ya estaban contemplados en los textos existentes. La apertura de esta posibilidad a partir de la obtenci\u00f3n de informaci\u00f3n sobre el lanzamiento hacia Rusia (o hacia sus aliados), no s\u00f3lo de misiles bal\u00edsticos, sino ahora de cualquier tipo de dispositivo aeroespacial (desde drones a aviones estrat\u00e9gicos), entraba en el \u00e1mbito de las disposiciones anteriores. Lo mismo ocurre con la extensi\u00f3n del \u201cparaguas\u201d nuclear ruso a Bielorrusia en caso de agresi\u00f3n, una disposici\u00f3n que no hace sino confirmar la doctrina militar de la Uni\u00f3n Europea en cuanto a esos dos pa\u00edses que data de 2021.<\/p>\n\n\n\n<p class=\"intro\">Sea como sea, Serguei Karaganov considera que nada de esto es suficiente, como revela la siguiente entrevista, publicada el 11 de septiembre.<\/p>\n\n\n\n<p class=\"intro\">Pol\u00edtico, fundador del Consejo de Pol\u00edtica Exterior y de Defensa, decano de la Facultad de Econom\u00eda Internacional y Asuntos Exteriores de la Escuela de Altos Estudios de Ciencias Econ\u00f3micas, asesor de la administraci\u00f3n del presidente en pol\u00edtica internacional y consultor del Consejo de Seguridad de la Federaci\u00f3n Rusa, Serguei Karaganov es uno de los grandes inspiradores y <a href=\"https:\/\/legrandcontinent.eu\/es\/2024\/10\/05\/ya-no-se-teme-la-guerra-ni-siquiera-la-nuclear-las-11-profecias-de-karaganov\/\">uno de los principales defensores intelectuales del belicismo de Putin<\/a>.<\/p>\n\n\n\n<p class=\"intro\">En su opini\u00f3n, la doctrina nuclear existente tiene una desventaja fatal para Rusia: al seguir operando seg\u00fan los reflejos pacifistas y la l\u00f3gica estrat\u00e9gica de la Guerra Fr\u00eda, pr\u00e1cticamente descarta cualquier posibilidad de utilizar armas at\u00f3micas, reduciendo as\u00ed la credibilidad de cualquier amenaza que Rusia pudiera hacer a sus enemigos. Sin embargo, la credibilidad es el fundamento mismo de todo el sistema de disuasi\u00f3n nuclear. En opini\u00f3n de Karaganov, Rusia no tiene otra opci\u00f3n, si quiere abandonar el camino que conduce inexorablemente a la guerra eterna y a su propia destrucci\u00f3n, que hacer comprender a sus adversarios que est\u00e1 m\u00e1s decidida que nunca a recurrir a las armas nucleares, y a utilizarlas eficazmente en caso de necesidad estrat\u00e9gica. Rusia debe abandonar sus h\u00e1bitos de letargo y cautela: si tiene que responder a un ataque de un dron contra el Kremlin con un misil contra el Reichstag, que lo haga; si su integridad territorial se ve amenazada, que tome represalias con una bomba at\u00f3mica; si el territorio ruso es golpeado, que caiga una lluvia nuclear sobre las bases militares estadounidenses y de sus aliados.<\/p>\n\n\n\n<p class=\"intro\">Sin querer sobreinterpretar lo que es ante todo una cuesti\u00f3n de h\u00e1bito ling\u00fc\u00edstico, no podemos dejar de observar la recurrencia de la expresi\u00f3n \u201c<em>Ne daj Bog\u201d<\/em>, es decir, \u201dDios no lo quiera\u00bb sobre el uso de un arma at\u00f3mica, expresi\u00f3n que han utilizado sucesivamente Vladimir Putin, Serguei Karaganov y Alexander Lukashenko en relaci\u00f3n con el endurecimiento de la doctrina nuclear rusa. No es de extra\u00f1ar que la perspectiva del uso de un arma capaz de destruir a la humanidad genere una ret\u00f3rica providencialista, pero estamos ante una l\u00f3gica a\u00fan m\u00e1s enga\u00f1osa.<\/p>\n\n\n\n<p class=\"intro\">Este \u201c<em>Ne daj Bog\u201d<\/em> nos deja con la idea de que s\u00f3lo Dios podr\u00eda salvarnos de la espiral que har\u00eda inevitable un ataque nuclear, como si toda esta cadena de acontecimientos no perteneciera, desde el punto de vista ruso, a la voluntad humana. En alg\u00fan momento, Rusia simplemente se ver\u00eda obligada, contra sus deseos m\u00e1s \u00edntimos y como consecuencia de las acciones irresponsables de sus adversarios, a emprender un ataque nuclear. Por lo tanto, ser\u00eda \u201cinocente\u201d tanto del ataque (ya que no tendr\u00eda otra opci\u00f3n) como de los pasos previos al mismo (ya que los \u00fanicos responsables ser\u00edan los belicistas occidentales). Sin embargo, Rusia ten\u00eda, y sigue teniendo, todo el margen de maniobra para no iniciar y profundizar el proceso que conduce a la destrucci\u00f3n nuclear; en pocas palabras, para no hacer la guerra a Ucrania. Por lo tanto, Rusia es plenamente responsable de cada etapa de esta \u201cescalada\u201d.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Usted ha abogado durante mucho tiempo por una reforma de la doctrina nuclear rusa y ha presentado sus propias sugerencias. \u00bfQu\u00e9 cambios cree que se producir\u00e1n con esta nueva doctrina?<\/h3>\n\n\n\n<p>Obviamente no s\u00e9 qu\u00e9 f\u00f3rmulas se mantendr\u00e1n en la versi\u00f3n final del documento, pero ya puedo adelantar algunas ideas. Ante todo, sin embargo, me gustar\u00eda subrayar que la doctrina y la pol\u00edtica actuales sobre el uso de armas nucleares son totalmente irresponsables. Parecen ancladas en los a\u00f1os sesenta y setenta. Nunca he entendido de d\u00f3nde vienen, cu\u00e1les son sus ra\u00edces. De hecho, esta doctrina excluye \u2013en un 99.9%\u2013 del arsenal potencial el uso de la herramienta m\u00e1s poderosa de nuestra pol\u00edtica exterior y estrategia militar. Esto no s\u00f3lo es err\u00f3neo; es francamente inmoral. Hace d\u00e9cadas, millones de personas dieron su vida para que pudi\u00e9ramos beneficiarnos de este escudo nuclear. Estamos hablando de una incre\u00edble historia de hero\u00edsmo y abnegaci\u00f3n, con un tel\u00f3n de fondo de guerra, hambruna y reconstrucci\u00f3n particularmente doloroso \u2013y de repente hemos decidido trazar una l\u00ednea sobre todo eso. Repito: no entiendo c\u00f3mo ha podido ocurrir. Tengo algunas hip\u00f3tesis al respecto, pero prefiero guard\u00e1rmelas para m\u00ed, porque podr\u00edan ofender a nuestra comunidad de expertos y otros c\u00edrculos asociados.<\/p>\n\n\n\n<p>Ya es hora de declarar oficialmente que tenemos derecho a responder con un ataque nuclear a cualquier ataque masivo contra nuestro territorio, incluido cualquier intento de conquista territorial. La nueva doctrina debe incluir tambi\u00e9n una disposici\u00f3n sobre la \u201cescalada nuclear\u201d, de modo que tales ataques vayan acompa\u00f1ados de medidas destinadas a convencer a un adversario hipot\u00e9tico o real de que estamos decididos a utilizar armas nucleares. Aqu\u00ed es donde debe residir el principal objetivo de esta doctrina: todos nuestros adversarios actuales y futuros deben estar absolutamente convencidos de que Rusia est\u00e1 dispuesta a utilizar esta arma. Esto no es s\u00f3lo un deber para con nuestro pa\u00eds y nuestros ciudadanos, tanto militares como civiles, que est\u00e1n dando su vida en los campos de batalla y en nuestras ciudades en este mismo momento; es un deber para con el mundo entero. Si no reactivamos la idea de la disuasi\u00f3n nuclear, el planeta se deslizar\u00e1 hacia un ciclo interminable de guerras, que inevitablemente tomar\u00e1n un giro nuclear y acabar\u00e1n degenerando en una Tercera Guerra Mundial. Es s\u00f3lo cuesti\u00f3n de unos a\u00f1os. El deber de Rusia es reintroducir con fuerza el factor nuclear en la pol\u00edtica internacional y convencer a nuestros adversarios de que estamos dispuestos a utilizar armas nucleares ante el menor ataque contra nuestro territorio y nuestros ciudadanos. Efectivamente, yo he participado en este cambio de rumbo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Usted dice que la doctrina nuclear actual se basa en principios heredados del siglo pasado. Sin embargo, el actual decreto presidencial sobre los fundamentos de la pol\u00edtica nacional en materia de disuasi\u00f3n nuclear s\u00f3lo tiene cuatro a\u00f1os, ya que se firm\u00f3 en 2020.<\/h3>\n\n\n\n<p>Creo que este documento ya est\u00e1 muy obsoleto, puesto que se basa en representaciones y fantas\u00edas que, la mayor\u00eda de las veces, ni siquiera son las nuestras, sino las del siglo pasado. Me culpo por no haberme pronunciado p\u00fablicamente contra este documento cuando se public\u00f3, y por haberme limitado a expresar mis opiniones dentro de un estrecho c\u00edrculo de expertos. Este documento es cualquier cosa menos una doctrina. Sus ra\u00edces se encuentran en ilusiones heredadas tanto de la situaci\u00f3n internacional del siglo XX como de un rechazo de principio a las armas nucleares, lo cual es perfectamente comprensible. Es un rasgo humano normal: \u00bfqui\u00e9n no se opondr\u00eda a su uso?<\/p>\n\n\n\n<p class=\"comment\">Sin embargo, Serguei Karaganov tiene raz\u00f3n en una cosa: acusa a los dirigentes pol\u00edticos de todos los pa\u00edses de vivir en las nubes de las realidades pasadas, en la pura inercia de las ilusiones de ayer. El alcance de estos reflejos anacr\u00f3nicos puede calibrarse cada vez que los dirigentes occidentales, ante el lejano espect\u00e1culo de la guerra en Ucrania, afirman que quieren reproducir hoy la ocupaci\u00f3n del Ruhr o la asfixia econ\u00f3mica sufrida por la URSS durante las \u00faltimas d\u00e9cadas de su existencia, como si Ucrania tuviera d\u00e9cadas por delante. No pasa un d\u00eda sin que aparezca un nuevo s\u00edntoma de esta incapacidad para adaptarse a los tiempos, que es en s\u00ed misma una caracter\u00edstica de nuestra \u00e9poca. Pero Karaganov se equivoca al aplicar este juicio al uso de las armas nucleares. Algunos objetos tienen propiedades internas que desaf\u00edan al tiempo, a las que el tiempo no se aplica. Dif\u00edcilmente nos atrever\u00edamos a decir que defender la idea de los \u201cderechos humanos\u201d (cualquiera que sea la cr\u00edtica alternativa que se les pueda hacer) equivaldr\u00eda a sumergirse en las ilusiones del siglo XVIII. Lo mismo ocurre con las armas nucleares, que contienen en s\u00ed mismas los fundamentos inextricables de su propia intemporalidad, y esta intemporalidad resulta, una y otra vez, del riesgo de destrucci\u00f3n total de la humanidad como especie.<\/p>\n\n\n\n<p class=\"comment\">A este respecto, debemos considerar el manifiesto Russell-Einstein de 1954, no como un documento hist\u00f3rico, testimonio de un determinado estado del conocimiento cient\u00edfico, de las actitudes pol\u00edticas o de las relaciones internacionales, sino como la afirmaci\u00f3n de una verdad atemporal, cuando dice: \u00ablas voces de las personalidades m\u00e1s autorizadas son un\u00e1nimes en afirmar que una guerra en la que se utilicen bombas H podr\u00eda marcar el fin de la raza humana. Lo que se teme es que, si se utilizan varias bombas H, todos los hombres morir\u00e1n, muerte s\u00fabita s\u00f3lo para una minor\u00eda, pero la lenta tortura de la enfermedad y la desintegraci\u00f3n para la mayor\u00eda. [&#8230;] La llamada que hacemos es la de unos seres humanos a otros seres humanos: recuerda que perteneces a la raza de los hombres y olvida lo dem\u00e1s\u00bb.<\/p>\n\n\n<section class=\"dive print-block my-16\" style=\"background-color:;\">\n\t<div class=\"wrapper\">\n\t\t<div class=\"container mx-auto \">\n\t\t\t<div class=\"row flex flex-wrap relative pt-6 pb-16 lg:py-8\">\n\t\t\t\t<div class=\"col w-full xl:ml-1\/10\n\t\t\t\t\t md:w-2\/5 xl:w-2\/5 \t\t\t\t\t\">\n\t\t\t\t\t<a href=\"https:\/\/legrandcontinent.eu\/es\/ofiertas-new\/\" style=\"color:#0a0a0a;\" class=\"font-display font-normal text-4xl leading-9 mb-5 text-white no-underline\">\n\t\t\t\t\t\tRetrato de un mundo roto\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<div style=\"color:#0a0a0a;\" class=\"text-base leading-none font-sans\">\n\t\t\t\t\t\t\t<p>Bajo la direcci\u00f3n de Giuliano da Empoli.<\/p>\n<p>Con contribuciones de Josep Borrell, Lea Ypi, Niall Ferguson, Timothy Garton Ash, Anu Bradford, Jean-Yves Dormagen, Aude Darnal, Branko Milanovi\u0107, Julia Cag\u00e9, Vladislav Surkov o Isabella Weber.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"mt-12 dive-list\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a  style=\"color:#dd203c;\" class=\"no-underline block border-t border-grey-darker py-2 flex\"\n\t\t\t\t\t\t\t\t   href=\"https:\/\/legrandcontinent.eu\/shop\/es\/producto\/el-grand-continent-vol-3-retrato-de-un-mundo-roto\/\"><span class=\"font-sans font-semibold pr-4\">\u2192<\/span> Pedir el volumen<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a  style=\"color:#dd203c;\" class=\"no-underline block border-t border-grey-darker py-2 flex\"\n\t\t\t\t\t\t\t\t   href=\"https:\/\/legrandcontinent.eu\/es\/ofiertas-new\/\"><span class=\"font-sans font-semibold pr-4\">\u2192<\/span> Descubra nuestras ofertas<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div style=\"color:#0a0a0a;\" class=\"dive-footer font-sans text-xs border-t border-grey-darker py-2 leading-4\">\n\t\t\t\t\t\t\t<p><em>Retrato de un mundo roto<\/em>, el nuevo volumen en papel del Grand Continent publicado por Arpa. Est\u00e1 disponible para <a href=\"https:\/\/legrandcontinent.eu\/shop\/es\/producto\/el-grand-continent-vol-3-retrato-de-un-mundo-roto\/\">su compra<\/a> e incluido en nuestra <a href=\"https:\/\/legrandcontinent.eu\/es\/ofiertas-new\/\">oferta de lanzamiento<\/a>.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"col w-full md:w-3\/5 xl:w-2\/5  md:px-0 relative overflow-hidden mt-8 md:mt-0 macron-img\">\n\t\t\t\t\t\t\t\t<a class=\"!absolute !bg-none w-full h-full pin-t pin-l\" href=\"https:\/\/legrandcontinent.eu\/es\/ofiertas-new\/\" class=\"no-underline\">\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" style=\"object-fit: contain; width: 100%; height: 100%;\" src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/09\/mediamodifier_image-128-990x660.png\" \/>\n\t\t\t\t\t\t\t\t<\/a> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n\n<h3 class=\"wp-block-heading\">Espero que nadie.<\/h3>\n\n\n\n<p>Y le entiendo perfectamente a usted y a todos los que piensan como usted. El problema es que, si los pacifistas pueden vivir, es gracias a quienes luchan por ellos. Me refiero a las decenas de miles de j\u00f3venes que, en este mismo momento, est\u00e1n luchando y muriendo en el frente, y, si las cosas siguen su trayectoria actual, incluso en nuestras ciudades, ya que la guerra est\u00e1 a punto de extenderse a\u00fan m\u00e1s. Incluso en una hip\u00f3tesis alternativa, en la que sigui\u00e9ramos desangr\u00e1ndonos en el frente, gastando recursos colosales en una competencia con medio centenar de Estados cuyas econom\u00edas son muy superiores a la nuestra, en cualquier caso nuestro pa\u00eds, que por fin hab\u00eda logrado alcanzar un cierto nivel de bienestar y comodidad, se estar\u00eda condenando a la ruina, o incluso a la desintegraci\u00f3n.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">La doctrina militar actual, de 2010, prev\u00e9 dos escenarios en los que las autoridades rusas podr\u00edan utilizar armas nucleares, mientras que el decreto de 2020 prev\u00e9 cuatro. \u00bfQu\u00e9 significar\u00e1 en la pr\u00e1ctica la introducci\u00f3n de estos escenarios adicionales?<\/h3>\n\n\n\n<p>Obligar\u00e1 a nuestras fuerzas armadas a prepararse para tales ataques. El cuarto escenario, que prev\u00e9 el uso de armas nucleares en caso de amenaza a la existencia del Estado, es tan provisional y circunstancial que ni siquiera tiene sentido discutirlo. En mi opini\u00f3n, se trata de un insulto al sentido com\u00fan.<\/p>\n\n\n\n<p>Nuestra doctrina actual no cumple su funci\u00f3n de disuasi\u00f3n y nos impide aprovechar muchas otras funciones de las armas at\u00f3micas. Hemos ido tan lejos en este sentido que nuestros adversarios est\u00e1n convencidos de que pr\u00e1cticamente no hay casos en los que las utilizar\u00edamos. Cambiaron de opini\u00f3n cuando, hace un a\u00f1o y medio, empezamos a hablar de la necesidad de endurecer nuestra doctrina nuclear, debate al que debo decir que contribu\u00ed activamente. En aquel momento, las revistas americanas estaban llenas de art\u00edculos que ped\u00edan evitar a toda costa la escalada nuclear. Por su parte, los europeos han perdido completamente el juicio: no entienden lo que hacen y parecen haber olvidado en qu\u00e9 consiste la guerra. Los estadounidenses, por su parte, empiezan a comportarse con mucha m\u00e1s cautela.<\/p>\n\n\n\n<p>Al mismo tiempo, persisten en difundir la idea de que Rusia no goza del apoyo de la mayor\u00eda del mundo. Est\u00e1 claro que hoy en d\u00eda no estamos trabajando con esta mayor\u00eda mundial como deber\u00edamos, el porqu\u00e9 es otra cuesti\u00f3n, pero el hecho es que en China, y en varios otros pa\u00edses, mucha gente entiende perfectamente la l\u00f3gica de nuestras acciones, incluidas nuestras iniciativas para reformar la doctrina nuclear. La idea, inculcada por expertos gubernamentales o paragubernamentales de Occidente, de que cualquier endurecimiento por nuestra parte en la cuesti\u00f3n nuclear alienar\u00eda a muchos pa\u00edses de la mayor\u00eda mundial, es una broma. Es un elemento de guerra psicol\u00f3gica y de informaci\u00f3n, y es lamentable que esta idea sea a veces retomada aqu\u00ed por necios o, peor a\u00fan, por personas que, en el fondo de su coraz\u00f3n, desean la derrota de Rusia.<\/p>\n\n\n\n<p class=\"comment\">Fue Serguei Karaganov, en particular, quien introdujo la noci\u00f3n de \u00abmayor\u00eda mundial\u00bb en el arsenal te\u00f3rico de la geoestrategia rusa, plenamente comprometido con su proyecto de sustituir la hegemon\u00eda occidental por un mundo multipolar.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Sin embargo, China ha dejado clara su posici\u00f3n. Hace poco, en respuesta a los anuncios de funcionarios rusos sobre pr\u00f3ximos cambios en la doctrina nuclear, el Ministerio de Asuntos Exteriores chino dijo que era necesario \u201cdescartar el uso de armas at\u00f3micas y evitar la guerra nuclear\u201d. En julio, China volvi\u00f3 a proponer que Rusia y otras potencias nucleares renunciaran al primer uso de armas nucleares. En mayo de este a\u00f1o, los l\u00edderes de Rusia y China, Vladimir Putin y Xi Jinping, firmaron una declaraci\u00f3n conjunta en la que subrayaban el car\u00e1cter impensable de una guerra nuclear, una guerra en la que no puede haber vencedor.<\/h3>\n\n\n\n<p>Esta es la postura oficial de China y la entiendo, hasta cierto punto. No les interesa impulsar la disuasi\u00f3n nuclear, ya que todav\u00eda son d\u00e9biles en este terreno. En cuanto a la declaraci\u00f3n firmada el 3 de enero de 2022 por los dirigentes de las cinco potencias nucleares y las f\u00f3rmulas que contiene, repetidas desde entonces en otros documentos, en el sentido de que \u201cno puede haber vencedor en una guerra nuclear, que por lo tanto debe evitarse\u201d, no veo m\u00e1s que un formidable error intelectual. La idea es que podemos librar cualquier otra forma de guerra, que tenemos toda la libertad para destruirnos unos a otros, siempre que sea con cualquier otro tipo de arma a nuestra disposici\u00f3n.<\/p>\n\n\n\n<p>Cuando estas f\u00f3rmulas aparecieron hace casi medio siglo, en la declaraci\u00f3n Gorbachov-Reagan de 1985, todav\u00eda se cre\u00eda que no pod\u00eda haber guerra entre potencias nucleares. Hoy, sin embargo, la OTAN, con armas nucleares y liderada por Estados Unidos, est\u00e1 librando una guerra a gran escala contra Rusia, utilizando a los ucranianos como carne de ca\u00f1\u00f3n. Si no ponemos fin a esta locura, pronto estar\u00e1n sacrificando a otros pueblos.<\/p>\n\n\n\n<p>Las armas at\u00f3micas son ante todo armas de paz y de prevenci\u00f3n de guerras. Al menos esa es la funci\u00f3n que cumplieron durante muchas d\u00e9cadas. Posteriormente, se nos impusieron conceptos y f\u00f3rmulas que allanaron el camino a la agresi\u00f3n no nuclear en todo el mundo. En la d\u00e9cada de 1990, poco despu\u00e9s de que los dirigentes de la URSS y Estados Unidos suscribieran por primera vez esta f\u00f3rmula, se abri\u00f3 el camino a la expansi\u00f3n de la OTAN, ya que Rusia renunci\u00f3 <em>de facto<\/em> al factor nuclear como instrumento de su pol\u00edtica exterior. Esto fue literalmente un crimen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Sin embargo, la declaraci\u00f3n de los dirigentes del \u201cclub nuclear\u201d del 3 de enero de 2022 descart\u00f3 radicalmente cualquier enfrentamiento militar entre potencias nucleares.<\/h3>\n\n\n\n<p>Esto es cierto. Han modificado un poco la f\u00f3rmula que hac\u00eda impensable cualquier guerra nuclear, y esto es un paso en la direcci\u00f3n correcta. Pero lo cierto es que no se ha roto con la declaraci\u00f3n anterior que, adem\u00e1s de sus premisas pacifistas, pretend\u00eda dar m\u00e1s margen de maniobra a los pa\u00edses cuyo arsenal convencional y poder econ\u00f3mico aumentan las posibilidades de victoria en un enfrentamiento interestatal. A fin de cuentas, se ve que Estados Unidos siempre ha estado y estar\u00e1 dispuesto a utilizar la bomba nuclear en primer lugar&#8230;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">El actual presidente de los Estados Unidos, Joe Biden, prometi\u00f3 durante su campa\u00f1a electoral revisar esta pr\u00e1ctica en el sentido de \u201cning\u00fan uso de las armas nucleares\u201d, o al menos un refuerzo del principio de \u201cuso \u00fanico\u201d con fines defensivos.<\/h3>\n\n\n\n<p>\u00bfNo me diga que sigue creyendo cada palabra que sale de la boca de un candidato a la presidencia de Estados Unidos?<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">No digo eso, s\u00f3lo digo que lo prometi\u00f3.<\/h3>\n\n\n\n<p>Hoy en d\u00eda hay varios grupos de personas que rechazan la idea misma de utilizar armas nucleares, y en parte estoy de acuerdo con algunas de sus opiniones. Comprendo que la decisi\u00f3n de utilizarlas, que inevitablemente provocar\u00eda la muerte de civiles inocentes, ser\u00eda un momento dram\u00e1tico. Esto no quita para nade el hecho de que poseer armas nucleares sin ser capaz de convencer a tu adversario de que est\u00e1s preparado para utilizarlas sea sencillamente un suicidio.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">En una reciente sesi\u00f3n del Foro Econ\u00f3mico Internacional de San Petersburgo, Vladimir Putin dijo: \u201cque Dios no lo quiera\u201d, a\u00f1adiendo que ser\u00eda \u201cmuy lamentable\u201d que se llegara al punto de utilizar armas nucleares, porque el n\u00famero de v\u00edctimas \u201cpodr\u00eda entonces aumentar hasta el infinito\u201d.<\/h3>\n\n\n\n<p>Yo tengo otra opini\u00f3n al respecto. Es una de las leyendas propagadas en el siglo pasado, yo mismo contribu\u00ed a ella en su momento con vistas a prevenir la guerra nuclear. La idea de que cualquier uso, por limitado que sea, de armas nucleares conducir\u00eda necesariamente a un Armaged\u00f3n nuclear mundial no resiste ninguna cr\u00edtica. Puedo asegurarles que todas las potencias nucleares disponen de estrategias para el uso razonado de armas nucleares seg\u00fan una serie de escenarios.<\/p>\n\n\n\n<p>Por otra parte, estoy dispuesto a afirmar con absoluta certeza que Estados Unidos siempre ha mentido y sigue mintiendo sobre el hecho de que sus garant\u00edas nucleares se aplican a sus aliados. Eso es absolutamente cierto.<\/p>\n\n\n\n<p class=\"comment\">La convicci\u00f3n de que Estados Unidos no responder\u00eda con un ataque nuclear a un ataque nuclear ruso en Europa, demostrando as\u00ed la invalidez del art\u00edculo 5 del Tratado y llevando potencialmente a la ruptura de la alianza, est\u00e1 muy extendida, m\u00e1s all\u00e1 de Serguei Karaganov, entre los expertos estrat\u00e9gicos que rodean a Vladimir Putin.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfEst\u00e1 diciendo que Estados Unidos no responder\u00e1 a un ataque nuclear ruso contra un miembro europeo de la OTAN?<\/h3>\n\n\n\n<p>Durante la Guerra Fr\u00eda, Estados Unidos contempl\u00f3 la posibilidad de que Rusia se expandiera hacia Occidente enviando sus columnas de tanques a trav\u00e9s de Alemania, mientras se proteg\u00eda bajo su paraguas nuclear. El \u00fanico escenario de represalia que idearon fue un ataque nuclear en territorio de la propia Alemania, no de la URSS. En este sentido, nada ha cambiado para Estados Unidos desde entonces, pero seguimos volando \u201cen las nubes\u201d de las falsas representaciones.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">El director de la CIA, Bill Burns, declar\u00f3 recientemente que, a pesar de los informes del oto\u00f1o de 2022 seg\u00fan los cuales Rusia podr\u00eda lanzar un ataque nuclear en Ucrania, estaba y sigue estando convencido de que este factor no debe influir en el apoyo occidental a Kiev. Y a\u00f1adi\u00f3: \u201cRusia se est\u00e1 comportando como un mat\u00f3n, pero no debemos dejar que nos intimide\u201d. \u00bfQu\u00e9 cambiar\u00e1 si la doctrina nuclear rusa se hace m\u00e1s estricta?<\/h3>\n\n\n\n<p>No basta con endurecer la doctrina nuclear; sobre todo, la clase dirigente rusa debe dejar claro que est\u00e1 dispuesta a utilizar esta arma.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfContra qui\u00e9n?<\/h3>\n\n\n\n<p>Contra aquellos Estados que apoyen la agresi\u00f3n de la OTAN en Ucrania.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">En otras palabras, todos los pa\u00edses miembros de la OTAN.<\/h3>\n\n\n\n<p>No, no todos. \u00bfPor qu\u00e9 debemos apuntar a todos? Los l\u00edderes militares necesitan elaborar una lista concreta de objetivos para un ataque nuclear. \u00a1Por supuesto, ojal\u00e1 Dios no lo quiera! Tenemos que hacer todo lo posible para detener las cosas antes de que lleguen a ese punto.<\/p>\n\n\n\n<p>Bill Burns es una persona inteligente, que cuenta con todo mi respeto, pero aqu\u00ed \u00e9l est\u00e1 diciendo una mentira tan fant\u00e1stica y brillante como descarada. Tengo entendido que ha amenazado a los funcionarios rusos con un golpe devastador, utilizando armas convencionales, contra Rusia, as\u00ed como contra nuestras fuerzas armadas en Ucrania y sus alrededores, si alguna vez atacamos a los pa\u00edses de la OTAN. Sin exagerar mi importancia hist\u00f3rica, le respond\u00ed que, en ese caso, tendr\u00edamos derecho a llevar a cabo un segundo ataque nuclear contra un n\u00famero mucho mayor de objetivos en Europa. Si la escalada continuaba, tambi\u00e9n tendr\u00edamos derecho a llevar a cabo ataques contra bases estadounidenses en pa\u00edses de la OTAN y en todo el mundo, lo que provocar\u00eda la muerte de cientos de miles de soldados.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfNo es \u00e9ste el camino hacia la guerra nuclear total?<\/h3>\n\n\n\n<p>Esto no suceder\u00e1 si nuestros adversarios son conscientes de nuestra determinaci\u00f3n a utilizar armas nucleares, aunque ello suponga un elevado n\u00famero de bajas, principalmente entre los militares.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Parece arriesgado e incierto.<\/h3>\n\n\n\n<p>No estoy pidiendo en absoluto que se tome el camino m\u00e1s peligroso, sino que se preserven la paz y Rusia. S\u00f3lo tenemos dos opciones: ganar esta guerra o hundirnos. Occidente puede permitirse luchar indefinidamente, ya que se est\u00e1 beneficiando de esta guerra. Pero eso no significa que yo est\u00e9 llamando a una guerra nuclear: al contrario, espero que las cosas no lleguen tan lejos, que se detengan antes de que tengamos que tomar esa terrible decisi\u00f3n.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Vladimir Putin ha dicho a menudo que Rusia tiene capacidad militar convencional m\u00e1s que suficiente para cumplir los objetivos que se ha fijado Mosc\u00fa. Al endurecer deliberadamente su doctrina nuclear y amenazar con lanzar ataques nucleares en respuesta a cualquier agresi\u00f3n, \u00bfno corre Rusia el peligro de difuminar a\u00fan m\u00e1s sus \u201cl\u00edneas rojas\u201d? Tomemos, por ejemplo, el ataque ucraniano con drones contra el Kremlin. \u00bfQu\u00e9 deber\u00edamos hacer si se repitiera un ataque semejante?<\/h3>\n\n\n\n<p>Nuestros adversarios necesitan saber que nuestro presidente tomar\u00e1 la decisi\u00f3n de lanzar un ataque nuclear, o que lo har\u00e1 otra persona. Tenemos que estar preparados para esta decisi\u00f3n: es una obligaci\u00f3n ante nuestro pa\u00eds, ante el mundo y ante Dios. Si nuestro adversario llega a ser plenamente consciente de nuestra determinaci\u00f3n, es casi seguro que no se lanzar\u00e1n m\u00e1s ataques con aviones no tripulados contra el Kremlin.<\/p>\n\n\n\n<p>Es hora de que comprendamos que la guerra a la que nos enfrentamos es una guerra de aniquilaci\u00f3n. Mucha gente a\u00fan no se ha dado cuenta de ello. Hasta que no nos hayan aniquilado, nuestros \u201csocios\u201d occidentales no tendr\u00e1n un momento de respiro. Hay que hacerles comprender que es imposible eliminarnos sin sufrir enormes p\u00e9rdidas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Sigo sin entender por qu\u00e9 debemos atarnos las manos amenazando con responder con armas nucleares a casi cualquier ataque convencional. El ejemplo del ataque con drones al Kremlin, al que las autoridades rusas respondieron de forma relativamente comedida, me parece revelador a este respecto.<\/h3>\n\n\n\n<p>Si un dron vuelve a sobrevolar el Kremlin, \u00bfpor qu\u00e9 no enviar un misil convencional contra el Reichstag? Que arda.<\/p>\n\n\n\n<p>Si los alemanes han olvidado sus aterradores cr\u00edmenes, que nunca deber\u00edan olvidarse, ser\u00eda una buena idea record\u00e1rselos. En cualquier caso, los ataques nucleares deben ir precedidos de ataques preventivos convencionales.<\/p>\n\n\n\n<p class=\"comment\">Este exceso de Serguei Karaganov, como el resto de sus propuestas, fueron le\u00eddos como una llamada expl\u00edcita a una guerra nuclear y desautorizados como tales por algunos expertos rusos, incluso dentro del Consejo de Pol\u00edtica Exterior y de Defensa.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfY usted cree que su respuesta no ser\u00e1 nuclear?<\/h3>\n\n\n\n<p>Obviamente, los primeros ataques no tienen por qu\u00e9 ser nucleares. Seg\u00fan la teor\u00eda de la escalada, todav\u00eda hay que subir 10 o 15 pelda\u00f1os antes de llegar a ese punto, y de momento s\u00f3lo hemos subido 5. Pero est\u00e1 claro que en una segunda fase ser\u00e1 necesario llevar a cabo ataques en el territorio de los pa\u00edses de la OTAN, que desempe\u00f1an un papel clave en el apoyo al r\u00e9gimen de Kiev. Si eso no los detiene, habr\u00e1 que ir m\u00e1s lejos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Y entonces: nuestros adversarios nos infligen un ataque masivo con armas convencionales, nosotros respondemos con un ataque en grupo a\u00fan m\u00e1s masivo, pero llega un momento en que nos acercamos a las fases finales&#8230;<\/h3>\n\n\n\n<p>Entonces tenemos que responder inmediatamente con un ataque nuclear contra objetivos en Europa.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfQu\u00e9 garant\u00eda hay de que ambas partes sean capaces de evitar destruir todo el planeta cuando llegue el momento?<\/h3>\n\n\n\n<p>Las \u00fanicas \u201cgarant\u00edas\u201d que existen son las que puedes obtener de Rosgosstraj. Lo que puedo garantizar es que, a menos que reactivemos la pol\u00edtica de disuasi\u00f3n nuclear, no evitaremos la autodestrucci\u00f3n de la humanidad. Y, en primer lugar, corremos el riesgo de desaparecer nosotros mismos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde hace unas semanas, los halcones del entorno de Vladimir Putin tocan en Mosc\u00fa una melod\u00eda: \u00bfqu\u00e9 tal un cambio de doctrina?<\/p>\n<p>Hemos traducido una entrevista con Sergei Karaganov, uno de los principales garantes intelectuales del belicismo de Putin, que so\u00f1ar\u00eda con mover el umbral a otro nivel. <\/p>\n","protected":false},"author":17959,"featured_media":46863,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-speeches.php","format":"standard","meta":{"_acf_changed":true,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":20,"footnotes":""},"categories":[754],"tags":[],"staff":[149],"editorial_format":[1474],"serie":[],"audience":[],"geo":[182],"class_list":["post-46850","post","type-post","status-publish","format-standard","hentry","category-doctrinas-de-la-rusia-de-putin-politica","staff-guillaume-lancereau","editorial_format-archivos-y-discursos","geo-asia-septentrional"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":46863,"excerpt":"Desde hace unas semanas, los halcones del entorno de Vladimir Putin tocan en Mosc\u00fa una melod\u00eda: \u00bfqu\u00e9 tal un cambio de doctrina?\r\n\r\nHemos traducido una entrevista con Sergei Karaganov, uno de los principales garantes intelectuales del belicismo de Putin, que so\u00f1ar\u00eda con mover el umbral a otro nivel. ","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Karaganov: \u00ab\u00bfPor qu\u00e9 no enviar un misil al Reichstag?\u00bb - El Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/es\/2024\/10\/13\/karaganov-por-que-no-enviar-un-misil-al-reichstag\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Karaganov: \u00ab\u00bfPor qu\u00e9 no enviar un misil al Reichstag?\u00bb - El Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Desde hace unas semanas, los halcones del entorno de Vladimir Putin tocan en Mosc\u00fa una melod\u00eda: \u00bfqu\u00e9 tal un cambio de doctrina?  Hemos traducido una entrevista con Sergei Karaganov, uno de los principales garantes intelectuales del belicismo de Putin, que so\u00f1ar\u00eda con mover el umbral a otro nivel.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/es\/2024\/10\/13\/karaganov-por-que-no-enviar-un-misil-al-reichstag\/\" \/>\n<meta property=\"og:site_name\" content=\"El Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-13T08:59:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-13T09:00:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/10\/gc-elkaraga-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"anainesfernandez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/10\/gc-elkaraga-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"anainesfernandez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"20 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/10\/13\/karaganov-por-que-no-enviar-un-misil-al-reichstag\/\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/2024\/10\/13\/karaganov-por-que-no-enviar-un-misil-al-reichstag\/\",\"name\":\"Karaganov: \u00ab\u00bfPor qu\u00e9 no enviar un misil al Reichstag?\u00bb - El Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/10\/13\/karaganov-por-que-no-enviar-un-misil-al-reichstag\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/10\/13\/karaganov-por-que-no-enviar-un-misil-al-reichstag\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/10\/SIPA_ap22898837_000002-scaled-1.jpg\",\"datePublished\":\"2024-10-13T08:59:53+00:00\",\"dateModified\":\"2024-10-13T09:00:39+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/570398dd8da37ba5d66dec6d242bd33c\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/10\/13\/karaganov-por-que-no-enviar-un-misil-al-reichstag\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/es\/2024\/10\/13\/karaganov-por-que-no-enviar-un-misil-al-reichstag\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/10\/13\/karaganov-por-que-no-enviar-un-misil-al-reichstag\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/10\/SIPA_ap22898837_000002-scaled-1.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/10\/SIPA_ap22898837_000002-scaled-1.jpg\",\"width\":2560,\"height\":1682,\"caption\":\"El presidente ruso, Vlad\u00edmir Putin, durante una reuni\u00f3n sobre asuntos econ\u00f3micos por videoconferencia en la residencia estatal de Novo-Ogaryovo, Mosc\u00fa, Rusia, lunes 26 de agosto de 2024. \u00a9 Alexander Kazakov\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/10\/13\/karaganov-por-que-no-enviar-un-misil-al-reichstag\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/legrandcontinent.eu\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Karaganov: \u00ab\u00bfPor qu\u00e9 no enviar un misil al Reichstag?\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/\",\"name\":\"El Grand Continent\",\"description\":\"La escala pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/570398dd8da37ba5d66dec6d242bd33c\",\"name\":\"anainesfernandez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/fe25c21e6213f69a683147fabda32586?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/fe25c21e6213f69a683147fabda32586?s=96&d=mm&r=g\",\"caption\":\"anainesfernandez\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Karaganov: \u00ab\u00bfPor qu\u00e9 no enviar un misil al Reichstag?\u00bb - El Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/es\/2024\/10\/13\/karaganov-por-que-no-enviar-un-misil-al-reichstag\/","og_locale":"es_ES","og_type":"article","og_title":"Karaganov: \u00ab\u00bfPor qu\u00e9 no enviar un misil al Reichstag?\u00bb - El Grand Continent","og_description":"Desde hace unas semanas, los halcones del entorno de Vladimir Putin tocan en Mosc\u00fa una melod\u00eda: \u00bfqu\u00e9 tal un cambio de doctrina?  Hemos traducido una entrevista con Sergei Karaganov, uno de los principales garantes intelectuales del belicismo de Putin, que so\u00f1ar\u00eda con mover el umbral a otro nivel.","og_url":"https:\/\/legrandcontinent.eu\/es\/2024\/10\/13\/karaganov-por-que-no-enviar-un-misil-al-reichstag\/","og_site_name":"El Grand Continent","article_published_time":"2024-10-13T08:59:53+00:00","article_modified_time":"2024-10-13T09:00:39+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/10\/gc-elkaraga-scaled.jpg","type":"image\/jpeg"}],"author":"anainesfernandez","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/10\/gc-elkaraga-scaled.jpg","twitter_misc":{"Escrito por":"anainesfernandez","Tiempo de lectura":"20 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/es\/2024\/10\/13\/karaganov-por-que-no-enviar-un-misil-al-reichstag\/","url":"https:\/\/legrandcontinent.eu\/es\/2024\/10\/13\/karaganov-por-que-no-enviar-un-misil-al-reichstag\/","name":"Karaganov: \u00ab\u00bfPor qu\u00e9 no enviar un misil al Reichstag?\u00bb - El Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/es\/2024\/10\/13\/karaganov-por-que-no-enviar-un-misil-al-reichstag\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/es\/2024\/10\/13\/karaganov-por-que-no-enviar-un-misil-al-reichstag\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/10\/SIPA_ap22898837_000002-scaled-1.jpg","datePublished":"2024-10-13T08:59:53+00:00","dateModified":"2024-10-13T09:00:39+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/570398dd8da37ba5d66dec6d242bd33c"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/es\/2024\/10\/13\/karaganov-por-que-no-enviar-un-misil-al-reichstag\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/es\/2024\/10\/13\/karaganov-por-que-no-enviar-un-misil-al-reichstag\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/2024\/10\/13\/karaganov-por-que-no-enviar-un-misil-al-reichstag\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/10\/SIPA_ap22898837_000002-scaled-1.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/10\/SIPA_ap22898837_000002-scaled-1.jpg","width":2560,"height":1682,"caption":"El presidente ruso, Vlad\u00edmir Putin, durante una reuni\u00f3n sobre asuntos econ\u00f3micos por videoconferencia en la residencia estatal de Novo-Ogaryovo, Mosc\u00fa, Rusia, lunes 26 de agosto de 2024. \u00a9 Alexander Kazakov"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/es\/2024\/10\/13\/karaganov-por-que-no-enviar-un-misil-al-reichstag\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legrandcontinent.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Karaganov: \u00ab\u00bfPor qu\u00e9 no enviar un misil al Reichstag?\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/es\/#website","url":"https:\/\/legrandcontinent.eu\/es\/","name":"El Grand Continent","description":"La escala pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/570398dd8da37ba5d66dec6d242bd33c","name":"anainesfernandez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/fe25c21e6213f69a683147fabda32586?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fe25c21e6213f69a683147fabda32586?s=96&d=mm&r=g","caption":"anainesfernandez"}}]}},"lgc_categories":[{"id":754,"name":"Doctrinas de la Rusia de Putin","slug":"doctrinas-de-la-rusia-de-putin-politica"}],"lgc_author":{"id":149,"name":"Guillaume Lancereau","slug":"guillaume-lancereau","description":"Es becario Max Weber en el Instituto Universitario Europeo. Especialista en la Revoluci\u00f3n Francesa y su historiograf\u00eda, es coautor del blog de historia del siglo XVIII \u00c9chos des Lumi\u00e8res.","first_name":"Guillaume","last_name":"Lancereau","picture":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/12\/2023\/09\/G-lancereau.jpeg","width":230,"height":345,"alt":""}},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/10\/SIPA_ap22898837_000002-scaled-1.jpg","width":2560,"height":1682,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/10\/SIPA_ap22898837_000002-scaled-1.jpg","width":2560,"height":1682,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/46850","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/users\/17959"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/comments?post=46850"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/46850\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media\/46863"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media?parent=46850"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/categories?post=46850"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/tags?post=46850"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/staff?post=46850"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/editorial_format?post=46850"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/serie?post=46850"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/audience?post=46850"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/geo?post=46850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}