{"id":46175,"date":"2024-10-01T13:52:42","date_gmt":"2024-10-01T11:52:42","guid":{"rendered":"https:\/\/legrandcontinent.eu\/es\/?p=46175"},"modified":"2024-10-02T13:54:56","modified_gmt":"2024-10-02T11:54:56","slug":"como-explicar-el-exito-del-fpo-autopsia-de-la-recomposicion-politica-en-austria-por-parte-de-la-extrema-derecha","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/es\/2024\/10\/01\/como-explicar-el-exito-del-fpo-autopsia-de-la-recomposicion-politica-en-austria-por-parte-de-la-extrema-derecha\/","title":{"rendered":"\u00bfC\u00f3mo explicar el \u00e9xito del FP\u00d6? Autopsia de la recomposici\u00f3n pol\u00edtica en Austria por parte de la extrema derecha"},"content":{"rendered":"\n<p><em>Para seguir todas las elecciones a escala pertinente, <\/em><a href=\"https:\/\/legrandcontinent.eu\/es\/ofiertas-new-1-1\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>suscr\u00edbete al Grand Continent<\/em><\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfC\u00f3mo explica el \u00e9xito simult\u00e1neo de dos partidos que tienen muy poco en com\u00fan, el ultraderechista FP\u00d6 (PfE) y el liberal NEOS (RE)?<\/h3>\n\n\n\n<p>El \u00e9xito del FP\u00d6 est\u00e1 ligado en gran medida al gran descontento de una parte de la poblaci\u00f3n con la pol\u00edtica gubernamental, que tiene muchas fuentes. La cuesti\u00f3n de la inmigraci\u00f3n desempe\u00f1\u00f3 un papel importante en la campa\u00f1a electoral, la situaci\u00f3n econ\u00f3mica no es especialmente buena y el recuerdo de la pol\u00edtica sanitaria sigue llevando a una parte del electorado a querer castigar al gobierno actual por las medidas tomadas en su momento.<\/p>\n\n\n\n<p>NEOS es un partido centrista y liberal cuyas posiciones son muy diferentes de las del FP\u00d6. Tradicionalmente, los partidos liberales no son muy fuertes en Austria. Pero esta vez, el partido pudo ganar puntos al ser una de las pocas formaciones pol\u00edticas que defendi\u00f3 un programa optimista. Probablemente, NEOS arrebat\u00f3 algunos votantes tanto a los Verdes como al \u00d6VP, sobre todo en las zonas urbanas, y se aprovech\u00f3 de la debilidad de sus competidores.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Antes de las elecciones, <a href=\"https:\/\/legrandcontinent.eu\/es\/2024\/04\/08\/la-neutralidad-estrategica-de-austria-una-conversacion-con-el-canciller-federal-karl-nehammer\/\">el canciller Karl Nehammer<\/a> hab\u00eda dicho que rechazaba cualquier coalici\u00f3n con el l\u00edder del FP\u00d6, Herbert Kickl. El domingo por la noche, el secretario general del \u00d6VP fue menos categ\u00f3rico y subray\u00f3 que no se exclu\u00eda <em>a<\/em> <em>priori<\/em> una colaboraci\u00f3n con el FP\u00d6 si el propio Kickl no formaba parte de la futura coalici\u00f3n. \u00bfQu\u00e9 probabilidades hay de que el FP\u00d6 est\u00e9 realmente dispuesto a formar una coalici\u00f3n sin Kickl?<\/h3>\n\n\n\n<p>Los comentarios de ayer del secretario general del \u00d6VP son coherentes con la actitud de su partido durante toda la campa\u00f1a electoral. El \u00d6VP ha dicho que no quiere a Kickl en el gobierno, ni como canciller ni como ministro federal. No creo que renuncie a esta condici\u00f3n.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/AiFGQ\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Por otra parte, parece poco probable que el FP\u00d6 acepte esta condici\u00f3n entrando en un gobierno de coalici\u00f3n sin Kickl. En consecuencia, es poco probable que se forme una coalici\u00f3n de este tipo.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Tradicionalmente, los partidos liberales no son muy fuertes en Austria.<\/p><cite>Marcelo Jenny<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00bfQu\u00e9 opina el electorado de una posible coalici\u00f3n turqueza-azul (\u00d6VP-FP\u00d6)?<\/strong> <strong>\u00bfLa base de centro-derecha del \u00d6VP no estar\u00eda m\u00e1s contenta si el \u00d6VP formara coalici\u00f3n con el FP\u00d6 en lugar de con los socialdem\u00f3cratas?<\/strong><\/h3>\n\n\n\n<p>Es dif\u00edcil decir cu\u00e1l de las dos posturas domina entre las bases del partido. Muchos votantes del \u00d6VP no quieren aliarse con el FP\u00d6. El presidente del partido federal declar\u00f3 que quiere un gobierno estable y, por tanto, descarta una coalici\u00f3n con Kickl, por considerar inaceptables sus posiciones en pol\u00edtica europea y exterior. Pero sea cual sea la opci\u00f3n que elija, sin duda decepcionar\u00e1 a una de las dos alas de su partido.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">En \u00faltima instancia, \u00bfha calculado mal Kickl al adoptar una pol\u00edtica exterior tan radical? \u00bfO simplemente espera ganar m\u00e1s puntos permaneciendo en la oposici\u00f3n?<\/h3>\n\n\n\n<p>Es una pregunta dif\u00edcil. Con la l\u00ednea de Kickl en el per\u00edodo previo a estas elecciones, el FP\u00d6 se ha convertido por primera vez en el partido m\u00e1s grande del pa\u00eds, ganando muchos m\u00e1s mandatos. Pero ahora su participaci\u00f3n en el gobierno podr\u00eda fracasar precisamente por esta l\u00ednea. Que esta estrategia se interprete como un \u00e9xito o un fracaso depender\u00e1 en gran medida de lo que los miembros y funcionarios del partido esperen de ella: si valoran m\u00e1s los resultados electorales o la participaci\u00f3n en el gobierno.<\/p>\n\n\n<section class=\"dive print-block my-16\" style=\"background-color:;\">\n\t<div class=\"wrapper\">\n\t\t<div class=\"container mx-auto \">\n\t\t\t<div class=\"row flex flex-wrap relative pt-6 pb-16 lg:py-8\">\n\t\t\t\t<div class=\"col w-full xl:ml-1\/10\n\t\t\t\t\t md:w-2\/5 xl:w-2\/5 \t\t\t\t\t\">\n\t\t\t\t\t<a href=\"https:\/\/legrandcontinent.eu\/es\/ofiertas-new\/\" style=\"color:#0a0a0a;\" class=\"font-display font-normal text-4xl leading-9 mb-5 text-white no-underline\">\n\t\t\t\t\t\tRetrato de un mundo roto\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<div style=\"color:#0a0a0a;\" class=\"text-base leading-none font-sans\">\n\t\t\t\t\t\t\t<p>Bajo la direcci\u00f3n de Giuliano da Empoli.<\/p>\n<p>Con contribuciones de Josep Borrell, Lea Ypi, Niall Ferguson, Timothy Garton Ash, Anu Bradford, Jean-Yves Dormagen, Aude Darnal, Branko Milanovi\u0107, Julia Cag\u00e9, Vladislav Surkov o Isabella Weber.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"mt-12 dive-list\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a  style=\"color:#dd203c;\" class=\"no-underline block border-t border-grey-darker py-2 flex\"\n\t\t\t\t\t\t\t\t   href=\"https:\/\/legrandcontinent.eu\/shop\/es\/producto\/el-grand-continent-vol-3-retrato-de-un-mundo-roto\/\"><span class=\"font-sans font-semibold pr-4\">\u2192<\/span> Pedir el volumen<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a  style=\"color:#dd203c;\" class=\"no-underline block border-t border-grey-darker py-2 flex\"\n\t\t\t\t\t\t\t\t   href=\"https:\/\/legrandcontinent.eu\/es\/ofiertas-new\/\"><span class=\"font-sans font-semibold pr-4\">\u2192<\/span> Descubra nuestras ofertas<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div style=\"color:#0a0a0a;\" class=\"dive-footer font-sans text-xs border-t border-grey-darker py-2 leading-4\">\n\t\t\t\t\t\t\t<p><em>Retrato de un mundo roto<\/em>, el nuevo volumen en papel del Grand Continent publicado por Arpa. Est\u00e1 disponible para <a href=\"https:\/\/legrandcontinent.eu\/shop\/es\/producto\/el-grand-continent-vol-3-retrato-de-un-mundo-roto\/\">su compra<\/a> e incluido en nuestra <a href=\"https:\/\/legrandcontinent.eu\/es\/ofiertas-new\/\">oferta de lanzamiento<\/a>.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"col w-full md:w-3\/5 xl:w-2\/5  md:px-0 relative overflow-hidden mt-8 md:mt-0 macron-img\">\n\t\t\t\t\t\t\t\t<a class=\"!absolute !bg-none w-full h-full pin-t pin-l\" href=\"https:\/\/legrandcontinent.eu\/es\/ofiertas-new\/\" class=\"no-underline\">\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" style=\"object-fit: contain; width: 100%; height: 100%;\" src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/09\/mediamodifier_image-128-990x660.png\" \/>\n\t\t\t\t\t\t\t\t<\/a> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n\n<h3 class=\"wp-block-heading\">Tras estas elecciones, son concebibles dos modelos principales de coalici\u00f3n: o bien el \u00d6VP gobierna con el FP\u00d6, o bien forma una coalici\u00f3n en el centro, con los socialdem\u00f3cratas. \u00bfCu\u00e1les podr\u00edan ser los puntos m\u00e1s destacados de un futuro acuerdo de coalici\u00f3n entre el \u00d6VP y el SP\u00d6?<\/h3>\n\n\n\n<p>Este programa depender\u00e1 en gran medida de la composici\u00f3n del equipo negociador de los socialdem\u00f3cratas. En el SP\u00d6 hay al menos tres alas: un ala izquierda, un ala centrista y un ala derecha. El presidente del partido, Andreas Babler, que tiende a pertenecer al ala izquierda, no ser\u00e1 el \u00fanico que participe en las negociaciones; los centristas tambi\u00e9n estar\u00e1n bien representados, entre otras cosas porque desean expresar su singularidad con respecto al l\u00edder del SP\u00d6, sobre el que han expresado reservas. El gobernador derechista de Burgenland, Hans Peter Doskozil, se ha situado al margen de su partido al declarar p\u00fablicamente su oposici\u00f3n a que el SP\u00d6 participe en el gobierno. As\u00ed las cosas, cabe esperar que dominen las posiciones m\u00e1s bien centristas del partido vien\u00e9s. En cualquier caso, es poco probable que la formaci\u00f3n de gobierno fracase como consecuencia de las disputas internas.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Con la l\u00ednea adoptada por Kickl de cara a estas elecciones, el FP\u00d6 se ha convertido por primera vez en el primer partido del pa\u00eds, ganando muchos m\u00e1s mandatos.<\/p><cite>Marcelo Jenny<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Un hipot\u00e9tico gobierno \u00d6VP-SP\u00d6 tendr\u00eda una mayor\u00eda de un solo esca\u00f1o. Sin embargo, es m\u00e1s probable que el \u00d6VP y el SP\u00d6 intenten incorporar a los liberales del NEOS o a los Verdes a su coalici\u00f3n para obtener una mayor\u00eda de gobierno m\u00e1s estable. \u00bfCu\u00e1l de los dos partidos m\u00e1s peque\u00f1os es el favorito para entrar en el gobierno?<\/h3>\n\n\n\n<p>Actualmente, NEOS est\u00e1 en mejor posici\u00f3n. Las relaciones entre el \u00d6VP y los Verdes, que forman el actual gobierno, se deterioraron durante la \u00faltima fase de la pasada legislatura. Los dos partidos fueron incapaces de ponerse de acuerdo en varios puntos importantes, sobre todo en materia de pol\u00edtica medioambiental y clim\u00e1tica. Los ministros verdes apoyaron a veces decisiones a nivel europeo que no conven\u00edan a su socio de gobierno. A los NEOS se les atribuyen importantes ganancias electorales, mientras que los Verdes han sufrido p\u00e9rdidas bastante considerables. Tambi\u00e9n ser\u00e1 m\u00e1s f\u00e1cil informar sobre el pr\u00f3ximo gobierno si no est\u00e1 formado \u00fanicamente por partidos que perdieron las elecciones, sino que tambi\u00e9n incluye a NEOS, que es uno de los ganadores de esta secuencia.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/m8835\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Si este escenario se materializa, el actual gobierno centrista ser\u00e1 sustituido por otro gobierno centrista. \u00bfQu\u00e9 cambios program\u00e1ticos se introducir\u00e1n?<\/h3>\n\n\n\n<p>Aunque los liberales probablemente intentar\u00e1n centrarse en la pol\u00edtica econ\u00f3mica, su tema principal siempre ha sido la pol\u00edtica educativa, y sin duda intentar\u00e1n obtener este ministerio a nivel federal. En este \u00e1mbito y en el relacionado con la integraci\u00f3n, NEOS siempre ha tenido puntos de convergencia con el \u00d6VP. Por eso a veces se describe a NEOS, de forma un tanto caricaturesca, como un \u00d6VP \u00abrejuvenecido\u00bb o \u00abmodernizado\u00bb. Geogr\u00e1ficamente, los partidos tambi\u00e9n son complementarios: NEOS ha sido capaz de ganar puntos en las zonas urbanas, mientras que el \u00d6VP es m\u00e1s fuerte en las zonas rurales. Hay que decir, sin embargo, que hay m\u00e1s ideas genuinamente liberales en el programa de NEOS que en el del \u00d6VP, cuyo programa siempre ha tenido tintes antiliberales en lo que se refiere a la pol\u00edtica econ\u00f3mica y agr\u00edcola.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Incluso en Alemania, gobernada por la coalici\u00f3n de Olaf Scholz (SPD), el gobierno ha adoptado recientemente una postura cr\u00edtica respecto a la inmigraci\u00f3n. \u00bfPodemos esperar una postura similar del pr\u00f3ximo gobierno austriaco?<\/h3>\n\n\n\n<p>Desde luego que s\u00ed. Los liberales, que actualmente ocupan la cartera de Educaci\u00f3n en el gobierno regional de Viena, han conocido de primera mano las dificultades de integraci\u00f3n a las que se enfrenta la regi\u00f3n. Sin embargo, hay que distinguir claramente entre inmigraci\u00f3n e integraci\u00f3n, y habr\u00e1 que estar atentos a la postura del futuro gobierno en este \u00e1mbito. En Viena, la proporci\u00f3n de poblaci\u00f3n de origen inmigrante es del 20-25%, pero este grupo incluye tanto a ciudadanos europeos altamente calificados como a descendientes de antiguas generaciones de trabajadores inmigrantes, as\u00ed como a refugiados m\u00e1s recientes de Ucrania y Medio Oriente. En la actualidad, el sector educativo vien\u00e9s experimenta dificultades sobre todo con los alumnos no german\u00f3fonos, cuyas trayectorias educativas son menos favorables que las del resto de la poblaci\u00f3n y que no tienen f\u00e1cil acceso a empleos bien remunerados. Cerrar las fronteras nacionales contribuye poco a resolver este tipo de problemas.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Las relaciones entre el \u00d6VP y los Verdes, que forman el actual gobierno, se deterioraron durante la \u00faltima fase de la pasada legislatura.<\/p><cite>Marcelo Jenny<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Unas semanas antes de las elecciones, el \u00abPartido de la Cerveza\u00bb, un partido sat\u00edrico dirigido por Dominik Wlazny, parec\u00eda capaz de ganar esca\u00f1os. Al final, el partido se qued\u00f3 muy lejos del 4%. \u00bfC\u00f3mo se explica este mal resultado?<\/h3>\n\n\n\n<p>El caso del Partido de la Cerveza es un ejemplo t\u00edpico de los problemas a los que se enfrentan los partidos peque\u00f1os, que a menudo caen v\u00edctimas de la l\u00f3gica del \u00abvoto \u00fatil\u00bb en las semanas previas a las elecciones. El Partido Comunista de Austria (KP\u00d6) sufri\u00f3 un destino similar: tras unos buenos resultados en las elecciones locales, los comunistas podr\u00edan haber entrado en el Consejo Nacional, pero tambi\u00e9n fracasaron. La candidatura del Partido de la Cerveza hab\u00eda proporcionado una forma de entretenimiento durante la campa\u00f1a electoral. Pero el partido tuvo que enfrentarse a una cobertura medi\u00e1tica muy cr\u00edtica, y tuvo dificultades para confeccionar sus listas y desarrollar posiciones concretas. Esto hizo que los votantes potenciales se preguntaran por qui\u00e9n estaban votando. Si el Partido de la Cerveza y el KP\u00d6 hubieran unido sus fuerzas, probablemente habr\u00edan alcanzado juntos la marca del 4% y, por tanto, habr\u00edan logrado entrar en el Parlamento. En lugar de eso, decidieron seguir caminos separados.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/R7tDO\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfPodemos establecer un paralelismo entre <a href=\"https:\/\/legrandcontinent.eu\/es\/2024\/03\/24\/que-significa-la-afd-en-alemania-una-conversacion-con-johann-chapoutot\/\">el \u00e9xito de la AfD en el Este<\/a> y la victoria electoral del FP\u00d6? Tanto en Austria como en Alemania, las recientes elecciones se han caracterizado por un aumento de la participaci\u00f3n, un debilitamiento de los Verdes y transferencias significativas de los no votantes a la extrema derecha.<\/h3>\n\n\n\n<p>No creo que estemos ante el mismo fen\u00f3meno en Alemania del Este que en Austria. <a href=\"https:\/\/legrandcontinent.eu\/es\/2024\/09\/30\/austria-que-es-el-fpo-historia-y-perspectivas-del-partido-de-extrema-derecha-que-acaba-de-ganar-las-elecciones-parlamentarias\/\">El populismo de derecha austriaco tiene una historia mucho m\u00e1s larga que el de la AfD; el FP\u00d6 es uno de los partidos populistas de derecha m\u00e1s antiguos de Europa<\/a>. La AfD se inspir\u00f3 m\u00e1s en el FP\u00d6 que viceversa, y el FP\u00d6 no necesit\u00f3 el impulso de toda Europa para ganar puntos y reclamar una parte del gobierno. Tras un regreso sorprendentemente r\u00e1pido tras el esc\u00e1ndalo de corrupci\u00f3n conocido como \u00abasunto Ibiza\u00bb o <em>Ibizagate<\/em>, el FP\u00d6 logr\u00f3 esta vez unos resultados hist\u00f3ricos a nivel federal.<\/p>\n\n\n\n<p>Es cierto que la participaci\u00f3n ha sido ligeramente superior a la de 2019, con un aumento de alrededor del 2.4%. Pero entre los antiguos abstencionistas que han votado este a\u00f1o tambi\u00e9n hab\u00eda muchos antiguos votantes del FP\u00d6 que se hab\u00edan distanciado de su partido en la situaci\u00f3n de crisis que sigui\u00f3 al asunto de Ibiza. A pesar de abstenerse en 2019, segu\u00edan siendo simpatizantes del FP\u00d6.<\/p>\n\n\n\n<p>Esta vez, fueron los Verdes los que perdieron votantes tras el affaire \u2014de naturaleza completamente distinta\u2014 que rode\u00f3 a su cabeza de lista en las elecciones europeas, Lena Schilling, acusada de denigraci\u00f3n y calumnias. Los Verdes tambi\u00e9n sufrieron p\u00e9rdidas despu\u00e9s de que su antigua portavoz nacional y regional, Madeleine Petrovic, decidiera crear su propia lista electoral, que obtuvo el 0.6% de los votos. Durante la pandemia de Covid-19, Petrovic hab\u00eda defendido posiciones anticient\u00edficas y antivacunas.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>La candidatura del Partido de la Cerveza proporcion\u00f3 una forma de entretenimiento durante la campa\u00f1a electoral. Pero el partido tuvo que enfrentarse a una cobertura medi\u00e1tica muy cr\u00edtica.<\/p><cite>Marcelo Jenny<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Como en la mayor\u00eda de los pa\u00edses europeos, las fuerzas de extrema derecha en Austria son m\u00e1s fuertes en el campo. Pero a diferencia de Francia o Alemania del Este, el FP\u00d6 austriaco no se ha convertido en la principal fuerza en todas las zonas rurales. En muchas regiones, el \u00d6VP sigue siendo fuerte. \u00bfC\u00f3mo se explica esto?<\/h3>\n\n\n\n<p>En Austria, los L\u00e4nder desempe\u00f1an un papel importante como segundo nivel de la pol\u00edtica. Los partidos al frente de cada Land influyen en el comportamiento electoral regional. A esto se a\u00f1aden las l\u00edneas divisorias hist\u00f3ricas. Carintia, por ejemplo, siempre ha sido un basti\u00f3n del FP\u00d6; esto se explica en parte por el hecho de que Carintia es una regi\u00f3n fronteriza donde el catolicismo siempre ha sido m\u00e1s d\u00e9bil que en otras partes del pa\u00eds. En el Tirol, en cambio, ha habido tradicionalmente una relaci\u00f3n mucho m\u00e1s estrecha entre el \u00d6VP y la poblaci\u00f3n rural.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfQu\u00e9 sabemos sobre el comportamiento electoral de los distintos grupos de edad?<\/h3>\n\n\n\n<p>ORF encarg\u00f3 una encuesta detallada el d\u00eda de las elecciones. Sus resultados muestran que el FP\u00d6 tiene la mayor proporci\u00f3n de votantes entre las personas de mediana edad (35 a 59 a\u00f1os), con alrededor del 37%. Los mayores de 60 a\u00f1os son los que menos votan por el FP\u00d6; el porcentaje electoral del partido en este grupo es s\u00f3lo del 22%. La proporci\u00f3n del FP\u00d6 entre los menores de 30 a\u00f1os es intermedia, con un 27%. Tambi\u00e9n es interesante observar que la diferencia entre hombres y mujeres var\u00eda seg\u00fan el grupo de edad. Seg\u00fan la encuesta, los hombres j\u00f3venes votan por el FP\u00d6 con m\u00e1s frecuencia que las mujeres j\u00f3venes, mientras que el \u00e9xito del FP\u00d6 entre las personas mayores es ligeramente mayor entre las mujeres que entre los hombres.<\/p>\n\n\n\n<p>La sobrerrepresentaci\u00f3n de los hombres es t\u00edpica de los partidos de derecha radical, mientras que los partidos de izquierda y ecologistas suelen tener un electorado m\u00e1s femenino y joven. Pero un partido s\u00f3lo puede llegar a las cotas alcanzadas por el FP\u00d6 el domingo si es capaz de reducir el gradiente de edad, obteniendo resultados significativos en todas las generaciones.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Tras el \u00e9xito del FP\u00d6 este a\u00f1o, las consecuencias del \u00abasunto Ibiza\u00bb parecen haberse desvanecido. \u00bfLa experiencia de los esc\u00e1ndalos de corrupci\u00f3n y la cuesti\u00f3n de la integridad pol\u00edtica de los representantes electos desempe\u00f1an un papel menos importante que hace unos a\u00f1os?<\/h3>\n\n\n\n<p>Todos los partidos pol\u00edticos deben ser conscientes de que los v\u00ednculos de los votantes con sus partidos se han debilitado. Un \u00e9xito electoral no garantiza que los votantes vuelvan a votar por el mismo partido en el futuro. En aquel momento, el esc\u00e1ndalo en torno al l\u00edder del FP\u00d6, Strache, da\u00f1\u00f3 gravemente al partido. Dos a\u00f1os despu\u00e9s lleg\u00f3 el caso de corrupci\u00f3n del \u00d6VP, en el que el excanciller austriaco Sebastian Kurz y su entorno fueron acusados de malversar dinero p\u00fablico para encargar encuestas falsas con dinero p\u00fablico. En la actualidad, siguen abiertos muchos casos de corrupci\u00f3n en los que est\u00e1n implicados pol\u00edticos regionales y locales. Ning\u00fan partido puede contar ya con que su electorado lo siga apoyando en las pr\u00f3ximas elecciones, ni siquiera ante el esc\u00e1ndalo. Los electorados son demasiado m\u00f3viles para eso.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>La AfD se inspir\u00f3 m\u00e1s en el FP\u00d6 que al rev\u00e9s, y el FP\u00d6 no necesitaba una din\u00e1mica a escala europea para ganar puntos y reclamar un esca\u00f1o en el gobierno.<\/p><cite>Marcelo Jenny<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfQu\u00e9 papel desempe\u00f1ar\u00e1 el presidente federal Alexander Van der Bellen (Verdes) en los pr\u00f3ximos meses?<\/h3>\n\n\n\n<p>En el pasado, Van der Bellen ha dejado claro que no quiere que Kickl se convierta en canciller. La noche de las elecciones cit\u00f3 una serie de criterios b\u00e1sicos: \u00abel Estado de derecho, la separaci\u00f3n de poderes, los derechos humanos y de las minor\u00edas, la independencia de los medios de comunicaci\u00f3n y la pertenencia a la Uni\u00f3n Europea\u00bb son algunos de los \u00abfundamentos\u00bb que pretende proteger en la pr\u00f3xima secuencia. Resulta bastante interesante que el presidente federal desee intervenir activamente, si es necesario, en la formaci\u00f3n del futuro gobierno. Pero esta participaci\u00f3n activa del presidente s\u00f3lo se producir\u00e1, probablemente, si se vuelve a plantear la hip\u00f3tesis de una coalici\u00f3n en la que participe el FP\u00d6.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En Austria, el FP\u00d6 liderado por Herbert Kickl ha completado su metamorfosis. <\/p>\n<p>Aunque es poco probable que se una a la coalici\u00f3n de gobierno, a pesar de su primer puesto en las elecciones parlamentarias del domingo, el partido extremista est\u00e1 barajando de nuevo las cartas. \u00bfQu\u00e9 ocurrir\u00e1 a continuaci\u00f3n? <\/p>\n<p>Analizamos esta convulsi\u00f3n electoral con el especialista Marcelo Jenny.<\/p>\n","protected":false},"author":17959,"featured_media":46230,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-interviews.php","format":"standard","meta":{"_acf_changed":true,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":12,"footnotes":""},"categories":[232],"tags":[],"staff":[12],"editorial_format":[1473],"serie":[],"audience":[],"geo":[177],"class_list":["post-46175","post","type-post","status-publish","format-standard","hentry","category-elecciones","staff-francois-hublet","editorial_format-entrevistas","geo-europa"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":46230,"excerpt":"En Austria, el FP\u00d6 liderado por Herbert Kickl ha completado su metamorfosis. \r\n\r\nAunque es poco probable que se una a la coalici\u00f3n de gobierno, a pesar de su primer puesto en las elecciones parlamentarias del domingo, el partido extremista est\u00e1 barajando de nuevo las cartas. \u00bfQu\u00e9 ocurrir\u00e1 a continuaci\u00f3n? \r\n\r\nAnalizamos esta convulsi\u00f3n electoral con el especialista Marcelo Jenny.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfC\u00f3mo explicar el \u00e9xito del FP\u00d6? Autopsia de la recomposici\u00f3n pol\u00edtica en Austria por parte de la extrema derecha - El Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/es\/2024\/10\/01\/como-explicar-el-exito-del-fpo-autopsia-de-la-recomposicion-politica-en-austria-por-parte-de-la-extrema-derecha\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfC\u00f3mo explicar el \u00e9xito del FP\u00d6? Autopsia de la recomposici\u00f3n pol\u00edtica en Austria por parte de la extrema derecha - El Grand Continent\" \/>\n<meta property=\"og:description\" content=\"En Austria, el FP\u00d6 liderado por Herbert Kickl ha completado su metamorfosis.   Aunque es poco probable que se una a la coalici\u00f3n de gobierno, a pesar de su primer puesto en las elecciones parlamentarias del domingo, el partido extremista est\u00e1 barajando de nuevo las cartas. \u00bfQu\u00e9 ocurrir\u00e1 a continuaci\u00f3n?   Analizamos esta convulsi\u00f3n electoral con el especialista Marcelo Jenny.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/es\/2024\/10\/01\/como-explicar-el-exito-del-fpo-autopsia-de-la-recomposicion-politica-en-austria-por-parte-de-la-extrema-derecha\/\" \/>\n<meta property=\"og:site_name\" content=\"El Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-01T11:52:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-02T11:54:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/10\/gc-elkickl2-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"anainesfernandez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/10\/gc-elkickl2-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"anainesfernandez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/10\/01\/como-explicar-el-exito-del-fpo-autopsia-de-la-recomposicion-politica-en-austria-por-parte-de-la-extrema-derecha\/\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/2024\/10\/01\/como-explicar-el-exito-del-fpo-autopsia-de-la-recomposicion-politica-en-austria-por-parte-de-la-extrema-derecha\/\",\"name\":\"\u00bfC\u00f3mo explicar el \u00e9xito del FP\u00d6? Autopsia de la recomposici\u00f3n pol\u00edtica en Austria por parte de la extrema derecha - El Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/10\/01\/como-explicar-el-exito-del-fpo-autopsia-de-la-recomposicion-politica-en-austria-por-parte-de-la-extrema-derecha\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/10\/01\/como-explicar-el-exito-del-fpo-autopsia-de-la-recomposicion-politica-en-austria-por-parte-de-la-extrema-derecha\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/10\/SIPA_ap22907333_000071-scaled-1.jpg\",\"datePublished\":\"2024-10-01T11:52:42+00:00\",\"dateModified\":\"2024-10-02T11:54:56+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/570398dd8da37ba5d66dec6d242bd33c\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/10\/01\/como-explicar-el-exito-del-fpo-autopsia-de-la-recomposicion-politica-en-austria-por-parte-de-la-extrema-derecha\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/es\/2024\/10\/01\/como-explicar-el-exito-del-fpo-autopsia-de-la-recomposicion-politica-en-austria-por-parte-de-la-extrema-derecha\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/10\/01\/como-explicar-el-exito-del-fpo-autopsia-de-la-recomposicion-politica-en-austria-por-parte-de-la-extrema-derecha\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/10\/SIPA_ap22907333_000071-scaled-1.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/10\/SIPA_ap22907333_000071-scaled-1.jpg\",\"width\":1707,\"height\":2560,\"caption\":\"Herbert Kickl, l\u00edder del FP\u00d6, se ajusta los lentes en el estudio de la radiotelevisi\u00f3n nacional en el edificio del Parlamento en Viena, Austria, domingo 29 de septiembre de 2024. \u00a9 AP Foto\/Andreea Alexandru\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/10\/01\/como-explicar-el-exito-del-fpo-autopsia-de-la-recomposicion-politica-en-austria-por-parte-de-la-extrema-derecha\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/legrandcontinent.eu\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfC\u00f3mo explicar el \u00e9xito del FP\u00d6? Autopsia de la recomposici\u00f3n pol\u00edtica en Austria por parte de la extrema derecha\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/\",\"name\":\"El Grand Continent\",\"description\":\"La escala pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/570398dd8da37ba5d66dec6d242bd33c\",\"name\":\"anainesfernandez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/fe25c21e6213f69a683147fabda32586?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/fe25c21e6213f69a683147fabda32586?s=96&d=mm&r=g\",\"caption\":\"anainesfernandez\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfC\u00f3mo explicar el \u00e9xito del FP\u00d6? Autopsia de la recomposici\u00f3n pol\u00edtica en Austria por parte de la extrema derecha - El Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/es\/2024\/10\/01\/como-explicar-el-exito-del-fpo-autopsia-de-la-recomposicion-politica-en-austria-por-parte-de-la-extrema-derecha\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfC\u00f3mo explicar el \u00e9xito del FP\u00d6? Autopsia de la recomposici\u00f3n pol\u00edtica en Austria por parte de la extrema derecha - El Grand Continent","og_description":"En Austria, el FP\u00d6 liderado por Herbert Kickl ha completado su metamorfosis.   Aunque es poco probable que se una a la coalici\u00f3n de gobierno, a pesar de su primer puesto en las elecciones parlamentarias del domingo, el partido extremista est\u00e1 barajando de nuevo las cartas. \u00bfQu\u00e9 ocurrir\u00e1 a continuaci\u00f3n?   Analizamos esta convulsi\u00f3n electoral con el especialista Marcelo Jenny.","og_url":"https:\/\/legrandcontinent.eu\/es\/2024\/10\/01\/como-explicar-el-exito-del-fpo-autopsia-de-la-recomposicion-politica-en-austria-por-parte-de-la-extrema-derecha\/","og_site_name":"El Grand Continent","article_published_time":"2024-10-01T11:52:42+00:00","article_modified_time":"2024-10-02T11:54:56+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/10\/gc-elkickl2-scaled.jpg","type":"image\/jpeg"}],"author":"anainesfernandez","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/10\/gc-elkickl2-scaled.jpg","twitter_misc":{"Escrito por":"anainesfernandez","Tiempo de lectura":"12 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/es\/2024\/10\/01\/como-explicar-el-exito-del-fpo-autopsia-de-la-recomposicion-politica-en-austria-por-parte-de-la-extrema-derecha\/","url":"https:\/\/legrandcontinent.eu\/es\/2024\/10\/01\/como-explicar-el-exito-del-fpo-autopsia-de-la-recomposicion-politica-en-austria-por-parte-de-la-extrema-derecha\/","name":"\u00bfC\u00f3mo explicar el \u00e9xito del FP\u00d6? Autopsia de la recomposici\u00f3n pol\u00edtica en Austria por parte de la extrema derecha - El Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/es\/2024\/10\/01\/como-explicar-el-exito-del-fpo-autopsia-de-la-recomposicion-politica-en-austria-por-parte-de-la-extrema-derecha\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/es\/2024\/10\/01\/como-explicar-el-exito-del-fpo-autopsia-de-la-recomposicion-politica-en-austria-por-parte-de-la-extrema-derecha\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/10\/SIPA_ap22907333_000071-scaled-1.jpg","datePublished":"2024-10-01T11:52:42+00:00","dateModified":"2024-10-02T11:54:56+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/570398dd8da37ba5d66dec6d242bd33c"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/es\/2024\/10\/01\/como-explicar-el-exito-del-fpo-autopsia-de-la-recomposicion-politica-en-austria-por-parte-de-la-extrema-derecha\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/es\/2024\/10\/01\/como-explicar-el-exito-del-fpo-autopsia-de-la-recomposicion-politica-en-austria-por-parte-de-la-extrema-derecha\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/2024\/10\/01\/como-explicar-el-exito-del-fpo-autopsia-de-la-recomposicion-politica-en-austria-por-parte-de-la-extrema-derecha\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/10\/SIPA_ap22907333_000071-scaled-1.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/10\/SIPA_ap22907333_000071-scaled-1.jpg","width":1707,"height":2560,"caption":"Herbert Kickl, l\u00edder del FP\u00d6, se ajusta los lentes en el estudio de la radiotelevisi\u00f3n nacional en el edificio del Parlamento en Viena, Austria, domingo 29 de septiembre de 2024. \u00a9 AP Foto\/Andreea Alexandru"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/es\/2024\/10\/01\/como-explicar-el-exito-del-fpo-autopsia-de-la-recomposicion-politica-en-austria-por-parte-de-la-extrema-derecha\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legrandcontinent.eu\/es\/"},{"@type":"ListItem","position":2,"name":"\u00bfC\u00f3mo explicar el \u00e9xito del FP\u00d6? Autopsia de la recomposici\u00f3n pol\u00edtica en Austria por parte de la extrema derecha"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/es\/#website","url":"https:\/\/legrandcontinent.eu\/es\/","name":"El Grand Continent","description":"La escala pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/570398dd8da37ba5d66dec6d242bd33c","name":"anainesfernandez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/fe25c21e6213f69a683147fabda32586?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fe25c21e6213f69a683147fabda32586?s=96&d=mm&r=g","caption":"anainesfernandez"}}]}},"lgc_categories":[{"id":232,"name":"Elecciones","slug":"elecciones"}],"lgc_author":{"id":12,"name":"Fran\u00e7ois Hublet","slug":"francois-hublet","description":null,"first_name":null,"last_name":null,"picture":null},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/10\/SIPA_ap22907333_000071-scaled-1.jpg","width":1707,"height":2560,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/10\/SIPA_ap22907333_000071-scaled-1.jpg","width":1707,"height":2560,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/46175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/users\/17959"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/comments?post=46175"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/46175\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media\/46230"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media?parent=46175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/categories?post=46175"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/tags?post=46175"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/staff?post=46175"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/editorial_format?post=46175"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/serie?post=46175"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/audience?post=46175"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/geo?post=46175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}