{"id":39966,"date":"2024-07-20T15:25:04","date_gmt":"2024-07-20T13:25:04","guid":{"rendered":"https:\/\/legrandcontinent.eu\/es\/?p=39966"},"modified":"2024-11-08T15:12:44","modified_gmt":"2024-11-08T14:12:44","slug":"el-agustinismo-de-josh-hawley-en-las-raices-teologico-politicas-del-trumpismo","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/es\/2024\/07\/20\/el-agustinismo-de-josh-hawley-en-las-raices-teologico-politicas-del-trumpismo\/","title":{"rendered":"El agustinismo de Josh Hawley: en las ra\u00edces teol\u00f3gico-pol\u00edticas del trumpismo"},"content":{"rendered":"\n<p class=\"intro\">Entre la nueva guardia conservadora del Partido Republicano, el senador trumpista Josh Hawley, de 45 a\u00f1os, no es el m\u00e1s conocido. Sin embargo, el siguiente texto revela que es la cabeza pensante de los republicanos ultraconservadores, aquellos para los que las batallas sociales superan con creces en importancia a los programas de recuperaci\u00f3n econ\u00f3mica. <\/p>\n\n\n\n<p class=\"intro\">En este sentido, al igual que J.D. Vance, es muy representativo de una nueva generaci\u00f3n en la que el trumpismo de la raz\u00f3n o de la adhesi\u00f3n no borra el esfuerzo de reflexi\u00f3n sobre los fundamentos del <em>Grand Ole Party<\/em>. <\/p>\n\n\n\n<p class=\"intro\">Nacido en Arkansas en el seno de una familia acomodada, Josh Hawley se licenci\u00f3 en Derecho e Historia en Yale y Stanford. En 2019 se convirti\u00f3 en fiscal general de Misuri, y en 2018 fue elegido senador por el mismo estado. No es ajeno a hacer comentarios pol\u00e9micos, que le han valido indignadas condenas incluso desde fuera del campo dem\u00f3crata. Trumpista de choque, pareci\u00f3 incluso aprobar los disturbios que desembocaron en el asalto al Capitolio. Todo ello basta para caracterizarlo como un exaltado en el Congreso que, al igual que Marjorie Taylor-Green, no se detiene ante nada para histerizar el debate p\u00fablico. <\/p>\n\n\n\n<p class=\"intro\">Su \u00faltimo discurso en <a href=\"https:\/\/legrandcontinent.eu\/es\/2024\/07\/16\/descubrir-a-j-d-vance-de-ohio-a-washington-una-profesion-de-fe-nacionalista\/\">la 4\u00aa la\u00a0<em>National Conservatism Conference<\/em><\/a>, la gran fiesta de la derecha neonacionalista, demuestra algo muy distinto, ya que pone de manifiesto como pocas veces antes los fundamentos teol\u00f3gico-pol\u00edticos de la \u00abguerra cultural\u00bb que se libra entre las dos Am\u00e9ricas. Mitt Romney, republicano moderado donde los haya, reconoci\u00f3 en \u00e9l a uno de los senadores m\u00e1s inteligentes, pero tambi\u00e9n m\u00e1s cerrados al di\u00e1logo.\u00a0<\/p>\n\n\n\n<p class=\"intro\">Para Josh Hawley, los principios sobre los que los Padres Fundadores de Estados Unidos construyeron el pa\u00eds se basan, en \u00faltima instancia, en la doctrina agustiniana de las dos ciudades; redescubrir los verdaderos valores de Estados Unidos significar\u00eda, por tanto, asumir un cristianismo mesi\u00e1nico como la verdadera religi\u00f3n civil de Estados Unidos, y reivindicar el \u00abnacionalismo cristiano\u00bb como su fundamento, con un programa de tres puntos: Trabajo, Familia, Dios. Al leerlo queda claro que tal tr\u00edptico exigir\u00eda una ruptura radical con las pol\u00edticas econ\u00f3micas neoliberales del \u00faltimo medio siglo, tanto dem\u00f3cratas como republicanas, as\u00ed como una ruptura igualmente radical con el liberalismo pol\u00edtico y los derechos de las minor\u00edas, en favor de una visi\u00f3n comunitaria y organicista de la naci\u00f3n. <\/p>\n\n\n\n<p class=\"intro\">Resulta sorprendente observar que el \u00abcristianismo identitario de lealtad\u00bb de Josh Hawley tiene muchos ecos de la historia europea del nacionalismo, e incluso ecos de la vieja pol\u00e9mica francesa entre Charles Maurras y Jacques Maritain sobre el papel pol\u00edtico del cristianismo. En resumen, el discurso de Hawley es la respuesta de un Maurras estadounidense al defensor de la <em>Primac\u00eda de lo espiritual<\/em>.\u00a0<\/p>\n\n\n\n<p>Me gustar\u00eda hablarles esta tarde sobre el futuro \u2014el futuro del movimiento conservador y el futuro del pa\u00eds\u2014. Por supuesto, todo futuro tiene sus ra\u00edces en un pasado. Como habr\u00eda dicho S\u00e9neca, \u00abtodo nuevo comienzo proviene del final de otro comienzo\u00bb.<\/p>\n\n\n\n<p class=\"comment\">Esta primera referencia filos\u00f3fica (le seguir\u00e1n otras) marca de inmediato el tono de un discurso que busca ser muy intelectual. Por eso resulta interesante comentarlo.<\/p>\n\n\n\n<p>Perm\u00edtanme comenzar por el a\u00f1o 410 de Nuestro Se\u00f1or. El a\u00f1o de una ca\u00edda. Fue el a\u00f1o, tal vez lo recuerden, en que la ciudad que se cre\u00eda eterna, inmutable, invencible, la capital del mundo antiguo, <a href=\"https:\/\/legrandcontinent.eu\/es\/2024\/06\/29\/romanizar-a-los-barbaros-una-conversacion-con-giovanni-orsina\/\">Roma, se dobleg\u00f3 finalmente ante los invasores visigodos<\/a>.<\/p>\n\n\n\n<p>Con la ca\u00edda de Roma, la era del imperio y el antiguo mundo pagano llegaron a su fin de golpe.&nbsp;<\/p>\n\n\n\n<p class=\"comment\">Aqu\u00ed, Josh Hawley se permite un atajo hist\u00f3rico demasiado r\u00e1pido: por un lado, la toma de Roma en 410 por los visigodos de Alarico no puso fin al \u00abantiguo mundo pagano\u00bb, puesto que el Imperio Romano ya era oficialmente cristiano desde 392 (edicto del emperador Teodosio), y el cristianismo hab\u00eda sido la religi\u00f3n dominante desde Constantino, poco menos de un siglo antes. El saqueo de Roma por Alarico fue sin duda un acontecimiento importante, ya que era la primera vez que Roma era tomada en 800 a\u00f1os, pero no marc\u00f3 el fin del Imperio Romano de Occidente, que convencionalmente se data a partir de la deposici\u00f3n del emperador R\u00f3mulo Aug\u00fastulo en 476. Entretanto, Roma hab\u00eda vuelto a ser tomada y saqueada en 455 por los v\u00e1ndalos de Genserico. En general, los historiadores hacen actualmente m\u00e1s hincapi\u00e9 en las continuidades civilizacionales del mundo de la Antig\u00fcedad tard\u00eda (del siglo IV al VI, e incluso m\u00e1s all\u00e1) que en las rupturas repentinas inducidas por la noci\u00f3n, un tanto enga\u00f1osa, de \u00abinvasiones b\u00e1rbaras\u00bb.\u00a0<\/p>\n\n\n\n<p class=\"comment\">Por otra parte, a J. Hawley se le da muy bien realzar el efecto de dramatizaci\u00f3n.<\/p>\n\n\n\n<p>Sin embargo, el fin de Roma marc\u00f3 un principio, nuestro principio, el principio de Occidente. Mientras Roma yac\u00eda destrozada y humeante a miles de kil\u00f3metros de distancia, al otro lado del mar Tirreno, el obispo cristiano de Hipona, un tal Agust\u00edn, tomaba la pluma para describir una nueva era.<\/p>\n\n\n\n<p class=\"comment\">Agust\u00edn (354-430), obispo de Hipona, en el norte de \u00c1frica, uno de los cuatro Padres de la Iglesia latina y gran referencia intelectual del cristianismo medieval, ha seguido siendo una figura clave del pensamiento cristiano. Actualmente est\u00e1 muy de moda entre los intelectuales y pol\u00edticos conservadores estadounidenses: el senador J. D. Vance, a quien Donald Trump acaba de elegir como candidato republicano a la vicepresidencia, se convirti\u00f3 al catolicismo tras leer a San Agust\u00edn, a quien eligi\u00f3 como patr\u00f3n para su confirmaci\u00f3n. Josh Hawley se inscribe plenamente en esta din\u00e1mica.<\/p>\n\n\n\n<p>Durante miles de a\u00f1os, su visi\u00f3n ha inspirado a Occidente. Ayud\u00f3 a forjar el destino de este pa\u00eds. Llam\u00f3 a su obra \u2014su obra maestra\u2014 <em>La Ciudad de Dios<\/em>. La principal ambici\u00f3n de Agust\u00edn en este manuscrito era defender a los cristianos acusados de haber provocado la ca\u00edda de Roma.<\/p>\n\n\n\n<p class=\"comment\">Aqu\u00ed Hawley se inscribe de lleno en lo que se ha dado en llamar \u00abagustinismo pol\u00edtico\u00bb (Mons. Arquilli\u00e8re, 1934), del que se dice que constituy\u00f3 el marco conceptual subyacente a la teor\u00eda pol\u00edtica medieval, aunque se haya discutido la pertinencia de esta noci\u00f3n. Cabe se\u00f1alar que el gran inter\u00e9s de la filosof\u00eda pol\u00edtica conservadora estadounidense por la obra de Agust\u00edn no es nuevo: puede encontrarse en Hannah Arendt, Leo Strauss o Allan Bloom.<\/p>\n\n\n\n<p>Las malas lenguas dec\u00edan que la religi\u00f3n cristiana, con sus nuevas virtudes como la humildad y la servidumbre, con su glorificaci\u00f3n de las cosas comunes como el matrimonio y el trabajo, con su alabanza de los pobres de esp\u00edritu, de la gente com\u00fan y corriente, hab\u00eda ablandado el imperio y lo hab\u00eda hecho vulnerable a sus enemigos. Pero Agust\u00edn sab\u00eda que ocurr\u00eda lo contrario; que la religi\u00f3n cristiana era la \u00fanica fuerza vital que quedaba en Roma cuando se derrumb\u00f3.<\/p>\n\n\n\n<p>Agust\u00edn ve\u00eda c\u00f3mo esta religi\u00f3n se levantaba de las ruinas del viejo mundo para forjar una civilizaci\u00f3n nueva y mejor. \u00bfCu\u00e1l ser\u00eda el secreto de este nuevo orden? El amor. El amor era una gran palabra para Agust\u00edn \u2014conten\u00eda toda su ciencia pol\u00edtica\u2014. \u00abCada persona, dec\u00eda, se define por lo que ama. Toda sociedad se rige por lo que ama\u00bb.<\/p>\n\n\n\n<p>De hecho, una naci\u00f3n no es m\u00e1s, citando a Agust\u00edn, \u00abque una multitud de criaturas racionales asociadas por un acuerdo com\u00fan en cuanto a las cosas que aman\u00bb. El problema de Roma era que amaba las cosas equivocadas. Y a medida que sus afectos se corromp\u00edan, la Rep\u00fablica Romana ca\u00eda en la ruina.<\/p>\n\n\n\n<p>Roma empez\u00f3 amando la gloria y practicando la abnegaci\u00f3n. Termin\u00f3 amando el placer y practicando todas las formas de indulgencia. As\u00ed fue como Roma se pudri\u00f3 hasta la m\u00e9dula.<\/p>\n\n\n\n<p>Pero entre las ruinas de Roma, Agust\u00edn imagin\u00f3 una nueva civilizaci\u00f3n impulsada por mejores afectos. No los viejos deseos romanos de gloria y honor, sino los amores m\u00e1s fuertes de la Biblia: amor a la esposa y a los hijos, amor al trabajo, al pr\u00f3jimo y al hogar, amor a Dios.<\/p>\n\n\n\n<p class=\"comment\">\u00c9ste y los p\u00e1rrafos anteriores son un resumen bastante fiel de los primeros libros de la principal obra de Agust\u00edn, <em>La Ciudad de Dios<\/em> (<em>De civitate Dei<\/em>), que fue efectivamente una respuesta a las acusaciones paganas de que fue el abandono de los dioses tradicionales de la ciudad lo que provoc\u00f3 la ca\u00edda de Roma en el a\u00f1o 410. Agust\u00edn contrasta la concupiscencia, el amor a uno mismo, que es el principio fundador de todas las ciudades terrenales, con el amor a Dios, el principio de la ciudad celestial. Si el amor a s\u00ed mismo y a la gloria es lo que asegura el nacimiento y la perpetuaci\u00f3n de los imperios, tambi\u00e9n los socava subrepticiamente y, en una segunda etapa, es la causa de su ruina. En cambio, el amor a Dios y al pr\u00f3jimo significa que el reino de Dios y la ciudad celestial son invisibles, indistinguibles en el mundo, pero entremezclados con todas las ciudades terrenas; la ciudad de Dios fundada en el verdadero amor se dirige hacia el fin de los tiempos, donde encontrar\u00e1 por fin su plena realizaci\u00f3n.<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-full\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/07\/SIPA_sipausa30421054_000010-scaled.jpg\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"2560\"\n        data-pswp-height=\"1706\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/07\/SIPA_sipausa30421054_000010-330x220.jpg\"\r\n                media=\"(max-width:  330px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/07\/SIPA_sipausa30421054_000010-690x460.jpg\"\r\n                media=\"(max-width:  690px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/07\/SIPA_sipausa30421054_000010-990x660.jpg\"\r\n                media=\"(max-width:  990px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/07\/SIPA_sipausa30421054_000010-1340x893.jpg\"\r\n                media=\"(max-width: 1340px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/07\/SIPA_sipausa30421054_000010-1600x1067.jpg\"\r\n                media=\"(max-width: 1600px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/07\/SIPA_sipausa30421054_000010-1920x1280.jpg\"\r\n                media=\"(min-width: 1601px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/07\/SIPA_sipausa30421054_000010-125x83.jpg\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">El senador Josh Hawley habla con los medios de comunicaci\u00f3n en el Capitolio de EE.UU. en Washington, D.C., el martes 14 de mayo de 2024. \u00a9 Graeme Sloan\/Sipa EE.UU.<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<p>Aunque Agust\u00edn afirmaba que todas las naciones est\u00e1n constituidas por lo que aman, su filosof\u00eda describ\u00eda de hecho una idea totalmente nueva de la naci\u00f3n, desconocida en el mundo antiguo: un nuevo tipo de nacionalismo \u2014un nacionalismo cristiano, organizado en torno a ideales cristianos\u2014. Un nacionalismo motivado no por la conquista, sino por un prop\u00f3sito com\u00fan; unido no por el miedo, sino por el amor com\u00fan; una naci\u00f3n hecha no para los ricos o los fuertes, sino para los \u00abpobres de esp\u00edritu\u00bb, los hombres ordinarios.<\/p>\n\n\n\n<p class=\"comment\">Se trata de una torsi\u00f3n de la obra agustiniana: Agust\u00edn, que razonaba dentro de un Imperio multi\u00e9tnico, as\u00ed como en el seno de una Iglesia cat\u00f3lica de alcance universal por definici\u00f3n, no pod\u00eda conocer la idea de naci\u00f3n, que es una creaci\u00f3n muy posterior, ni tampoco la ideolog\u00eda nacionalista, a\u00fan m\u00e1s tard\u00eda, que no apareci\u00f3 hasta finales del siglo XIX.<\/p>\n\n\n\n<p>Su sue\u00f1o se ha convertido en nuestra realidad.<\/p>\n\n\n\n<p>Mil a\u00f1os despu\u00e9s de los escritos de Agust\u00edn, unos 20.000 agustinos practicantes se aventuraron a llegar a estas costas para crear una sociedad basada en sus principios. La historia los conoce como los Puritanos. Inspirados por la Ciudad de Dios, fundaron la Ciudad sobre una colina.<\/p>\n\n\n\n<p class=\"comment\">Aqu\u00ed Josh Hawley reactiva un mito en la base de la vida pol\u00edtica estadounidense a largo plazo, el mesianismo del nuevo pueblo elegido: se refiere a los 20.000 brit\u00e1nicos que acudieron a las colonias de Nueva Inglaterra durante la <em>Great Migration<\/em> (1621-1642). En su mayor\u00eda, estos <em>Pilgrim Fathers<\/em> eran protestantes puritanos estrictos (por eso Hawley tambi\u00e9n se refiere a ellos como \u00abagustinianos\u00bb, en el sentido de que en la base del protestantismo se encuentra una visi\u00f3n agustiniana radicalizada), y su mundo estaba realmente saturado de referencias b\u00edblicas: en sus propias vidas, pensaban que estaban reviviendo la historia del pueblo elegido del antiguo Israel, o de los seguidores de Cristo: la Ciudad Brillante sobre la Colina se refiere as\u00ed a la ciudad de Boston, en la que los puritanos esperaban fundar una nueva Jerusal\u00e9n, una ciudad que viviera seg\u00fan el esp\u00edritu del Evangelio.<\/p>\n\n\n\n<p class=\"comment\">Los puritanos utilizan esta expresi\u00f3n \u2014derivada de la ense\u00f1anza de la sal y la luz en el Serm\u00f3n de la Monta\u00f1a de Jes\u00fas (Mateo 5:14: \u00abVosotros sois la luz del mundo; una ciudad asentada sobre un monte no se puede esconder\u00bb)\u2014 para referirse al Boston del siglo XVII.<\/p>\n\n\n\n<p>Somos una naci\u00f3n forjada a partir de la visi\u00f3n de Agust\u00edn. Una naci\u00f3n definida por la dignidad del hombre com\u00fan, tal y como nos la otorga la religi\u00f3n cristiana; una naci\u00f3n unida por los afectos familiares expresados en la fe cristiana \u2014amor a Dios, a la familia, al pr\u00f3jimo, al hogar y a la patria\u2014.<\/p>\n\n\n\n<p>Algunos dir\u00e1n que estoy haciendo de Am\u00e9rica una naci\u00f3n cristiana. Lo estoy haciendo. Y algunos dir\u00e1n que defiendo el nacionalismo cristiano. As\u00ed es. \u00bfHay alg\u00fan otro tipo de nacionalismo que merezca la pena practicar?<\/p>\n\n\n\n<p>El nacionalismo de Roma llev\u00f3 a la sed de sangre y a la conquista; los viejos tribalismos paganos condujeron al odio \u00e9tnico. Los imperios de Oriente aplastaron al individuo, y el sangriento nativismo de la Europa de los dos \u00faltimos siglos condujo al salvajismo y al genocidio.&nbsp;<\/p>\n\n\n\n<p class=\"comment\">En los p\u00e1rrafos precedentes, Hawley contrapone el \u00abnacionalismo cristiano\u00bb, abierto e inclusivo (lo que es una contradicci\u00f3n en los t\u00e9rminos&#8230;), ya que la Iglesia o el mensaje cristiano no hacen distinci\u00f3n de etnia o cultura, a todas las dem\u00e1s formas de \u00abnacionalismo\u00bb, o incluso de organizaci\u00f3n colectiva de la sociedad, que han fracasado: el viejo paganismo de los \u00abdioses de la ciudad\u00bb ser\u00eda incapaz de pensar un verdadero universalismo, y por tanto conducir\u00eda inevitablemente a la conquista y al sometimiento violento de unos pueblos por otros; los \u00abimperios del Este\u00bb son una alusi\u00f3n al comunismo sovi\u00e9tico; el \u00abnativismo sangriento\u00bb europeo es una clara alusi\u00f3n al racismo, especialmente al nazismo. Pero es una represalia: el \u00abnativismo\u00bb en sentido estricto es una ideolog\u00eda netamente estadounidense, nacida y realizada en Estados Unidos.<\/p>\n\n\n\n<p>Pero el nacionalismo cristiano de Agust\u00edn ha sido el orgullo de Occidente. Ha sido nuestra br\u00fajula moral y nos ha proporcionado nuestros ideales m\u00e1s preciados. Pi\u00e9nsenlo: aquellos estrictos puritanos, disc\u00edpulos de Agust\u00edn, nos dieron un gobierno limitado, la libertad de conciencia y la soberan\u00eda del pueblo.<\/p>\n\n\n\n<p class=\"comment\">De nuevo una conclusi\u00f3n hist\u00f3rica precipitada: aqu\u00ed, Hawley confunde a los Pilgrim Fathers puritanos del siglo XVII con los Padres Fundadores de la Declaraci\u00f3n de Independencia estadounidense del siglo XVIII (1776). Sin embargo, esta teleolog\u00eda no es del todo irrelevante: la libertad de conciencia se convirti\u00f3 gradualmente en un valor cardinal en las Trece Colonias americanas porque all\u00ed los puritanos y los no conformistas hu\u00edan de la persecuci\u00f3n de las confesiones establecidas en Gran Breta\u00f1a (anglicanismo) como en otros lugares de Europa, aunque sus sociedades altamente teocr\u00e1ticas no dejaban lugar a la disidencia religiosa (excepto en algunas islas, como Rhode Island). Del mismo modo, los principios de organizaci\u00f3n de las comunidades congregacionalistas de Nueva Inglaterra eran mucho m\u00e1s democr\u00e1ticos que los de las sociedades europeas de la \u00e9poca.<\/p>\n\n\n\n<p>Gracias a nuestra herencia cristiana, protegemos la libertad de cada uno para practicar su culto seg\u00fan su conciencia. Gracias a nuestra tradici\u00f3n cristiana, acogemos a personas de todas las razas y or\u00edgenes \u00e9tnicos para que se unan a una naci\u00f3n constituida de amor compartido.<\/p>\n\n\n\n<p class=\"comment\">A la idea de la naci\u00f3n como comunidad de destino elegido, J. Hawley amalgama el universalismo del mensaje cristiano; pero tambi\u00e9n pasa por alto otra fuente de libertad de conciencia, garantizada por la Primera Enmienda de la Constituci\u00f3n estadounidense: el pensamiento de la Ilustraci\u00f3n, y el concepto moderno de tolerancia que se deriva de \u00e9l. Al igual que Jefferson, muchos de los \u00abPadres Fundadores\u00bb de Estados Unidos eran m\u00e1s de\u00edstas que creyentes en la revelaci\u00f3n cristiana.<\/p>\n\n\n\n<p>El nacionalismo cristiano no es una amenaza para la democracia estadounidense. Fund\u00f3 la democracia estadounidense, es decir la mejor forma de democracia jam\u00e1s concebida por el hombre: la m\u00e1s justa, la m\u00e1s libre, la m\u00e1s humana y la m\u00e1s loable.<\/p>\n\n\n\n<p>Es ahora cuando debemos recuperar los principios de nuestra tradici\u00f3n pol\u00edtica cristiana, por el bien de nuestro futuro. Esto es cierto tanto si eres cristiano como si no, tanto si perteneces a otra fe como si no perteneces a ninguna. La tradici\u00f3n pol\u00edtica cristiana es nuestra tradici\u00f3n, es la tradici\u00f3n estadounidense, es la mayor fuente de energ\u00eda e ideas de nuestra pol\u00edtica, y siempre lo ha sido. Esta tradici\u00f3n ha inspirado a conservadores y liberales, reformistas y activistas, moralistas y sindicalistas a lo largo de nuestra historia. Hoy necesitamos de nuevo esa gran tradici\u00f3n.<\/p>\n\n\n\n<p class=\"comment\">En este p\u00e1rrafo, J. Hawley traza las l\u00edneas de una lealtad identitaria al cristianismo como tradici\u00f3n pol\u00edtica espec\u00edfica de los Estados Unidos; precisa que dicha lealtad no exige la adhesi\u00f3n personal a una confesi\u00f3n cristiana, que sigue siendo una cuesti\u00f3n privada garantizada por la libertad de conciencia, pero que uno no puede llamarse estadounidense sin reconocer la inscripci\u00f3n de los Estados Unidos en la tradici\u00f3n cristiana. Esta idea no es muy diferente del papel que Charles Maurras atribu\u00eda al catolicismo en la historia de Francia.<\/p>\n\n\n\n<p>El amor que tenemos en com\u00fan y que sostiene a esta naci\u00f3n se est\u00e1 desmoronando. Y en el proceso, la propia naci\u00f3n corre el riesgo de desintegrarse.<\/p>\n\n\n\n<p>Ustedes conocen la letan\u00eda de nuestros males tan bien como yo; saben leer los signos de los tiempos.<\/p>\n\n\n\n<p>Nuestras calles son inseguras, entre otras cosas porque nuestra frontera est\u00e1 completamente abierta. Millones de inmigrantes ilegales llegan a nuestro pa\u00eds sin ning\u00fan inter\u00e9s por nuestro patrimonio com\u00fan y sin ning\u00fan compromiso con nuestros ideales compartidos.<\/p>\n\n\n\n<p>Hay muy pocos empleos estables y de calidad. Nuestra econom\u00eda ha entrado en una nueva y decadente edad de oro, en la que los empleos de la clase trabajadora desaparecen, los salarios de los trabajadores se erosionan, las familias trabajadoras y los barrios se desintegran, mientras que los miembros de la clase alta viven enclaustrados tras verjas y seguridad privada y los jefes de la econom\u00eda de libre mercado se embolsan sueldos millonarios.<\/p>\n\n\n\n<p class=\"comment\">Volvemos aqu\u00ed a un discurso pol\u00edtico mucho m\u00e1s convencional, y a una lista poco original de los problemas identificados por la derecha estadounidense: inmigraci\u00f3n masiva, inseguridad, empobrecimiento, etc.<\/p>\n\n\n\n<p>Mientras tanto, la religi\u00f3n est\u00e1 siendo expulsada de la plaza p\u00fablica. Y los fan\u00e1ticos se instalan en los campus para corear \u00abMuerte a Israel\u00bb \u2014precisamente porque desprecian la tradici\u00f3n b\u00edblica que vincula a la naci\u00f3n de Israel con nuestra Rep\u00fablica estadounidense\u2014.<\/p>\n\n\n\n<p class=\"comment\">El mesianismo del \u00abnuevo pueblo elegido\u00bb se reactiva una vez m\u00e1s, esta vez al servicio de un tema preciado de la derecha evang\u00e9lica: la defensa de la alianza con el Estado de Israel por razones pol\u00edtico-religiosas de apoyo al proyecto sionista, del que se dice que es una manifestaci\u00f3n de la voluntad divina, y la proximidad del fin de los tiempos.<\/p>\n\n\n\n<p>En la ra\u00edz de cada una de estas tendencias, y de todas ellas, hay un asalto al amor que compartimos \u2014los afectos que nos vienen de nuestra herencia cristiana\u2014.<\/p>\n\n\n\n<p>Dios, el trabajo, el pr\u00f3jimo, el hogar. Los grandes afectos de Occidente. Se est\u00e1n desintegrando ante nuestros propios ojos.<\/p>\n\n\n\n<p>\u00bfPor qu\u00e9? No es casualidad. La izquierda moderna quiere destruir las cosas que amamos en com\u00fan y sustituirlas por otras, destruir nuestros lazos comunes y sustituirlos por otra fe, disolver la naci\u00f3n tal como la conocemos y rehacerla a su imagen. Este ha sido su proyecto durante m\u00e1s de cincuenta a\u00f1os.<\/p>\n\n\n\n<p>Y, sin embargo, es la derecha la que est\u00e1 fallando a este pa\u00eds en estos momentos. Conocemos el programa de la izquierda. Esperamos esta amenaza. Y son los conservadores los que deber\u00edan estar defendiendo esta naci\u00f3n, defendiendo lo que nos hace ser una naci\u00f3n. \u00bfPero en vez de eso? En este momento de crisis, est\u00e1n demasiado ocupados avivando las brasas moribundas del neoliberalismo, con los ojos pegados a sus ejemplares de John Stuart Mill y Ayn Rand. Siguen debatiendo sobre el fusionismo y su tr\u00edptico.<\/p>\n\n\n\n<p class=\"comment\">Para los conservadores estadounidenses, el \u00abfusionismo\u00bb es la doctrina que pretende combinar la vena social y la vena tradicionalista del conservadurismo. Fue teorizada en las p\u00e1ginas de la <em>National Review<\/em> en los a\u00f1os 50 por el fil\u00f3sofo Frank Meyer (1909-1972). El \u00abtr\u00edptico\u00bb al que se refiere Hawley es la dif\u00edcil combinaci\u00f3n de libertarismo, conservadurismo social y una actitud de halc\u00f3n en pol\u00edtica exterior. Lo que pide es que el nacionalismo cristiano supere este viejo trilema.<\/p>\n\n\n\n<p>Para los conservadores, esto ya no es suficiente.<\/p>\n\n\n\n<p>En este momento de caos y crisis, la \u00fanica esperanza para los conservadores \u2014y para la naci\u00f3n\u2014 es volver a conectar con la tradici\u00f3n cristiana sobre la que sobrevive esta naci\u00f3n. Nuestra \u00fanica esperanza es renovar lo que amamos en com\u00fan.<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-full\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/07\/SIPA_01016250_000011-scaled.jpg\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"2560\"\n        data-pswp-height=\"1708\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/07\/SIPA_01016250_000011-330x220.jpg\"\r\n                media=\"(max-width:  330px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/07\/SIPA_01016250_000011-690x460.jpg\"\r\n                media=\"(max-width:  690px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/07\/SIPA_01016250_000011-990x660.jpg\"\r\n                media=\"(max-width:  990px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/07\/SIPA_01016250_000011-1340x894.jpg\"\r\n                media=\"(max-width: 1340px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/07\/SIPA_01016250_000011-1600x1067.jpg\"\r\n                media=\"(max-width: 1600px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/07\/SIPA_01016250_000011-1920x1281.jpg\"\r\n                media=\"(min-width: 1601px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/07\/SIPA_01016250_000011-125x83.jpg\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">Josh Hawley asiste a una audiencia del Comit\u00e9 Judicial del Senado de Estados Unidos sobre el derecho al voto en el Capitolio en Washington, Estados Unidos, 20 de abril de 2021. \u00a9 Evelyn Hockstein \/ Pool v\u00eda CNP<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<p>Hoy no necesitamos la ideolog\u00eda de Rand, Mill o Milton Friedman. Necesitamos la visi\u00f3n de Agust\u00edn.<\/p>\n\n\n\n<p class=\"comment\">J. Hawley ofrece una amplia cr\u00edtica de las pol\u00edticas aplicadas por el Partido Republicano desde Ronald Reagan y el \u00abgiro neoliberal\u00bb de los a\u00f1os ochenta: para Hawley, el economicismo del que se dice que da testimonio este \u00faltimo partido deriva en \u00faltima instancia de las filosof\u00edas utilitaristas, de las que John Stuart Mill (1806-1873) es uno de los padres fundadores, y Ayn Rand (1905-1982) una versi\u00f3n popularizada y radicalizada que tambi\u00e9n es muy antirreligiosa. Milton Friedman (1912-2006), m\u00e1ximo exponente del neoliberalismo en la teor\u00eda econ\u00f3mica, tambi\u00e9n se ve descartado. La cr\u00edtica de J. Hawley se acerca mucho al movimiento paleoconservador, que subordina el liberalismo econ\u00f3mico a la defensa de los valores familiares tradicionales dentro de una sociedad org\u00e1nica.<\/p>\n\n\n\n<p>Para el futuro, para salvar a este pa\u00eds, \u00e9sa debe ser nuestra misi\u00f3n: defender el amor que une a nuestro pa\u00eds; que nos hace ser un pa\u00eds \u2014defender el trabajo del hombre ordinario, su hogar y su religi\u00f3n\u2014.<\/p>\n\n\n\n<p>Me temo que mis colegas republicanos han sido v\u00edctimas de un malentendido.&nbsp;<\/p>\n\n\n\n<p>La estrategia de la izquierda, su objetivo primordial, no es simplemente frenar nuestra econom\u00eda mediante la regulaci\u00f3n. Tampoco es aumentar el peso del gobierno \u2014la concentraci\u00f3n de poder es s\u00f3lo una peque\u00f1a parte de su agenda\u2014.<\/p>\n\n\n\n<p class=\"comment\">Aqu\u00ed, son los \u00abconservadores fiscales\u00bb y luego los libertarios los que est\u00e1n en el punto de mira: para Hawley, a diferencia de ellos, el crecimiento del Estado federal no es el principal peligro, sino un efecto delet\u00e9reo del programa de la izquierda.<\/p>\n\n\n\n<p>El principal objetivo de la izquierda es atacar nuestra unidad espiritual y las cosas que amamos en com\u00fan. Quiere destruir los afectos que nos unen y sustituirlos por una serie de ideales totalmente distintos.<\/p>\n\n\n\n<p>La izquierda predica su propio evangelio: un credo de interseccionalidad que implicar\u00eda la liberaci\u00f3n de la tradici\u00f3n, de la familia, del sexo biol\u00f3gico y, por supuesto, de Dios. Considera la fe de nuestros padres como un grillete que hay que romper \u2014y nuestra herencia moral com\u00fan como un motivo de arrepentimiento\u2014.<\/p>\n\n\n\n<p class=\"comment\">Hawley sabe que un poderoso tema movilizador es el ataque a lo que \u00e9l identifica como un proyecto oculto de la izquierda, que residir\u00eda en las llamadas luchas sociales woke (teniendo en cuenta los impensados coloniales y el \u00abracismo estructural\u00bb, la interseccionalidad de las luchas, la pol\u00edtica de g\u00e9nero, etc.). Para \u00e9l, \u00e9sta es la amenaza fundamental, que identifica como un rechazo global de la herencia y, por tanto, una disoluci\u00f3n de la naci\u00f3n, aunque la unidad de estas diversas reivindicaciones \u00abwoke\u00bb no parezca evidente.\u00a0<\/p>\n\n\n\n<p class=\"comment\">Como se ha se\u00f1alado, podr\u00eda argumentarse a cambio que estas manifestaciones son quiz\u00e1s menos antirreligiosas en esencia que herederas ellas mismas de los diversos renacimientos pietistas de la historia estadounidense, aunque s\u00f3lo sea a la manera de \u00abideas cristianas que se han enloquecido\u00bb (G. K. Chesterton): no son menos producto de la historia estadounidense que su propuesta de \u00abnacionalismo cristiano\u00bb.<\/p>\n\n\n\n<p>En lugar de la Navidad, les gustar\u00eda un \u00abMes del Orgullo\u00bb. En lugar de la oraci\u00f3n en las escuelas, adoran la bandera trans. Diversidad, equidad e inclusi\u00f3n son sus consignas, su nueva sant\u00edsima trinidad.<\/p>\n\n\n\n<p class=\"comment\">Hawley est\u00e1 jugando a fondo la \u00abguerra cultural\u00bb entre una izquierda \u00abwoke\u00bb y una derecha ultraconservadora, a trav\u00e9s de sus cr\u00edticas a los derechos LGBT y a los departamentos DEI (Diversity, Equity, Inclusion) de las administraciones, nuevo tema de predilecci\u00f3n de la derecha.<\/p>\n\n\n\n<p>Y esperan que se respete su pr\u00e9dica. Pueden hablar de tolerancia, pero son fundamentalistas. Los que se resisten son tachados de deplorables. A los que cuestionan se les tacha de amenazas a la democracia.<\/p>\n\n\n\n<p class=\"comment\">Alusi\u00f3n clara a las palabras de Hillary Clinton durante la campa\u00f1a de 2016, muy se\u00f1aladas y estigmatizadas como marcas del desprecio de clase.<\/p>\n\n\n\n<p>Por eso los progresistas tienen hoy tan poca paciencia con los trabajadores, demasiado apegados a las viejas costumbres, a la vieja fe en Dios, la familia, la patria y la naci\u00f3n.<\/p>\n\n\n\n<p>Esta es la verdadera teor\u00eda de la izquierda del Gran Reemplazo, su verdadero programa: reemplazar los ideales cristianos sobre los que se fund\u00f3 nuestra naci\u00f3n y silenciar a los estadounidenses que todav\u00eda se atreven a defenderlos.<\/p>\n\n\n\n<p class=\"comment\">Esta vez una alusi\u00f3n a la teor\u00eda del Gran Reemplazo de Renaud Camus, importada al otro lado del Atl\u00e1ntico por la ultraderecha; pero para Hawley, el propio \u00abpeligro migratorio\u00bb es secundario frente a la cuesti\u00f3n de los valores.<\/p>\n\n\n\n<p>Por desgracia, el Partido Republicano de los \u00faltimos 30 a\u00f1os ha sido incapaz de resistir este embate. En lugar de defender los afectos que nos unen, los republicanos de la era Bush-Romney han defendido la econom\u00eda libertariana y los intereses corporativos. Su fe en el feminismo se convirti\u00f3 en un mantra: el dinero primero, las personas despu\u00e9s.<\/p>\n\n\n\n<p>En nombre del \u00abmercado\u00bb, estos republicanos aplaudieron los recortes de impuestos a las empresas y la reducci\u00f3n de las barreras comerciales, y luego vieron c\u00f3mo esas mismas empresas externalizaban puestos de trabajo estadounidenses al extranjero y utilizaban los beneficios para contratar a expertos en DEI.<\/p>\n\n\n\n<p>En nombre del capitalismo, estos republicanos cantaban las alabanzas de la integraci\u00f3n global mientras Wall Street apostaba contra la industria estadounidense y compraba viviendas individuales, de modo que una vez que los bancos le quitaban el trabajo al trabajador, \u00e9ste ya no pod\u00eda permitirse comprar una casa para su familia. Despu\u00e9s, Wall Street hundi\u00f3 la econom\u00eda mundial \u2014repetidamente\u2014 y el mercado inmobiliario, y esos mismos republicanos siguieron con sus alabanzas. Y subvencionando.<\/p>\n\n\n\n<p>Todo era simplemente <em>too big to fail<\/em>.<\/p>\n\n\n\n<p>Estos republicanos olvidaron que la econom\u00eda trata ante todo de las personas y de lo que aman. Se trata de mantener a una familia. Se trata de la independencia personal. Se trata de tener un hogar y un trabajo que te hagan sentir orgulloso.<\/p>\n\n\n\n<p>Se podr\u00eda decir lo siguiente: el libre mercado s\u00f3lo es \u00fatil en la medida en que apoya las cosas que amamos juntos. De lo contrario, no es m\u00e1s que un beneficio fr\u00edo.<\/p>\n\n\n\n<p class=\"comment\">Aqu\u00ed y en los p\u00e1rrafos anteriores, otro verso antieconomicista: Hawley se sit\u00faa muy h\u00e1bilmente del lado de la \u00abgente corriente\u00bb, a nivel humano, y critica el neoliberalismo y el \u00abwokitalismo\u00bb en nombre de los valores cristianos, en un discurso moral que casi suena a arm\u00f3nicas de izquierda.<\/p>\n\n\n\n<p>En cierto sentido, los republicanos se han enamorado del beneficio por el beneficio mismo. Y parecen casi avergonzados de que sus votantes m\u00e1s comprometidos y fiables sean creyentes.<\/p>\n\n\n\n<p>Seamos sinceros. En el tr\u00edptico fusionista \u2014conservadores religiosos, libertarios y halcones de la seguridad nacional\u2014 siempre han sido los religiosos los que han aportado los votos. Y es nuestra tradici\u00f3n religiosa compartida la que ha transmitido las ideas m\u00e1s convincentes del conservadurismo \u2014gobierno constitucional, libertad individual o derechos de los trabajadores\u2014.<\/p>\n\n\n\n<p class=\"comment\">Tambi\u00e9n aqu\u00ed se expresa claramente la preferencia por los \u00abconservadores religiosos\u00bb tradicionales, a los que se considera los favoritos de una farsa electoral que s\u00f3lo beneficiar\u00eda a los otros dos componentes de los republicanos, los \u00ablibertarios\u00bb y los \u00abneoconservadores\u00bb. La ret\u00f3rica populista de Hawley enfrenta a la base electoral del Partido Republicano con sus l\u00edderes, a la manera de Trump.<\/p>\n\n\n\n<p>A\u00fan hoy, los estadounidenses que van a la iglesia, est\u00e1n casados y tienen hijos \u2014ya sean blancos, hispanos, asi\u00e1ticos u otros\u2014 son la columna vertebral del Partido Republicano. Si los republicanos tienen futuro, es gracias a ellos.<\/p>\n\n\n\n<p class=\"comment\">Un claro indicio de que el \u00abnacionalismo cristiano\u00bb de Hawley no es ni racismo ni nativismo, aunque la ausencia de menci\u00f3n alguna a negros o indios pueda resultar sorprendente (\u00bfun retorno de lo reprimido?).<\/p>\n\n\n\n<p>Y son precisamente estas personas las que el partido m\u00e1s a menudo da por sentadas y a las que peor sirve.<\/p>\n\n\n\n<p>Hay que reconocerle a la izquierda que, al menos, sabe que es el pueblo el que hace la pol\u00edtica y recompensa a su electorado \u2014testigo de ello es la bandera transg\u00e9nero en todos los edificios federales y el dinero federal que se vierte en proyectos contra el cambio clim\u00e1tico\u2014.<\/p>\n\n\n\n<p>\u00bfPero los republicanos? Est\u00e1n dando a sus votantes la elecci\u00f3n de Hobson, es decir, una alternativa que no es tal. B\u00e1sicamente, la gente tiene que elegir entre el globalismo de impuestos altos y regulaci\u00f3n alta de la izquierda y el globalismo de impuestos ligeramente m\u00e1s bajos y regulaci\u00f3n ligeramente m\u00e1s baja de la derecha. Una elecci\u00f3n entre el liberalismo social agresivo de la izquierda y el liberalismo social acomodaticio de la derecha.<\/p>\n\n\n\n<p class=\"comment\">Aqu\u00ed encontramos una constante en el discurso (ultra)conservador: la izquierda sabe afirmar sus propios valores, mientras que la derecha siempre est\u00e1 \u00abavergonzada\u00bb y abochornada por los suyos.<\/p>\n\n\n\n<p>Y los republicanos se preguntan por qu\u00e9 s\u00f3lo han conseguido ganar el voto popular dos veces en las \u00faltimas nueve elecciones presidenciales.<\/p>\n\n\n\n<p>Necesitan un punto de anclaje. Necesitan un futuro que ofrecer a nuestro pa\u00eds. Y para los conservadores que quieren salvar esta rep\u00fablica, s\u00f3lo hay un lugar donde situarse y una visi\u00f3n que ofrecer: la tradici\u00f3n cristiana del nacionalismo que nos une.<\/p>\n\n\n\n<p>Trabajo, familia y Dios. Estas son las tres formas de amor que definen a Estados Unidos. Y son estos ideales los que el Partido Republicano debe defender ahora.<\/p>\n\n\n\n<p class=\"comment\">Un lector europeo podr\u00eda ver esto como una fusi\u00f3n del lema de Vichy \u00abTrabajo, Familia, Patria\u00bb, y el lema nacionalcat\u00f3lico \u00abDios, Familia, Patria\u00bb, recientemente adoptado por G. Meloni o J. Bolsonaro. Pero no es seguro que J. Hawley tenga en mente todas estas referencias.<\/p>\n\n\n\n<p>Los republicanos pueden empezar por defender el trabajo del hombre ordinario. En la elecci\u00f3n entre trabajo y capital, entre dinero y personas, es hora de que los republicanos vuelvan a sus ra\u00edces cristianas y nacionalistas y empiecen a poner al trabajador en primer lugar.<\/p>\n\n\n\n<p>El Partido Republicano de los a\u00f1os 90 hizo todo lo posible para favorecer a las clases adineradas. Adaptando las pol\u00edticas p\u00fablicas en su beneficio. Relajando el c\u00f3digo fiscal. Elogiando su actitud. Piensen en toda la ret\u00f3rica sobre los recortes del impuesto de sociedades. Piensen en toda la ret\u00f3rica sobre la asignaci\u00f3n eficiente de los recursos. Todo significaba m\u00e1s beneficios para Wall Street.<\/p>\n\n\n\n<p>Mientras tanto, los trabajadores fueron abandonados a su suerte: vieron cerrar sus f\u00e1bricas, estancarse sus salarios, dispararse sus hipotecas y desplomarse el valor de sus viviendas. Tuvieron que explicar a sus hijos por qu\u00e9 ten\u00edan que abandonar el hogar en el que hab\u00edan crecido, por qu\u00e9 ya no pod\u00edan ir al m\u00e9dico mientras sus padres trataban de encontrar trabajo.<\/p>\n\n\n\n<p>A todo esto, los republicanos respondieron que estaba en la naturaleza de las cosas.<\/p>\n\n\n\n<p>S\u00f3lo quiero se\u00f1alar que \u00e9sta no es la tradici\u00f3n nacionalista y cristiana de este pa\u00eds.<\/p>\n\n\n\n<p>Abraham Lincoln lo dijo mejor cuando afirm\u00f3 que \u00abel capital no es m\u00e1s que el <em>fruto<\/em> del trabajo, que es superior al capital y merece mayor consideraci\u00f3n\u00bb.<\/p>\n\n\n\n<p>Theodore Roosevelt habl\u00f3 en nombre de esta misma tradici\u00f3n cuando dijo: \u00abEstoy a favor de los negocios, s\u00ed. Pero estoy primero por el hombre \u2014y por los negocios como sustitutos del hombre\u2014\u00bb.<\/p>\n\n\n\n<p class=\"comment\">En este p\u00e1rrafo y en los anteriores se vuelven a escuchar las mismas arm\u00f3nicas de izquierda, sobre las personas antes que el dinero, las vidas antes que los beneficios y, en definitiva, el trabajo antes que el capital. Tal discurso se nutre de varias fuentes: en primer lugar, una tradici\u00f3n de socialcristianismo, alimentada por la doctrina social de la Iglesia, que concede protecci\u00f3n a los trabajadores y rechaza la b\u00fasqueda desenfrenada de beneficios; pero tambi\u00e9n una tradici\u00f3n propiamente de extrema derecha, m\u00e1s corporativista, que pretende defender los derechos de los trabajadores frente a las finanzas an\u00f3nimas, los c\u00edrculos empresariales, etc. Es esta \u00faltima tradici\u00f3n la que puede tener connotaciones antisemitas.<\/p>\n\n\n\n<p class=\"comment\">Tambi\u00e9n hay que se\u00f1alar que Josh Hawley escribi\u00f3 una biograf\u00eda de Theodore Roosevelt cuando era estudiante de Derecho en Yale.<\/p>\n\n\n\n<p>Ese es el esp\u00edritu.<\/p>\n\n\n\n<p>El Partido Republicano del ma\u00f1ana, un partido que sea capaz de unir a la naci\u00f3n, debe anteponer las personas al dinero. Y la forma de hacerlo es anteponer los intereses de los trabajadores.<\/p>\n\n\n\n<p>El mayor reto econ\u00f3mico de nuestro tiempo no es la deuda, el d\u00e9ficit o el valor del d\u00f3lar \u2014es el asombroso n\u00famero de hombres sanos que no tienen un trabajo de calidad\u2014.<\/p>\n\n\n\n<p>Para darles trabajo, tenemos que cambiar la pol\u00edtica.<\/p>\n\n\n\n<p>Estamos a punto de celebrar un gran debate sobre la pr\u00f3rroga de los recortes fiscales. Quiz\u00e1 deber\u00edamos empezar con esta pregunta: \u00bfpor qu\u00e9 el trabajo debe tributar m\u00e1s que el capital? No deber\u00eda ser as\u00ed. \u00bfPor qu\u00e9 las familias deben tener menos desgravaciones fiscales que las empresas? Las familias deben ser siempre lo primero.<\/p>\n\n\n\n<p>Hace siglos que no se oye la palabra \u00abusura\u00bb. Sin embargo, ha ocupado a muchos pensadores cristianos a lo largo de los a\u00f1os, y deber\u00eda ocuparnos de nuevo. No hay ninguna raz\u00f3n por la que deba permitirse a las empresas de tarjetas de cr\u00e9dito o a los bancos que las apoyan cobrar a los trabajadores un inter\u00e9s del 30% al 40%. Ning\u00fan beneficio en el mundo puede justificar este tipo de extorsi\u00f3n. Ninguna cantidad de dinero puede excusar que se saque provecho del sufrimiento ajeno. Los tipos de inter\u00e9s de las tarjetas de cr\u00e9dito deber\u00edan estar limitados por ley.<\/p>\n\n\n\n<p class=\"comment\">Aqu\u00ed Hawley retoma las antiguas condenas cristianas de la usura, por ejemplo en la Edad Media por parte de escol\u00e1sticos como Tom\u00e1s de Aquino. Rechaza los tipos de inter\u00e9s usureros que privar\u00edan a los trabajadores de su medio de vida. En esto se acerca a las ideas de Ren\u00e9 de La Tour du Pin (1834-1924), que hizo de puente entre el catolicismo social y el maurrasismo en Francia.<\/p>\n\n\n\n<p>Es hora de que los republicanos se unan a los sindicatos de trabajadores. No hablo de sindicatos gubernamentales o del sector p\u00fablico, sino de sindicatos que defienden a los trabajadores y a sus familias.<\/p>\n\n\n\n<p>He estado en los piquetes de los <em>Teamsters<\/em>. Vot\u00e9 a favor de la sindicalizaci\u00f3n de Amazon. Apoy\u00e9 la huelga de los ferroviarios y la de los trabajadores del autom\u00f3vil. Y estoy orgulloso de ello.<\/p>\n\n\n\n<p>En lo que respecta a las empresas \u00abwoke\u00bb, solo dir\u00e9 lo siguiente: si quieren cambiar las prioridades de las empresas estadounidenses, que vuelvan a rendir cuentas a los trabajadores estadounidenses. Devuelvan el poder a los trabajadores y cambiar\u00e1n las prioridades del capital.<\/p>\n\n\n\n<p class=\"comment\">Este \u00faltimo mandato sit\u00faa todo el marco del pensamiento socioecon\u00f3mico de Hawley: no anticapitalismo, sino un reparto m\u00e1s justo de los frutos del capitalismo, lo que puede asimilarse a ideas corporativistas o que promueven la participaci\u00f3n de los trabajadores y el reparto de beneficios en sus empresas.<\/p>\n\n\n\n<p>Quiz\u00e1 una de las razones por las que los republicanos no han puesto al trabajador en primer lugar en los \u00faltimos a\u00f1os es que no han querido poner a la familia del trabajador en primer lugar.<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-full\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/07\/SIPA_sipausa30333618_000024-scaled.jpg\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"2560\"\n        data-pswp-height=\"1706\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/07\/SIPA_sipausa30333618_000024-330x220.jpg\"\r\n                media=\"(max-width:  330px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/07\/SIPA_sipausa30333618_000024-690x460.jpg\"\r\n                media=\"(max-width:  690px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/07\/SIPA_sipausa30333618_000024-990x660.jpg\"\r\n                media=\"(max-width:  990px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/07\/SIPA_sipausa30333618_000024-1340x893.jpg\"\r\n                media=\"(max-width: 1340px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/07\/SIPA_sipausa30333618_000024-1600x1067.jpg\"\r\n                media=\"(max-width: 1600px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/07\/SIPA_sipausa30333618_000024-1920x1280.jpg\"\r\n                media=\"(min-width: 1601px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/07\/SIPA_sipausa30333618_000024-125x83.jpg\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">El senador Josh Hawley se r\u00ede mientras habla con los medios de comunicaci\u00f3n en el Capitolio de Estados Unidos en Washington, DC, el martes 6 de diciembre de 2022. \u00a9 Graeme Sloan\/Sipa EE.UU.<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<p>El partido de una naci\u00f3n cristiana debe defender a la familia.<\/p>\n\n\n\n<p class=\"comment\">Esto nos lleva a la segunda parte del tr\u00edptico, el discurso familista: se supone que la familia, la \u00abunidad de base de la sociedad\u00bb, tambi\u00e9n protege contra la decadencia de las sociedades modernas. El discurso de Hawley, innegablemente conservador, es aqu\u00ed decididamente social, centr\u00e1ndose en las dificultades materiales a las que se enfrenta el estadounidense medio para fundar una familia, y haciendo menos hincapi\u00e9 en los temas provida. Cabe se\u00f1alar que parece retomar la ant\u00edfona del salario familiar (como los planes del Estado franc\u00e9s de Vichy), lo que implica que las mujeres se quedar\u00edan en casa, aunque esto no se diga expl\u00edcitamente. Hawley tambi\u00e9n parece correlacionar el trabajo de las mujeres con una ca\u00edda relativa de los ingresos familiares.<\/p>\n\n\n\n<p>Es cierto que los republicanos han hablado de la familia. Nunca han dejado de hablar de ella. Pero los republicanos como Bush rara vez se han parado un momento a preguntarse por qu\u00e9 tan pocos de sus compatriotas fundan familias. La gente feliz y esperanzada tiene hijos. Pero cada vez menos estadounidenses lo hacen. \u00bfPor qu\u00e9 cada vez menos estadounidenses tienen hijos? \u00bfPodr\u00eda ser que la econom\u00eda defendida por los republicanos \u2014la econom\u00eda globalista y corporativista que ayudaron a crear\u2014 sea mala para la familia?<\/p>\n\n\n\n<p>Hubo un tiempo en que un trabajador pod\u00eda mantener a su familia \u2014esposa e hijos\u2014 trabajando con sus propias manos. Esos d\u00edas han quedado atr\u00e1s. Hoy, los estadounidenses se afanan en empleos sin futuro, trabajando para multinacionales, mientras pagan sumas exorbitantes por la vivienda y la sanidad.<\/p>\n\n\n\n<p>No tienen familia porque no pueden permit\u00edrselo.<\/p>\n\n\n\n<p>No es de extra\u00f1ar que est\u00e9n ansiosos. No es de extra\u00f1ar que est\u00e9n deprimidos.<\/p>\n\n\n\n<p>Peor a\u00fan: los que tienen hijos no pueden permitirse estar en casa con ellos. Hoy en d\u00eda, dos padres tienen que trabajar para ganar la misma cantidad de dinero, con el mismo poder adquisitivo que proporcionaba un solo salario hace 50 a\u00f1os. Las guarder\u00edas p\u00fablicas forman la visi\u00f3n del mundo de nuestros hijos. Las pantallas ense\u00f1an a nuestros hijos a valorarse o depreciarse. Los medios de comunicaci\u00f3n y la industria publicitaria informan su sentido del bien y del mal.<\/p>\n\n\n\n<p>\u00bfQuieren dar prioridad a la familia? Faciliten la maternidad. Y devuelvan a mam\u00e1 y pap\u00e1 a casa. Hagan de la pol\u00edtica de este pa\u00eds una pol\u00edtica de salario familiar para los trabajadores estadounidenses \u2014un salario que permita a un hombre mantener a su familia y a un matrimonio criar a sus hijos como mejor les parezca\u2014.<\/p>\n\n\n\n<p>Porque la verdadera medida de la fortaleza estadounidense es el florecimiento del hogar y la familia.<\/p>\n\n\n\n<p>Los conservadores deben defender la religi\u00f3n del hombre com\u00fan.<\/p>\n\n\n\n<p>De todos los afectos que unen a una sociedad, ninguno es m\u00e1s poderoso que el afecto religioso \u2014una visi\u00f3n compartida de la verdad trascendente\u2014.<\/p>\n\n\n\n<p>Cuando nuestras cabezas pensantes se dignan reconocer la religi\u00f3n, suelen insistir en que es la libertad religiosa lo que une a los estadounidenses. En sentido estricto, esto no es cierto. La religi\u00f3n une a los estadounidenses, y \u00e9sa es la raz\u00f3n principal por la que la libertad de practicarla es tan importante.<\/p>\n\n\n\n<p class=\"comment\">En la \u00faltima parte del tr\u00edptico, dedicada a los valores religiosos, Hawley da un sutil giro: de la \u00ablibertad religiosa\u00bb consagrada en la Constituci\u00f3n estadounidense, y de hecho un valor cardinal en Estados Unidos, a una celebraci\u00f3n de la \u00abreligi\u00f3n\u00bb (que no se define, aunque s\u00f3lo se d\u00e9 a entender la religi\u00f3n cristiana) como principio efectivo de la vida en comunidad. Ahora bien, si la libertad religiosa es realmente la libertad de practicar la propia religi\u00f3n, tambi\u00e9n implica la libertad de cambiar de religi\u00f3n o de no tenerla, un punto sobre el que Hawley no dice nada aqu\u00ed.<\/p>\n\n\n\n<p>Todas las grandes civilizaciones conocidas han nacido de una gran religi\u00f3n. La nuestra no es diferente. Aunque los expertos llevan d\u00e9cadas diciendo a los estadounidenses que la religi\u00f3n les divide, destruye la paz civil, les empuja fuera de sus l\u00edmites, la mayor\u00eda de ellos comparten convicciones religiosas amplias y fundamentales: te\u00edstas, b\u00edblicas, cristianas.<\/p>\n\n\n\n<p class=\"comment\">Una vez m\u00e1s, pasamos aqu\u00ed de los juicios de hecho a los juicios de derecho: en efecto, la sociedad estadounidense (hoy en d\u00eda y m\u00e1s a\u00fan en la \u00e9poca de los Padres Fundadores) no es una sociedad laica, y Dios est\u00e1 omnipresente en el discurso p\u00fablico; pero de esta impregnaci\u00f3n impl\u00edcita del marco de referencia cristiano, parece que Hawley quiere pasar a una especie de marco normativo, que es precisamente lo que los Padres Fundadores se cuidaron de excluir, porque sab\u00edan que las cuestiones confesionales pod\u00edan dividirles de hecho. Todas las referencias religiosas y \u00abp\u00fablicas\u00bb que alega Hawley son correctas, pero no son tanto normativas como descriptivas de las creencias de sus autores.<\/p>\n\n\n\n<p>Nuestra fe nacional est\u00e1 consagrada en la Declaraci\u00f3n de Independencia: \u00abTodos los hombres son creados iguales y dotados por su Creador de derechos inalienables\u00bb.<\/p>\n\n\n\n<p>Nuestra fe nacional est\u00e1 inscrita en nuestra moneda: \u00abIn God We Trust\u00bb. El Presidente Eisenhower lo resumi\u00f3 bien cuando dijo de este lema en 1954: \u00abHe aqu\u00ed es el pa\u00eds de la libertad \u2014y el pa\u00eds que vive en el respecto por la misericordia del Todopoderoso hacia nosotros\u00bb.<\/p>\n\n\n\n<p>El consenso de las \u00e9lites sobre la religi\u00f3n es totalmente err\u00f3neo. La religi\u00f3n es uno de los grandes factores unificadores de la vida estadounidense, uno de nuestros grandes afectos comunes. Los trabajadores creen en Dios, leen la Biblia, van a la iglesia, algunos a menudo, otros no. Pero todos se ven a s\u00ed mismos como miembros de una naci\u00f3n cristiana. Y comprenden esta verdad fundamental: sus derechos proceden de Dios, no del gobierno.<\/p>\n\n\n\n<p class=\"comment\">Hawley se inscribe claramente en la tradici\u00f3n del derecho natural, muy viva en Estados Unidos; tambi\u00e9n en este caso, da valor normativo a un estado de cosas de la sociedad estadounidense, mucho m\u00e1s religiosa que la francesa, por ejemplo.<\/p>\n\n\n\n<p>Los esfuerzos realizados en los \u00faltimos setenta a\u00f1os para eliminar todo vestigio de observancia religiosa de nuestra vida p\u00fablica son precisamente lo contrario de lo que necesita la naci\u00f3n. Necesitamos m\u00e1s religi\u00f3n civil, no menos. Necesitamos un reconocimiento abierto de la herencia religiosa y de la fe que une a los estadounidenses\u00bb.<\/p>\n\n\n\n<p class=\"comment\">Para Hawley, un cristianismo no confesional podr\u00eda desempe\u00f1ar el papel de \u00abreligi\u00f3n civil\u00bb en Estados Unidos. Pero, aparte del hecho de que esto ya es as\u00ed en cierto sentido, especialmente en comparaci\u00f3n con la \u00abla\u00efcit\u00e9 \u00e0 la fran\u00e7aise\u00bb, podr\u00eda objetarse que se trata de una restricci\u00f3n singular del alcance y el valor del cristianismo (de nuevo, no muy diferente del papel asignado al catolicismo por Maurras).<\/p>\n\n\n\n<p>La campa\u00f1a que busca borrar la religi\u00f3n estadounidense de la plaza p\u00fablica es simplemente una continuaci\u00f3n de la lucha de clases por otros medios: la \u00e9lite contra el hombre de la calle, la clase acomodada atea contra los trabajadores estadounidenses. Y en realidad no se trata de eliminar la religi\u00f3n, sino de sustituir una religi\u00f3n por otra.<\/p>\n\n\n\n<p class=\"comment\">Aqu\u00ed, el discurso adquiere tintes un tanto conspirativos, en el sentido de que el declive religioso observado durante las \u00faltimas d\u00e9cadas en Estados Unidos no es tanto el resultado de un supuesto desprecio de la religi\u00f3n por parte de las \u00ab\u00e9lites\u00bb, con efectos sociales limitados a fin de cuentas, como un fen\u00f3meno de secularizaci\u00f3n propio de muchas otras sociedades.\u00a0<\/p>\n\n\n\n<p class=\"comment\">Esta radicalizaci\u00f3n de las oposiciones tambi\u00e9n se pone de manifiesto cuando se equipara la \u00abreligi\u00f3n\u00bb de las \u00e9lites con una \u00abreligi\u00f3n LGBT\u00bb que sustituir\u00eda a la antigua.<\/p>\n\n\n\n<p>Toda naci\u00f3n tiene una religi\u00f3n civil. Toda naci\u00f3n tiene una unidad espiritual. La izquierda quiere una religi\u00f3n: la religi\u00f3n de la bandera del Orgullo. Nosotros queremos la religi\u00f3n de la Biblia.<\/p>\n\n\n\n<p>As\u00ed que tengo una sugerencia que hacer: retirar las banderas trans de nuestros edificios p\u00fablicos y en su lugar inscribir en cada edificio propiedad o gestionado por el gobierno federal nuestro lema nacional: \u00abIn God We Trust\u00bb.<\/p>\n\n\n\n<p>Los s\u00edmbolos son importantes.<\/p>\n\n\n\n<p>La mayor\u00eda de los estadounidenses, la mayor\u00eda de los trabajadores estadounidenses, se sienten solidarios con la fe cristiana. Creen que Dios ha bendecido a Estados Unidos; creen que Dios tiene un plan para Estados Unidos, y quieren formar parte de \u00e9l. Es esta creencia la que les da la sensaci\u00f3n de que, como escribi\u00f3 Burke, la naci\u00f3n es un \u00abv\u00ednculo entre los que viven, los que han muerto y los que nacer\u00e1n\u00bb.<\/p>\n\n\n\n<p class=\"comment\">La filosof\u00eda de Edmund Burke (1729-1797), otro gran referente del pensamiento conservador, cuestiona la naci\u00f3n y su necesaria relaci\u00f3n con la trascendencia como comunidad de destino, rompiendo con la ilusi\u00f3n del contractualismo inmediato y la autoinstituci\u00f3n de la sociedad. En este sentido, la comunidad pol\u00edtica debe necesariamente dar cabida a la religi\u00f3n como tradici\u00f3n. Es aqu\u00ed donde la visi\u00f3n de Hawley, cuando vuelve a los fundamentos del conservadurismo cl\u00e1sico, se muestra m\u00e1s articulada y h\u00e1bil.<\/p>\n\n\n\n<p>D\u00e9cadas de fallos judiciales err\u00f3neos y de propaganda de las \u00e9lites no han borrado las convicciones religiosas de los estadounidenses. Todav\u00eda no. Y esa es una de las principales razones por las que todav\u00eda tenemos una naci\u00f3n. Los conservadores deben defender nuestra religi\u00f3n nacional y su papel en nuestra vida nacional. Deben defender ese v\u00ednculo moral tan fundamental y antiguo \u2014como dijo Macaulay, \u00ablas cenizas de [nuestros] padres y los templos de [nuestro] Dios\u00bb\u2014.<\/p>\n\n\n\n<p class=\"comment\">La referencia a Macaulay (1800-1859) es tanto m\u00e1s inteligente cuanto que el fil\u00f3sofo utilitarista se utiliza aqu\u00ed a contracorriente, para defender una forma de valor trascendente.<\/p>\n\n\n\n<p>El trabajo, el hogar, Dios. Son las cosas que amamos juntos. Son las cosas que sostienen nuestra vida en com\u00fan. Nos hacen una naci\u00f3n y forman la base de nuestra unidad.<\/p>\n\n\n\n<p>Y eso es lo que significa el nacionalismo cristiano, en el sentido m\u00e1s verdadero y profundo de la palabra. No todos los ciudadanos estadounidenses son cristianos, por supuesto, y nunca lo ser\u00e1n. Pero todo ciudadano es heredero de las libertades, la justicia y el prop\u00f3sito com\u00fan que nos ofrece nuestra tradici\u00f3n b\u00edblica y cristiana.<\/p>\n\n\n\n<p class=\"comment\">En esta asimilaci\u00f3n entre valores nacionales y cristianos, tradiciones democr\u00e1ticas y agustinianas, encontramos un reflejo, al estilo estadounidense, del animado debate de los a\u00f1os 2000 sobre las \u00abra\u00edces cristianas de Europa\u00bb y su posible inclusi\u00f3n en el pre\u00e1mbulo de la \u00abConstituci\u00f3n Europea\u00bb.<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-full\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/07\/SIPA_sipausa30302637_000019-scaled.jpg\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"2560\"\n        data-pswp-height=\"1703\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/07\/SIPA_sipausa30302637_000019-330x220.jpg\"\r\n                media=\"(max-width:  330px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/07\/SIPA_sipausa30302637_000019-690x459.jpg\"\r\n                media=\"(max-width:  690px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/07\/SIPA_sipausa30302637_000019-990x659.jpg\"\r\n                media=\"(max-width:  990px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/07\/SIPA_sipausa30302637_000019-1340x891.jpg\"\r\n                media=\"(max-width: 1340px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/07\/SIPA_sipausa30302637_000019-1600x1064.jpg\"\r\n                media=\"(max-width: 1600px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/07\/SIPA_sipausa30302637_000019-1920x1277.jpg\"\r\n                media=\"(min-width: 1601px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/07\/SIPA_sipausa30302637_000019-125x83.jpg\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">Josh Hawley habla durante las audiencias del Comit\u00e9 Judicial del Senado para la nominaci\u00f3n del juez Kentanji Brown Jackson al Tribunal Supremo, en el Capitolio en Washington, D.C., el martes 22 de marzo de 2022. \u00a9 Graeme Sloan\/Sipa EE.UU.<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<p>Por esta tradici\u00f3n creemos en la libertad de expresi\u00f3n. Por eso creemos en la libertad de conciencia. Tambi\u00e9n es la raz\u00f3n por la que deploramos el virulento antisemitismo que se manifiesta en nuestras instituciones de \u00e9lite y en nuestros campus.<\/p>\n\n\n\n<p class=\"comment\">Aqu\u00ed, el concepto subyacente de \u00abcivilizaci\u00f3n judeo-cristiana\u00bb sirve para afirmar la idea de la alianza con el pueblo jud\u00edo (y por tanto la alianza estadounidense-israel\u00ed), y tambi\u00e9n ilustra la idea de una identidad cristiana intr\u00ednsecamente abierta, ya que deja espacio en su narrativa para otra comunidad. El Islam, el tercer \u00abgran monote\u00edsmo\u00bb, es una gran omisi\u00f3n en este texto, en comparaci\u00f3n con los otros dos. \u00bfSe trata de convertirlo en un adversario impl\u00edcito de los valores nacionales? La cuesti\u00f3n no es tan aguda en Estados Unidos como en Europa.<\/p>\n\n\n\n<p>Por \u00faltimo, observo que algunos de los que se autodenominan \u00abnacionalistas cristianos\u00bb ofrecen un tono diferente, un serm\u00f3n de desesperaci\u00f3n. <a href=\"https:\/\/legrandcontinent.eu\/es\/2022\/12\/31\/el-fin-del-mundo-como-utopia\/\">Suenan a fin de los tiempos<\/a>. Todo estar\u00eda perdido, nos dicen. Estados Unidos no podr\u00eda salvarse \u2014o no merecer\u00eda la pena salvarse\u2014.<\/p>\n\n\n\n<p class=\"comment\">\u00bfQui\u00e9n es el objetivo aqu\u00ed? Quiz\u00e1s las conspiraciones apocal\u00edpticas de Monse\u00f1or Vigano; quiz\u00e1s tambi\u00e9n el comunitarismo radical de Rod Dreher, el autor de <em>The Benedict Option<\/em>, que aboga por una clara separaci\u00f3n entre las peque\u00f1as comunidades cristianas y la mayor\u00eda de la sociedad entregada al mal. Esto supondr\u00eda una ruptura con los principios del agustinismo pol\u00edtico.<\/p>\n\n\n\n<p>Y desde este lugar de miedo, recomiendan pol\u00edticas aterradoras: una iglesia establecida, etnocentrismo \u2014un \u00abFranco protestante\u00bb para gobernarnos\u2014. \u00a1Qu\u00e9 estupidez!<\/p>\n\n\n\n<p class=\"comment\">Tambi\u00e9n en este caso, J. Hawley se distancia de los nacionalistas m\u00e1s extremos y rechaza todo racismo y toda idea de \u00abreligi\u00f3n de Estado\u00bb, lo que demuestra que, a pesar de su conservadurismo radical, puede incluirse en cierto modo en la tradici\u00f3n liberal estadounidense, en el sentido originalista.<\/p>\n\n\n\n<p>Esa no es nuestra tradici\u00f3n. Eso no es en lo que creemos. No dejemos que el miedo nos controle. No volvamos al nacionalismo \u00e9tnico de l\u00ednea dura del viejo mundo ni a la ideolog\u00eda autoritaria de sangre y tierra. Eso no es lo que nos ha legado la herencia cristiana. En este pa\u00eds, defendemos la libertad de todos. En esta naci\u00f3n, practicamos la autonom\u00eda del pueblo.<\/p>\n\n\n\n<p>Volvamos, en cambio, a lo que nos une, en comuni\u00f3n. La dignidad del trabajo. La santidad del hogar. El amor a la familia y a Dios.<\/p>\n\n\n\n<p>Esa es nuestra civilizaci\u00f3n. Eso es Am\u00e9rica.<\/p>\n\n\n\n<p class=\"comment\">En conclusi\u00f3n, J. Hawley vuelve al \u00abamor\u00bb, entendido en su sentido m\u00e1s inmediato (y, por tanto, capaz de hablar a los votantes ordinarios: amor a los seres queridos, al trabajo, a la bandera), como fundamento de toda comunidad pol\u00edtica. Este hilo agustiniano subraya hasta qu\u00e9 punto se ha reflexionado y articulado este verdadero curso de filosof\u00eda pol\u00edtica. Si se llevara a la pr\u00e1ctica \u2014lo que, en cierto sentido, constituye un reto, dada la vaguedad de sus aspectos pr\u00e1cticos\u2014, el programa civilizacional esbozado por Josh Hawley representar\u00eda, no obstante, una ruptura con las pr\u00e1cticas pol\u00edticas de los republicanos durante las \u00faltimas d\u00e9cadas.<\/p>\n\n\n\n<p>Las cosas que amamos en com\u00fan y sobre las que se fund\u00f3 nuestra naci\u00f3n no nos han fallado. Son tan apremiantes hoy como lo eran cuando Agust\u00edn las describi\u00f3 por primera vez. Est\u00e1n tan vivas hoy como lo estaban cuando los primeros puritanos desembarcaron en estas costas.<\/p>\n\n\n\n<p>Todo lo que tenemos que hacer es comprometernos de nuevo a defenderlas, a fortalecerlas, a reavivar nuestra devoci\u00f3n.&nbsp;<\/p>\n\n\n\n<p>Cuando lo hagamos, salvaremos a la naci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abLa campa\u00f1a que busca borrar la religi\u00f3n estadounidense de la plaza p\u00fablica es simplemente una continuaci\u00f3n de la lucha de clases por otros medios.\u00bb<\/p>\n<p>Cercana a Trump y a J.D. Vance, la figura de Josh Hawley nos sumerge en una m\u00edstica particular, a la vez conservadora y social, que encarna una nueva generaci\u00f3n de la extrema derecha estadounidense \u2014mejor articulada, mejor preparada, quiere ganar los votos de los electores pobres con un programa simple: el nacionalismo cristiano\u2014. Traducimos su \u00faltimo gran discurso y lo comentamos, p\u00e1rrafo por p\u00e1rrafo.<\/p>\n","protected":false},"author":1366,"featured_media":39967,"comment_status":"closed","ping_status":"","sticky":false,"template":"templates\/post-speeches.php","format":"standard","meta":{"_acf_changed":true,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":37,"footnotes":""},"categories":[956],"tags":[],"staff":[151],"editorial_format":[1474],"serie":[],"audience":[],"geo":[172],"class_list":["post-39966","post","type-post","status-publish","format-standard","hentry","category-trump-fuentes-intelectuales-de-una-revolucion-cultural","staff-jean-benoit-poulle","editorial_format-archivos-y-discursos","geo-americas"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":39967,"excerpt":"\u00abLa campa\u00f1a que busca borrar la religi\u00f3n estadounidense de la plaza p\u00fablica es simplemente una continuaci\u00f3n de la lucha de clases por otros medios.\u00bb\r\n\r\nCercana a Trump y a J.D. Vance, la figura de Josh Hawley nos sumerge en una m\u00edstica particular, a la vez conservadora y social, que encarna una nueva generaci\u00f3n de la extrema derecha estadounidense \u2014mejor articulada, mejor preparada, quiere ganar los votos de los electores pobres con un programa simple: el nacionalismo cristiano\u2014. Traducimos su \u00faltimo gran discurso y lo comentamos, p\u00e1rrafo por p\u00e1rrafo.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El agustinismo de Josh Hawley: en las ra\u00edces teol\u00f3gico-pol\u00edticas del trumpismo - El Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/es\/2024\/07\/20\/el-agustinismo-de-josh-hawley-en-las-raices-teologico-politicas-del-trumpismo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El agustinismo de Josh Hawley: en las ra\u00edces teol\u00f3gico-pol\u00edticas del trumpismo - El Grand Continent\" \/>\n<meta property=\"og:description\" content=\"\u00abLa campa\u00f1a que busca borrar la religi\u00f3n estadounidense de la plaza p\u00fablica es simplemente una continuaci\u00f3n de la lucha de clases por otros medios.\u00bb  Cercana a Trump y a J.D. Vance, la figura de Josh Hawley nos sumerge en una m\u00edstica particular, a la vez conservadora y social, que encarna una nueva generaci\u00f3n de la extrema derecha estadounidense \u2014mejor articulada, mejor preparada, quiere ganar los votos de los electores pobres con un programa simple: el nacionalismo cristiano\u2014. Traducimos su \u00faltimo gran discurso y lo comentamos, p\u00e1rrafo por p\u00e1rrafo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/es\/2024\/07\/20\/el-agustinismo-de-josh-hawley-en-las-raices-teologico-politicas-del-trumpismo\/\" \/>\n<meta property=\"og:site_name\" content=\"El Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-20T13:25:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-08T14:12:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/07\/gc-elhawley-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"florent\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/07\/gc-elhawley-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"florent\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"37 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/07\/20\/el-agustinismo-de-josh-hawley-en-las-raices-teologico-politicas-del-trumpismo\/\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/2024\/07\/20\/el-agustinismo-de-josh-hawley-en-las-raices-teologico-politicas-del-trumpismo\/\",\"name\":\"El agustinismo de Josh Hawley: en las ra\u00edces teol\u00f3gico-pol\u00edticas del trumpismo - El Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/07\/20\/el-agustinismo-de-josh-hawley-en-las-raices-teologico-politicas-del-trumpismo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/07\/20\/el-agustinismo-de-josh-hawley-en-las-raices-teologico-politicas-del-trumpismo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/07\/SIPA_shutterstock41134440_000001-scaled-1.jpg\",\"datePublished\":\"2024-07-20T13:25:04+00:00\",\"dateModified\":\"2024-11-08T14:12:44+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/07\/20\/el-agustinismo-de-josh-hawley-en-las-raices-teologico-politicas-del-trumpismo\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/es\/2024\/07\/20\/el-agustinismo-de-josh-hawley-en-las-raices-teologico-politicas-del-trumpismo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/07\/20\/el-agustinismo-de-josh-hawley-en-las-raices-teologico-politicas-del-trumpismo\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/07\/SIPA_shutterstock41134440_000001-scaled-1.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/07\/SIPA_shutterstock41134440_000001-scaled-1.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"El senador Josh Hawley (R-MO) asiste a la audiencia del Comit\u00e9 Judicial del Senado \\\"Big Tech y la crisis de la explotaci\u00f3n sexual infantil en l\u00ednea\\\" en el Capitolio en Washington, DC, mi\u00e9rcoles, 31 de enero de 2024. \u00a9 Bonnie Cash\/UPI\/Shutterstock\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/07\/20\/el-agustinismo-de-josh-hawley-en-las-raices-teologico-politicas-del-trumpismo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/legrandcontinent.eu\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El agustinismo de Josh Hawley: en las ra\u00edces teol\u00f3gico-pol\u00edticas del trumpismo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/\",\"name\":\"El Grand Continent\",\"description\":\"La escala pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\",\"name\":\"florent\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"caption\":\"florent\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El agustinismo de Josh Hawley: en las ra\u00edces teol\u00f3gico-pol\u00edticas del trumpismo - El Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/es\/2024\/07\/20\/el-agustinismo-de-josh-hawley-en-las-raices-teologico-politicas-del-trumpismo\/","og_locale":"es_ES","og_type":"article","og_title":"El agustinismo de Josh Hawley: en las ra\u00edces teol\u00f3gico-pol\u00edticas del trumpismo - El Grand Continent","og_description":"\u00abLa campa\u00f1a que busca borrar la religi\u00f3n estadounidense de la plaza p\u00fablica es simplemente una continuaci\u00f3n de la lucha de clases por otros medios.\u00bb  Cercana a Trump y a J.D. Vance, la figura de Josh Hawley nos sumerge en una m\u00edstica particular, a la vez conservadora y social, que encarna una nueva generaci\u00f3n de la extrema derecha estadounidense \u2014mejor articulada, mejor preparada, quiere ganar los votos de los electores pobres con un programa simple: el nacionalismo cristiano\u2014. Traducimos su \u00faltimo gran discurso y lo comentamos, p\u00e1rrafo por p\u00e1rrafo.","og_url":"https:\/\/legrandcontinent.eu\/es\/2024\/07\/20\/el-agustinismo-de-josh-hawley-en-las-raices-teologico-politicas-del-trumpismo\/","og_site_name":"El Grand Continent","article_published_time":"2024-07-20T13:25:04+00:00","article_modified_time":"2024-11-08T14:12:44+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/07\/gc-elhawley-scaled.jpg","type":"image\/jpeg"}],"author":"florent","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/07\/gc-elhawley-scaled.jpg","twitter_misc":{"Escrito por":"florent","Tiempo de lectura":"37 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/es\/2024\/07\/20\/el-agustinismo-de-josh-hawley-en-las-raices-teologico-politicas-del-trumpismo\/","url":"https:\/\/legrandcontinent.eu\/es\/2024\/07\/20\/el-agustinismo-de-josh-hawley-en-las-raices-teologico-politicas-del-trumpismo\/","name":"El agustinismo de Josh Hawley: en las ra\u00edces teol\u00f3gico-pol\u00edticas del trumpismo - El Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/es\/2024\/07\/20\/el-agustinismo-de-josh-hawley-en-las-raices-teologico-politicas-del-trumpismo\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/es\/2024\/07\/20\/el-agustinismo-de-josh-hawley-en-las-raices-teologico-politicas-del-trumpismo\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/07\/SIPA_shutterstock41134440_000001-scaled-1.jpg","datePublished":"2024-07-20T13:25:04+00:00","dateModified":"2024-11-08T14:12:44+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/es\/2024\/07\/20\/el-agustinismo-de-josh-hawley-en-las-raices-teologico-politicas-del-trumpismo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/es\/2024\/07\/20\/el-agustinismo-de-josh-hawley-en-las-raices-teologico-politicas-del-trumpismo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/2024\/07\/20\/el-agustinismo-de-josh-hawley-en-las-raices-teologico-politicas-del-trumpismo\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/07\/SIPA_shutterstock41134440_000001-scaled-1.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/07\/SIPA_shutterstock41134440_000001-scaled-1.jpg","width":2560,"height":1707,"caption":"El senador Josh Hawley (R-MO) asiste a la audiencia del Comit\u00e9 Judicial del Senado \"Big Tech y la crisis de la explotaci\u00f3n sexual infantil en l\u00ednea\" en el Capitolio en Washington, DC, mi\u00e9rcoles, 31 de enero de 2024. \u00a9 Bonnie Cash\/UPI\/Shutterstock"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/es\/2024\/07\/20\/el-agustinismo-de-josh-hawley-en-las-raices-teologico-politicas-del-trumpismo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legrandcontinent.eu\/es\/"},{"@type":"ListItem","position":2,"name":"El agustinismo de Josh Hawley: en las ra\u00edces teol\u00f3gico-pol\u00edticas del trumpismo"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/es\/#website","url":"https:\/\/legrandcontinent.eu\/es\/","name":"El Grand Continent","description":"La escala pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c","name":"florent","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","caption":"florent"}}]}},"lgc_categories":[{"id":956,"name":"Trump: fuentes intelectuales de una revoluci\u00f3n cultural","slug":"trump-fuentes-intelectuales-de-una-revolucion-cultural"}],"lgc_author":{"id":151,"name":"Jean-Beno\u00eet Poulle","slug":"jean-benoit-poulle","description":"Antiguo alumno (A\/L 2013) y titulado (2018) de la \u00c9cole normale sup\u00e9rieure de la rue d'Ulm, profesor agregado de Historia (2017), doctorando contratado en la Sorbona (2018-2022) y becario de la Fundaci\u00f3n Thiers (2022-2023), actualmente es profesor asistente en Historia Moderna en la Universidad de la Sorbona y est\u00e1 realizando su tesis doctoral bajo la direcci\u00f3n conjunta de los profesores Reynald Abad y Olivier Chaline.","first_name":"Jean-Beno\u00eet","last_name":"Poulle","picture":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2023\/09\/1600007532804.png","width":576,"height":592,"alt":""}},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/07\/SIPA_shutterstock41134440_000001-scaled-1.jpg","width":2560,"height":1707,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/07\/SIPA_shutterstock41134440_000001-scaled-1.jpg","width":2560,"height":1707,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/39966","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/users\/1366"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/comments?post=39966"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/39966\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media\/39967"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media?parent=39966"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/categories?post=39966"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/tags?post=39966"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/staff?post=39966"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/editorial_format?post=39966"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/serie?post=39966"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/audience?post=39966"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/geo?post=39966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}