{"id":33216,"date":"2024-04-15T22:53:18","date_gmt":"2024-04-15T20:53:18","guid":{"rendered":"https:\/\/legrandcontinent.eu\/es\/?p=33216"},"modified":"2024-04-15T23:06:45","modified_gmt":"2024-04-15T21:06:45","slug":"el-mundo-ante-el-ataque-de-iran-a-israel-cartografia-de-las-reacciones-mapa-exclusivo","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/es\/2024\/04\/15\/el-mundo-ante-el-ataque-de-iran-a-israel-cartografia-de-las-reacciones-mapa-exclusivo\/","title":{"rendered":"El mundo ante el ataque de Ir\u00e1n a Israel. Cartograf\u00eda de las reacciones [mapa exclusivo]"},"content":{"rendered":"\n<p><em>Desde la invasi\u00f3n de Ucrania el 24 de febrero de 2022 hasta el ataque de Ham\u00e1s el 7 de octubre de 2023, el mundo ha cambiado. Cartografiamos las fracturas tect\u00f3nicas y la recomposici\u00f3n geopol\u00edtica en curso. Decenas de millones de personas han consultado los mapas elaborados por la revista. Son accesibles a todos gracias a tu apoyo: si puedes permit\u00edrtelo, <a href=\"https:\/\/legrandcontinent.eu\/es\/ofiertas-new-1\/\" target=\"_blank\" rel=\"noreferrer noopener\">considera la posibilidad de suscribirse<\/a>.<\/em><\/p>\n\n\n\n<p class=\"has-drop-cap\">Aunque la mayor\u00eda de los pa\u00edses han pedido la desescalada y la contenci\u00f3n, observamos dos matices en su posicionamiento: un grupo que expresa su apoyo a Israel, condena el ataque y pide la desescalada; y otro que pide la contenci\u00f3n y expresa su preocupaci\u00f3n por la estabilidad regional, pero sin condenar el ataque ni apoyar a Israel.<\/p>\n\n\n\n<p>Sorprendentemente, ning\u00fan pa\u00eds expres\u00f3 expl\u00edcitamente su apoyo a Ir\u00e1n. S\u00f3lo Afganist\u00e1n, Yemen, Siria y Malasia insistieron en el derecho del pa\u00eds a la \u00ableg\u00edtima defensa\u00bb, que Teher\u00e1n reivindic\u00f3 invocando el art\u00edculo 51 de la Carta de las Naciones Unidas el s\u00e1bado 13 de abril.&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-33216' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2024\/04\/15\/el-mundo-ante-el-ataque-de-iran-a-israel-cartografia-de-las-reacciones-mapa-exclusivo\/#easy-footnote-bottom-1-33216' title='&lt;a href=&quot;https:\/\/newyork.mfa.ir\/files\/Survey\/2024041405034885681365472.pdf&quot;&gt;Ambassadors Letter to UNSC Regarding Iran\u2019s Response to Israeli Regimes Aggressions&lt;\/a&gt;, Representaci\u00f3n Permanente de la Rep\u00fablica Isl\u00e1mica de Ir\u00e1n ante las Naciones Unidas, 13 de abril de 2024.'><sup>1<\/sup><\/a><\/span><\/span><\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-large  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/1Rg01\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>En Europa, la mayor\u00eda de los Estados miembros de la Uni\u00f3n Europea expresaron su apoyo a Israel, con la excepci\u00f3n de Irlanda, uno de los pa\u00edses europeos que m\u00e1s simpatiza con la causa palestina, que s\u00f3lo pidi\u00f3 una desescalada.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Francia y el Reino Unido&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-33216' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2024\/04\/15\/el-mundo-ante-el-ataque-de-iran-a-israel-cartografia-de-las-reacciones-mapa-exclusivo\/#easy-footnote-bottom-2-33216' title='Seg\u00fan Rishi Sunak, el Reino Unido ha derribado \u00abvarios\u00bb drones iran\u00edes.'><sup>2<\/sup><\/a><\/span><\/span> \u2014y en menor medida Alemania\u2014&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-33216' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2024\/04\/15\/el-mundo-ante-el-ataque-de-iran-a-israel-cartografia-de-las-reacciones-mapa-exclusivo\/#easy-footnote-bottom-3-33216' title='Un avi\u00f3n de la Luftwaffe reabasteci\u00f3 a un caza franc\u00e9s en vuelo.'><sup>3<\/sup><\/a><\/span><\/span> se implicaron directamente en la defensa del territorio israel\u00ed. &nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-4-33216' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2024\/04\/15\/el-mundo-ante-el-ataque-de-iran-a-israel-cartografia-de-las-reacciones-mapa-exclusivo\/#easy-footnote-bottom-4-33216' title='Emmanuel Macron ha asegurado que el Ej\u00e9rcito franc\u00e9s ha ayudado a interceptar drones iran\u00edes \u00aba petici\u00f3n de Jordania\u00bb.'><sup>4<\/sup><\/a><\/span><\/span><\/li>\n\n\n\n<li>Estas posturas se reflejan tambi\u00e9n en la declaraci\u00f3n del G7, cuya presidencia italiana conden\u00f3 en\u00e9rgicamente el ataque, reiter\u00f3 su pleno apoyo a la seguridad de Israel y pidi\u00f3 la desescalada tras una reuni\u00f3n celebrada el domingo 14 de abril.&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-5-33216' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2024\/04\/15\/el-mundo-ante-el-ataque-de-iran-a-israel-cartografia-de-las-reacciones-mapa-exclusivo\/#easy-footnote-bottom-5-33216' title='&lt;a href=&quot;https:\/\/www.governo.it\/sites\/governo.it\/files\/G7_leaders_statement_20240414.pdf&quot;&gt;G7 Leaders\u2019 Statement on Iran\u2019s attack against Israel&lt;\/a&gt;.'><sup>5<\/sup><\/a><\/span><\/span><\/li>\n\n\n\n<li>La Rusia de Putin hizo un llamado a la moderaci\u00f3n, mientras que Ucrania conden\u00f3 el ataque de Ir\u00e1n por \u00abinaceptable\u00bb e \u00abirresponsable\u00bb.<\/li>\n<\/ul>\n\n\n\n<p>A nivel regional, varios funcionarios estadounidenses han indicado que Arabia Saudita y Emiratos \u00c1rabes Unidos <a href=\"https:\/\/legrandcontinent.eu\/es\/2024\/04\/15\/arabia-saudi-emiratos-y-jordania-protegen-a-israel-la-nueva-geopolitica-de-oriente-proximo-tras-el-ataque-de-iran-mapas-exclusivos\/\">desempe\u00f1aron un papel en la defensa del territorio israel\u00ed<\/a> al compartir informaci\u00f3n sobre los planes iran\u00edes con Washington y Jerusal\u00e9n.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-large  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/XbGMs\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>La mayor\u00eda de los pa\u00edses de la regi\u00f3n \u2014a excepci\u00f3n de Yemen, cuyo territorio est\u00e1 parcialmente controlado por los hut\u00edes, y L\u00edbano, cuya pol\u00edtica exterior est\u00e1 controlada por el secretario general de Hezbol\u00e1, Hassan Nasrallah\u2014 han hecho un llamado a la desescalada.<\/p>\n\n\n\n<p>En Am\u00e9rica Latina, el Brasil de Lula pidi\u00f3 \u00abm\u00e1xima contenci\u00f3n\u00bb e inst\u00f3 a la comunidad internacional a movilizar sus esfuerzos para evitar una escalada del enfrentamiento. Sin embargo, el pa\u00eds no conden\u00f3 el ataque.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La Argentina de Milei expres\u00f3 \u00absu solidaridad y compromiso inquebrantable con el Estado de Israel\u00bb. Lo mismo hicieron Paraguay y Ecuador.<\/li>\n\n\n\n<li>Las declaraciones de Colombia y Venezuela destacaron la responsabilidad de Estados Unidos y de los dirigentes de Tel Aviv: Caracas dijo que \u00abdebido al genocidio en Palestina y a la irracionalidad del r\u00e9gimen israel\u00ed, as\u00ed como a la inacci\u00f3n del sistema de Naciones Unidas, la situaci\u00f3n de inestabilidad en la regi\u00f3n ha empeorado considerablemente en las \u00faltimas semanas\u00bb.<\/li>\n\n\n\n<li>Bogot\u00e1 a\u00f1adi\u00f3 que \u00abel apoyo pr\u00e1ctico de Estados Unidos al genocidio [en Gaza] ha enardecido al mundo\u00bb.<\/li>\n<\/ul>\n\n\n\n<p>En Asia, los principales pa\u00edses musulmanes \u2014Pakist\u00e1n e Indonesia\u2014 hicieron un llamado a la contensi\u00f3n.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>En su declaraci\u00f3n, Bangladesh se centr\u00f3 en la guerra de Gaza: \u00abEsperamos que todos los pa\u00edses que deben desempe\u00f1ar un papel tomen inmediatamente medidas efectivas para resolver la tensi\u00f3n entre Ir\u00e1n e Israel y pongan fin a la masacre indiscriminada de la poblaci\u00f3n de Gaza\u00bb.<\/li>\n\n\n\n<li>Afganist\u00e1n y Malasia insistieron en el derecho de Ir\u00e1n a la \u00ableg\u00edtima defensa\u00bb.<\/li>\n\n\n\n<li>China pidi\u00f3 contenci\u00f3n, mientras que Taiw\u00e1n, Jap\u00f3n y Corea del Sur condenaron el ataque.<\/li>\n<\/ul>\n\n\n\n<p>Entre los pa\u00edses que han ratificado los Acuerdos de Abraham, Emiratos \u00c1rabes Unidos, Bahr\u00e9in y Marruecos hicieron un llamado a la contensi\u00f3n. Sud\u00e1n, al borde de la hambruna tras un a\u00f1o de guerra civil, a\u00fan no se ha pronunciado.<\/p>\n\n\n\n<p>Hasta el 7 de octubre, 12 pa\u00edses hab\u00edan declarado su apoyo a Ham\u00e1s: Venezuela, Mauritania, Argelia, T\u00fanez, Libia, Siria, Irak, Yemen, Ir\u00e1n, Nicaragua, Corea del Norte y Afganist\u00e1n.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-large  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/dGQpt\/29\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Cinco pa\u00edses han expresado su apoyo a Ir\u00e1n, subrayando el derecho del pa\u00eds a la \u00ableg\u00edtima defensa\u00bb: Afganist\u00e1n, Yemen, Siria y Malasia. Aunque Malasia se ha unido al grupo, ninguno de estos cuatro pa\u00edses reconoce a Israel.<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/1t1oC\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Venezuela, T\u00fanez e Irak hicieron hincapi\u00e9 en la necesidad de detener la guerra en Gaza.<\/li>\n\n\n\n<li>Nicaragua, Mauritania, Corea del Norte y Libia a\u00fan no se han pronunciado.<\/li>\n\n\n\n<li>Argelia hizo un llamado a la moderaci\u00f3n en el Consejo de Seguridad de las Naciones Unidas, insistiendo en las causas profundas de la escalada: \u00abla ocupaci\u00f3n israel\u00ed\u00bb y el conflicto de Gaza.<\/li>\n\n\n\n<li>Jordania, que hab\u00eda hecho un llamado a la desescalada el 7 de octubre, particip\u00f3 en la defensa del territorio israel\u00ed.<\/li>\n<\/ul>\n\n\n\n<p>En cuanto a las posiciones adoptadas por los pa\u00edses que apoyaron a Israel el 7 de octubre, observamos que los mismos pa\u00edses expresaron su apoyo al ataque iran\u00ed, con algunas excepciones: India \u2014as\u00ed como Suiza e Irlanda\u2014 piden esta vez una desescalada, y gran parte de \u00c1frica a\u00fan no se ha pronunciado.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-large  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/BuqnO\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>El 15 de abril a las 20:30 (hora de Madrid), los pa\u00edses que ped\u00edan la desescalada o la contenci\u00f3n sin apoyar a Israel representaban el 58.8% de la poblaci\u00f3n mundial y el 35.2% del PIB. Los pa\u00edses que apoyaban a Israel y\/o hab\u00edan contribuido a la defensa de su territorio (Estados Unidos, Francia, Reino Unido, Jordania) representaban m\u00e1s de la mitad del PIB mundial (52.4%) pero s\u00f3lo el 16.3% de la poblaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El lunes 15 de abril a las 20:30 (hora de Madrid), cerca de 100 pa\u00edses comunicaron p\u00fablicamente su posici\u00f3n ante el ataque iran\u00ed contra territorio israel\u00ed en la noche del 13 al 14 de abril.<\/p>\n<p>Las analizamos y creamos un primer mapa in\u00e9dito.<\/p>\n","protected":false},"author":17959,"featured_media":33218,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-studies.php","format":"standard","meta":{"_acf_changed":true,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":5,"footnotes":""},"categories":[668],"tags":[],"staff":[7],"editorial_format":[1469],"serie":[],"audience":[],"geo":[198],"class_list":["post-33216","post","type-post","status-publish","format-standard","hentry","category-guerra-de-sucot","staff-el-grand-continent","editorial_format-estudios","geo-mundo"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":33218,"excerpt":"El lunes 15 de abril a las 20:30 (hora de Madrid), cerca de 100 pa\u00edses comunicaron p\u00fablicamente su posici\u00f3n ante el ataque iran\u00ed contra territorio israel\u00ed en la noche del 13 al 14 de abril.\r\n\r\nLas analizamos y creamos un primer mapa in\u00e9dito.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El mundo ante el ataque de Ir\u00e1n a Israel. Cartograf\u00eda de las reacciones [mapa exclusivo] - El Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/es\/2024\/04\/15\/el-mundo-ante-el-ataque-de-iran-a-israel-cartografia-de-las-reacciones-mapa-exclusivo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El mundo ante el ataque de Ir\u00e1n a Israel. Cartograf\u00eda de las reacciones [mapa exclusivo] - El Grand Continent\" \/>\n<meta property=\"og:description\" content=\"El lunes 15 de abril a las 20:30 (hora de Madrid), cerca de 100 pa\u00edses comunicaron p\u00fablicamente su posici\u00f3n ante el ataque iran\u00ed contra territorio israel\u00ed en la noche del 13 al 14 de abril.  Las analizamos y creamos un primer mapa in\u00e9dito.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/es\/2024\/04\/15\/el-mundo-ante-el-ataque-de-iran-a-israel-cartografia-de-las-reacciones-mapa-exclusivo\/\" \/>\n<meta property=\"og:site_name\" content=\"El Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-15T20:53:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-15T21:06:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/04\/1Rg01-reacciones-al-ataque-iran-contra-territorio-israel-los-d-as-13-y-14-de-abril-de-2024-.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1840\" \/>\n\t<meta property=\"og:image:height\" content=\"996\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"anainesfernandez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/04\/1Rg01-reacciones-al-ataque-iran-contra-territorio-israel-los-d-as-13-y-14-de-abril-de-2024-.png\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"anainesfernandez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/04\/15\/el-mundo-ante-el-ataque-de-iran-a-israel-cartografia-de-las-reacciones-mapa-exclusivo\/\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/2024\/04\/15\/el-mundo-ante-el-ataque-de-iran-a-israel-cartografia-de-las-reacciones-mapa-exclusivo\/\",\"name\":\"El mundo ante el ataque de Ir\u00e1n a Israel. Cartograf\u00eda de las reacciones [mapa exclusivo] - El Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/04\/15\/el-mundo-ante-el-ataque-de-iran-a-israel-cartografia-de-las-reacciones-mapa-exclusivo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/04\/15\/el-mundo-ante-el-ataque-de-iran-a-israel-cartografia-de-las-reacciones-mapa-exclusivo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/04\/198383_309-1.jpg\",\"datePublished\":\"2024-04-15T20:53:18+00:00\",\"dateModified\":\"2024-04-15T21:06:45+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/570398dd8da37ba5d66dec6d242bd33c\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/04\/15\/el-mundo-ante-el-ataque-de-iran-a-israel-cartografia-de-las-reacciones-mapa-exclusivo\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/es\/2024\/04\/15\/el-mundo-ante-el-ataque-de-iran-a-israel-cartografia-de-las-reacciones-mapa-exclusivo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/04\/15\/el-mundo-ante-el-ataque-de-iran-a-israel-cartografia-de-las-reacciones-mapa-exclusivo\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/04\/198383_309-1.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/04\/198383_309-1.jpg\",\"width\":1016,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/04\/15\/el-mundo-ante-el-ataque-de-iran-a-israel-cartografia-de-las-reacciones-mapa-exclusivo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/legrandcontinent.eu\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El mundo ante el ataque de Ir\u00e1n a Israel. Cartograf\u00eda de las reacciones [mapa exclusivo]\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/\",\"name\":\"El Grand Continent\",\"description\":\"La escala pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/570398dd8da37ba5d66dec6d242bd33c\",\"name\":\"anainesfernandez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/fe25c21e6213f69a683147fabda32586?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/fe25c21e6213f69a683147fabda32586?s=96&d=mm&r=g\",\"caption\":\"anainesfernandez\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El mundo ante el ataque de Ir\u00e1n a Israel. Cartograf\u00eda de las reacciones [mapa exclusivo] - El Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/es\/2024\/04\/15\/el-mundo-ante-el-ataque-de-iran-a-israel-cartografia-de-las-reacciones-mapa-exclusivo\/","og_locale":"es_ES","og_type":"article","og_title":"El mundo ante el ataque de Ir\u00e1n a Israel. Cartograf\u00eda de las reacciones [mapa exclusivo] - El Grand Continent","og_description":"El lunes 15 de abril a las 20:30 (hora de Madrid), cerca de 100 pa\u00edses comunicaron p\u00fablicamente su posici\u00f3n ante el ataque iran\u00ed contra territorio israel\u00ed en la noche del 13 al 14 de abril.  Las analizamos y creamos un primer mapa in\u00e9dito.","og_url":"https:\/\/legrandcontinent.eu\/es\/2024\/04\/15\/el-mundo-ante-el-ataque-de-iran-a-israel-cartografia-de-las-reacciones-mapa-exclusivo\/","og_site_name":"El Grand Continent","article_published_time":"2024-04-15T20:53:18+00:00","article_modified_time":"2024-04-15T21:06:45+00:00","og_image":[{"width":1840,"height":996,"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/04\/1Rg01-reacciones-al-ataque-iran-contra-territorio-israel-los-d-as-13-y-14-de-abril-de-2024-.png","type":"image\/png"}],"author":"anainesfernandez","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/04\/1Rg01-reacciones-al-ataque-iran-contra-territorio-israel-los-d-as-13-y-14-de-abril-de-2024-.png","twitter_misc":{"Escrito por":"anainesfernandez","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/es\/2024\/04\/15\/el-mundo-ante-el-ataque-de-iran-a-israel-cartografia-de-las-reacciones-mapa-exclusivo\/","url":"https:\/\/legrandcontinent.eu\/es\/2024\/04\/15\/el-mundo-ante-el-ataque-de-iran-a-israel-cartografia-de-las-reacciones-mapa-exclusivo\/","name":"El mundo ante el ataque de Ir\u00e1n a Israel. Cartograf\u00eda de las reacciones [mapa exclusivo] - El Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/es\/2024\/04\/15\/el-mundo-ante-el-ataque-de-iran-a-israel-cartografia-de-las-reacciones-mapa-exclusivo\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/es\/2024\/04\/15\/el-mundo-ante-el-ataque-de-iran-a-israel-cartografia-de-las-reacciones-mapa-exclusivo\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/04\/198383_309-1.jpg","datePublished":"2024-04-15T20:53:18+00:00","dateModified":"2024-04-15T21:06:45+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/570398dd8da37ba5d66dec6d242bd33c"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/es\/2024\/04\/15\/el-mundo-ante-el-ataque-de-iran-a-israel-cartografia-de-las-reacciones-mapa-exclusivo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/es\/2024\/04\/15\/el-mundo-ante-el-ataque-de-iran-a-israel-cartografia-de-las-reacciones-mapa-exclusivo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/2024\/04\/15\/el-mundo-ante-el-ataque-de-iran-a-israel-cartografia-de-las-reacciones-mapa-exclusivo\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/04\/198383_309-1.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/04\/198383_309-1.jpg","width":1016,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/es\/2024\/04\/15\/el-mundo-ante-el-ataque-de-iran-a-israel-cartografia-de-las-reacciones-mapa-exclusivo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legrandcontinent.eu\/es\/"},{"@type":"ListItem","position":2,"name":"El mundo ante el ataque de Ir\u00e1n a Israel. Cartograf\u00eda de las reacciones [mapa exclusivo]"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/es\/#website","url":"https:\/\/legrandcontinent.eu\/es\/","name":"El Grand Continent","description":"La escala pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/570398dd8da37ba5d66dec6d242bd33c","name":"anainesfernandez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/fe25c21e6213f69a683147fabda32586?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fe25c21e6213f69a683147fabda32586?s=96&d=mm&r=g","caption":"anainesfernandez"}}]}},"lgc_categories":[{"id":668,"name":"Israel, Ham\u00e1s: el 7 de octubre, dos a\u00f1os despu\u00e9s","slug":"guerra-de-sucot"}],"lgc_author":{"id":7,"name":"El Grand Continent","slug":"el-grand-continent","description":null,"first_name":null,"last_name":null,"picture":null},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/04\/198383_309-1.jpg","width":1016,"height":700,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/04\/198383_309-1.jpg","width":1016,"height":700,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/33216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/users\/17959"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/comments?post=33216"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/33216\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media\/33218"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media?parent=33216"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/categories?post=33216"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/tags?post=33216"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/staff?post=33216"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/editorial_format?post=33216"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/serie?post=33216"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/audience?post=33216"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/geo?post=33216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}