{"id":33172,"date":"2024-04-15T16:18:00","date_gmt":"2024-04-15T14:18:00","guid":{"rendered":"https:\/\/legrandcontinent.eu\/es\/?p=33172"},"modified":"2024-04-15T17:00:20","modified_gmt":"2024-04-15T15:00:20","slug":"arabia-saudi-emiratos-y-jordania-protegen-a-israel-la-nueva-geopolitica-de-oriente-proximo-tras-el-ataque-de-iran-mapas-exclusivos","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/es\/2024\/04\/15\/arabia-saudi-emiratos-y-jordania-protegen-a-israel-la-nueva-geopolitica-de-oriente-proximo-tras-el-ataque-de-iran-mapas-exclusivos\/","title":{"rendered":"Arabia Saud\u00ed, Emiratos y Jordania protegen a Israel. La nueva geopol\u00edtica de Oriente Pr\u00f3ximo tras el ataque de Ir\u00e1n [mapas exclusivos]"},"content":{"rendered":"\n<p>En la noche del 13 al 14 de abril, Ir\u00e1n y los <em>proxies<\/em> del r\u00e9gimen de Teher\u00e1n en cuatro pa\u00edses \u2014Yemen, Irak, Siria y L\u00edbano\u2014 atacaron territorio israel\u00ed con un arsenal compuesto por al menos 30 misiles de crucero, 110 misiles bal\u00edsticos y 170 drones. Fue el mayor ataque a distancia de la historia en cuanto a proyectiles lanzados en una sola \u00absalva\u00bb.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-large  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/Z9o4P\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>En total, al menos 13 pa\u00edses participaron en las operaciones iran\u00edes y en las destinadas a defender territorio israel\u00ed.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Cuatro pa\u00edses desplegaron aviones para destruir los misiles y drones lanzados contra Israel antes de que alcanzaran sus objetivos: Estados Unidos, Francia, Jordania y Reino Unido.<\/li>\n\n\n\n<li>La participaci\u00f3n de Alemania se limit\u00f3 a un avi\u00f3n de la Luftwaffe que reabasteci\u00f3 de combustible a un caza franc\u00e9s en el espacio a\u00e9reo jordano&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-33172' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2024\/04\/15\/arabia-saudi-emiratos-y-jordania-protegen-a-israel-la-nueva-geopolitica-de-oriente-proximo-tras-el-ataque-de-iran-mapas-exclusivos\/#easy-footnote-bottom-1-33172' title='\u00ab\u00a0&lt;a href=&quot;https:\/\/www.spiegel.de\/ausland\/iran-israel-news-israel-oeffnet-den-luftraum-wieder-a-271a5530-0cf1-4d2b-b06f-aa56128bc4c7&quot;&gt;Luftwaffe tankte in der Nacht franz\u00f6sische Kampfjets auf&lt;\/a&gt;\u00a0\u00bb,\u00a0&lt;em&gt;Der Spiegel&lt;\/em&gt;, 14 de abril de 2024.'><sup>1<\/sup><\/a><\/span><\/span>.<\/li>\n\n\n\n<li>La US Navy tambi\u00e9n destruy\u00f3 entre 4 y 6 misiles bal\u00edsticos iran\u00edes desde dos buques desplegados en el Mediterr\u00e1neo oriental: el USS Arleigh Burke y el USS Carney.<\/li>\n\n\n\n<li>Las operaciones de defensa a\u00e9rea contra territorio israel\u00ed fueron coordinadas por el Mando Central de las Fuerzas A\u00e9reas estadounidenses desde la base militar de Al-Udeid, en Qatar&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-33172' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2024\/04\/15\/arabia-saudi-emiratos-y-jordania-protegen-a-israel-la-nueva-geopolitica-de-oriente-proximo-tras-el-ataque-de-iran-mapas-exclusivos\/#easy-footnote-bottom-2-33172' title='Chris Gordon, \u00ab\u00a0&lt;a href=&quot;https:\/\/www.airandspaceforces.com\/usaf-fighters-shoot-down-iranian-drones-in-defense-of-israel\/&quot;&gt;USAF Fighters Shoot Down Iranian Drones in Defense of Israel&lt;\/a&gt;\u00a0\u00bb,\u00a0&lt;em&gt;Air &amp;amp; Space Forces Magazine&lt;\/em&gt;, 14 de abril de 2024.'><sup>2<\/sup><\/a><\/span><\/span>.<\/li>\n<\/ul>\n\n\n\n<p>Varios funcionarios estadounidenses han indicado que Arabia Saud\u00ed y Emiratos \u00c1rabes Unidos tambi\u00e9n desempe\u00f1aron un papel en la defensa del territorio israel\u00ed al compartir informaci\u00f3n sobre los planes iran\u00edes con Washington y Jerusal\u00e9n&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-33172' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2024\/04\/15\/arabia-saudi-emiratos-y-jordania-protegen-a-israel-la-nueva-geopolitica-de-oriente-proximo-tras-el-ataque-de-iran-mapas-exclusivos\/#easy-footnote-bottom-3-33172' title='David S. Cloud, Dov Lieber, Stephen Kalin y Summer Said, \u00ab\u00a0&lt;a href=&quot;https:\/\/www.wsj.com\/world\/middle-east\/how-the-u-s-forged-a-fragile-middle-eastern-alliance-to-repel-irans-israel-attack-4a1fbc00?mod=hp_lead_pos7&quot;&gt;How the U.S. Forged a Fragile Middle Eastern Alliance to Repel Iran\u2019s Israel Attack&lt;\/a&gt;\u00a0\u00bb,\u00a0&lt;em&gt;The Wall Street Journal&lt;\/em&gt;, 15 de abril de 2024.'><sup>3<\/sup><\/a><\/span><\/span>. Tras <a href=\"https:\/\/legrandcontinent.eu\/es\/2024\/04\/02\/ataque-israeli-dirigido-contra-iran-en-damasco-riesgo-de-escalada-regional\/\">el ataque israel\u00ed contra la secci\u00f3n consular de la embajada iran\u00ed en Damasco el 1 de abril<\/a>, Estados Unidos comenz\u00f3 r\u00e1pidamente a \u00abpresionar a los gobiernos \u00e1rabes para que compartieran informaci\u00f3n de inteligencia sobre los planes de Ir\u00e1n\u00bb, seg\u00fan fuentes saud\u00edes y egipcias cercanas al asunto.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-large  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/XbGMs\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Los F-15 estadounidenses del 494\u00ba Escuadr\u00f3n de Cazas y del 335\u00ba Escuadr\u00f3n de Cazas destruyeron unos 70 drones.<\/li>\n\n\n\n<li>Una bater\u00eda Patriot estadounidense en Erbil, en el Kurdist\u00e1n iraqu\u00ed, intercept\u00f3 un misil bal\u00edstico iran\u00ed.<\/li>\n\n\n\n<li>Cazas brit\u00e1nicos desplegados en el marco de la operaci\u00f3n Shader despegaron de la base chipriota de Akrotiri e interceptaron drones iran\u00edes sobre el espacio a\u00e9reo sirio e iraqu\u00ed.<\/li>\n\n\n\n<li>Cazas franceses despegaron de la base a\u00e9rea proyectada en Jordania para interceptar drones iran\u00edes.<\/li>\n\n\n\n<li>La fuerza a\u00e9rea jordana derrib\u00f3 misiles y drones iran\u00edes que hab\u00edan violado su espacio a\u00e9reo.<\/li>\n\n\n\n<li>Arabia Saud\u00ed y Emiratos \u00c1rabes Unidos acordaron compartir informaci\u00f3n de inteligencia que ayud\u00f3 a contrarrestar el ataque iran\u00ed.<\/li>\n\n\n\n<li>Al menos cuatro misiles iran\u00edes impactaron en territorio israel\u00ed, uno de los cuales caus\u00f3 da\u00f1os menores en la base a\u00e9rea de Nevatim.<\/li>\n<\/ul>\n\n\n\n<p>En la ma\u00f1ana del lunes 15 de abril, Emmanuel Macron dijo que el ej\u00e9rcito franc\u00e9s hab\u00eda ayudado a interceptar drones iran\u00edes \u00aba petici\u00f3n de Jordania\u00bb. Desde el lanzamiento de la operaci\u00f3n antiterrorista Chammal en 2014, Par\u00eds dispone de una base a\u00e9rea proyectada (BAP) en la base jordana Pr\u00edncipe-Hassan, de la que partieron los aviones franceses que realizaron las interceptaciones.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la noche del s\u00e1bado 13 al domingo 14 de abril, Ir\u00e1n, con el apoyo de sus <em>proxies<\/em>, lanz\u00f3 un ataque contra territorio israel\u00ed a una escala sin precedentes. Mientras se disparaban proyectiles desde Irak, Siria, L\u00edbano y Yemen, Arabia Saud\u00ed, Jordania y Emiratos \u00c1rabes Unidos contribuyeron directamente a la defensa de Israel. Publicamos dos mapas exclusivos sobre la nueva geopol\u00edtica de Oriente Pr\u00f3ximo.<\/p>\n","protected":false},"author":1366,"featured_media":33174,"comment_status":"closed","ping_status":"","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":true,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":3,"footnotes":""},"categories":[668],"tags":[],"staff":[],"editorial_format":[1472],"serie":[],"audience":[],"geo":[196],"class_list":["post-33172","post","type-post","status-publish","format-standard","hentry","category-guerra-de-sucot","editorial_format-analisis","geo-asia-central"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":33174,"excerpt":"En la noche del s\u00e1bado 13 al domingo 14 de abril, Ir\u00e1n, con el apoyo de sus <em>proxies<\/em>, lanz\u00f3 un ataque contra territorio israel\u00ed a una escala sin precedentes. Mientras se disparaban proyectiles desde Irak, Siria, L\u00edbano y Yemen, Arabia Saud\u00ed, Jordania y Emiratos \u00c1rabes Unidos contribuyeron directamente a la defensa de Israel. Publicamos dos mapas exclusivos sobre la nueva geopol\u00edtica de Oriente Pr\u00f3ximo.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Arabia Saud\u00ed, Emiratos y Jordania protegen a Israel. La nueva geopol\u00edtica de Oriente Pr\u00f3ximo tras el ataque de Ir\u00e1n [mapas exclusivos] - El Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/es\/2024\/04\/15\/arabia-saudi-emiratos-y-jordania-protegen-a-israel-la-nueva-geopolitica-de-oriente-proximo-tras-el-ataque-de-iran-mapas-exclusivos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arabia Saud\u00ed, Emiratos y Jordania protegen a Israel. La nueva geopol\u00edtica de Oriente Pr\u00f3ximo tras el ataque de Ir\u00e1n [mapas exclusivos] - El Grand Continent\" \/>\n<meta property=\"og:description\" content=\"En la noche del s\u00e1bado 13 al domingo 14 de abril, Ir\u00e1n, con el apoyo de sus proxies, lanz\u00f3 un ataque contra territorio israel\u00ed a una escala sin precedentes. Mientras se disparaban proyectiles desde Irak, Siria, L\u00edbano y Yemen, Arabia Saud\u00ed, Jordania y Emiratos \u00c1rabes Unidos contribuyeron directamente a la defensa de Israel. Publicamos dos mapas exclusivos sobre la nueva geopol\u00edtica de Oriente Pr\u00f3ximo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/es\/2024\/04\/15\/arabia-saudi-emiratos-y-jordania-protegen-a-israel-la-nueva-geopolitica-de-oriente-proximo-tras-el-ataque-de-iran-mapas-exclusivos\/\" \/>\n<meta property=\"og:site_name\" content=\"El Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-15T14:18:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-15T15:00:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/04\/XbGMs-la-nueva-geopol-tica-de-oriente-pr-ximo-tras-el-ataque-de-ir-n-.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1931\" \/>\n\t<meta property=\"og:image:height\" content=\"1717\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"florent\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"florent\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/04\/15\/arabia-saudi-emiratos-y-jordania-protegen-a-israel-la-nueva-geopolitica-de-oriente-proximo-tras-el-ataque-de-iran-mapas-exclusivos\/\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/2024\/04\/15\/arabia-saudi-emiratos-y-jordania-protegen-a-israel-la-nueva-geopolitica-de-oriente-proximo-tras-el-ataque-de-iran-mapas-exclusivos\/\",\"name\":\"Arabia Saud\u00ed, Emiratos y Jordania protegen a Israel. La nueva geopol\u00edtica de Oriente Pr\u00f3ximo tras el ataque de Ir\u00e1n [mapas exclusivos] - El Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/04\/15\/arabia-saudi-emiratos-y-jordania-protegen-a-israel-la-nueva-geopolitica-de-oriente-proximo-tras-el-ataque-de-iran-mapas-exclusivos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/04\/15\/arabia-saudi-emiratos-y-jordania-protegen-a-israel-la-nueva-geopolitica-de-oriente-proximo-tras-el-ataque-de-iran-mapas-exclusivos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/04\/XbGMs-la-nueva-geopol-tica-de-oriente-pr-ximo-tras-el-ataque-de-ir-n-.png\",\"datePublished\":\"2024-04-15T14:18:00+00:00\",\"dateModified\":\"2024-04-15T15:00:20+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/04\/15\/arabia-saudi-emiratos-y-jordania-protegen-a-israel-la-nueva-geopolitica-de-oriente-proximo-tras-el-ataque-de-iran-mapas-exclusivos\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/es\/2024\/04\/15\/arabia-saudi-emiratos-y-jordania-protegen-a-israel-la-nueva-geopolitica-de-oriente-proximo-tras-el-ataque-de-iran-mapas-exclusivos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/04\/15\/arabia-saudi-emiratos-y-jordania-protegen-a-israel-la-nueva-geopolitica-de-oriente-proximo-tras-el-ataque-de-iran-mapas-exclusivos\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/04\/XbGMs-la-nueva-geopol-tica-de-oriente-pr-ximo-tras-el-ataque-de-ir-n-.png\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/04\/XbGMs-la-nueva-geopol-tica-de-oriente-pr-ximo-tras-el-ataque-de-ir-n-.png\",\"width\":1931,\"height\":1717},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/04\/15\/arabia-saudi-emiratos-y-jordania-protegen-a-israel-la-nueva-geopolitica-de-oriente-proximo-tras-el-ataque-de-iran-mapas-exclusivos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/legrandcontinent.eu\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arabia Saud\u00ed, Emiratos y Jordania protegen a Israel. La nueva geopol\u00edtica de Oriente Pr\u00f3ximo tras el ataque de Ir\u00e1n [mapas exclusivos]\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/\",\"name\":\"El Grand Continent\",\"description\":\"La escala pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\",\"name\":\"florent\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"caption\":\"florent\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arabia Saud\u00ed, Emiratos y Jordania protegen a Israel. La nueva geopol\u00edtica de Oriente Pr\u00f3ximo tras el ataque de Ir\u00e1n [mapas exclusivos] - El Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/es\/2024\/04\/15\/arabia-saudi-emiratos-y-jordania-protegen-a-israel-la-nueva-geopolitica-de-oriente-proximo-tras-el-ataque-de-iran-mapas-exclusivos\/","og_locale":"es_ES","og_type":"article","og_title":"Arabia Saud\u00ed, Emiratos y Jordania protegen a Israel. La nueva geopol\u00edtica de Oriente Pr\u00f3ximo tras el ataque de Ir\u00e1n [mapas exclusivos] - El Grand Continent","og_description":"En la noche del s\u00e1bado 13 al domingo 14 de abril, Ir\u00e1n, con el apoyo de sus proxies, lanz\u00f3 un ataque contra territorio israel\u00ed a una escala sin precedentes. Mientras se disparaban proyectiles desde Irak, Siria, L\u00edbano y Yemen, Arabia Saud\u00ed, Jordania y Emiratos \u00c1rabes Unidos contribuyeron directamente a la defensa de Israel. Publicamos dos mapas exclusivos sobre la nueva geopol\u00edtica de Oriente Pr\u00f3ximo.","og_url":"https:\/\/legrandcontinent.eu\/es\/2024\/04\/15\/arabia-saudi-emiratos-y-jordania-protegen-a-israel-la-nueva-geopolitica-de-oriente-proximo-tras-el-ataque-de-iran-mapas-exclusivos\/","og_site_name":"El Grand Continent","article_published_time":"2024-04-15T14:18:00+00:00","article_modified_time":"2024-04-15T15:00:20+00:00","og_image":[{"width":1931,"height":1717,"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/04\/XbGMs-la-nueva-geopol-tica-de-oriente-pr-ximo-tras-el-ataque-de-ir-n-.png","type":"image\/png"}],"author":"florent","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"florent","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/es\/2024\/04\/15\/arabia-saudi-emiratos-y-jordania-protegen-a-israel-la-nueva-geopolitica-de-oriente-proximo-tras-el-ataque-de-iran-mapas-exclusivos\/","url":"https:\/\/legrandcontinent.eu\/es\/2024\/04\/15\/arabia-saudi-emiratos-y-jordania-protegen-a-israel-la-nueva-geopolitica-de-oriente-proximo-tras-el-ataque-de-iran-mapas-exclusivos\/","name":"Arabia Saud\u00ed, Emiratos y Jordania protegen a Israel. La nueva geopol\u00edtica de Oriente Pr\u00f3ximo tras el ataque de Ir\u00e1n [mapas exclusivos] - El Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/es\/2024\/04\/15\/arabia-saudi-emiratos-y-jordania-protegen-a-israel-la-nueva-geopolitica-de-oriente-proximo-tras-el-ataque-de-iran-mapas-exclusivos\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/es\/2024\/04\/15\/arabia-saudi-emiratos-y-jordania-protegen-a-israel-la-nueva-geopolitica-de-oriente-proximo-tras-el-ataque-de-iran-mapas-exclusivos\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/04\/XbGMs-la-nueva-geopol-tica-de-oriente-pr-ximo-tras-el-ataque-de-ir-n-.png","datePublished":"2024-04-15T14:18:00+00:00","dateModified":"2024-04-15T15:00:20+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/es\/2024\/04\/15\/arabia-saudi-emiratos-y-jordania-protegen-a-israel-la-nueva-geopolitica-de-oriente-proximo-tras-el-ataque-de-iran-mapas-exclusivos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/es\/2024\/04\/15\/arabia-saudi-emiratos-y-jordania-protegen-a-israel-la-nueva-geopolitica-de-oriente-proximo-tras-el-ataque-de-iran-mapas-exclusivos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/2024\/04\/15\/arabia-saudi-emiratos-y-jordania-protegen-a-israel-la-nueva-geopolitica-de-oriente-proximo-tras-el-ataque-de-iran-mapas-exclusivos\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/04\/XbGMs-la-nueva-geopol-tica-de-oriente-pr-ximo-tras-el-ataque-de-ir-n-.png","contentUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/04\/XbGMs-la-nueva-geopol-tica-de-oriente-pr-ximo-tras-el-ataque-de-ir-n-.png","width":1931,"height":1717},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/es\/2024\/04\/15\/arabia-saudi-emiratos-y-jordania-protegen-a-israel-la-nueva-geopolitica-de-oriente-proximo-tras-el-ataque-de-iran-mapas-exclusivos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legrandcontinent.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Arabia Saud\u00ed, Emiratos y Jordania protegen a Israel. La nueva geopol\u00edtica de Oriente Pr\u00f3ximo tras el ataque de Ir\u00e1n [mapas exclusivos]"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/es\/#website","url":"https:\/\/legrandcontinent.eu\/es\/","name":"El Grand Continent","description":"La escala pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c","name":"florent","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","caption":"florent"}}]}},"lgc_categories":[{"id":668,"name":"Israel, Ham\u00e1s: el 7 de octubre, dos a\u00f1os despu\u00e9s","slug":"guerra-de-sucot"}],"lgc_author":null,"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/04\/XbGMs-la-nueva-geopol-tica-de-oriente-pr-ximo-tras-el-ataque-de-ir-n-.png","width":1931,"height":1717,"alt":""},"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/33172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/users\/1366"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/comments?post=33172"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/33172\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media\/33174"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media?parent=33172"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/categories?post=33172"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/tags?post=33172"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/staff?post=33172"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/editorial_format?post=33172"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/serie?post=33172"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/audience?post=33172"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/geo?post=33172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}