{"id":32285,"date":"2024-04-01T16:37:00","date_gmt":"2024-04-01T14:37:00","guid":{"rendered":"https:\/\/legrandcontinent.eu\/es\/?p=32285"},"modified":"2024-04-01T17:14:18","modified_gmt":"2024-04-01T15:14:18","slug":"el-punto-de-inflexion-de-erdogan-la-oposicion-gana-las-elecciones-municipales-en-turquia","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/es\/2024\/04\/01\/el-punto-de-inflexion-de-erdogan-la-oposicion-gana-las-elecciones-municipales-en-turquia\/","title":{"rendered":"El punto de inflexi\u00f3n de Erdo\u011fan. La oposici\u00f3n gana las elecciones municipales en Turqu\u00eda"},"content":{"rendered":"\n<p>La oposici\u00f3n de centroizquierda turca, dominada por el Partido Republicano del Pueblo (CHP), gan\u00f3 las elecciones municipales celebradas ayer, 31 de marzo, con el 37,7% de los votos, por delante del gobernante Partido de la Justicia y el Desarrollo (AKP), que se hizo con el 35,4% (frente al 44% de 2019).<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/6m1C5\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La oposici\u00f3n gan\u00f3 as\u00ed las cinco mayores ciudades del pa\u00eds: Estambul, Ankara, \u0130zmir, Bursa y Antalya. En Estambul, el actual alcalde Ekrem \u0130mamo\u011flu (CHP) -el oponente m\u00e1s cre\u00edble de Erdo\u011fan- se impuso, a pesar del activismo del presidente, \u00e9l mismo alcalde de la ciudad entre 1994 y 1998, junto a su candidato Murat Kurum.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Se espera que el AKP de Erdo\u011fan gane las elecciones en 12 provincias (frente a 21 de la oposici\u00f3n). El ascenso del partido islamista YRP, sobre todo en Anatolia, antiguo aliado del AKP y ahora su adversario, explica en parte este rev\u00e9s para el presidente turco, tras su victoria en las elecciones presidenciales y legislativas de mayo de 2023. El YRP hizo campa\u00f1a, en particular, sobre los compromisos del presidente turco con Israel y el hecho de que no ser\u00eda un buen musulm\u00e1n.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Como suele ocurrir, los electores kurdos votaron estrat\u00e9gicamente. Prefieren candidatos anti-Erdo\u011fan, como en Estambul con Ekrem \u0130mamo\u011flu, al tiempo que conservan el control de sus bastiones en el sureste.<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/Jiq8y\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/7Zu9e\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Seg\u00fan Ariane Bonzon: \u00abQue haya ganado la oposici\u00f3n republicana no significa que las elecciones hayan respondido a los criterios democr\u00e1ticos de un Estado de derecho (tiempo de palabra desigual entre el partido en el poder y la oposici\u00f3n, movilizaci\u00f3n del aparato del Estado en favor del partido en el poder, etc.).\u00bb<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Esto es una bofetada en la cara del r\u00e9gimen de Erdo\u011fan. Por un lado, hubo una fuerte ca\u00edda de la participaci\u00f3n -76% frente al 84% de 2019-, lo que refleja la desilusi\u00f3n entre los votantes del AKP. Por otro, el avance de la oposici\u00f3n en zonas de Anatolia que fueron de Erdo\u011fan (las provincias de Bursa, Afyonkarahisar y Adiyaman) marca \u00abun punto de inflexi\u00f3n\u00bb.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Erdo\u011fan ha pronunciado un discurso a primera hora de la ma\u00f1ana de hoy, reconociendo su derrota: \u00abEsto no es el final para nosotros, sino m\u00e1s bien un punto de inflexi\u00f3n\u00bb, reconociendo una \u00abp\u00e9rdida de altura\u00bb para el AKP.<\/li>\n<\/ul>\n\n\n\n<p>De estos resultados se desprenden tres tendencias:<\/p>\n\n\n\n<p>A nivel interno, mientras asistimos a un avance del partido islamista YRP, cabe esperar una carrera por el liderazgo del gran vencedor de las elecciones, el CHP, entre el alcalde de Estambul, Ekrem \u0130mamo\u011flu, y el alcalde de Ankara, Mansur Yava\u015f.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Este \u00faltimo, especialmente popular entre el empresariado turco, est\u00e1 casado con una mujer sin velo. Ya ha declarado: \u00abPrefiero perder las elecciones municipales que utilizar la religi\u00f3n como instrumento\u00bb.<\/li>\n\n\n\n<li>Por su parte, el alcalde de Estambul procede de \u00abuna familia tradicionalmente del lado socialdem\u00f3crata, pero con tendencias conservadoras, en la que el Islam ocupa un lugar importante\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-32285' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2024\/04\/01\/el-punto-de-inflexion-de-erdogan-la-oposicion-gana-las-elecciones-municipales-en-turquia\/#easy-footnote-bottom-1-32285' title='&lt;a href=&quot;https:\/\/www.lorientlejour.com\/article\/1167143\/qui-est-ekrem-imamoglu-le-nouveau-maire-distanbul-.html&quot;&gt;&lt;em&gt;L\u2019Orient-Le Jour&lt;\/em&gt;, 19 de abril de 2019&lt;\/a&gt;.'><sup>1<\/sup><\/a><\/span><\/span> y consider\u00f3 -al igual que el gobierno de Erdo\u011fan- que el reconocimiento del genocidio armenio por parte del presidente estadounidense fue un \u00abgrave error\u00bb.<\/li>\n<\/ul>\n\n\n\n<p>La situaci\u00f3n econ\u00f3mica figura entre las principales preocupaciones de los electores: la inflaci\u00f3n se situ\u00f3 en febrero en el 67,1% interanual. Seg\u00fan datos de la Agencia de Planificaci\u00f3n de Estambul, el coste de la vida en la ciudad aument\u00f3 un 81% en el a\u00f1o.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>De hecho, el AKP parece salir perdiendo en las regiones industriales, donde muchos trabajadores perciben un salario m\u00ednimo que no ha subido al ritmo de la inflaci\u00f3n. En un discurso particularmente introspectivo en el que reconoc\u00eda su derrota, Erdo\u011fan insisti\u00f3 en que el Gobierno debe concentrarse ahora en enderezar la econom\u00eda. De hecho, el 20 de marzo, en una medida inesperada para atajar la inflaci\u00f3n, el banco central subi\u00f3 su tipo de inter\u00e9s oficial en 5 puntos porcentuales, hasta el 50%, su nivel m\u00e1s alto en 20 a\u00f1os.<\/li>\n\n\n\n<li>No es imposible, sin embargo, que ante una situaci\u00f3n incontrolable, el inter\u00e9s del Presidente turco sea reinvertir en pol\u00edtica exterior: en particular, atacando a los kurdos en Siria.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>El Partido Popular Republicano (CHP) ha ganado las elecciones en Estambul y Ankara, as\u00ed como en la mayor\u00eda de las principales ciudades de Anatolia. Se trata de un punto de inflexi\u00f3n para el r\u00e9gimen de Erdo\u011fan, que ha sufrido su peor derrota electoral desde que lleg\u00f3 al poder. Dos mapas y un an\u00e1lisis sint\u00e9tico para hacer balance.<\/p>\n","protected":false},"author":1366,"featured_media":32282,"comment_status":"closed","ping_status":"","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":true,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":4,"footnotes":""},"categories":[6],"tags":[],"staff":[],"editorial_format":[1472],"serie":[],"audience":[],"geo":[196],"class_list":["post-32285","post","type-post","status-publish","format-standard","hentry","category-politica","editorial_format-analisis","geo-asia-central"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":32282,"excerpt":"El Partido Popular Republicano (CHP) ha ganado las elecciones en Estambul y Ankara, as\u00ed como en la mayor\u00eda de las principales ciudades de Anatolia. Se trata de un punto de inflexi\u00f3n para el r\u00e9gimen de Erdo\u011fan, que ha sufrido su peor derrota electoral desde que lleg\u00f3 al poder. Dos mapas y un an\u00e1lisis sint\u00e9tico para hacer balance.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El punto de inflexi\u00f3n de Erdo\u011fan. La oposici\u00f3n gana las elecciones municipales en Turqu\u00eda - El Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/es\/2024\/04\/01\/el-punto-de-inflexion-de-erdogan-la-oposicion-gana-las-elecciones-municipales-en-turquia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El punto de inflexi\u00f3n de Erdo\u011fan. La oposici\u00f3n gana las elecciones municipales en Turqu\u00eda - El Grand Continent\" \/>\n<meta property=\"og:description\" content=\"El Partido Popular Republicano (CHP) ha ganado las elecciones en Estambul y Ankara, as\u00ed como en la mayor\u00eda de las principales ciudades de Anatolia. Se trata de un punto de inflexi\u00f3n para el r\u00e9gimen de Erdo\u011fan, que ha sufrido su peor derrota electoral desde que lleg\u00f3 al poder. Dos mapas y un an\u00e1lisis sint\u00e9tico para hacer balance.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/es\/2024\/04\/01\/el-punto-de-inflexion-de-erdogan-la-oposicion-gana-las-elecciones-municipales-en-turquia\/\" \/>\n<meta property=\"og:site_name\" content=\"El Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-01T14:37:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-01T15:14:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/04\/Capture-decran-2024-04-01-a-16.26.48.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1626\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"florent\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"florent\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/04\/01\/el-punto-de-inflexion-de-erdogan-la-oposicion-gana-las-elecciones-municipales-en-turquia\/\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/2024\/04\/01\/el-punto-de-inflexion-de-erdogan-la-oposicion-gana-las-elecciones-municipales-en-turquia\/\",\"name\":\"El punto de inflexi\u00f3n de Erdo\u011fan. La oposici\u00f3n gana las elecciones municipales en Turqu\u00eda - El Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/04\/01\/el-punto-de-inflexion-de-erdogan-la-oposicion-gana-las-elecciones-municipales-en-turquia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/04\/01\/el-punto-de-inflexion-de-erdogan-la-oposicion-gana-las-elecciones-municipales-en-turquia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/04\/Capture-decran-2024-04-01-a-16.26.48.png\",\"datePublished\":\"2024-04-01T14:37:00+00:00\",\"dateModified\":\"2024-04-01T15:14:18+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/04\/01\/el-punto-de-inflexion-de-erdogan-la-oposicion-gana-las-elecciones-municipales-en-turquia\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/es\/2024\/04\/01\/el-punto-de-inflexion-de-erdogan-la-oposicion-gana-las-elecciones-municipales-en-turquia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/04\/01\/el-punto-de-inflexion-de-erdogan-la-oposicion-gana-las-elecciones-municipales-en-turquia\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/04\/Capture-decran-2024-04-01-a-16.26.48.png\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/04\/Capture-decran-2024-04-01-a-16.26.48.png\",\"width\":1626,\"height\":750},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/04\/01\/el-punto-de-inflexion-de-erdogan-la-oposicion-gana-las-elecciones-municipales-en-turquia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/legrandcontinent.eu\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El punto de inflexi\u00f3n de Erdo\u011fan. La oposici\u00f3n gana las elecciones municipales en Turqu\u00eda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/\",\"name\":\"El Grand Continent\",\"description\":\"La escala pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\",\"name\":\"florent\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"caption\":\"florent\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El punto de inflexi\u00f3n de Erdo\u011fan. La oposici\u00f3n gana las elecciones municipales en Turqu\u00eda - El Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/es\/2024\/04\/01\/el-punto-de-inflexion-de-erdogan-la-oposicion-gana-las-elecciones-municipales-en-turquia\/","og_locale":"es_ES","og_type":"article","og_title":"El punto de inflexi\u00f3n de Erdo\u011fan. La oposici\u00f3n gana las elecciones municipales en Turqu\u00eda - El Grand Continent","og_description":"El Partido Popular Republicano (CHP) ha ganado las elecciones en Estambul y Ankara, as\u00ed como en la mayor\u00eda de las principales ciudades de Anatolia. Se trata de un punto de inflexi\u00f3n para el r\u00e9gimen de Erdo\u011fan, que ha sufrido su peor derrota electoral desde que lleg\u00f3 al poder. Dos mapas y un an\u00e1lisis sint\u00e9tico para hacer balance.","og_url":"https:\/\/legrandcontinent.eu\/es\/2024\/04\/01\/el-punto-de-inflexion-de-erdogan-la-oposicion-gana-las-elecciones-municipales-en-turquia\/","og_site_name":"El Grand Continent","article_published_time":"2024-04-01T14:37:00+00:00","article_modified_time":"2024-04-01T15:14:18+00:00","og_image":[{"width":1626,"height":750,"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/04\/Capture-decran-2024-04-01-a-16.26.48.png","type":"image\/png"}],"author":"florent","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"florent","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/es\/2024\/04\/01\/el-punto-de-inflexion-de-erdogan-la-oposicion-gana-las-elecciones-municipales-en-turquia\/","url":"https:\/\/legrandcontinent.eu\/es\/2024\/04\/01\/el-punto-de-inflexion-de-erdogan-la-oposicion-gana-las-elecciones-municipales-en-turquia\/","name":"El punto de inflexi\u00f3n de Erdo\u011fan. La oposici\u00f3n gana las elecciones municipales en Turqu\u00eda - El Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/es\/2024\/04\/01\/el-punto-de-inflexion-de-erdogan-la-oposicion-gana-las-elecciones-municipales-en-turquia\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/es\/2024\/04\/01\/el-punto-de-inflexion-de-erdogan-la-oposicion-gana-las-elecciones-municipales-en-turquia\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/04\/Capture-decran-2024-04-01-a-16.26.48.png","datePublished":"2024-04-01T14:37:00+00:00","dateModified":"2024-04-01T15:14:18+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/es\/2024\/04\/01\/el-punto-de-inflexion-de-erdogan-la-oposicion-gana-las-elecciones-municipales-en-turquia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/es\/2024\/04\/01\/el-punto-de-inflexion-de-erdogan-la-oposicion-gana-las-elecciones-municipales-en-turquia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/2024\/04\/01\/el-punto-de-inflexion-de-erdogan-la-oposicion-gana-las-elecciones-municipales-en-turquia\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/04\/Capture-decran-2024-04-01-a-16.26.48.png","contentUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/04\/Capture-decran-2024-04-01-a-16.26.48.png","width":1626,"height":750},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/es\/2024\/04\/01\/el-punto-de-inflexion-de-erdogan-la-oposicion-gana-las-elecciones-municipales-en-turquia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legrandcontinent.eu\/es\/"},{"@type":"ListItem","position":2,"name":"El punto de inflexi\u00f3n de Erdo\u011fan. La oposici\u00f3n gana las elecciones municipales en Turqu\u00eda"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/es\/#website","url":"https:\/\/legrandcontinent.eu\/es\/","name":"El Grand Continent","description":"La escala pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c","name":"florent","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","caption":"florent"}}]}},"lgc_categories":[{"id":6,"name":"Pol\u00edtica","slug":"politica"}],"lgc_author":null,"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/04\/Capture-decran-2024-04-01-a-16.26.48.png","width":1626,"height":750,"alt":""},"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/32285","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/users\/1366"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/comments?post=32285"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/32285\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media\/32282"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media?parent=32285"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/categories?post=32285"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/tags?post=32285"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/staff?post=32285"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/editorial_format?post=32285"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/serie?post=32285"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/audience?post=32285"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/geo?post=32285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}