{"id":30510,"date":"2024-03-02T19:01:29","date_gmt":"2024-03-02T18:01:29","guid":{"rendered":"https:\/\/legrandcontinent.eu\/es\/?p=30510"},"modified":"2024-03-02T19:01:32","modified_gmt":"2024-03-02T18:01:32","slug":"china-rusia-iran-la-guerra-mundial-vista-por-el-kissinger-persa","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/es\/2024\/03\/02\/china-rusia-iran-la-guerra-mundial-vista-por-el-kissinger-persa\/","title":{"rendered":"China, Rusia, Ir\u00e1n: la guerra mundial vista por el \u00abKissinger persa\u00bb"},"content":{"rendered":"\n<p class=\"intro\">\u00abHoy anunciamos el fin de la Cuarta Guerra Mundial, el fin de la recomposici\u00f3n pol\u00edtica del Gran Oriente Pr\u00f3ximo, el fin de la guerra de religi\u00f3n. Ha comenzado un nuevo cap\u00edtulo. Lo llamamos: la nueva guerra fr\u00eda\u00bb.<\/p>\n\n\n\n<p class=\"intro\">Para Hassan Abbasi, ide\u00f3logo conspiracionista de la Guardia Revolucionaria iran\u00ed, hemos salido del interregno. Estar\u00edan fijadas las coordenadas de la conflictualidad en los pr\u00f3ximos cincuenta a\u00f1os y se identificar\u00edan las fuerzas implicadas: una nueva trilateral Rusia-China-Ir\u00e1n se enfrentar\u00eda a Estados Unidos, que a trav\u00e9s de tres ramas de la OTAN \u2013Europa, Oriente Medio y Pac\u00edfico\u2013 se enfrentar\u00eda a esta coalici\u00f3n de enemigos en tres zonas de tensi\u00f3n: Ucrania, Palestina y Taiw\u00e1n.<\/p>\n\n\n\n<p class=\"intro\">En su opini\u00f3n, el pensamiento estrat\u00e9gico debe adaptarse a esta \u00abnueva guerra fr\u00eda\u00bb, que explica los conflictos actuales y permite predecir los de los pr\u00f3ximos a\u00f1os. Pide que se abandone el marco de pensamiento de la \u00abCuarta Guerra Mundial\u00bb, durante la cual, de los a\u00f1os 1990 a los 2020, Estados Unidos habr\u00eda pretendido dividir a los Estados de Oriente Pr\u00f3ximo para reducirlos a la impotencia, destruir la regi\u00f3n inflamando la oposici\u00f3n religiosa entre sun\u00edes y chi\u00edes, y apoderarse de los recursos de la regi\u00f3n. Esta guerra habr\u00eda sido perdida por Washington, que se habr\u00eda visto obligado a abandonar progresivamente las diferentes zonas en las que hab\u00eda llevado a cabo operaciones militares \u2013desde Irak hasta Afganist\u00e1n\u2013 a partir de 2021.\u00a0<\/p>\n\n\n\n<p class=\"intro\">Esta voz de un ide\u00f3logo de la Guardia Revolucionaria no puede resumir toda la ideolog\u00eda pol\u00edtica de la Rep\u00fablica Isl\u00e1mica: es una expresi\u00f3n m\u00e1s radical y extremista que el centro de gravedad del r\u00e9gimen iran\u00ed. A diferencia de Kissinger \u2013a Abbasi se le llama a veces \u00abel Kissinger persa\u00bb\u2013, nunca ha ocupado un cargo pol\u00edtico de primer orden. Sus posiciones son especialmente expl\u00edcitas al encarnar el \u00abTriple Eje\u00bb de intereses compartidos entre Rusia, China e Ir\u00e1n&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-30510' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/es\/2024\/03\/02\/china-rusia-iran-la-guerra-mundial-vista-por-el-kissinger-persa\/#easy-footnote-bottom-1-30510' title='La idea de un \u00abtriple eje\u00bb de Ir\u00e1n, China y Rusia se explora en Ariane Tabatabai y Dina Esfandiary, Triple Axis: Iran&amp;#8217;s Relations With Russia and China, 2018, I.B. Tauris.'><sup>1<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<p class=\"intro\">Este discurso es tambi\u00e9n el \u00faltimo avatar de una tendencia de pol\u00edtica exterior influyente en la historia de la Rep\u00fablica Isl\u00e1mica de Ir\u00e1n, la \u00abMirada hacia Oriente\u00bb (<em>N\u00e9g\u00e2h b\u00e9 Sharq<\/em>) teorizada y defendida por Mahmud Ahmadineyad durante sus dos mandatos presidenciales (2005-2013), basada en la idea de que con el desplazamiento del centro de gravedad del mundo hacia Asia, Ir\u00e1n deber\u00eda verse cada vez m\u00e1s como una potencia asi\u00e1tica, y antioccidental.<\/p>\n\n\n\n<p class=\"intro\">Esta visi\u00f3n del mundo coexiste con otras doctrinas pol\u00edticas y geopol\u00edticas, cuya importancia cambia en funci\u00f3n de la coyuntura pol\u00edtica internacional. La posible reelecci\u00f3n de Donald Trump y una pol\u00edtica m\u00e1s hostil hacia Ir\u00e1n podr\u00edan reforzar la corriente representada por Abbasi en el seno de la Rep\u00fablica Isl\u00e1mica. En el Grand Continent publicaremos pr\u00f3ximamente otras voces, de cl\u00e9rigos conservadores, te\u00f3logos reformistas y juristas moderados, que sugieren, cada uno a su manera, formas de imaginar el futuro de la Rep\u00fablica Isl\u00e1mica, <a href=\"https:\/\/legrandcontinent.eu\/es\/2024\/02\/26\/el-futuro-de-una-ambicion-la-geopolitica-de-iran-en-la-era-post-jamenei-una-conversacion-con-ali-vaez\/\">el d\u00eda en que desaparezca la actual piedra angular del sistema, el ayatol\u00e1 Al\u00ed Jamenei<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">1 &#8211; La Cuarta Guerra Mundial y el plan de gulliverizaci\u00f3n de Oriente Pr\u00f3ximo<\/h2>\n\n\n\n<p>Un nuevo orden mundial est\u00e1 tomando forma. Podr\u00eda definir las relaciones internacionales durante los pr\u00f3ximos cincuenta a\u00f1os: en su juventud, en su madurez y quiz\u00e1s hasta su vejez.<\/p>\n\n\n\n<p class=\"comment\">Este discurso se pronunci\u00f3 el 23 de enero de 2024 (03 Bahman 1402) en el think tank \u00abCentro de An\u00e1lisis Doctrinal\u00bb (<em>markaz-\u00e9 beressi-y\u00e9 doctrin\u00e2l<\/em>), que dirige Hassan Abbasi.\u00a0<\/p>\n\n\n\n<p>Me gustar\u00eda empezar recordando la Cuarta Guerra Mundial. Estall\u00f3 despu\u00e9s de la Guerra Fr\u00eda, que a su vez dur\u00f3 desde la Segunda Guerra Mundial hasta el colapso de la URSS y la ca\u00edda del Muro de Berl\u00edn. Al igual que la Guerra Fr\u00eda, la Cuarta Guerra Mundial ha terminado.<\/p>\n\n\n\n<p class=\"comment\">Hassan Abbasi considera que la Guerra Fr\u00eda fue la Tercera Guerra Mundial; el periodo que sigui\u00f3 a la Guerra Fr\u00eda y que termina hoy, seg\u00fan \u00e9l, ser\u00eda por tanto la \u00abCuarta\u00bb Guerra Mundial.\u00a0<\/p>\n\n\n\n<p>Pero primero volvamos a sus or\u00edgenes. Hace d\u00e9cadas, Alexandre de Marenches, jefe del servicio de inteligencia exterior de Francia, teoriz\u00f3 la idea de una Cuarta Guerra Mundial en su libro <em>The Fourth World War<\/em>, publicado en ingl\u00e9s en 1992 y traducido al persa hace exactamente treinta a\u00f1os.<\/p>\n\n\n\n<p>En su libro, explica que la guerra entre Oriente y Occidente, entre marxismo y liberalismo, entre socialismo y capitalismo, ha terminado. Lo que prev\u00e9 no es una guerra entre el Norte y el Sur, ni una guerra entre pa\u00edses ricos y pobres, sino una guerra entre Occidente y el mundo isl\u00e1mico.<\/p>\n\n\n\n<p class=\"comment\">El libro de Alexandre de Marenches ha tenido un recorrido sorprendente. Publicado inicialmente en Francia como un libro de memorias en forma de entrevistas con la periodista Christine Ockrent en 1986, titulado <em>Dans le secret des princes<\/em>, fue traducido y parcialmente reescrito en ingl\u00e9s en 1992 con el t\u00edtulo <em>The Fourth World War: Diplomacy and Espionage in the Age of Terrorism<\/em>. Gan\u00f3 notoriedad por haber anunciado la invasi\u00f3n estadounidense de Irak. En Ir\u00e1n, el libro se tradujo con bastante rapidez, pero sigui\u00f3 siendo confidencial. No obstante, a veces se cita, como en el peri\u00f3dico ultraconservador <em>Jav\u00e2n<\/em>, pr\u00f3ximo a la Guardia Revolucionaria, que se alegra de que los iran\u00edes sean identificados en el libro como un enemigo potencialmente formidable de las potencias occidentales.\u00a0<\/p>\n\n\n\n<p>Diez a\u00f1os despu\u00e9s de Alexandre de Marenches, James Woolsey, el jefe de la CIA, anunci\u00f3 que la Cuarta Guerra Mundial hab\u00eda comenzado efectivamente tras el 11 de septiembre de 2001 \u2013y que tendr\u00eda lugar en Oriente Pr\u00f3ximo\u2013.&nbsp;<\/p>\n\n\n\n<p>\u00bfCu\u00e1l era el objetivo final? Declarar la guerra a Ir\u00e1n. Esta Cuarta Guerra Mundial era ante todo un intento de dividir a los Estados de Oriente Pr\u00f3ximo para reducir su capacidad de acci\u00f3n, como explica James Blackwell en su libro<em>Thunder in the Desert<\/em>.<\/p>\n\n\n\n<p class=\"comment\">El libro de Blackwell, citado por Abbasi, es de hecho un an\u00e1lisis t\u00e1ctico del \u00e9xito estadounidense en la operaci\u00f3n \u00abTormenta del Desierto\u00bb. Como explicaba Louis Gautier <a href=\"https:\/\/legrandcontinent.eu\/es\/2023\/08\/15\/la-era-estrategica-de-la-guerra-del-golfo\/\">en nuestras p\u00e1ginas<\/a>, m\u00e1s all\u00e1 de este aspecto t\u00e1ctico, la primera Guerra del Golfo inaugur\u00f3 una nueva era geoestrat\u00e9gica: \u00abLa Guerra del Golfo tambi\u00e9n fue precursora de conflictos que incorporaron dimensiones colaterales a la intervenci\u00f3n militar: comunicaci\u00f3n en tiempo real con la opini\u00f3n p\u00fablica, compromiso humanitario con la poblaci\u00f3n kurda, v\u00edctimas de actos colaterales de represi\u00f3n perpetrados por el r\u00e9gimen de Saddam Hussein, protecci\u00f3n del medio ambiente, continuidad del derecho internacional.\u00bb<\/p>\n\n\n\n<p>Se trataba de un plan para la gulliverizaci\u00f3n de la regi\u00f3n: el objetivo era convertir a los Estados de Oriente Pr\u00f3ximo en Liliputienses que cupieran en la palma de la mano de Gulliver, es decir, el r\u00e9gimen sionista, que se convertir\u00eda, como resultado de las divisiones, en el m\u00e1s poderoso de todos.&nbsp;<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-large\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/03\/unnamed-39.png\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"512\"\n        data-pswp-height=\"452\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/03\/unnamed-39-330x291.png\"\r\n                media=\"(max-width: 374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/03\/unnamed-39.png\"\r\n                media=\"(max-width: 989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/03\/unnamed-39.png\"\r\n                media=\"(min-width: 990px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/03\/unnamed-39-125x110.png\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">Extracto de la presentaci\u00f3n en Power Point de Abbasi<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<p class=\"comment\">En la teor\u00eda conspirativa de Abbasi, esta imagen representar\u00eda a los pa\u00edses de un Oriente Pr\u00f3ximo ampliado y dividido en tres categor\u00edas:\u00a0<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"comment\">a la derecha, los seis pa\u00edses \u00abGulliver\u00bb (los m\u00e1s grandes que se dividir\u00edan): Ir\u00e1n, Egipto, Turqu\u00eda, Siria, Irak y el \u00abr\u00e9gimen sionista\u00bb (Israel)<\/li>\n\n\n\n<li class=\"comment\">en el centro, los pa\u00edses \u00abesperanzado\u00bb: Libia, Arabia Saud\u00ed, Yemen, Om\u00e1n, Argelia y Sud\u00e1n\u00a0<\/li>\n\n\n\n<li class=\"comment\">a la izquierda, los pa\u00edses \u00abinquietos\u00bb: L\u00edbano, Emiratos \u00c1rabes Unidos, Qatar, Kuwait, T\u00fanez y Jordania<\/li>\n<\/ul>\n\n\n\n<p>Si Arabia Saud\u00ed se divide en cinco pa\u00edses, Ir\u00e1n en siete, Turqu\u00eda en dos, Egipto en dos, Siria en tres, Irak en tres, Afganist\u00e1n en dos o tres y Pakist\u00e1n en dos, al mundo musulm\u00e1n s\u00f3lo le quedar\u00e1n Estados del tama\u00f1o de Bahr\u00e9in, Qatar y Emiratos \u00c1rabes Unidos, incapaces de decidir por s\u00ed mismos.<\/p>\n\n\n\n<p>En este contexto, la estrategia oficial de la Rep\u00fablica Isl\u00e1mica ha sido impedir que Estados Unidos aplique este plan y oponerse a la desintegraci\u00f3n de estos pa\u00edses. Esta es la principal tarea que se ha fijado el Cuerpo de Guardias Revolucionarios, como parte del Eje de la Resistencia.<\/p>\n\n\n\n<p class=\"comment\">Esta visi\u00f3n del mundo equivale a presentar a los Guardias Revolucionarios como los inesperados defensores de la intangibilidad de las fronteras en el orden posterior a 1945. Es una respuesta a la opini\u00f3n de Kissinger de que Ir\u00e1n ten\u00eda que elegir entre ser \u00abuna causa o una naci\u00f3n\u00bb y de que la Rep\u00fablica Isl\u00e1mica era una potencia revisionista, es decir, que quer\u00eda transformar y desafiar el orden mundial existente.\u00a0<\/p>\n\n\n\n<p class=\"comment\">El \u00abEje de la Resistencia\u00bb es una forma de referirse a la coalici\u00f3n de intereses antioccidentales en Oriente Pr\u00f3ximo, que re\u00fane a actores con ideolog\u00edas <em>a priori <\/em>diferentes o incluso opuestas en torno al concepto de \u00abResistencia\u00bb. Recordemos que Hezbol\u00e1 es la rama pol\u00edtica de la organizaci\u00f3n armada conocida como \u00abResistencia Isl\u00e1mica en L\u00edbano\u00bb (<em>al-muq\u0101wamah al-isl\u0101m\u012byah f\u012b lubn\u0101n<\/em>) y Ham\u00e1s es un acr\u00f3nimo que significa \u00ab<em>\u1e25arakat al-muq\u0101wma al-\u02beisl\u0101miyya<\/em>\u00bb o \u00abMovimiento de Resistencia Isl\u00e1mica\u00bb.<\/p>\n\n\n\n<p>La fuerza Qods sigue la idea expresada por el m\u00e1rtir Qassem Soleimani sobre el separatismo iraqu\u00ed. Durante la votaci\u00f3n por la independencia del Kurdist\u00e1n, se vio a partidarios de la independencia enarbolando banderas sionistas junto a banderas kurdas. Pero dos o tres d\u00edas despu\u00e9s de la ceremonia f\u00fanebre del difunto Jalal Talabani [el 06 de octubre de 2017], el ex presidente de Irak y fundador de la Uni\u00f3n Patri\u00f3tica del Kurdist\u00e1n iraqu\u00ed, Hadj Qassem dijo a Massoud Barzani: \u00abimpediremos la desintegraci\u00f3n de Irak, no dejaremos que ocurra, porque entonces puede ocurrirle a todos los pa\u00edses, que se desintegrar\u00e1n todos\u00bb.<\/p>\n\n\n\n<p class=\"comment\">A lo largo del discurso se menciona a Qassem Soleimani como referencia, modelo a seguir y prueba de la justeza de la causa de la Revoluci\u00f3n iran\u00ed contra sus enemigos. Hassan Abbasi le llama de diversas formas: \u00abHajj Qassem\u00bb recuerda su piedad, ya que \u00abHajj\u00bb es un t\u00edtulo que se adjunta al nombre de un creyente musulm\u00e1n que peregrin\u00f3 a La Meca; \u00abshahid\u00bb, o \u00abm\u00e1rtir\u00bb, sit\u00faa al general Soleimani en el martirologio chi\u00ed de la Rep\u00fablica Isl\u00e1mica.\u00a0<\/p>\n\n\n\n<p class=\"comment\">La oposici\u00f3n a las autonom\u00edas kurdas es un elemento central de la doctrina de la Guardia Revolucionaria. La insistencia en la intangibilidad de las fronteras es tambi\u00e9n una forma de negar una mayor autonom\u00eda a las poblaciones kurdas, en Irak y Siria por supuesto, pero tambi\u00e9n en Ir\u00e1n, donde viven m\u00e1s de 10 millones de kurdos en el oeste del pa\u00eds. Fabrice Balanche <a href=\"https:\/\/legrandcontinent.eu\/es\/2023\/02\/13\/irak-y-siria-las-autonomias-kurdas-amenazadas\/\">analiza en el Grand Continent<\/a> esta oposici\u00f3n de las potencias regionales a las autonom\u00edas kurdas.<\/p>\n\n\n\n<p>Este plan reproduce el que Estados Unidos y Europa elaboraron hace cien a\u00f1os, en 1915, cuando dividieron el Imperio Otomano en una decena de pa\u00edses: Turqu\u00eda, Siria, L\u00edbano, Irak, etc&#8230;.. 100 a\u00f1os despu\u00e9s de los Acuerdos Sykes-Picot, vuelve a empezar la misma historia. Picot era franc\u00e9s y Sykes ingl\u00e9s. Pusieron una regla en el mapa, trazando una l\u00ednea que dec\u00eda que Siria estar\u00eda aqu\u00ed, Irak all\u00ed, Arabia Saud\u00ed aqu\u00ed, y as\u00ed sucesivamente.&nbsp;<\/p>\n\n\n\n<p>Una vez m\u00e1s, quer\u00edan destrozar el mundo isl\u00e1mico, como hab\u00edan hecho con el Imperio Otomano. Todos los occidentales que llegaron a la regi\u00f3n lo hicieron despu\u00e9s de estudiar Sykes-Picot y la desintegraci\u00f3n del Imperio Otomano: Lawrence de Arabia, Gertrude Bell \u2013sobre quien se estren\u00f3 una pel\u00edcula en 2015 titulada La reina del desierto\u2013.&nbsp;<\/p>\n\n\n\n<p class=\"comment\">A lo largo de la conferencia de Hassan Abbasi se entrelazan referencias a hechos reales, teor\u00edas geopol\u00edticas y representaciones cinematogr\u00e1ficas del cine de Hollywood. Gertrude Bell (1868-1926), arque\u00f3loga brit\u00e1nica, apoy\u00f3 la creaci\u00f3n de Estados \u00e1rabes independientes en Oriente Pr\u00f3ximo, incluido Irak, tras la ca\u00edda del Imperio Otomano. En la pel\u00edcula mencionada de Hassan Abbasi y dirigida por Werner Herzog, la interpreta Nicole Kidman. Tambi\u00e9n fue una de las primeras traductoras al ingl\u00e9s del <em>Divan<\/em> de H\u00e2f\u00e9z, una de las antolog\u00edas m\u00e1s importantes de poes\u00eda cl\u00e1sica persa.<\/p>\n\n\n\n<p>Parte de su plan se denomin\u00f3 el Gran Proyecto Oriente Pr\u00f3ximo, cuyo objetivo era la desaparici\u00f3n de Oriente Pr\u00f3ximo tal y como exist\u00eda. Quer\u00edan que todo el mundo musulm\u00e1n, desde Marrakech hasta Indonesia en la costa del Oc\u00e9ano Pac\u00edfico, una distancia de quince mil kil\u00f3metros de largo y cinco mil kil\u00f3metros de ancho, fuera un gran pa\u00eds.&nbsp;<\/p>\n\n\n\n<p>Por eso dividieron Sud\u00e1n, un pa\u00eds del tama\u00f1o de Francia, en dos y lo llamaron Sud\u00e1n del Sur; lo mismo ocurri\u00f3 en la Rep\u00fablica Centroafricana, donde favorecieron a los cristianos y expulsaron a los musulmanes a N\u00edger; hemos visto el mismo fen\u00f3meno en N\u00edger, y en Myanmar, donde apoyaron a los budistas y masacraron a los musulmanes, antes de enviarlos a Bangladesh.<\/p>\n\n\n\n<p>\u00bfQui\u00e9n se opuso a esta estrategia? La Rep\u00fablica Isl\u00e1mica de Ir\u00e1n. \u00bfQui\u00e9n prepar\u00f3 la respuesta? El Cuerpo de la Guardia Revolucionaria Isl\u00e1mica. \u00bfQui\u00e9n tom\u00f3 la iniciativa? El Im\u00e1n de los Musulmanes.<\/p>\n\n\n\n<p class=\"comment\">El Im\u00e1n de los Musulmanes es otra forma de referirse al L\u00edder Al\u00ed Jamenei. En este pasaje, la lucha contra Estados Unidos se extiende a todo el planeta y no se detiene en Oriente Medio.\u00a0<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-large\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/03\/unnamed-40.png\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"512\"\n        data-pswp-height=\"324\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/03\/unnamed-40-330x209.png\"\r\n                media=\"(max-width: 374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/03\/unnamed-40.png\"\r\n                media=\"(max-width: 989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/03\/unnamed-40.png\"\r\n                media=\"(min-width: 990px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/03\/unnamed-40-125x79.png\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">Extracto de la presentaci\u00f3n en Power Point de Abbasi<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<p class=\"comment\">Se supone que este mapa muestra el supuesto plan de Estados Unidos de dividir Ir\u00e1n en varios Estados, cada uno de los cuales unir\u00eda a un grupo \u00e9tnico dominante en la regi\u00f3n en cuesti\u00f3n. Evidentemente no se basa en ninguna realidad, y es sobre todo un s\u00edntoma de la oposici\u00f3n radical de la Rep\u00fablica Isl\u00e1mica, y en particular de la Guardia Revolucionaria, desde 1979, a cualquier forma de separatismo en un pa\u00eds donde la etnia mayoritaria s\u00f3lo representa entre el 55 y el 65% de la poblaci\u00f3n. Mientras que el proyecto de crear un Kurdist\u00e1n aut\u00f3nomo se ha debatido largo y tendido y hubo un Gobierno Popular de Azerbaiy\u00e1n durante un a\u00f1o en 1945-1946, creado en el marco de la crisis irano-sovi\u00e9tica, la idea de un \u00abArabist\u00e1n\u00bb o un \u00abBaluchist\u00e1n iran\u00ed\u00bb parece ser una invenci\u00f3n total de Hassan Abbasi.<\/p>\n\n\n\n<p>Los que ahora hablan de la ruptura de Ir\u00e1n alientan a los separatistas iran\u00edes en Europa y Am\u00e9rica. Les dan tribunas con las banderas de las diferentes regiones \u00e9tnicas de Ir\u00e1n en las calles de Alemania, B\u00e9lgica, Holanda, Francia, Inglaterra, Am\u00e9rica y Canad\u00e1.<\/p>\n\n\n\n<p>Han pasado muchas cosas en los \u00faltimos treinta a\u00f1os. Hemos sido testigos del debilitamiento del liberalismo, de los problemas en las esferas econ\u00f3mica y financiera, y de <a href=\"https:\/\/legrandcontinent.eu\/es\/2022\/02\/18\/el-imperio-y-el-orden-mundial-segun-jiang-shigong\/\">los problemas sociales y psicol\u00f3gicos de los Estados liberales<\/a>.&nbsp;<\/p>\n\n\n\n<p>El r\u00e9gimen baasista de Sadam nos atac\u00f3 con ayuda occidental. Esa guerra termin\u00f3 en 1988. Esta \u00abguerra impuesta\u00bb contra Ir\u00e1n dur\u00f3 ocho a\u00f1os, contra la sagrada defensa, pero todo el mundo la ha olvidado. Pero la guerra que nosotros vivimos dur\u00f3 30 a\u00f1os.&nbsp;<\/p>\n\n\n\n<p class=\"comment\">Esta es una parte obligatoria de cualquier discurso de pol\u00edtica exterior iran\u00ed, destinada a recordar lo que el poder pol\u00edtico iran\u00ed percibe como la culpa original m\u00e1s evidente de las potencias occidentales: el masivo apoyo militar occidental prestado a Sadam Husein durante la larga guerra que enfrent\u00f3 a Irak con la Rep\u00fablica Isl\u00e1mica de Ir\u00e1n, de 1980 a 1988. Esta guerra se conoce en persa como \u00abla guerra impuesta\u00bb (<em>djang-\u00e9 tahmili<\/em>), mientras que la lucha iran\u00ed durante esta guerra se describe como \u00abla defensa sagrada\u00bb (<em>d\u00e9f\u00e2h-\u00e9 moqadas<\/em>). La gran mayor\u00eda de los actuales dirigentes de la Rep\u00fablica Isl\u00e1mica y todos los generales de la Guardia Revolucionaria comenzaron sus carreras pol\u00edticas y militares durante el conflicto.<\/p>\n\n\n\n<p class=\"comment\">La denuncia de la ayuda occidental a Sadam Husein durante la guerra Ir\u00e1n-Irak es un punto de consenso dentro del sistema pol\u00edtico iran\u00ed, desde los m\u00e1s moderados hasta los m\u00e1s conservadores. Este argumento se utiliza en particular para justificar la existencia del programa de misiles bal\u00edsticos de Ir\u00e1n, alegando que, durante la guerra contra Irak, las ciudades iran\u00edes fueron bombardeadas en numerosas ocasiones, pero no pudieron tomar represalias por falta de misiles bal\u00edsticos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">2 &#8211; La Cuarta Guerra Mundial frustrada por la resistencia iran\u00ed<\/h2>\n\n\n\n<p>Viendo que la desintegraci\u00f3n de los Estados de Oriente Pr\u00f3ximo no funcionaba, intentaron cambiar la estrategia de la Cuarta Guerra Mundial atizando las tensiones religiosas entre Daesh, por un lado, y el Hezbol\u00e1 liban\u00e9s, por otro, con la esperanza de que la guerra extendida a sun\u00edes y chi\u00edes ayudara a destruir el mundo isl\u00e1mico.<\/p>\n\n\n\n<p class=\"comment\">Hassan Abbasi hace referencia a un art\u00edculo de Richard N. Hass en <em>Project Syndicate<\/em>, 21 de julio de 2014, \u00abThe New Thirty Years War\u00bb, del que muestra una captura de pantalla a su audiencia en ese momento.<\/p>\n\n\n\n<p>Ir\u00e1n ha escapado a la Cuarta Guerra Mundial. Sin embargo, como muestra el director Oliver Stone en la pel\u00edcula <em>W<\/em>, que narra la vida de George W. Bush, el plan original de Estados Unidos era ir a por Ir\u00e1n. En una escena de la pel\u00edcula, Dick Cheney, el vicepresidente estadounidense, propone atacar a Ir\u00e1n a trav\u00e9s de Iraq y Afganist\u00e1n, para \u00abdesecar el pantano\u00bb y hacerse con el petr\u00f3leo.&nbsp;<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-large\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/03\/unnamed-41.png\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"512\"\n        data-pswp-height=\"275\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/03\/unnamed-41-330x177.png\"\r\n                media=\"(max-width: 374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/03\/unnamed-41.png\"\r\n                media=\"(max-width: 989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/03\/unnamed-41.png\"\r\n                media=\"(min-width: 990px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/03\/unnamed-41-125x67.png\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">Escena de la pel\u00edcula W de Oliver Stone (2008). Extracto de la presentaci\u00f3n en Power Point de Abbasi<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<p>Dentro del Partido Republicano, hay dos grupos: los halcones y las palomas. Los halcones incluyen a Paul Wolfowitz y a sus allegados, como Condoleezza Rice y Eliot A. Cohen, que han intentado implantar la Cuarta Guerra Mundial. Eliot A. Cohen escribi\u00f3 oficialmente que Estados Unidos estaba librando la Cuarta Guerra Mundial. El objetivo principal era atacar Ir\u00e1n y destruir el Islam.<\/p>\n\n\n\n<p class=\"comment\">Hassan Abbasi se refiere a un art\u00edculo de Eliot A. Cohen, asesor de Condolezza Rice de 2007 a 2009, y ahora profesor en la Escuela Paul H. Nitze de Estudios Internacionales Avanzados de la Universidad Johns-Hopkins, escrito en el <em>Washington Post<\/em> el 20 de noviembre de 2001 y titulado \u00abWorld War IV\u00bb.<\/p>\n\n\n\n<p>La Cuarta Guerra Mundial est\u00e1 llegando a su fin gracias al camino mostrado por la Rep\u00fablica Isl\u00e1mica, y sobre todo gracias a los preceptos del L\u00edder Supremo, que era consciente de la naturaleza de esta Cuarta Guerra Mundial incluso antes de que se declarara. Su capacidad para advertirnos es un testimonio de su sabidur\u00eda y de su gracia especial, que es la gracia de Dios.&nbsp;<\/p>\n\n\n\n<p>De hecho, los estadounidenses tuvieron que huir de Afganist\u00e1n en el verano de 2021. Irak, mientras tanto, ya no es estadounidense, sino que est\u00e1 en manos del Hachd al-Shaabi.&nbsp;<\/p>\n\n\n\n<p>Hoy anunciamos el fin de la Cuarta Guerra Mundial, el fin de la reconstrucci\u00f3n pol\u00edtica del Gran Oriente Medio, el fin de la guerra de religi\u00f3n. Ha comenzado un nuevo cap\u00edtulo, que llamamos: la nueva guerra fr\u00eda.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">3 &#8211; La nueva guerra fr\u00eda<\/h2>\n\n\n\n<p>Para comprender la configuraci\u00f3n de la nueva guerra fr\u00eda, hemos representado en este gr\u00e1fico la OTAN mundial en tres ramas: la OTAN \u00e1rabe, la OTAN europea y la OTAN oriental, frente a las tres potencias regionales que las enfrentan. Dentro de cinco a\u00f1os, \u00e9sta ser\u00e1 la hoja de ruta para todos, no s\u00f3lo para Ir\u00e1n.&nbsp;<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-large\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/03\/unnamed-42.png\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"512\"\n        data-pswp-height=\"336\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/03\/unnamed-42-330x217.png\"\r\n                media=\"(max-width: 374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/03\/unnamed-42.png\"\r\n                media=\"(max-width: 989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/03\/unnamed-42.png\"\r\n                media=\"(min-width: 990px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/03\/unnamed-42-125x82.png\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">Extracto de la presentaci\u00f3n en Power Point de Abbasi<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<p>Si detr\u00e1s de la bandera estadounidense vemos la ideolog\u00eda liberal-sionista, detr\u00e1s de las banderas de Rusia, Ir\u00e1n y China vemos respectivamente la ortodoxia, el islam y el social-confucianismo. Estas tres ideolog\u00edas difieren de la ideolog\u00eda liberal.<\/p>\n\n\n\n<p>Durante la anterior Guerra Fr\u00eda, \u00bfcu\u00e1l fue el lugar de m\u00e1xima tensi\u00f3n? La ciudad de Berl\u00edn, rodeada por su muro. Cuando cay\u00f3 el Muro de Berl\u00edn, termin\u00f3 la primera guerra fr\u00eda.&nbsp;<\/p>\n\n\n\n<p class=\"comment\">El tema de <a href=\"https:\/\/legrandcontinent.eu\/es\/2023\/12\/09\/el-futuro-de-la-segunda-guerra-fria\/\">la nueva guerra fr\u00eda<\/a> y la idea de una alianza natural entre China, Rusia e Ir\u00e1n, es una continuaci\u00f3n de la pol\u00edtica exterior de \u00abmirada hacia el Este\u00bb, lanzada por Mahmud Ahmadineyad durante su presidencia y que ya hab\u00eda hecho su aggiornamento en un Di\u00e1logo de Seguridad Regional organizado en octubre de 2018 en Teher\u00e1n, donde se habl\u00f3 de \u00abMirada hacia el Este 2.0\u00bb.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Los tres Berl\u00edn de la nueva guerra fr\u00eda<\/h3>\n\n\n\n<p>En esta nueva guerra fr\u00eda, hay tres Berl\u00edn.&nbsp;<\/p>\n\n\n\n<p>El primer Berl\u00edn es Ucrania; el segundo Berl\u00edn es Palestina; y el tercer Berl\u00edn es Taiw\u00e1n. Cada una de las tres potencias, Rusia, China e Ir\u00e1n, est\u00e1 detr\u00e1s de un punto de tensi\u00f3n: Rusia detr\u00e1s de Ucrania; China detr\u00e1s de Taiw\u00e1n; la Revoluci\u00f3n Isl\u00e1mica y la Rep\u00fablica Isl\u00e1mica detr\u00e1s de Palestina.\u00a0<\/p>\n\n\n\n<p>Cada Berl\u00edn podr\u00eda representar el fracaso o el \u00e9xito de cada uno de estos actores. Si la civilizaci\u00f3n liberal se retira de Ucrania, es porque ha fracasado all\u00ed. Si la civilizaci\u00f3n liberal se retira de Taiw\u00e1n, es que all\u00ed ha fracasado. Si la civilizaci\u00f3n liberal se retira de Palestina, es porque all\u00ed ha fracasado. Las derrotas y las victorias de esta nueva guerra fr\u00eda se producir\u00e1n en estos tres campos de batalla.&nbsp;<\/p>\n\n\n\n<p>Todos los acontecimientos recientes pueden resumirse en este esquema. La evoluci\u00f3n y los movimientos estrat\u00e9gicos suelen durar al menos 25 a\u00f1os y a menudo abarcan dos generaciones, es decir, 50 a\u00f1os. Tenemos que hacer evolucionar nuestro pensamiento estrat\u00e9gico alej\u00e1ndonos de los conceptos de la Cuarta Guerra Mundial y adoptar las coordenadas de la nueva guerra fr\u00eda.&nbsp;<\/p>\n\n\n\n<p>Se trata de un mundo dividido en cuatro polos ideol\u00f3gicos, tres de los cuales se enfrentan a un enemigo com\u00fan: la civilizaci\u00f3n liberal.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">La Trilateral en la nueva guerra fr\u00eda<\/h3>\n\n\n\n<p>En la anterior guerra fr\u00eda, el Trilateralismo estuvo del lado de la civilizaci\u00f3n occidental, a trav\u00e9s de la alianza entre Norteam\u00e9rica, Europa Occidental y Jap\u00f3n. En la nueva guerra fr\u00eda, el Trilateralismo apareci\u00f3 en el lado opuesto: los rusos ortodoxos, los chinos confucianos sociales y los iran\u00edes musulmanes crearon una nueva Trilateral.<\/p>\n\n\n\n<p>Me refiero al concepto de este libro, <em>The Trilateral Commission and Elite Planning for World Management<\/em>.<\/p>\n\n\n\n<p>Cualquiera que quiera entender la forma en que se organiza el mundo hoy en d\u00eda necesita comprender el concepto Trilateral. El nuevo trilateralismo une a China, Ir\u00e1n y Rusia, que no est\u00e1n unidos por la ideolog\u00eda, sino por su pertenencia com\u00fan al Pacto de Shanghai y su oposici\u00f3n a la ideolog\u00eda liberal.<\/p>\n\n\n\n<p class=\"comment\">La referencia a la Comisi\u00f3n Trilateral es un <em>topos<\/em> del discurso conspiracionista. En este caso, parece tanto menos justificada cuanto que los \u00abtr\u00edpticos\u00bb opuestos de Abbasi tienen poco en com\u00fan. El t\u00e9rmino \u00abtrilateralismo\u00bb se esgrime como un eslogan que no tiene ninguna base en la realidad: se trata esencialmente de un intento de poner a Ir\u00e1n al mismo nivel que China o Rusia.<\/p>\n\n\n\n<p>Estados Unidos est\u00e1 obligado a defender a sus aliados en Ucrania, en el frente oriental, y a defender su basti\u00f3n en Taiw\u00e1n para que no se derrumbe. Debe defender su posici\u00f3n en el frente intermedio en Palestina para que el r\u00e9gimen sionista no se derrumbe y no se vea obligado a retirarse de Palestina.&nbsp;<\/p>\n\n\n\n<p>En resumen, en los \u00faltimos a\u00f1os la civilizaci\u00f3n liberal ha creado tres frentes, tres Berl\u00edn, donde se jugar\u00e1 el futuro del mundo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Algo profundo se est\u00e1 moviendo en Ir\u00e1n. Mientras el L\u00edder Supremo ten\u00eda un plan para contrarrestar a Washington con Rusia y China, Teher\u00e1n podr\u00eda estar dando un vuelco. Por primera vez, traducimos al espa\u00f1ol un texto fundamental de Hassan Abbasi: ide\u00f3logo pr\u00f3ximo al r\u00e9gimen, en el coraz\u00f3n de la opaca estructura de una teocracia preocupada, articula, en l\u00edneas puramente complotistas, el esquema de una geopol\u00edtica de la confrontaci\u00f3n mundial.<\/p>\n","protected":false},"author":1366,"featured_media":30497,"comment_status":"closed","ping_status":"","sticky":false,"template":"templates\/post-speeches.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":17,"_lgc_tts_audio_url":"","_lgc_tts_voice":"","_lgc_tts_publish":false,"_lgc_tts_history_item_id":"","_lgc_tts_generated_at":"","_lgc_tts_status":"","_lgc_tts_error":"","footnotes":""},"categories":[6],"tags":[],"staff":[185],"editorial_format":[1474],"serie":[],"audience":[],"geo":[196],"class_list":["post-30510","post","type-post","status-publish","format-standard","hentry","category-politica","staff-pierre-ramond","editorial_format-archivos-y-discursos","geo-asia-central"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":30497,"excerpt":"Algo profundo se est\u00e1 moviendo en Ir\u00e1n. Mientras el L\u00edder Supremo ten\u00eda un plan para contrarrestar a Washington con Rusia y China, Teher\u00e1n podr\u00eda estar dando un vuelco. Por primera vez, traducimos al espa\u00f1ol un texto fundamental de Hassan Abbasi: ide\u00f3logo pr\u00f3ximo al r\u00e9gimen, en el coraz\u00f3n de la opaca estructura de una teocracia preocupada, articula, en l\u00edneas puramente complotistas, el esquema de una geopol\u00edtica de la confrontaci\u00f3n mundial.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>China, Rusia, Ir\u00e1n: la guerra mundial vista por el \u00abKissinger persa\u00bb - El Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/es\/2024\/03\/02\/china-rusia-iran-la-guerra-mundial-vista-por-el-kissinger-persa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"China, Rusia, Ir\u00e1n: la guerra mundial vista por el \u00abKissinger persa\u00bb - El Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Algo profundo se est\u00e1 moviendo en Ir\u00e1n. Mientras el L\u00edder Supremo ten\u00eda un plan para contrarrestar a Washington con Rusia y China, Teher\u00e1n podr\u00eda estar dando un vuelco. Por primera vez, traducimos al espa\u00f1ol un texto fundamental de Hassan Abbasi: ide\u00f3logo pr\u00f3ximo al r\u00e9gimen, en el coraz\u00f3n de la opaca estructura de una teocracia preocupada, articula, en l\u00edneas puramente complotistas, el esquema de una geopol\u00edtica de la confrontaci\u00f3n mundial.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/es\/2024\/03\/02\/china-rusia-iran-la-guerra-mundial-vista-por-el-kissinger-persa\/\" \/>\n<meta property=\"og:site_name\" content=\"El Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-02T18:01:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-02T18:01:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/03\/gc-elabbasi-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"florent\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/03\/gc-elabbasi-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"florent\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"17 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/03\/02\/china-rusia-iran-la-guerra-mundial-vista-por-el-kissinger-persa\/\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/2024\/03\/02\/china-rusia-iran-la-guerra-mundial-vista-por-el-kissinger-persa\/\",\"name\":\"China, Rusia, Ir\u00e1n: la guerra mundial vista por el \u00abKissinger persa\u00bb - El Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/03\/02\/china-rusia-iran-la-guerra-mundial-vista-por-el-kissinger-persa\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/03\/02\/china-rusia-iran-la-guerra-mundial-vista-por-el-kissinger-persa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/03\/SIPA_shutterstock40856631_000018-2-scaled.jpg\",\"datePublished\":\"2024-03-02T18:01:29+00:00\",\"dateModified\":\"2024-03-02T18:01:32+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/03\/02\/china-rusia-iran-la-guerra-mundial-vista-por-el-kissinger-persa\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/es\/2024\/03\/02\/china-rusia-iran-la-guerra-mundial-vista-por-el-kissinger-persa\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/03\/02\/china-rusia-iran-la-guerra-mundial-vista-por-el-kissinger-persa\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/03\/SIPA_shutterstock40856631_000018-2-scaled.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/03\/SIPA_shutterstock40856631_000018-2-scaled.jpg\",\"width\":2560,\"height\":1709,\"caption\":\"\u00a9 Sobhan Farajvan\/Pacific Press\/Shutterstock\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/03\/02\/china-rusia-iran-la-guerra-mundial-vista-por-el-kissinger-persa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/legrandcontinent.eu\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"China, Rusia, Ir\u00e1n: la guerra mundial vista por el \u00abKissinger persa\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/\",\"name\":\"El Grand Continent\",\"description\":\"La escala pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\",\"name\":\"florent\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"caption\":\"florent\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"China, Rusia, Ir\u00e1n: la guerra mundial vista por el \u00abKissinger persa\u00bb - El Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/es\/2024\/03\/02\/china-rusia-iran-la-guerra-mundial-vista-por-el-kissinger-persa\/","og_locale":"es_ES","og_type":"article","og_title":"China, Rusia, Ir\u00e1n: la guerra mundial vista por el \u00abKissinger persa\u00bb - El Grand Continent","og_description":"Algo profundo se est\u00e1 moviendo en Ir\u00e1n. Mientras el L\u00edder Supremo ten\u00eda un plan para contrarrestar a Washington con Rusia y China, Teher\u00e1n podr\u00eda estar dando un vuelco. Por primera vez, traducimos al espa\u00f1ol un texto fundamental de Hassan Abbasi: ide\u00f3logo pr\u00f3ximo al r\u00e9gimen, en el coraz\u00f3n de la opaca estructura de una teocracia preocupada, articula, en l\u00edneas puramente complotistas, el esquema de una geopol\u00edtica de la confrontaci\u00f3n mundial.","og_url":"https:\/\/legrandcontinent.eu\/es\/2024\/03\/02\/china-rusia-iran-la-guerra-mundial-vista-por-el-kissinger-persa\/","og_site_name":"El Grand Continent","article_published_time":"2024-03-02T18:01:29+00:00","article_modified_time":"2024-03-02T18:01:32+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/03\/gc-elabbasi-scaled.jpg","type":"image\/jpeg"}],"author":"florent","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/03\/gc-elabbasi-scaled.jpg","twitter_misc":{"Escrito por":"florent","Tiempo de lectura":"17 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/es\/2024\/03\/02\/china-rusia-iran-la-guerra-mundial-vista-por-el-kissinger-persa\/","url":"https:\/\/legrandcontinent.eu\/es\/2024\/03\/02\/china-rusia-iran-la-guerra-mundial-vista-por-el-kissinger-persa\/","name":"China, Rusia, Ir\u00e1n: la guerra mundial vista por el \u00abKissinger persa\u00bb - El Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/es\/2024\/03\/02\/china-rusia-iran-la-guerra-mundial-vista-por-el-kissinger-persa\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/es\/2024\/03\/02\/china-rusia-iran-la-guerra-mundial-vista-por-el-kissinger-persa\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/03\/SIPA_shutterstock40856631_000018-2-scaled.jpg","datePublished":"2024-03-02T18:01:29+00:00","dateModified":"2024-03-02T18:01:32+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/es\/2024\/03\/02\/china-rusia-iran-la-guerra-mundial-vista-por-el-kissinger-persa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/es\/2024\/03\/02\/china-rusia-iran-la-guerra-mundial-vista-por-el-kissinger-persa\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/2024\/03\/02\/china-rusia-iran-la-guerra-mundial-vista-por-el-kissinger-persa\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/03\/SIPA_shutterstock40856631_000018-2-scaled.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/03\/SIPA_shutterstock40856631_000018-2-scaled.jpg","width":2560,"height":1709,"caption":"\u00a9 Sobhan Farajvan\/Pacific Press\/Shutterstock"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/es\/2024\/03\/02\/china-rusia-iran-la-guerra-mundial-vista-por-el-kissinger-persa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legrandcontinent.eu\/es\/"},{"@type":"ListItem","position":2,"name":"China, Rusia, Ir\u00e1n: la guerra mundial vista por el \u00abKissinger persa\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/es\/#website","url":"https:\/\/legrandcontinent.eu\/es\/","name":"El Grand Continent","description":"La escala pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c","name":"florent","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","caption":"florent"}}]}},"lgc_categories":[{"id":6,"name":"Pol\u00edtica","slug":"politica"}],"lgc_author":{"id":185,"name":"Pierre Ramond","slug":"pierre-ramond","description":null,"first_name":null,"last_name":null,"picture":null},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/03\/SIPA_shutterstock40856631_000018-2-scaled.jpg","width":2560,"height":1709,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/03\/SIPA_shutterstock40856631_000018-2-scaled.jpg","width":2560,"height":1709,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/30510","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/users\/1366"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/comments?post=30510"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/30510\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media\/30497"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media?parent=30510"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/categories?post=30510"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/tags?post=30510"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/staff?post=30510"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/editorial_format?post=30510"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/serie?post=30510"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/audience?post=30510"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/geo?post=30510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}