{"id":28307,"date":"2024-01-12T19:37:55","date_gmt":"2024-01-12T18:37:55","guid":{"rendered":"https:\/\/legrandcontinent.eu\/es\/?p=28307"},"modified":"2024-01-20T11:56:31","modified_gmt":"2024-01-20T10:56:31","slug":"hay-un-60-de-posibilidades-de-que-trump-vuelva-a-la-casa-blanca-una-conversacion-con-niall-ferguson-1","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/es\/2024\/01\/12\/hay-un-60-de-posibilidades-de-que-trump-vuelva-a-la-casa-blanca-una-conversacion-con-niall-ferguson-1\/","title":{"rendered":"\u00abHay un 60% de posibilidades de que Trump vuelva a la Casa Blanca\u00bb, una conversaci\u00f3n con Niall Ferguson"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\"><strong>Como brit\u00e1nico residente en Estados Unidos cuyo trabajo se ha centrado tambi\u00e9n en Europa, debe de sentirse tentado a establecer comparaciones. \u00bfC\u00f3mo ve la situaci\u00f3n actual de la Uni\u00f3n?<\/strong><\/h3>\n\n\n\n<p>Aunque vivo y trabajo en Estados Unidos desde hace casi veinte a\u00f1os, mis opiniones sobre la evoluci\u00f3n reciente de la Uni\u00f3n est\u00e1n, en efecto, profundamente influidas por mis ra\u00edces escocesas y mi identidad brit\u00e1nica \u2013a pesar de mi ciudadan\u00eda estadounidense desde 2018\u2013. La identidad europea siempre ha sido un sentimiento muy fuerte para m\u00ed.<\/p>\n\n\n\n<p>Durante la saga del Brexit, me aline\u00e9 con los partidarios del <em>Remain<\/em>, siendo testigo de lo que percib\u00ed como un momento crucial en la historia brit\u00e1nica y europea. Hoy, mientras observo las cosas desde otra orilla del Atl\u00e1ntico, me sorprende el hecho de que el Brexit puede haber facilitado, casi inadvertidamente, una integraci\u00f3n mucho m\u00e1s coherente en la Uni\u00f3n. Es una evoluci\u00f3n que parece haber cogido por sorpresa a algunos cr\u00edticos en el Reino Unido.<\/p>\n\n\n\n<p>En lo que respecta a Estados Unidos, la historia es diferente. Aunque hay que reconocer que la Uni\u00f3n ha actuado para gestionar las recientes crisis a las que se ha enfrentado \u2013incluida su estrategia econ\u00f3mica y sus esfuerzos para hacer frente a una desaceleraci\u00f3n o recesi\u00f3n\u2013, tambi\u00e9n hay que reconocer que esta actuaci\u00f3n ha seguido siendo insuficiente. La situaci\u00f3n econ\u00f3mica de Alemania, por ejemplo, que coquetea con la recesi\u00f3n, ha suscitado comparaciones con los retos econ\u00f3micos de Jap\u00f3n, a pesar de las diferencias en el nivel de intervenci\u00f3n fiscal y monetaria. Desde una perspectiva estadounidense, el contraste entre las respuestas a estas crisis es especialmente llamativo. A fin de cuentas, hay algo dif\u00edcil de ignorar: a Estados Unidos le ha ido mejor econ\u00f3micamente que a Europa durante estos a\u00f1os de crisis.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>A fin de cuentas, hay algo dif\u00edcil de ignorar: a Estados Unidos le ha ido mejor econ\u00f3micamente que a Europa durante estos a\u00f1os de crisis.<\/p><cite>NIALL FERGUSON<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>A medida que nos adentramos en un a\u00f1o electoral muy cargado y la guerra sigue extendi\u00e9ndose, \u00bfen qu\u00e9 situaci\u00f3n se encuentra hoy Estados Unidos?<\/strong><\/h3>\n\n\n\n<p>Washington define hoy su papel esencialmente por su adhesi\u00f3n bipartidista a la agenda de \u00ab<em>America first<\/em>\u00ab. Esta frase, resucitada casi accidentalmente durante la campa\u00f1a de Trump en 2016 \u2013en su momento quiz\u00e1 fue sugerida por David Ignatius o David Sanger\u2013 se ha hecho eco, sin saberlo, de un importante sentimiento hist\u00f3rico.<\/p>\n\n\n\n<p>Sorprendentemente, al parecer, para la mayor\u00eda de los europeos, este enfoque ha continuado bajo la presidencia de Joe Biden. En los \u00faltimos tres a\u00f1os, los europeos se han sentido desilusionados porque esta presidencia no ha representado la mejora que esperaban. A pesar de la esperanzadora ret\u00f3rica de \u00ab<em>America is back<\/em>\u00bb y del regreso de los \u00ab<em>adults in the room<\/em>\u00ab, es dif\u00edcil discutir que Joe Biden ha perseguido una pol\u00edtica exterior pone Am\u00e9rica <em>primero<\/em> con al menos tanto fervor \u2013si no m\u00e1s\u2013 que Donald Trump. Y quiz\u00e1 tambi\u00e9n con m\u00e1s eficacia.<\/p>\n\n\n\n<p>En algunos aspectos, la Ley de Reducci\u00f3n de la Inflaci\u00f3n se considera m\u00e1s proteccionista que cualquiera de las pol\u00edticas arancelarias de Trump. La pol\u00edtica exterior de Joe Biden, en particular la ca\u00f3tica retirada de Afganist\u00e1n y el fracaso a la hora de disuadir a Putin de invadir Ucrania, ha sido una serie de decepciones. Esto se extiende al manejo de Ir\u00e1n y sus <em>proxies<\/em> contra Israel. A medida que entramos en un nuevo a\u00f1o de la administraci\u00f3n Biden, el entusiasmo europeo inicial por su victoria en 2020 ha disminuido considerablemente.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Al entrar en un nuevo a\u00f1o de la administraci\u00f3n Biden, el entusiasmo europeo inicial por su victoria en 2020 ha disminuido considerablemente.<\/p><cite>NIALL FERGUSON<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Sin embargo, en el contexto de <a href=\"https:\/\/legrandcontinent.eu\/es\/2022\/07\/12\/la-segunda-guerra-fria\/\">lo que podr\u00eda llamarse la Segunda Guerra Fr\u00eda<\/a>, Estados Unidos sigue siendo una de las dos superpotencias \u2013un estatus que ahora depende no s\u00f3lo de sus capacidades nucleares, sino tambi\u00e9n de la destreza tecnol\u00f3gica en \u00e1reas como la inteligencia artificial y la computaci\u00f3n cu\u00e1ntica\u2013. En estos \u00e1mbitos, Europa est\u00e1 lejos de ser un actor importante, lo que subraya la creciente brecha entre las dos superpotencias y el resto del mundo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00bfNo podr\u00eda ser \u00e9sta una oportunidad para reforzar la autonom\u00eda estrat\u00e9gica de la Uni\u00f3n?<\/strong><\/h3>\n\n\n\n<p>Para decirlo brutalmente: no.&nbsp;<\/p>\n\n\n\n<p>La idea de que Europa podr\u00eda elegir su camino de forma independiente \u2013un tema de debate en Berl\u00edn y Francia\u2013 es una pista falsa ante una crisis potencial, como la que podr\u00eda estallar en torno a Taiw\u00e1n tras las elecciones. En realidad, Europa, que sigue dependiendo en gran medida de Estados Unidos para su seguridad, no tiene realmente opciones. Si bien el concepto y el modelo de no alineamiento pueden haber tenido sentido durante la primera Guerra Fr\u00eda, es poco probable que podamos articular una posici\u00f3n similar durante la segunda.<\/p>\n\n\n<section class=\"dive print-block my-16\" style=\"background-color:;\">\n\t<div class=\"wrapper\">\n\t\t<div class=\"container mx-auto \">\n\t\t\t<div class=\"row flex flex-wrap relative pt-6 pb-16 lg:py-8\">\n\t\t\t\t<div class=\"col w-full xl:ml-1\/10\n\t\t\t\t\t md:w-2\/5 xl:w-2\/5 \t\t\t\t\t\">\n\t\t\t\t\t<a href=\"https:\/\/legrandcontinent.eu\/es\/ofiertas-new\/\" style=\"color:#0a0a0a;\" class=\"font-display font-normal text-4xl leading-9 mb-5 text-white no-underline\">\n\t\t\t\t\t\tFracturas de la guerra ampliada\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<div style=\"color:#0a0a0a;\" class=\"text-base leading-none font-sans\">\n\t\t\t\t\t\t\t<p>Las claves de un mundo roto.<\/p>\n<p>Desde el centro del globo hasta sus fronteras m\u00e1s lejanas, la guerra est\u00e1 aqu\u00ed. La invasi\u00f3n de Ucrania por la Rusia de Putin nos ha golpeado duramente, pero no basta con comprender este enfrentamiento crucial.<\/p>\n<p>Nuestra \u00e9poca est\u00e1 atravesada por un fen\u00f3meno oculto y estructurante que proponemos denominar: guerra ampliada.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"mt-12 dive-list\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a  style=\"color:#000000;\" class=\"no-underline block border-t border-grey-darker py-2 flex\"\n\t\t\t\t\t\t\t\t   href=\"https:\/\/legrandcontinent.eu\/es\/ofiertas-new\/\"><span class=\"font-sans font-semibold pr-4\">\u2192<\/span> Pedir el volumen<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a  style=\"color:#000000;\" class=\"no-underline block border-t border-grey-darker py-2 flex\"\n\t\t\t\t\t\t\t\t   href=\"https:\/\/legrandcontinent.eu\/es\/ofiertas-new\/\"><span class=\"font-sans font-semibold pr-4\">\u2192<\/span> Descubran nuestras ofertas<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a  style=\"color:#000000;\" class=\"no-underline block border-t border-grey-darker py-2 flex\"\n\t\t\t\t\t\t\t\t   href=\"https:\/\/legrandcontinent.eu\/shop\/produit\/politiques-de-linterregne\/\"><span class=\"font-sans font-semibold pr-4\">\u2192<\/span> \u00bfYa es suscriptor? Pida el n\u00famero anterior<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div style=\"color:#0a0a0a;\" class=\"dive-footer font-sans text-xs border-t border-grey-darker py-2 leading-4\">\n\t\t\t\t\t\t\t<p><em>Fracturas de la guerra ampliada: de Ucrania al metaverso<\/em>, el nuevo volumen en papel del Grand Continent se publica hoy en la editorial del C\u00edrculo de Bellas Artes. Est\u00e1 disponible para <a href=\"https:\/\/legrandcontinent.eu\/es\/ofiertas-new\/\">su compra<\/a> e incluido en nuestra <a href=\"https:\/\/legrandcontinent.eu\/es\/ofiertas-new\/\">oferta de lanzamiento<\/a>.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"col w-full md:w-3\/5 xl:w-2\/5  md:px-0 relative overflow-hidden mt-8 md:mt-0 macron-img\">\n\t\t\t\t\t\t\t\t<a class=\"!absolute !bg-none w-full h-full pin-t pin-l\" href=\"https:\/\/legrandcontinent.eu\/es\/ofiertas-new\/\" class=\"no-underline\">\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" style=\"object-fit: contain; width: 100%; height: 100%;\" src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/01\/mediamodifier_image-99-990x660.png\" \/>\n\t\t\t\t\t\t\t\t<\/a> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n\n<p>El intento de la Uni\u00f3n de mantenerse no alineada ante estos nuevos retos globales no ser\u00eda una opci\u00f3n viable. Puede que los votantes alemanes, por ejemplo, a\u00fan no lo reconozcan plenamente, pero es inevitable. El camino hacia la autonom\u00eda estrat\u00e9gica \u2013y quiz\u00e1 incluso hacia el estatus de superpotencia\u2013 es largo. Requiere transformaciones a lo largo de varios a\u00f1os. Pero ser\u00eda poco realista esperar el r\u00e1pido desarrollo de un complejo militar-industrial a escala europea, especialmente dada la naturaleza inmediata y urgente de los retos que tenemos por delante. El tiempo de que disponemos para actuar es limitado.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Europa, que sigue dependiendo en gran medida de Estados Unidos para su seguridad, no tiene realmente opciones.<\/p><cite>NIALL FERGUSON<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Dada esta urgencia, \u00bfc\u00f3mo ve las elecciones estadounidenses?<\/strong><\/h3>\n\n\n\n<p><a href=\"https:\/\/legrandcontinent.eu\/es\/2023\/08\/28\/bidenomics-por-su-creador-una-conversacion-con-brian-deese\/\"><em>Bidenomics<\/em> han sido una pol\u00edtica p\u00fablica excelente sobre el papel<\/a>, pero los estadounidenses la odian. La percepci\u00f3n del estado de la econom\u00eda es alarmante y negativa. Las encuestas de opini\u00f3n son similares a las de 2009, tras la mayor crisis financiera desde los a\u00f1os setenta o incluso los treinta. Esto supone un grave problema para los estrategas dem\u00f3cratas, que pretend\u00edan hacer campa\u00f1a precisamente sobre los m\u00e9ritos de <em>Bidenomics<\/em>. Los sondeos actuales muestran que son superados ampliamente por los republicanos, sobre todo en el terreno econ\u00f3mico, donde Donald Trump est\u00e1 mostrando una fuerza y una resistencia considerables.<\/p>\n\n\n\n<p>Los dem\u00f3cratas se encuentran pues en un callej\u00f3n sin salida, sin soluci\u00f3n aparente. Las limitaciones de tiempo no permitir\u00e1n sustituir a Biden y, si \u00e9l no pudiera hacerlo, la vicepresidenta Kamala Harris tomar\u00eda el relevo. En cuanto a la nominaci\u00f3n republicana, Donald Trump se perfila como un formidable favorito \u2013posiblemente el m\u00e1s fuerte desde que se introdujo el sistema moderno de primarias a principios de la d\u00e9cada de 1970\u2013. Es poco probable que se materialicen las especulaciones sobre alternativas como Nikki Haley, con una probabilidad de \u00e9xito de s\u00f3lo alrededor del 10%.<\/p>\n\n\n\n<p>Por otro lado, cada acci\u00f3n legal contra Trump parece reforzar su apoyo entre los potenciales votantes republicanos. Esto me lleva a la preocupante conclusi\u00f3n de que existe una alta probabilidad \u2013que yo estimo en torno al 60%\u2013 de que Donald Trump vuelva a la Casa Blanca, convirti\u00e9ndose en el primer presidente desde Grover Cleveland que cumple dos mandatos no consecutivos. Un potencial segundo mandato que, por supuesto, es probable que sea muy diferente al de Grover Cleveland.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Estimo que las probabilidades de que Donald Trump vuelva a la Casa Blanca rondan el 60%.<\/p><cite>NIALL FERGUSON<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00bfC\u00f3mo ser\u00eda ese segundo mandato?<\/strong><\/h3>\n\n\n\n<p>Muy poca gente, incluso en Estados Unidos, entiende realmente lo diferente que ser\u00eda del primero. Muchos asumen que ser\u00eda como lo que Trump hizo entre 2017 y 2020: una pol\u00edtica caracterizada por una gobernanza ca\u00f3tica y una presencia controvertida en las redes sociales. Pero en este segundo mandato, no habr\u00eda <em>establishment<\/em> republicano ni generales del Pent\u00e1gono para atemperar sus acciones. Trump ha llegado a ver a la \u00e9lite militar como un adversario y se espera que dote a su administraci\u00f3n de figuras de think tanks como la Heritage Foundation y America First. A diferencia de 2017, cuando el enfoque era improvisado, ahora tiene un plan \u2013m\u00e1s radical y mejor definido\u2013.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00bfCu\u00e1les son sus l\u00edneas generales?<\/strong><\/h3>\n\n\n\n<p>En pol\u00edtica interior, parece centrarse en purgar la burocracia federal de figuras disidentes, empezando por el Departamento de Justicia y bajando hasta los niveles m\u00e1s profundos de la administraci\u00f3n. En pol\u00edtica exterior, la direcci\u00f3n es menos predecible, pero podr\u00eda implicar distanciarse de alianzas tradicionales como la OTAN, que \u00e9l ve como una relaci\u00f3n entre una Am\u00e9rica agraviada y una Europa aprovechada. Por no mencionar el hecho de que figuras clave del primer mandato, como H.R. McMaster y James Mattis, ya no estar\u00e1n para ejercer su influencia moderadora.<\/p>\n\n\n\n<p>Este escenario potencial subraya la crisis m\u00e1s amplia en la que ha entrado \u00abOccidente\u00bb, un concepto cada vez m\u00e1s marginado en los c\u00edrculos acad\u00e9micos progresistas. Las implicaciones de un segundo mandato de Trump ser\u00edan profundas. Ofrecer\u00edan importantes oportunidades a rivales geopol\u00edticos como China, Rusia e Ir\u00e1n. La crisis pondr\u00eda a prueba la resistencia de las instituciones y alianzas occidentales.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>A diferencia de 2017, cuando el planteamiento fue improvisado, Trump tiene ahora un plan \u2013m\u00e1s radical y mejor definido\u2013.<\/p><cite>NIALL FERGUSON<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00bfHay remedios para un escenario as\u00ed?<\/strong><\/h3>\n\n\n\n<p>En este contexto \u2013y no me canso de repetirlo\u2013, el mantenimiento de la alianza transatl\u00e1ntica se vuelve crucial. La idea de una autonom\u00eda estrat\u00e9gica europea, aunque atractiva, no es viable a corto plazo. La prioridad debe ser preservar la Alianza, proporcionar un apoyo eficaz a Ucrania e impedir que China explote las divisiones existentes, que ya han alcanzado un nivel estrat\u00e9gico cr\u00edtico. Este planteamiento resulta esencial si queremos hacer frente a los retos y crisis del futuro.<\/p>\n\n\n\n<p>Pero tambi\u00e9n nos incita a adoptar una perspectiva m\u00e1s amplia: el aislacionismo es un elemento estructurador de la filosof\u00eda \u00ab<em>America first<\/em>\u00ab, que resuena en todo el espectro pol\u00edtico de Estados Unidos. Este sentimiento es especialmente relevante en el contexto de la administraci\u00f3n de Joe Biden, donde cualquier implicaci\u00f3n que plantee la perspectiva de un conflicto prolongado es recibida con cr\u00edticas bipartidistas&#8230;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>La situaci\u00f3n en Ucrania es otro claro ejemplo de esta tendencia.<\/strong><\/h3>\n\n\n\n<p>Precisamente. E incluso antes de que Donald Trump gane la nominaci\u00f3n republicana, Ucrania ya se enfrenta a graves dificultades, como la escasez de municiones y la falta de apoyo financiero, mientras la C\u00e1mara de Representantes sigue mostr\u00e1ndose reacia a aprobar los fondos necesarios. Esta dif\u00edcil situaci\u00f3n no necesita la victoria de Trump para empeorar; los problemas ya est\u00e1n ah\u00ed.<\/p>\n\n\n\n<p>Estos desarrollos subrayan la urgente necesidad de que Europa consolide su posici\u00f3n y su respuesta. Las implicaciones de una derrota ucraniana ser\u00edan devastadoras para el continente; sus consecuencias son demasiado importantes para subestimarlas. En Oriente Pr\u00f3ximo, una victoria de Trump podr\u00eda verse parad\u00f3jicamente como favorable a Israel y perjudicial para Ir\u00e1n. Pero tal resultado probablemente ahondar\u00eda las desavenencias entre Estados Unidos y Europa sobre la regi\u00f3n, ya que sus perspectivas son marcadamente diferentes.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>En Oriente Medio, una victoria de Trump podr\u00eda verse parad\u00f3jicamente como favorable a Israel y perjudicial para Ir\u00e1n.<\/p><cite>NIALL FERGUSON<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00bfCree que la reelecci\u00f3n de Trump podr\u00eda provocar disturbios masivos?&nbsp;<\/strong><\/h3>\n\n\n\n<p>Por desgracia, me temo que sea cual sea el resultado de las elecciones del pr\u00f3ximo noviembre, la otra parte no lo aceptar\u00e1 como leg\u00edtimo. Las encuestas actuales, que muestran a Trump por delante en estados clave, sugieren una alta probabilidad de victoria. Si Trump es declarado vencedor la noche de las elecciones, creo que eso desencadenar\u00e1 protestas masivas, que podr\u00edan superar la intensidad de las que siguieron al asesinato de George Floyd.<\/p>\n\n\n\n<p>El aspecto alarmante de tal escenario es la respuesta potencial, particularmente en los estados republicanos. La represi\u00f3n de los manifestantes podr\u00eda ser mucho m\u00e1s dura que en 2020. Esta posibilidad es profundamente preocupante y plantea serias dudas sobre la estabilidad y la seguridad de la propia rep\u00fablica. Creo que tenemos raz\u00f3n al sentirnos aprensivos ante tal desenlace. Nuestra aprensi\u00f3n est\u00e1 justificada y subraya el precario estado de la pol\u00edtica estadounidense y la estabilidad social en caso de reelecci\u00f3n de Trump.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Ante este sombr\u00edo panorama, \u00bfqu\u00e9 debe hacer Europa?&nbsp;<\/strong><\/h3>\n\n\n\n<p>Su respuesta ser\u00e1 crucial, sobre todo si tenemos en cuenta la situaci\u00f3n de la pol\u00edtica interna alemana: el ascenso de la AfD, que alcanza el 20% en las encuestas, es quiz\u00e1 lo que m\u00e1s preocupa. Este ascenso no s\u00f3lo refleja cambios pol\u00edticos internos, sino que tambi\u00e9n env\u00eda una se\u00f1al de aliento a Putin, sobre todo dada la postura derrotista de la AfD respecto a Ucrania.<\/p>\n\n\n\n<p>Hacer frente a esta situaci\u00f3n no es s\u00f3lo una cuesti\u00f3n de estrategia pol\u00edtica; es un imperativo urgente para la supervivencia de los valores europeos. Hay mucho en juego y el futuro de Europa depende de su respuesta a estos nuevos desaf\u00edos.&nbsp;<\/p>\n\n\n\n<p>Sin embargo, como ahora soy estadounidense, intentar\u00e9 terminar con una nota de esperanza. Reflexionando sobre la historia de Europa, est\u00e1 claro que los grandes avances hacia la integraci\u00f3n y la unidad a menudo han sido catalizados por crisis. La situaci\u00f3n actual, con su mir\u00edada de crisis en ciernes, podr\u00eda impulsar a Europa hacia una mayor integraci\u00f3n. Esta v\u00eda de integraci\u00f3n cada vez m\u00e1s estrecha me parece estrat\u00e9gica si queremos evitar el desastre. Teniendo esto en cuenta, los numerosos retos a los que nos enfrentamos son intimidantes y aterradores. Pero debemos obligarnos a verlos como oportunidades para un progreso significativo y la unidad de Europa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abTrump tiene ahora un plan \u2014m\u00e1s radical, mejor definido\u2014. Europa, que sigue dependiendo de Washington para su seguridad, no tiene realmente opciones.\u00a0\u00bb Si es sin duda el m\u00e1s famoso de los historiadores brit\u00e1nicos, Niall Ferguson es tambi\u00e9n un sutil observador de las transformaciones econ\u00f3micas y pol\u00edticas a ambos lados del Atl\u00e1ntico. Desde el Valle de Aosta, al margen del Grand Continent Summit, nos ofrece sus perspectivas sobre un 2024 de alto riesgo.<\/p>\n","protected":false},"author":1366,"featured_media":28350,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-interviews.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":10,"footnotes":""},"categories":[724,718],"tags":[],"staff":[50],"editorial_format":[1473],"serie":[],"audience":[],"geo":[172],"class_list":["post-28307","post","type-post","status-publish","format-standard","hentry","category-trump-contra-biden-por-la-casa-blanca-seguir-las-elecciones-estadounidenses-de-2024","category-grand-continent-summit","staff-shahin-vallee","editorial_format-entrevistas","geo-americas"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":28350,"excerpt":"\u00abTrump tiene ahora un plan \u2014m\u00e1s radical, mejor definido\u2014. Europa, que sigue dependiendo de Washington para su seguridad, no tiene realmente opciones.\u00a0\u00bb Si es sin duda el m\u00e1s famoso de los historiadores brit\u00e1nicos, Niall Ferguson es tambi\u00e9n un sutil observador de las transformaciones econ\u00f3micas y pol\u00edticas a ambos lados del Atl\u00e1ntico. Desde el Valle de Aosta, al margen del Grand Continent Summit, nos ofrece sus perspectivas sobre un 2024 de alto riesgo.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00abHay un 60% de posibilidades de que Trump vuelva a la Casa Blanca\u00bb, una conversaci\u00f3n con Niall Ferguson - El Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/es\/2024\/01\/12\/hay-un-60-de-posibilidades-de-que-trump-vuelva-a-la-casa-blanca-una-conversacion-con-niall-ferguson-1\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00abHay un 60% de posibilidades de que Trump vuelva a la Casa Blanca\u00bb, una conversaci\u00f3n con Niall Ferguson - El Grand Continent\" \/>\n<meta property=\"og:description\" content=\"\u00abTrump tiene ahora un plan \u2014m\u00e1s radical, mejor definido\u2014. Europa, que sigue dependiendo de Washington para su seguridad, no tiene realmente opciones.\u00a0\u00bb Si es sin duda el m\u00e1s famoso de los historiadores brit\u00e1nicos, Niall Ferguson es tambi\u00e9n un sutil observador de las transformaciones econ\u00f3micas y pol\u00edticas a ambos lados del Atl\u00e1ntico. Desde el Valle de Aosta, al margen del Grand Continent Summit, nos ofrece sus perspectivas sobre un 2024 de alto riesgo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/es\/2024\/01\/12\/hay-un-60-de-posibilidades-de-que-trump-vuelva-a-la-casa-blanca-una-conversacion-con-niall-ferguson-1\/\" \/>\n<meta property=\"og:site_name\" content=\"El Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-12T18:37:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-20T10:56:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/01\/gc-elferguson-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"florent\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/01\/gc-elferguson-1-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"florent\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/01\/12\/hay-un-60-de-posibilidades-de-que-trump-vuelva-a-la-casa-blanca-una-conversacion-con-niall-ferguson-1\/\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/2024\/01\/12\/hay-un-60-de-posibilidades-de-que-trump-vuelva-a-la-casa-blanca-una-conversacion-con-niall-ferguson-1\/\",\"name\":\"\u00abHay un 60% de posibilidades de que Trump vuelva a la Casa Blanca\u00bb, una conversaci\u00f3n con Niall Ferguson - El Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/01\/12\/hay-un-60-de-posibilidades-de-que-trump-vuelva-a-la-casa-blanca-una-conversacion-con-niall-ferguson-1\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/01\/12\/hay-un-60-de-posibilidades-de-que-trump-vuelva-a-la-casa-blanca-una-conversacion-con-niall-ferguson-1\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/01\/SUMMIT_GRAND_CONTINENT_0993_Niall-Ferguson_B_umbertocostamagna\u00a92023-scaled.jpg\",\"datePublished\":\"2024-01-12T18:37:55+00:00\",\"dateModified\":\"2024-01-20T10:56:31+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/01\/12\/hay-un-60-de-posibilidades-de-que-trump-vuelva-a-la-casa-blanca-una-conversacion-con-niall-ferguson-1\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/es\/2024\/01\/12\/hay-un-60-de-posibilidades-de-que-trump-vuelva-a-la-casa-blanca-una-conversacion-con-niall-ferguson-1\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/01\/12\/hay-un-60-de-posibilidades-de-que-trump-vuelva-a-la-casa-blanca-una-conversacion-con-niall-ferguson-1\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/01\/SUMMIT_GRAND_CONTINENT_0993_Niall-Ferguson_B_umbertocostamagna\u00a92023-scaled.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/01\/SUMMIT_GRAND_CONTINENT_0993_Niall-Ferguson_B_umbertocostamagna\u00a92023-scaled.jpg\",\"width\":1919,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2024\/01\/12\/hay-un-60-de-posibilidades-de-que-trump-vuelva-a-la-casa-blanca-una-conversacion-con-niall-ferguson-1\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/legrandcontinent.eu\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00abHay un 60% de posibilidades de que Trump vuelva a la Casa Blanca\u00bb, una conversaci\u00f3n con Niall Ferguson\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/\",\"name\":\"El Grand Continent\",\"description\":\"La escala pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\",\"name\":\"florent\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"caption\":\"florent\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00abHay un 60% de posibilidades de que Trump vuelva a la Casa Blanca\u00bb, una conversaci\u00f3n con Niall Ferguson - El Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/es\/2024\/01\/12\/hay-un-60-de-posibilidades-de-que-trump-vuelva-a-la-casa-blanca-una-conversacion-con-niall-ferguson-1\/","og_locale":"es_ES","og_type":"article","og_title":"\u00abHay un 60% de posibilidades de que Trump vuelva a la Casa Blanca\u00bb, una conversaci\u00f3n con Niall Ferguson - El Grand Continent","og_description":"\u00abTrump tiene ahora un plan \u2014m\u00e1s radical, mejor definido\u2014. Europa, que sigue dependiendo de Washington para su seguridad, no tiene realmente opciones.\u00a0\u00bb Si es sin duda el m\u00e1s famoso de los historiadores brit\u00e1nicos, Niall Ferguson es tambi\u00e9n un sutil observador de las transformaciones econ\u00f3micas y pol\u00edticas a ambos lados del Atl\u00e1ntico. Desde el Valle de Aosta, al margen del Grand Continent Summit, nos ofrece sus perspectivas sobre un 2024 de alto riesgo.","og_url":"https:\/\/legrandcontinent.eu\/es\/2024\/01\/12\/hay-un-60-de-posibilidades-de-que-trump-vuelva-a-la-casa-blanca-una-conversacion-con-niall-ferguson-1\/","og_site_name":"El Grand Continent","article_published_time":"2024-01-12T18:37:55+00:00","article_modified_time":"2024-01-20T10:56:31+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/01\/gc-elferguson-1-scaled.jpg","type":"image\/jpeg"}],"author":"florent","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2024\/01\/gc-elferguson-1-scaled.jpg","twitter_misc":{"Escrito por":"florent","Tiempo de lectura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/es\/2024\/01\/12\/hay-un-60-de-posibilidades-de-que-trump-vuelva-a-la-casa-blanca-una-conversacion-con-niall-ferguson-1\/","url":"https:\/\/legrandcontinent.eu\/es\/2024\/01\/12\/hay-un-60-de-posibilidades-de-que-trump-vuelva-a-la-casa-blanca-una-conversacion-con-niall-ferguson-1\/","name":"\u00abHay un 60% de posibilidades de que Trump vuelva a la Casa Blanca\u00bb, una conversaci\u00f3n con Niall Ferguson - El Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/es\/2024\/01\/12\/hay-un-60-de-posibilidades-de-que-trump-vuelva-a-la-casa-blanca-una-conversacion-con-niall-ferguson-1\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/es\/2024\/01\/12\/hay-un-60-de-posibilidades-de-que-trump-vuelva-a-la-casa-blanca-una-conversacion-con-niall-ferguson-1\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/01\/SUMMIT_GRAND_CONTINENT_0993_Niall-Ferguson_B_umbertocostamagna\u00a92023-scaled.jpg","datePublished":"2024-01-12T18:37:55+00:00","dateModified":"2024-01-20T10:56:31+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/es\/2024\/01\/12\/hay-un-60-de-posibilidades-de-que-trump-vuelva-a-la-casa-blanca-una-conversacion-con-niall-ferguson-1\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/es\/2024\/01\/12\/hay-un-60-de-posibilidades-de-que-trump-vuelva-a-la-casa-blanca-una-conversacion-con-niall-ferguson-1\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/2024\/01\/12\/hay-un-60-de-posibilidades-de-que-trump-vuelva-a-la-casa-blanca-una-conversacion-con-niall-ferguson-1\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/01\/SUMMIT_GRAND_CONTINENT_0993_Niall-Ferguson_B_umbertocostamagna\u00a92023-scaled.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/01\/SUMMIT_GRAND_CONTINENT_0993_Niall-Ferguson_B_umbertocostamagna\u00a92023-scaled.jpg","width":1919,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/es\/2024\/01\/12\/hay-un-60-de-posibilidades-de-que-trump-vuelva-a-la-casa-blanca-una-conversacion-con-niall-ferguson-1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legrandcontinent.eu\/es\/"},{"@type":"ListItem","position":2,"name":"\u00abHay un 60% de posibilidades de que Trump vuelva a la Casa Blanca\u00bb, una conversaci\u00f3n con Niall Ferguson"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/es\/#website","url":"https:\/\/legrandcontinent.eu\/es\/","name":"El Grand Continent","description":"La escala pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c","name":"florent","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","caption":"florent"}}]}},"lgc_categories":[{"id":724,"name":"Elecciones estadounidenses 2024","slug":"trump-contra-biden-por-la-casa-blanca-seguir-las-elecciones-estadounidenses-de-2024"},{"id":718,"name":"Grand Continent Summit","slug":"grand-continent-summit"}],"lgc_author":{"id":50,"name":"Shahin Vall\u00e9e","slug":"shahin-vallee","description":"Ex asesor del Presidente del Consejo Europeo (Herman Von Rompuy) y ex asesor del Ministro de Econom\u00eda (Emmanuel Macron), Shahin Vall\u00e9e es investigador en econom\u00eda pol\u00edtica en la Deutsche Gesellschaft f\u00fcr Ausw\u00e4rtige Politik (DGAP).","first_name":null,"last_name":null,"picture":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/01\/SUMMIT_GRAND_CONTINENT_1173_Shahin-Vallee_umbertocostamagna\u00a92023.png","width":1307,"height":1340,"alt":""}},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/01\/SUMMIT_GRAND_CONTINENT_0993_Niall-Ferguson_B_umbertocostamagna\u00a92023-scaled.jpg","width":1919,"height":2560,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2024\/01\/SUMMIT_GRAND_CONTINENT_0993_Niall-Ferguson_B_umbertocostamagna\u00a92023-scaled.jpg","width":1919,"height":2560,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/28307","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/users\/1366"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/comments?post=28307"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/28307\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media\/28350"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media?parent=28307"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/categories?post=28307"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/tags?post=28307"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/staff?post=28307"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/editorial_format?post=28307"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/serie?post=28307"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/audience?post=28307"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/geo?post=28307"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}