{"id":26107,"date":"2023-11-09T12:00:00","date_gmt":"2023-11-09T11:00:00","guid":{"rendered":"https:\/\/legrandcontinent.eu\/es\/?p=26107"},"modified":"2023-11-09T17:25:08","modified_gmt":"2023-11-09T16:25:08","slug":"en-espana-pedro-sanchez-esta-a-un-paso-de-la-investidura","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/es\/2023\/11\/09\/en-espana-pedro-sanchez-esta-a-un-paso-de-la-investidura\/","title":{"rendered":"En Espa\u00f1a, Pedro S\u00e1nchez est\u00e1 a un paso de la investidura"},"content":{"rendered":"\n<p>Tras una semana de negociaciones m\u00e1s dif\u00edciles de lo esperado entre el n\u00famero 3 del PSOE, Santos Cerd\u00e1n, y Carles Puigdemont al frente del equipo de Junts, finalmente se ha llegado a un acuerdo para permitir la investidura. Aunque nunca hubo preocupaci\u00f3n por ninguna de las partes de que se llegara a un acuerdo, el retraso de este acuerdo final tiene consecuencias notables.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>El plan original de S\u00e1nchez era concluir las negociaciones la semana pasada para poder jurar su cargo esta semana -en concreto, el mi\u00e9rcoles 8 de noviembre- y as\u00ed poder asistir como nuevo presidente del Gobierno al congreso del Partido Socialista Europeo (PSE) que se celebrar\u00e1 en M\u00e1laga los d\u00edas 10 y 11 de noviembre. Pero esta ambici\u00f3n fue sin duda enunciada con demasiada fuerza, y Puigdemont mantuvo el suspense -y el protagonismo-.<\/li>\n\n\n\n<li>El acuerdo en s\u00ed nunca se puso en duda, pero las discusiones se centraron en cuestiones t\u00e9cnicas relativas a qui\u00e9n se beneficiar\u00eda de la amnist\u00eda, con Junts especialmente interesado en ampliar la lista de posibles beneficiarios. Fuentes cercanas a las negociaciones apuntan a que este punto a\u00fan no se ha resuelto del todo; los negociadores han acordado el pacto general que garantiza la investidura de S\u00e1nchez, pero a\u00fan no han llegado a un acuerdo definitivo sobre la ley de amnist\u00eda.<\/li>\n\n\n\n<li>Durante estos d\u00edas de latencia, la mayor\u00eda conservadora del Consejo General del Poder Judicial (CGPJ) se ha pronunciado oficialmente en contra de la ley de amnist\u00eda. El juez de la Audiencia Nacional Manuel Garc\u00eda-Castell\u00f3n anunci\u00f3 incluso que Puigdemont hab\u00eda sido imputado por terrorismo en relaci\u00f3n con el caso <em>Tsunami Democr\u00e0tic<\/em>. Esto reforz\u00f3 la idea entre los negociadores de que la ley ten\u00eda que ser \u00abintocable\u00bb y \u00abperfecta\u00bb para que pudiera superar todas las fases legislativas.<\/li>\n\n\n\n<li>Tambi\u00e9n se celebraron manifestaciones en Madrid contra la amnist\u00eda, sobre todo frente a la sede del PSOE en Ferraz. Las concentraciones fueron interrumpidas por grupos de extrema derecha, lo que provoc\u00f3 violencia f\u00edsica y verbal que dej\u00f3 unos 40 heridos, seg\u00fan la polic\u00eda. En los v\u00eddeos de los incidentes se pueden ver saludos nazis y escuchar el himno franquista \u00abCara al sol\u00bb.<\/li>\n<\/ul>\n\n\n\n<p>El Partido Popular (PP) no conden\u00f3 inicialmente la violencia en Madrid. Su presidente, Feij\u00f3o, culp\u00f3 a S\u00e1nchez: \u00abCuando pretendes amnistiar la violencia no puedes dar ning\u00fan ejemplo\u00bb.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>En el equilibrio de fuerzas interno del PP, fue la presidenta de la Comunidad de Madrid, Isabel D\u00edaz Ayuso, la primera en condenar la violencia.<\/li>\n\n\n\n<li>Tambi\u00e9n fue D\u00edaz Ayuso quien declar\u00f3 el jueves por la ma\u00f1ana que el anuncio del pacto era \u00abel inicio de la dictadura\u00bb.<\/li>\n\n\n\n<li>Haci\u00e9ndose eco del <a href=\"https:\/\/legrandcontinent.eu\/es\/2023\/07\/21\/como-la-derecha-espanola-se-esta-pasando-al-trumpismo-x-1-x\/\">fen\u00f3meno de la trumpizaci\u00f3n de la derecha espa\u00f1ola<\/a> descrito por Manuel Escudero, el jefe de gabinete de S\u00e1nchez, \u00d3scar L\u00f3pez escribi\u00f3 en X: \u00abTodo tiene un l\u00edmite. Las palabras importan y tienen un significado. No se puede hablar por hablar sin medir las consecuencias. No podemos consentir que el trumpismo envenene Espa\u00f1a. Antes de que sea demasiado tarde.\u00bb<\/li>\n\n\n\n<li>Vox, por su parte, alent\u00f3 las manifestaciones; Santiago Abascal incluso particip\u00f3 en las concentraciones, llamando a la polic\u00eda a desobedecer al Gobierno.<\/li>\n<\/ul>\n\n\n\n<p>El mi\u00e9rcoles, la preocupaci\u00f3n por la ley de amnist\u00eda tambi\u00e9n se expres\u00f3 en Bruselas a trav\u00e9s de una carta del comisario Didier Reynders en la que ped\u00eda explicaciones al Gobierno espa\u00f1ol.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Fue el Ministro de la Presidencia, F\u00e9lix Bola\u00f1os, quien no tard\u00f3 en responder el mi\u00e9rcoles por la noche, mostrando cierto descontento con las preguntas del Comisario, en particular sobre el hecho de que la carta de Reynders se hubiera publicado en la prensa.<\/li>\n\n\n\n<li>Adem\u00e1s de agradecer a Reynders sus preocupaciones, Bola\u00f1os tambi\u00e9n le dijo que, como el Gobierno actual estaba \u00aben funciones\u00bb, eran los grupos parlamentarios del Congreso los que presentar\u00edan la ley -y no el Ejecutivo-. Y todav\u00eda no se ha registrado ninguna ley.<\/li>\n<\/ul>\n\n\n\n<p>S\u00f3lo falta el acuerdo de los socialistas con el Partido Nacionalista Vasco (PNV). El equipo de S\u00e1nchez quiere que la investidura se celebre el mi\u00e9rcoles y el jueves de la semana que viene.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A \u00faltima hora del mi\u00e9rcoles 8 de noviembre, los principales protagonistas de las negociaciones entre el PSOE y Junts anunciaron que hab\u00edan llegado a un acuerdo. Esto allana el camino para la investidura de S\u00e1nchez, prevista para la pr\u00f3xima semana.<\/p>\n","protected":false},"author":1366,"featured_media":26108,"comment_status":"closed","ping_status":"","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":4,"_lgc_tts_audio_url":"","_lgc_tts_voice":"","_lgc_tts_publish":false,"_lgc_tts_history_item_id":"","_lgc_tts_generated_at":"","_lgc_tts_status":"","_lgc_tts_error":"","footnotes":""},"categories":[577],"tags":[],"staff":[],"editorial_format":[1472],"serie":[],"audience":[],"geo":[173],"class_list":["post-26107","post","type-post","status-publish","format-standard","hentry","category-geopolitica-del-23j-elecciones","editorial_format-analisis","geo-mediterraneo"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":26108,"excerpt":"A \u00faltima hora del mi\u00e9rcoles 8 de noviembre, los principales protagonistas de las negociaciones entre el PSOE y Junts anunciaron que hab\u00edan llegado a un acuerdo. Esto allana el camino para la investidura de S\u00e1nchez, prevista para la pr\u00f3xima semana.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>En Espa\u00f1a, Pedro S\u00e1nchez est\u00e1 a un paso de la investidura - El Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/es\/2023\/11\/09\/en-espana-pedro-sanchez-esta-a-un-paso-de-la-investidura\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En Espa\u00f1a, Pedro S\u00e1nchez est\u00e1 a un paso de la investidura - El Grand Continent\" \/>\n<meta property=\"og:description\" content=\"A \u00faltima hora del mi\u00e9rcoles 8 de noviembre, los principales protagonistas de las negociaciones entre el PSOE y Junts anunciaron que hab\u00edan llegado a un acuerdo. Esto allana el camino para la investidura de S\u00e1nchez, prevista para la pr\u00f3xima semana.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/es\/2023\/11\/09\/en-espana-pedro-sanchez-esta-a-un-paso-de-la-investidura\/\" \/>\n<meta property=\"og:site_name\" content=\"El Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-09T11:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-09T16:25:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/11\/U6gmK-resultados-de-las-elecciones-generales-espa-olas-3.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"1240\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"florent\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"florent\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/11\/09\/en-espana-pedro-sanchez-esta-a-un-paso-de-la-investidura\/\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/2023\/11\/09\/en-espana-pedro-sanchez-esta-a-un-paso-de-la-investidura\/\",\"name\":\"En Espa\u00f1a, Pedro S\u00e1nchez est\u00e1 a un paso de la investidura - El Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/11\/09\/en-espana-pedro-sanchez-esta-a-un-paso-de-la-investidura\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/11\/09\/en-espana-pedro-sanchez-esta-a-un-paso-de-la-investidura\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/11\/U6gmK-resultados-de-las-elecciones-generales-espa-olas-3.png\",\"datePublished\":\"2023-11-09T11:00:00+00:00\",\"dateModified\":\"2023-11-09T16:25:08+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/11\/09\/en-espana-pedro-sanchez-esta-a-un-paso-de-la-investidura\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/es\/2023\/11\/09\/en-espana-pedro-sanchez-esta-a-un-paso-de-la-investidura\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/11\/09\/en-espana-pedro-sanchez-esta-a-un-paso-de-la-investidura\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/11\/U6gmK-resultados-de-las-elecciones-generales-espa-olas-3.png\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/11\/U6gmK-resultados-de-las-elecciones-generales-espa-olas-3.png\",\"width\":1440,\"height\":1240},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/11\/09\/en-espana-pedro-sanchez-esta-a-un-paso-de-la-investidura\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/legrandcontinent.eu\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En Espa\u00f1a, Pedro S\u00e1nchez est\u00e1 a un paso de la investidura\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/\",\"name\":\"El Grand Continent\",\"description\":\"La escala pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\",\"name\":\"florent\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"caption\":\"florent\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"En Espa\u00f1a, Pedro S\u00e1nchez est\u00e1 a un paso de la investidura - El Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/es\/2023\/11\/09\/en-espana-pedro-sanchez-esta-a-un-paso-de-la-investidura\/","og_locale":"es_ES","og_type":"article","og_title":"En Espa\u00f1a, Pedro S\u00e1nchez est\u00e1 a un paso de la investidura - El Grand Continent","og_description":"A \u00faltima hora del mi\u00e9rcoles 8 de noviembre, los principales protagonistas de las negociaciones entre el PSOE y Junts anunciaron que hab\u00edan llegado a un acuerdo. Esto allana el camino para la investidura de S\u00e1nchez, prevista para la pr\u00f3xima semana.","og_url":"https:\/\/legrandcontinent.eu\/es\/2023\/11\/09\/en-espana-pedro-sanchez-esta-a-un-paso-de-la-investidura\/","og_site_name":"El Grand Continent","article_published_time":"2023-11-09T11:00:00+00:00","article_modified_time":"2023-11-09T16:25:08+00:00","og_image":[{"width":1440,"height":1240,"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/11\/U6gmK-resultados-de-las-elecciones-generales-espa-olas-3.png","type":"image\/png"}],"author":"florent","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"florent","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/es\/2023\/11\/09\/en-espana-pedro-sanchez-esta-a-un-paso-de-la-investidura\/","url":"https:\/\/legrandcontinent.eu\/es\/2023\/11\/09\/en-espana-pedro-sanchez-esta-a-un-paso-de-la-investidura\/","name":"En Espa\u00f1a, Pedro S\u00e1nchez est\u00e1 a un paso de la investidura - El Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/es\/2023\/11\/09\/en-espana-pedro-sanchez-esta-a-un-paso-de-la-investidura\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/es\/2023\/11\/09\/en-espana-pedro-sanchez-esta-a-un-paso-de-la-investidura\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/11\/U6gmK-resultados-de-las-elecciones-generales-espa-olas-3.png","datePublished":"2023-11-09T11:00:00+00:00","dateModified":"2023-11-09T16:25:08+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/es\/2023\/11\/09\/en-espana-pedro-sanchez-esta-a-un-paso-de-la-investidura\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/es\/2023\/11\/09\/en-espana-pedro-sanchez-esta-a-un-paso-de-la-investidura\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/2023\/11\/09\/en-espana-pedro-sanchez-esta-a-un-paso-de-la-investidura\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/11\/U6gmK-resultados-de-las-elecciones-generales-espa-olas-3.png","contentUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/11\/U6gmK-resultados-de-las-elecciones-generales-espa-olas-3.png","width":1440,"height":1240},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/es\/2023\/11\/09\/en-espana-pedro-sanchez-esta-a-un-paso-de-la-investidura\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legrandcontinent.eu\/es\/"},{"@type":"ListItem","position":2,"name":"En Espa\u00f1a, Pedro S\u00e1nchez est\u00e1 a un paso de la investidura"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/es\/#website","url":"https:\/\/legrandcontinent.eu\/es\/","name":"El Grand Continent","description":"La escala pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c","name":"florent","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","caption":"florent"}}]}},"lgc_categories":[{"id":577,"name":"Geopol\u00edtica del 23J","slug":"geopolitica-del-23j-elecciones"}],"lgc_author":null,"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/11\/U6gmK-resultados-de-las-elecciones-generales-espa-olas-3.png","width":1440,"height":1240,"alt":""},"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/26107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/users\/1366"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/comments?post=26107"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/26107\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media\/26108"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media?parent=26107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/categories?post=26107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/tags?post=26107"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/staff?post=26107"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/editorial_format?post=26107"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/serie?post=26107"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/audience?post=26107"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/geo?post=26107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}