{"id":25469,"date":"2023-10-27T15:15:00","date_gmt":"2023-10-27T13:15:00","guid":{"rendered":"https:\/\/legrandcontinent.eu\/es\/?p=25469"},"modified":"2023-10-27T16:05:56","modified_gmt":"2023-10-27T14:05:56","slug":"almacenamiento-y-restricciones-a-la-exportacion-pekin-refuerza-su-control-sobre-los-metales-estrategicos","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/es\/2023\/10\/27\/almacenamiento-y-restricciones-a-la-exportacion-pekin-refuerza-su-control-sobre-los-metales-estrategicos\/","title":{"rendered":"Almacenamiento y restricciones a la exportaci\u00f3n: Pek\u00edn refuerza su control sobre los metales estrat\u00e9gicos"},"content":{"rendered":"\n<p>Seg\u00fan informaciones publicadas por <em>Bloomberg<\/em> el 23 de octubre, China tiene previsto aumentar sus existencias de cobalto en hasta 3.000 toneladas, en un contexto de ca\u00edda de los precios mundiales de esta materia prima.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/z3WMx\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Desde el punto de vista geol\u00f3gico, el cobalto se considera un metal raro o escaso debido a su concentraci\u00f3n geol\u00f3gica. Desde el punto de vista estrat\u00e9gico, est\u00e1 incluido en la lista de materias primas estrat\u00e9gicas de la Uni\u00f3n Europea. El cobalto es un componente crucial en la fabricaci\u00f3n de bater\u00edas el\u00e9ctricas, junto con el litio, el grafito, el manganeso, el molibdeno y el n\u00edquel.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La producci\u00f3n mundial de cobalto ha experimentado un fuerte aumento desde 2021 -debido al incremento de la producci\u00f3n en la Rep\u00fablica Democr\u00e1tica del Congo e Indonesia-, lo que ha provocado una ca\u00edda de los precios en los mercados mundiales. El precio del cobalto era de 15,1 d\u00f3lares el 26 de octubre, tras caer por debajo de los 15 d\u00f3lares la libra en septiembre. Se esperaba que alcanzara los 40 d\u00f3lares la libra en mayo de 2022.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>China domina la cadena de valor del cobalto. Pek\u00edn controla el 77% de las actividades mundiales de refinado. Tambi\u00e9n controla gran parte de la producci\u00f3n a trav\u00e9s de sus empresas en la RDC. Para 2025, se espera que la cuota de China en la producci\u00f3n de cobalto alcance la mitad de la producci\u00f3n mundial.<\/li>\n<\/ul>\n\n\n\n<p>China, que controla gran parte de la producci\u00f3n mundial de metales estrat\u00e9gicos, ha adoptado recientemente una serie de medidas para controlar sus exportaciones de determinados metales.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>El 20 de octubre, Pek\u00edn anunci\u00f3 la introducci\u00f3n de controles sobre sus exportaciones de grafito. A partir del 1 de diciembre, los exportadores deber\u00e1n disponer de una licencia de exportaci\u00f3n para un determinado n\u00famero de productos a base de grafito.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Esta decisi\u00f3n sigue a la introducci\u00f3n en julio de restricciones a las exportaciones de galio y germanio, dos materiales utilizados en la fabricaci\u00f3n de semiconductores.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Estas decisiones se producen en un contexto de competencia sino-estadounidense y de mayores restricciones a las importaciones procedentes de Estados Unidos, que el 17 de octubre anunci\u00f3 una nueva serie de medidas para restringir las exportaciones de semiconductores a China.<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/2EmCO\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Estas decisiones se siguen de cerca ante el fuerte aumento de la demanda de metales estrat\u00e9gicos previsto para los pr\u00f3ximos a\u00f1os, sobre todo para satisfacer las necesidades de la transici\u00f3n energ\u00e9tica. En la \u00faltima versi\u00f3n de su informe de referencia sobre la estrategia de neutralidad de carbono para 2050, la Agencia Internacional de la Energ\u00eda se\u00f1ala que uno de los principales riesgos para el desarrollo de las energ\u00edas verdes reside en la seguridad energ\u00e9tica y las cadenas de suministro de materias primas cr\u00edticas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entre la introducci\u00f3n de restricciones a la exportaci\u00f3n de grafito y el aumento de las reservas de cobalto por parte de China, la competencia mundial por los metales estrat\u00e9gicos es cada vez m\u00e1s dura, mientras que se espera que la demanda mundial aumente considerablemente en los pr\u00f3ximos a\u00f1os. Un balance de las \u00faltimas decisiones chinas.<\/p>\n","protected":false},"author":1366,"featured_media":25470,"comment_status":"closed","ping_status":"","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":3,"footnotes":""},"categories":[522],"tags":[],"staff":[],"editorial_format":[1472],"serie":[],"audience":[],"geo":[197],"class_list":["post-25469","post","type-post","status-publish","format-standard","hentry","category-los-datos-que-lo-cambian-todo","editorial_format-analisis","geo-asia-oriental"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":25470,"excerpt":"Entre la introducci\u00f3n de restricciones a la exportaci\u00f3n de grafito y el aumento de las reservas de cobalto por parte de China, la competencia mundial por los metales estrat\u00e9gicos es cada vez m\u00e1s dura, mientras que se espera que la demanda mundial aumente considerablemente en los pr\u00f3ximos a\u00f1os. Un balance de las \u00faltimas decisiones chinas.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Almacenamiento y restricciones a la exportaci\u00f3n: Pek\u00edn refuerza su control sobre los metales estrat\u00e9gicos - El Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/es\/2023\/10\/27\/almacenamiento-y-restricciones-a-la-exportacion-pekin-refuerza-su-control-sobre-los-metales-estrategicos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Almacenamiento y restricciones a la exportaci\u00f3n: Pek\u00edn refuerza su control sobre los metales estrat\u00e9gicos - El Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Entre la introducci\u00f3n de restricciones a la exportaci\u00f3n de grafito y el aumento de las reservas de cobalto por parte de China, la competencia mundial por los metales estrat\u00e9gicos es cada vez m\u00e1s dura, mientras que se espera que la demanda mundial aumente considerablemente en los pr\u00f3ximos a\u00f1os. Un balance de las \u00faltimas decisiones chinas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/es\/2023\/10\/27\/almacenamiento-y-restricciones-a-la-exportacion-pekin-refuerza-su-control-sobre-los-metales-estrategicos\/\" \/>\n<meta property=\"og:site_name\" content=\"El Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-27T13:15:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-27T14:05:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/10\/z3WMx-se-espera-que-la-producci-n-de-cobalto-aumente-considerablemente-de-aqu-a-2025.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1240\" \/>\n\t<meta property=\"og:image:height\" content=\"840\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"florent\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"florent\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/10\/27\/almacenamiento-y-restricciones-a-la-exportacion-pekin-refuerza-su-control-sobre-los-metales-estrategicos\/\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/2023\/10\/27\/almacenamiento-y-restricciones-a-la-exportacion-pekin-refuerza-su-control-sobre-los-metales-estrategicos\/\",\"name\":\"Almacenamiento y restricciones a la exportaci\u00f3n: Pek\u00edn refuerza su control sobre los metales estrat\u00e9gicos - El Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/10\/27\/almacenamiento-y-restricciones-a-la-exportacion-pekin-refuerza-su-control-sobre-los-metales-estrategicos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/10\/27\/almacenamiento-y-restricciones-a-la-exportacion-pekin-refuerza-su-control-sobre-los-metales-estrategicos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/10\/z3WMx-se-espera-que-la-producci-n-de-cobalto-aumente-considerablemente-de-aqu-a-2025.png\",\"datePublished\":\"2023-10-27T13:15:00+00:00\",\"dateModified\":\"2023-10-27T14:05:56+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/10\/27\/almacenamiento-y-restricciones-a-la-exportacion-pekin-refuerza-su-control-sobre-los-metales-estrategicos\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/es\/2023\/10\/27\/almacenamiento-y-restricciones-a-la-exportacion-pekin-refuerza-su-control-sobre-los-metales-estrategicos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/10\/27\/almacenamiento-y-restricciones-a-la-exportacion-pekin-refuerza-su-control-sobre-los-metales-estrategicos\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/10\/z3WMx-se-espera-que-la-producci-n-de-cobalto-aumente-considerablemente-de-aqu-a-2025.png\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/10\/z3WMx-se-espera-que-la-producci-n-de-cobalto-aumente-considerablemente-de-aqu-a-2025.png\",\"width\":1240,\"height\":840},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/10\/27\/almacenamiento-y-restricciones-a-la-exportacion-pekin-refuerza-su-control-sobre-los-metales-estrategicos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/legrandcontinent.eu\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Almacenamiento y restricciones a la exportaci\u00f3n: Pek\u00edn refuerza su control sobre los metales estrat\u00e9gicos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/\",\"name\":\"El Grand Continent\",\"description\":\"La escala pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\",\"name\":\"florent\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"caption\":\"florent\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Almacenamiento y restricciones a la exportaci\u00f3n: Pek\u00edn refuerza su control sobre los metales estrat\u00e9gicos - El Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/es\/2023\/10\/27\/almacenamiento-y-restricciones-a-la-exportacion-pekin-refuerza-su-control-sobre-los-metales-estrategicos\/","og_locale":"es_ES","og_type":"article","og_title":"Almacenamiento y restricciones a la exportaci\u00f3n: Pek\u00edn refuerza su control sobre los metales estrat\u00e9gicos - El Grand Continent","og_description":"Entre la introducci\u00f3n de restricciones a la exportaci\u00f3n de grafito y el aumento de las reservas de cobalto por parte de China, la competencia mundial por los metales estrat\u00e9gicos es cada vez m\u00e1s dura, mientras que se espera que la demanda mundial aumente considerablemente en los pr\u00f3ximos a\u00f1os. Un balance de las \u00faltimas decisiones chinas.","og_url":"https:\/\/legrandcontinent.eu\/es\/2023\/10\/27\/almacenamiento-y-restricciones-a-la-exportacion-pekin-refuerza-su-control-sobre-los-metales-estrategicos\/","og_site_name":"El Grand Continent","article_published_time":"2023-10-27T13:15:00+00:00","article_modified_time":"2023-10-27T14:05:56+00:00","og_image":[{"width":1240,"height":840,"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/10\/z3WMx-se-espera-que-la-producci-n-de-cobalto-aumente-considerablemente-de-aqu-a-2025.png","type":"image\/png"}],"author":"florent","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"florent","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/es\/2023\/10\/27\/almacenamiento-y-restricciones-a-la-exportacion-pekin-refuerza-su-control-sobre-los-metales-estrategicos\/","url":"https:\/\/legrandcontinent.eu\/es\/2023\/10\/27\/almacenamiento-y-restricciones-a-la-exportacion-pekin-refuerza-su-control-sobre-los-metales-estrategicos\/","name":"Almacenamiento y restricciones a la exportaci\u00f3n: Pek\u00edn refuerza su control sobre los metales estrat\u00e9gicos - El Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/es\/2023\/10\/27\/almacenamiento-y-restricciones-a-la-exportacion-pekin-refuerza-su-control-sobre-los-metales-estrategicos\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/es\/2023\/10\/27\/almacenamiento-y-restricciones-a-la-exportacion-pekin-refuerza-su-control-sobre-los-metales-estrategicos\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/10\/z3WMx-se-espera-que-la-producci-n-de-cobalto-aumente-considerablemente-de-aqu-a-2025.png","datePublished":"2023-10-27T13:15:00+00:00","dateModified":"2023-10-27T14:05:56+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/es\/2023\/10\/27\/almacenamiento-y-restricciones-a-la-exportacion-pekin-refuerza-su-control-sobre-los-metales-estrategicos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/es\/2023\/10\/27\/almacenamiento-y-restricciones-a-la-exportacion-pekin-refuerza-su-control-sobre-los-metales-estrategicos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/2023\/10\/27\/almacenamiento-y-restricciones-a-la-exportacion-pekin-refuerza-su-control-sobre-los-metales-estrategicos\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/10\/z3WMx-se-espera-que-la-producci-n-de-cobalto-aumente-considerablemente-de-aqu-a-2025.png","contentUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/10\/z3WMx-se-espera-que-la-producci-n-de-cobalto-aumente-considerablemente-de-aqu-a-2025.png","width":1240,"height":840},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/es\/2023\/10\/27\/almacenamiento-y-restricciones-a-la-exportacion-pekin-refuerza-su-control-sobre-los-metales-estrategicos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legrandcontinent.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Almacenamiento y restricciones a la exportaci\u00f3n: Pek\u00edn refuerza su control sobre los metales estrat\u00e9gicos"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/es\/#website","url":"https:\/\/legrandcontinent.eu\/es\/","name":"El Grand Continent","description":"La escala pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c","name":"florent","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","caption":"florent"}}]}},"lgc_categories":[{"id":522,"name":"Los datos que lo cambian todo","slug":"los-datos-que-lo-cambian-todo"}],"lgc_author":null,"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/10\/z3WMx-se-espera-que-la-producci-n-de-cobalto-aumente-considerablemente-de-aqu-a-2025.png","width":1240,"height":840,"alt":""},"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/25469","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/users\/1366"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/comments?post=25469"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/25469\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media\/25470"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media?parent=25469"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/categories?post=25469"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/tags?post=25469"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/staff?post=25469"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/editorial_format?post=25469"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/serie?post=25469"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/audience?post=25469"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/geo?post=25469"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}