{"id":24257,"date":"2023-10-07T22:33:00","date_gmt":"2023-10-07T20:33:00","guid":{"rendered":"https:\/\/legrandcontinent.eu\/es\/?p=24257"},"modified":"2023-10-08T00:50:54","modified_gmt":"2023-10-07T22:50:54","slug":"ataque-de-hamas-contra-israel-tel-aviv-de-nuevo-bajo-una-lluvia-de-cohetes-israel-toma-represalias-en-gaza-un-balance-del-primer-dia","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/es\/2023\/10\/07\/ataque-de-hamas-contra-israel-tel-aviv-de-nuevo-bajo-una-lluvia-de-cohetes-israel-toma-represalias-en-gaza-un-balance-del-primer-dia\/","title":{"rendered":"Ataque de Ham\u00e1s contra Israel: Tel Aviv de nuevo bajo una lluvia de cohetes, Israel toma represalias en Gaza. Un balance del primer d\u00eda"},"content":{"rendered":"\n<p>El balance humano:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Las autoridades israel\u00edes confirmaron la muerte de al menos 200 israel\u00edes y 230 palestinos.<\/li>\n\n\n\n<li>Al menos 1.000 israel\u00edes y 1.600 palestinos resultaron heridos.<\/li>\n\n\n\n<li>No se dio una cifra oficial del n\u00famero de rehenes, pero el ej\u00e9rcito israel\u00ed confirm\u00f3 que Ham\u00e1s hab\u00eda tomado como rehenes a civiles y soldados israel\u00edes, llev\u00e1ndolos a Gaza. En las redes sociales, numerosos v\u00eddeos, algunos sin fuentes, informan de una situaci\u00f3n ca\u00f3tica en determinadas zonas y de la toma de ciertos puestos por Ham\u00e1s.<\/li>\n\n\n\n<li>Tambi\u00e9n se informa de dos tomas de rehenes en dos pueblos israel\u00edes cercanos a la frontera. Ham\u00e1s, por su parte, afirma haber capturado a varias decenas de israel\u00edes.<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-large  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/6938L\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>La secuencia militar, hora a hora:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Desde las 6h30 (5h30 Madrid) se han disparado cohetes desde varios puntos de la Franja de Gaza. Testigos citados por Reuters afirman haber o\u00eddo el ruido de enfrentamientos armados a lo largo de la l\u00ednea de separaci\u00f3n de la Franja de Gaza. Las autoridades israel\u00edes calculan que se han disparado unos 2.200 cohetes contra Israel. Ham\u00e1s ha anunciado la cifra de 5.000. A modo de comparaci\u00f3n, durante la guerra de 2014, que dur\u00f3 50 d\u00edas, se dispararon unos 4.000 cohetes desde Gaza. Bajo la intensidad de los ataques, la C\u00fapula de Hierro parece saturada.<\/li>\n\n\n\n<li>La invasi\u00f3n terrestre comenz\u00f3 en torno a las 7h30 (6h30 en Madrid) cuando Ham\u00e1s utiliz\u00f3 excavadoras para demoler partes del muro fronterizo entre Gaza e Israel, y algunos terroristas utilizaron parapentes.<\/li>\n\n\n\n<li>Israel respondi\u00f3 con ataques a\u00e9reos contra Gaza. Desde que comenz\u00f3 el ataque han muerto m\u00e1s de 150 israel\u00edes y al menos 198 palestinos.<\/li>\n\n\n\n<li>Hacia las 20h (hora de Madrid), otra lluvia de cohetes alcanz\u00f3 la ciudad de Tel Aviv.<\/li>\n<\/ul>\n\n\n\n<p>Contexto interno:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>El estado de sorpresa y aterramiento es evidente. Los israel\u00edes est\u00e1n acostumbrados a las sirenas y a las amenazas de bomba. Pero esta vez, Ham\u00e1s ha cogido el pa\u00eds por sorpresa, desorientando a toda una sociedad. En nuestras p\u00e1ginas, Mil\u00e0n Czerny da <a href=\"https:\/\/legrandcontinent.eu\/es\/2023\/10\/07\/ataque-de-hamas-en-israel-7-puntos-2-mapas-y-un-testimonio-desde-tel-aviv\/\">testimonio de ello desde un refugio en Tel Aviv<\/a>.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u00abCiudadanos de Israel, estamos en guerra -esto no es una operaci\u00f3n, no es un ejercicio- estamos en guerra\u00bb, declar\u00f3 Benjamin Netanyahu en un v\u00eddeo.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Ante el desasosiego de la poblaci\u00f3n, el portavoz de las FDI, el teniente coronel Richard Hecht, declar\u00f3 a la CNN que \u00abdecenas de miles\u00bb de reservistas israel\u00edes tambi\u00e9n hab\u00edan sido llamados como refuerzo, y a\u00f1adi\u00f3 que esperaba que \u00abno haya m\u00e1s terroristas vivos en Israel\u00bb al final del d\u00eda.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>No faltaron analog\u00edas hist\u00f3ricas a lo largo del d\u00eda: un antiguo portavoz del ej\u00e9rcito israel\u00ed dijo que era \u00abun momento Pearl Harbor para Israel\u00bb. La analog\u00eda hist\u00f3rica con la Guerra de Yom Kipur es tambi\u00e9n una referencia hist\u00f3rica m\u00e1s directa, ya que el ataque de esta ma\u00f1ana se produce 50 a\u00f1os y un d\u00eda despu\u00e9s del estallido del conflicto en 1973 por parte de Siria y Egipto. El gran fallo de seguridad que ha hecho posible esta ofensiva -en un momento en que la inteligencia es la joya de la defensa israel\u00ed- recuerda tambi\u00e9n a la conmoci\u00f3n del 11 de septiembre en el aparato de seguridad estadounidense.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>El Likud, el partido del primer ministro Benjamin Netanyahu, ofreci\u00f3 a Benny Gantz (Unidad Nacional) y al l\u00edder de la oposici\u00f3n, Yair Lapid, formar parte de un \u00abgobierno de emergencia ampliado\u00bb. El presidente de Unidad Nacional, Benny Gantz, se reuni\u00f3 el s\u00e1bado con el primer ministro Benjamin Netanyahu, durante una reuni\u00f3n en la que se plante\u00f3 la cuesti\u00f3n de formar un gobierno de emergencia.<\/li>\n<\/ul>\n\n\n\n<p>Seg\u00fan nos ha explicado esta ma\u00f1ana Azar Gat, el Primer Ministro israel\u00ed tratar\u00e1 de reunir al pa\u00eds y a la oposici\u00f3n tras la bandera, <a href=\"https:\/\/legrandcontinent.eu\/es\/2023\/10\/07\/israel-la-guerra-de-sucot-ha-comenzado-primeras-lecciones-estrategicas-y-escenarios\/\">en preparaci\u00f3n de una gran operaci\u00f3n terrestre en Gaza<\/a>. Esta hip\u00f3tesis parece haber sido confirmada esta tarde por la \u00faltima declaraci\u00f3n del Ministro de Defensa israel\u00ed. Queda por ver si Israel planea una ocupaci\u00f3n total de Gaza al final de esta operaci\u00f3n, seg\u00fan el modelo que exist\u00eda antes de 2005.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con el anuncio del ministro israel\u00ed de Defensa, Yoav Gallant, de que quiere \u00abcambiar la realidad en Gaza\u00bb, anunciando un ataque terrestre masivo en los pr\u00f3ximos d\u00edas, hacemos balance de las p\u00e9rdidas humanas, los movimientos militares y las repercusiones pol\u00edticas del estallido de la guerra de Sucot por parte de Ham\u00e1s. Actualizaci\u00f3n a las 21:30 (hora de Madrid).<\/p>\n","protected":false},"author":1366,"featured_media":24258,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":3,"footnotes":""},"categories":[668],"tags":[],"staff":[],"editorial_format":[1472],"serie":[],"audience":[],"geo":[173],"class_list":["post-24257","post","type-post","status-publish","format-standard","hentry","category-guerra-de-sucot","editorial_format-analisis","geo-mediterraneo"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":24258,"excerpt":"Con el anuncio del ministro israel\u00ed de Defensa, Yoav Gallant, de que quiere \"cambiar la realidad en Gaza\", anunciando un ataque terrestre masivo en los pr\u00f3ximos d\u00edas, hacemos balance de las p\u00e9rdidas humanas, los movimientos militares y las repercusiones pol\u00edticas del estallido de la guerra de Sucot por parte de Ham\u00e1s. Actualizaci\u00f3n a las 21:30 (hora de Madrid).","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ataque de Ham\u00e1s contra Israel: Tel Aviv de nuevo bajo una lluvia de cohetes, Israel toma represalias en Gaza. Un balance del primer d\u00eda - El Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/es\/2023\/10\/07\/ataque-de-hamas-contra-israel-tel-aviv-de-nuevo-bajo-una-lluvia-de-cohetes-israel-toma-represalias-en-gaza-un-balance-del-primer-dia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ataque de Ham\u00e1s contra Israel: Tel Aviv de nuevo bajo una lluvia de cohetes, Israel toma represalias en Gaza. Un balance del primer d\u00eda - El Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Con el anuncio del ministro israel\u00ed de Defensa, Yoav Gallant, de que quiere &quot;cambiar la realidad en Gaza&quot;, anunciando un ataque terrestre masivo en los pr\u00f3ximos d\u00edas, hacemos balance de las p\u00e9rdidas humanas, los movimientos militares y las repercusiones pol\u00edticas del estallido de la guerra de Sucot por parte de Ham\u00e1s. Actualizaci\u00f3n a las 21:30 (hora de Madrid).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/es\/2023\/10\/07\/ataque-de-hamas-contra-israel-tel-aviv-de-nuevo-bajo-una-lluvia-de-cohetes-israel-toma-represalias-en-gaza-un-balance-del-primer-dia\/\" \/>\n<meta property=\"og:site_name\" content=\"El Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-07T20:33:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-07T22:50:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/10\/gc-elbalance-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"florent\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/10\/gc-elbalance-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"florent\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/10\/07\/ataque-de-hamas-contra-israel-tel-aviv-de-nuevo-bajo-una-lluvia-de-cohetes-israel-toma-represalias-en-gaza-un-balance-del-primer-dia\/\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/2023\/10\/07\/ataque-de-hamas-contra-israel-tel-aviv-de-nuevo-bajo-una-lluvia-de-cohetes-israel-toma-represalias-en-gaza-un-balance-del-primer-dia\/\",\"name\":\"Ataque de Ham\u00e1s contra Israel: Tel Aviv de nuevo bajo una lluvia de cohetes, Israel toma represalias en Gaza. Un balance del primer d\u00eda - El Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/10\/07\/ataque-de-hamas-contra-israel-tel-aviv-de-nuevo-bajo-una-lluvia-de-cohetes-israel-toma-represalias-en-gaza-un-balance-del-primer-dia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/10\/07\/ataque-de-hamas-contra-israel-tel-aviv-de-nuevo-bajo-una-lluvia-de-cohetes-israel-toma-represalias-en-gaza-un-balance-del-primer-dia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/10\/6938L-combates-en-el-sur-de-israel-1.png\",\"datePublished\":\"2023-10-07T20:33:00+00:00\",\"dateModified\":\"2023-10-07T22:50:54+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/10\/07\/ataque-de-hamas-contra-israel-tel-aviv-de-nuevo-bajo-una-lluvia-de-cohetes-israel-toma-represalias-en-gaza-un-balance-del-primer-dia\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/es\/2023\/10\/07\/ataque-de-hamas-contra-israel-tel-aviv-de-nuevo-bajo-una-lluvia-de-cohetes-israel-toma-represalias-en-gaza-un-balance-del-primer-dia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/10\/07\/ataque-de-hamas-contra-israel-tel-aviv-de-nuevo-bajo-una-lluvia-de-cohetes-israel-toma-represalias-en-gaza-un-balance-del-primer-dia\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/10\/6938L-combates-en-el-sur-de-israel-1.png\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/10\/6938L-combates-en-el-sur-de-israel-1.png\",\"width\":1240,\"height\":1216},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/10\/07\/ataque-de-hamas-contra-israel-tel-aviv-de-nuevo-bajo-una-lluvia-de-cohetes-israel-toma-represalias-en-gaza-un-balance-del-primer-dia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/legrandcontinent.eu\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ataque de Ham\u00e1s contra Israel: Tel Aviv de nuevo bajo una lluvia de cohetes, Israel toma represalias en Gaza. Un balance del primer d\u00eda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/\",\"name\":\"El Grand Continent\",\"description\":\"La escala pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\",\"name\":\"florent\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"caption\":\"florent\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ataque de Ham\u00e1s contra Israel: Tel Aviv de nuevo bajo una lluvia de cohetes, Israel toma represalias en Gaza. Un balance del primer d\u00eda - El Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/es\/2023\/10\/07\/ataque-de-hamas-contra-israel-tel-aviv-de-nuevo-bajo-una-lluvia-de-cohetes-israel-toma-represalias-en-gaza-un-balance-del-primer-dia\/","og_locale":"es_ES","og_type":"article","og_title":"Ataque de Ham\u00e1s contra Israel: Tel Aviv de nuevo bajo una lluvia de cohetes, Israel toma represalias en Gaza. Un balance del primer d\u00eda - El Grand Continent","og_description":"Con el anuncio del ministro israel\u00ed de Defensa, Yoav Gallant, de que quiere \"cambiar la realidad en Gaza\", anunciando un ataque terrestre masivo en los pr\u00f3ximos d\u00edas, hacemos balance de las p\u00e9rdidas humanas, los movimientos militares y las repercusiones pol\u00edticas del estallido de la guerra de Sucot por parte de Ham\u00e1s. Actualizaci\u00f3n a las 21:30 (hora de Madrid).","og_url":"https:\/\/legrandcontinent.eu\/es\/2023\/10\/07\/ataque-de-hamas-contra-israel-tel-aviv-de-nuevo-bajo-una-lluvia-de-cohetes-israel-toma-represalias-en-gaza-un-balance-del-primer-dia\/","og_site_name":"El Grand Continent","article_published_time":"2023-10-07T20:33:00+00:00","article_modified_time":"2023-10-07T22:50:54+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/10\/gc-elbalance-scaled.jpg","type":"image\/jpeg"}],"author":"florent","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/10\/gc-elbalance-scaled.jpg","twitter_misc":{"Escrito por":"florent","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/es\/2023\/10\/07\/ataque-de-hamas-contra-israel-tel-aviv-de-nuevo-bajo-una-lluvia-de-cohetes-israel-toma-represalias-en-gaza-un-balance-del-primer-dia\/","url":"https:\/\/legrandcontinent.eu\/es\/2023\/10\/07\/ataque-de-hamas-contra-israel-tel-aviv-de-nuevo-bajo-una-lluvia-de-cohetes-israel-toma-represalias-en-gaza-un-balance-del-primer-dia\/","name":"Ataque de Ham\u00e1s contra Israel: Tel Aviv de nuevo bajo una lluvia de cohetes, Israel toma represalias en Gaza. Un balance del primer d\u00eda - El Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/es\/2023\/10\/07\/ataque-de-hamas-contra-israel-tel-aviv-de-nuevo-bajo-una-lluvia-de-cohetes-israel-toma-represalias-en-gaza-un-balance-del-primer-dia\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/es\/2023\/10\/07\/ataque-de-hamas-contra-israel-tel-aviv-de-nuevo-bajo-una-lluvia-de-cohetes-israel-toma-represalias-en-gaza-un-balance-del-primer-dia\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/10\/6938L-combates-en-el-sur-de-israel-1.png","datePublished":"2023-10-07T20:33:00+00:00","dateModified":"2023-10-07T22:50:54+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/es\/2023\/10\/07\/ataque-de-hamas-contra-israel-tel-aviv-de-nuevo-bajo-una-lluvia-de-cohetes-israel-toma-represalias-en-gaza-un-balance-del-primer-dia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/es\/2023\/10\/07\/ataque-de-hamas-contra-israel-tel-aviv-de-nuevo-bajo-una-lluvia-de-cohetes-israel-toma-represalias-en-gaza-un-balance-del-primer-dia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/2023\/10\/07\/ataque-de-hamas-contra-israel-tel-aviv-de-nuevo-bajo-una-lluvia-de-cohetes-israel-toma-represalias-en-gaza-un-balance-del-primer-dia\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/10\/6938L-combates-en-el-sur-de-israel-1.png","contentUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/10\/6938L-combates-en-el-sur-de-israel-1.png","width":1240,"height":1216},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/es\/2023\/10\/07\/ataque-de-hamas-contra-israel-tel-aviv-de-nuevo-bajo-una-lluvia-de-cohetes-israel-toma-represalias-en-gaza-un-balance-del-primer-dia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legrandcontinent.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Ataque de Ham\u00e1s contra Israel: Tel Aviv de nuevo bajo una lluvia de cohetes, Israel toma represalias en Gaza. Un balance del primer d\u00eda"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/es\/#website","url":"https:\/\/legrandcontinent.eu\/es\/","name":"El Grand Continent","description":"La escala pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c","name":"florent","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","caption":"florent"}}]}},"lgc_categories":[{"id":668,"name":"Israel, Ham\u00e1s: el 7 de octubre, dos a\u00f1os despu\u00e9s","slug":"guerra-de-sucot"}],"lgc_author":null,"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/10\/6938L-combates-en-el-sur-de-israel-1.png","width":1240,"height":1216,"alt":""},"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/24257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/users\/1366"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/comments?post=24257"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/24257\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media\/24258"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media?parent=24257"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/categories?post=24257"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/tags?post=24257"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/staff?post=24257"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/editorial_format?post=24257"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/serie?post=24257"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/audience?post=24257"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/geo?post=24257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}