{"id":23647,"date":"2023-09-29T05:00:00","date_gmt":"2023-09-29T04:00:00","guid":{"rendered":"https:\/\/legrandcontinent.eu\/es\/?p=23647"},"modified":"2023-09-28T23:58:00","modified_gmt":"2023-09-28T22:58:00","slug":"los-beneficios-del-sector-bancario-europeo-alcanzan-su-nivel-mas-alto-desde-la-crisis-financiera-de-2008","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/es\/2023\/09\/29\/los-beneficios-del-sector-bancario-europeo-alcanzan-su-nivel-mas-alto-desde-la-crisis-financiera-de-2008\/","title":{"rendered":"Los beneficios del sector bancario europeo alcanzan su nivel m\u00e1s alto desde la crisis financiera de 2008"},"content":{"rendered":"\n<p>El sector bancario europeo se ha beneficiado enormemente de la pol\u00edtica monetaria restrictiva aplicada por el Banco Central Europeo desde julio de 2022.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/KHHxy\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La subida de los tipos de inter\u00e9s se est\u00e1 traduciendo en mayores ingresos para los bancos comerciales. Seg\u00fan una nota publicada por Deutsche Bank&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-23647' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2023\/09\/29\/los-beneficios-del-sector-bancario-europeo-alcanzan-su-nivel-mas-alto-desde-la-crisis-financiera-de-2008\/#easy-footnote-bottom-1-23647' title='&lt;a href=&quot;https:\/\/www.dbresearch.com\/MAIL\/RPS_EN-PROD\/PROD0000000000529987.xhtml&quot;&gt;Deutsche Bank, 28 de septiembre de 2023&lt;\/a&gt;.'><sup>1<\/sup><\/a><\/span><\/span>, casi el 90% del aumento de los ingresos bancarios puede atribuirse directamente a la subida de los tipos de inter\u00e9s y los ingresos asociados.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Seg\u00fan los c\u00e1lculos de Deutsche Bank, los principales bancos europeos lograron unos ingresos netos de 74.000 millones de euros en el primer semestre de 2023, un nivel de rentabilidad comparable al de los bancos estadounidenses. Estos elevados beneficios tambi\u00e9n se han traducido en \u00abconsiderables\u00bb repartos de dividendos para los accionistas.<\/li>\n<\/ul>\n\n\n\n<p>En un contexto de debate sobre <a href=\"https:\/\/legrandcontinent.eu\/es\/2023\/01\/31\/gravar-los-superbeneficios-de-la-guerra-en-ucrania-una-propuesta\/\">la imposici\u00f3n de los superbeneficios<\/a>, estas cifras confirman que el sector bancario es uno de los m\u00e1s afectados por el crecimiento excepcional de sus ingresos netos, junto con las empresas energ\u00e9ticas. Varios pa\u00edses europeos han empezado a tomar medidas a escala nacional.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/6wYNk\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>En agosto, Italia anunci\u00f3 un impuesto dirigido al sector bancario, encabezado por el Ministro de Econom\u00eda Giancarlo Giorgetti. El plan consiste en recaudar el 40% de los superbeneficios (definidos como la proporci\u00f3n de los ingresos netos por intereses que sea un 5% superior a la del a\u00f1o anterior en 2022, y un 10% superior en 2023). Sin embargo, tras la reacci\u00f3n negativa de los mercados financieros, el Gobierno italiano anunci\u00f3 que estas contribuciones se limitar\u00edan al 0,1% de los activos de los bancos afectados.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Espa\u00f1a es tambi\u00e9n uno de los pa\u00edses que ha introducido un impuesto excepcional de dos a\u00f1os sobre el sector bancario, con el que el Gobierno de S\u00e1nchez espera recaudar 1.500 millones de euros.<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/1ie66\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>A escala de la Uni\u00f3n, a ra\u00edz del impuesto sobre los superbeneficios del sector energ\u00e9tico&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-23647' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2023\/09\/29\/los-beneficios-del-sector-bancario-europeo-alcanzan-su-nivel-mas-alto-desde-la-crisis-financiera-de-2008\/#easy-footnote-bottom-2-23647' title='&lt;a href=&quot;https:\/\/www.consilium.europa.eu\/en\/press\/press-releases\/2022\/09\/30\/council-agrees-on-emergency-measures-to-reduce-energy-prices\/&quot;&gt;Decisiones del Consejo de 30 de septiembre de 2022&lt;\/a&gt;.'><sup>2<\/sup><\/a><\/span><\/span>, que entr\u00f3 en vigor en diciembre de 2022, podr\u00eda reavivarse el debate sobre la ampliaci\u00f3n de su \u00e1mbito de aplicaci\u00f3n al sector bancario.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>El Banco Central Europeo no se ha pronunciado a favor de impuestos dirigidos al sector bancario. Advierte a los Estados miembros de los riesgos que podr\u00edan plantear para la estabilidad financiera&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-23647' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2023\/09\/29\/los-beneficios-del-sector-bancario-europeo-alcanzan-su-nivel-mas-alto-desde-la-crisis-financiera-de-2008\/#easy-footnote-bottom-3-23647' title='&lt;a href=&quot;https:\/\/www.ecb.europa.eu\/pub\/pdf\/legal\/ecb.con_2023_26.en.pdf&quot;&gt;\u00ab\u00a0Opinion of the European Central Bank of 12 September 2023 on the imposition of an extraordinary tax on credit institutions\u00a0\u00bb, 12 de septiembre de 2023&lt;\/a&gt;.'><sup>3<\/sup><\/a><\/span><\/span>.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Mientras la econom\u00eda europea se ralentiza, la subida de tipos de inter\u00e9s del Banco Central Europeo tambi\u00e9n est\u00e1 impulsando los beneficios de los bancos comerciales. Estos han alcanzado un nivel r\u00e9cord, superando su nivel de 2007 en t\u00e9rminos nominales. Se ha reavivado el debate sobre los impuestos excepcionales sobre los superbeneficios.<\/p>\n","protected":false},"author":1366,"featured_media":23648,"comment_status":"closed","ping_status":"","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":2,"footnotes":""},"categories":[522],"tags":[],"staff":[],"editorial_format":[1472],"serie":[],"audience":[],"geo":[198],"class_list":["post-23647","post","type-post","status-publish","format-standard","hentry","category-los-datos-que-lo-cambian-todo","editorial_format-analisis","geo-mundo"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":23648,"excerpt":"Mientras la econom\u00eda europea se ralentiza, la subida de tipos de inter\u00e9s del Banco Central Europeo tambi\u00e9n est\u00e1 impulsando los beneficios de los bancos comerciales. Estos han alcanzado un nivel r\u00e9cord, superando su nivel de 2007 en t\u00e9rminos nominales. Se ha reavivado el debate sobre los impuestos excepcionales sobre los superbeneficios.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Los beneficios del sector bancario europeo alcanzan su nivel m\u00e1s alto desde la crisis financiera de 2008 - El Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/es\/2023\/09\/29\/los-beneficios-del-sector-bancario-europeo-alcanzan-su-nivel-mas-alto-desde-la-crisis-financiera-de-2008\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los beneficios del sector bancario europeo alcanzan su nivel m\u00e1s alto desde la crisis financiera de 2008 - El Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Mientras la econom\u00eda europea se ralentiza, la subida de tipos de inter\u00e9s del Banco Central Europeo tambi\u00e9n est\u00e1 impulsando los beneficios de los bancos comerciales. Estos han alcanzado un nivel r\u00e9cord, superando su nivel de 2007 en t\u00e9rminos nominales. Se ha reavivado el debate sobre los impuestos excepcionales sobre los superbeneficios.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/es\/2023\/09\/29\/los-beneficios-del-sector-bancario-europeo-alcanzan-su-nivel-mas-alto-desde-la-crisis-financiera-de-2008\/\" \/>\n<meta property=\"og:site_name\" content=\"El Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-29T04:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/09\/gc-elbancoseuropeos.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1230\" \/>\n\t<meta property=\"og:image:height\" content=\"1076\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"florent\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/09\/gc-elbancoseuropeos.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"florent\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/09\/29\/los-beneficios-del-sector-bancario-europeo-alcanzan-su-nivel-mas-alto-desde-la-crisis-financiera-de-2008\/\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/2023\/09\/29\/los-beneficios-del-sector-bancario-europeo-alcanzan-su-nivel-mas-alto-desde-la-crisis-financiera-de-2008\/\",\"name\":\"Los beneficios del sector bancario europeo alcanzan su nivel m\u00e1s alto desde la crisis financiera de 2008 - El Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/09\/29\/los-beneficios-del-sector-bancario-europeo-alcanzan-su-nivel-mas-alto-desde-la-crisis-financiera-de-2008\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/09\/29\/los-beneficios-del-sector-bancario-europeo-alcanzan-su-nivel-mas-alto-desde-la-crisis-financiera-de-2008\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/09\/gc-elbancoseuropeos.jpg\",\"datePublished\":\"2023-09-29T04:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/09\/29\/los-beneficios-del-sector-bancario-europeo-alcanzan-su-nivel-mas-alto-desde-la-crisis-financiera-de-2008\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/es\/2023\/09\/29\/los-beneficios-del-sector-bancario-europeo-alcanzan-su-nivel-mas-alto-desde-la-crisis-financiera-de-2008\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/09\/29\/los-beneficios-del-sector-bancario-europeo-alcanzan-su-nivel-mas-alto-desde-la-crisis-financiera-de-2008\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/09\/gc-elbancoseuropeos.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/09\/gc-elbancoseuropeos.jpg\",\"width\":1230,\"height\":1076},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/09\/29\/los-beneficios-del-sector-bancario-europeo-alcanzan-su-nivel-mas-alto-desde-la-crisis-financiera-de-2008\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/legrandcontinent.eu\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los beneficios del sector bancario europeo alcanzan su nivel m\u00e1s alto desde la crisis financiera de 2008\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/\",\"name\":\"El Grand Continent\",\"description\":\"La escala pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\",\"name\":\"florent\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"caption\":\"florent\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los beneficios del sector bancario europeo alcanzan su nivel m\u00e1s alto desde la crisis financiera de 2008 - El Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/es\/2023\/09\/29\/los-beneficios-del-sector-bancario-europeo-alcanzan-su-nivel-mas-alto-desde-la-crisis-financiera-de-2008\/","og_locale":"es_ES","og_type":"article","og_title":"Los beneficios del sector bancario europeo alcanzan su nivel m\u00e1s alto desde la crisis financiera de 2008 - El Grand Continent","og_description":"Mientras la econom\u00eda europea se ralentiza, la subida de tipos de inter\u00e9s del Banco Central Europeo tambi\u00e9n est\u00e1 impulsando los beneficios de los bancos comerciales. Estos han alcanzado un nivel r\u00e9cord, superando su nivel de 2007 en t\u00e9rminos nominales. Se ha reavivado el debate sobre los impuestos excepcionales sobre los superbeneficios.","og_url":"https:\/\/legrandcontinent.eu\/es\/2023\/09\/29\/los-beneficios-del-sector-bancario-europeo-alcanzan-su-nivel-mas-alto-desde-la-crisis-financiera-de-2008\/","og_site_name":"El Grand Continent","article_published_time":"2023-09-29T04:00:00+00:00","og_image":[{"width":1230,"height":1076,"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/09\/gc-elbancoseuropeos.jpg","type":"image\/jpeg"}],"author":"florent","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/09\/gc-elbancoseuropeos.jpg","twitter_misc":{"Escrito por":"florent","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/es\/2023\/09\/29\/los-beneficios-del-sector-bancario-europeo-alcanzan-su-nivel-mas-alto-desde-la-crisis-financiera-de-2008\/","url":"https:\/\/legrandcontinent.eu\/es\/2023\/09\/29\/los-beneficios-del-sector-bancario-europeo-alcanzan-su-nivel-mas-alto-desde-la-crisis-financiera-de-2008\/","name":"Los beneficios del sector bancario europeo alcanzan su nivel m\u00e1s alto desde la crisis financiera de 2008 - El Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/es\/2023\/09\/29\/los-beneficios-del-sector-bancario-europeo-alcanzan-su-nivel-mas-alto-desde-la-crisis-financiera-de-2008\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/es\/2023\/09\/29\/los-beneficios-del-sector-bancario-europeo-alcanzan-su-nivel-mas-alto-desde-la-crisis-financiera-de-2008\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/09\/gc-elbancoseuropeos.jpg","datePublished":"2023-09-29T04:00:00+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/es\/2023\/09\/29\/los-beneficios-del-sector-bancario-europeo-alcanzan-su-nivel-mas-alto-desde-la-crisis-financiera-de-2008\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/es\/2023\/09\/29\/los-beneficios-del-sector-bancario-europeo-alcanzan-su-nivel-mas-alto-desde-la-crisis-financiera-de-2008\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/2023\/09\/29\/los-beneficios-del-sector-bancario-europeo-alcanzan-su-nivel-mas-alto-desde-la-crisis-financiera-de-2008\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/09\/gc-elbancoseuropeos.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/09\/gc-elbancoseuropeos.jpg","width":1230,"height":1076},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/es\/2023\/09\/29\/los-beneficios-del-sector-bancario-europeo-alcanzan-su-nivel-mas-alto-desde-la-crisis-financiera-de-2008\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legrandcontinent.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Los beneficios del sector bancario europeo alcanzan su nivel m\u00e1s alto desde la crisis financiera de 2008"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/es\/#website","url":"https:\/\/legrandcontinent.eu\/es\/","name":"El Grand Continent","description":"La escala pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c","name":"florent","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","caption":"florent"}}]}},"lgc_categories":[{"id":522,"name":"Los datos que lo cambian todo","slug":"los-datos-que-lo-cambian-todo"}],"lgc_author":null,"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/09\/gc-elbancoseuropeos.jpg","width":1230,"height":1076,"alt":""},"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/23647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/users\/1366"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/comments?post=23647"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/23647\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media\/23648"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media?parent=23647"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/categories?post=23647"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/tags?post=23647"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/staff?post=23647"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/editorial_format?post=23647"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/serie?post=23647"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/audience?post=23647"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/geo?post=23647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}