{"id":2342,"date":"2021-11-26T12:48:54","date_gmt":"2021-11-26T12:48:54","guid":{"rendered":"https:\/\/legrandcontinent.eu\/es\/?p=2342"},"modified":"2022-10-31T06:31:39","modified_gmt":"2022-10-31T06:31:39","slug":"que-lugar-para-brasil-en-el-mundo-de-manana","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/es\/2021\/11\/26\/que-lugar-para-brasil-en-el-mundo-de-manana\/","title":{"rendered":"Lula: \u00bfQu\u00e9 lugar para Brasil en el mundo de ma\u00f1ana?"},"content":{"rendered":"\n<p class=\"has-drop-cap\">Tengo mucho que agradecer por el apoyo y la solidaridad que recib\u00ed de tantos amigos y compa\u00f1eros en Francia, a lo largo del per\u00edodo en que fui objeto de una implacable persecuci\u00f3n judicial, pol\u00edtica y medi\u00e1tica en mi pa\u00eds&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-2342' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2021\/11\/26\/que-lugar-para-brasil-en-el-mundo-de-manana\/#easy-footnote-bottom-1-2342' title='Este texto es una traducci\u00f3n del&lt;a href=&quot;https:\/\/lula.com.br\/leia-o-discurso-de-lula-no-sciences-po\/&quot;&gt; discurso del ex presidente Luiz In\u00e1cio Lula da Silva&lt;\/a&gt; en Sciences Po Paris y moderado por Gaspard Estrada (director ejecutivo del OPALC), el 16 de noviembre de 2021.'><sup>1<\/sup><\/a><\/span><\/span>. Y como ya lo dije, reafirmo una vez m\u00e1s que estos homenajes no me pertenecen a t\u00edtulo personal, sino que pertenecen al sufrido y valiente pueblo brasile\u00f1o, por su lucha permanente por un pa\u00eds y un mundo m\u00e1s justo, menos desigual y m\u00e1s democr\u00e1tico.<\/p>\n\n\n\n<p>La solidaridad con los perseguidos del mundo es una de las tradiciones m\u00e1s admirables del pueblo de Par\u00eds; una tradici\u00f3n que, afortunadamente, persiste en estos tiempos en los que el odio y la intolerancia se extienden. Agradezco especialmente al Comit\u00e9 Lula Libre de Francia, el apoyo que he recibido de compa\u00f1eros como Fran\u00e7ois Hollande y Jean-Luc M\u00e9lenchon, al Consejo de Par\u00eds y la alcaldesa Anne Hidalgo, por mi nombramiento como Ciudadano de Honor de Par\u00eds. Fueron gestos generosos que rompieron el muro de silencio sobre nuestra resistencia en Brasil.<\/p>\n\n\n\n<p>Fueron cinco a\u00f1os de lucha por la verdad y la justicia, hasta que el Tribunal Supremo de Brasil acab\u00f3 por demostrar la sospecha y la parcialidad del juez que me conden\u00f3 sin pruebas y sin motivo, como hab\u00edan denunciado desde el principio mis incansables abogados Cristiano Zanin y Valeska Teixeira Martins.<\/p>\n\n\n\n<p>Siempre entend\u00ed que al condenarme, encarcelarme de manera ilegal e intentar proscribirme, se pretend\u00eda destruir el proyecto de un pa\u00eds m\u00e1s justo, soberano, comprometido con la sostenibilidad ambiental e integrado democr\u00e1ticamente en el mundo, ese pa\u00eds que los gobiernos del Partido de los Trabajadores representaban y siguen representando en Brasil.<\/p>\n\n\n\n<p>Nuestra victoria en la dura batalla por el restablecimiento de mi inocencia y mis derechos pol\u00edticos forma parte de la lucha m\u00e1s amplia del pueblo brasile\u00f1o y de quienes defienden la libertad y la democracia a lo largo y ancho del mundo. Si ganamos, es porque nunca estuve solo. Los 580 d\u00edas y noches que pas\u00e9 en la c\u00e1rcel fueron tambi\u00e9n 580 d\u00edas y noches en los que, del otro lado, afuera, bajo el sol o la lluvia, compa\u00f1eros que ni siquiera conoc\u00eda personalmente estaban en permanente y solidaria vigilia.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"despues-de-diez-anos-de-retroceso\"><strong>Despu\u00e9s de diez a\u00f1os de retroceso<\/strong><\/h3>\n\n\n\n<p>Cuando estuve en Francia, en septiembre de 2011, el mundo a\u00fan sufr\u00eda los impactos de la gran crisis del capitalismo de 2008, resultado de la especulaci\u00f3n financiera desenfrenada y descontrolada.<\/p>\n\n\n\n<p>La advertencia sobre los efectos nocivos del calentamiento global ya formaba parte de la agenda. Debatimos sobre la necesidad de reforzar las organizaciones multilaterales y de actuar de forma coordinada por la paz, contra la desigualdad, la miseria y el hambre en el mundo.<\/p>\n\n\n\n<p>Diez a\u00f1os despu\u00e9s, los retos fundamentales de la humanidad siguen siendo los mismos. La urgencia de hacerles frente es cada vez mayor; una urgencia agravada por una pandemia que sigue devastando especialmente a las poblaciones de los pa\u00edses m\u00e1s pobres, adem\u00e1s de aquellos cuyos gobiernos han negado la Ciencia o, peor a\u00fan, han invertido en la muerte, como ha ocurrido en Brasil.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>La solidaridad con los perseguidos del mundo es una de las tradiciones m\u00e1s admirables del pueblo de Par\u00eds; una tradici\u00f3n que, afortunadamente, persiste en estos tiempos en los que el odio y la intolerancia se extienden.<\/p><cite>Luiz In\u00e1cio Lula da Silva<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Es duro, pero necesario, admitir que en la \u00faltima d\u00e9cada el mundo ha retrocedido.<\/p>\n\n\n\n<p>No hay manera de explicar a las generaciones futuras que en nuestros tiempos el 1% de la humanidad posee casi la mitad de la riqueza del planeta, mientras 800 millones de personas pasan hambre. O explicar que unos pocos privilegiados viajan al espacio por capricho de un multimillonario, mientras millones de familias no tienen ni siquiera un lugar donde vivir.<\/p>\n\n\n\n<p>No hay justificaci\u00f3n para no haber gravado las transacciones financieras mundiales y creado fondos para el desarrollo y la lucha contra la pobreza.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"una-razon-para-la-esperanza\"><strong>Una raz\u00f3n para la esperanza<\/strong><\/h3>\n\n\n\n<p>Es ante estos desaf\u00edos que se me invita a hablar del papel de Brasil en el futuro pr\u00f3ximo. A pesar de la grav\u00edsima situaci\u00f3n y de todos los retrocesos que se han impuesto al pa\u00eds y al pueblo brasile\u00f1o en los \u00faltimos a\u00f1os, quiero traer una palabra de esperanza.<\/p>\n\n\n\n<p>Es inevitable comparar la posici\u00f3n que Brasil hab\u00eda alcanzado en las relaciones internacionales con el aislamiento en el que se encuentra hoy. Esto no es casualidad. Es el resultado de una disputa por el poder que extrapol\u00f3 los l\u00edmites de la Constituci\u00f3n y el respeto a la democracia, hasta culminar en el golpe del <em>impeachment<\/em> sin delito de la presidenta Dilma Rousseff en 2016, y todo lo que vino despu\u00e9s.<\/p>\n\n\n\n<p>El objetivo no disimulado del golpe fue revertir el proyecto de un pa\u00eds soberano, centrado en el desarrollo econ\u00f3mico, social y ambientalmente sostenible, con creaci\u00f3n de empleo y distribuci\u00f3n de la renta para la inmensa mayor\u00eda hist\u00f3ricamente excluida.<\/p>\n\n\n\n<p>Aumentamos significativamente la inversi\u00f3n p\u00fablica en pol\u00edticas sociales y de infraestructura para el crecimiento, reduciendo y controlando la inflaci\u00f3n y la deuda p\u00fablica. Brasil se convirti\u00f3 en la sexta econom\u00eda del mundo. En 12 a\u00f1os, creamos 20 millones de empleos formales, aumentamos el salario m\u00ednimo en un 74% y, gracias a un conjunto de programas, con el Bolsa Fam\u00edlia como el m\u00e1s conocido, sacamos a 36 millones de personas de la pobreza. En 2012, Brasil fue eliminado del Mapa del Hambre de la ONU.<\/p>\n\n\n\n<p>Creamos 18 universidades, con 178 nuevos campus y 422 escuelas t\u00e9cnicas en todo el pa\u00eds. El Estado cre\u00f3 y comenz\u00f3 a garantizar el cr\u00e9dito educativo, ampli\u00f3 la oferta de plazas y reserv\u00f3 cupos para estudiantes negros, ind\u00edgenas y de escuelas p\u00fablicas en las universidades. La matriculaci\u00f3n en la ense\u00f1anza superior pas\u00f3 de 3,5 millones a 8 millones y, por primera vez, los negros, mulatos e hijos de trabajadores se convirtieron en mayor\u00eda en las universidades p\u00fablicas de Brasil.<\/p>\n\n\n\n<p>De este modo, redujimos la desigualdad y, al mismo tiempo, profundizamos la democracia.<\/p>\n\n\n\n<p>Suelo decir que todo esto ocurri\u00f3 porque, tambi\u00e9n por primera vez, pusimos a los pobres y a los trabajadores en el presupuesto federal, el <em>Or\u00e7amento da Uni\u00e3o<\/em>, demostrando que no constituyen el problema, sino la soluci\u00f3n para el pa\u00eds.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"el-proceso-de-destruccion-nacional\"><strong>El proceso de destrucci\u00f3n nacional<\/strong><\/h3>\n\n\n\n<p>Transformaciones de esta magnitud parecen intolerables para unas \u00e9lites forjadas en un proceso hist\u00f3rico marcado por la apropiaci\u00f3n violenta de la tierra y las riquezas naturales, por el genocidio de los ind\u00edgenas y por m\u00e1s de tres siglos de esclavitud de los pueblos africanos.&nbsp;<\/p>\n\n\n\n<p>Hab\u00edamos interrumpido un ciclo de pol\u00edticas econ\u00f3micas neoliberales, de contracci\u00f3n del Estado y de privatizaci\u00f3n sin criterio. Fuimos contra poderosos intereses econ\u00f3micos, financieros y geopol\u00edticos dentro y fuera de Brasil. Fue para interrumpir ese proyecto de pa\u00eds soberano y reanudar el ciclo neoliberal que mintieron al pa\u00eds hasta conducir a un gobierno autoritario y oscurantista a la presidencia de la Rep\u00fablica.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>El objetivo no disimulado del golpe fue revertir el proyecto de un pa\u00eds soberano, centrado en el desarrollo econ\u00f3mico, social y ambientalmente sostenible, con creaci\u00f3n de empleo y distribuci\u00f3n de la renta para la inmensa mayor\u00eda hist\u00f3ricamente excluida.<\/p><cite>Luiz In\u00e1cio Lula da Silva<\/cite><\/blockquote><\/figure>\n\n\n\n<p>En realidad, el proceso de destrucci\u00f3n nacional en curso en Brasil solo podr\u00eda ser dirigido por un gobierno antidemocr\u00e1tico, en un pa\u00eds envenenado por la industria de las <em>fake news<\/em> y en el que la oposici\u00f3n est\u00e1 excluida de los debates en los principales medios de comunicaci\u00f3n.<\/p>\n\n\n\n<p>Han destruido cadenas econ\u00f3micas esenciales: los sectores de ingenier\u00eda, petr\u00f3leo y gas, y est\u00e1n destruyendo la mayor empresa del pueblo brasile\u00f1o, Petrobras. Han erosionado las finanzas p\u00fablicas y, a contracorriente de sus promesas, han minado la confianza de los inversores. Han transformado Brasil en una econom\u00eda en la que solo obtienen beneficios los especuladores y los oportunistas.<\/p>\n\n\n\n<p>El resultado es que en tan solo cinco a\u00f1os los trabajadores han perdido derechos fundamentales, el desempleo y el coste de la vida se han disparado, los programas sociales se han abandonado o interrumpido, incluyendo el de Bolsa Fam\u00edlia. El hambre forma parte una vez m\u00e1s de la vida cotidiana de las familias.<\/p>\n\n\n\n<p>El gobierno desmantela pol\u00edticas p\u00fablicas exitosas y persigue a cient\u00edficos, artistas, profesores y l\u00edderes sociales; fomenta la destrucci\u00f3n de los bosques y la miner\u00eda ilegal.<\/p>\n\n\n\n<p>Este gobierno coloc\u00f3 a Brasil de espaldas hacia el mundo y es el pueblo el que m\u00e1s sufre por ello.<\/p>\n\n\n\n<p>Por todo ello, una nueva inserci\u00f3n de Brasil en el escenario mundial pasa necesariamente por la reconstrucci\u00f3n del pa\u00eds, en un proceso de elecciones democr\u00e1ticas y verdaderamente libres, sin <em>fake news<\/em>, a diferencia de lo ocurrido en 2018.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"brasil-en-el-mundo-tras-el-aislamiento-el-regreso-al-primer-plano\"><strong>Brasil en el mundo: tras el aislamiento, \u00bfel regreso al primer plano?&nbsp;<\/strong><\/h3>\n\n\n\n<p>El aislamiento pol\u00edtico y diplom\u00e1tico de Brasil es perjudicial no solo para nuestro pa\u00eds, sino para la comunidad de naciones. Me atrevo a decir que nuestra participaci\u00f3n activa en los principales foros mundiales es muy escasa para el mundo.<\/p>\n\n\n\n<p>Brasil es mucho m\u00e1s que un inmenso territorio, un gran mercado y una econom\u00eda que hasta hace poco era uno de los mayores destinos de la inversi\u00f3n productiva. Brasil son 213 millones de seres humanos, de los m\u00e1s diversos or\u00edgenes, con capacidad de trabajar, aprender, ense\u00f1ar y so\u00f1ar. Un pa\u00eds defensor del di\u00e1logo, con una tradici\u00f3n de convivencia pac\u00edfica y respeto a la autodeterminaci\u00f3n de los pueblos.<\/p>\n\n\n\n<p>Tenemos mucho que aportar en cuestiones como la lucha contra la pobreza y el hambre; el di\u00e1logo pol\u00edtico; la construcci\u00f3n de la paz; el equilibrio geopol\u00edtico del mundo; la democratizaci\u00f3n de las relaciones financieras y comerciales entre pa\u00edses; y la lucha contra la emergencia clim\u00e1tica. Tenemos mucho que aportar a la seguridad alimentaria del planeta, la econom\u00eda mundial, la cultura, la ciencia y la tecnolog\u00eda.<\/p>\n\n\n\n<p>Como el pueblo brasile\u00f1o vuelve a decidir el rumbo del pa\u00eds, estoy seguro de que actuaremos con firmeza en el conjunto de las iniciativas para superar la indecente desigualdad entre pa\u00edses, y para garantizar la seguridad ambiental del planeta. Esta es nuestra vocaci\u00f3n y era la pr\u00e1ctica que nos guiaba cuando gobern\u00e1bamos.<\/p>\n\n\n\n<p>Recuerdo que fuimos a la Conferencia Internacional sobre el Cambio Clim\u00e1tico en Copenhague, all\u00e1 por 2009, donde presentamos el objetivo voluntario de reducir las emisiones de CO2 en un 39% para 2020, compromiso que fue transformado en ley por el Congreso Nacional. Aquella actitud nos dio legitimidad para convocar a los grandes pa\u00edses a la mesa, lanzando all\u00ed las semillas de lo que ser\u00eda el Acuerdo Clim\u00e1tico de Par\u00eds de 2015.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\" id=\"como-el-pueblo-brasileno-vuelve-a-decidir-el-rumbo-del-pais-estoy-seguro-de-que-actuaremos-con-firmeza-en-el-conjunto-de-las-iniciativas-para-superar-la-indecente-desigualdad-entre-paises-y-para-garantizar-la-seguridad-ambiental-del-planeta\"><blockquote><p>Como el pueblo brasile\u00f1o vuelve a decidir el rumbo del pa\u00eds, estoy seguro de que actuaremos con firmeza en el conjunto de las iniciativas para superar la indecente desigualdad entre pa\u00edses, y para garantizar la seguridad ambiental del planeta.<\/p><cite>Luiz In\u00e1cio Lula da Silva<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Nuestra credibilidad se vio respaldada por la reducci\u00f3n del 75% de la tasa de deforestaci\u00f3n, el nivel m\u00e1s bajo alcanzado hasta entonces. Nuestro gobierno fue responsable del 74% de las unidades de conservaci\u00f3n forestal y medioambiental creadas en el mundo en ese periodo. Present\u00e9 esos datos en Sciences Po, en 2011 y, a pesar de todos los contratiempos, es lo que realmente representa el compromiso del pueblo brasile\u00f1o con el planeta en el que vivimos.<\/p>\n\n\n\n<p>Somos plenamente conscientes de la necesidad de preservar la Amazonia, por una raz\u00f3n muy sencilla y poco extendida: en ella viven m\u00e1s de 25 millones de brasile\u00f1os y brasile\u00f1as, incluido pueblos ind\u00edgenas, poblaciones ribere\u00f1as, pescadores y extractivistas. Nadie tiene m\u00e1s inter\u00e9s en preservar la selva, sana y en pie, que quienes viven de ella, en necesario equilibrio.<\/p>\n\n\n\n<p>Hemos delimitado m\u00e1s de 50 millones de \u00e1reas de protecci\u00f3n forestal en nuestros gobiernos, para que puedan convivir los ind\u00edgenas, los quilombolas y las poblaciones locales en armon\u00eda con la naturaleza. Fomentamos la investigaci\u00f3n cient\u00edfica y el uso sostenible de los recursos amaz\u00f3nicos en beneficio de la humanidad.<\/p>\n\n\n\n<p>Los que destruyen, degradan, incendian y deforestan son invasores que, durante nuestro periodo, ven\u00edan siendo cada vez m\u00e1s reprimidos por la ley y por el Estado, pero bajo el actual gobierno se les ha dado un salvoconducto para cometer sus delitos.<\/p>\n\n\n\n<p>Somos nosotros los m\u00e1s radicalmente interesados en mantener vivo ese patrimonio natural, sin renunciar a nuestra soberan\u00eda ni a nuestra responsabilidad intransferible. Fue as\u00ed como obtuvimos, por ejemplo, el apoyo financiero de Alemania y Noruega para crear el Fondo Amazonia, que lamentablemente fue convertido en algo inviable por el actual gobierno de Brasil.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"la-importancia-de-la-integracion-regional-en-un-mundo-multipolar\"><strong>La importancia de la integraci\u00f3n regional en un mundo multipolar<\/strong><\/h3>\n\n\n\n<p>Fue para abrirnos al mundo, de manera soberana y solidaria, que nos comprometimos con la integraci\u00f3n latinoamericana comenzando por Am\u00e9rica del Sur. Fortalecimos el Mercosur, creamos Unasur, el Instituto Sudamericano de Gobierno en Salud, el Consejo de Defensa Sudamericano y luego la Comunidad de Estados Latinoamericanos y Caribe\u00f1os, la CELAC.<\/p>\n\n\n\n<p>No es insignificante, teniendo en cuenta la historia, que hayamos establecido en Am\u00e9rica Latina y el Caribe un foro pol\u00edtico y diplom\u00e1tico aut\u00f3nomo de Estados Unidos.<\/p>\n\n\n\n<p>En mi opini\u00f3n, el avance de la integraci\u00f3n regional permitir\u00e1 que nuestros pa\u00edses contribuyan eficazmente a un di\u00e1logo global m\u00e1s democr\u00e1tico. Por eso tambi\u00e9n innovamos con la creaci\u00f3n del Foro Trilateral IBSA, con India y Sud\u00e1frica, y del BRICS, que incluye a Rusia y China.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Los que destruyen, degradan, incendian y deforestan son invasores que, durante nuestro periodo, ven\u00edan siendo cada vez m\u00e1s reprimidos por la ley y por el Estado, pero bajo el actual gobierno se les ha dado un salvoconducto para cometer sus delitos.<\/p><cite>Luiz In\u00e1cio Lula da Silva<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Ampliamos el comercio y las relaciones con la Uni\u00f3n Europea y avanzamos en la asociaci\u00f3n estrat\u00e9gica y de defensa con Francia. Cooperamos con los pa\u00edses africanos, establecimos un nuevo di\u00e1logo con los pa\u00edses \u00e1rabes y con China, sin perjuicio de las relaciones comerciales y diplom\u00e1ticas que ten\u00edamos con otros pa\u00edses.<\/p>\n\n\n\n<p>Fueron avances importantes, en el marco de una visi\u00f3n de un mundo multipolar, cuyas consecuencias pr\u00e1cticas contribuyeron a la defensa de unas relaciones econ\u00f3micas y pol\u00edticas m\u00e1s equilibradas entre los pa\u00edses. La necesidad de reforzar o renovar el sistema multilateral, haci\u00e9ndolo m\u00e1s eficaz mediante su democratizaci\u00f3n, es una cuesti\u00f3n dram\u00e1ticamente urgente para el mundo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"reformar-el-sistema-multilateral\"><strong>Reformar el sistema multilateral<\/strong><\/h3>\n\n\n\n<p>Nunca he estado satisfecho con que los pa\u00edses ricos no siguieran las resoluciones del G20 en las reuniones de Londres y Pittsburgh en 2009.<\/p>\n\n\n\n<p>M\u00e1s all\u00e1 de la frustraci\u00f3n por lo que se dej\u00f3 de hacer, me preocupa que la comunidad internacional haya hecho tan poco para evitar otra crisis a una escala a\u00fan mayor. El sistema financiero globalmente integrado ejerce su poder de forma instant\u00e1nea sobre la vida de 7.800 millones de personas.<\/p>\n\n\n\n<p>\u00bfTendremos que esperar hasta la pr\u00f3xima crisis para volver a hablar de la necesidad de una gobernanza mundial democr\u00e1tica? \u00bfHasta cu\u00e1ndo la codicia de los ricos, el aislacionismo de los gobiernos y el individualismo prevalecer\u00e1n sobre los intereses del planeta y de la humanidad?<\/p>\n\n\n\n<p>Estamos hablando de la responsabilidad de los Estados nacionales y de la recuperaci\u00f3n del papel de la Pol\u00edtica, en su sentido m\u00e1s elevado, para afrontar juntos y de forma coordinada el reto de la desigualdad.<\/p>\n\n\n\n<p>El atraso, la pobreza y el hambre no son mandamientos divinos. Son el resultado de lo que hacemos o dejamos de hacer en este mundo.<\/p>\n\n\n\n<p>La experiencia me ha demostrado que para enfrentar la desigualdad en un pa\u00eds, el rol del Estado es central para recaudar y distribuir, para planificar y ejecutar pol\u00edticas p\u00fablicas integrales, para garantizar los derechos de los m\u00e1s d\u00e9biles. Estas funciones ejerce el Estado cuando se gobierna democr\u00e1ticamente, coexistiendo con la energ\u00eda de una sociedad libre: partidos, movimientos, prensa, universidades e individuos.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>\u00bfHasta cu\u00e1ndo la codicia de los ricos, el aislacionismo de los gobiernos y el individualismo prevalecer\u00e1n sobre los intereses del planeta y de la humanidad?<\/p><cite>Luiz In\u00e1cio Lula da Silva<\/cite><\/blockquote><\/figure>\n\n\n\n<p>La desigualdad entre pueblos y pa\u00edses tampoco naci\u00f3 con la humanidad. Es el resultado de procesos hist\u00f3ricos que han privilegiado a algunos en detrimento de muchos, en un c\u00edrculo vicioso, hasta llegar al punto en que nos encontramos.<\/p>\n\n\n\n<p>Es cierto que no tenemos respuestas preparadas a estas preguntas, pero es a\u00fan m\u00e1s cierto que solo empeorar\u00e1n si permanecemos quietos y todo sigue como est\u00e1.<\/p>\n\n\n\n<p>Debemos buscar esos caminos en un di\u00e1logo democr\u00e1tico, sincero y con sentido de la justicia, al que Brasil tendr\u00e1 mucho que aportar, en cuanto vuelva a ser un pa\u00eds soberano.<\/p>\n\n\n\n<p>El mundo sigue viviendo la gran crisis provocada por la pandemia. Como ocurri\u00f3 tras otras grandes crisis, es necesario reconstruir las instituciones internacionales sobre nuevas bases. No podemos seguir rigi\u00e9ndonos por el sistema creado tras la Segunda Guerra Mundial. Es urgente convocar una conferencia mundial, con representaci\u00f3n de todos los Estados y la participaci\u00f3n de la sociedad civil, para definir una nueva gobernanza mundial que sea justa y representativa.<\/p>\n\n\n\n<p>En este planeta que compartimos, el futuro de la humanidad debe construirse con di\u00e1logo y no con autoritarismo, con paz y no con violencia; con m\u00e1s libros y no con m\u00e1s armas; con m\u00e1s escuelas y menos c\u00e1rceles. Con m\u00e1s verdades y menos mentiras. Con m\u00e1s respeto por la naturaleza, para asegurar el agua, el aire y la vida para nuestros hijos y nietos. Con m\u00e1s acogida y solidaridad, y menos exclusi\u00f3n. Con m\u00e1s amor y menos odio.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"la-posicion-de-brasil-ante-la-rivalidad-entre-estados-unidos-y-china\"><strong>La posici\u00f3n de Brasil ante la rivalidad entre Estados Unidos y China<\/strong><\/h3>\n\n\n\n<p>No puedo hablar en nombre de Brasil: no soy autoridad brasile\u00f1a. Lo que puedo decir es lo que pienso. Hemos conversado con algunos compa\u00f1eros para que no nos enfrentemos a una segunda Guerra Fr\u00eda, luego de la primera Guerra Fr\u00eda entre el capitalismo y el comunismo, entre Estados Unidos y la Uni\u00f3n Sovi\u00e9tica. Ahora es la revoluci\u00f3n tecnol\u00f3gica la que marca la disputa entre Estados Unidos y China. No tenemos por qu\u00e9 aceptarlo. Y es por eso que tenemos que tratar de perfeccionar nuestro trabajo en Am\u00e9rica del Sur, en Am\u00e9rica Latina, mejorando nuestras relaciones y tratando de establecer un acuerdo con la Uni\u00f3n Europea.&nbsp;<\/p>\n\n\n\n<p>Esto es lo que puedo decir. Tuve un encuentro con el compa\u00f1ero Olaf Scholz, que ser\u00e1 el futuro Canciller de Alemania, para conversar un poco sobre el futuro de un acuerdo entre Am\u00e9rica Latina y la Uni\u00f3n Europea. Me encontr\u00e9 con el Presidente Macron y convers\u00e9 sobre este mismo asunto, porque s\u00e9 cu\u00e1l es el papel de Francia y s\u00e9 cu\u00e1l es el papel de Brasil. Despu\u00e9s convers\u00e9 con el Primer Ministro de Espa\u00f1a e incluso con otras personas. La raz\u00f3n es que nosotros tenemos una peque\u00f1a divergencia. Nosotros, en Am\u00e9rica del Sur y en Am\u00e9rica Latina, queremos desarrollarnos desde el punto de vista industrial, para que podamos exportar productos manufacturados de mayor valor agregado. Hist\u00f3ricamente, nosotros exportamos soja, harina de soja, aceite de soja, de ma\u00edz y minerales de hierro. Para que se hagan una idea, hace treinta a\u00f1os, 30% de la econom\u00eda brasile\u00f1a era industrial. Hoy es apenas el 11%. Tendremos entonces que hacer un esfuerzo inmenso, inconmensurable, extraordinario para volver a industrializar el pa\u00eds. Nosotros tambi\u00e9n queremos producir productos con valor agregado.&nbsp;<\/p>\n\n\n\n<p>Creo en particular que Brasil tiene que conversar muy seriamente con China y que Brasil tiene que conversar muy seriamente con Estados Unidos. No creo que Brasil tenga que estar a un lado. Tiene que pesar por los dos lados. Brasil no es un pa\u00eds que tenga una cultura anti-americana, ni que la quiera tener. Queremos que tambi\u00e9n nos permitan ser grandes y fuertes, que nos permitan entrar en el juego. Ahora, cuando a Brasil le pasan la bola, la patea y sale corriendo.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Creo que Brasil tiene que conversar muy seriamente con China y que Brasil tiene que conversar muy seriamente con Estados Unidos. No creo que Brasil tenga que estar a un lado. <\/p><cite>Luiz In\u00e1cio Lula da Silva<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Brasil son 500 a\u00f1os de espera. Hace 500 a\u00f1os que estamos esperando crecer, que pretendemos desarrollarnos. Y a\u00fan nunca hemos llegado all\u00ed donde queremos llegar. Hay cosas entonces que no podemos aceptar. Creo que Brasil cuenta con una autoridad moral ahora que tendr\u00e1 un Presidente democr\u00e1tico, una persona civilizada. Brasil se sentar\u00e1 con la UE, como nos hemos sentado muchas veces, y se sentar\u00e1 con India y China. En su momento, particip\u00e9 en muchas reuniones de la Organizaci\u00f3n Mundial del Comercio. Mucha gente conversaba con cierto nerviosismo conmigo cuando reconoc\u00ed a China como econom\u00eda de mercado. Y reconoc\u00ed a China como econom\u00eda de mercado porque quer\u00eda que China estuviera dentro de la OMC. Era muy dif\u00edcil hacer una reuni\u00f3n de la OMC con China fuera. Ten\u00eda que estar dentro para que pudi\u00e9ramos negociar. Ese es el tipo de trabajo que Brasil puede hacer. Creo que ahora que Brasil regresar\u00e1 a la normalidad democr\u00e1tica, la normalidad \u00e9tica, la normalidad de la civilizaci\u00f3n, podr\u00e1 tener un peso en las discusiones y ayudar a encontrar salidas. Creo con toda humildad que, en este instante, Europa precisa de Brasil como sost\u00e9n para llegar a un acuerdo y para que tengamos un bloque m\u00e1s fuerte. El mundo est\u00e1 compuesto de bloques. Nos tenemos que juntar para tener mayor fuerza y hacer que la econom\u00eda mundial sea m\u00e1s solidaria.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"las-prioridades-de-un-eventual-gobierno-lula\"><strong>Las prioridades de un eventual gobierno Lula&nbsp;<\/strong><\/h3>\n\n\n\n<p>A veces me encuentro frustrado porque Dios quiso que yo participara del momento m\u00e1s excepcional en t\u00e9rminos de democracia y de inclusi\u00f3n social en Am\u00e9rica Latina. Fue un momento muy importante: Michelle Bachelet en Chile, Cristina Kirchner en Argentina, Rafael Correa en Ecuador, Hugo Ch\u00e1vez en Venezuela, Evo Morales en Bolivia.&nbsp;<\/p>\n\n\n\n<p>Se suele hablar de Evo Morales como si fuese un cualquiera. Evo Morales fue un Presidente ind\u00edgena, el que m\u00e1s pol\u00edticas de inclusi\u00f3n social ha promovido en Bolivia. Gracias a \u00e9l, Bolivia tiene hoy m\u00e1s reservas internacionales que el equivalente a su PIB. Es cierto: \u00e9l quiso ser Presidente otra vez. Yo sinceramente estaba en contra. En un sistema presidencial, uno no puede tener cuatro mandatos. Algo que no es as\u00ed parlamentarismo, donde uno puede tener 50. Merkel acaba de terminar 16 a\u00f1os de gesti\u00f3n, Miterrand ha tenido 15, Tony Blair 12, Margaret Tatcher 16. En la democracia presidencialista, eso no se puede.&nbsp;<\/p>\n\n\n\n<p>Nuestra relaci\u00f3n con Per\u00fa era muy buena. Per\u00fa tiene un problema fant\u00e1stico: durante todo el gobierno de Toledo y todo el gobierno de Al\u00e1n Garc\u00eda, la econom\u00eda peruana crec\u00eda a un ritmo de 7% anual. Sin embargo, no hab\u00eda ni una mejora en la calidad de vida del pueblo. No s\u00e9 por qu\u00e9 no se hac\u00edan pol\u00edticas sociales.&nbsp;<\/p>\n\n\n\n<p>Sinceramente creo que viv\u00ed un momento excepcional. Las personas hablan mucho de Ch\u00e1vez. Ch\u00e1vez era una de las personas m\u00e1s extraordinarias que conoc\u00ed. A veces no concord\u00e1bamos con \u00e9l. Le dec\u00edamos que no peleara tanto, que se quedara quieto. A veces peleaba de m\u00e1s, pero era un ser humano extraordinario. Si se encontraran con Ch\u00e1vez y tuvieran media hora de conversaci\u00f3n con \u00e9l, se ir\u00edan encantados.&nbsp;<\/p>\n\n\n\n<p>Ten\u00edamos tambi\u00e9n a Uribe, Presidente colombiano de derecha. Ten\u00eda una relaci\u00f3n muy buena, muy civilizada con nosotros, muy respetuosa. Brasil ten\u00eda relaci\u00f3n con Guyana, con Nicaragua, con Cuba, con Costa Rica. Visitamos todos los pa\u00edses m\u00e1s de una vez. Visitamos casi 30 pa\u00edses africanos. Abrimos una universidad en Mozambique. Abrimos una f\u00e1brica en Mozambique para producir remedios contra el HIV para toda \u00c1frica, que creo que ya cerr\u00f3. Llevamos a Embrapa a Ghana porque imagin\u00e1bamos que la sabana africana ten\u00eda la misma capacidad productiva que el cerrado brasilero. Todo eso acab\u00f3. Y todo eso puede volver si el pueblo as\u00ed lo desea.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El ex presidente brasile\u00f1o Lula hace un balance grave de la situaci\u00f3n de su pa\u00eds, pero ofrece perspectivas optimistas para el regreso al primer plano de Brasil en el mundo.<\/p>\n","protected":false},"author":1366,"featured_media":2352,"comment_status":"open","ping_status":"open","sticky":false,"template":"templates\/post-editorials.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":18,"footnotes":""},"categories":[6],"tags":[],"staff":[108],"editorial_format":[1471],"serie":[],"audience":[],"geo":[172],"class_list":["post-2342","post","type-post","status-publish","format-standard","hentry","category-politica","staff-luiz-inacio-lula-da-silva","editorial_format-piezas-de-doctrinas","geo-americas"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":2352,"excerpt":"El ex presidente brasile\u00f1o Lula hace un balance grave de la situaci\u00f3n de su pa\u00eds, pero ofrece perspectivas optimistas para el regreso al primer plano de Brasil en el mundo.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Lula: \u00bfQu\u00e9 lugar para Brasil en el mundo de ma\u00f1ana? - El Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/es\/2021\/11\/26\/que-lugar-para-brasil-en-el-mundo-de-manana\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lula: \u00bfQu\u00e9 lugar para Brasil en el mundo de ma\u00f1ana? - El Grand Continent\" \/>\n<meta property=\"og:description\" content=\"El ex presidente brasile\u00f1o Lula hace un balance grave de la situaci\u00f3n de su pa\u00eds, pero ofrece perspectivas optimistas para el regreso al primer plano de Brasil en el mundo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/es\/2021\/11\/26\/que-lugar-para-brasil-en-el-mundo-de-manana\/\" \/>\n<meta property=\"og:site_name\" content=\"El Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-26T12:48:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-31T06:31:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2021\/11\/Lula-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"florent\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2021\/11\/Lula-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"florent\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"18 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2021\/11\/26\/que-lugar-para-brasil-en-el-mundo-de-manana\/\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/2021\/11\/26\/que-lugar-para-brasil-en-el-mundo-de-manana\/\",\"name\":\"Lula: \u00bfQu\u00e9 lugar para Brasil en el mundo de ma\u00f1ana? - El Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2021\/11\/26\/que-lugar-para-brasil-en-el-mundo-de-manana\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2021\/11\/26\/que-lugar-para-brasil-en-el-mundo-de-manana\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2021\/11\/MicrosoftTeams-image-3.jpg\",\"datePublished\":\"2021-11-26T12:48:54+00:00\",\"dateModified\":\"2022-10-31T06:31:39+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2021\/11\/26\/que-lugar-para-brasil-en-el-mundo-de-manana\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/es\/2021\/11\/26\/que-lugar-para-brasil-en-el-mundo-de-manana\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2021\/11\/26\/que-lugar-para-brasil-en-el-mundo-de-manana\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2021\/11\/MicrosoftTeams-image-3.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2021\/11\/MicrosoftTeams-image-3.jpg\",\"width\":1969,\"height\":984},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2021\/11\/26\/que-lugar-para-brasil-en-el-mundo-de-manana\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/legrandcontinent.eu\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lula: \u00bfQu\u00e9 lugar para Brasil en el mundo de ma\u00f1ana?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/\",\"name\":\"El Grand Continent\",\"description\":\"La escala pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\",\"name\":\"florent\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"caption\":\"florent\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lula: \u00bfQu\u00e9 lugar para Brasil en el mundo de ma\u00f1ana? - El Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/es\/2021\/11\/26\/que-lugar-para-brasil-en-el-mundo-de-manana\/","og_locale":"es_ES","og_type":"article","og_title":"Lula: \u00bfQu\u00e9 lugar para Brasil en el mundo de ma\u00f1ana? - El Grand Continent","og_description":"El ex presidente brasile\u00f1o Lula hace un balance grave de la situaci\u00f3n de su pa\u00eds, pero ofrece perspectivas optimistas para el regreso al primer plano de Brasil en el mundo.","og_url":"https:\/\/legrandcontinent.eu\/es\/2021\/11\/26\/que-lugar-para-brasil-en-el-mundo-de-manana\/","og_site_name":"El Grand Continent","article_published_time":"2021-11-26T12:48:54+00:00","article_modified_time":"2022-10-31T06:31:39+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2021\/11\/Lula-scaled.jpg","type":"image\/jpeg"}],"author":"florent","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2021\/11\/Lula-scaled.jpg","twitter_misc":{"Escrito por":"florent","Tiempo de lectura":"18 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/es\/2021\/11\/26\/que-lugar-para-brasil-en-el-mundo-de-manana\/","url":"https:\/\/legrandcontinent.eu\/es\/2021\/11\/26\/que-lugar-para-brasil-en-el-mundo-de-manana\/","name":"Lula: \u00bfQu\u00e9 lugar para Brasil en el mundo de ma\u00f1ana? - El Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/es\/2021\/11\/26\/que-lugar-para-brasil-en-el-mundo-de-manana\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/es\/2021\/11\/26\/que-lugar-para-brasil-en-el-mundo-de-manana\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2021\/11\/MicrosoftTeams-image-3.jpg","datePublished":"2021-11-26T12:48:54+00:00","dateModified":"2022-10-31T06:31:39+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/es\/2021\/11\/26\/que-lugar-para-brasil-en-el-mundo-de-manana\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/es\/2021\/11\/26\/que-lugar-para-brasil-en-el-mundo-de-manana\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/2021\/11\/26\/que-lugar-para-brasil-en-el-mundo-de-manana\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2021\/11\/MicrosoftTeams-image-3.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2021\/11\/MicrosoftTeams-image-3.jpg","width":1969,"height":984},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/es\/2021\/11\/26\/que-lugar-para-brasil-en-el-mundo-de-manana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legrandcontinent.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Lula: \u00bfQu\u00e9 lugar para Brasil en el mundo de ma\u00f1ana?"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/es\/#website","url":"https:\/\/legrandcontinent.eu\/es\/","name":"El Grand Continent","description":"La escala pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c","name":"florent","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","caption":"florent"}}]}},"lgc_categories":[{"id":6,"name":"Pol\u00edtica","slug":"politica"}],"lgc_author":{"id":108,"name":"Luiz In\u00e1cio Lula da Silva","slug":"luiz-inacio-lula-da-silva","description":null,"first_name":null,"last_name":null,"picture":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2025\/03\/Luiz_Inacio_Lula_da_Silva_3x4_cropped.jpg","width":816,"height":832,"alt":""}},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2021\/11\/MicrosoftTeams-image-3.jpg","width":1969,"height":984,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2021\/11\/MicrosoftTeams-image-3.jpg","width":1969,"height":984,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/2342","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/users\/1366"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/comments?post=2342"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/2342\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media\/2352"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media?parent=2342"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/categories?post=2342"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/tags?post=2342"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/staff?post=2342"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/editorial_format?post=2342"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/serie?post=2342"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/audience?post=2342"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/geo?post=2342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}