{"id":21929,"date":"2023-08-28T16:05:43","date_gmt":"2023-08-28T15:05:43","guid":{"rendered":"https:\/\/legrandcontinent.eu\/es\/?p=21929"},"modified":"2023-08-28T16:14:19","modified_gmt":"2023-08-28T15:14:19","slug":"ampliarse-a-partir-de-2030-el-discurso-de-charles-michel-en-bled","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/es\/2023\/08\/28\/ampliarse-a-partir-de-2030-el-discurso-de-charles-michel-en-bled\/","title":{"rendered":"\u00abAmpliarse a partir de 2030\u00bb: el discurso de Charles Michel en Bled"},"content":{"rendered":"\n<p class=\"intro\">En la inauguraci\u00f3n del Foro Estrat\u00e9gico de Bled \u2013que re\u00fane cada a\u00f1o a finales de agosto en Eslovenia a personalidades europeas de alto nivel, en particular de los Balcanes\u2013, el Presidente del Consejo Europeo, <a href=\"https:\/\/legrandcontinent.eu\/es\/2022\/04\/01\/europa-potencia-en-formacion\/\">Charles Michel<\/a>, acaba de pronunciar un importante discurso sobre la ampliaci\u00f3n de la Uni\u00f3n Europea al Este y a los Balcanes Occidentales. En un momento en que esta cuesti\u00f3n va a dominar los debates de las pr\u00f3ximas reuniones del Consejo Europeo, se compromete firmemente al proponer una fecha \u20132030\u2013 a partir de la cual la Uni\u00f3n estar\u00eda dispuesta a ampliarse. Asimismo, contribuye a crear una oportunidad pol\u00edtica capaz de catalizar los esfuerzos necesarios para ello, tanto en el seno de la Uni\u00f3n como por parte de los pa\u00edses candidatos.<\/p>\n\n\n\n<p class=\"intro\"><a href=\"https:\/\/legrandcontinent.eu\/es\/2022\/05\/09\/la-europa-de-las-siete-uniones\/\">La cuesti\u00f3n de la ampliaci\u00f3n no es nueva<\/a>: hace veinte a\u00f1os que los Jefes de Estado y de Gobierno de la Uni\u00f3n reconocieron la \u00abperspectiva europea de los pa\u00edses de los Balcanes Occidentales\u00bb en el Consejo Europeo de Sal\u00f3nica de 19 y 20 de junio de 2003, y desde entonces se ha debatido en numerosas ocasiones en las cumbres peri\u00f3dicas UE-Balcanes. Sin embargo, la guerra en Ucrania volvi\u00f3 a situar la cuesti\u00f3n en el primer plano de la mente de los dirigentes europeos. Ya en la Cumbre de Versalles, celebrada los d\u00edas 10 y 11 de marzo de 2022, se plante\u00f3 la cuesti\u00f3n de la ampliaci\u00f3n de la Uni\u00f3n a Ucrania, antes de que el Consejo Europeo decidiera los d\u00edas 23 y 24 de junio de 2022 \u00abconceder el estatuto de pa\u00eds candidato a Ucrania y a la Rep\u00fablica de Moldavia\u00bb, se declarara \u00abdispuesto a conceder el estatuto de pa\u00eds candidato a Georgia\u00bb una vez cumplidas las condiciones, y pidiera \u00abacelerar el proceso de adhesi\u00f3n\u00bb de los pa\u00edses de los Balcanes Occidentales.<\/p>\n\n\n\n<p class=\"intro\">El reto de la secuencia pol\u00edtica que est\u00e1 a punto de comenzar es dar contenido a esta perspectiva. En este contexto, el discurso de Charles Michel prepara el terreno para los debates que podr\u00edan comenzar ya en el Consejo Europeo informal de Granada del 6 de octubre de 2023 y prolongarse hasta el Consejo Europeo de diciembre, cuando los Jefes de Estado y de Gobierno <a href=\"https:\/\/legrandcontinent.eu\/es\/2023\/07\/20\/la-union-como-imperio-postimperial\/\">podr\u00edan decidir la apertura de negociaciones de adhesi\u00f3n con Ucrania y Moldavia<\/a>. Y ello pronunci\u00e1ndose decididamente a favor de la ampliaci\u00f3n, pero a condici\u00f3n de que se cumplan las condiciones para su \u00e9xito, lo que probablemente promover\u00e1 el consenso entre los Jefes de Estado y de Gobierno de la Uni\u00f3n.<\/p>\n\n\n\n<p>Estimados amigos,<\/p>\n\n\n\n<p>Ayer visit\u00e9 algunas de las regiones afectadas por las recientes inundaciones. Pero tambi\u00e9n fui testigo del notable coraje del pueblo esloveno. Tambi\u00e9n me impresionaron la concentraci\u00f3n y la determinaci\u00f3n de las autoridades eslovenas y el liderazgo del Primer Ministro Golob.<\/p>\n\n\n\n<p>La Uni\u00f3n Europea tambi\u00e9n est\u00e1 prestando un apoyo significativo, junto con sus Estados miembros y con socios como Ucrania y los Balcanes Occidentales.<\/p>\n\n\n\n<p>El t\u00edtulo del foro de este a\u00f1o, \u00abSolidaridad para la seguridad mundial\u00bb, adquiere por tanto todo su significado. La solidaridad es lo que fortalece el tejido de una comunidad. Es lo que nos da la fuerza para afrontar los mayores retos de la vida. Y esta misma solidaridad est\u00e1 en el coraz\u00f3n mismo de la integraci\u00f3n europea. Hace m\u00e1s fuerte a nuestra Uni\u00f3n Europea.<\/p>\n\n\n\n<p>Por eso no les sorprender\u00e1 que hoy quiera hablar de solidaridad y tambi\u00e9n de ampliaci\u00f3n.<\/p>\n\n\n\n<p class=\"comment\">El Foro Estrat\u00e9gico de Bled, organizado cada a\u00f1o por iniciativa del Gobierno esloveno, se ha consolidado como una plataforma central para los intercambios entre los dirigentes de las instituciones europeas y los Jefes de Estado y de Gobierno de los Balcanes Occidentales. Este a\u00f1o participan de nuevo todos ellos. La cuesti\u00f3n de la ampliaci\u00f3n de la Uni\u00f3n ocupa un lugar prioritario en su agenda pol\u00edtica.<\/p>\n\n\n\n<p>Queridos amigos,<\/p>\n\n\n\n<p>Nos enfrentamos a crisis sin precedentes e interconectadas. Las cat\u00e1strofes naturales de este verano \u2013aqu\u00ed en Eslovenia, en Grecia y en todo el mundo\u2013 son un recordatorio urgente de que necesitamos gestionar nuestra transici\u00f3n hacia la neutralidad clim\u00e1tica.&nbsp;<\/p>\n\n\n\n<p>La guerra en Europa \u2013en suelo ucraniano\u2013 ha demostrado que la paz y la democracia no pueden darse por sentadas. Esta guerra no s\u00f3lo est\u00e1 devastando Ucrania, sino que est\u00e1 teniendo un profundo impacto en el futuro de nuestro continente y en la seguridad mundial.&nbsp;<\/p>\n\n\n\n<p>El Covid-19 tambi\u00e9n nos ha ense\u00f1ado algunas duras lecciones: la seguridad sanitaria mundial no es un hecho, ni siquiera en los pa\u00edses desarrollados.&nbsp;<\/p>\n\n\n\n<p>Ante estos retos, la Uni\u00f3n ha demostrado que es capaz de actuar con audacia y decisi\u00f3n. Fuimos los primeros del mundo en decidir que nuestro continente ser\u00eda neutro en la dimensi\u00f3n clim\u00e1tica en 2050. Ante la primera pandemia mundial en un siglo, nos unimos para decidir un plan de recuperaci\u00f3n masiva. Y cuando las fuerzas rusas invadieron Ucrania, el Kremlin y muchos otros esperaban una respuesta d\u00e9bil de una Europa dividida. Ocurri\u00f3 todo lo contrario. En pocas horas, el 24 de febrero, respondimos con sanciones masivas contra Rusia y con entregas de armas y municiones a Ucrania.<\/p>\n\n\n\n<p>Ese d\u00eda, la Uni\u00f3n Europea se mostr\u00f3 de una forma completamente distinta: r\u00e1pida, decidida, unida y contundente. Y cuando Putin nos apunt\u00f3 con su \u00abmisil energ\u00e9tico\u00bb, respondimos con un poderoso escudo energ\u00e9tico, un aut\u00e9ntico \u00absistema de defensa energ\u00e9tica\u00bb.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Al diversificar nuestras fuentes de energ\u00eda y poner fin a nuestra excesiva dependencia de los combustibles f\u00f3siles rusos, tambi\u00e9n hemos revitalizado nuestras alianzas con nuestros socios estrat\u00e9gicos.&nbsp;<\/p>\n\n\n\n<p>Todas estas acciones decisivas han estado guiadas por la solidaridad.<\/p>\n\n\n\n<p class=\"comment\">Charles Michel repasa brevemente las principales decisiones adoptadas por el Consejo Europeo en respuesta a las crisis a las que se ha enfrentado la Uni\u00f3n en los \u00faltimos a\u00f1os \u2013cambio clim\u00e1tico, COVID 19, guerra en Ucrania\u2013. Al hacerlo, subraya hasta qu\u00e9 punto la Uni\u00f3n ha sido capaz de demostrar a sus cr\u00edticos que estaban equivocados adoptando medidas en\u00e9rgicas que durante mucho tiempo parecieron impensables: endeudamiento conjunto como parte del plan de recuperaci\u00f3n, entrega de armas a Ucrania, fin de la dependencia del gas ruso, el Pacto Verde. Todas ellas son medidas que han transformado profundamente la Uni\u00f3n.<\/p>\n\n\n\n<p>Queridos amigos,<\/p>\n\n\n\n<p>En un mundo cada vez m\u00e1s complejo, los europeos tenemos que tomar decisiones cruciales. \u00bfNos conformaremos con una Uni\u00f3n Europea que se limite a gestionar las crisis? \u00bfO queremos ser un actor global de primer orden que d\u00e9 forma al futuro? \u00bfNos resignamos a un mundo bipolar en el que prevalezca la confrontaci\u00f3n? \u00bfO aspiramos a construir un mundo multipolar basado en la cooperaci\u00f3n global?&nbsp;<\/p>\n\n\n\n<p>Ya nos hemos vuelto m\u00e1s influyentes (por ejemplo, en la cuesti\u00f3n de la neutralidad clim\u00e1tica), m\u00e1s firmes (por ejemplo, frente a la agresi\u00f3n rusa) y m\u00e1s realistas (por ejemplo, a la hora de trabajar con socios que no est\u00e1n totalmente en sinton\u00eda con nuestros valores). Tambi\u00e9n estamos trabajando duro para ayudar a remodelar el enfoque global del desarrollo, porque es esencial para hacer del mundo un lugar m\u00e1s seguro y pr\u00f3spero. Queremos influir m\u00e1s en la creaci\u00f3n de un mundo mejor. Y queremos ser m\u00e1s fuertes, siendo un aliado m\u00e1s fuerte.&nbsp;<\/p>\n\n\n\n<p>Por eso estamos construyendo nuestra autonom\u00eda estrat\u00e9gica, piedra a piedra.<\/p>\n\n\n\n<p class=\"comment\">Desde el inicio de su mandato, Charles Michel se ha comprometido a reforzar la autonom\u00eda estrat\u00e9gica de la Uni\u00f3n, que describi\u00f3 como \u00abel objetivo de nuestra generaci\u00f3n\u00bb en un discurso pronunciado ante el Instituto Bruegel el 28 de septiembre de 2020. Junto con otros dirigentes europeos, en particular el Presidente Macron, su objetivo es insistir en la necesidad de que la Uni\u00f3n Europea sea un actor de pleno derecho en el escenario internacional, lo que implicar\u00e1 reforzar las capacidades de defensa de la Uni\u00f3n, reducir la dependencia energ\u00e9tica y construir una base econ\u00f3mica m\u00e1s s\u00f3lida, tal como definieron los Jefes de Estado y de Gobierno europeos en la declaraci\u00f3n adoptada el 11 de marzo de 2022 en la Cumbre de Versalles.<\/p>\n\n\n\n<p>Queridos amigos,<\/p>\n\n\n\n<p>Para ser m\u00e1s fuerte y m\u00e1s segura, la Uni\u00f3n debe estrechar sus lazos y hacerse m\u00e1s poderosa. Por eso ha llegado el momento de afrontar el reto de la ampliaci\u00f3n. Tanto para nosotros en la Uni\u00f3n Europea como para nuestros futuros miembros. S\u00ed, creo que as\u00ed deber\u00edamos llamar ahora a los pa\u00edses con perspectivas confirmadas de adhesi\u00f3n a la Uni\u00f3n: los futuros Estados miembros.<\/p>\n\n\n\n<p>Es hora de acabar con las ambig\u00fcedades y afrontar los retos que tenemos por delante con claridad y honestidad.<\/p>\n\n\n\n<p>Para los Balcanes Occidentales, el camino hacia la Uni\u00f3n empez\u00f3 hace m\u00e1s de 20 a\u00f1os: es una regi\u00f3n en el coraz\u00f3n de Europa, rodeada por la Uni\u00f3n Europea. Tambi\u00e9n era una regi\u00f3n que sal\u00eda de un conflicto tras la desintegraci\u00f3n de Yugoslavia. La Cumbre de Sal\u00f3nica de 2003 confirm\u00f3 la perspectiva europea de los Balcanes Occidentales. Pero su lento avance hacia Europa ha decepcionado a muchos, tanto en la regi\u00f3n como en la Uni\u00f3n.&nbsp;<\/p>\n\n\n\n<p>Estoy de acuerdo con <a href=\"https:\/\/legrandcontinent.eu\/es\/2022\/08\/29\/discurso-de-praga-entender-el-giro-de-scholz-sobre-la-union\/\">el Canciller Scholz cuando dice que Europa debe cumplir sus promesas<\/a>. En este mismo momento, los ucranianos est\u00e1n defendiendo heroicamente su pa\u00eds. El Kremlin no s\u00f3lo est\u00e1 atacando a un vecino libre y soberano. Est\u00e1 atacando todo aquello en lo que creemos: libertad, democracia, prosperidad y cooperaci\u00f3n. Por eso, el pasado mes de junio concedimos el estatus de candidatos a Ucrania y Moldavia. A Georgia se le conceder\u00e1 el mismo estatus una vez haya dado los pasos necesarios.<\/p>\n\n\n\n<p class=\"comment\">En su discurso pronunciado en Praga el 29 de agosto de 2022, <a href=\"https:\/\/legrandcontinent.eu\/es\/2022\/08\/30\/lo-que-hay-que-destacar-del-discurso-de-olaf-scholz-en-praga\/\">el Canciller Scholz se mostr\u00f3 resueltamente a favor de la ampliaci\u00f3n de la Uni\u00f3n, declarando<\/a>: \u00abS\u00ed, Ucrania, la Rep\u00fablica de Moldavia y, con el tiempo, Georgia y, por supuesto, los seis pa\u00edses de los Balcanes Occidentales son nuestros, pertenecen a la parte libre y democr\u00e1tica de Europa. Su adhesi\u00f3n a la UE redunda en nuestro inter\u00e9s\u00bb. Tras recordar que la promesa de ampliaci\u00f3n ya se hab\u00eda hecho a los Balcanes Occidentales hace casi veinte a\u00f1os, a\u00f1adi\u00f3: \u00abEstas palabras deben traducirse finalmente en hechos\u00bb.<\/p>\n\n\n\n<p>As\u00ed pues, la ampliaci\u00f3n ya no es un sue\u00f1o. Ha llegado el momento de avanzar. Queda mucho trabajo por hacer. Ser\u00e1 dif\u00edcil y a veces doloroso. Para los futuros Estados miembros&#8230; y para la UE.<\/p>\n\n\n\n<p>Para ser cre\u00edbles, creo que tenemos que hablar de calendarios y obligaciones.&nbsp;<\/p>\n\n\n\n<p>Y tengo una propuesta que hacer. Mientras preparamos la pr\u00f3xima agenda estrat\u00e9gica de la Uni\u00f3n, tenemos que fijarnos un objetivo claro. Creo que tenemos que estar preparados \u2013por ambas partes\u2013 para ampliarnos a partir de 2030.&nbsp;<\/p>\n\n\n\n<p class=\"comment\">Este es el punto clave del discurso del Presidente del Consejo Europeo: la Uni\u00f3n debe estar preparada para ampliarse a partir de 2030. La definici\u00f3n de ese horizonte temporal cumple varios objetivos. En primer lugar, marca un rumbo claro para los pa\u00edses afectados, especialmente los Balcanes Occidentales, cuyos dirigentes se encuentran en la sala y han expresado p\u00fablicamente en numerosas ocasiones su decepci\u00f3n por la falta de avances concretos en las dos \u00faltimas d\u00e9cadas. En cuanto a Ucrania y Moldavia, esto tambi\u00e9n elimina cualquier ambig\u00fcedad sobre la duraci\u00f3n del pr\u00f3ximo proceso, cuando varios actores han insistido en los \u00faltimos meses en que en la pr\u00e1ctica podr\u00eda llevar a\u00f1os o incluso d\u00e9cadas. Por \u00faltimo, en un sentido m\u00e1s pragm\u00e1tico, este calendario establece un v\u00ednculo con varios de los grandes proyectos de la Uni\u00f3n a medio plazo, en particular las negociaciones sobre el pr\u00f3ximo presupuesto plurianual, que menciona inmediatamente despu\u00e9s. Por \u00faltimo, todo ello tiene como tel\u00f3n de fondo la preparaci\u00f3n de la Agenda Estrat\u00e9gica 2024-2029, que deber\u00e1 ser adoptada por el Consejo Europeo en junio de 2024 y en la que los Jefes de Estado y de Gobierno definir\u00e1n los grandes ejes estrat\u00e9gicos que guiar\u00e1n el trabajo de las instituciones europeas durante el pr\u00f3ximo ciclo institucional.<\/p>\n\n\n\n<p>Esto significa que el pr\u00f3ximo presupuesto a largo plazo de la Uni\u00f3n deber\u00e1 incluir estos objetivos comunes. Es ambicioso, pero necesario. Demuestra que vamos en serio. Crear\u00e1 impulso. Dar\u00e1 un impulso transformador a la reforma. Generar\u00e1 inter\u00e9s, inversi\u00f3n y comprensi\u00f3n. Y nos animar\u00e1 a todos a trabajar juntos. La oportunidad est\u00e1 abierta: debemos actuar en consecuencia.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Por eso los dirigentes de la Uni\u00f3n Europea debatir\u00e1n la ampliaci\u00f3n en las pr\u00f3ximas reuniones del Consejo Europeo. Nos pronunciaremos sobre la apertura de negociaciones con Ucrania y Moldavia.&nbsp;<\/p>\n\n\n\n<p>Tambi\u00e9n espero que se vuelvan a poner sobre la mesa las adhesiones de Bosnia-Herzegovina y Georgia.<\/p>\n\n\n\n<p>Queridos amigos de los Balcanes Occidentales,<\/p>\n\n\n\n<p>Hab\u00e9is expresado claramente vuestras aspiraciones, y yo deseo que teng\u00e1is \u00e9xito.<\/p>\n\n\n\n<p>\u00bfQu\u00e9 hace falta para conseguirlo?<\/p>\n\n\n\n<p class=\"comment\">En esta parte, el Presidente del Consejo Europeo repasa los llamados \u00abcriterios de Copenhague\u00bb que los pa\u00edses candidatos deben cumplir para ingresar en la Uni\u00f3n. Estos criterios fueron definidos por el Consejo Europeo de junio de 1993 con vistas a la ampliaci\u00f3n al Este, e incluyen un criterio pol\u00edtico (democracia, Estado de Derecho, derechos humanos y defensa de los derechos de las minor\u00edas), un criterio econ\u00f3mico (una econom\u00eda de mercado viable) y un criterio institucional (la capacidad de asumir y aplicar el acervo comunitario).<\/p>\n\n\n\n<p><em>Valores y Estado de Derecho&nbsp;<\/em><\/p>\n\n\n\n<p>Nuestra Uni\u00f3n se basa en los valores fundamentales de los derechos humanos y la dignidad humana, la democracia y la solidaridad. El Estado de Derecho garantiza que podamos vivir, trabajar, crear y comerciar lealmente en un amplio espacio de libertad y con pleno respeto de nuestra diversidad. En la Uni\u00f3n Europea, todos los ciudadanos y todas las empresas deben confiar en que ser\u00e1n tratados con equidad, vivan donde vivan o hagan negocios.<\/p>\n\n\n\n<p>Esto incluye el respeto de los derechos de las minor\u00edas.<\/p>\n\n\n\n<p class=\"comment\">El \u00e9nfasis en el Estado de Derecho tambi\u00e9n forma parte del considerable refuerzo de los mecanismos espec\u00edficos de la Uni\u00f3n Europea en los \u00faltimos a\u00f1os. Tras la reuni\u00f3n del Consejo Europeo de los d\u00edas 17 a 21 de julio de 2020 sobre el plan de recuperaci\u00f3n y el presupuesto plurianual, la Uni\u00f3n Europea adopt\u00f3 un Reglamento relativo a un sistema general de condicionalidad para la protecci\u00f3n del presupuesto de la Uni\u00f3n contra las violaciones del Estado de Derecho que afecten o puedan afectar gravemente a la buena gesti\u00f3n financiera del presupuesto. Este reglamento entr\u00f3 en vigor el 1 de enero de 2021 y desde entonces se ha activado contra Hungr\u00eda, con la decisi\u00f3n adoptada en diciembre de 2022 de suspender el pago de 6.300 millones de euros.<\/p>\n\n\n\n<p class=\"comment\">En cuanto a la cuesti\u00f3n de los derechos de las minor\u00edas, se trata de un tema especialmente sensible en los Balcanes Occidentales y en Ucrania, <a href=\"https:\/\/legrandcontinent.eu\/es\/2023\/07\/26\/postliberalismo-el-mundo-de-viktor-orban\/\">donde existe una minor\u00eda h\u00fangara<\/a>, cuesti\u00f3n que ha ganado recientemente en importancia y virulencia en los discursos del Primer Ministro h\u00fangaro.&nbsp;<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-medium\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2023\/08\/07a0cf9e-bf7a-4fd3-b4ad-3bb203056d25-scaled.jpg\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"2560\"\n        data-pswp-height=\"1707\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2023\/08\/07a0cf9e-bf7a-4fd3-b4ad-3bb203056d25-330x220.jpg\"\r\n                media=\"(max-width:  374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2023\/08\/07a0cf9e-bf7a-4fd3-b4ad-3bb203056d25-690x460.jpg\"\r\n                media=\"(max-width:  989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2023\/08\/07a0cf9e-bf7a-4fd3-b4ad-3bb203056d25-990x660.jpg\"\r\n                media=\"(max-width: 1319px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2023\/08\/07a0cf9e-bf7a-4fd3-b4ad-3bb203056d25-690x460.jpg\"\r\n                media=\"(max-width: 1599px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2023\/08\/07a0cf9e-bf7a-4fd3-b4ad-3bb203056d25-990x660.jpg\"\r\n                media=\"(min-width: 1600px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2023\/08\/07a0cf9e-bf7a-4fd3-b4ad-3bb203056d25-125x83.jpg\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">Intervenci\u00f3n de Charles Michel en el Foro Estrat\u00e9gico de Bled. \u00a9 European Council<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<p><em>Reformas&nbsp;<\/em><\/p>\n\n\n\n<p>La ampliaci\u00f3n es y seguir\u00e1 siendo un proceso basado en los m\u00e9ritos.<\/p>\n\n\n\n<p>La pertenencia a la Uni\u00f3n conlleva tanto responsabilidades como ventajas. Si queremos asumir las primeras y cosechar las segundas en un entorno altamente competitivo, tenemos que estar preparados.&nbsp;<\/p>\n\n\n\n<p>Esto significa garantizar que el poder judicial pueda funcionar con independencia y que pueda luchar contra la corrupci\u00f3n y la delincuencia organizada.<\/p>\n\n\n\n<p>Tambi\u00e9n debemos estar preparados en t\u00e9rminos econ\u00f3micos, en particular adoptando el acervo comunitario. Y necesitamos apoyo en pol\u00edtica exterior.&nbsp; Esto es ahora m\u00e1s importante que nunca.<\/p>\n\n\n\n<p><em>Tratar las cuestiones bilaterales\/regionales<\/em><\/p>\n\n\n\n<p>Resolver los conflictos bilaterales del pasado puede ser m\u00e1s doloroso que la reforma. Pero es necesario. Ustedes est\u00e1n siguiendo el mismo camino que los miembros fundadores de nuestra Uni\u00f3n. No puede haber cooperaci\u00f3n sin reconciliaci\u00f3n, y debo decirlo claramente: en la Uni\u00f3n no hay lugar para los conflictos del pasado.&nbsp;<\/p>\n\n\n\n<p>Su pueblo, especialmente los j\u00f3venes, quieren inspirarse en un futuro m\u00e1s brillante, m\u00e1s justo y m\u00e1s pr\u00f3spero. Unirse a nuestra Uni\u00f3n ser\u00eda un brillante ejemplo de \u00e9xito colectivo.&nbsp;<\/p>\n\n\n\n<p>Lo ideal ser\u00eda que todos se unieran, pero los futuros Estados miembros se encuentran en distintas fases de su camino hacia la UE. Por tanto, debemos asegurarnos de que los conflictos del pasado no se importen a la Uni\u00f3n y se utilicen para bloquear la adhesi\u00f3n de sus vecinos y futuros Estados miembros.&nbsp;<\/p>\n\n\n\n<p>Una soluci\u00f3n podr\u00eda ser a\u00f1adir una \u00abcl\u00e1usula de confianza\u00bb a los tratados de adhesi\u00f3n para garantizar que los pa\u00edses que acaban de ingresar en la Uni\u00f3n no puedan bloquear a los futuros Estados miembros.<\/p>\n\n\n\n<p>Estimados amigos,<\/p>\n\n\n\n<p>Para hacer frente a todos estos retos, la Uni\u00f3n Europea est\u00e1 intensificando el apoyo que os brinda, pero tenemos que hacer m\u00e1s para salvar la brecha del desarrollo.&nbsp;<\/p>\n\n\n\n<p>En primer lugar, tenemos que integrar gradualmente las pol\u00edticas de la Uni\u00f3n, para que sus beneficios se dejen sentir m\u00e1s r\u00e1pidamente, incluso antes de que se haya producido la adhesi\u00f3n. Propuse esta idea el a\u00f1o pasado y el Consejo Europeo la apoy\u00f3. El paquete de ampliaci\u00f3n de la Comisi\u00f3n, previsto para octubre, brindar\u00e1 la oportunidad de definir los detalles concretos de esta integraci\u00f3n gradual.&nbsp;<\/p>\n\n\n\n<p>Esto podr\u00eda tener lugar en varios \u00e1mbitos. El mercado \u00fanico, por ejemplo. Tenemos marcos ambiciosos que animan a los futuros Estados miembros a alinearse con el acervo comunitario. Pueden aprovechar las opciones existentes, como las comunidades de la energ\u00eda y el transporte.&nbsp;<\/p>\n\n\n\n<p>Propongo que utilicemos estos marcos para integrar gradualmente a los futuros Estados miembros en \u00e1mbitos pol\u00edticos espec\u00edficos de la UE, una vez cumplidas las condiciones. Por ejemplo, un pa\u00eds podr\u00eda participar en la formaci\u00f3n pertinente del Consejo una vez que haya concluido las negociaciones en el cap\u00edtulo pol\u00edtico de que se trate.<\/p>\n\n\n\n<p>Con el mismo esp\u00edritu, hemos establecido el principio de cumbres anuales entre la Uni\u00f3n y los Balcanes Occidentales. Convocar\u00e9 nuestra pr\u00f3xima Cumbre UE-Balcanes Occidentales en diciembre, justo despu\u00e9s de la reuni\u00f3n del Consejo Europeo.<\/p>\n\n\n\n<p>Otro \u00e1mbito de integraci\u00f3n progresiva podr\u00eda ser la seguridad y la defensa. Podr\u00edamos invitar a los futuros Estados miembros interesados a participar m\u00e1s activamente en determinadas pol\u00edticas o herramientas, como las misiones de la Pol\u00edtica Exterior y de Seguridad Com\u00fan (PESC), nuestro Fondo de Defensa o el Fondo Europeo para la Paz.<\/p>\n\n\n\n<p class=\"comment\">La noci\u00f3n de integraci\u00f3n progresiva a la que se refiere aqu\u00ed Charles Michel figura en las conclusiones del Consejo Europeo de los d\u00edas 23 y 24 de junio de 2022, que invit\u00f3 a la Comisi\u00f3n a presentar propuestas en este sentido en el marco del informe que presentar\u00e1 sobre la ampliaci\u00f3n el pr\u00f3ximo mes de octubre.<\/p>\n\n\n\n<p>La Uni\u00f3n Europea tambi\u00e9n debe prepararse para la ampliaci\u00f3n. Estoy totalmente de acuerdo con el Presidente Macron: ser\u00eda un error fundamental no hacer reformas por nuestra parte antes de la pr\u00f3xima ampliaci\u00f3n.&nbsp;<\/p>\n\n\n\n<p class=\"comment\">Emmanuel Macron reiter\u00f3 este punto esta ma\u00f1ana en su discurso ante la Conferencia de Embajadores.<\/p>\n\n\n\n<p>Seamos sinceros: a veces hemos utilizado la falta de progreso de los futuros Estados miembros para evitar cuestionar nuestro propio grado de preparaci\u00f3n. Ahora tenemos que analizar seriamente la capacidad de la Uni\u00f3n Europea para absorber nuevos miembros. A veces se considera err\u00f3neamente que esto es un obst\u00e1culo oculto a la adhesi\u00f3n. No lo es. Es l\u00f3gico que los nuevos Estados miembros se incorporen a una Uni\u00f3n eficiente.&nbsp;<\/p>\n\n\n\n<p class=\"comment\">La noci\u00f3n de capacidad de absorci\u00f3n se a\u00f1adi\u00f3 a los criterios de Copenhague en diciembre de 2006, tras la gran ampliaci\u00f3n al Este de 2004. Se refiere a la capacidad de la Uni\u00f3n para acoger a nuevos miembros en un momento dado, sin poner en peligro los objetivos pol\u00edticos establecidos en los Tratados.<\/p>\n\n\n\n<p>Tambi\u00e9n tiene sentido para los Estados miembros actuales \u2013si crea nuevas oportunidades\u2013.<\/p>\n\n\n\n<p>Estimados amigos,<\/p>\n\n\n\n<p>La integraci\u00f3n de nuevos miembros en nuestra Uni\u00f3n no ser\u00e1 f\u00e1cil. Afectar\u00e1 a nuestras pol\u00edticas, programas y presupuestos.<\/p>\n\n\n\n<p>Exigir\u00e1 reformas y coraje pol\u00edtico.&nbsp;<\/p>\n\n\n\n<p>El territorio y la demograf\u00eda de la UE crecer\u00e1n. Sin embargo, su prosperidad relativa no ser\u00e1 inmediata: se necesitar\u00e1n fondos sustanciales para ayudar a los pa\u00edses a ponerse al d\u00eda. Debemos garantizar que el presupuesto de la Uni\u00f3n aporte valor a\u00f1adido europeo para todos.<\/p>\n\n\n\n<p>El PIB de los futuros Estados miembros equivale aproximadamente al 50-70% del de la econom\u00eda m\u00e1s peque\u00f1a de la Uni\u00f3n Europea. Esto significa que ser\u00e1n beneficiarios netos. Por otra parte, varios beneficiarios netos actuales se convertir\u00e1n en contribuyentes netos.&nbsp;<\/p>\n\n\n\n<p>Por tanto, tenemos que determinar c\u00f3mo podemos gestionar esta compleja transici\u00f3n.&nbsp;<\/p>\n\n\n\n<p>El proceso de toma de decisiones de la Uni\u00f3n ha dado un gran salto adelante en los \u00faltimos a\u00f1os. Pero podemos hacer m\u00e1s para acelerarlo a\u00fan m\u00e1s. M\u00e1s miembros significar\u00e1 mayor diversidad.&nbsp;<\/p>\n\n\n\n<p>Tendremos que adaptar nuestro marco institucional y nuestros procedimientos para que una Uni\u00f3n ampliada pueda tomar decisiones eficaces y oportunas. En cuanto a la dif\u00edcil cuesti\u00f3n de la unanimidad, creo que suprimirla ser\u00eda como tirar el grano con la paja.&nbsp;<\/p>\n\n\n\n<p>De hecho, la unidad es la base de la fuerza de la Uni\u00f3n Europea. Es la mejor manera de garantizar que las decisiones se apliquen de manera uniforme.<\/p>\n\n\n\n<p>Hay varias maneras de unirse.&nbsp;<\/p>\n\n\n\n<p>Cuando decidimos activar el Fondo de Apoyo a la Paz para financiar la entrega de armas a Ucrania, los Estados miembros neutrales recurrieron a la abstenci\u00f3n constructiva para no impedir la unanimidad.&nbsp;<\/p>\n\n\n\n<p>Tambi\u00e9n hay varias formas de adaptar el voto por mayor\u00eda cualificada, tanto en t\u00e9rminos num\u00e9ricos como de aplicaci\u00f3n.&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>Ser\u00e1 un problema dif\u00edcil de resolver. Pero hoy no hay forma de evitar este debate.<\/p>\n\n\n\n<p class=\"comment\">La cuesti\u00f3n del mantenimiento o no del voto por unanimidad en el seno de la Uni\u00f3n es actualmente objeto de un nuevo examen, en particular tras la propuesta formulada por el Canciller Scholz en su discurso de Praga de \u00abpasar progresivamente al voto por mayor\u00eda en pol\u00edtica exterior com\u00fan, pero tambi\u00e9n en otros \u00e1mbitos, como la pol\u00edtica fiscal\u00bb. Como Presidente del Consejo Europeo, Charles Michel ha defendido en repetidas ocasiones el principio del voto por unanimidad, se\u00f1alando, como hace aqu\u00ed, que este principio no ha impedido a la Uni\u00f3n tomar medidas en\u00e9rgicas en los \u00faltimos a\u00f1os, en particular en respuesta a la crisis del COVID (plan de recuperaci\u00f3n, compras conjuntas de vacunas) o a la guerra en Ucrania (suministro de armas). Al mencionar la opci\u00f3n de la abstenci\u00f3n constructiva \u2013utilizada, por ejemplo, por Hungr\u00eda en la cuesti\u00f3n del suministro de armas a Ucrania desde el inicio de la guerra\u2013 y las modalidades precisas de votaci\u00f3n por mayor\u00eda cualificada, esboza varias v\u00edas que podr\u00edan ayudar a construir un consenso entre los Jefes de Estado y de Gobierno.<\/p>\n\n\n\n<p>Queridos amigos,<\/p>\n\n\n\n<p>Perm\u00edtanme compartir con ustedes una convicci\u00f3n personal.&nbsp;<\/p>\n\n\n\n<p>El coraz\u00f3n de la ampliaci\u00f3n no es una cuesti\u00f3n de procesos, evaluaciones, negociaciones y tratados.<\/p>\n\n\n\n<p>El coraz\u00f3n de la ampliaci\u00f3n son las personas. Se trata del futuro de nuestros hijos y del destino de Europa. As\u00ed que tenemos que asegurarnos de que sabemos c\u00f3mo ganarnos sus corazones.&nbsp;<\/p>\n\n\n\n<p>Este es quiz\u00e1 nuestro mayor reto.&nbsp;<\/p>\n\n\n\n<p>Se trata de explicar la Uni\u00f3n Europea. Y destacar sus ventajas. Tambi\u00e9n se trata de superar el lenguaje del pasado para centrarnos en el futuro.&nbsp;<\/p>\n\n\n\n<p>Es una elecci\u00f3n para la sociedad.&nbsp;<\/p>\n\n\n\n<p>Con verdadera voluntad pol\u00edtica, podemos garantizar que la Uni\u00f3n y los futuros Estados miembros est\u00e9n preparados.&nbsp;<\/p>\n\n\n\n<p>Ahora es el momento de ser audaces. Ahora es el momento de construir juntos nuestro gran futuro europeo.<\/p>\n\n\n\n<p>Gracias por su atenci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta ser\u00e1 la cuesti\u00f3n pol\u00edtica clave hasta las elecciones europeas del pr\u00f3ximo mes de junio -y probablemente m\u00e1s all\u00e1-. \u00bfQu\u00e9 forma adoptar\u00e1 la pr\u00f3xima ampliaci\u00f3n de la Uni\u00f3n Europea? Es el tema crucial que el Presidente del Consejo Europeo, Charles Michel, decidi\u00f3 abordar en un discurso esencial en el Foro Estrat\u00e9gico de Bled. Lo traducimos y comentamos l\u00ednea por l\u00ednea.<\/p>\n","protected":false},"author":1366,"featured_media":21930,"comment_status":"closed","ping_status":"","sticky":false,"template":"templates\/post-speeches.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":18,"footnotes":""},"categories":[6],"tags":[],"staff":[7],"editorial_format":[1474],"serie":[],"audience":[],"geo":[177],"class_list":["post-21929","post","type-post","status-publish","format-standard","hentry","category-politica","staff-el-grand-continent","editorial_format-archivos-y-discursos","geo-europa"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":21930,"excerpt":"Esta ser\u00e1 la cuesti\u00f3n pol\u00edtica clave hasta las elecciones europeas del pr\u00f3ximo mes de junio -y probablemente m\u00e1s all\u00e1-. \u00bfQu\u00e9 forma adoptar\u00e1 la pr\u00f3xima ampliaci\u00f3n de la Uni\u00f3n Europea? Es el tema crucial que el Presidente del Consejo Europeo, Charles Michel, decidi\u00f3 abordar en un discurso esencial en el Foro Estrat\u00e9gico de Bled. Lo traducimos y comentamos l\u00ednea por l\u00ednea.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00abAmpliarse a partir de 2030\u00bb: el discurso de Charles Michel en Bled - El Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/es\/2023\/08\/28\/ampliarse-a-partir-de-2030-el-discurso-de-charles-michel-en-bled\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00abAmpliarse a partir de 2030\u00bb: el discurso de Charles Michel en Bled - El Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Esta ser\u00e1 la cuesti\u00f3n pol\u00edtica clave hasta las elecciones europeas del pr\u00f3ximo mes de junio -y probablemente m\u00e1s all\u00e1-. \u00bfQu\u00e9 forma adoptar\u00e1 la pr\u00f3xima ampliaci\u00f3n de la Uni\u00f3n Europea? Es el tema crucial que el Presidente del Consejo Europeo, Charles Michel, decidi\u00f3 abordar en un discurso esencial en el Foro Estrat\u00e9gico de Bled. Lo traducimos y comentamos l\u00ednea por l\u00ednea.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/es\/2023\/08\/28\/ampliarse-a-partir-de-2030-el-discurso-de-charles-michel-en-bled\/\" \/>\n<meta property=\"og:site_name\" content=\"El Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-28T15:05:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-28T15:14:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/08\/gc-elmichelbled-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"florent\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/08\/gc-elmichelbled-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"florent\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"18 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/08\/28\/ampliarse-a-partir-de-2030-el-discurso-de-charles-michel-en-bled\/\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/2023\/08\/28\/ampliarse-a-partir-de-2030-el-discurso-de-charles-michel-en-bled\/\",\"name\":\"\u00abAmpliarse a partir de 2030\u00bb: el discurso de Charles Michel en Bled - El Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/08\/28\/ampliarse-a-partir-de-2030-el-discurso-de-charles-michel-en-bled\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/08\/28\/ampliarse-a-partir-de-2030-el-discurso-de-charles-michel-en-bled\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/08\/3796f503-91a3-4cbf-b3f0-24babaf3e8ab-scaled-1.jpg\",\"datePublished\":\"2023-08-28T15:05:43+00:00\",\"dateModified\":\"2023-08-28T15:14:19+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/08\/28\/ampliarse-a-partir-de-2030-el-discurso-de-charles-michel-en-bled\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/es\/2023\/08\/28\/ampliarse-a-partir-de-2030-el-discurso-de-charles-michel-en-bled\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/08\/28\/ampliarse-a-partir-de-2030-el-discurso-de-charles-michel-en-bled\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/08\/3796f503-91a3-4cbf-b3f0-24babaf3e8ab-scaled-1.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/08\/3796f503-91a3-4cbf-b3f0-24babaf3e8ab-scaled-1.jpg\",\"width\":2560,\"height\":1708,\"caption\":\"Charles Michel en el Foro Estrat\u00e9gico de Bled. \u00a9 European Council\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/08\/28\/ampliarse-a-partir-de-2030-el-discurso-de-charles-michel-en-bled\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/legrandcontinent.eu\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00abAmpliarse a partir de 2030\u00bb: el discurso de Charles Michel en Bled\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/\",\"name\":\"El Grand Continent\",\"description\":\"La escala pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\",\"name\":\"florent\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"caption\":\"florent\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00abAmpliarse a partir de 2030\u00bb: el discurso de Charles Michel en Bled - El Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/es\/2023\/08\/28\/ampliarse-a-partir-de-2030-el-discurso-de-charles-michel-en-bled\/","og_locale":"es_ES","og_type":"article","og_title":"\u00abAmpliarse a partir de 2030\u00bb: el discurso de Charles Michel en Bled - El Grand Continent","og_description":"Esta ser\u00e1 la cuesti\u00f3n pol\u00edtica clave hasta las elecciones europeas del pr\u00f3ximo mes de junio -y probablemente m\u00e1s all\u00e1-. \u00bfQu\u00e9 forma adoptar\u00e1 la pr\u00f3xima ampliaci\u00f3n de la Uni\u00f3n Europea? Es el tema crucial que el Presidente del Consejo Europeo, Charles Michel, decidi\u00f3 abordar en un discurso esencial en el Foro Estrat\u00e9gico de Bled. Lo traducimos y comentamos l\u00ednea por l\u00ednea.","og_url":"https:\/\/legrandcontinent.eu\/es\/2023\/08\/28\/ampliarse-a-partir-de-2030-el-discurso-de-charles-michel-en-bled\/","og_site_name":"El Grand Continent","article_published_time":"2023-08-28T15:05:43+00:00","article_modified_time":"2023-08-28T15:14:19+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/08\/gc-elmichelbled-scaled.jpg","type":"image\/jpeg"}],"author":"florent","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/08\/gc-elmichelbled-scaled.jpg","twitter_misc":{"Escrito por":"florent","Tiempo de lectura":"18 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/es\/2023\/08\/28\/ampliarse-a-partir-de-2030-el-discurso-de-charles-michel-en-bled\/","url":"https:\/\/legrandcontinent.eu\/es\/2023\/08\/28\/ampliarse-a-partir-de-2030-el-discurso-de-charles-michel-en-bled\/","name":"\u00abAmpliarse a partir de 2030\u00bb: el discurso de Charles Michel en Bled - El Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/es\/2023\/08\/28\/ampliarse-a-partir-de-2030-el-discurso-de-charles-michel-en-bled\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/es\/2023\/08\/28\/ampliarse-a-partir-de-2030-el-discurso-de-charles-michel-en-bled\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/08\/3796f503-91a3-4cbf-b3f0-24babaf3e8ab-scaled-1.jpg","datePublished":"2023-08-28T15:05:43+00:00","dateModified":"2023-08-28T15:14:19+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/es\/2023\/08\/28\/ampliarse-a-partir-de-2030-el-discurso-de-charles-michel-en-bled\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/es\/2023\/08\/28\/ampliarse-a-partir-de-2030-el-discurso-de-charles-michel-en-bled\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/2023\/08\/28\/ampliarse-a-partir-de-2030-el-discurso-de-charles-michel-en-bled\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/08\/3796f503-91a3-4cbf-b3f0-24babaf3e8ab-scaled-1.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/08\/3796f503-91a3-4cbf-b3f0-24babaf3e8ab-scaled-1.jpg","width":2560,"height":1708,"caption":"Charles Michel en el Foro Estrat\u00e9gico de Bled. \u00a9 European Council"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/es\/2023\/08\/28\/ampliarse-a-partir-de-2030-el-discurso-de-charles-michel-en-bled\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legrandcontinent.eu\/es\/"},{"@type":"ListItem","position":2,"name":"\u00abAmpliarse a partir de 2030\u00bb: el discurso de Charles Michel en Bled"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/es\/#website","url":"https:\/\/legrandcontinent.eu\/es\/","name":"El Grand Continent","description":"La escala pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c","name":"florent","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","caption":"florent"}}]}},"lgc_categories":[{"id":6,"name":"Pol\u00edtica","slug":"politica"}],"lgc_author":{"id":7,"name":"El Grand Continent","slug":"el-grand-continent","description":null,"first_name":null,"last_name":null,"picture":null},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/08\/3796f503-91a3-4cbf-b3f0-24babaf3e8ab-scaled-1.jpg","width":2560,"height":1708,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/08\/3796f503-91a3-4cbf-b3f0-24babaf3e8ab-scaled-1.jpg","width":2560,"height":1708,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/21929","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/users\/1366"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/comments?post=21929"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/21929\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media\/21930"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media?parent=21929"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/categories?post=21929"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/tags?post=21929"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/staff?post=21929"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/editorial_format?post=21929"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/serie?post=21929"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/audience?post=21929"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/geo?post=21929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}