{"id":2162,"date":"2021-10-15T17:25:31","date_gmt":"2021-10-15T16:25:31","guid":{"rendered":"https:\/\/legrandcontinent.eu\/es\/?p=2162"},"modified":"2022-05-31T15:59:18","modified_gmt":"2022-05-31T14:59:18","slug":"el-negro-homenaje-a-samuel-paty","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/es\/2021\/10\/15\/el-negro-homenaje-a-samuel-paty\/","title":{"rendered":"El Negro. Homenaje a Samuel Paty"},"content":{"rendered":"\n<p class=\"intro\"><strong>Homenaje a un ex alumno de historia<\/strong><\/p>\n\n\n\n<p class=\"intro\"><\/p>\n\n\n\n<p class=\"has-text-align-right intro\"><em>El color negro contiene lo imposible de vivir. Su campo mental es la sede de todos los imprevistos, de todos los paroxismos. Su prestigio escolta a los poemas y prepara a los hombres de acci\u00f3n<\/em>&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-2162' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/es\/2021\/10\/15\/el-negro-homenaje-a-samuel-paty\/#easy-footnote-bottom-1-2162' title='Ren\u00e9 Char, \u00ab Fragments n\u00ba 229 \u00bb, en &lt;em&gt;Feuillets d\u2019Hypnos&lt;\/em&gt;, 1946, p. 230. Este poemario fue escrito mientras Ren\u00e9 Char estaba comprometido con la Resistencia bajo el nombre de Capitaine Alexandre.'><sup>1<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<p class=\"intro\"><\/p>\n\n\n\n<p class=\"intro\">El 16 de octubre de 2020, Samuel Paty, profesor de historia y geograf\u00eda de 47 a\u00f1os, fue brutalmente asesinado por haber ense\u00f1ado a sus alumnos caricaturas del profeta Mahoma&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-2162' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/es\/2021\/10\/15\/el-negro-homenaje-a-samuel-paty\/#easy-footnote-bottom-2-2162' title='Seg\u00fan la terminolog\u00eda utilizada en los programas escolares y, presumiblemente, por Samuel Paty.'><sup>2<\/sup><\/a><\/span><\/span> como parte de una clase sobre la libertad de expresi\u00f3n. Samuel Paty era originario de Moulins, donde vivir\u00eda hasta que en 1991 se graduara en el instituto y se mudara a Lyon para realizar sus estudios superiores. Los diferentes lugares y etapas de su formaci\u00f3n \u2013clase preparatoria al concurso de la \u00c9cole normale sup\u00e9rieure y estudios universitarios en Lyon 3 y Lyon 2, Instituto Universitario de Formaci\u00f3n de Profesores (IUFM)\u2013 le condujeron a la profesi\u00f3n de profesor, tras haber reunido las condiciones de admisibilidad de la Agregaci\u00f3n de historia y ser admitido en el CAPES en historia-geograf\u00eda. Tras una primera experiencia durante su a\u00f1o de pr\u00e1cticas en el instituto Les Batti\u00e8res del distrito 5 de Lyon, en el marco de su formaci\u00f3n en el IUFM, asume la profesi\u00f3n con orgullo y entusiasmo. Al ser trasladado a la academia de Cr\u00e9teil y luego a la de Versalles, su carrera transcurre en la regi\u00f3n de Par\u00eds, en escuelas de ense\u00f1anza media, donde se siente realizado entre adolescentes en ciernes, hasta que sobreviene la tragedia en v\u00edsperas de las vacaciones de oto\u00f1o de 2020. Samuel Paty estaba divorciado y dejar\u00eda un hijo de cinco a\u00f1os.<\/p>\n\n\n\n<p class=\"intro\">Esta tragedia fundamenta nuestro enfoque. Nos result\u00f3 necesario honrar la memoria de este profesor que pag\u00f3 con su vida el haber cumplido su misi\u00f3n: promover entre los alumnos el pensamiento cr\u00edtico y abordar sin rodeos los desaf\u00edos propios de la libertad de expresi\u00f3n, particularmente los de la libertad de prensa. En un plano m\u00e1s personal, constituye tambi\u00e9n una forma de celebrar a esa persona que conoc\u00ed y apreci\u00e9 [Christophe Capuano], y con la que forj\u00e9 una amistad durante mis a\u00f1os de formaci\u00f3n en Lyon&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-2162' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/es\/2021\/10\/15\/el-negro-homenaje-a-samuel-paty\/#easy-footnote-bottom-3-2162' title='Durante el homenaje nacional que se le rindi\u00f3 en el patio de la Sorbona el 21 de octubre de 2020, quise honrar la memoria de Samuel eligiendo la lectura de \u00ab La lettre aux instituteurs et institutrices \u00bb de Jean Jaur\u00e8s (La D\u00e9p\u00eache de Toulouse, 1888).'><sup>3<\/sup><\/a><\/span><\/span>. Por mi parte [Olivier Faure], aunque probablemente me haya cruzado con Samuel Paty sin verlo, me pareci\u00f3 que, al haber sido nombrado profesor de la Universidad de Lyon 3 el mismo a\u00f1o de su maestr\u00eda (1994), no pod\u00eda permanecer inerte ante el atroz asesinato de un ex alumno de esa universidad.<\/p>\n\n\n\n<p class=\"intro\">Pero, \u00bfc\u00f3mo rendir homenaje a Samuel sin traicionarlo? Muy poco despu\u00e9s de la tragedia, con la ayuda de Christine Chadier, la bibliotecaria del <em>Laboratoire de recherche historique Rh\u00f4ne-Alpes<\/em> (LARHRA), y con la aprobaci\u00f3n de su director Bernard Hours, tuvimos acceso a la tesis de maestr\u00eda de Samuel Paty, defendida en 1995 y conservada en los archivos del laboratorio. Luego de tres lecturas cruzadas, nos pareci\u00f3 que este texto dedicado a la simbolog\u00eda del negro pod\u00eda seguir ense\u00f1\u00e1ndonos las relaciones que nuestra sociedad mantiene con los colores. Adem\u00e1s, publicarlo pod\u00eda constituir una forma de dar voz a Samuel, de comprender el joven intelectual que hab\u00eda sido. Con este trabajo final de maestr\u00eda se puede retratar el desarrollo de su pensamiento como estudiante y conocer al historiador en formaci\u00f3n. Esta publicaci\u00f3n ha sido posible gracias a la aprobaci\u00f3n de sus padres y de sus hermanas, a quienes agradecemos muy sinceramente su confianza; gracias tambi\u00e9n a los miembros del equipo de las <em>Presses universitaires de Lyon<\/em> que se sumaron inmediatamente al proyecto y nos acompa\u00f1aron y apoyaron en \u00e9l. Les estamos muy agradecidos.<\/p>\n\n\n\n<p class=\"intro\">Al comenzar este trabajo de investigaci\u00f3n, Samuel Paty tiene 21 a\u00f1os. Es un estudiante brillante que transcurri\u00f3 por los pasillos del Lyc\u00e9e \u00c9douard Herriot, donde floreci\u00f3 intelectualmente gracias a la formaci\u00f3n multidisciplinar de las clases preparatorias literarias antes de ingresar en la Universidad para obtener la licenciatura en Historia. Curioso por todo, desarrolla durante sus primeros a\u00f1os de estudio una s\u00f3lida cultura general, en historia, por supuesto, pero tambi\u00e9n en filosof\u00eda, literatura, semiolog\u00eda e historia del arte. Aprecia, tambi\u00e9n, las diferentes formas de escritura y figuras ret\u00f3ricas, lo que le conduce a escribir poemas sobre el sentido de la vida o la belleza del mundo. Y se compromete con pasi\u00f3n y rigor en sus estudios. Samuel Paty a\u00fan no sab\u00eda si se convertir\u00eda en profesor-investigador universitario o en profesor de historia y geograf\u00eda en la ense\u00f1anza secundaria, pero le entusiasmaba la idea de sumergirse en su primera experiencia en la investigaci\u00f3n y sus m\u00e9todos espec\u00edficos. De naturaleza m\u00e1s bien reservada, pero con un car\u00e1cter asertivo, desea tratar un tema original y cercano a su coraz\u00f3n, con el que pueda expresar su gusto por la historia de los colores, las novelas realistas del siglo XIX, la m\u00fasica contempor\u00e1nea y la pintura simbolista. Es al negro al que dedica su apetito intelectual, en primer lugar por considerar su polisemia heur\u00edstica, pero tambi\u00e9n por su atracci\u00f3n por los textos oscuros, que le parec\u00edan especialmente \u00ab vivos \u00bb, y por su fascinaci\u00f3n por la dimensi\u00f3n m\u00edstica u on\u00edrica a la que remite este color, una especie de clave para los interrogantes existenciales del joven. Sin embargo, no nos confundamos: la elecci\u00f3n de este tema no corresponde en absoluto a un temperamento saturniano o depresivo. Ciertos pasajes \u2013como los dedicados a la obra de Odilon Redon\u2013 no deben leerse de forma premonitoria o anacr\u00f3nica, aunque podamos sentir cierto malestar por las tr\u00e1gicas circunstancias de la muerte del autor. Por el contrario, la curiosidad y el gusto por lo desafiante son los que gu\u00edan a un Samuel Paty juguet\u00f3n y travieso por naturaleza, decidido a explotar toda la gama de sus talentos y su polifac\u00e9tica cultura. Decide entonces considerar el negro a trav\u00e9s del prisma de la simbolog\u00eda que tanto le atrae por los diferentes niveles de interpretaci\u00f3n que ofrece, y estudiar la evoluci\u00f3n de los usos de ese color en la \u00e9poca contempor\u00e1nea, a trav\u00e9s del cruce de una historia social con una historia cultural y de representaciones.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>El negro y el sabio (p. 77)<\/strong><\/h2>\n\n\n\n<p>En realidad, las personas de negro suelen tener un v\u00ednculo con la instrucci\u00f3n. Esto es evidente para los uniformes negros de m\u00e9dicos, abogados y acad\u00e9micos, como se ha dicho. Tambi\u00e9n hay que pensar en los que quieren saber: los escolares cuyas batas negras son garant\u00eda de seriedad. El \u00e1rbitro de f\u00fatbol es otra figura social que sabe. El negro es tambi\u00e9n el color de las personas que no trabajan con sus manos, pero que han recibido una educaci\u00f3n: los burgueses. El negro del sabio es un absoluto. El sabio debe olvidar el mundo de la superficialidad, del dorado descrito por Balzac, porque saber es ir m\u00e1s all\u00e1 de las apariencias, es no conformarse con lo evidente. La toma de h\u00e1bito (vestido o bata negra) separa los lugares del esp\u00edritu del mundo de las frivolidades. Por las razones que ya hemos explicado, especialmente la condici\u00f3n de no-color del negro, el color m\u00e1s oscuro es apropiado para traducir este desprendimiento de lo inesencial, es decir, de lo colorido. El negro no acerca aqu\u00ed a lo divino, sino a los secretos de la naturaleza, la justicia o cualquier otra cosa. El negro lo hace a uno profundo, sabio; los otros colores (excepto el blanco) son atrevidos. Al igual que para el sacerdote o el monje, tanto para un universitario como para un escolar, vestirse de negro es morir simb\u00f3licamente para el mundo de las apariencias y renacer como un curioso en b\u00fasqueda, no de lo divino, sino de lo verdadero. Saber requiere el sacrificio de una realidad agradable pero falsa.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>La lucha del blanco y el negro (p. 93)<\/strong><\/h2>\n\n\n\n<p>La lucha entre el bien y el mal, entre el blanco y el negro, tambi\u00e9n est\u00e1 omnipresente en la literatura fant\u00e1stica del siglo XIX. La novela g\u00f3tica, plagada de espectros, pactos con el diablo, h\u00e9roes malvados o puros, fue muy popular durante todo ese siglo.&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-4-2162' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/es\/2021\/10\/15\/el-negro-homenaje-a-samuel-paty\/#easy-footnote-bottom-4-2162' title='Liliane Abensour &amp;amp; Fran\u00e7oise Charras (\u00e9d.), &lt;em&gt;Romantisme noir&lt;\/em&gt;, &lt;em&gt;op. cit&lt;\/em&gt;.'><sup>4<\/sup><\/a><\/span><\/span> Los grandes mitos de <em>Frankenstein<\/em> (1818) de Mary Shelley y <em>Dr\u00e1cula<\/em> (1897) de Bram Stoker son apenas los abanderados de un inmenso r\u00edo negro de la literatura europea. El diab\u00f3lico negro se combina con el rojo, el otro color del mal. En la iconograf\u00eda, al diablo se le representa en negro o en rojo. Este \u00e9xito de la lucha metaf\u00edsica entre la oscuridad y la luz es, sin duda, una reacci\u00f3n a una dominante ideolog\u00eda racionalista de la que el cientificismo es la caricatura. Una criatura tenebrosa como Dr\u00e1cula es un oasis de misterio y magia en un mundo que desea excluir lo desconocido con la luz de la ciencia. Tal vez exista una necesidad irreductible de magia, y esa necesidad se expresar\u00eda a\u00fan m\u00e1s en la literatura en tanto en cuanto se aleja el misterio de la vida cotidiana. Ser\u00eda interesante determinar si la lucha metaf\u00edsica entre el bien y el mal no tiene mayor \u00e9xito en un periodo de crisis socioecon\u00f3mica. Lo irracional y la metaf\u00edsica ser\u00edan un refugio contra la hostilidad de la vida cotidiana. El pensamiento maniqueo tambi\u00e9n tiene un efecto tranquilizador. No hay nada m\u00e1s claro que una batalla entre el blanco y el negro. Esta claridad es la que agrada en un momento en que las referencias tradicionales dan paso a las dudas. Bajo estas condiciones, el pensamiento maniqueo puede invadir la realidad cotidiana mediante la b\u00fasqueda de chivos expiatorios, figuras negras que quieren desestabilizar el orden social. A priori, parece delicado establecer la correspondencia entre los periodos de crisis y el gusto por la oscuridad llena de espectros y vampiros. Cualquier interpretaci\u00f3n en ese \u00e1mbito es cuestionable, ya que siempre se tiende a ver lo que se quiere ver cuando se pasa de la idea a los documentos y no de los documentos a la idea.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>El negro de lo absoluto (p. 96)<\/strong><\/h2>\n\n\n\n<p>Es imposible trazar un retrato perfecto de la simbolog\u00eda de un color. Siempre hay que producir una lectura entre otras de tal o cual color. El negro contiene una idea de lo absoluto, que puede encontrarse en el negro de la humildad cristiana, en las vestimentas del sabio, en el uso pol\u00edtico extremista del color negro o en el lirismo negro del Romanticismo. Tambi\u00e9n remite a las nociones de autoridad y respetabilidad. El negro del absoluto y el negro honorable tienen una connotaci\u00f3n positiva, pero tambi\u00e9n hay un negro que da miedo: el negro de la tristeza, la muerte y el mal. Hemos elegido centrarnos en el negro de lo absoluto y en el negro de la autoridad, porque revelan c\u00f3mo la realidad est\u00e1 vinculada a una simbolog\u00eda. Y es dif\u00edcil eludir los atributos m\u00e1s evidentes del negro: la tristeza, la muerte y el mal. Cada gran tema se subdivide en subtemas. Habitualmente, los subtemas evolucionan, se diversifican, mientras que el tema general no cambia o lo hace muy lentamente. Esta observaci\u00f3n es especialmente cierta en el caso del negro de lo absoluto, cuyas expresiones var\u00edan con el tiempo. El tercer conjunto denominado&nbsp; \u00ab mal negro \u00bb no es en s\u00ed mismo un tema simb\u00f3lico: en realidad re\u00fane tres temas generales que hemos agrupado por sus connotaciones negativas y porque a menudo est\u00e1n relacionados. Por ejemplo, el mal trae consigo la muerte, que siembra la tristeza. Esta lectura simb\u00f3lica nos ha llevado a no tratar otros posibles temas por separado. Para completar lo ya dicho, podemos agregar que este poder del negro est\u00e1 ciertamente ligado a la historia del pensamiento occidental. Desde Plat\u00f3n, al mundo exterior se le percibe como una apariencia que nos oculta la esencia de las cosas. Los colores que pertenecen a la evidencia sensible nos distraen del ser. Sin embargo, el negro no es realmente un color porque se dice que es incoloro (el blanco tiene la misma condici\u00f3n de incoloro, pero niega menos los colores porque remite a la luz del d\u00eda y, entonces, a los colores, y porque cient\u00edficamente los re\u00fane). Por lo tanto, el negro no oculta la esencia: la revela. Este tema simb\u00f3lico se encuentra en la moda de la fotograf\u00eda en blanco y negro, que abordaremos luego. Esa condici\u00f3n particular del negro tambi\u00e9n lo hace el m\u00e1s apto a apartar socialmente. Al ser extra\u00f1o, este color es el ideal para aislar a un grupo de la sociedad.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Las relaciones simb\u00f3licas del negro con otros colores (p. 97)<\/strong><\/h2>\n\n\n\n<p>Las relaciones simb\u00f3licas del negro con otros colores son interesantes. El negro est\u00e1 relacionado con el blanco y el rojo. El rojo, color de la sangre y la vida, se opone al color de la muerte, el negro. El cuadro abstracto de Franz Marc <em>Formas de lucha<\/em> (1914)59 (v\u00e9ase el anexo VI), que representa la lucha de dos entidades, una roja y otra negra, puede interpretarse como una figuraci\u00f3n de la eterna guerra de la vida y la muerte. El negro y el rojo se reconcilian en el reino de Sat\u00e1n, con el arc\u00e1ngel a veces negro, a veces rojo, que gobierna un mundo de fuego y oscuridad. El negro maligno se opone al blanco ben\u00e9fico, y el negro, color de la desesperanza, se opone al blanco, color de la esperanza. Estos v\u00ednculos simb\u00f3licos impregnan nuestro subconsciente y por esa raz\u00f3n combinamos el blanco y el negro, el negro y el rojo en nuestra vestimenta o en nuestro entorno. Instintivamente combinamos el negro con el rojo o el blanco. <\/p>\n\n\n\n<p class=\"comment\">Lejos de ser instintivo, nuestro h\u00e1bito de combinar colores contrastados obedece a un c\u00f3digo crom\u00e1tico social que no siempre ha existido. Las im\u00e1genes de los trajes del Antiguo R\u00e9gimen muestran combinaciones de colores (marr\u00f3n, naranja, verde) que hoy nos parecen de muy mal gusto.<\/p>\n\n\n\n<p>Evidentemente, estas combinaciones de colores tambi\u00e9n se explican por la psicolog\u00eda de la visi\u00f3n: el color m\u00e1s oscuro contrasta con el color m\u00e1s claro y el color m\u00e1s p\u00e1lido contrasta con el color m\u00e1s vivo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Antes de ser brutalmente asesinado el 16 de octubre de 2020, Samuel Paty era profesor. Como estudiante de historia, tambi\u00e9n fue autor de una tesis de maestr\u00eda sobre el color negro. Para rendirle homenaje, publicamos fragmentos de su trabajo, en muchos sentidos innovador.<\/p>\n","protected":false},"author":1366,"featured_media":2163,"comment_status":"open","ping_status":"open","sticky":false,"template":"templates\/post-speeches.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":11,"_lgc_tts_audio_url":"","_lgc_tts_voice":"","_lgc_tts_publish":false,"_lgc_tts_history_item_id":"","_lgc_tts_generated_at":"","_lgc_tts_status":"","_lgc_tts_error":"","footnotes":""},"categories":[58],"tags":[],"staff":[100],"editorial_format":[1474],"serie":[],"audience":[],"geo":[177],"class_list":["post-2162","post","type-post","status-publish","format-standard","hentry","category-historia","staff-olivier-faure-y-christophe-capuano","editorial_format-archivos-y-discursos","geo-europa"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":2163,"excerpt":"Antes de ser brutalmente asesinado el 16 de octubre de 2020, Samuel Paty era profesor. Como estudiante de historia, tambi\u00e9n fue autor de una tesis de maestr\u00eda sobre el color negro. Para rendirle homenaje, publicamos fragmentos de su trabajo, en muchos sentidos innovador.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El Negro. Homenaje a Samuel Paty - El Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/es\/2021\/10\/15\/el-negro-homenaje-a-samuel-paty\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Negro. Homenaje a Samuel Paty - El Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Antes de ser brutalmente asesinado el 16 de octubre de 2020, Samuel Paty era profesor. Como estudiante de historia, tambi\u00e9n fue autor de una tesis de maestr\u00eda sobre el color negro. Para rendirle homenaje, publicamos fragmentos de su trabajo, en muchos sentidos innovador.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/es\/2021\/10\/15\/el-negro-homenaje-a-samuel-paty\/\" \/>\n<meta property=\"og:site_name\" content=\"El Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-15T16:25:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-31T14:59:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2021\/10\/MicrosoftTeams-image-11-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"florent\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2021\/10\/MicrosoftTeams-image-11-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"florent\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2021\/10\/15\/el-negro-homenaje-a-samuel-paty\/\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/2021\/10\/15\/el-negro-homenaje-a-samuel-paty\/\",\"name\":\"El Negro. Homenaje a Samuel Paty - El Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2021\/10\/15\/el-negro-homenaje-a-samuel-paty\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2021\/10\/15\/el-negro-homenaje-a-samuel-paty\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2021\/10\/MicrosoftTeams-image-10-scaled.jpg\",\"datePublished\":\"2021-10-15T16:25:31+00:00\",\"dateModified\":\"2022-05-31T14:59:18+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2021\/10\/15\/el-negro-homenaje-a-samuel-paty\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/es\/2021\/10\/15\/el-negro-homenaje-a-samuel-paty\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2021\/10\/15\/el-negro-homenaje-a-samuel-paty\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2021\/10\/MicrosoftTeams-image-10-scaled.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2021\/10\/MicrosoftTeams-image-10-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Le Centre Pompidou expose les derniers tableaux qu'il a acquis de Pierre Soulages , ainsi que 7 tableaux faisant partie de la donation Pierette Bloch . Le peintre est egalement expose au Louvre et fetera prochainement ses 1oo ans le 24 decembre . PARIS. 9 DECEMBRE 2019. detail d'un outrenoir\/\/GINIES_ginies0176\/1912091435\/Credit:GINIES\/SIPA\/1912091438\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2021\/10\/15\/el-negro-homenaje-a-samuel-paty\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/legrandcontinent.eu\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Negro. Homenaje a Samuel Paty\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/\",\"name\":\"El Grand Continent\",\"description\":\"La escala pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\",\"name\":\"florent\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"caption\":\"florent\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Negro. Homenaje a Samuel Paty - El Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/es\/2021\/10\/15\/el-negro-homenaje-a-samuel-paty\/","og_locale":"es_ES","og_type":"article","og_title":"El Negro. Homenaje a Samuel Paty - El Grand Continent","og_description":"Antes de ser brutalmente asesinado el 16 de octubre de 2020, Samuel Paty era profesor. Como estudiante de historia, tambi\u00e9n fue autor de una tesis de maestr\u00eda sobre el color negro. Para rendirle homenaje, publicamos fragmentos de su trabajo, en muchos sentidos innovador.","og_url":"https:\/\/legrandcontinent.eu\/es\/2021\/10\/15\/el-negro-homenaje-a-samuel-paty\/","og_site_name":"El Grand Continent","article_published_time":"2021-10-15T16:25:31+00:00","article_modified_time":"2022-05-31T14:59:18+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2021\/10\/MicrosoftTeams-image-11-scaled.jpg","type":"image\/jpeg"}],"author":"florent","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2021\/10\/MicrosoftTeams-image-11-scaled.jpg","twitter_misc":{"Escrito por":"florent","Tiempo de lectura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/es\/2021\/10\/15\/el-negro-homenaje-a-samuel-paty\/","url":"https:\/\/legrandcontinent.eu\/es\/2021\/10\/15\/el-negro-homenaje-a-samuel-paty\/","name":"El Negro. Homenaje a Samuel Paty - El Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/es\/2021\/10\/15\/el-negro-homenaje-a-samuel-paty\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/es\/2021\/10\/15\/el-negro-homenaje-a-samuel-paty\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2021\/10\/MicrosoftTeams-image-10-scaled.jpg","datePublished":"2021-10-15T16:25:31+00:00","dateModified":"2022-05-31T14:59:18+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/es\/2021\/10\/15\/el-negro-homenaje-a-samuel-paty\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/es\/2021\/10\/15\/el-negro-homenaje-a-samuel-paty\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/2021\/10\/15\/el-negro-homenaje-a-samuel-paty\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2021\/10\/MicrosoftTeams-image-10-scaled.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2021\/10\/MicrosoftTeams-image-10-scaled.jpg","width":2560,"height":1707,"caption":"Le Centre Pompidou expose les derniers tableaux qu'il a acquis de Pierre Soulages , ainsi que 7 tableaux faisant partie de la donation Pierette Bloch . Le peintre est egalement expose au Louvre et fetera prochainement ses 1oo ans le 24 decembre . PARIS. 9 DECEMBRE 2019. detail d'un outrenoir\/\/GINIES_ginies0176\/1912091435\/Credit:GINIES\/SIPA\/1912091438"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/es\/2021\/10\/15\/el-negro-homenaje-a-samuel-paty\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legrandcontinent.eu\/es\/"},{"@type":"ListItem","position":2,"name":"El Negro. Homenaje a Samuel Paty"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/es\/#website","url":"https:\/\/legrandcontinent.eu\/es\/","name":"El Grand Continent","description":"La escala pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c","name":"florent","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","caption":"florent"}}]}},"lgc_categories":[{"id":58,"name":"Historia","slug":"historia"}],"lgc_author":{"id":100,"name":"Olivier Faure y Christophe Capuano","slug":"olivier-faure-y-christophe-capuano","description":null,"first_name":null,"last_name":null,"picture":null},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2021\/10\/MicrosoftTeams-image-10-scaled.jpg","width":2560,"height":1707,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2021\/10\/MicrosoftTeams-image-10-scaled.jpg","width":2560,"height":1707,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/2162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/users\/1366"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/comments?post=2162"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/2162\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media\/2163"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media?parent=2162"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/categories?post=2162"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/tags?post=2162"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/staff?post=2162"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/editorial_format?post=2162"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/serie?post=2162"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/audience?post=2162"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/geo?post=2162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}