{"id":21058,"date":"2023-08-10T15:03:00","date_gmt":"2023-08-10T14:03:00","guid":{"rendered":"https:\/\/legrandcontinent.eu\/es\/?p=21058"},"modified":"2023-08-10T16:31:54","modified_gmt":"2023-08-10T15:31:54","slug":"de-marignano-a-pavia-luchar-durante-las-guerras-italianas-una-conversacion-con-didier-le-fur","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/es\/2023\/08\/10\/de-marignano-a-pavia-luchar-durante-las-guerras-italianas-una-conversacion-con-didier-le-fur\/","title":{"rendered":"De Marignano a Pav\u00eda, luchar durante las guerras italianas, una conversaci\u00f3n con Didier Le Fur"},"content":{"rendered":"\n<p><em>A lo largo del verano, <a href=\"https:\/\/legrandcontinent.eu\/es\/category\/guerra\/estrategias\/\">la serie \u00abEstrategias\u00bb examina las formas de la guerra y las batallas en diferentes \u00e9pocas, de Cannas a Bajmut<\/a>, pasando por Azincourt y Austerlitz. <a href=\"https:\/\/legrandcontinent.eu\/es\/2023\/08\/07\/la-guerra-sin-fin-de-maquiavelo-una-conversacion-con-jean-louis-fournel-y-jean-claude-zancarini\/\">Tras el caso de Maquiavelo<\/a>, nos quedamos en Italia para el episodio 2, con una inmersi\u00f3n en el campo de batalla de las primeras grandes batallas de la era moderna: las de las Guerras Italianas.<\/em><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00bfDe qu\u00e9 fuentes dispone el historiador militar de las guerras italianas?\u00a0\u00a0\u00a0<\/strong><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\">Didier Le Fur<\/h4>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-small\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2023\/08\/gc-LeFurBruno.png\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"542\"\n        data-pswp-height=\"548\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2023\/08\/gc-LeFurBruno-125x126.png\"\r\n                media=\"(max-width: 374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2023\/08\/gc-LeFurBruno-330x334.png\"\r\n                media=\"(min-width: 375px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2023\/08\/gc-LeFurBruno-125x126.png\" \/>\r\n        <\/picture>\r\n                            \n            <\/a>\n<\/figure>\n\n\n<p>Hay muchas, pero es muy dif\u00edcil trabajar con ellas. A partir del reinado de Carlos VIII, disponemos de una inmensa cantidad de material propagand\u00edstico impreso. Mientras que el desarrollo de la imprenta en Francia hab\u00eda sido un tanto frenado por las autoridades, por temor al peligro potencial que pod\u00eda crear en la opini\u00f3n p\u00fablica, Carlos VIII comprendi\u00f3 r\u00e1pidamente el uso que pod\u00eda hacer de ella cuando, a la edad de 24 a\u00f1os, decidi\u00f3 hacer valer sus derechos a la corona de N\u00e1poles. Era una manera de subrayar el car\u00e1cter excepcional de la campa\u00f1a que preparaba: por primera vez desde San Luis, un rey franc\u00e9s iba a hacer la guerra lejos de su territorio.<\/p>\n\n\n\n<p>Era necesario tranquilizar a la poblaci\u00f3n sobre ese viaje lejano, sobre la capacidad de Francia para salir victoriosa y legitimar tal empresa por motivos distintos de los ligados a la ley; los reyes de Francia ten\u00edan la misi\u00f3n de ayudar al regreso de Cristo a la tierra, y el viaje a N\u00e1poles se presentaba como la primera etapa de una cruzada que conducir\u00eda a Carlos VIII a Jerusal\u00e9n, donde, seg\u00fan las profec\u00edas reescritas para el soberano, entrar\u00eda en los \u00faltimos d\u00edas de su vida, despu\u00e9s de haber pacificado el mundo; all\u00ed, en el Monte de los Olivos, depositar\u00eda todas sus coronas a los pies de un Cristo que hab\u00eda vuelto para vivir entre los hombres, para celebrar la paz en el mundo; conquistar N\u00e1poles significaba, por tanto, participar en la victoria del cristianismo sobre el mundo y contribuir a instaurar la paz universal.<\/p>\n\n\n\n<p>La propaganda escrita contribuy\u00f3 a construir una nueva imagen real, mientras que otros soportes, especialmente las miniaturas y los grabados, relataban los acontecimientos, aunque de forma muy simplificada. La producci\u00f3n po\u00e9tica era abundante, pero no se trataba de informar sobre la violencia, o s\u00f3lo cuando se consideraba necesario mostrar el valor del soberano o de sus ej\u00e9rcitos. Por esta raz\u00f3n, y porque el rey de Francia estaba oficialmente en su derecho, los textos nunca hablaban de \u00abguerra\u00bb, sino de \u00abviaje\u00bb, \u00abreconquista\u00bb o \u00abexpedici\u00f3n\u00bb.\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Por primera vez desde San Luis, un rey franc\u00e9s iba a hacer la guerra lejos de su territorio.<\/p><cite>DIDIER LE FUR<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Seg\u00fan sus publicistas, los reyes de Francia s\u00f3lo hac\u00edan la guerra contra sus rivales o contra quienes trataban de obstaculizar sus planes. Evidentemente, esos relatos son una forma de desviar la atenci\u00f3n de la cuesti\u00f3n principal: el rey de Francia hac\u00eda la guerra para afirmar su soberan\u00eda sobre un territorio en nombre de una determinada interpretaci\u00f3n del principio din\u00e1stico. Como historiadores, nos enfrentamos constantemente a la construcci\u00f3n de una ideolog\u00eda que pretende justificar la conquista. Una ideolog\u00eda que tambi\u00e9n merece la pena estudiar, pues de lo contrario nos perder\u00edamos por completo el imaginario mesi\u00e1nico e imperial que tanto caracteriz\u00f3 esas guerras italianas.<\/p>\n\n\n\n<p>Cuando la campa\u00f1a militar sal\u00eda bien, los relatos eran \u00e9picos y colmaban de gloria al rey y a sus compa\u00f1eros. Los poemas, cantos y procesiones creaban una imagen del rey de Francia como superior a todos sus rivales, que tambi\u00e9n ten\u00edan derechos sobre los mismos territorios e intentaban reivindicarlos. Luis XII desarroll\u00f3 ese discurso a gran escala, animado por sus brillantes \u00e9xitos militares. Los relatos de la derrota eran mucho m\u00e1s el\u00edpticos, por supuesto, y a menudo desconectados de la gran narraci\u00f3n de las guerras italianas: la atenci\u00f3n se centraba en la batalla, para dejarla atr\u00e1s m\u00e1s pronto. Por tanto, es necesario recurrir a fuentes espa\u00f1olas, imperiales o italianas para obtener una imagen m\u00e1s completa.<\/p>\n\n\n\n<p>Por supuesto, esos relatos contempor\u00e1neos no son las \u00fanicas fuentes disponibles. Existe una gran cantidad de correspondencia -tanto privada como diplom\u00e1tica- entre los distintos protagonistas de las campa\u00f1as italianas. En esa masa, los informes de los embajadores son delicados. A primera vista, destacan porque a menudo son muy diferentes de los textos escritos por autores a sueldo del gobierno. En realidad, eso tiene menos que ver con la calidad de sus redes de inteligencia que con una pr\u00e1ctica curial muy extendida: en tiempos de guerra, los embajadores se mantienen alejados del pr\u00edncipe para que no tengan acceso a informaci\u00f3n de demasiada calidad. Tambi\u00e9n sol\u00edan compartir entre ellos las noticias y rumores que escuchaban: el hecho de que los informes de diferentes embajadores puedan corresponderse no es un signo de la veracidad de la informaci\u00f3n sobre una batalla o acontecimiento concreto, sino la prueba de que exist\u00eda una red de embajadores bien establecida.<\/p>\n\n\n\n<p>Para los historiadores militares, no es f\u00e1cil navegar a trav\u00e9s de esos relatos fragmentados. Si bien es cierto que las referencias cruzadas revelan algo sobre las batallas, a menudo nos quedamos con las ganas de preguntarnos, esbozar o incluso formular hip\u00f3tesis.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>En tiempos de guerra, los embajadores se mantienen alejados del pr\u00edncipe para que no tengan acceso a informaci\u00f3n de demasiada calidad.<\/p><cite>DIDIER LE FUR<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00bfCu\u00e1les eran las formas de enfrentamiento militar durante las guerras italianas? \u00bfQu\u00e9 armas se utilizaron?<\/strong><\/h3>\n\n\n\n<p>Desde la Guerra de los Cien A\u00f1os -y en particular desde el desastre de Azincourt-, la caballer\u00eda fue menos explotada. Esa tendencia se reforz\u00f3 durante las guerras italianas, principalmente a causa del terreno. Los caminos escarpados eran menos f\u00e1ciles para los jinetes que para los peatones, pero la caballer\u00eda segu\u00eda estando presente porque siempre era necesario integrar a la nobleza en las campa\u00f1as. Sin embargo, el considerable costo econ\u00f3mico condujo a su progresiva reducci\u00f3n.&nbsp;<\/p>\n\n\n\n<p>A partir del reinado de Carlos VII coexistieron dos tipos diferentes de tropas: por un lado, un ej\u00e9rcito profesional; por otro, mercenarios -sobre todo suizos- que se integraron cada vez m\u00e1s en el resto de las tropas. Adquirieron una posici\u00f3n dominante en la infanter\u00eda, que era su arma preferida. Se les consideraba fiables por su paga: en caso de incumplimiento del contrato, los suizos abandonaban las filas y regresaban a casa, aun sabiendo que ser\u00edan castigados en sus cantones. A finales del siglo XV, Suiza se hab\u00eda convertido en un supermercado humano para los franceses, de donde pod\u00edan reclutar buenos soldados que reun\u00edan una cualidad esencial: estaban dispuestos a morir. Dentro de esa infanter\u00eda, los arqueros fueron sustituidos paulatinamente por soldados equipados con armas de fuego, cuya precisi\u00f3n a\u00fan dejaba mucho que desear.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>A finales del siglo XV, Suiza se hab\u00eda convertido en un supermercado humano para los franceses, de donde pod\u00edan reclutar buenos soldados que reun\u00edan una cualidad esencial: estaban dispuestos a morir. <\/p><cite>DIDIER LE FUR<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Adem\u00e1s, a partir del reinado de Carlos VIII, la infanter\u00eda se vio reforzada por una artiller\u00eda que no hay que sobrevalorar. La corona francesa era rica y la artiller\u00eda era una novedad: durante la campa\u00f1a de N\u00e1poles de Carlos VIII, se trataba de piezas impresionantes pero poco manejables que al final no sirvieron mucho. Eran tan pesadas que ten\u00edan que ser remolcadas por una veintena de animales de carga. A esas piezas de artiller\u00eda no les fue bien en los Alpes y, una vez que llegaron a Italia, fueron abandonadas r\u00e1pidamente debido a la falta de piezas de repuesto. Sin embargo, a medida que avanzaban las guerras, y en particular a partir del reinado de Francisco I, los franceses adquirieron una artiller\u00eda m\u00e1s m\u00f3vil y ligera que pod\u00eda utilizarse tanto para las batallas en l\u00ednea como para la guerra de asedio.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>En el campo de batalla, \u00bfc\u00f3mo era posible entenderse, dado que una de las caracter\u00edsticas de la \u00abguerra europea\u00bb era que los soldados proced\u00edan de todo el continente? \u00bfExiste una <em>lingua franca<\/em> militar en el mosaico del campo de batalla?<\/strong><\/h3>\n\n\n\n<p>En lo que respecta a la lengua, tenemos que hacer algunas suposiciones. En primer lugar, la cuesti\u00f3n nunca se plantea en las fuentes porque era perfectamente normal no entenderse en el siglo XVI. En aquella \u00e9poca, los franceses a\u00fan estaban muy orgullosos de tener 23 dialectos en su territorio. En algunos textos se burlan de los ingleses por tener s\u00f3lo cuatro o cinco. Dicho esto, el franc\u00e9s era utilizado por todos los capitanes y otros oficiales importantes; el hecho es que era necesario poder mandar a los hombres en campa\u00f1a, y sigue siendo un misterio si ciertos gascones o mercenarios suizos de las provincias germanas hablaban franc\u00e9s. Sin embargo, la organizaci\u00f3n del ej\u00e9rcito en lanzas, compa\u00f1\u00edas y luego regimientos condujo sin duda a una mayor cohesi\u00f3n dentro de los grupos. Esas peque\u00f1as unidades, por lo general ling\u00fc\u00edsticamente homog\u00e9neas, permanec\u00edan siempre unidas. Adem\u00e1s, tanto en el campo de batalla como en la marcha, las distintas nacionalidades no se mezclaban: los suizos se quedaban con los suizos; los normandos, con los normandos; los gascones, con los gascones, etc. Incluso hab\u00eda rastros de rivalidades regionales bastante importantes: cuando el ej\u00e9rcito franc\u00e9s sal\u00eda victorioso, algunas regiones se apropiaban de la gloria resaltando sus haza\u00f1as y burl\u00e1ndose de las dem\u00e1s.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>La organizaci\u00f3n del ej\u00e9rcito en lanzas, compa\u00f1\u00edas y luego regimientos condujo sin duda a una mayor cohesi\u00f3n dentro de los grupos.<\/p><cite>DIDIER LE FUR<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00bfY c\u00f3mo se combat\u00eda?<\/strong><\/h3>\n\n\n\n<p>En el siglo XVI, las batallas se libraban en varias hect\u00e1reas. Poco despu\u00e9s de las guerras italianas, durante las guerras civiles y religiosas bajo el reinado de Carlos IX, una \u00abpeque\u00f1a\u00bb batalla como la de Saint-Denis en 1568 se libraba en una zona que se extend\u00eda desde Pontoise a Saint-Denis y Aubervilliers. En Pav\u00eda, en 1525, se utiliz\u00f3 como campo de batalla toda la periferia de una ciudad y parte de la campi\u00f1a.<\/p>\n\n\n\n<p>Para reunir ej\u00e9rcitos heterog\u00e9neos repartidos por un vasto territorio fue necesaria una log\u00edstica cuidadosamente dise\u00f1ada. En el coraz\u00f3n de los ej\u00e9rcitos multirregionales -o incluso multinacionales- de la \u00e9poca hab\u00eda una especie de entente. En la c\u00faspide, los jefes de los distintos regimientos hablaban todos la lengua del estado mayor: por ejemplo, los oficiales suizos sol\u00edan ser franc\u00f3fonos. Eso significaba que la informaci\u00f3n fluyera con facilidad. Sin embargo, como ocurri\u00f3 en Pav\u00eda, la informaci\u00f3n puede tardar en llegar, o incluso distorsionarse, ya que el rumor es un arma tan destructiva como el ca\u00f1\u00f3n m\u00e1s eficaz.<\/p>\n\n\n\n<p>La organizaci\u00f3n en s\u00ed segu\u00eda siendo bastante arcaica: el ej\u00e9rcito se divid\u00eda en tres grupos -la vanguardia, la batalla y la retaguardia-, cada uno de los cuales inclu\u00eda artiller\u00eda, infanter\u00eda y caballer\u00eda. Tal estructura ten\u00eda la ventaja de ser bastante laxa, lo que permit\u00eda una forma de adaptaci\u00f3n cuando el \u00e9xito tardaba en llegar: fue el caso de Marignano, donde el car\u00e1cter monol\u00edtico de los suizos llev\u00f3 a los franceses a aumentar el compromiso de su artiller\u00eda.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>El ej\u00e9rcito se divid\u00eda en tres grupos -la vanguardia, la batalla y la retaguardia-, cada uno de los cuales inclu\u00eda artiller\u00eda, infanter\u00eda y caballer\u00eda.<\/p><cite>DIDIER LE FUR<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00bfPor qu\u00e9 algunas batallas son m\u00e1s sangrientas que otras?<\/strong><\/h3>\n\n\n\n<p>En primer lugar, est\u00e1 la duraci\u00f3n del conflicto. Por lo general, una batalla dura siete u ocho horas, y la media de muertos por hora en las batallas de principios del siglo XVI ronda el millar. Pero hubo excepciones. En Marignano, por ejemplo, la batalla comenz\u00f3 a \u00faltima hora de la tarde del 13 de septiembre, se prolong\u00f3 durante toda la noche y se reanud\u00f3 al amanecer del d\u00eda 14. No termin\u00f3 realmente hasta despu\u00e9s del mediod\u00eda. El balance fue proporcional a la duraci\u00f3n de los intercambios: casi 15 mil muertos, por no hablar de los heridos que murieron en las semanas siguientes. Adem\u00e1s, el combate cuerpo a cuerpo fue una constante en las batallas de ese periodo. El hecho es que las batallas m\u00e1s sangrientas siempre tuvieron lugar en terrenos accidentados. El terreno puede ser especialmente letal. Tal fue el caso, por ejemplo, de la batalla de La Bicoca en 1522, en la que los espa\u00f1oles tomaron una posici\u00f3n elevada en una villa amurallada de la que los franceses pensaron que podr\u00edan desalojarlos tom\u00e1ndolos por la retaguardia. Pero los hombres de Carlos V hab\u00edan previsto esa t\u00e1ctica y su potencia de fuego estaba bien estructurada: el resultado fue un aut\u00e9ntico desastre para el ej\u00e9rcito real. La batalla dur\u00f3 apenas hora y media, pero dej\u00f3 m\u00e1s de 5 mil muertos, la mayor\u00eda de ellos mercenarios suizos que, temerarios como eran, hab\u00edan pensado que su n\u00famero derrotar\u00eda a la artiller\u00eda de sus enemigos. Fueron aniquilados.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00bfCu\u00e1ndo y c\u00f3mo se gana una batalla en la Europa de principios del siglo XVI?<\/strong><\/h3>\n\n\n\n<p>Hab\u00eda esencialmente dos maneras de ganar una batalla. O bien el adversario abandonaba el campo, como en Marignano, o bien se capturaba al comandante en jefe, como en Pav\u00eda.\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Una batalla dura siete u ocho horas, y la media de muertos por hora en las batallas de principios del siglo XVI ronda el millar. Hab\u00eda esencialmente dos maneras de ganar una batalla. O bien el adversario abandonaba el campo, como en Marignano, o bien se capturaba al comandante en jefe, como en Pav\u00eda.\u00a0<\/p><cite>DIDIER LE FUR<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Marignano ilustra la evoluci\u00f3n de los suizos durante las guerras italianas, ya que en el espacio de dos d\u00e9cadas pasaron del mercenarismo a la acci\u00f3n aut\u00f3noma. \u00bfC\u00f3mo puede explicarse esto? \u00bfExiste un paralelismo con el grupo de Wagner?<\/strong><\/h3>\n\n\n\n<p>Siempre es el mismo problema con los mercenarios. Internamente, la mayor\u00eda de los cantones de la confederaci\u00f3n suiza est\u00e1n estructurados democr\u00e1ticamente y ya tienen un sentido de naci\u00f3n bien desarrollado, pero la extrema pobreza de los campesinos los obliga a vender parte de su mano de obra. En el campo, los suizos luchan para ganarse el salario, a veces con armamento rudimentario. Matan, pero no toman prisioneros. Su presencia en todas las expediciones francesas, desde la de Carlos VIII a N\u00e1poles hasta la batalla de Agnadel provocada por Luis XII para destruir a los venecianos en 1509, les dio un aura \u00fanica en toda Europa. Pero, aunque la confederaci\u00f3n suiza fuera ya una verdadera democracia, ten\u00eda no obstante verdaderas ambiciones expansionistas, como todos los Estados de su entorno. A medida que avanzaban las batallas y las negociaciones, fueron tomando conciencia de las ganancias territoriales que pod\u00edan obtener, sobre todo en la pen\u00ednsula, eligiendo como principales patrocinadores no a Francia, sino al Papado o a Mil\u00e1n; las ventajas econ\u00f3micas y comerciales eran las consecuencias de esas nuevas alianzas. Poco a poco, imitaron a los pr\u00edncipes a los que serv\u00edan impulsando sus pretensiones hacia la llanura del Po. Durante un breve periodo, la Confederaci\u00f3n Helv\u00e9tica se convirti\u00f3 en una potencia pol\u00edtica y diplom\u00e1tica por derecho propio.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00bfMarignano fue la culminaci\u00f3n de ese proceso?<\/strong><\/h3>\n\n\n\n<p>Tom\u00f3 forma hacia 1510, cuando empez\u00f3 a perfilarse el enfrentamiento entre Luis XII y el Papado. Conscientes de su poder de arbitraje, los suizos acabaron eligiendo al papa antes que al rey de Francia, pero a cambio de algo. Desempe\u00f1aron un papel importante en la expulsi\u00f3n de los franceses de la pen\u00ednsula, a cambio de diversos derechos y privilegios comerciales en Mil\u00e1n y la ocupaci\u00f3n de parte del ducado a lo largo del Tesino. Esa din\u00e1mica no se rompi\u00f3 en Marignano, pero es innegable que se fren\u00f3 considerablemente.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00bfQu\u00e9 evoluciones t\u00e1cticas y estrat\u00e9gicas se derivaron de las guerras italianas?<\/strong><\/h3>\n\n\n\n<p>Desde el punto de vista de la configuraci\u00f3n del enfrentamiento, el campo de batalla segu\u00eda siendo absolutamente crucial. Sin embargo, la artiller\u00eda iba a desempe\u00f1ar un papel cada vez m\u00e1s importante, aunque siguiera siendo bastante marginal: un ca\u00f1\u00f3n tardaba cuatro minutos en recargarse. Su funci\u00f3n principal era intimidar al enemigo en la batalla. Era mucho m\u00e1s eficaz en la guerra de asedio. La guerra de asedio estaba evolucionando considerablemente. Las murallas convencionales eran cada vez menos resistentes al fuego de artiller\u00eda y, para reconstruirlas, era necesario destruir toda la muralla maltrecha. Eso llevaba demasiado tiempo y era demasiado caro. En Francia, en particular, empezaron a proliferar los terraplenes a lo largo de la frontera franco-imperial, conglomerados de materiales diversos y variados, menos resistentes pero m\u00e1s f\u00e1ciles de levantar y especialmente eficaces durante un conflicto para proteger a la ciudad en peligro. La estrategia de las defensas fronterizas tambi\u00e9n cambi\u00f3. Ya no se trataba de defender una l\u00ednea continua, sino de organizar eficazmente la fortificaci\u00f3n de unas pocas ciudades que pudieran constituir la base de la defensa del territorio.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>La estrategia de las defensas fronterizas tambi\u00e9n cambi\u00f3. Ya no se trataba de defender una l\u00ednea continua, sino de organizar eficazmente la fortificaci\u00f3n de unas pocas ciudades que pudieran constituir la base de la defensa del territorio.<\/p><cite>didier le fur<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00bfQu\u00e9 papel desempe\u00f1\u00f3 el honor en esas guerras?<\/strong><\/h3>\n\n\n\n<p>Tiene un papel esencial, aunque es muy dif\u00edcil dar una definici\u00f3n exacta. Siempre que se habla de honor, se asocia a la ley: actuar honorablemente es defender el derecho propio o actuar de acuerdo a la ley. La idea de una guerra justa era omnipresente en el pensamiento contempor\u00e1neo sobre la guerra.<\/p>\n\n\n\n<p>Al entrar en campa\u00f1a, el sentido del honor es inseparable de la cultura caballeresca y aristocr\u00e1tica que comparten los pr\u00edncipes. Todos afirman actuar en defensa de valores inmemoriales, insistiendo en que no son tiranos, sino que act\u00faan por el bien. En ese caso, el honor significa aceptar luchar -o incluso morir- para defender una causa justa. Actuar con honor es tambi\u00e9n una forma de expresar la confianza en Dios.<\/p>\n\n\n\n<p>Francisco I habl\u00f3 de su honor despu\u00e9s de Marignano, porque esa victoria le permiti\u00f3 restaurar su soberan\u00eda sobre un territorio que consideraba suyo y que le hab\u00eda sido usurpado. Del mismo modo, en los a\u00f1os siguientes, fue una cuesti\u00f3n de su honor como rey muy cristiano reclamar la corona imperial, a pesar de que la mayor\u00eda de sus consejeros le hab\u00edan dicho que era in\u00fatil. Finalmente, tras la derrota de Pav\u00eda, escribi\u00f3 estas palabras a su madre: \u00abSe\u00f1ora, para que sepa c\u00f3mo se desenvuelve mi desgracia, de todas las cosas s\u00f3lo me quedan el honor y la vida, que est\u00e1 a salvo\u00bb. Esta frase, que se ha hecho famosa en una forma muy alterada y arcaica &#8211; \u00abTodo est\u00e1 perdido, salvo el honor\u00bb- tiene algo de program\u00e1tico: si le queda el honor, podr\u00e1 seguir haciendo valer sus derechos; sobre todo, no se ha mostrado cobarde y conserva as\u00ed toda su dignidad de pr\u00edncipe.<\/p>\n\n\n\n<p>Con el paso del tiempo, el relato de la batalla de Pav\u00eda trat\u00f3 de ocultar la derrota, que acab\u00f3 con la captura del rey, y de subrayar el honor intacto de la nobleza francesa en la batalla. Al no poder conservar sus tierras italianas, Francisco I se convirti\u00f3 en el garante del ideal caballeresco en Francia.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Con el paso del tiempo, el relato de la batalla de Pav\u00eda trat\u00f3 de ocultar la derrota, que acab\u00f3 con la captura del rey, y de subrayar el honor intacto de la nobleza francesa en la batalla. Al no poder conservar sus tierras italianas, Francisco I se convirti\u00f3 en el garante del ideal caballeresco en Francia.<\/p><cite>didier le fur<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00bfQu\u00e9 significa librar una guerra entre pr\u00edncipes cristianos? \u00bfQu\u00e9 papel desempe\u00f1\u00f3 la religi\u00f3n en esas batallas?<\/strong><\/h3>\n\n\n\n<p>La religi\u00f3n era omnipresente durante las batallas. En primer lugar, las figuras religiosas acompa\u00f1aban siempre a los soldados, se celebraba misa y se organizaban oraciones colectivas a diario. Cuando comenzaba la batalla, se invocaba a Dios para que protegiera al rey, al reino y a sus hombres. Adem\u00e1s de las oraciones constantes a lo largo de la batalla, se escrutaban las manifestaciones divinas porque se cre\u00eda que Dios, amo de la batalla, siempre interven\u00eda en el conflicto con un milagro para ayudar a ganar a su pueblo favorito: la llegada de la lluvia, un viento en contra o el brillo del sol suelen considerarse intervenciones divinas. Por \u00faltimo, se daba gracias a Dios al final de los combates. En la retaguardia, se organizaban procesiones para proteger al reino, a los ej\u00e9rcitos y a sus l\u00edderes. Una vez anunciada la victoria, se organizaban otras procesiones y acciones de gracias por todo el reino. A veces, los milagros eran espectaculares. En Agnadel, por ejemplo, se dice que el Esp\u00edritu Santo, en forma de paloma, descendi\u00f3 del cielo y se pos\u00f3 sobre la cabeza emplumada de Luis XII, anunciando a todos sus hombres el final de la batalla y la victoria del rey de Francia. Todav\u00eda es inconcebible, y lo seguir\u00e1 siendo durante mucho tiempo, que Dios no pudiera estar presente en momentos tan importantes para el futuro de una pol\u00edtica, o incluso de un reino.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00bfPor qu\u00e9 las batallas de Marignano y Pav\u00eda dejaron una huella tan duradera en la memoria francesa?<\/strong><\/h3>\n\n\n\n<p>Marignano es f\u00e1cil de entender. Fue la primera batalla del reinado de Francisco I, su primera victoria y, en cierto modo, la \u00faltima.<\/p>\n\n\n\n<p>En cuanto a Pav\u00eda, fue un verdadero desastre. Desde Poitiers, ning\u00fan rey franc\u00e9s hab\u00eda sido prisionero del enemigo en batalla. Adem\u00e1s, durante mucho tiempo en Francia, los s\u00fabditos del rey supieron poco o nada del desarrollo de la batalla, s\u00f3lo el resultado. Aunque la historia de la batalla de Marignano se ofreci\u00f3 a los franceses, obviamente en su versi\u00f3n m\u00e1s gloriosa, y s\u00f3lo en 1519, ning\u00fan autor en Francia relat\u00f3 la batalla de Pav\u00eda. Los publicistas del rey, cuando la mencionaron m\u00e1s tarde, siempre la envolvieron en el misterio, declarando que era un acontecimiento demasiado doloroso para ser recordado. Pero el rey derrotado, hecho prisionero y liberado frente a sus dos hijos mayores, rehenes en las futuras negociaciones de paz, deb\u00eda devolver la confianza a un pueblo que ya no pod\u00eda creer en \u00e9l ni en su capacidad para defenderlo; as\u00ed que los mismos autores intentaron convertir esa tremenda derrota en un momento glorioso, a pesar del rev\u00e9s, un momento de valent\u00eda, coloreado por la imaginaci\u00f3n caballeresca. Se trataba de guardar las apariencias, disimular el fiasco, restablecer la confianza y, sobre todo, dar la impresi\u00f3n de que ni el hombre ni el reino hab\u00edan sido abandonados por Dios. Fue esa versi\u00f3n, que honraba el supuesto esp\u00edritu caballeresco del rey, la que permanecer\u00eda en los libros de historia, construyendo poco a poco la imagen del soberano como caballero que tantos escolares de la Tercera Rep\u00fablica aclamar\u00edan. Lo cierto es que desde el 24 de febrero de 1525 nunca m\u00e1s un rey franc\u00e9s se expuso a la batalla.\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Desde el 24 de febrero de 1525 nunca m\u00e1s un rey franc\u00e9s se expuso a la batalla.\u00a0<\/p><cite>didier le fur<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Sin embargo, no hay que sobrestimar el impacto que esas batallas tuvieron en Francia hasta principios del siglo XIX, sobre todo porque Francisco I, desde la \u00e9poca de Enrique IV, fue considerado un mal rey. Adem\u00e1s, Marignano ha quedado en gran medida relegada tras su fecha: mientras que hoy en d\u00eda la mayor\u00eda de la gente dice reflexivamente \u00abMarignano\u00bb cuando oye \u00ab1515\u00bb, no tiene ni idea de lo que pudo significar esa batalla. En t\u00e9rminos m\u00e1s generales, las guerras italianas fueron objeto de cr\u00edticas a menudo violentas en los libros de historia a partir de finales del siglo XVI. Murieron tantos hombres, se gast\u00f3 tanto dinero y no se consigui\u00f3 nada. Un inmenso despilfarro. Y aunque la Restauraci\u00f3n de Luis XVIII y Carlos X, el renacimiento de la monarqu\u00eda, dio un lugar de honor a ese periodo de la historia francesa, inventando poco a poco el concepto de \u00abRenacimiento\u00bb, no se trataba de recordar las batallas si no eran victoriosas. Luis Felipe no fue diferente: cre\u00f3 su Galer\u00eda de Batallas y conmemor\u00f3 \u00fanicamente la batalla de Marignano, sin ayudar al p\u00fablico a recontextualizarla. Despu\u00e9s de Michelet, los historiadores se limitan la mayor\u00eda de las veces a ver en esos conflictos s\u00f3lo los vestigios de una sociedad feudal moribunda, una monarqu\u00eda terrateniente, de la que Luis XII habr\u00eda sido el ejemplo m\u00e1s perfecto, poniendo la memoria de ese hombre en el purgatorio durante siglo y medio.\u00a0<\/p>\n\n\n\n<p>En cuanto a Francisco I, sus fracasos fueron poco a poco perdonados, sobre todo porque entretanto se hab\u00eda convertido en el \u00abpr\u00edncipe del Renacimiento\u00bb, la encarnaci\u00f3n de una renovaci\u00f3n, de un replanteamiento del hombre que, salido de la noche de la Edad Media, impregnado de religi\u00f3n, renac\u00eda en s\u00ed mismo y tomaba conciencia de su progreso para reaprender la libertad. Esto es b\u00e1sicamente lo que los historiadores quisieron ver en \u00e9l hasta finales de los a\u00f1os ochenta, cuando otros historiadores volvieron a la historia militar, abandonada desde finales del siglo XIX, para reelaborar progresivamente las guerras italianas y alterar as\u00ed considerablemente la memoria del monarca.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Las guerras italianas est\u00e1n marcadas por la carrera del condestable Borb\u00f3n. \u00bfPodr\u00eda repasar su historia y c\u00f3mo influy\u00f3 en la guerra del siglo XVI?<\/strong><\/h3>\n\n\n\n<p>Ante todo, Carlos de Borb\u00f3n era un joven pr\u00edncipe de sangre, muy lejos del trono. Gracias a su matrimonio con su prima, Susana de Borb\u00f3n, y al afecto que le profesaba Luis XII, recibi\u00f3 t\u00edtulos, tierras y considerables honores. Fue uno de los mayores se\u00f1ores feudales de su \u00e9poca: los territorios que controlaba eran inmensos, el equivalente a tres departamentos franceses. En 1507, a la edad de 17 a\u00f1os, acompa\u00f1\u00f3 al rey a G\u00e9nova para recuperar el se\u00f1or\u00edo que se hab\u00eda sublevado, mientras el rey segu\u00eda pensando en reconquistar el reino de N\u00e1poles, que hab\u00eda perdido en 1504. En 1509, estuvo en Agnadel, luchando al lado de su soberano. Durante la guerra contra el papa Julio II, particip\u00f3 en varias batallas en Francia e Italia. A la muerte de Luis XII, ten\u00eda 25 a\u00f1os y era uno de los se\u00f1ores m\u00e1s poderosos de Francia. Apenas era mayor que Francisco I, un joven rey que carec\u00eda de apoyo en la corte. Francisco I no pod\u00eda prescindir de \u00e9l y, a su llegada, lo nombr\u00f3 condestable de Francia, el m\u00e1s alto cargo militar del reino, otorgado de por vida. Durante la reconquista de Mil\u00e1n, en el verano de 1515, dirigi\u00f3 la vanguardia y, naturalmente, estuvo presente en la batalla de Marignano, donde se distingui\u00f3.\u00a0<\/p>\n\n\n\n<p>Francisco I continu\u00f3 colm\u00e1ndolo de honores y, tras la reconquista de Mil\u00e1n, lo nombr\u00f3 lugarteniente general del ducado. Sin embargo, el intento fallido de Maximiliano I en Mil\u00e1n sirvi\u00f3 de pretexto al rey de Francia para distanciar progresivamente al Borb\u00f3n de su c\u00edrculo \u00edntimo. El condestable no s\u00f3lo fue llamado a Francia, sino que cada vez particip\u00f3 menos en el Consejo Privado. As\u00ed, a partir de 1517, aunque sigue siendo un actor del ceremonial real, pierde progresivamente cualquier forma de poder efectivo en la Corte. Adem\u00e1s, se opuso con demasiada firmeza a la candidatura de Francisco I a la corona imperial. En los meses siguientes, sus relaciones con Francisco I siguieron deterior\u00e1ndose. En 1521, perdi\u00f3 a su esposa y su herencia provoc\u00f3 la codicia de la corona, lo que condujo a un juicio en el que intervino directamente la madre del rey, Luisa de Saboya. Al mismo tiempo, se reanud\u00f3 la guerra en Mil\u00e1n y Picard\u00eda. Aunque el Borb\u00f3n era te\u00f3ricamente la figura militar m\u00e1s poderosa de Francia, fue excluido de cualquier forma de mando.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Aunque el Borb\u00f3n era te\u00f3ricamente la figura militar m\u00e1s poderosa de Francia, fue excluido de cualquier forma de mando.<\/p><cite>didier le fur<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Fue entonces cuando Carlos V decidi\u00f3 intervenir. Le hizo una oferta de matrimonio, proponi\u00e9ndole que se casara con una de sus hermanas o con una de sus sobrinas. Tambi\u00e9n parece que le propuso participar en el reparto del reino de Francia ya previsto con Enrique VIII de Inglaterra: a Carlos V, las antiguas tierras de los duques de Borgo\u00f1a; al ingl\u00e9s, la fachada occidental y el t\u00edtulo de rey de Francia; al Borb\u00f3n, la restituci\u00f3n de todas sus tierras m\u00e1s Provenza, con derecho a formar reino.<\/p>\n\n\n\n<p>Finalmente, ante el deterioro de su situaci\u00f3n en Francia, el condestable opt\u00f3 por abandonar el reino en 1523 para servir a Carlos V. Es muy probable que con ello salvara la vida, pero al mismo tiempo se conden\u00f3 definitivamente en Francia: acababa de cometer un delito de lesa majestad. Parece que a Francisco I le sorprendi\u00f3 su decisi\u00f3n: aunque deb\u00eda acompa\u00f1ar al ej\u00e9rcito, decidi\u00f3 quedarse en Francia para seguir el resultado del juicio de los familiares del condestable detenidos tras su deserci\u00f3n, que esperaba fuera ejemplar. El hecho es que la traici\u00f3n de este \u00faltimo se limitaba sobre todo a una lealtad sin l\u00edmites al duque de Borb\u00f3n. En cuanto al Borb\u00f3n, se uni\u00f3 al ej\u00e9rcito imperial durante los combates de Sesia, donde muri\u00f3 Bayard.&nbsp;<\/p>\n\n\n\n<p>Los publicistas de la monarqu\u00eda aprovecharon este encuentro, fatal para Bayard, para construir una imagen del traidor por excelencia en torno a la memoria del Borb\u00f3n. Por un lado, la lealtad absoluta de un capit\u00e1n a su soberano, capaz de morir por \u00e9l y por Francia; por otro, un pr\u00edncipe de sangre, ejemplo oficial de lealtad a la monarqu\u00eda, porque ten\u00eda posibilidades de triunfar y portador de sangre elegido por Dios para proteger a Francia, pero que se entreg\u00f3 al enemigo para destruir ese mismo reino. Ese manique\u00edsmo encajaba bien con la propaganda que rodeaba la historia de las guerras italianas. En mayo de 1527, el Borb\u00f3n, que hab\u00eda participado en la batalla de Pav\u00eda en el bando imperial, puso sitio a Roma, pero muri\u00f3 de un disparo de arcabuz antes de poder tomar la ciudad. Su juicio no concluy\u00f3 hasta el verano de 1527 en Par\u00eds. Adem\u00e1s de la confiscaci\u00f3n de todas sus posesiones en beneficio de la corona, se le conden\u00f3 a muerte y se le ejecut\u00f3 simb\u00f3licamente; tambi\u00e9n se le orden\u00f3 retirar su nombre, lemas y retratos de todas sus casas, y se prohibi\u00f3 mencionar su nombre en las historias. A ra\u00edz de esa sentencia, hubo que reescribir la batalla de Marignano.\u00a0<\/p>\n\n\n\n<p>Este asunto dio origen a una nueva figura del traidor ideal en el imaginario colectivo, lo que sin duda contribuy\u00f3 a restaurar la imagen de Francisco I, muy deteriorada tras su regreso de la prisi\u00f3n espa\u00f1ola.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estrategias | Episodio 2 <\/p>\n<p>\u00bfC\u00f3mo se luchaba en Europa a principios del siglo XVI? \u00bfQu\u00e9 significaba ganar una batalla cuando dos pr\u00edncipes cristianos se enfrentaban en la pen\u00ednsula italiana? Las guerras italianas son una ruptura moderna. Para saber por qu\u00e9, hemos conversado con el historiador Didier Le Fur.<\/p>\n","protected":false},"author":1366,"featured_media":21075,"comment_status":"closed","ping_status":"","sticky":false,"template":"templates\/post-interviews.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":23,"_lgc_tts_audio_url":"","_lgc_tts_voice":"","_lgc_tts_publish":false,"_lgc_tts_history_item_id":"","_lgc_tts_generated_at":"","_lgc_tts_status":"","_lgc_tts_error":"","footnotes":""},"categories":[608],"tags":[],"staff":[57],"editorial_format":[1473],"serie":[],"audience":[],"geo":[177],"class_list":["post-21058","post","type-post","status-publish","format-standard","hentry","category-estrategias","staff-baptiste-roger-lacan","editorial_format-entrevistas","geo-europa"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":21075,"excerpt":"Estrategias | Episodio 2 \r\n\r\n\u00bfC\u00f3mo se luchaba en Europa a principios del siglo XVI? \u00bfQu\u00e9 significaba ganar una batalla cuando dos pr\u00edncipes cristianos se enfrentaban en la pen\u00ednsula italiana? Las guerras italianas son una ruptura moderna. Para saber por qu\u00e9, hemos conversado con el historiador Didier Le Fur.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>De Marignano a Pav\u00eda, luchar durante las guerras italianas, una conversaci\u00f3n con Didier Le Fur - El Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/es\/2023\/08\/10\/de-marignano-a-pavia-luchar-durante-las-guerras-italianas-una-conversacion-con-didier-le-fur\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"De Marignano a Pav\u00eda, luchar durante las guerras italianas, una conversaci\u00f3n con Didier Le Fur - El Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Estrategias | Episodio 2   \u00bfC\u00f3mo se luchaba en Europa a principios del siglo XVI? \u00bfQu\u00e9 significaba ganar una batalla cuando dos pr\u00edncipes cristianos se enfrentaban en la pen\u00ednsula italiana? Las guerras italianas son una ruptura moderna. Para saber por qu\u00e9, hemos conversado con el historiador Didier Le Fur.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/es\/2023\/08\/10\/de-marignano-a-pavia-luchar-durante-las-guerras-italianas-una-conversacion-con-didier-le-fur\/\" \/>\n<meta property=\"og:site_name\" content=\"El Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-10T14:03:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-10T15:31:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/08\/gc-elguerrasdeitalia-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"florent\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/08\/gc-elguerrasdeitalia-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"florent\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"23 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/08\/10\/de-marignano-a-pavia-luchar-durante-las-guerras-italianas-una-conversacion-con-didier-le-fur\/\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/2023\/08\/10\/de-marignano-a-pavia-luchar-durante-las-guerras-italianas-una-conversacion-con-didier-le-fur\/\",\"name\":\"De Marignano a Pav\u00eda, luchar durante las guerras italianas, una conversaci\u00f3n con Didier Le Fur - El Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/08\/10\/de-marignano-a-pavia-luchar-durante-las-guerras-italianas-una-conversacion-con-didier-le-fur\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/08\/10\/de-marignano-a-pavia-luchar-durante-las-guerras-italianas-una-conversacion-con-didier-le-fur\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/08\/gc-The_Battle_of_Pavia_Rupert_Heller_-_Nationalmuseum_-_17222-scaled-1.jpg\",\"datePublished\":\"2023-08-10T14:03:00+00:00\",\"dateModified\":\"2023-08-10T15:31:54+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/08\/10\/de-marignano-a-pavia-luchar-durante-las-guerras-italianas-una-conversacion-con-didier-le-fur\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/es\/2023\/08\/10\/de-marignano-a-pavia-luchar-durante-las-guerras-italianas-una-conversacion-con-didier-le-fur\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/08\/10\/de-marignano-a-pavia-luchar-durante-las-guerras-italianas-una-conversacion-con-didier-le-fur\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/08\/gc-The_Battle_of_Pavia_Rupert_Heller_-_Nationalmuseum_-_17222-scaled-1.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/08\/gc-The_Battle_of_Pavia_Rupert_Heller_-_Nationalmuseum_-_17222-scaled-1.jpg\",\"width\":2560,\"height\":2288,\"caption\":\"Rupert Heller, La batalla de Pav\u00eda, 1925, Nationalmuseum, Estocolmo, NM 272, 115 x 128 cm (dominio p\u00fablico)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/08\/10\/de-marignano-a-pavia-luchar-durante-las-guerras-italianas-una-conversacion-con-didier-le-fur\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/legrandcontinent.eu\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"De Marignano a Pav\u00eda, luchar durante las guerras italianas, una conversaci\u00f3n con Didier Le Fur\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/\",\"name\":\"El Grand Continent\",\"description\":\"La escala pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\",\"name\":\"florent\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"caption\":\"florent\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"De Marignano a Pav\u00eda, luchar durante las guerras italianas, una conversaci\u00f3n con Didier Le Fur - El Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/es\/2023\/08\/10\/de-marignano-a-pavia-luchar-durante-las-guerras-italianas-una-conversacion-con-didier-le-fur\/","og_locale":"es_ES","og_type":"article","og_title":"De Marignano a Pav\u00eda, luchar durante las guerras italianas, una conversaci\u00f3n con Didier Le Fur - El Grand Continent","og_description":"Estrategias | Episodio 2   \u00bfC\u00f3mo se luchaba en Europa a principios del siglo XVI? \u00bfQu\u00e9 significaba ganar una batalla cuando dos pr\u00edncipes cristianos se enfrentaban en la pen\u00ednsula italiana? Las guerras italianas son una ruptura moderna. Para saber por qu\u00e9, hemos conversado con el historiador Didier Le Fur.","og_url":"https:\/\/legrandcontinent.eu\/es\/2023\/08\/10\/de-marignano-a-pavia-luchar-durante-las-guerras-italianas-una-conversacion-con-didier-le-fur\/","og_site_name":"El Grand Continent","article_published_time":"2023-08-10T14:03:00+00:00","article_modified_time":"2023-08-10T15:31:54+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/08\/gc-elguerrasdeitalia-scaled.jpg","type":"image\/jpeg"}],"author":"florent","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/08\/gc-elguerrasdeitalia-scaled.jpg","twitter_misc":{"Escrito por":"florent","Tiempo de lectura":"23 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/es\/2023\/08\/10\/de-marignano-a-pavia-luchar-durante-las-guerras-italianas-una-conversacion-con-didier-le-fur\/","url":"https:\/\/legrandcontinent.eu\/es\/2023\/08\/10\/de-marignano-a-pavia-luchar-durante-las-guerras-italianas-una-conversacion-con-didier-le-fur\/","name":"De Marignano a Pav\u00eda, luchar durante las guerras italianas, una conversaci\u00f3n con Didier Le Fur - El Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/es\/2023\/08\/10\/de-marignano-a-pavia-luchar-durante-las-guerras-italianas-una-conversacion-con-didier-le-fur\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/es\/2023\/08\/10\/de-marignano-a-pavia-luchar-durante-las-guerras-italianas-una-conversacion-con-didier-le-fur\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/08\/gc-The_Battle_of_Pavia_Rupert_Heller_-_Nationalmuseum_-_17222-scaled-1.jpg","datePublished":"2023-08-10T14:03:00+00:00","dateModified":"2023-08-10T15:31:54+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/es\/2023\/08\/10\/de-marignano-a-pavia-luchar-durante-las-guerras-italianas-una-conversacion-con-didier-le-fur\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/es\/2023\/08\/10\/de-marignano-a-pavia-luchar-durante-las-guerras-italianas-una-conversacion-con-didier-le-fur\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/2023\/08\/10\/de-marignano-a-pavia-luchar-durante-las-guerras-italianas-una-conversacion-con-didier-le-fur\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/08\/gc-The_Battle_of_Pavia_Rupert_Heller_-_Nationalmuseum_-_17222-scaled-1.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/08\/gc-The_Battle_of_Pavia_Rupert_Heller_-_Nationalmuseum_-_17222-scaled-1.jpg","width":2560,"height":2288,"caption":"Rupert Heller, La batalla de Pav\u00eda, 1925, Nationalmuseum, Estocolmo, NM 272, 115 x 128 cm (dominio p\u00fablico)"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/es\/2023\/08\/10\/de-marignano-a-pavia-luchar-durante-las-guerras-italianas-una-conversacion-con-didier-le-fur\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legrandcontinent.eu\/es\/"},{"@type":"ListItem","position":2,"name":"De Marignano a Pav\u00eda, luchar durante las guerras italianas, una conversaci\u00f3n con Didier Le Fur"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/es\/#website","url":"https:\/\/legrandcontinent.eu\/es\/","name":"El Grand Continent","description":"La escala pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c","name":"florent","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","caption":"florent"}}]}},"lgc_categories":[{"id":608,"name":"Estrategias: de Cannas a Bajmut","slug":"estrategias"}],"lgc_author":{"id":57,"name":"Baptiste Roger-Lacan","slug":"baptiste-roger-lacan","description":null,"first_name":null,"last_name":null,"picture":null},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/08\/gc-The_Battle_of_Pavia_Rupert_Heller_-_Nationalmuseum_-_17222-scaled-1.jpg","width":2560,"height":2288,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/08\/gc-The_Battle_of_Pavia_Rupert_Heller_-_Nationalmuseum_-_17222-scaled-1.jpg","width":2560,"height":2288,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/21058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/users\/1366"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/comments?post=21058"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/21058\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media\/21075"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media?parent=21058"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/categories?post=21058"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/tags?post=21058"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/staff?post=21058"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/editorial_format?post=21058"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/serie?post=21058"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/audience?post=21058"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/geo?post=21058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}