{"id":20620,"date":"2023-07-28T15:46:00","date_gmt":"2023-07-28T14:46:00","guid":{"rendered":"https:\/\/legrandcontinent.eu\/es\/?p=20620"},"modified":"2023-07-28T19:30:46","modified_gmt":"2023-07-28T18:30:46","slug":"catalunya-de-nuevo-en-el-centro-del-tablero-x","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/es\/2023\/07\/28\/catalunya-de-nuevo-en-el-centro-del-tablero-x\/","title":{"rendered":"Catalunya de nuevo en el centro del tablero"},"content":{"rendered":"\n<p class=\"has-drop-cap\">Catalunya vuelve a ser el foco de la disputa pol\u00edtica en Espa\u00f1a despu\u00e9s de las elecciones generales del 23 de julio. El ajustado resultado entre bloques, con una izquierda que pese a la remontada vivida durante la campa\u00f1a no ha podido sobreponerse a un bloque conservador que ha padecido una amarga victoria, vuelve a situar en el centro del tablero a los partidos independentistas catalanes. La cuesti\u00f3n catalana se posiciona como eje fundamental de la pr\u00f3xima legislatura en el caso de que se conforme un gobierno progresista entre PSOE y Sumar.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>La izquierda y las fuerzas pol\u00edticas plurinacionales han parado al bloque reaccionario&nbsp;<\/strong><\/h2>\n\n\n\n<p>Sin embargo, hace falta primero repasar brevemente la historia de estas elecciones. Tal y como relata Pablo Stefanoni en <a href=\"https:\/\/legrandcontinent.eu\/es\/2023\/07\/24\/la-izquierda-espanola-frena-la-ola-reaccionaria-x\/\">estas p\u00e1ginas<\/a>, S\u00e1nchez convoc\u00f3 elecciones generales anticipadas con el objetivo de evitar el desgaste de su ejecutivo, pillar a contrapi\u00e9 al resto de actores pol\u00edticos y aprovechar las negociaciones entre PP y Vox en la formaci\u00f3n de gobiernos locales y auton\u00f3micos para movilizar a la izquierda ante la amenaza de un retroceso claro en materia de derechos y libertades. S\u00e1nchez y el PSOE se erigieron en el baluarte contra la Espa\u00f1a en blanco y negro que representaba la alianza PP-Vox, que reavivaba a gran parte del electorado progresista. A su izquierda, Sumar tambi\u00e9n cohesionaba a gran parte de la izquierda transformadora y permit\u00eda aguantar un resultado digno estirando el bloque progresista bajo el liderazgo de Yolanda D\u00edaz. Paralelamente, los votantes de partidos nacionalistas e independentistas tambi\u00e9n se reactivaban ante las amenazas de regresi\u00f3n en materia territorial que supondr\u00eda un gobierno n\u00edtidamente nacionalista espa\u00f1ol como el que hubiese encabezado el candidato popular.&nbsp;<\/p>\n\n\n\n<p>Esta m\u00faltiple movilizaci\u00f3n junto a una \u00faltima semana de campa\u00f1a desastrosa para Feij\u00f3o \u2212que ha acabado desmovilizando a parte de los votantes m\u00e1s centristas de los populares\u2212, es lo que ha permitido un resultado m\u00e1s ajustado del que la mayor\u00eda de las encuestas apuntaban. Es por ello que la mejora del resultado electoral del PP no ha servido para que la suma con Vox les permita alcanzar la mayor\u00eda absoluta necesaria en el Congreso. Suceso que ha abierto una posibilidad al bloque progresista y plurinacional, que tiene ahora la oportunidad de negociar la formaci\u00f3n de un nuevo ejecutivo de coalici\u00f3n progresista entre PSOE y Sumar. Esta conjunci\u00f3n de voto de las clases trabajadoras, de los hijos del 15M y de las minor\u00edas nacionales, es la que ha conformado un bloque pol\u00edtico capaz de parar la ola reaccionaria en Espa\u00f1a, siendo as\u00ed el primer pa\u00eds europeo en los \u00faltimos dos a\u00f1os, en el que conservadores y ultras no arrasan electoralmente.&nbsp;<\/p>\n\n\n\n<p>La diferencia, sin embargo, con la anterior legislatura, es que si en noviembre de 2019 para investir a S\u00e1nchez fueron necesarios los votos de PSOE, UP, M\u00e1s Pa\u00eds, ERC, PNV, Bildu y Teruel Existe, en estas elecciones \u2212debido a la debilidad de las izquierdas que pierden 12 diputados (141 para PSOE y Sumar), y a la subida de las derechas que suman 18 diputados m\u00e1s (169 para PP y Vox)\u2212, para que haya una coalici\u00f3n de gobierno progresista es necesaria la concurrencia de un nuevo actor pol\u00edtico: Junts. El partido de centroderecha independentista vuelve a situar a Catalunya y a las reivindicaciones del movimiento independentista en el centro del tablero pol\u00edtico. Es por esto que, antes de analizar las derivadas de esta correlaci\u00f3n de fuerzas, es necesario hacer un repaso de los \u00faltimos a\u00f1os en Catalunya y del mapa pol\u00edtico que dibujan las elecciones de 2023 all\u00ed.<\/p>\n\n\n\n<p><em>[Si encuentra nuestro trabajo \u00fatil y quiere que el GC siga siendo una publicaci\u00f3n abierta, puede suscribirse&nbsp;<a href=\"https:\/\/legrandcontinent.eu\/es\/ofiertas-new\/\">aqu\u00ed.<\/a>]<\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Catalunya: auge y ca\u00edda del movimiento independentista<\/strong><\/h2>\n\n\n\n<p>Catalunya ha dominado las \u00faltimas legislaturas en la pol\u00edtica espa\u00f1ola. Desde el inicio del conocido como proceso independentista, la agenda catalana \u2212ya sea en su gesti\u00f3n o en su omisi\u00f3n\u2212, ha estado presente en la discusi\u00f3n pol\u00edtica en el Congreso, siendo tambi\u00e9n una de las principales problem\u00e1ticas a las que los diferentes gobiernos espa\u00f1oles se han enfrentado desde el a\u00f1o 2012.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Los votantes de partidos nacionalistas e independentistas tambi\u00e9n se reactivaban ante las amenazas de regresi\u00f3n en materia territorial que supondr\u00eda un gobierno n\u00edtidamente nacionalista espa\u00f1ol como el que hubiese encabezado el candidato popular.&nbsp;<\/p><cite>MARIO R\u00cdOS FERN\u00c1NDEZ<\/cite><\/blockquote><\/figure>\n\n\n\n<p>El inicio del proceso independentista coincidi\u00f3 con los cambios pol\u00edticos y sociales que trajo consigo la Gran Recesi\u00f3n y la crisis de la deuda europea en la mayor parte de democracias continentales. Fue en este contexto de crisis social, econ\u00f3mica y pol\u00edtica cuando el independentismo catal\u00e1n se convirti\u00f3 en la <em>utop\u00eda disponible<\/em> para cientos de miles de catalanes que vieron en la lucha por un Estado independiente propio una v\u00eda de escape a los problemas que afrontaba Espa\u00f1a. Esto moviliz\u00f3 a buena parte de la sociedad catalana, especialmente aquella ubicada en el nacionalismo catal\u00e1n.&nbsp;<\/p>\n\n\n\n<p>A partir de aqu\u00ed, los partidos independentistas \u2212ERC, Junts y la CUP, empujados por esta movilizaci\u00f3n masiva que sacaba a millones de personas a la calle cada 11 de septiembre\u2212, fueron entrando en una espiral incrementalista en la que cada formaci\u00f3n compet\u00eda con sus adversarios buscando una reivindicaci\u00f3n cada vez mayor. De la mejora del autogobierno se pas\u00f3 a un pacto fiscal; del refer\u00e9ndum pactado a uno unilateral; y de este refer\u00e9ndum a una declaraci\u00f3n unilateral de independencia. Cabe recordar que desde 2012 hasta ahora, el independentismo ha gobernado Catalunya siempre con mayor\u00eda absoluta.<\/p>\n\n\n\n<p>Los acontecimientos se precipitaron en octubre de 2017. Despu\u00e9s de que el <em>Parlament de Catalunya<\/em> \u2212con mayor\u00eda independentista\u2212, y el Gobierno de Catalu\u00f1a \u2212conformado por una coalici\u00f3n presidida por Carles Puigdemont entre Junts y ERC\u2212, elevaran la en\u00e9sima propuesta de refer\u00e9ndum al Gobierno espa\u00f1ol de Rajoy y este se negara a negociar, se decidi\u00f3 desde el independentismo preparar todo el entramado legal y pol\u00edtico para hacer efectiva una consulta unilateral que tendr\u00eda lugar el 1 de octubre. Los hechos, de sobra conocidos, dieron la vuelta al mundo: miles de voluntarios prepararon el refer\u00e9ndum unilateral en secreto y el d\u00eda de su convocatoria aparecieron miles de urnas y m\u00e1s de 2 millones de catalanes fueron a votar.&nbsp;<\/p>\n\n\n\n<p>La gesti\u00f3n del Gobierno de Rajoy \u2212puramente represiva\u2212 trat\u00f3 de impedir el refer\u00e9ndum unilateral enviando desde el resto de Espa\u00f1a a miles de polic\u00edas que agredieron y reprimieron a centenares de votantes. Despu\u00e9s de este refer\u00e9ndum, en el que s\u00f3lo particip\u00f3 el independentismo civil y pol\u00edtico, se produjo una movilizaci\u00f3n masiva con una huelga general el 3 de octubre que paraliz\u00f3 Catalunya. Pocos d\u00edas despu\u00e9s, el ejecutivo catal\u00e1n declarar\u00eda unilateralmente la independencia para anularla y abrir un proceso negociador con el Estado. Esta estrategia no dio el fruto deseado, y ante lo que el gobierno de Rajoy consider\u00f3 un ataque a la Constituci\u00f3n, el ejecutivo espa\u00f1ol activ\u00f3 <em>el 155<\/em>: un art\u00edculo de la Carta Magna espa\u00f1ola que permite al Gobierno central suprimir el autogobierno de una Comunidad Aut\u00f3noma si esta vulnera el inter\u00e9s general.&nbsp;<\/p>\n\n\n\n<p>Poco despu\u00e9s, la justicia espa\u00f1ola iniciar\u00eda todo el proceso judicial derivado de lo que la fiscal\u00eda consider\u00f3 rebeli\u00f3n. Proceso en el que los principales l\u00edderes del independentismo catal\u00e1n \u2212entre ellos el vicepresidente del Gobierno catal\u00e1n Oriol Junqueras\u2212, fueron detenidos. <a href=\"https:\/\/legrandcontinent.eu\/es\/2023\/07\/28\/el-factor-puigdemont-en-la-ecuacion-sanchez-una-conversacion-con-josu-de-miguel-barcena\/\">Otros l\u00edderes, como el presidente Carles Puigdemont, huyeron a B\u00e9lgica para evitarla<\/a>. Adem\u00e1s, la aprobaci\u00f3n del art\u00edculo 155 llevaba aparejada consigo la convocatoria de elecciones auton\u00f3micas. Elecciones que, con un 80% de participaci\u00f3n electoral, fueron las m\u00e1s participativas de la historia dando la victoria en esca\u00f1os (pero no en votos) al independentismo.<\/p>\n\n\n\n<p>Sin embargo, despu\u00e9s de la conformaci\u00f3n del gobierno de Quim Torra, en mayo de 2018 y tras una investidura tambi\u00e9n tortuosa, la tensi\u00f3n social y pol\u00edtica en Catalunya empez\u00f3 a aflojar. Situaci\u00f3n que en 2019, con motivo de la sentencia a los presos del proceso independentista \u2212acusados de sedici\u00f3n, malversaci\u00f3n y desobediencia\u2212, volvi\u00f3 a encender las calles en Catalunya con miles de manifestaciones, boicots y ocupaciones a lo largo del oto\u00f1o de ese mismo a\u00f1o. Un oto\u00f1o electoral en el que despu\u00e9s de la victoria del PSOE en abril y ante la incapacidad de conformar gobierno con Unidas Podemos, llev\u00f3 a una repetici\u00f3n electoral que coincidi\u00f3 en el tiempo con las manifestaciones m\u00e1s duras en Catalunya. Unas manifestaciones que impactaron en parte de la poblaci\u00f3n espa\u00f1ola, <a href=\"https:\/\/legrandcontinent.eu\/es\/2023\/07\/07\/meditaciones-de-la-espana-contemporanea-una-conversacion-con-benoit-pellistrandi\/\">que opt\u00f3 electoralmente por Vox como opci\u00f3n dura contra el independentismo<\/a>. Sin embargo, el resultado electoral a nivel de bloques no cambi\u00f3, dejando a PSOE y Unidas Podemos conformar gobierno. Gobierno que tendr\u00eda como uno de sus principales objetivos la gesti\u00f3n del conflicto en Catalunya.&nbsp;<\/p>\n\n\n\n<p>Esta gesti\u00f3n \u2212basada en el reconocimiento del conflicto en Catalunya como un conflicto pol\u00edtico y no como una cuesti\u00f3n de orden p\u00fablico tal y como lo hab\u00eda entendido el gobierno conservador anterior\u2212, dio inicio a una negociaci\u00f3n entre los dos gobiernos (el espa\u00f1ol y el catal\u00e1n), dando lugar a la aprobaci\u00f3n de unos indultos que permitieran la libertad a los presos independentistas. Se busc\u00f3 adem\u00e1s la reforma de los delitos de sedici\u00f3n y rebeli\u00f3n para rebajar las penas existentes y aplicadas estos l\u00edderes. El gobierno espa\u00f1ol articul\u00f3 un programa para desinflamar el conflicto en Catalunya, rebajar la tensi\u00f3n y que se diese as\u00ed un retorno a la convivencia, y el resultado fue un \u00e9xito.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>La gesti\u00f3n de Pedro S\u00e1nchez se bas\u00f3 en el reconocimiento del conflicto en Catalunya como un conflicto pol\u00edtico y no como una cuesti\u00f3n de orden p\u00fablico tal y como lo hab\u00eda entendido el gobierno conservador anterior.<\/p><cite>MARIO R\u00cdOS FERN\u00c1NDEZ<\/cite><\/blockquote><\/figure>\n\n\n\n<p>A partir de este momento, la mayor\u00eda de los indicadores sobre opini\u00f3n p\u00fablica que nos muestra el <em>Centre d\u2019Estudis d\u2019Opini\u00f3 <\/em>tras las generales de 2019 y de la aprobaci\u00f3n de estas medidas, muestran un claro retroceso en el apoyo al proyecto independentista. Proceso que pas\u00f3 de un S\u00cd mayoritario a que el NO a esta opci\u00f3n se situase a 10 puntos de ventaja. Tambi\u00e9n la consideraci\u00f3n del conflicto entre Catalunya y el Estado como el primer problema de los catalanes se ha visto reducida en los \u00faltimos a\u00f1os, donde la econom\u00eda o la insatisfacci\u00f3n pol\u00edtica han tomado la delantera. Estos cambios, adem\u00e1s, van de la mano de una despolitizaci\u00f3n enorme de gran parte de la sociedad catalana que ha pasado de estar ampliamente interesada e informada sobre pol\u00edtica a mostrar sentimientos negativos como desencanto, enfado o desinter\u00e9s hacia ella.<\/p>\n\n\n\n<p>Dos a\u00f1os m\u00e1s tarde, este desinter\u00e9s se materializ\u00f3 en las elecciones al <em>Parlament de Catalunya<\/em> de 2021, las menos participativas de la historia del autogobierno catal\u00e1n. La participaci\u00f3n electoral pas\u00f3 de casi el 80% en 2017 al 51,5% en 2021: una ca\u00edda de casi 30 puntos en tan solo cuatro a\u00f1os. Es cierto que las elecciones se celebraron durante la pandemia, concretamente al final de la tercera ola del Coronavirus, pero los estudios postelectorales realizados mostraron que la pandemia o el miedo al contagio s\u00f3lo fueron la causa de la abstenci\u00f3n para algo m\u00e1s del 20% de la poblaci\u00f3n. La abstenci\u00f3n de 2021 fue eminentemente pol\u00edtica y estaba basada en dos bloques que hab\u00edan sido movilizados electoralmente al m\u00e1ximo desde 2015. Sin embargo, en el momento en que el independentismo asumi\u00f3 la imposibilidad de su proyecto, ambos se desmovilizaron: los unos por desmotivaci\u00f3n ante el final de etapa, y los otros porque ya no era necesario defender el status quo existente.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Las elecciones generales en Catalunya: una defensa ante el conflicto territorial<\/strong><\/h2>\n\n\n\n<p>Todo este viaje por la historia pol\u00edtica catalana de los \u00faltimos 10 a\u00f1os nos sirve para ubicar las elecciones generales de 2023. Estas elecciones se han producido, como hemos visto, en un momento en que la sociedad catalana da claros signos de fatiga a nivel pol\u00edtico. Un momento en que las pasiones pol\u00edticas se han enfriado despu\u00e9s de a\u00f1os en los que la pol\u00edtica \u2212ya fuese por el 15M o, especialmente, por el proceso independentista\u2212, fue el centro de atenci\u00f3n de gran parte de la sociedad catalana.&nbsp;<\/p>\n\n\n\n<p>Lo primero que hay que apuntar sobre estas elecciones generales es que son una de las menos participativas en la historia electoral de Catalunya. El final de ciclo del proceso independentista nos ha dejado una sociedad m\u00e1s despolitizada y desmovilizada que se ha dejado notar en la participaci\u00f3n, una de las m\u00e1s bajas registrada nunca en unas generales: s\u00f3lo por encima del 64,7% de marzo de 2000 en las que el PP obtuvo la mayor\u00eda absoluta. El porcentaje de votantes ha sido del 65,4%: 7 puntos por debajo de noviembre de 2019 y 12 puntos inferior a las de abril del mismo a\u00f1o. De hecho, es una participaci\u00f3n electoral similar a la de la repetici\u00f3n electoral de junio de 2016 en las que tambi\u00e9n gan\u00f3 el PP de Rajoy. Si analizamos la participaci\u00f3n a nivel territorial vemos que mientras en las zonas metropolitanas y costeras la ca\u00edda es de alrededor de 4 puntos de participaci\u00f3n, en los feudos independentistas de Girona o de la Catalunya Central (ciudades como Figueres, Girona, Olot, Manresa o Vic), la ca\u00edda es de entre 8 y 10 puntos.<\/p>\n\n\n\n<p>Para analizar e interpretar pol\u00edticamente el resultado, es interesante saber de qu\u00e9 iban las elecciones generales en Catalunya en este 2023 y cu\u00e1l era la pregunta a la que se enfrentaban los electores a la hora de decidir su voto. A diferencia de las \u00faltimas generales en las que el independentismo impuso el marco antirrepresivo tras los juicios a los l\u00edderes independentistas \u2212obteniendo su mejor resultado hist\u00f3rico en unas generales con el 43% de los votos y 22 diputados\u2212, en esta ocasi\u00f3n los comicios han girado alrededor de mantener el Gobierno de coalici\u00f3n. El debate se situaba en si los catalanes y catalanas prefer\u00edan un gobierno de S\u00e1nchez y D\u00edaz o uno de Feij\u00f3o y Abascal. Una pregunta claramente estatal que impon\u00eda un marco y una din\u00e1mica de pol\u00edtica espa\u00f1ola que como veremos ha favorecido principalmente a dos fuerzas pol\u00edticas como son el PSOE y Sumar.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Estas elecciones de 2023 se han producido en un momento en que la sociedad catalana da claros signos de fatiga a nivel pol\u00edtico.<\/p><cite>MARIO R\u00cdOS FERN\u00c1NDEZ<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Paralelamente a la ca\u00edda de la participaci\u00f3n electoral que hemos comentado antes, se ha vuelto a producir un cl\u00e1sico del comportamiento electoral en Catalunya: el voto dual. Hist\u00f3ricamente, en Catalunya se produc\u00eda una din\u00e1mica pol\u00edtica en la que una parte considerable del electorado catal\u00e1n en las elecciones auton\u00f3micas se inclinaba por partidos nacionalistas o independentistas, pero cuando llegaban las generales votaban a partidos de \u00e1mbito estatal y, especialmente, a los socialistas. El proceso independentista acab\u00f3 en gran medida con este comportamiento y eso permiti\u00f3 a los partidos independentistas obtener sus mejores resultados en el Congreso como fue el caso de ERC en 2019. Sin embargo, en este 2023 se ha vuelto a dar este comportamiento electoral. Una espectacular victoria del PSC \u2212que ha obtenido 19 diputados y un 34,5% de voto\u2212, y un buen resultado de Sumar-ECP (la candidatura catalana de Yolanda D\u00edaz) \u2212con 7 diputados y un 14% de voto\u2212, que han superado a ERC \u2212ganadora en 2019 con 13 esca\u00f1os y m\u00e1s de 800.000 votos, y quien ha perdido la mitad qued\u00e1ndose en 7 representantes y 460.000 sufragios\u2212, se explica por este cambio en el comportamiento electoral.<\/p>\n\n\n\n<p>Como muestran los polit\u00f3logos Jordi Mu\u00f1oz y Toni Rod\u00f3n en sus an\u00e1lisis sobre las transferencias de voto a partir de los resultados electorales, el independentismo ha enviado una gran cantidad de voto a PSC y Sumar-ECP. Tanto ERC y Junts, como la CUP, han transferido voto \u00fatil a las candidaturas de \u00e1mbito estatal. M\u00e1s de 250.000 hacia los socialistas y 120.000 a Sumar-ECP. Sin embargo, este hecho que confirma la vuelta del voto dual, no nos explica la raz\u00f3n del por qu\u00e9 se ha dado en este momento tras unas elecciones generales que lo hab\u00edan reducido enormemente como fueron las de 2019.<\/p>\n\n\n\n<p>Una de las causas que explican este cambio es que los catalanes y las catalanas han entendido que cualquier resoluci\u00f3n a su conflicto pol\u00edtico pasa porque el Gobierno de coalici\u00f3n progresista se mantenga. Sea cual sea la resoluci\u00f3n, s\u00f3lo podr\u00e1 venir si la izquierda est\u00e1 en el poder en Madrid. Eso y el miedo a una ultraderecha que agitaba la aplicaci\u00f3n de nuevo del 155 para suprimir el autogobierno catal\u00e1n, ha llevado a muchos ciudadanos independentistas a apoyar a las opciones estatales de cara a evitar un recrudecimiento del conflicto y un retroceso en materia territorial, cultural y ling\u00fc\u00edstica como ya se ha producido en los gobiernos entre PP y Vox en la Comunidad Valenciana o en Baleares.<\/p>\n\n\n\n<p><em>[Si encuentra nuestro trabajo \u00fatil y quiere que el GC siga siendo una publicaci\u00f3n abierta, puede suscribirse&nbsp;<a href=\"https:\/\/legrandcontinent.eu\/es\/ofiertas-new\/\">aqu\u00ed.<\/a>]<\/em><\/p>\n\n\n\n<p>Por lo tanto, si queremos entender lo que ha pasado en Catalunya en estas elecciones, debemos comprender que un independentismo en depresi\u00f3n por el final del proyecto que ha sido hegem\u00f3nico en Catalunya en los \u00faltimos 10 a\u00f1os, ha decidido no jugar a la ruleta rusa apostando por un independentismo sin estrategia pol\u00edtica clara y se ha inclinado por fuerzas estatales que garanticen que el conflicto no se iniciar\u00e1 de nuevo y cuya agenda reformista ha permitido desinflamar la situaci\u00f3n e iniciar una gesti\u00f3n pol\u00edtica del contencioso territorial. La defensa del autogobierno catal\u00e1n esta vez no la han representado los partidos independentistas, como tradicionalmente han hecho, sino las fuerzas de izquierdas estatales.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Una agenda reformista a nivel territorial: el resultado de un posible acuerdo entre izquierdas y fuerzas plurinacionales<\/strong><\/h2>\n\n\n\n<p>Pero m\u00e1s all\u00e1 de la interpretaci\u00f3n de los resultados de este 23J es necesario repasar qu\u00e9 escenarios pueden abrirse con la actual correlaci\u00f3n de fuerzas. As\u00ed como Bildu y PNV han dejado claro ya que apoyar\u00e1n la actual mayor\u00eda de gobierno, en el independentismo catal\u00e1n se ha producido un cambio estrat\u00e9gico. ERC, que durante toda la legislatura ha sido un sost\u00e9n \u2212tanto en la investidura como en la mayor\u00eda de las leyes y presupuestos aprobados por el Gobierno de S\u00e1nchez\u2212, ha empezado a mostrar dudas sobre su apoyo, y lo ha hecho precisamente en el momento en el que Junts, el partido de centroderecha independentista y m\u00e1s ubicado en la v\u00eda unilateral \u2212al menos a nivel discursivo y simb\u00f3lico\u2212, es un actor imprescindible para que la investidura salga y evitar as\u00ed la repetici\u00f3n electoral.&nbsp;<\/p>\n\n\n\n<p>Esta situaci\u00f3n de dependencia de ambas formaciones independentistas para S\u00e1nchez puede llevar a que ERC y Junts inicien una competici\u00f3n al alza en sus demandas al PSOE y Sumar, lo que puede hacer descarrilar cualquier negociaci\u00f3n. Si se inicia una subasta con ambas formaciones apostando fuerte en la negociaci\u00f3n, puede darse un bloqueo que lleve a una repetici\u00f3n electoral: hay cosas que S\u00e1nchez no puede aceptar como son un refer\u00e9ndum o una amnist\u00eda para que Puigdemont pueda volver a Catalunya.&nbsp;<\/p>\n\n\n\n<p>Sin embargo, si tomamos en consideraci\u00f3n el resultado electoral, observamos que tanto ERC como Junts han enviado a casi 300.000 personas a la abstenci\u00f3n, y a unas 260.000 a PSC y Sumar. Esto es una advertencia clara de que, si hay repetici\u00f3n electoral, el empeoramiento de su resultado electoral puede ir a m\u00e1s. Los votantes de ambos partidos no entender\u00edan c\u00f3mo estos llevan a Catalunya a una repetici\u00f3n electoral que puede acabar con Santiago Abascal de vicepresidente del Gobierno atacando el autogobierno, la lengua y la cultura catalana con una mayor\u00eda absoluta.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>El contexto pol\u00edtico actual, por lo tanto, permite al independentismo una mayor capacidad de influencia en la direcci\u00f3n del Estado y le permite lograr algunos de sus objetivos y reivindicaciones hist\u00f3ricas.<\/p><cite>MARIO R\u00cdOS FERN\u00c1NDEZ<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Adem\u00e1s, ambas formaciones tienen la posibilidad de aprovechar el contexto pol\u00edtico que se ha abierto e impulsar junto a la coalici\u00f3n de izquierdas una serie de reformas y medidas en la estructura territorial, pol\u00edtica e institucional del Estado. Un bloque hist\u00f3rico de izquierdas y plurinacional podr\u00eda acometer la reforma del Poder Judicial y sus \u00f3rganos principales (CGPJ, por ejemplo) con el objetivo de que se parezcan m\u00e1s a la Espa\u00f1a real. Es decir, que la magistratura no est\u00e9 copada por los sectores m\u00e1s conservadores y tradicionalistas del Estado y tenga en cuenta las diferentes minor\u00edas nacionales existentes en Espa\u00f1a&nbsp; \u2212especialmente la catalana y la vasca\u2212. Una reforma de la situaci\u00f3n financiera de la Generalitat y de la capacidad de gesti\u00f3n de sus propios recursos econ\u00f3micos y financieros tambi\u00e9n podr\u00eda ponerse sobre la mesa.<\/p>\n\n\n\n<p>Adem\u00e1s, podr\u00eda impulsarse la Mesa de Di\u00e1logo entre ambos ejecutivos iniciada en 2020, y conseguir reforzar el autogobierno catal\u00e1n con traspasos, inversiones y competencias. Un impulso que podr\u00eda llegar al blindaje competencial, cultural y ling\u00fc\u00edstico y a un reconocimiento de las realidades nacionales que conforman Espa\u00f1a mediante legislaci\u00f3n estatal como el que se dio en la C\u00e1mara de los Comunes canadiense respecto al Quebec como <em>sociedad distinta.<\/em>&nbsp;<\/p>\n\n\n\n<p>El contexto pol\u00edtico actual, por lo tanto, permite al independentismo una mayor capacidad de influencia en la direcci\u00f3n del Estado y le permite lograr algunos de sus objetivos y reivindicaciones hist\u00f3ricas aunque no sean las dos principales (refer\u00e9ndum y amnist\u00eda). Del an\u00e1lisis de la situaci\u00f3n pol\u00edtica concreta depende que tanto ERC como Junts, apuesten por reformar el Estado y no por darle una nueva oportunidad al bloque conservador de llevar a Espa\u00f1a a un retroceso pol\u00edtico, democr\u00e1tico y territorial sin precedentes en las \u00faltimas d\u00e9cadas.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Catalu\u00f1a decidir\u00e1 el destino de Espa\u00f1a. En un an\u00e1lisis detallado de la \u00faltima d\u00e9cada de conflictos y tensiones pol\u00edticas, Mario R\u00edos Fern\u00e1ndez intenta comprender las razones de una votaci\u00f3n parad\u00f3jica en la comunidad aut\u00f3noma. Pocas veces los partidos independentistas han sido tan mal elegidos, pero ser\u00e1n los que decidir\u00e1n en el Congreso. \u00bfJugar\u00e1n a la pol\u00edtica de lo peor o elegir\u00e1n abrir una nueva p\u00e1gina en la historia del independentismo?<\/p>\n","protected":false},"author":1366,"featured_media":20625,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-angles.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":16,"footnotes":""},"categories":[577],"tags":[],"staff":[602],"editorial_format":[1470],"serie":[],"audience":[],"geo":[173],"class_list":["post-20620","post","type-post","status-publish","format-standard","hentry","category-geopolitica-del-23j-elecciones","staff-mario-rios-fernandez","editorial_format-perspectivas-sobre-la-actualidad","geo-mediterraneo"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":20625,"excerpt":"Catalu\u00f1a decidir\u00e1 el destino de Espa\u00f1a. En un an\u00e1lisis detallado de la \u00faltima d\u00e9cada de conflictos y tensiones pol\u00edticas, Mario R\u00edos Fern\u00e1ndez intenta comprender las razones de una votaci\u00f3n parad\u00f3jica en la comunidad aut\u00f3noma. Pocas veces los partidos independentistas han sido tan mal elegidos, pero ser\u00e1n los que decidir\u00e1n en el Congreso. \u00bfJugar\u00e1n a la pol\u00edtica de lo peor o elegir\u00e1n abrir una nueva p\u00e1gina en la historia del independentismo?","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Catalunya de nuevo en el centro del tablero - El Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/es\/2023\/07\/28\/catalunya-de-nuevo-en-el-centro-del-tablero-x\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Catalunya de nuevo en el centro del tablero - El Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Catalu\u00f1a decidir\u00e1 el destino de Espa\u00f1a. En un an\u00e1lisis detallado de la \u00faltima d\u00e9cada de conflictos y tensiones pol\u00edticas, Mario R\u00edos Fern\u00e1ndez intenta comprender las razones de una votaci\u00f3n parad\u00f3jica en la comunidad aut\u00f3noma. Pocas veces los partidos independentistas han sido tan mal elegidos, pero ser\u00e1n los que decidir\u00e1n en el Congreso. \u00bfJugar\u00e1n a la pol\u00edtica de lo peor o elegir\u00e1n abrir una nueva p\u00e1gina en la historia del independentismo?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/es\/2023\/07\/28\/catalunya-de-nuevo-en-el-centro-del-tablero-x\/\" \/>\n<meta property=\"og:site_name\" content=\"El Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-28T14:46:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-28T18:30:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/07\/gc-elcatalunya-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"florent\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/07\/gc-elcatalunya-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"florent\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"16 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/07\/28\/catalunya-de-nuevo-en-el-centro-del-tablero-x\/\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/2023\/07\/28\/catalunya-de-nuevo-en-el-centro-del-tablero-x\/\",\"name\":\"Catalunya de nuevo en el centro del tablero - El Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/07\/28\/catalunya-de-nuevo-en-el-centro-del-tablero-x\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/07\/28\/catalunya-de-nuevo-en-el-centro-del-tablero-x\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/07\/SIPA_shutterstock41038179_000006-scaled-1.jpeg\",\"datePublished\":\"2023-07-28T14:46:00+00:00\",\"dateModified\":\"2023-07-28T18:30:46+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/07\/28\/catalunya-de-nuevo-en-el-centro-del-tablero-x\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/es\/2023\/07\/28\/catalunya-de-nuevo-en-el-centro-del-tablero-x\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/07\/28\/catalunya-de-nuevo-en-el-centro-del-tablero-x\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/07\/SIPA_shutterstock41038179_000006-scaled-1.jpeg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/07\/SIPA_shutterstock41038179_000006-scaled-1.jpeg\",\"width\":2560,\"height\":1707,\"caption\":\"En enero de 2023, separatistas catalanes se re\u00fanen bajo una bandera gigante durante una manifestaci\u00f3n contra la cumbre Espa\u00f1a-Francia que pide que Catalu\u00f1a sea independiente. \u00a9 Matthias Oesterle\/Shutterstock\/SIPA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/07\/28\/catalunya-de-nuevo-en-el-centro-del-tablero-x\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/legrandcontinent.eu\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Catalunya de nuevo en el centro del tablero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/\",\"name\":\"El Grand Continent\",\"description\":\"La escala pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\",\"name\":\"florent\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"caption\":\"florent\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Catalunya de nuevo en el centro del tablero - El Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/es\/2023\/07\/28\/catalunya-de-nuevo-en-el-centro-del-tablero-x\/","og_locale":"es_ES","og_type":"article","og_title":"Catalunya de nuevo en el centro del tablero - El Grand Continent","og_description":"Catalu\u00f1a decidir\u00e1 el destino de Espa\u00f1a. En un an\u00e1lisis detallado de la \u00faltima d\u00e9cada de conflictos y tensiones pol\u00edticas, Mario R\u00edos Fern\u00e1ndez intenta comprender las razones de una votaci\u00f3n parad\u00f3jica en la comunidad aut\u00f3noma. Pocas veces los partidos independentistas han sido tan mal elegidos, pero ser\u00e1n los que decidir\u00e1n en el Congreso. \u00bfJugar\u00e1n a la pol\u00edtica de lo peor o elegir\u00e1n abrir una nueva p\u00e1gina en la historia del independentismo?","og_url":"https:\/\/legrandcontinent.eu\/es\/2023\/07\/28\/catalunya-de-nuevo-en-el-centro-del-tablero-x\/","og_site_name":"El Grand Continent","article_published_time":"2023-07-28T14:46:00+00:00","article_modified_time":"2023-07-28T18:30:46+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/07\/gc-elcatalunya-scaled.jpg","type":"image\/jpeg"}],"author":"florent","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/07\/gc-elcatalunya-scaled.jpg","twitter_misc":{"Escrito por":"florent","Tiempo de lectura":"16 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/es\/2023\/07\/28\/catalunya-de-nuevo-en-el-centro-del-tablero-x\/","url":"https:\/\/legrandcontinent.eu\/es\/2023\/07\/28\/catalunya-de-nuevo-en-el-centro-del-tablero-x\/","name":"Catalunya de nuevo en el centro del tablero - El Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/es\/2023\/07\/28\/catalunya-de-nuevo-en-el-centro-del-tablero-x\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/es\/2023\/07\/28\/catalunya-de-nuevo-en-el-centro-del-tablero-x\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/07\/SIPA_shutterstock41038179_000006-scaled-1.jpeg","datePublished":"2023-07-28T14:46:00+00:00","dateModified":"2023-07-28T18:30:46+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/es\/2023\/07\/28\/catalunya-de-nuevo-en-el-centro-del-tablero-x\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/es\/2023\/07\/28\/catalunya-de-nuevo-en-el-centro-del-tablero-x\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/2023\/07\/28\/catalunya-de-nuevo-en-el-centro-del-tablero-x\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/07\/SIPA_shutterstock41038179_000006-scaled-1.jpeg","contentUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/07\/SIPA_shutterstock41038179_000006-scaled-1.jpeg","width":2560,"height":1707,"caption":"En enero de 2023, separatistas catalanes se re\u00fanen bajo una bandera gigante durante una manifestaci\u00f3n contra la cumbre Espa\u00f1a-Francia que pide que Catalu\u00f1a sea independiente. \u00a9 Matthias Oesterle\/Shutterstock\/SIPA"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/es\/2023\/07\/28\/catalunya-de-nuevo-en-el-centro-del-tablero-x\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legrandcontinent.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Catalunya de nuevo en el centro del tablero"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/es\/#website","url":"https:\/\/legrandcontinent.eu\/es\/","name":"El Grand Continent","description":"La escala pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c","name":"florent","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","caption":"florent"}}]}},"lgc_categories":[{"id":577,"name":"Geopol\u00edtica del 23J","slug":"geopolitica-del-23j-elecciones"}],"lgc_author":{"id":602,"name":"Mario R\u00edos Fern\u00e1ndez","slug":"mario-rios-fernandez","description":"Profesor de Ciencias Pol\u00edticas en la Universidad de Girona y analista pol\u00edtico. \r\n","first_name":"Mario","last_name":"R\u00edos Fern\u00e1ndez","picture":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2023\/07\/1670698682621.png","width":512,"height":515,"alt":""}},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/07\/SIPA_shutterstock41038179_000006-scaled-1.jpeg","width":2560,"height":1707,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/07\/SIPA_shutterstock41038179_000006-scaled-1.jpeg","width":2560,"height":1707,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/20620","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/users\/1366"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/comments?post=20620"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/20620\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media\/20625"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media?parent=20620"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/categories?post=20620"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/tags?post=20620"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/staff?post=20620"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/editorial_format?post=20620"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/serie?post=20620"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/audience?post=20620"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/geo?post=20620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}