{"id":19755,"date":"2023-07-10T16:57:00","date_gmt":"2023-07-10T15:57:00","guid":{"rendered":"https:\/\/legrandcontinent.eu\/es\/?p=19755"},"modified":"2023-07-10T19:45:33","modified_gmt":"2023-07-10T18:45:33","slug":"cuales-son-las-perspectivas-para-la-cumbre-de-vilna","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/es\/2023\/07\/10\/cuales-son-las-perspectivas-para-la-cumbre-de-vilna\/","title":{"rendered":"\u00bfCu\u00e1les son las perspectivas para la Cumbre de Vilna?"},"content":{"rendered":"\n<p>En la cumbre de Bucarest de 2008, los 26 pa\u00edses de la Alianza \u00abacordaron que Ucrania y Georgia se convertir\u00e1n en miembros de la OTAN\u00bb, aunque sin fijar un calendario preciso&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-19755' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/es\/2023\/07\/10\/cuales-son-las-perspectivas-para-la-cumbre-de-vilna\/#easy-footnote-bottom-1-19755' title='&lt;a href=&quot;https:\/\/www.nato.int\/cps\/en\/natolive\/official_texts_8443.htm?mode=pressrelease&quot;&gt;Declaraci\u00f3n de la Cumbre de Bucarest&lt;\/a&gt;, 3 de abril de 2008.'><sup>1<\/sup><\/a><\/span><\/span>. Quince a\u00f1os despu\u00e9s, ahora que la Alianza Atl\u00e1ntica cuenta con 31 miembros, la declaraci\u00f3n de la cumbre de Vilna tendr\u00e1 que encontrar un equilibrio que permita a Ucrania integrarse en la OTAN dejando de lado una futura fecha de adhesi\u00f3n, en l\u00ednea con la postura defendida por Berl\u00edn y Washington a pesar de la presi\u00f3n ejercida por los dem\u00e1s aliados&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-19755' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/es\/2023\/07\/10\/cuales-son-las-perspectivas-para-la-cumbre-de-vilna\/#easy-footnote-bottom-2-19755' title='Henry Foy y Ben Hall, \u00ab &lt;a href=&quot;https:\/\/www.ft.com\/content\/277fa5db-4113-4d5b-a5b6-f8f9adf90cdf&quot;&gt;US and Germany resist pressure to advance Ukraine\u2019s Nato bid&lt;\/a&gt; \u00bb, &lt;em&gt;Financial Times&lt;\/em&gt;, 9 de julio de 2023.'><sup>2<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/RJCr6\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>En una entrevista con la <em>CNN<\/em> emitida el domingo, Joe Biden declar\u00f3 que consideraba \u00abprematuro\u00bb iniciar el proceso de adhesi\u00f3n de Ucrania a la OTAN hasta que no se hubiera firmado un acuerdo de paz con Rusia&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-19755' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/es\/2023\/07\/10\/cuales-son-las-perspectivas-para-la-cumbre-de-vilna\/#easy-footnote-bottom-3-19755' title='&lt;a href=&quot;https:\/\/www.youtube.com\/watch?v=-SKC_rvEXrY&amp;amp;ab_channel=CNN&quot;&gt;Fareed Zakaria sits down with President Joe Biden&lt;\/a&gt;, &lt;em&gt;CNN&lt;\/em&gt;, 9 de julio de 2023.'><sup>3<\/sup><\/a><\/span><\/span>.\u00a0<\/li>\n\n\n\n<li>Esta postura tambi\u00e9n es defendida por el canciller alem\u00e1n Olaf Scholz, para quien la \u00abprioridad absoluta\u00bb en la cumbre de Vilna debe ser \u00abreforzar el poder de combate de Ucrania\u00bb, y no en cambio el ingreso del pa\u00eds en la OTAN&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-4-19755' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/es\/2023\/07\/10\/cuales-son-las-perspectivas-para-la-cumbre-de-vilna\/#easy-footnote-bottom-4-19755' title='\u00ab &lt;a href=&quot;https:\/\/www.reuters.com\/world\/europe\/scholz-pledges-security-assurances-kyiv-no-swift-nato-membership-2023-06-22\/&quot;&gt;Scholz pledges security assurances to Kyiv but no swift NATO membership&lt;\/a&gt; \u00bb, &lt;em&gt;Reuters&lt;\/em&gt;, 22 de junio de 2023.'><sup>4<\/sup><\/a><\/span><\/span>.<\/li>\n\n\n\n<li>Anteriormente de acuerdo con Berl\u00edn sobre la (no) concesi\u00f3n del estatus de miembro a Ucrania, Par\u00eds se ha acercado en los \u00faltimos meses a la posici\u00f3n de los Estados b\u00e1lticos y Polonia en particular, que piden que se proporcione a Kiev un \u00abcamino despejado\u00bb hacia la Alianza&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-5-19755' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/es\/2023\/07\/10\/cuales-son-las-perspectivas-para-la-cumbre-de-vilna\/#easy-footnote-bottom-5-19755' title='Philippe Ricard y C\u00e9dric Pietralunga, \u00ab &lt;a href=&quot;https:\/\/www.lemonde.fr\/en\/international\/article\/2023\/06\/20\/france-resolves-to-support-ukraine-s-nato-membership_6034362_4.html&quot;&gt;France resolves to support Ukraine&amp;#8217;s NATO membership&lt;\/a&gt; \u00bb, &lt;em&gt;Le Monde&lt;\/em&gt;, 20 de junio de 2023.'><sup>5<\/sup><\/a><\/span><\/span>.<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium \">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/flo.uri.sh\/visualisation\/14397521\/embed\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>A pesar del apoyo de que goza Ucrania, sobre todo en Europa del Este, la oposici\u00f3n de Washington pone fin -por el momento- a cualquier perspectiva de acceso a la alianza militar. Para que la cumbre de Vilna no se considere una oportunidad perdida para reafirmar el apoyo de la Alianza a Ucrania, las principales potencias militares de la OTAN (Estados Unidos, Reino Unido, Francia y Alemania) anunciar\u00e1n compromisos bilaterales en materia de seguridad, que deber\u00edan adoptar la forma de una codificaci\u00f3n y un compromiso de seguir prestando a largo plazo la ayuda ya concedida a Kiev&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-6-19755' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/es\/2023\/07\/10\/cuales-son-las-perspectivas-para-la-cumbre-de-vilna\/#easy-footnote-bottom-6-19755' title='Hans von der Burchard, Paul McLeary y Laura Kayali, \u00ab &lt;a href=&quot;https:\/\/www.politico.eu\/article\/western-powers-nato-security-pledges-ukraine-putin-russia-war\/&quot;&gt;Western powers race to finish security pledges for Ukraine&lt;\/a&gt; \u00bb, &lt;em&gt;Politico&lt;\/em&gt;, 9 de julio de 2023.'><sup>6<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/MYb10\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Si bien Turqu\u00eda y Hungr\u00eda siguen bloqueando la ratificaci\u00f3n de la adhesi\u00f3n de Suecia a la OTAN, el presidente turco Recep Tayyip Erdo\u011fan ha anunciado sus condiciones para levantar el veto.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Antes de pronunciarse p\u00fablicamente sobre el tema el lunes 10 de julio, Erdo\u011fan hab\u00eda comunicado el d\u00eda anterior a Joe Biden su deseo de \u00abdesbloquear\u00bb la adhesi\u00f3n de Turqu\u00eda a la Uni\u00f3n para \u00aballanar el camino\u00bb al ingreso de Estocolmo en la Alianza Atl\u00e1ntica&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-7-19755' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/es\/2023\/07\/10\/cuales-son-las-perspectivas-para-la-cumbre-de-vilna\/#easy-footnote-bottom-7-19755' title='Huseyin Hayatsever y Ece Toksabay, \u00ab &lt;a href=&quot;https:\/\/www.reuters.com\/world\/europe\/erdogan-links-swedens-nato-membership-turkeys-eu-accession-2023-07-10\/?taid=64abe4ed8cb4af0001865bf6&amp;amp;utm_campaign=trueAnthem:+Trending+Content&amp;amp;utm_medium=trueAnthem&amp;amp;utm_source=twitter&quot;&gt;Erdogan links Sweden&amp;#8217;s NATO membership to Turkey&amp;#8217;s EU accession&lt;\/a&gt; \u00bb, &lt;em&gt;Reuters&lt;\/em&gt;, 10 de julio de 2023.'><sup>7<\/sup><\/a><\/span><\/span>.<\/li>\n\n\n\n<li>Desde hace varios meses, Ankara tambi\u00e9n pretende comprar a Washington aviones de combate estadounidenses F-16, algo de lo que Biden es partidario, pero para lo que necesita el apoyo del Congreso&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-8-19755' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/es\/2023\/07\/10\/cuales-son-las-perspectivas-para-la-cumbre-de-vilna\/#easy-footnote-bottom-8-19755' title='&lt;a href=&quot;https:\/\/www.whitehouse.gov\/briefing-room\/press-briefings\/2023\/07\/09\/press-gaggle-by-press-secretary-karine-jean-pierre-and-national-security-advisor-jake-sullivan-en-route-london-united-kingdom\/&quot;&gt;Press Gaggle by Press Secretary Karine Jean-Pierre and National Security Advisor Jake Sullivan En Route London&lt;\/a&gt;, Reino Unido, Casa Blanca, 9 de julio de 2023.'><sup>8<\/sup><\/a><\/span><\/span>. Aunque el acuerdo de la Casa Blanca podr\u00eda utilizarse como medio de presi\u00f3n en las negociaciones, tanto los estadounidenses como los turcos se niegan a vincular ambas cuestiones&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-9-19755' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/es\/2023\/07\/10\/cuales-son-las-perspectivas-para-la-cumbre-de-vilna\/#easy-footnote-bottom-9-19755' title='&lt;a href=&quot;https:\/\/www.consilium.europa.eu\/en\/press\/press-releases\/2019\/06\/18\/council-conclusions-on-enlargement-and-stabilisation-and-association-process\/&quot;&gt;Council conclusions on enlargement and stabilisation and association process&lt;\/a&gt;, Consejo de la Uni\u00f3n Europea, 18 de junio de 2019.'><sup>9<\/sup><\/a><\/span><\/span>.<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/f1DpX\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Aunque Turqu\u00eda est\u00e1 reconocida como pa\u00eds candidato desde 1999, las negociaciones se han estancado porque Ankara \u00absigue distanci\u00e1ndose de la Uni\u00f3n Europea\u00bb. Para Olaf Scholz, el primer dirigente europeo en reaccionar a la declaraci\u00f3n de Erdo\u011fan, la pertenencia de Suecia a la OTAN y la de Turqu\u00eda a la Uni\u00f3n Europea no deben considerarse \u00abcuestiones vinculadas\u00bb entre s\u00ed&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-10-19755' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-2'><a href='https:\/\/legrandcontinent.eu\/es\/2023\/07\/10\/cuales-son-las-perspectivas-para-la-cumbre-de-vilna\/#easy-footnote-bottom-10-19755' title='\u00ab &lt;a href=&quot;https:\/\/www.welt.de\/politik\/ausland\/article246310332\/Tuerkei-Erdogan-fordert-neue-EU-Beitrittsgespraeche-Aussenpolitiker-sprechen-von-Erpressung.html&quot;&gt;Erdogan fordert neue EU-Beitrittsgespr\u00e4che \u2013Au\u00dfenpolitiker sprechen von \u201eErpressung\u201c&lt;\/a&gt; \u00bb, &lt;em&gt;Die Welt&lt;\/em&gt;, 10 de julio de 2023.'><sup>10<\/sup><\/a><\/span><\/span>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La 74\u00aa cumbre de la OTAN se inaugura en Vilna el martes 11 de julio. Tras m\u00e1s de 500 d\u00edas de invasi\u00f3n rusa de su territorio, Ucrania no recibir\u00e1 un calendario preciso para su adhesi\u00f3n a la Alianza. Sin embargo, se espera que las principales potencias militares formalicen sus compromisos en materia de seguridad.<\/p>\n","protected":false},"author":1366,"featured_media":19754,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":4,"_lgc_tts_audio_url":"","_lgc_tts_voice":"","_lgc_tts_publish":false,"_lgc_tts_history_item_id":"","_lgc_tts_generated_at":"","_lgc_tts_status":"","_lgc_tts_error":"","footnotes":""},"categories":[179],"tags":[],"staff":[],"editorial_format":[1472],"serie":[],"audience":[],"geo":[177],"class_list":["post-19755","post","type-post","status-publish","format-standard","hentry","category-seguridad","editorial_format-analisis","geo-europa"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":19754,"excerpt":"La 74\u00aa cumbre de la OTAN se inaugura en Vilna el martes 11 de julio. Tras m\u00e1s de 500 d\u00edas de invasi\u00f3n rusa de su territorio, Ucrania no recibir\u00e1 un calendario preciso para su adhesi\u00f3n a la Alianza. Sin embargo, se espera que las principales potencias militares formalicen sus compromisos en materia de seguridad.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfCu\u00e1les son las perspectivas para la Cumbre de Vilna? - El Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/es\/2023\/07\/10\/cuales-son-las-perspectivas-para-la-cumbre-de-vilna\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfCu\u00e1les son las perspectivas para la Cumbre de Vilna? - El Grand Continent\" \/>\n<meta property=\"og:description\" content=\"La 74\u00aa cumbre de la OTAN se inaugura en Vilna el martes 11 de julio. Tras m\u00e1s de 500 d\u00edas de invasi\u00f3n rusa de su territorio, Ucrania no recibir\u00e1 un calendario preciso para su adhesi\u00f3n a la Alianza. Sin embargo, se espera que las principales potencias militares formalicen sus compromisos en materia de seguridad.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/es\/2023\/07\/10\/cuales-son-las-perspectivas-para-la-cumbre-de-vilna\/\" \/>\n<meta property=\"og:site_name\" content=\"El Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-10T15:57:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-10T18:45:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2023\/07\/gc-sommet-de-vilnius-e1689000437893.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1453\" \/>\n\t<meta property=\"og:image:height\" content=\"812\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"florent\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2023\/07\/gc-sommet-de-vilnius-e1689000437893.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"florent\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/07\/10\/cuales-son-las-perspectivas-para-la-cumbre-de-vilna\/\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/2023\/07\/10\/cuales-son-las-perspectivas-para-la-cumbre-de-vilna\/\",\"name\":\"\u00bfCu\u00e1les son las perspectivas para la Cumbre de Vilna? - El Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/07\/10\/cuales-son-las-perspectivas-para-la-cumbre-de-vilna\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/07\/10\/cuales-son-las-perspectivas-para-la-cumbre-de-vilna\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2023\/07\/gc-sommet-de-vilnius-e1689000437893.jpg\",\"datePublished\":\"2023-07-10T15:57:00+00:00\",\"dateModified\":\"2023-07-10T18:45:33+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/07\/10\/cuales-son-las-perspectivas-para-la-cumbre-de-vilna\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/es\/2023\/07\/10\/cuales-son-las-perspectivas-para-la-cumbre-de-vilna\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/07\/10\/cuales-son-las-perspectivas-para-la-cumbre-de-vilna\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2023\/07\/gc-sommet-de-vilnius-e1689000437893.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2023\/07\/gc-sommet-de-vilnius-e1689000437893.jpg\",\"width\":1453,\"height\":812},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/07\/10\/cuales-son-las-perspectivas-para-la-cumbre-de-vilna\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/legrandcontinent.eu\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfCu\u00e1les son las perspectivas para la Cumbre de Vilna?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/\",\"name\":\"El Grand Continent\",\"description\":\"La escala pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\",\"name\":\"florent\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"caption\":\"florent\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfCu\u00e1les son las perspectivas para la Cumbre de Vilna? - El Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/es\/2023\/07\/10\/cuales-son-las-perspectivas-para-la-cumbre-de-vilna\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfCu\u00e1les son las perspectivas para la Cumbre de Vilna? - El Grand Continent","og_description":"La 74\u00aa cumbre de la OTAN se inaugura en Vilna el martes 11 de julio. Tras m\u00e1s de 500 d\u00edas de invasi\u00f3n rusa de su territorio, Ucrania no recibir\u00e1 un calendario preciso para su adhesi\u00f3n a la Alianza. Sin embargo, se espera que las principales potencias militares formalicen sus compromisos en materia de seguridad.","og_url":"https:\/\/legrandcontinent.eu\/es\/2023\/07\/10\/cuales-son-las-perspectivas-para-la-cumbre-de-vilna\/","og_site_name":"El Grand Continent","article_published_time":"2023-07-10T15:57:00+00:00","article_modified_time":"2023-07-10T18:45:33+00:00","og_image":[{"width":1453,"height":812,"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2023\/07\/gc-sommet-de-vilnius-e1689000437893.jpg","type":"image\/jpeg"}],"author":"florent","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2023\/07\/gc-sommet-de-vilnius-e1689000437893.jpg","twitter_misc":{"Escrito por":"florent","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/es\/2023\/07\/10\/cuales-son-las-perspectivas-para-la-cumbre-de-vilna\/","url":"https:\/\/legrandcontinent.eu\/es\/2023\/07\/10\/cuales-son-las-perspectivas-para-la-cumbre-de-vilna\/","name":"\u00bfCu\u00e1les son las perspectivas para la Cumbre de Vilna? - El Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/es\/2023\/07\/10\/cuales-son-las-perspectivas-para-la-cumbre-de-vilna\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/es\/2023\/07\/10\/cuales-son-las-perspectivas-para-la-cumbre-de-vilna\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2023\/07\/gc-sommet-de-vilnius-e1689000437893.jpg","datePublished":"2023-07-10T15:57:00+00:00","dateModified":"2023-07-10T18:45:33+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/es\/2023\/07\/10\/cuales-son-las-perspectivas-para-la-cumbre-de-vilna\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/es\/2023\/07\/10\/cuales-son-las-perspectivas-para-la-cumbre-de-vilna\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/2023\/07\/10\/cuales-son-las-perspectivas-para-la-cumbre-de-vilna\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2023\/07\/gc-sommet-de-vilnius-e1689000437893.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2023\/07\/gc-sommet-de-vilnius-e1689000437893.jpg","width":1453,"height":812},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/es\/2023\/07\/10\/cuales-son-las-perspectivas-para-la-cumbre-de-vilna\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legrandcontinent.eu\/es\/"},{"@type":"ListItem","position":2,"name":"\u00bfCu\u00e1les son las perspectivas para la Cumbre de Vilna?"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/es\/#website","url":"https:\/\/legrandcontinent.eu\/es\/","name":"El Grand Continent","description":"La escala pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c","name":"florent","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","caption":"florent"}}]}},"lgc_categories":[{"id":179,"name":"Seguridad","slug":"seguridad"}],"lgc_author":null,"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/2\/2023\/07\/gc-sommet-de-vilnius-e1689000437893.jpg","width":1453,"height":812,"alt":""},"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/19755","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/users\/1366"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/comments?post=19755"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/19755\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media\/19754"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media?parent=19755"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/categories?post=19755"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/tags?post=19755"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/staff?post=19755"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/editorial_format?post=19755"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/serie?post=19755"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/audience?post=19755"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/geo?post=19755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}