{"id":15905,"date":"2023-04-20T11:23:57","date_gmt":"2023-04-20T10:23:57","guid":{"rendered":"https:\/\/legrandcontinent.eu\/es\/?p=15905"},"modified":"2023-04-20T11:23:58","modified_gmt":"2023-04-20T10:23:58","slug":"modelizar-las-revoluciones-una-cliometria-de-las-desigualdades","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/es\/2023\/04\/20\/modelizar-las-revoluciones-una-cliometria-de-las-desigualdades\/","title":{"rendered":"Modelizar las revoluciones: una cliometr\u00eda de las desigualdades"},"content":{"rendered":"\n<p>Durante casi veinte a\u00f1os, Peter Turchin ha participado, junto con muchos colegas y coautores, en un proyecto hist\u00f3rico: determinar, con pruebas cuantificables, qu\u00e9 fuerzas conducen al auge y, lo que es m\u00e1s importante, al declive de las naciones, a las turbulencias y a la decadencia pol\u00edticas y a las revoluciones. Este trabajo ha dado lugar a una enorme base de datos (CrisisDB) que abarca multitud de naciones e imperios a lo largo de los siglos, y a varios vol\u00famenes de escritos de Turchin (por ejemplo, <em>Secular Cycles<\/em>, escrito con Sergey Nefedov, <em>War and Peace and War<\/em>; he le\u00eddo el primero, pero no el segundo).<\/p>\n\n\n\n<p><em>End Times<\/em> es el intento de Turchin de presentar el complejo trabajo en curso en el campo de la cliodin\u00e1mica a un p\u00fablico general. Es un libro de \u00abalta divulgaci\u00f3n\u00bb, aunque el adjetivo \u00abalta\u00bb es a veces inaplicable porque, en su intento de llegar al p\u00fablico m\u00e1s amplio posible, Turchin ha ido a veces demasiado abajo al nivel estil\u00edstico, suponiendo por supuesto que sus lectores no tienen pr\u00e1cticamente ning\u00fan conocimiento previo. Pero se trata aqu\u00ed simplemente de una cuesti\u00f3n de estilo.<\/p>\n\n\n\n<p>\u00bfCu\u00e1l es el cuerpo del libro? Para simplificar a mi vez: el modelo de decadencia de Turchin tiene una variable, la desigualdad de ingresos o de riqueza. Esta variable, que a menudo se presenta como fuente de discordia pol\u00edtica, recibe de Turchin un significado muy concreto; por cierto, me recuerda una experiencia personal y recurrente, a menudo inc\u00f3moda: es la situaci\u00f3n en la que me encuentro cuando estoy con personas que quieren elogiar mi trabajo sobre la desigualdad y decir que es importante porque una desigualdad elevada conduce al conflicto social, pero ni ellas ni yo somos capaces de especificar exactamente c\u00f3mo sucede eso. Hoy, Peter Turchin ofrece una explicaci\u00f3n.<\/p>\n\n\n\n<p>El aumento de la desigualdad significa, por definici\u00f3n, que la persona con ingresos medianos se ver\u00e1 cada vez m\u00e1s superada por la persona con ingresos medios, y cada vez m\u00e1s superada por el 10% o el 1% m\u00e1s rico. La persona con ingresos medianos puede ser, como en Estados Unidos hoy (pa\u00eds al que se dedica la mayor parte del an\u00e1lisis del libro), un trabajador poco cualificado de la industria o los servicios, o un obrero semicualificado en la Gran Breta\u00f1a del siglo XIX, o un peque\u00f1o terrateniente en la Francia de 1830 y la Rusia de 1850. As\u00ed pues, la profesi\u00f3n o la clase social no importan, lo que importa es la posici\u00f3n de renta.<\/p>\n\n\n\n<p>\u00bfQu\u00e9 ocurre en la parte superior de la distribuci\u00f3n de la renta? El aumento de la desigualdad significa, tambi\u00e9n por definici\u00f3n, que los de arriba se hacen m\u00e1s ricos en relaci\u00f3n con los dem\u00e1s, o dicho de otro modo, que aumenta la ventaja de pertenecer al decil o percentil superior. Como todos los economistas saben, esto implica que la \u00abdemanda\u00bb de estas posiciones superiores aumenta. Si la \u00e9lite -el decil o percentil superior- est\u00e1 compuesta, como ocurre hoy en Estados Unidos, por ejecutivos, banqueros de inversi\u00f3n, abogados de empresa, cada vez se intentar\u00e1 m\u00e1s estudiar los campos m\u00e1s lucrativos y adoptar el tipo de comportamiento que con mayor probabilidad conduzca a la pertenencia a la \u00e9lite. Si hay m\u00e1s candidatos que puestos por cubrir en la \u00e9lite, se producir\u00e1 un juego de sillas vac\u00edas. No todos los aspirantes a la \u00e9lite entrar\u00e1n en ella. La divisi\u00f3n de la \u00e9lite, creada por aspirantes decepcionados que luchan por los puestos m\u00e1s altos, viene a continuaci\u00f3n.<\/p>\n\n\n\n<p>En condiciones en las que (a) no todos los aspirantes llegan a la \u00e9lite y (b) aumenta la distancia entre la mediana y la cima (lo que Turchin denomina \u00abinmiseraci\u00f3n\u00bb, aunque es importante se\u00f1alar que se trata de una inmiseraci\u00f3n relativa; es decir, la persona con ingresos medianos puede ver c\u00f3mo mejora su situaci\u00f3n), se produce una situaci\u00f3n prerrevolucionaria. La inmovilidad no es suficiente. Para que se produzca un colapso, deben enfrentarse diferentes \u00e9lites y una de ellas debe asegurarse el apoyo del \u00abpueblo\u00bb para prevalecer.<\/p>\n\n\n\n<p>Incluso un conocimiento somero del contexto de las revoluciones m\u00e1s importantes de la era moderna demuestra que el modelo de Turchin se presta bien a ello. Consideremos la Revoluci\u00f3n Francesa: el estancamiento de los ingresos y las hambrunas recurrentes se produjeron simult\u00e1neamente con una \u00e9lite dividida (la aristocracia y parte del clero se opon\u00edan a la creciente clase mercantil de las ciudades); en Rusia, en 1917, una parte de la aristocracia, que hab\u00eda perdido su propiedad terrateniente y su riqueza tras la abolici\u00f3n de la servidumbre y no pod\u00eda compensarlo con empleos estatales bien remunerados, luch\u00f3 contra sus iguales: las estad\u00edsticas del n\u00famero de revolucionarios que eran a su vez nobles empobrecidos son sorprendentes. Otro ejemplo es la revoluci\u00f3n iran\u00ed de 1979: el clero fue marginado por la \u00e9lite burguesa; como en el caso ruso, produjo a los futuros revolucionarios a trav\u00e9s de su descendencia.<\/p>\n\n\n\n<p>El modelo encaja bien -casi demasiado bien- con la realidad estadounidense actual. La persona intermedia es un \u00abdeplorable\u00bb (por citar a Hillary Clinton), un populista (por citar a los principales medios de comunicaci\u00f3n), un Hillbilly (por citar a J. D. Vance) o uno de los candidatos a la muerte por desesperaci\u00f3n (por citar a Anne Case y Angus Deaton). La clase media baja estadounidense, desafectada y desencantada, ha sido ampliamente estudiada tras la llegada de Trump al poder. La \u00e9lite actual, que Turchin disecciona de forma casi forense, est\u00e1 formada por directores generales y directores de consejos de administraci\u00f3n, grandes inversores, abogados corporativos, \u00abredes de planificaci\u00f3n pol\u00edtica\u00bb y altos cargos electos; en otras palabras, cualquiera con dinero que lo utilice para tener voz y poder. (Como era de esperar, Turchin sostiene que Estados Unidos es una plutocracia que utiliza las herramientas del derecho de voto general para legitimar su poder).<\/p>\n\n\n\n<p>Pero esta \u00e9lite no es monol\u00edtica; una \u00e9lite aspirante (un \u00abprecariado certificado\u00bb) la secunda. Hasta ahora no ha conseguido llegar a la cima y se ha definido ideol\u00f3gicamente en oposici\u00f3n a la inmigraci\u00f3n, la globalizaci\u00f3n y la ideolog\u00eda \u00abwoke\u00bb. Turchin sostiene que esta \u00e9lite aspirante se est\u00e1 apoderando del Partido Republicano y creando as\u00ed una herramienta pol\u00edtica para la competencia efectiva dentro de la \u00e9lite. Obviamente, la \u00e9lite gobernante se resiente de ello, ya que tuvo su apogeo entre 1980 y 2008, cuando su visi\u00f3n del mundo (capitalismo neoliberal y pol\u00edtica identitaria) fue abrazada por los dos partidos dominantes. Para Turchin, la actual lucha pol\u00edtica en Estados Unidos ve a la clase dominante intentando desesperadamente defenderse del asalto a su ideolog\u00eda y, lo que es m\u00e1s importante, a su posici\u00f3n econ\u00f3mica, por parte de una \u00e9lite aspirante que est\u00e1 consiguiendo el apoyo de la clase media descontenta.<\/p>\n\n\n\n<p>Se trata de una batalla de proporciones \u00e9picas. Muchos signos prerrevolucionarios est\u00e1n presentes: un sistema pol\u00edtico disfuncional, fuertes divisiones entre partidos y una falta de representaci\u00f3n pol\u00edtica para los de fuera. Turchin elogia el trabajo emp\u00edrico de Amory Gethin, Clara Mart\u00ednez Toledano y Thomas Piketty, quienes sostienen que en todas las democracias occidentales, los partidos de izquierda o socialdem\u00f3cratas se han convertido en los partidos de las \u00e9lites educadas y diplomadas, mientras que las clases medias y trabajadoras han perdido influencia e incluso representaci\u00f3n.<\/p>\n\n\n\n<p>No obstante, Turchin se muestra agn\u00f3stico sobre el desenlace de la crisis pol\u00edtica estadounidense. El sistema pol\u00edtico estadounidense ha demostrado ser extraordinariamente flexible y capaz de resistir grandes sacudidas. En cierto modo, incluso se podr\u00eda pensar que las diversas \u00absubversiones\u00bb conscientes e inconscientes de Trump han jugado precisamente a favor del sistema, ya que han demostrado su resistencia, incluso cuando el presidente ha intentado derrocarlo. Pero, por otro lado, la profunda incomprensi\u00f3n y la falta de inter\u00e9s por el punto de vista de la otra parte es precisamente una de las caracter\u00edsticas de los per\u00edodos prerrevolucionarios, y Estados Unidos tiene sobradas pruebas de ello.<\/p>\n\n\n\n<p>El modelo de Turchin se aplica probablemente tanto a China (que no se analiza en el libro) como a Estados Unidos. El empobrecimiento relativo de la clase media ha continuado en los \u00faltimos cuarenta a\u00f1os; es cierto que es menos perceptible que en Estados Unidos, dado el fenomenal aumento de su bienestar material; y en el extremo superior de la distribuci\u00f3n, la clase pol\u00edtico-administrativa que hist\u00f3ricamente ha gobernado China sigue oponi\u00e9ndose con mucha cautela a la clase ascendente de capitalistas y comerciantes. En un art\u00edculo de Yang, Novokmet y Milanovic, documentamos y analizamos el cambio m\u00e1s radical en la \u00e9lite entre 1988 y 2013: el crecimiento econ\u00f3mico desplaz\u00f3 a la clase administrativa en favor de la clase relacionada con el sector privado.<\/p>\n\n\n\n<p>El modelo de colapso interno de Turchin adquiere as\u00ed una dimensi\u00f3n geopol\u00edtica.&nbsp; La lucha por la supremac\u00eda mundial entre Estados Unidos y China puede verse entonces como una cuesti\u00f3n de qu\u00e9 sistema pol\u00edtico se resquebrajar\u00e1 primero. Si lo hace, China tendr\u00e1 que reducir sus ambiciones exteriores y aceptar el papel de potencia subordinada (en comparaci\u00f3n con Estados Unidos), incluso en Asia. Si el sistema pol\u00edtico estadounidense se derrumba primero, Estados Unidos se inclinar\u00e1 hacia el aislacionismo y tendr\u00e1 que aceptar el ascenso de China en Asia, perdiendo as\u00ed su papel de control en la parte m\u00e1s din\u00e1mica del mundo.<\/p>\n\n\n\n<p>\u00bfSer\u00e1n correctas las predicciones del modelo de Turchin? No lo sabemos, pero creo que es importante centrarse en la l\u00f3gica del mecanismo propuesto por Turchin y considerar las pr\u00f3ximas dos d\u00e9cadas como un periodo de dificultades, en lugar de pensar, como hicieron algunas de las personas que popularizaron las opiniones de Turchin en el verano de 2020, que los procesos sociales pueden predecirse con una exactitud equivalente a la del movimiento de los cuerpos celestes.<\/p>\n\n\n\n<p>La tesis de Turchin es fascinante y merece la pena leerla, y luego ser testigo de la cr\u00f3nica que traza, o tal vez asegurarse de que no se va por el camino equivocado -pues Turchin demuestra que ha habido casos en los que la previsi\u00f3n de las \u00e9lites y el inter\u00e9s propio bien entendido las han ayudado a superar un periodo de dificultades-.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abPara que se produzca un colapso, tienen que competir distintas \u00e9lites y una de ellas tiene que asegurarse el apoyo del &#8216;pueblo&#8217; para ganar\u00bb. Branko Milanovic ha le\u00eddo el \u00faltimo libro de Peter Turchin, cuya ambici\u00f3n es proporcionar una historia cuantitativa de la desigualdad -instituyendo un modelo que se ajusta casi demasiado bien a la realidad actual de Estados Unidos-.<\/p>\n","protected":false},"author":1366,"featured_media":15906,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-reviews.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":8,"_lgc_tts_audio_url":"","_lgc_tts_voice":"","_lgc_tts_publish":false,"_lgc_tts_history_item_id":"","_lgc_tts_generated_at":"","_lgc_tts_status":"","_lgc_tts_error":"","footnotes":""},"categories":[159],"tags":[],"staff":[208],"editorial_format":[1476],"serie":[],"audience":[],"geo":[172],"class_list":["post-15905","post","type-post","status-publish","format-standard","hentry","category-libros","staff-branko-milanovic","editorial_format-resenas","geo-americas"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":15906,"excerpt":"\"Para que se produzca un colapso, tienen que competir distintas \u00e9lites y una de ellas tiene que asegurarse el apoyo del 'pueblo' para ganar\". Branko Milanovic ha le\u00eddo el \u00faltimo libro de Peter Turchin, cuya ambici\u00f3n es proporcionar una historia cuantitativa de la desigualdad -instituyendo un modelo que se ajusta casi demasiado bien a la realidad actual de Estados Unidos-.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Modelizar las revoluciones: una cliometr\u00eda de las desigualdades - El Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/es\/2023\/04\/20\/modelizar-las-revoluciones-una-cliometria-de-las-desigualdades\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Modelizar las revoluciones: una cliometr\u00eda de las desigualdades - El Grand Continent\" \/>\n<meta property=\"og:description\" content=\"&quot;Para que se produzca un colapso, tienen que competir distintas \u00e9lites y una de ellas tiene que asegurarse el apoyo del &#039;pueblo&#039; para ganar&quot;. Branko Milanovic ha le\u00eddo el \u00faltimo libro de Peter Turchin, cuya ambici\u00f3n es proporcionar una historia cuantitativa de la desigualdad -instituyendo un modelo que se ajusta casi demasiado bien a la realidad actual de Estados Unidos-.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/es\/2023\/04\/20\/modelizar-las-revoluciones-una-cliometria-de-las-desigualdades\/\" \/>\n<meta property=\"og:site_name\" content=\"El Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-20T10:23:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-20T10:23:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/04\/gc-elturchinmilanovic-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1474\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"florent\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/04\/gc-elturchinmilanovic-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"florent\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/04\/20\/modelizar-las-revoluciones-una-cliometria-de-las-desigualdades\/\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/2023\/04\/20\/modelizar-las-revoluciones-una-cliometria-de-las-desigualdades\/\",\"name\":\"Modelizar las revoluciones: una cliometr\u00eda de las desigualdades - El Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/04\/20\/modelizar-las-revoluciones-una-cliometria-de-las-desigualdades\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/04\/20\/modelizar-las-revoluciones-una-cliometria-de-las-desigualdades\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/04\/81OzOqeyCjL.jpg\",\"datePublished\":\"2023-04-20T10:23:57+00:00\",\"dateModified\":\"2023-04-20T10:23:58+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/04\/20\/modelizar-las-revoluciones-una-cliometria-de-las-desigualdades\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/es\/2023\/04\/20\/modelizar-las-revoluciones-una-cliometria-de-las-desigualdades\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/04\/20\/modelizar-las-revoluciones-una-cliometria-de-las-desigualdades\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/04\/81OzOqeyCjL.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/04\/81OzOqeyCjL.jpg\",\"width\":1684,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/04\/20\/modelizar-las-revoluciones-una-cliometria-de-las-desigualdades\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/legrandcontinent.eu\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Modelizar las revoluciones: una cliometr\u00eda de las desigualdades\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/\",\"name\":\"El Grand Continent\",\"description\":\"La escala pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\",\"name\":\"florent\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"caption\":\"florent\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Modelizar las revoluciones: una cliometr\u00eda de las desigualdades - El Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/es\/2023\/04\/20\/modelizar-las-revoluciones-una-cliometria-de-las-desigualdades\/","og_locale":"es_ES","og_type":"article","og_title":"Modelizar las revoluciones: una cliometr\u00eda de las desigualdades - El Grand Continent","og_description":"\"Para que se produzca un colapso, tienen que competir distintas \u00e9lites y una de ellas tiene que asegurarse el apoyo del 'pueblo' para ganar\". Branko Milanovic ha le\u00eddo el \u00faltimo libro de Peter Turchin, cuya ambici\u00f3n es proporcionar una historia cuantitativa de la desigualdad -instituyendo un modelo que se ajusta casi demasiado bien a la realidad actual de Estados Unidos-.","og_url":"https:\/\/legrandcontinent.eu\/es\/2023\/04\/20\/modelizar-las-revoluciones-una-cliometria-de-las-desigualdades\/","og_site_name":"El Grand Continent","article_published_time":"2023-04-20T10:23:57+00:00","article_modified_time":"2023-04-20T10:23:58+00:00","og_image":[{"width":2560,"height":1474,"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/04\/gc-elturchinmilanovic-scaled.jpg","type":"image\/jpeg"}],"author":"florent","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/04\/gc-elturchinmilanovic-scaled.jpg","twitter_misc":{"Escrito por":"florent","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/es\/2023\/04\/20\/modelizar-las-revoluciones-una-cliometria-de-las-desigualdades\/","url":"https:\/\/legrandcontinent.eu\/es\/2023\/04\/20\/modelizar-las-revoluciones-una-cliometria-de-las-desigualdades\/","name":"Modelizar las revoluciones: una cliometr\u00eda de las desigualdades - El Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/es\/2023\/04\/20\/modelizar-las-revoluciones-una-cliometria-de-las-desigualdades\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/es\/2023\/04\/20\/modelizar-las-revoluciones-una-cliometria-de-las-desigualdades\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/04\/81OzOqeyCjL.jpg","datePublished":"2023-04-20T10:23:57+00:00","dateModified":"2023-04-20T10:23:58+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/es\/2023\/04\/20\/modelizar-las-revoluciones-una-cliometria-de-las-desigualdades\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/es\/2023\/04\/20\/modelizar-las-revoluciones-una-cliometria-de-las-desigualdades\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/2023\/04\/20\/modelizar-las-revoluciones-una-cliometria-de-las-desigualdades\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/04\/81OzOqeyCjL.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/04\/81OzOqeyCjL.jpg","width":1684,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/es\/2023\/04\/20\/modelizar-las-revoluciones-una-cliometria-de-las-desigualdades\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legrandcontinent.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Modelizar las revoluciones: una cliometr\u00eda de las desigualdades"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/es\/#website","url":"https:\/\/legrandcontinent.eu\/es\/","name":"El Grand Continent","description":"La escala pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c","name":"florent","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","caption":"florent"}}]}},"lgc_categories":[{"id":159,"name":"Lecturas","slug":"libros"}],"lgc_author":{"id":208,"name":"Branko Milanovic","slug":"branko-milanovic","description":null,"first_name":null,"last_name":null,"picture":null},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/04\/81OzOqeyCjL.jpg","width":1684,"height":2560,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/04\/81OzOqeyCjL.jpg","width":1684,"height":2560,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/15905","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/users\/1366"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/comments?post=15905"}],"version-history":[{"count":1,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/15905\/revisions"}],"predecessor-version":[{"id":93949,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/15905\/revisions\/93949"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media\/15906"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media?parent=15905"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/categories?post=15905"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/tags?post=15905"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/staff?post=15905"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/editorial_format?post=15905"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/serie?post=15905"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/audience?post=15905"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/geo?post=15905"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}