{"id":15868,"date":"2023-04-19T16:35:27","date_gmt":"2023-04-19T15:35:27","guid":{"rendered":"https:\/\/legrandcontinent.eu\/es\/?p=15868"},"modified":"2023-04-19T16:35:29","modified_gmt":"2023-04-19T15:35:29","slug":"estructurar-la-ecologia-politica-en-espana-una-conversacion-con-oscar-urralburu","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/es\/2023\/04\/19\/estructurar-la-ecologia-politica-en-espana-una-conversacion-con-oscar-urralburu\/","title":{"rendered":"Estructurar la ecolog\u00eda pol\u00edtica en Espa\u00f1a, una conversaci\u00f3n con \u00d3scar Urralburu"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Muy pronto se avecina un nuevo ciclo electoral y es imposible no comenzar pregunt\u00e1ndote sobre el liderazgo emergente en el bloque progresista encabezado por <a href=\"https:\/\/legrandcontinent.eu\/es\/2023\/02\/22\/la-doctrina-diaz-para-la-izquierda-en-europa-l\/\">Yolanda D\u00edaz<\/a>, cuya plataforma Sumar tiene algo de revulsivo ante el menguante deterioro de Podemos de los \u00faltimos a\u00f1os. Pareciera que Sumar extiende de manera pragm\u00e1tica <a href=\"https:\/\/legrandcontinent.eu\/es\/2021\/06\/07\/madrid-sistema-politico-espanol-conversacion-inigo-errejon\/\">aquella f\u00f3rmula errejonista de la transversalidad<\/a>. La pregunta es doble: \u00bfqu\u00e9 consideraci\u00f3n puedes hacer de la plataforma de D\u00edaz, y c\u00f3mo ves la relaci\u00f3n de Sumar con otros proyectos regionales, como M\u00e1s Regi\u00f3n y la coalici\u00f3n verde en Murcia?\u00a0<\/h3>\n\n\n\n<h4 class=\"wp-block-heading\">\u00d3SCAR URRALBURU<\/h4>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-small\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/04\/Oscar_Urralburu-1.png\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"279\"\n        data-pswp-height=\"268\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/04\/Oscar_Urralburu-1-125x120.png\"\r\n                media=\"(max-width: 374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/04\/Oscar_Urralburu-1.png\"\r\n                media=\"(min-width: 375px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/04\/Oscar_Urralburu-1-125x120.png\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">\u00d3scar Urralburu es portavoz de la formaci\u00f3n progresista M\u00e1s Pa\u00eds, y coordinador regional de M\u00e1s Regi\u00f3n en Murcia. Durante los \u00faltimos a\u00f1os, Urralburu ha desplegado una serie de importantes tareas en la regi\u00f3n que lo convierten en una de los liderazgos m\u00e1s interesantes de la nueva formaci\u00f3n ecol\u00f3gica en la pol\u00edtica regional espa\u00f1ola.<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<p><em>Sumar<\/em> ya ha presentado su propuesta. Asist\u00ed, como parte de la delegaci\u00f3n de <em>M\u00e1s Pa\u00eds<\/em>, el domingo 2 de abril a la presentaci\u00f3n y tengo que decir que hubo muchas cosas que me gustaron. Quiz\u00e1 lo m\u00e1s notable es que su \u201cdenominaci\u00f3n\u201d define con literalidad su objetivo: Sumar. Yolanda D\u00edaz nos ha puesto sobre la mesa una propuesta pol\u00edtica democr\u00e1tica, abierta a quien quiera participar, que tiene como objetivo colocar a la gente y sus problemas cotidianos en el centro de la actividad pol\u00edtica. Eso es algo que algunos llevamos mucho tiempo diciendo: los partidos en democracia son instrumentos de mejora de la vida de todos, no fines en s\u00ed mismos. Precisamente por ello, y as\u00ed lo interpreto, la propuesta de sumar a partidos de \u00e1mbito estatal y de \u00e1mbito territorial tiene como vocaci\u00f3n no servir a sus intereses, sino ir m\u00e1s all\u00e1 de los l\u00edmites de los propios partidos y construir una herramienta electoral m\u00e1s potente que permita movilizar al conjunto de la sociedad espa\u00f1ola y hacerla avanzar en una d\u00e9cada clave. Pero creo que esto no solo va de partidos pol\u00edticos, adem\u00e1s pretende como una metodolog\u00eda de trabajo social que permita sumar a cuantos m\u00e1s colectivos sociales, medioambientales, vecinales, sindicales, profesionales, de aut\u00f3nomos, mejor, para construir un proyecto progresista y aut\u00f3nomo capaz de hacer realidad el deseo de gobernar Espa\u00f1a. <\/p>\n\n\n\n<p>Le va a sonar la expresi\u00f3n, pero todo proyecto que ambicione dirigirse a la mayor\u00eda e incluir \u201ca los que faltan\u201d (y no se\u00f1alar \u201ca los que sobran\u201d) es un proyecto en el que me siento representado. Precisamente por ello, estoy convencido de que en la Regi\u00f3n de Murcia es m\u00e1s importante, si cabe, que en ning\u00fan otro lugar crear un proyecto pol\u00edtico que permita \u201cincluir a los que faltan\u201d, ampliar el campo progresista y darnos una oportunidad de poder ganar las elecciones a la derecha y la ultraderecha cuanto antes, algo que no ha pasado en 30 a\u00f1os. En este sentido, considero que la participaci\u00f3n de M\u00e1s Regi\u00f3n y la Coalici\u00f3n Verde en Sumar, debe ser semejante a la participaci\u00f3n de M\u00e1s Pa\u00eds y Verdes Equo en el conjunto del pa\u00eds: ser instrumentos para aportar de manera constructiva, apoyar un proyecto que incluya a m\u00e1s gente, dialogar, ofrecer ideas y propuestas y, si hace falta, cuadros pol\u00edticos para llevarlas a cabo. Pero lo importante es lograr los objetivos. Por eso es una decepci\u00f3n no haberlo logrado de cara al 28M y que hayan primado intereses particulares sobre los intereses generales.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>La participaci\u00f3n de M\u00e1s Regi\u00f3n y la Coalici\u00f3n Verde en Sumar, debe ser semejante a la participaci\u00f3n de M\u00e1s Pa\u00eds y Verdes Equo en el conjunto del pa\u00eds<\/p><cite>\u00d3SCAR URRALBURU<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Poniendo el foco en la Regi\u00f3n de cara al ciclo electoral, me gustar\u00eda preguntarte sobre c\u00f3mo llevan los trabajos de organizaci\u00f3n territorial y capacitaci\u00f3n de candidatos. \u00bfC\u00f3mo describir\u00edas las relaciones entre las comunidades y las comarcas de la Regi\u00f3n con los nuevos liderazgos que van despuntando de M\u00e1s Regi\u00f3n?\u00a0<\/h3>\n\n\n\n<p>Es la primera vez que nos presentamos a las elecciones regionales y municipales como fuerza pol\u00edtica junto a los compa\u00f1eros y compa\u00f1eras de Verdes Equo. Y lo hacemos porque ha sido imposible alcanzar una confluencia m\u00e1s amplia que incluyera a IU-V y Podemos. Durante los meses de octubre, noviembre y diciembre, se fijaron 2 mesas paralelas de negociaci\u00f3n ya que Podemos no aceptaba una mesa com\u00fan. Dicen querer \u201cunidad\u201d pero s\u00f3lo con IU. Seguimos trabajando con la convicci\u00f3n de que la unidad era posible en la regi\u00f3n, como paso previo a la unidad defendida por Sumar a nivel estatal. Pero tras la firma de un preacuerdo de 34 p\u00e1ginas con IU y Verdes Equo, finalmente la oferta de Podemos a IU mejor\u00f3 y terminan cerrando en enero un acuerdo que nos excluye. Decepcionante, sin duda, pero por suerte llev\u00e1bamos ya mucho trabajo avanzado. A finales de enero, concretamos el acuerdo a 2 con Verdes Equo y nos pusimos a trabajar en el Plan de Campa\u00f1a, el programa electoral, la propuesta pol\u00edtica para los principales municipios de la regi\u00f3n, aquellos que engloban un 70% del censo regional (Murcia, Cartagena, Molina y Lorca) y, finalmente, a lo largo del mes de marzo hemos ido presentando las candidaturas. Ya solo nos queda presentar el acuerdo a tres, esta vez con IU, en Molina de Segura.&nbsp;<\/p>\n\n\n\n<p>Aprovechando que la compa\u00f1era de Verdes Equo, Helena Vidal, entr\u00f3 como diputada a la Asamblea Regional, convirti\u00e9ndose en la primera diputada verde de la regi\u00f3n, hemos optado por ofrecer a la regi\u00f3n su continuidad en la representaci\u00f3n regional: una candidata joven, pero con mucha experiencia profesional como psic\u00f3loga y tambi\u00e9n como militante, completamente comprometida con el proyecto de coalici\u00f3n entre Verdes Equo y M\u00e1s Regi\u00f3n, as\u00ed como con el proyecto de Sumar. En Murcia, hemos optado por otro liderazgo joven, un profesor y activista municipalista de 30 a\u00f1os que quiere contribuir desde el ayuntamiento de Murcia a construir una ciudad m\u00e1s sostenible y m\u00e1s vivible para el siglo XXI. En Lorca presentamos a Pepe Fern\u00e1ndez Rufete, que es muy conocido en la ciudad del Sol por su compromiso con las luchas medioambientales desde finales de los a\u00f1os 80. Y en los pr\u00f3ximos d\u00edas anunciaremos los candidatos y candidatas en la ciudad de Cartagena, con su cabeza de lista, una joven curtida en la pol\u00edtica regional. Por otro lado, tambi\u00e9n hemos presentado la coalici\u00f3n con IU en Molina de Segura, con el reto important\u00edsimo de mantener el gobierno progresista y verde que tan bien ha ayudado a construir Mariano Vicente en la \u00faltima legislatura.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>En Murcia, hemos optado por otro liderazgo joven, un profesor y activista municipalista de 30 a\u00f1os que quiere contribuir desde el ayuntamiento de Murcia a construir una ciudad m\u00e1s sostenible y m\u00e1s vivible para el siglo XXI. <\/p><cite>\u00d3SCAR URRALBURU<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Desde hace a\u00f1os la Regi\u00f3n ha sido el sitio de intensas pugnas en torno al problema de las infraestructuras (pienso en el soterramiento de la v\u00eda ferroviaria en Murcia), que es tambi\u00e9n un tema candente en toda la geograf\u00eda sure\u00f1a en la geograf\u00eda de la llamada Espa\u00f1a radial. \u00bfSe est\u00e1 discutiendo el tema de las infraestructuras por parte de M\u00e1s Regi\u00f3n? \u00bfCu\u00e1l es su orientaci\u00f3n y visi\u00f3n de cara a las exigencias ecol\u00f3gicas y de la transici\u00f3n energ\u00e9tica del pa\u00eds?\u00a0<\/h3>\n\n\n\n<p>En el programa electoral, que est\u00e1 ya en su fase final de elaboraci\u00f3n hemos abordado de modo especial el asunto de las infraestructuras y del desequilibrio territorial existente en esta materia en la Regi\u00f3n de Murcia. El derecho a la movilidad es determinante en una fase de transici\u00f3n energ\u00e9tica, por ello debemos esforzarnos en fomentar los accesos a los servicios p\u00fablicos esenciales, las infraestructuras del transporte y el urbanismo, zonificando el territorio rural en comarcas, seg\u00fan sus particularidades sociales, carencias y potencialidades, pero hay que hacerlo siempre protegiendo los ecosistemas y los recursos naturales b\u00e1sicos -aguas, bosques y tierra f\u00e9rtil-.\u00a0<\/p>\n\n\n\n<p>No cabe duda que desde el \u00faltimo cuarto del siglo pasado, la poblaci\u00f3n de la Regi\u00f3n de Murcia ha crecido muy r\u00e1pidamente, al igual que la actividad econ\u00f3mica, pero este crecimiento no ha ido acompa\u00f1ado de una adecuaci\u00f3n de las redes de log\u00edstica y transporte. La comunicaci\u00f3n entre los municipios de la Regi\u00f3n se ha basado, casi en exclusiva, en la red de carreteras y autov\u00edas apostando por el transporte privado en coche y de mercanc\u00edas en cami\u00f3n, precisamente por ello, ahora que es necesario abordar una transici\u00f3n energ\u00e9tica y, por tanto, tambi\u00e9n una transici\u00f3n en el modelo de movilidad, la situaci\u00f3n es tan precaria. Desde los sucesivos gobiernos del Partido Popular, se ha promovido en la Regi\u00f3n una cultura del coche que ha provocado que nuestras ciudades tengan un alto \u00edndice de contaminaci\u00f3n por \u00f3xidos de nitr\u00f3geno. Seg\u00fan la Agencia Europea de Medio Ambiente, la ciudad de Murcia es la cuarta ciudad m\u00e1s contaminada de Espa\u00f1a por di\u00f3xido de nitr\u00f3geno. Con las nuevas directrices de la OMS sobre niveles de contaminaci\u00f3n del aire, las ciudades de Murcia, Cartagena y Lorca, sobrepasan los m\u00e1ximos considerados como tolerables.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Desde los sucesivos gobiernos del Partido Popular, se ha promovido en la Regi\u00f3n una cultura del coche que ha provocado que nuestras ciudades tengan un alto \u00edndice de contaminaci\u00f3n por \u00f3xidos de nitr\u00f3geno. <\/p><cite>\u00d3SCAR URRALBURU<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Por otro lado, si la finalizaci\u00f3n de las obras del soterramiento del AVE por Alicante, como parte del corredor Mediterr\u00e1neo, y su continuaci\u00f3n hacia Andaluc\u00eda, ha supuesto el triunfo de las reivindicaciones de d\u00e9cadas de la Plataforma Pro-Soterramiento, pero al mismo tiempo ha supuesto la paralizaci\u00f3n, hasta la finalizaci\u00f3n de una l\u00ednea muy costosa de los trenes de cercan\u00edas Murcia Lorca \u00c1guilas y la interrupci\u00f3n de la posibilidad de acceder en tren a Cieza, lo que contribuye a saturar m\u00e1s, si cabe, las autov\u00edas y carreteras de nuestra Regi\u00f3n. Frente a un modelo basado en la inversi\u00f3n para aumentar de forma constante la capacidad de la red viaria y el espacio de aparcamiento, en el que los recursos se despilfarran sin sentido, caben f\u00f3rmulas encaminadas a aumentar la eficiencia del patrimonio infraestructural construido y promover los modos de transporte m\u00e1s sostenibles y menos agresivos para la salud.&nbsp;<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-large\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/04\/SIPA_sipausa30324267_000012-scaled-1.jpg\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"2560\"\n        data-pswp-height=\"1917\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/04\/SIPA_sipausa30324267_000012-scaled-1-330x247.jpg\"\r\n                media=\"(max-width: 374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/04\/SIPA_sipausa30324267_000012-scaled-1-690x517.jpg\"\r\n                media=\"(max-width: 989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/04\/SIPA_sipausa30324267_000012-scaled-1-1340x1003.jpg\"\r\n                media=\"(min-width: 990px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/04\/SIPA_sipausa30324267_000012-scaled-1-125x94.jpg\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">Escombrera minera y suelo y rocas extremadamente ricos en minerales, marcados por la explotaci\u00f3n a cielo abierto de R\u00edo Tinto, en la localidad de Minas de Riotinto, vista a\u00e9rea, tomada con dron, provincia de Huelva, Andaluc\u00eda \u00a9 Thomas Dressler\/SIPA<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<p>Somos conscientes de que tras la irrupci\u00f3n del Covid-19, los patrones de movilidad han cambiado cada vez es mayor la parte de la poblaci\u00f3n que teletrabaja y ya no se desplaza cada d\u00eda, gran parte de nuestras actividades las realizamos a distancias asumibles caminando o en bicicleta, queremos gozar de un mejor espacio p\u00fablico y de una mejor calidad del aire en nuestras ciudades y para ello es necesaria una mayor oferta y frecuencia del transporte p\u00fablico, tambi\u00e9n de ampliaci\u00f3n de las l\u00edneas de tranv\u00eda en la ciudad de Murcia, tal y como hemos propuesto con un plan espec\u00edfico. Estas nuevas necesidades hacen imprescindible un cambio de modelo de movilidad. Estamos, por tanto, frente a una oportunidad \u00fanica para alcanzar una movilidad m\u00e1s saludable, m\u00e1s sostenible, m\u00e1s eficiente, m\u00e1s segura y m\u00e1s equitativa que pivote en torno al\u00a0 transporte p\u00fablico colectivo, mucho m\u00e1s eficiente y ecol\u00f3gico que cualquier otra opci\u00f3n. Pero para ello, es necesario reforzar el transporte p\u00fablico como espina dorsal del sistema de movilidad: dotando al sistema de suficiente personal y medios econ\u00f3micos y materiales; generando un nuevo modelo de gobernanza; ampliando su cobertura creando nuevas l\u00edneas y construyendo nuevos intercambiadores de transporte; garantizando la accesibilidad universal de paradas, estaciones y veh\u00edculos.\u00a0<\/p>\n\n\n\n<p>En nuestro programa recogemos la voluntad de recuperar una Entidad P\u00fablica de Transporte de la Regi\u00f3n de Murcia que integre y coordine el transporte interurbano, como organismo aut\u00f3nomo que act\u00fae como autoridad de transporte planificando, implementando las estrategias de transporte y administrando los servicios de transporte de las \u00e1reas metropolitana y funcionales de la regi\u00f3n. As\u00ed mismo,\u00a0 realizaremos estudios sobre el uso diferencial del transporte de la regi\u00f3n seg\u00fan el g\u00e9nero del usuario, prestando especial atenci\u00f3n a los viajes vinculados a cuidados (acompa\u00f1ar a personas dependientes, ir a hacer la compra de comida y medicinas e ir al m\u00e9dico),\u00a0 as\u00ed como un estudio espec\u00edfico para diagnosticar las carencias de movilidad de los municipios, los barrios y pueblos m\u00e1s vulnerables y despoblados de la Regi\u00f3n, que sirva como hoja de ruta para el reequilibrio territorial en materia de movilidad. Sus resultados ser\u00e1n de obligado cumplimiento en el dise\u00f1o de rutas y frecuencias. Proponemos un Abono Social para las personas con renta m\u00e1s baja e implantaremos un nuevo abono especial para familias.\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>El tren es la infraestructura m\u00e1s sostenible para el transporte por tierra, tanto de personas como de mercanc\u00edas. El 85% de las exportaciones agr\u00edcolas de la Regi\u00f3n se hacen por carretera con un alt\u00edsimo coste ambiental y energ\u00e9tico.<\/p><cite>\u00d3SCAR URRALBURU<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Para nosotros y nosotras, el tren es la infraestructura m\u00e1s sostenible para el transporte por tierra, tanto de personas como de mercanc\u00edas. El Corredor Mediterr\u00e1neo debe servir para mejorar el abandonado transporte de mercanc\u00edas y para ello, se deben adecuar y modernizar las instalaciones de carga y descarga existentes, establecer Zonas de Actividad Log\u00edstica que aseguren la intermodalidad. El 85% de las exportaciones agr\u00edcolas de la Regi\u00f3n se hacen por carretera con un alt\u00edsimo coste ambiental y energ\u00e9tico. Exigiremos la recuperaci\u00f3n, modernizaci\u00f3n y electrificaci\u00f3n de los trenes de cercan\u00edas, aumentando la frecuencia y destinos y potenciaremos la intermodalidad, conectando las estaciones de tren con las estaciones de autobuses y estableciendo bonos intermodales (tren-autob\u00fas) que permitan viajar entre las poblaciones de la Regi\u00f3n, a toda la poblaci\u00f3n, tambi\u00e9n a las personas con discapacidad o a quienes quieren emplear la bicicleta como medio personal de transporte&nbsp; en nuestras ciudades.<\/p>\n\n\n\n<p>En este sentido, en el contexto actual de emergencia clim\u00e1tica, sanitaria y econ\u00f3mica, es obligatorio el impulso de la bicicleta como un proyecto estrat\u00e9gico en las pol\u00edticas p\u00fablicas de movilidad. Pocas cosas como la bicicleta aportan una respuesta a los retos actuales en diversos frentes como el proceso de recuperaci\u00f3n econ\u00f3mica, la emergencia clim\u00e1tica y la necesaria transici\u00f3n eco-social y energ\u00e9tica. A\u00f1adido a los comprobados beneficios de su uso para prevenir enfermedades mentales y f\u00edsicas y al gran retorno econ\u00f3mico que genera a la sociedad, esta es la oportunidad para destinar fondos a pol\u00edticas de fomento del uso de la bicicleta.&nbsp;<\/p>\n\n\n\n<p>La bicicleta es el medio de transporte m\u00e1s eficaz entre 1 y 8 km, lo que supone la mayor\u00eda de los desplazamientos que se realizan diariamente en la Regi\u00f3n. Su uso abre oportunidades de desplazamientos mucho m\u00e1s diversos, seguros, econ\u00f3micos y respetuosos con el medio ambiente. Es imprescindible incentivar este medio de transporte y a las empresas que utilicen la bicicleta como elemento de activaci\u00f3n econ\u00f3mica como es el caso de la ciclolog\u00edstica o el cicloturismo. Nos comprometeremos pol\u00edticamente con la bicicleta a trav\u00e9s de la aprobaci\u00f3n de un Plan Regional de la Bicicleta, en el que \u00e9sta cobrar\u00e1 un papel central en la movilidad regional y como pieza fundamental en el fomento de la intermodalidad y se har\u00e1 en coordinaci\u00f3n con las organizaciones representantes de personas usuarias y otros sectores involucrados. Se contemplar\u00e1 la financiaci\u00f3n para la ejecuci\u00f3n del plan, de la red ciclista planteada y campa\u00f1as de comunicaci\u00f3n institucional en favor de la promoci\u00f3n del uso de la bicicleta en los medios p\u00fablicos de radio y televisi\u00f3n. Este Plan Especial incluir\u00e1 varios ejes: el desarrollo de la red ciclista regional, supramunicipal y local; un Plan de red de Estacionamiento de Bicicletas en el que incluiremos\u2028medidas concretas para llevar las bicicletas a bordo de trenes\u2028y autobuses interurbanos; crearemos una l\u00ednea de apoyo econ\u00f3mico destinado a que los municipios dispongan de redes propias de bicicletas que protagonicen la movilidad dentro de las ciudades y pueblos; e impulsaremos la ciclolog\u00edstica como una pieza m\u00e1s en el transporte de mercanc\u00edas en la \u00faltima milla y el cicloturismo. Apoyaremos a los municipios para que dispongan de redes propias de bicicletas p\u00fablicas. Todas ellas estar\u00e1n integradas en el nuevo marco tarifario, garantizando intermodalidad bici-transporte p\u00fablico colectivo y la comunicaci\u00f3n en bicicleta entre municipios en condiciones de seguridad, comodidad y eficacia.&nbsp;<\/p>\n\n\n\n<p>Fomentaremos la construcci\u00f3n de pasarelas y carriles bicis que comuniquen nuestros municipios, con el objetivo de generar una red ciclista local, metropolitana y regional. Esta red coherente, intuitiva y homog\u00e9nea, unir\u00e1 y complementar\u00e1 las v\u00edas ciclistas existentes, creando nuevas, con el objetivo de unir localidades vecinas entre s\u00ed, intercambiadores de transporte y lugares de especial inter\u00e9s, como estaciones de tren, hospitales, campings, pol\u00edgonos industriales, centros comerciales y de ocio, etc., que se encuentran fuera de los \u00e1mbitos locales. Promocionaremos el uso de la bicicleta en los Centros Educativos. Entrenamiento integrado como programas educativos sobre movilidad sostenible y circulaci\u00f3n segura, apoyo en adecuaci\u00f3n de aparcamientos en los centros educativos y entornos escolares pacificados, seguros y saludables impulsando caminos seguros, carriles bici y bici- buses, adem\u00e1s de programas para acceder a la bicicleta. Queremos crear una Oficina Regional de la Bicicleta con equipo t\u00e9cnico propio que elabore un Manual de Infraestructuras Ciclistas.\u00a0<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-large\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/04\/SIPA_sipausa30324267_000017-scaled-1.jpg\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"2560\"\n        data-pswp-height=\"1918\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/04\/SIPA_sipausa30324267_000017-scaled-1-330x247.jpg\"\r\n                media=\"(max-width: 374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/04\/SIPA_sipausa30324267_000017-scaled-1-690x517.jpg\"\r\n                media=\"(max-width: 989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/04\/SIPA_sipausa30324267_000017-scaled-1-1340x1004.jpg\"\r\n                media=\"(min-width: 990px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/04\/SIPA_sipausa30324267_000017-scaled-1-125x94.jpg\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">Red de canales y arroyos en marea baja, en las marismas de la Bah\u00eda de C\u00e1diz, a lo lejos la ciudad de Chiclana de la Frontera, vista a\u00e9rea, tomada con dron, provincia de C\u00e1diz \u00a9 Thomas Dressler\/SIPA<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<p>Y todo ello lo haremos, sin olvidar que las carreteras son y seguir\u00e1n siendo infraestructuras b\u00e1sicas de la Regi\u00f3n de Murcia. Asumimos el reto de superar la pol\u00edtica de la ampliaci\u00f3n permanente de la capacidad, gestionando las carreteras de forma diferente: priorizando el transporte p\u00fablico sobre el coche, impulsando la intermodalidad, reforzando el mantenimiento del patrimonio infraestructural, corrigiendo las deficiencias de la red, incrementando la seguridad vial y reduciendo los impactos ambientales de la red: aparcamientos disuasorios, construcci\u00f3n de pantallas ac\u00fasticas, inventario de tramos protegidos\u00a0 con sistemas para protecci\u00f3n de motoristas en las carreteras de titularidad regional, priorizaci\u00f3n de las conexiones entre barrios y municipios especialmente aislados como las pedan\u00edas altas del Noroeste, creaci\u00f3n de infraestructuras para una Red log\u00edstica de producci\u00f3n y distribuci\u00f3n de productos agroecol\u00f3gicos en la Regi\u00f3n, etc. Crearemos un plan espec\u00edfico para la renovaci\u00f3n de infraestructuras cient\u00edfico-t\u00e9cnicas, utilizadas tanto en ciencias experimentales como en computaci\u00f3n, y la creaci\u00f3n de otras nuevas en las universidades e instituciones p\u00fablicas regionales.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>El PP lleva 30 a\u00f1os instalado en San Esteban gracias a su hegemon\u00eda pol\u00edtica en materia h\u00eddrica. Una variante del nacionalismo espa\u00f1ol convertido en una versi\u00f3n regional de \u201cnacionalismo del agua\u201d que hoy pretende heredar Vox.<\/p><cite>\u00d3SCAR URRALBURU<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">La tensi\u00f3n territorial entre pueblos, territorios, y grandes centros metropolitanos es hoy una clave interpretativa de la comprensi\u00f3n pol\u00edtica. Pareciera\u00a0 que la derecha ha logrado captarlo con cierta eficacia. El mes pasado en un mitin en Murcia, Abascal enfatiz\u00f3 la ira anti-metropolitana y aludi\u00f3 al problema del agua y de los regaderos de la Regi\u00f3n. \u00bfC\u00f3mo leen desde M\u00e1s Regi\u00f3n el auge de la derecha nacionalista y su incepcion en los territorios?\u00a0<\/h3>\n\n\n\n<p>El PP lleva 30 a\u00f1os instalado en San Esteban gracias a su hegemon\u00eda pol\u00edtica en materia h\u00eddrica. Una variante del nacionalismo espa\u00f1ol convertido en una versi\u00f3n regional de \u201cnacionalismo del agua\u201d que hoy pretende heredar Vox. Pero es el mismo discurso y las mismas mentiras, un discurso y unas mentiras sostenidas sobre una necesidad h\u00eddrica real que se vive de manera dram\u00e1tica en las zonas rurales y agr\u00edcolas en las que el agua se ha convertido en el principal motor productivo. Pero esta din\u00e1mica est\u00e1 llegando a sus l\u00edmites, quiz\u00e1 por ello tambi\u00e9n se extreman los discursos: el cambio clim\u00e1tico, el aumento de la sequ\u00eda, no solo en el sureste espa\u00f1ol, sino principalmente en la cabecera del Tajo, anuncian el fin del modelo de la agroindustria regional, un modelo que ha estado vigente por m\u00e1s de cuarenta a\u00f1os y que\u00a0 ha evidenciado su err\u00f3neo dise\u00f1o en el colapso medioambiental provocado en el Mar Menor. <\/p>\n\n\n\n<p>Todo est\u00e1 enlazado en esta cuesti\u00f3n. Por ello, desde M\u00e1s Regi\u00f3n \u2013 Verdes Equo queremos hacer del agua un asunto de Estado que evite el conflicto social en torno a las grandes infraestructuras del agua. Solamente desde la cooperaci\u00f3n y el entendimiento mutuo se podr\u00e1n alcanzar f\u00f3rmulas de consenso ampliamente participativas en el seno de la planificaci\u00f3n de todas las cuencas, con transparencia y con los procedimientos que establece la Directiva Marco Europea del Agua. Creemos que el objetivo debe ser avanzar hacia un horizonte menos dependiente de recursos h\u00eddricos externos y conseguir, a largo plazo, una mayor autosuficiencia h\u00eddrica en cada demarcaci\u00f3n hidrogr\u00e1fica, s\u00f3lo as\u00ed lograremos despejar del horizonte pol\u00edtico el discurso demag\u00f3gico del agua que hacen PP y Vox.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Queremos hacer del agua un asunto de Estado que evite el conflicto social en torno a las grandes infraestructuras del agua. <\/p><cite>\u00d3SCAR URRALBURU<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Se trata de gestionar y contener la demanda agraria, urbana e industrial, complementada con la optimizaci\u00f3n de los recursos no convencionales (reutilizaci\u00f3n de aguas residuales y desalaci\u00f3n marina) como piezas clave en esta hoja de ruta de transici\u00f3n hacia horizontes m\u00e1s sostenibles y adaptados al cambio clim\u00e1tico. Por ello, desde M\u00e1s Regi\u00f3n-Verdes Equo sostenemos que es necesaria la gesti\u00f3n adaptativa de las infraestructuras ya existentes, como la del Acueducto Tajo-Segura, entre otras, que tenga en cuenta el cambio clim\u00e1tico, cuyo impacto en las cuencas cedentes ser\u00e1 cada vez m\u00e1s significativo. Debemos acabar con la corrupci\u00f3n y con la mercantilizaci\u00f3n del agua, promoviendo nuevos modelos de gesti\u00f3n, basados en la transparencia y la participaci\u00f3n ciudadana en la gesti\u00f3n del agua como un bien p\u00fablico. Es verdad que existe un d\u00e9ficit h\u00eddrico, fruto de la escasez de recursos, pero tambi\u00e9n existe una mala y especulativa gesti\u00f3n del agua y hay que decirlo. Es una verg\u00fcenza que mientras se manifiestan porque no hay agua en la regi\u00f3n \u00e9sta se venda en el mercado negro a comunidades de regantes de otras CCAA. Los agricultores preocupados por su cosecha y el campo regional se merecen que desde la pol\u00edtica se reduzcan sus incertidumbres en torno a la disponibilidad de agua y sus impactos econ\u00f3micos. Solo al gobierno regional, al PP y a Vox, les interesa esta permanente inestabilidad en cuanto al reconocimiento de los recursos disponibles. As\u00ed mismo, debemos asegurar la equidad social en el acceso al agua, protegiendo los peque\u00f1os productores y los regad\u00edos hist\u00f3ricos (huertas tradicionales) y su valioso patrimonio ambiental y cultural, estamos comprometidos con el objetivo de recuperar y mantener el buen estado ecol\u00f3gico de nuestros r\u00edos, manantiales, acu\u00edferos y humedales.<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-large\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/04\/SIPA_sipausa30324267_000003-scaled-1.jpg\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"2560\"\n        data-pswp-height=\"1917\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/04\/SIPA_sipausa30324267_000003-scaled-1-330x247.jpg\"\r\n                media=\"(max-width: 374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/04\/SIPA_sipausa30324267_000003-scaled-1-690x517.jpg\"\r\n                media=\"(max-width: 989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/04\/SIPA_sipausa30324267_000003-scaled-1-1340x1003.jpg\"\r\n                media=\"(min-width: 990px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/04\/SIPA_sipausa30324267_000003-scaled-1-125x94.jpg\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">Campos cultivados en invierno en la Campi\u00f1a Cordobesa, una f\u00e9rtil zona rural al sur de la ciudad de C\u00f3rdoba, vista a\u00e9rea, tomada con dron, provincia de C\u00f3rdoba \u00a9 Thomas Dressler\/SIPA<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<p>Tenemos que recordar que las pol\u00edticas del agua y su interrelaci\u00f3n con la agricultura van a tener una gran trascendencia para el futuro del entramado socioecon\u00f3mico en el medio rural de nuestro pa\u00eds. El cambio clim\u00e1tico en marcha agravar\u00e1 los problemas de rentabilidad y viabilidad de muchas explotaciones agrarias y ganaderas, en especial las que representan al modelo social y familiar que defendemos. A pesar de ser un sector altamente vulnerable al cambio clim\u00e1tico, el sector agrario puede contribuir eficazmente a frenar los impactos del cambio clim\u00e1tico, si se le proporcionan los medios necesarios y el marco normativo adecuado. El sector agrario puede estar en condiciones de respuesta a los retos alimentarios, energ\u00e9ticos y ambientales vigentes pasando a ser parte importante de la soluci\u00f3n.\u00a0\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Las pol\u00edticas del agua y su interrelaci\u00f3n con la agricultura van a tener una gran trascendencia para el futuro del entramado socioecon\u00f3mico en el medio rural de nuestro pa\u00eds.<\/p><cite>\u00d3SCAR URRALBURU<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Ante esta situaci\u00f3n y durante muchos a\u00f1os, numerosos colectivos sociales y ambientales han venido reclamando un Acuerdo Social por el Agua que sea la base de una pol\u00edtica de Estado, basada en la defensa de nuestros r\u00edos, que vele por la gesti\u00f3n p\u00fablica del agua, y que reconozca y garantice el acceso universal a los servicios de abastecimiento y saneamiento, en tanto que se trata de un derecho humano, reconocido como tal por Naciones Unidas. Ese Acuerdo Social por el Agua ha sido elaborado y firmado por cerca de un centenar de organizaciones, colectivos y sindicatos de las diversas Comunidades Aut\u00f3nomas de Espa\u00f1a. Por ello, desde M\u00e1s Regi\u00f3n \u2013 Verdes Equo asumimos sus demandas y nos comprometemos a trabajar en la defensa, tal y como establece la Directiva Marco de Aguas (DMA), de una gesti\u00f3n integrada y sostenible de r\u00edos, lagos, humedales y acu\u00edferos, a nivel de cuenca, desde enfoques ecosist\u00e9micos, promover de forma efectiva el objetivo de recuperar el buen estado ecol\u00f3gico de las masas de agua, respetando los reg\u00edmenes de caudales ecol\u00f3gicos que permitan garantizar el buen estado de r\u00edos y humedales frente al cambio clim\u00e1tico y gestionar a nivel de cuenca los flujos s\u00f3lidos y sedimentos de los que depende la sostenibilidad de deltas, playas y ecosistemas litorales. Y ante los efectos adversos del Cambio Clim\u00e1tico, es obligatorio desarrollar planes de ordenaci\u00f3n territorial y urban\u00edstica que eviten de forma efectiva la construcci\u00f3n de viviendas, instalaciones industriales y ganaderas en ramblas y territorios inundables, recuperando sotos de ribera, meandros y espacios de inundaci\u00f3n fluvial en crecida, con retranqueo de motas, con el objeto de generar estrategias de ablandamiento y gesti\u00f3n de crecidas extraordinarias en coherencia con la Directiva de Inundaciones.<\/p>\n\n\n\n<p>Es necesario acabar con la opacidad institucional y el autoritarismo tecnocr\u00e1tico en la gesti\u00f3n del agua. El buen gobierno del agua debe regirse por criterios m\u00e1s democr\u00e1ticos, transparentes y participativos, al servicio de todos los usuarios. Tenemos que promover la actualizaci\u00f3n concesional de las dotaciones en funci\u00f3n de las disponibilidades actuales y futuras, a la luz del cambio clim\u00e1tico en curso y combatir la sobreasignaci\u00f3n de concesiones, por encima de los caudales realmente disponibles, especialmente en el futuro. Pero para ello es necesario revisar la relaci\u00f3n de las Confederaciones Hidrogr\u00e1ficas con los municipios y delimitar funciones y responsabilidades para mejorar la coordinaci\u00f3n interinstitucional en materia de gesti\u00f3n de cauces, ramblas y barrancos, al tiempo que se refuerza\u00a0 el papel de las Comunidades de Regantes (tradicionales o no), d\u00e1ndoles apoyo, evitando la privatizaci\u00f3n de la gesti\u00f3n del riego en grandes sistemas.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Es necesario acabar con la opacidad institucional y el autoritarismo tecnocr\u00e1tico en la gesti\u00f3n del agua. <\/p><cite>\u00d3SCAR URRALBURU<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Estamos despilfarrando cientos de millones de euros de fondos p\u00fablicos en grandes obras hidr\u00e1ulicas conflictivas, de dudosa rentabilidad y con graves impactos socio-ambientales, realizando, en su caso, adecuadas obras de regulaci\u00f3n en tr\u00e1nsito que permitan modernizar y consolidar la explotaci\u00f3n familiar en los regad\u00edos existentes, minimizando impactos ambientales. Vamos a impulsar la desalaci\u00f3n de agua de mar y de caudales salobres, as\u00ed \u0301 como la regeneraci\u00f3n y la reutilizaci\u00f3n de retornos, en territorios costeros, usando energ\u00eda solar y e\u00f3lica que pueden alumbrar perspectivas de autosuficiencia sostenible en territorios vulnerables.<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-large\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/04\/SIPA_sipausa30324267_000010-scaled-1.jpg\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"2560\"\n        data-pswp-height=\"1917\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/04\/SIPA_sipausa30324267_000010-scaled-1-330x247.jpg\"\r\n                media=\"(max-width: 374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/04\/SIPA_sipausa30324267_000010-scaled-1-690x517.jpg\"\r\n                media=\"(max-width: 989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/04\/SIPA_sipausa30324267_000010-scaled-1-1340x1003.jpg\"\r\n                media=\"(min-width: 990px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/04\/SIPA_sipausa30324267_000010-scaled-1-125x94.jpg\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">Almendros j\u00f3venes (<em>Prunus dulcis<\/em>) cultivados en la Campina Cordobesa, una f\u00e9rtil zona rural al sur de la ciudad de C\u00f3rdoba, al atardecer y con luna llena, vista a\u00e9rea, tomada con dron, provincia de C\u00f3rdoba \u00a9 Thomas Dressler\/SIPA<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<h3 class=\"wp-block-heading\">Una pregunta m\u00e1s de corte geopol\u00edtico y fiscal: pensando en el programa de <em>Next Generation EU<\/em> para el desarrollo postpand\u00e9mico, \u00bfqu\u00e9 lectura han hecho de la colaboraci\u00f3n entre el gobierno central y la Uni\u00f3n Europea? \u00bfEs posible pensar una mayor compenetraci\u00f3n de los territorios lejanos del centro con los dise\u00f1os de las pol\u00edticas p\u00fablicas de la Uni\u00f3n?\u00a0<\/h3>\n\n\n\n<p>El <em>Next Generation <\/em>es el mayor paquete de est\u00edmulo jam\u00e1s dise\u00f1ado por la Uni\u00f3n en toda su historia. Una oportunidad para convertir el problema generado por la pandemia del Covid-19 en una oportunidad para transformar nuestra econom\u00eda y crear nuevas oportunidades adaptadas a las necesidades del siglo XXI,\u00a0 para crear una Europa m\u00e1s ecol\u00f3gica, m\u00e1s digital y m\u00e1s resiliente de cara al futuro. Y eso es algo que ha logrado el gobierno de coalici\u00f3n en Espa\u00f1a y que confronta de modo radical con el modo de abordar la crisis que tuvo el gobierno de Espa\u00f1a y la Uni\u00f3n Europea en 2010. Como bien sabes, se trata de\u00a0 un paquete de inversi\u00f3n focalizado en la investigaci\u00f3n y la innovaci\u00f3n, a trav\u00e9s de Horizonte Europa, en las transiciones clim\u00e1tica y digital, a trav\u00e9s del Fondo de Transici\u00f3n Justa y el programa Europa Digital, y en la preparaci\u00f3n, la recuperaci\u00f3n y la resiliencia, a trav\u00e9s del Mecanismo de Recuperaci\u00f3n y Resiliencia, <em>rescEU<\/em> y un nuevo programa de salud, UEproSalud. <\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Los paquetes de la Uni\u00f3n han permitido que este 2023 tengamos el mayor presupuesto en materia de ingresos de nuestra historia, pero a\u00fan podr\u00eda haber sido mayor si el gobierno regional no estuviera todo el tiempo en guerra con el gobierno de Espa\u00f1a.<\/p><cite>\u00d3SCAR URRALBURU<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Junto a estos tres ejes m\u00e1s innovadores, tambi\u00e9n se han articulado medidas en materia de la modernizaci\u00f3n de pol\u00edticas tradicionales, como la de cohesi\u00f3n y la pol\u00edtica agr\u00edcola com\u00fan, para que contribuyan al m\u00e1ximo a las prioridades de la Uni\u00f3n, en la lucha contra el cambio clim\u00e1tico, con el 30 % de los fondos de la Uni\u00f3n Europea, el mayor porcentaje en la historia del presupuesto europeo y en protecci\u00f3n de la biodiversidad y la igualdad de g\u00e9nero, seis\u00a0 dimensiones de inversi\u00f3n especialmente sensibles en nuestra Regi\u00f3n que el gobierno regional no deber\u00eda desaprovechar y, en gran medida, est\u00e1 desaprovechando. Estos paquetes han permitido que este 2023 tengamos el mayor presupuesto en materia de ingresos de nuestra historia, pero a\u00fan podr\u00eda haber sido mayor si el gobierno regional no estuviera todo el tiempo en guerra con el gobierno de Espa\u00f1a, viendo quien se pone la medalla y evitando que el discurso del cuidado medioambiental y el respeto a la biodiversidad, la lucha contra el cambio clim\u00e1tico, por la igualdad o por la innovaci\u00f3n, la tecnologizaci\u00f3n de nuestros modelos productivos y la transici\u00f3n energ\u00e9tica se puedan convertir en dominantes culturalmente. Es esta forma de hacer pol\u00edtica que tiene el PP y su socio ultra y es la base de sus propias ideas, alejadas del sentido com\u00fan de \u00e9poca lo que nos hace perder oportunidades. \u00bfC\u00f3mo aprovechar estos fondos si son la ant\u00edtesis de lo que defienden? En este sentido, desde la regi\u00f3n deber\u00edamos aprovechar estos fondos para acercarnos al coraz\u00f3n de Europa, pero me da la sensaci\u00f3n de que con este Presidente y este gobierno regional cada vez estamos m\u00e1s lejos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para entender las mutaciones de la pol\u00edtica territorial espa\u00f1ola hoy, hay que mirar hacia el sur. \u00d3scar Urralburu, coordinador regional de M\u00e1s Regi\u00f3n en Murcia, analiza la organizaci\u00f3n territorial fuera de los grandes centros urbanos y las tensiones entre infraestructuras y medio ambiente.<\/p>\n","protected":false},"author":1366,"featured_media":15874,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-angles.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":22,"footnotes":""},"categories":[98],"tags":[],"staff":[168],"editorial_format":[1470],"serie":[],"audience":[],"geo":[177],"class_list":["post-15868","post","type-post","status-publish","format-standard","hentry","category-energia-y-medio-ambiente","staff-gerardo-munoz","editorial_format-perspectivas-sobre-la-actualidad","geo-europa"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":15874,"excerpt":"Para entender las mutaciones de la pol\u00edtica territorial espa\u00f1ola hoy, hay que mirar hacia el sur. \u00d3scar Urralburu, coordinador regional de M\u00e1s Regi\u00f3n en Murcia, analiza la organizaci\u00f3n territorial fuera de los grandes centros urbanos y las tensiones entre infraestructuras y medio ambiente.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Estructurar la ecolog\u00eda pol\u00edtica en Espa\u00f1a, una conversaci\u00f3n con \u00d3scar Urralburu - El Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/es\/2023\/04\/19\/estructurar-la-ecologia-politica-en-espana-una-conversacion-con-oscar-urralburu\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estructurar la ecolog\u00eda pol\u00edtica en Espa\u00f1a, una conversaci\u00f3n con \u00d3scar Urralburu - El Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Para entender las mutaciones de la pol\u00edtica territorial espa\u00f1ola hoy, hay que mirar hacia el sur. \u00d3scar Urralburu, coordinador regional de M\u00e1s Regi\u00f3n en Murcia, analiza la organizaci\u00f3n territorial fuera de los grandes centros urbanos y las tensiones entre infraestructuras y medio ambiente.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/es\/2023\/04\/19\/estructurar-la-ecologia-politica-en-espana-una-conversacion-con-oscar-urralburu\/\" \/>\n<meta property=\"og:site_name\" content=\"El Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-19T15:35:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-19T15:35:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/04\/gc-eloscarurralburu-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"florent\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/04\/gc-eloscarurralburu-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"florent\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"22 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/04\/19\/estructurar-la-ecologia-politica-en-espana-una-conversacion-con-oscar-urralburu\/\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/2023\/04\/19\/estructurar-la-ecologia-politica-en-espana-una-conversacion-con-oscar-urralburu\/\",\"name\":\"Estructurar la ecolog\u00eda pol\u00edtica en Espa\u00f1a, una conversaci\u00f3n con \u00d3scar Urralburu - El Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/04\/19\/estructurar-la-ecologia-politica-en-espana-una-conversacion-con-oscar-urralburu\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/04\/19\/estructurar-la-ecologia-politica-en-espana-una-conversacion-con-oscar-urralburu\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/04\/SIPA_sipausa30324267_000013-scaled-1.jpg\",\"datePublished\":\"2023-04-19T15:35:27+00:00\",\"dateModified\":\"2023-04-19T15:35:29+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/04\/19\/estructurar-la-ecologia-politica-en-espana-una-conversacion-con-oscar-urralburu\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/es\/2023\/04\/19\/estructurar-la-ecologia-politica-en-espana-una-conversacion-con-oscar-urralburu\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/04\/19\/estructurar-la-ecologia-politica-en-espana-una-conversacion-con-oscar-urralburu\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/04\/SIPA_sipausa30324267_000013-scaled-1.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/04\/SIPA_sipausa30324267_000013-scaled-1.jpg\",\"width\":2560,\"height\":1917,\"caption\":\"The town of San Agustin amidst masses of shimmering plastic greenhouses, on the right the shallow lagoon Salinas de Cerrillos, aerial view, drone shot, Almeria province, Andalusia, Spain, Europe\/ibxtdr08556964\/imageBROKER.com\/Thomas Dressler\/SIPA\/2209261523\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2023\/04\/19\/estructurar-la-ecologia-politica-en-espana-una-conversacion-con-oscar-urralburu\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/legrandcontinent.eu\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estructurar la ecolog\u00eda pol\u00edtica en Espa\u00f1a, una conversaci\u00f3n con \u00d3scar Urralburu\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/\",\"name\":\"El Grand Continent\",\"description\":\"La escala pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\",\"name\":\"florent\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"caption\":\"florent\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estructurar la ecolog\u00eda pol\u00edtica en Espa\u00f1a, una conversaci\u00f3n con \u00d3scar Urralburu - El Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/es\/2023\/04\/19\/estructurar-la-ecologia-politica-en-espana-una-conversacion-con-oscar-urralburu\/","og_locale":"es_ES","og_type":"article","og_title":"Estructurar la ecolog\u00eda pol\u00edtica en Espa\u00f1a, una conversaci\u00f3n con \u00d3scar Urralburu - El Grand Continent","og_description":"Para entender las mutaciones de la pol\u00edtica territorial espa\u00f1ola hoy, hay que mirar hacia el sur. \u00d3scar Urralburu, coordinador regional de M\u00e1s Regi\u00f3n en Murcia, analiza la organizaci\u00f3n territorial fuera de los grandes centros urbanos y las tensiones entre infraestructuras y medio ambiente.","og_url":"https:\/\/legrandcontinent.eu\/es\/2023\/04\/19\/estructurar-la-ecologia-politica-en-espana-una-conversacion-con-oscar-urralburu\/","og_site_name":"El Grand Continent","article_published_time":"2023-04-19T15:35:27+00:00","article_modified_time":"2023-04-19T15:35:29+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/04\/gc-eloscarurralburu-scaled.jpg","type":"image\/jpeg"}],"author":"florent","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/04\/gc-eloscarurralburu-scaled.jpg","twitter_misc":{"Escrito por":"florent","Tiempo de lectura":"22 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/es\/2023\/04\/19\/estructurar-la-ecologia-politica-en-espana-una-conversacion-con-oscar-urralburu\/","url":"https:\/\/legrandcontinent.eu\/es\/2023\/04\/19\/estructurar-la-ecologia-politica-en-espana-una-conversacion-con-oscar-urralburu\/","name":"Estructurar la ecolog\u00eda pol\u00edtica en Espa\u00f1a, una conversaci\u00f3n con \u00d3scar Urralburu - El Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/es\/2023\/04\/19\/estructurar-la-ecologia-politica-en-espana-una-conversacion-con-oscar-urralburu\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/es\/2023\/04\/19\/estructurar-la-ecologia-politica-en-espana-una-conversacion-con-oscar-urralburu\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/04\/SIPA_sipausa30324267_000013-scaled-1.jpg","datePublished":"2023-04-19T15:35:27+00:00","dateModified":"2023-04-19T15:35:29+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/es\/2023\/04\/19\/estructurar-la-ecologia-politica-en-espana-una-conversacion-con-oscar-urralburu\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/es\/2023\/04\/19\/estructurar-la-ecologia-politica-en-espana-una-conversacion-con-oscar-urralburu\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/2023\/04\/19\/estructurar-la-ecologia-politica-en-espana-una-conversacion-con-oscar-urralburu\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/04\/SIPA_sipausa30324267_000013-scaled-1.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/04\/SIPA_sipausa30324267_000013-scaled-1.jpg","width":2560,"height":1917,"caption":"The town of San Agustin amidst masses of shimmering plastic greenhouses, on the right the shallow lagoon Salinas de Cerrillos, aerial view, drone shot, Almeria province, Andalusia, Spain, Europe\/ibxtdr08556964\/imageBROKER.com\/Thomas Dressler\/SIPA\/2209261523"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/es\/2023\/04\/19\/estructurar-la-ecologia-politica-en-espana-una-conversacion-con-oscar-urralburu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legrandcontinent.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Estructurar la ecolog\u00eda pol\u00edtica en Espa\u00f1a, una conversaci\u00f3n con \u00d3scar Urralburu"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/es\/#website","url":"https:\/\/legrandcontinent.eu\/es\/","name":"El Grand Continent","description":"La escala pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c","name":"florent","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","caption":"florent"}}]}},"lgc_categories":[{"id":98,"name":"Energ\u00eda y medio ambiente","slug":"energia-y-medio-ambiente"}],"lgc_author":{"id":168,"name":"Gerardo Mu\u00f1oz","slug":"gerardo-munoz","description":null,"first_name":null,"last_name":null,"picture":null},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/04\/SIPA_sipausa30324267_000013-scaled-1.jpg","width":2560,"height":1917,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2023\/04\/SIPA_sipausa30324267_000013-scaled-1.jpg","width":2560,"height":1917,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/15868","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/users\/1366"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/comments?post=15868"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/15868\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media\/15874"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media?parent=15868"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/categories?post=15868"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/tags?post=15868"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/staff?post=15868"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/editorial_format?post=15868"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/serie?post=15868"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/audience?post=15868"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/geo?post=15868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}