{"id":10656,"date":"2022-11-17T10:07:00","date_gmt":"2022-11-17T10:07:00","guid":{"rendered":"https:\/\/legrandcontinent.eu\/es\/?p=10656"},"modified":"2022-11-18T00:00:20","modified_gmt":"2022-11-18T00:00:20","slug":"por-una-antropologia-del-antropoceno","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/es\/2022\/11\/17\/por-una-antropologia-del-antropoceno\/","title":{"rendered":"Por una antropolog\u00eda del Antropoceno"},"content":{"rendered":"\n<p class=\"has-drop-cap\">Es se\u00f1al de \u00ab<em>alarma y m\u00e1xima preocupaci\u00f3n<\/em> en relaci\u00f3n con las actividades humanas que han provocado un incremento de 1,1&nbsp;\u00b0C en las temperaturas hasta la fecha, los efectos del cual ya se aprecian en todas las regiones, y con que los presupuestos de carbono actuales destinados a alcanzar el objetivo de temperatura del Pacto de Par\u00eds son poco ambiciosos y se exceden r\u00e1pidamente\u00bb. Esta advertencia, contenida en la declaraci\u00f3n final de la COP26 celebrada en Glasgow hace un a\u00f1o&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-10656' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2022\/11\/17\/por-una-antropologia-del-antropoceno\/#easy-footnote-bottom-1-10656' title='&lt;a href=&quot;https:\/\/www.un.org\/fr\/climatechange\/cop26#:~:text=Ils%20sont%20d&#039;ailleurs%20all%C3%A9s,objectif%20de%20l&#039;Accord%20de&quot;&gt;Leer aqu\u00ed.&lt;\/a&gt;'><sup>1<\/sup><\/a><\/span><\/span>, es otro recordatorio de la emergencia clim\u00e1tica. La cuesti\u00f3n ya no es por qu\u00e9 se produce el calentamiento global -ya no hay dudas entre los expertos de que es antropog\u00e9nico&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-10656' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2022\/11\/17\/por-una-antropologia-del-antropoceno\/#easy-footnote-bottom-2-10656' title='V\u00e9ase la primera parte del sexto informe del IPCC publicado el 6 de agosto de 2021: Climate Change 2021: The Physical Science Basis.'><sup>2<\/sup><\/a><\/span><\/span>-, sino c\u00f3mo reducir las emisiones de gases de efecto invernadero lo antes posible para alcanzar el objetivo de la neutralidad del carbono a mediados de siglo. Sin embargo, puede ser \u00fatil volver a la ra\u00edz del problema: \u00bfc\u00f3mo llegamos hasta aqu\u00ed? Dado que el dedo se\u00f1ala al ser humano, una forma de abordar esta cuesti\u00f3n es mediante un enfoque antropol\u00f3gico. <a href=\"https:\/\/legrandcontinent.eu\/es\/2022\/06\/25\/una-espiral-de-autodestruccion\/\">Como dice Jean Vioulac<\/a>, \u00abla cuesti\u00f3n es saber por qu\u00e9 y c\u00f3mo un antropoide pudo poner en marcha un proceso de antropizaci\u00f3n de la naturaleza que hoy conduce a su devastaci\u00f3n\u00bb. La investigaci\u00f3n antropol\u00f3gica as\u00ed entendida es necesariamente hist\u00f3rica, ya que se sit\u00faa en una historia de largo plazo, de la que s\u00f3lo trataremos la \u00faltima fase, aquella en la que la devastaci\u00f3n de la naturaleza por parte del ser humano es cada vez m\u00e1s r\u00e1pida: desde el final de la Segunda Guerra Mundial, los m\u00faltiples indicadores que miden los impactos destructivos del hombre sobre la naturaleza han seguido curvas exponenciales. Esto se ha llamado, en la bibliograf\u00eda especializada, \u00abla Gran Aceleraci\u00f3n\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-10656' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2022\/11\/17\/por-una-antropologia-del-antropoceno\/#easy-footnote-bottom-3-10656' title='A este respecto, me gustar\u00eda remitirme a mi libro &lt;em&gt;L&amp;#8217;acc\u00e9l\u00e9ration de l&amp;#8217;histoire. Des Lumi\u00e8res \u00e0 l&amp;#8217;Anthropoc\u00e8ne&lt;\/em&gt;, Par\u00eds, Seuil, 2022, cap\u00edtulo VI.'><sup>3<\/sup><\/a><\/span><\/span>. En este tenso contexto, es comprensible que la COP26 hable de una \u00abd\u00e9cada cr\u00edtica\u00bb para la acci\u00f3n. \u00bfC\u00f3mo ha podido el ser humano encontrarse en una situaci\u00f3n de peligro creciente para s\u00ed mismo y para otras especies? Esta cuesti\u00f3n aparece en la bibliograf\u00eda sobre el Antropoceno, donde algunos autores se preguntan: \u00bfqui\u00e9n es el Anthropos que est\u00e1 en el origen del Antropoceno&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-4-10656' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2022\/11\/17\/por-una-antropologia-del-antropoceno\/#easy-footnote-bottom-4-10656' title='Me baso sobre todo en el art\u00edculo de Bronislaw Szerszynski, \u00abThe End of the End of Nature: The Anthropocene and the Fate of the Human\u00bb, &lt;em&gt;The Oxford Literary Review&lt;\/em&gt;, 34.2, 2012, pp. 165-184.'><sup>4<\/sup><\/a><\/span><\/span>? En otras palabras, \u00bfc\u00f3mo se convirti\u00f3 la especie humana en un agente geol\u00f3gico y biol\u00f3gico capaz de competir con las grandes fuerzas de la naturaleza, hasta el punto de alterar sus equilibrios fundamentales? Este controvertido concepto del \u00abAntropoceno\u00bb -la era del hombre- a\u00fan no ha sido validado por los organismos geol\u00f3gicos internacionales. Se le ha criticado por diluir la responsabilidad del calentamiento global en una humanidad an\u00f3nima, ignorando las diferencias geogr\u00e1ficas, econ\u00f3micas y pol\u00edticas que son esenciales para entender el fen\u00f3meno. Por ello, se ha sustituido por una serie de \u00abX-cenos\u00bb para especificarlo: el \u00abAngloceno\u00bb, el \u00abCapitaloceno\u00bb, el \u00abCarboceno\u00bb, el \u00abIndustrialoceno\u00bb, el \u00abMolismoceno\u00bb, el \u00abOccidentaloceno\u00bb, el \u00abPlantationoceno\u00bb, el \u00abTecnoceno\u00bb y, m\u00e1s recientemente, el \u00abAndroceno\u00bb y el \u00abPIBceno\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-5-10656' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2022\/11\/17\/por-una-antropologia-del-antropoceno\/#easy-footnote-bottom-5-10656' title='Cf. Adela\u00efde Bon, Sandrine Roudaut, Sandrine Rousseau, &lt;em&gt;Par-del\u00e0 l\u2019androc\u00e8ne&lt;\/em&gt;, Par\u00eds, Seuil, \u00ab&amp;nbsp;Libelle&amp;nbsp;\u00bb, 2022; y Timoth\u00e9e Parrique, &lt;em&gt;Ralentir&amp;nbsp;ou p\u00e9rir : L&amp;#8217;\u00e9conomie de la d\u00e9croissance&lt;\/em&gt;, Par\u00eds, Seuil, 2022.'><sup>5<\/sup><\/a><\/span><\/span>. El objetivo de este art\u00edculo no es discutir la pertinencia de estas nociones alternativas, sino aportar algunos elementos para una antropolog\u00eda del Antropoceno, con el fin de arrojar luz sobre los retos actuales de la emergencia clim\u00e1tica.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>\u00bfC\u00f3mo se convirti\u00f3 la especie humana en un agente geol\u00f3gico y biol\u00f3gico capaz de competir con las grandes fuerzas de la naturaleza, hasta el punto de alterar sus equilibrios fundamentales?<\/p><cite>CHRISTOPHE BOUTON<\/cite><\/blockquote><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Del Homo faber al Homo consumens<\/strong><\/h2>\n\n\n\n<p>En <em>La ideolog\u00eda alemana<\/em>, que escribi\u00f3 con Engels, Marx sostiene que el hombre se diferencia del animal no en la conciencia de s\u00ed mismo ni en el pensamiento, sino en el hecho de que tiene que producir sus medios de existencia, que tiene que transformar la naturaleza para satisfacer sus necesidades vitales, para alimentarse, alojarse, vestirse, etc. El Homo sapiens es ante todo un Homo faber: \u00abLos hombres tienen historia porque se ven obligados a <em>producir<\/em> su vida y deben, adem\u00e1s, producirla de un <em>determinado <\/em>modo: esta necesidad est\u00e1 impuesta por su organizaci\u00f3n f\u00edsica\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-6-10656' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2022\/11\/17\/por-una-antropologia-del-antropoceno\/#easy-footnote-bottom-6-10656' title='K.&amp;nbsp;Marx, F. Engels, &lt;em&gt;La ideolog\u00eda alemana&lt;\/em&gt;, Wenceslao Roces (trad.), Grijalbo, Barcelona, 1968, p. 31, nota.'><sup>6<\/sup><\/a><\/span><\/span>. Marx retoma el mito de Epimeteo y Prometeo a su manera. La desnudez, la vulnerabilidad y la debilidad originales del cuerpo humano, el hecho de que no tenga protecci\u00f3n contra el fr\u00edo ni las heridas (como un pelaje o un caparaz\u00f3n), ni \u00f3rganos eficaces para defenderse (como cuernos o garras), ni sentidos especializados (como la aguda vista de las aves de rapi\u00f1a o el olfato altamente sensible de los felinos), o incluso los instintos para fabricar espont\u00e1neamente los medios de supervivencia (la tela de ara\u00f1a, el nido de los p\u00e1jaros), todas esas carencias son compensadas por la inteligencia y la t\u00e9cnica, que permiten al hombre <em>producir<\/em> sus medios de subsistencia. El modo de vida de esta especie implica, pues, un determinado modelo de producci\u00f3n, que cambia a lo largo de su historia. \u00bfPor qu\u00e9 los humanos no han mantenido el mismo modelo de producci\u00f3n y la misma forma de vida? \u00bfPor qu\u00e9 no han seguido siendo siempre cazadores-recolectores que viven con las mismas herramientas, en armon\u00eda con su entorno natural? S\u00f3lo mencionaremos aqu\u00ed dos respuestas sugeridas por Marx. Por un lado, el crecimiento demogr\u00e1fico aument\u00f3 la cantidad de necesidades a satisfacer, por otro lado, la satisfacci\u00f3n de las primeras necesidades dio lugar a otras nuevas: \u00abla primera necesidad una vez satisfecha, la acci\u00f3n de satisfacerla y el instrumento ya adquirido de esta satisfacci\u00f3n empujan a nuevas necesidades, &#8211; y esta producci\u00f3n de nuevas necesidades es el primer hecho hist\u00f3rico\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-7-10656' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2022\/11\/17\/por-una-antropologia-del-antropoceno\/#easy-footnote-bottom-7-10656' title='&lt;em&gt;Ibid&lt;\/em&gt;.'><sup>7<\/sup><\/a><\/span><\/span>. Sin entrar en la historia de los sucesivos modos de producci\u00f3n distinguidos por Marx -asi\u00e1tico, antiguo, feudal y capitalista-, subrayemos que es este \u00faltimo el que resulta obviamente decisivo para entender el Antropoceno. Pues la carrera por la productividad inherente al capitalismo no s\u00f3lo transforma al Homo faber en un \u00abanimal laborans\u00bb, seg\u00fan la f\u00f3rmula de Hannah Arendt&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-8-10656' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2022\/11\/17\/por-una-antropologia-del-antropoceno\/#easy-footnote-bottom-8-10656' title='Cf. H. Arendt, &lt;em&gt;La condici\u00f3n humana&lt;\/em&gt;, Paid\u00f3s, Barcelona, 1998.'><sup>8<\/sup><\/a><\/span><\/span>, sino que tambi\u00e9n conduce al desarrollo del maquinismo y a la extracci\u00f3n de cantidades cada vez mayores de combustibles f\u00f3siles, que ahora sabemos que son los principales causantes del calentamiento global. De ah\u00ed la innegable relevancia del concepto \u00abCapitaloceno\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-9-10656' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2022\/11\/17\/por-una-antropologia-del-antropoceno\/#easy-footnote-bottom-9-10656' title='Cf. por ejemplo, Andreas Malm, &lt;em&gt;L\u2019Anthropoc\u00e8ne contre l\u2019histoire. Le r\u00e9chauffement climatique \u00e0 l\u2019\u00e8re du capital&lt;\/em&gt;, \u00c9tienne Dobenesque (trad.), Par\u00eds,La Fabrique, 2017.'><sup>9<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-large\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2022\/11\/saadiyat-pylons-scaled-1.jpg\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"2560\"\n        data-pswp-height=\"2067\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2022\/11\/saadiyat-pylons-scaled-1-330x266.jpg\"\r\n                media=\"(max-width: 374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2022\/11\/saadiyat-pylons-scaled-1-690x557.jpg\"\r\n                media=\"(max-width: 989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2022\/11\/saadiyat-pylons-scaled-1-1340x1082.jpg\"\r\n                media=\"(min-width: 990px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2022\/11\/saadiyat-pylons-scaled-1-125x101.jpg\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">Richard Allenby-Pratt, &#8216;saadiytat pylons-6-6&#8217;, <em>consumption<\/em>.\r\n\u00abA partir de 2011, pas\u00e9 varios a\u00f1os fotografiando el entorno cambiante de los Emiratos \u00c1rabes Unidos. Investigu\u00e9 este proyecto utilizando im\u00e1genes de sat\u00e9lite, buscando los lugares en los que el desarrollo humano, tanto urbano como industrial, estaba afectando al antiguo paisaje. Lo llamo \u00abantiguo\u00bb porque gran parte del paisaje nunca ha sido utilizado por el ser humano, con la posible excepci\u00f3n del pastoreo de cabras en las monta\u00f1as y de camellos en el desierto\u00bb. Richard Allenby-Pratt<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<p>En el transcurso del siglo XX, la cr\u00edtica del capitalismo se extendi\u00f3 al consumo, que hab\u00eda sido menos estudiado por Marx, a pesar de ser una parte indispensable del modelo de producci\u00f3n capitalista, ya que rige lo que sucede una vez que las mercanc\u00edas salen de la f\u00e1brica. As\u00ed, Erich Fromm, miembro de la primera generaci\u00f3n de la Escuela de Fr\u00e1ncfort, acu\u00f1\u00f3 en los a\u00f1os sesenta el concepto de Homo consumens, que es la otra cara del Homo laborans: \u00abEl Homo consumens es el hombre cuyo principal objetivo no es <em>poseer<\/em> cosas, sino <em>consumir<\/em> m\u00e1s y m\u00e1s, y as\u00ed compensar su vac\u00edo interior, su pasividad, su soledad y su ansiedad\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-10-10656' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2022\/11\/17\/por-una-antropologia-del-antropoceno\/#easy-footnote-bottom-10-10656' title='Erich Fromm, \u00abThe Application of Humanist Psychoanalysis to Marx\u2019s Theory\u00bb, en Erich Fromm (ed.), &lt;em&gt;Socialist Humanism: An International Symposium&lt;\/em&gt;, Garden City, Nueva York, Doubleday, 1965, p. 214.'><sup>10<\/sup><\/a><\/span><\/span>. No hay consumo sin producci\u00f3n, pero lo contrario tambi\u00e9n es cierto. Sin el frenes\u00ed del consumo que caracteriza a las sociedades occidentales modernas, cuyos s\u00edmbolos son sin duda los centros comerciales o los gigantescos malls estadounidenses, la m\u00e1quina capitalista y su productivismo se agarrotar\u00edan r\u00e1pidamente.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Homo colossus<\/strong><\/h2>\n\n\n\n<p>La denuncia de la \u00absociedad de consumo\u00bb es un conocido leitmotiv de la segunda mitad del siglo XX. Lleva a interpretar el Antropoceno no s\u00f3lo como el \u00abCapitaloceno\u00bb, sino tambi\u00e9n como el \u00abMolismoceno\u00bb, la \u00abera de la contaminaci\u00f3n\u00bb, si es cierto que el consumismo provoca una cantidad colosal de desechos que contribuyen a la devastaci\u00f3n de la naturaleza, como muestra la imagen del s\u00e9ptimo continente de pl\u00e1sticos que se ha formado en medio del Pac\u00edfico. Lo que me interesa en particular es se\u00f1alar que el problema del consumo ha dado lugar a una tesis antropol\u00f3gica espec\u00edfica, que apareci\u00f3 en el pensamiento ecol\u00f3gico unos a\u00f1os antes de los debates sobre el calentamiento global y el Antropoceno: el Homo colossus. La noci\u00f3n fue propuesta por el soci\u00f3logo medioambiental William R. Catton en 1980, en su libro pionero <em>Overshoot. The Ecological Basis of Revolutionary Change<\/em>. Se\u00f1ala la tendencia del ser humano, desde el descubrimiento de los combustibles f\u00f3siles a principios del siglo XIX, a producir y consumir una cantidad de energ\u00eda cada vez mayor, una cantidad totalmente desproporcionada con respecto a su tama\u00f1o y sus necesidades: \u00abCuando se descubrieron los recursos minerales y de combustibles f\u00f3siles de la Tierra, el Homo sapiens a\u00fan no estaba preparado por la evoluci\u00f3n para aprovecharlos. Tan pronto como la tecnolog\u00eda permiti\u00f3 a la humanidad hacerlo, la gente pas\u00f3 r\u00e1pidamente (y sin prever las consecuencias finales) a un estilo de vida con un alto nivel de consumo de energ\u00eda. El hombre se ha convertido en un detrit\u00edvoro, un Homo colossus. Nuestra especie ha florecido y ahora debemos esperar, de un modo u otro, un choque como consecuencia natural de tal desarrollo\u201d&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-11-10656' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2022\/11\/17\/por-una-antropologia-del-antropoceno\/#easy-footnote-bottom-11-10656' title='William R. Catton, &lt;em&gt;Overshoot: The Ecological Basis of Revolutionary Change&lt;\/em&gt;, Urbana, University of Illinois Press, 1980, p.&amp;nbsp;170.'><sup>11<\/sup><\/a><\/span><\/span>. El Homo colossus es un \u00abdetrit\u00edvoro\u00bb, porque los combustibles f\u00f3siles de los que se alimenta son residuos naturales (carb\u00f3n, gas, petr\u00f3leo). Se trata, obviamente, de una figura del hombre hist\u00f3ricamente situada. En el cap\u00edtulo 9, titulado \u00abLa naturaleza y la naturaleza del hombre\u00bb, Catton retoma la concepci\u00f3n del Homo sapiens como Homo faber. El hombre es un animal capaz de dotarse, a trav\u00e9s de la tecnolog\u00eda, de \u00ab\u00f3rganos extra\u00edbles\u00bb, siendo las herramientas, en su opini\u00f3n, s\u00f3lo pr\u00f3tesis del cuerpo humano. A continuaci\u00f3n, esboza la \u00abtr\u00e1gica historia del \u00e9xito humano\u00bb. A trav\u00e9s de las herramientas y luego de la tecnolog\u00eda, los seres humanos han creado muchos nichos ambientales, y finalmente, un \u00fanico nicho: el mundo entero. Pudieron hacerlo porque fueron capaces de transformar su h\u00e1bitat aumentando cada vez m\u00e1s la \u00abcapacidad de carga\u00bb de su entorno&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-12-10656' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2022\/11\/17\/por-una-antropologia-del-antropoceno\/#easy-footnote-bottom-12-10656' title='Este concepto, derivado de la ecolog\u00eda de las poblaciones, se refiere al tama\u00f1o m\u00e1ximo de la poblaci\u00f3n de un organismo que un entorno determinado puede soportar indefinidamente.'><sup>12<\/sup><\/a><\/span><\/span>. La tecnolog\u00eda les ha permitido prosperar a un ritmo mucho mayor que la evoluci\u00f3n biol\u00f3gica. Catton ilustra este punto con una an\u00e9cdota. Mientras circula detr\u00e1s de un ciclista por una peque\u00f1a carretera de monta\u00f1a, reflexiona que el ciclista s\u00f3lo tard\u00f3 unas horas en improvisar un espejo retrovisor en su bicicleta, \u00a1mientras que el conejo tard\u00f3 decenas de miles de a\u00f1os en conseguir una vista que le permitiera ver ligeramente por detr\u00e1s!&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>El problema del consumo ha dado lugar a una tesis antropol\u00f3gica espec\u00edfica, que apareci\u00f3 en el pensamiento ecol\u00f3gico unos a\u00f1os antes de los debates sobre el calentamiento global y el Antropoceno: el Homo colossus.<\/p><cite>CHRISTOPHE BOUTON<\/cite><\/blockquote><\/figure>\n\n\n\n<p>A partir de 1800, el modelo de vida agrario fue dejando paso a un modelo de vida industrial m\u00e1s r\u00e1pido, basado en el uso intensivo de combustibles f\u00f3siles. Fue entonces cuando el Homo sapiens se convirti\u00f3 en Homo colossus, es decir, en un ser desproporcionado, un \u00abgigante con pr\u00f3tesis\u00bb que necesitaba consumir cantidades de energ\u00eda cada vez mayores. El Homo colossus es una consecuencia del Homo faber, ya que la fabricaci\u00f3n, en el sentido de producir bienes, consume energ\u00eda, y del Homo consumens, en la medida en que muchas actividades dom\u00e9sticas tambi\u00e9n utilizan energ\u00eda: en primer lugar el transporte, pero tambi\u00e9n los electrodom\u00e9sticos, la calefacci\u00f3n, etc. \u00bfC\u00f3mo no reconocer en esta figura del Homo colossus el antiguo tema de la <em>hibris<\/em>? Con la diferencia de que el castigo de Prometeo ya no es estar encadenado: es el riesgo de desaparecer. Catton aplica el motivo de la iron\u00eda de la historia a la \u00abhistoria ecol\u00f3gica de la humanidad\u00bb: la tecnolog\u00eda, destinada a aumentar la capacidad de carga del entorno humano, se ha convertido finalmente en la causa de su \u00abrebasamiento\u00bb. El Homo Colossus es un gigante con pies de barro. Cuanto m\u00e1s crezca, m\u00e1s probable ser\u00e1 que se derrumbe.<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-large\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2022\/11\/JA-cars-3-scaled-1.jpg\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"2560\"\n        data-pswp-height=\"2052\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2022\/11\/JA-cars-3-scaled-1-330x265.jpg\"\r\n                media=\"(max-width: 374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2022\/11\/JA-cars-3-scaled-1-690x553.jpg\"\r\n                media=\"(max-width: 989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2022\/11\/JA-cars-3-scaled-1-1340x1074.jpg\"\r\n                media=\"(min-width: 990px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2022\/11\/JA-cars-3-scaled-1-125x100.jpg\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">Richard Allenby-Pratt, &#8216;JA cars 3-4-4&#8217;, <em>consumption<\/em><\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<p>El Homo colossus encarna una de las causas de la aceleraci\u00f3n t\u00e9cnica observada en Occidente desde la Revoluci\u00f3n Industrial: el aumento de la velocidad de producci\u00f3n, del transporte y de la comunicaci\u00f3n s\u00f3lo ha sido posible gracias a un suministro de energ\u00eda cada vez m\u00e1s considerable. Este concepto tiene probablemente el defecto de no diferenciar entre pa\u00edses. Debe situarse hist\u00f3rica <em>y<\/em> geogr\u00e1ficamente. El Homo colossus se asent\u00f3 principalmente en Europa y Am\u00e9rica del Norte hasta la d\u00e9cada de 1960, antes de conquistar la India y China. Y sabemos que muchos pa\u00edses del Sur \u00aben v\u00edas de desarrollo\u00bb -incluidos los pa\u00edses africanos donde se celebra la pr\u00f3xima COP27- se han quedado en una fase \u00abprecolosal\u00bb, mientras sufren todas las consecuencias de los diversos impactos del Homo colossus en la naturaleza. A pesar de estas limitaciones, el concepto tiene el m\u00e9rito de subrayar la importancia del problema energ\u00e9tico en la relaci\u00f3n entre el hombre y la naturaleza. Ya en 1972, el periodista estadounidense Richard Niel denunci\u00f3 el aumento exponencial del consumo de electricidad en Estados Unidos, que, de media, proporcionaba a cada individuo el equivalente a cuarenta esclavos&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-13-10656' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2022\/11\/17\/por-una-antropologia-del-antropoceno\/#easy-footnote-bottom-13-10656' title='G. Piel, &lt;em&gt;The Acceleration of History&lt;\/em&gt;, Nueva York, Alfred A. Knopf, 1972, p.&amp;nbsp;40.'><sup>13<\/sup><\/a><\/span><\/span>. M\u00e1s recientemente, el historiador del medio ambiente John McNeil ha documentado lo que llama la \u00aborg\u00eda energ\u00e9tica\u00bb de las sociedades occidentales modernas&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-14-10656' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2022\/11\/17\/por-una-antropologia-del-antropoceno\/#easy-footnote-bottom-14-10656' title='\u00abEnergy, Population, and Environmental Change Since 1750: Entering the Anthropocene \u00bb, en J. R. McNeill y Kenneth L Pomeranz (dir.), &lt;em&gt;The Cambridge World History, vol. 7.1, Production, Destruction and Connection, 1750-Present. Part I: Structures, Spaces and Boundary Making&lt;\/em&gt;, Cambridge, Cambridge University Press, 2015, pp.&amp;nbsp;51-82.'><sup>14<\/sup><\/a><\/span><\/span>. Los cazadores-recolectores, cuyo modo de vida perdur\u00f3 durante decenas de miles de generaciones hasta la revoluci\u00f3n agr\u00edcola de finales del Pleistoceno (hace unos 12 mil a\u00f1os), consum\u00edan aproximadamente el 2% de la energ\u00eda diaria utilizada por los humanos del siglo XXI. Con la invenci\u00f3n de la agricultura y la ganader\u00eda, el ser humano fue sextuplicando la cantidad de energ\u00eda cosechada, y este nivel se estabiliz\u00f3 hasta finales del siglo XVIII, sin que la invenci\u00f3n del molino de viento o de agua alterara significativamente estos datos. La era del carb\u00f3n (de 1750 a 1950), y luego la del petr\u00f3leo (de 1950 a la actualidad), marcaron un salto cualitativo en el consumo de energ\u00eda, debido a la inmensa reserva de energ\u00eda solar fosilizada acumulada durante 500 millones de a\u00f1os. La org\u00eda energ\u00e9tica a la que se refiere McNeil es el hecho de que, en un siglo, desde 1920 hasta el presente, la especie humana probablemente haya consumido m\u00e1s energ\u00eda que en toda la historia de la humanidad, lo que, en retrospectiva, apoya la tesis del Homo colossus de Catton y la relaciona con el tema de la \u00abGran Aceleraci\u00f3n\u00bb: \u00abLos humanos han cambiado el medio ambiente, y el medio ambiente, al cambiar, ha cambiado a los humanos. Este abrazo es como siempre ha sido, salvo que \u00faltimamente ha adquirido una intensidad y una velocidad cada vez mayores, como un patinador art\u00edstico que gira en una espiral cada vez m\u00e1s cerrada\u201d&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-15-10656' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2022\/11\/17\/por-una-antropologia-del-antropoceno\/#easy-footnote-bottom-15-10656' title='&lt;em&gt;Ibid&lt;\/em&gt;., p.&amp;nbsp;80.'><sup>15<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>El Homo continens<\/strong><\/h2>\n\n\n\n<p>Est\u00e1 claro que la aproximaci\u00f3n antropol\u00f3gica al Antropoceno no consiste en naturalizar las figuras humanas, que por el contrario son fundamentalmente hist\u00f3ricas. M\u00e1s bien, concibe al ser humano como una especie dotada de un conjunto indefinido de disposiciones que pueden desarrollarse o no en funci\u00f3n de los contextos hist\u00f3ricos, econ\u00f3micos y sociales. El Homo colossus apareci\u00f3, pues, en un momento dado, con la Revoluci\u00f3n Industrial, y es una criatura hipertrofiada del modo de producci\u00f3n capitalista. Precisamente porque es s\u00f3lo una posibilidad entre otras de lo que puede llegar a ser la especie humana, esta figura puede ser modificada o sustituida por otra. Por eso la tr\u00e1gica historia de la humanidad que reconstruye Catton no termina con un catastrofismo que anuncie el fin de la historia (humana). Pide una \u00abmodestia ecol\u00f3gica\u00bb que reconozca el fin de la \u00abera de la exuberancia y la abundancia\u00bb anunciada por la primera crisis del petr\u00f3leo de 1973. La noci\u00f3n de \u00abmodestia\u00bb, que recuerda a los discursos actuales de moda sobre la \u00absobriedad\u00bb y el \u00abfin de la abundancia\u00bb, significa para Catton que el ser humano debe vivir sin aumentar la capacidad de carga de su entorno, consumiendo los recursos a un ritmo que no supere el tiempo necesario para su renovaci\u00f3n. La antropolog\u00eda del hombre como destructor de la naturaleza adquiere, pues, una dimensi\u00f3n normativa, que conduce a una \u00e9tica de la sobriedad que parece inscribirse en la \u00e9tica de la responsabilidad preconizada por Hans Jonas, quien al mismo tiempo denunciaba a \u00abPrometeo definitivamente desatado, al que la ciencia confiere fuerzas nunca antes conocidas y la econom\u00eda su impulso desenfrenado\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-16-10656' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2022\/11\/17\/por-una-antropologia-del-antropoceno\/#easy-footnote-bottom-16-10656' title='H. Jonas, &lt;em&gt;Le Principe Responsabilit\u00e9. Une \u00e9thique pour la civilisation technologique&lt;\/em&gt; (1979), Jean Greisch (trad.), Par\u00eds, Champ-Flammarion, 1998, p.&amp;nbsp;15.'><sup>16<\/sup><\/a><\/span><\/span>. <\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>El Homo colossus apareci\u00f3 en un momento dado, con la Revoluci\u00f3n Industrial, y es una criatura hipertrofiada del modo de producci\u00f3n capitalista. Precisamente porque es s\u00f3lo una posibilidad entre otras de lo que puede llegar a ser la especie humana, esta figura puede ser modificada o sustituida por otra. <\/p><cite>CHRISTOPHE BOUTON<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Podr\u00edamos llamar \u00abHomo sobrius\u00bb o, mejor a\u00fan, \u00abHomo continens\u00bb a la figura del hombre que emerge en los debates actuales sobre el calentamiento global y la sobriedad energ\u00e9tica. \u00abContinens\u00bb en el sentido latino de la palabra: sobrio, moderado. Si el Homo consumens y el Homo colossus son conceptos descriptivos, te\u00f1idos de una normatividad cr\u00edtica, el Homo continens es un concepto prescriptivo, que pretende romper con el imaginario consumista y productivista de las sociedades modernas. Designa un modelo de seres humanos que frenan su consumo (el verbo \u00abcontineo\u00bb significa contener, frenar), contienen los diversos impulsos de compra que suscita la omnipresencia de la publicidad y la l\u00f3gica del reconocimiento social&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-17-10656' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2022\/11\/17\/por-una-antropologia-del-antropoceno\/#easy-footnote-bottom-17-10656' title='En &lt;em&gt;Ralentir ou p\u00e9rir&lt;\/em&gt; (&lt;em&gt;op. cit&lt;\/em&gt;., cap\u00edtulo 6). T. Parrique distingue entre \u00abfrugalidad\u00bb, que consiste en renunciar a actividades que consumen energ\u00eda, como volar, y \u00absobriedad\u00bb, que es sin\u00f3nimo de moderaci\u00f3n (ir menos lejos).'><sup>17<\/sup><\/a><\/span><\/span>. Llama, al modo de un nuevo ideal a alcanzar, al fin del Homo colossus, al que se le pide que baje, que vuelva <em>a la tierra<\/em> de cierta forma.<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-large\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2022\/11\/Palm-JA-16-scaled-1.jpg\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"2560\"\n        data-pswp-height=\"2084\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2022\/11\/Palm-JA-16-scaled-1-330x269.jpg\"\r\n                media=\"(max-width: 374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2022\/11\/Palm-JA-16-scaled-1-690x562.jpg\"\r\n                media=\"(max-width: 989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2022\/11\/Palm-JA-16-scaled-1-1340x1091.jpg\"\r\n                media=\"(min-width: 990px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2022\/11\/Palm-JA-16-scaled-1-125x102.jpg\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">Richard Allenby-Pratt, &#8216;Palm JA 16-2-2, <em>consumption<\/em><\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<h2 class=\"wp-block-heading\"><strong>\u00bfEs una nueva iron\u00eda de la historia?<\/strong><\/h2>\n\n\n\n<p>En las medidas pol\u00edticas para combatir el calentamiento global, la acci\u00f3n suele dirigirse a la producci\u00f3n, probablemente porque es m\u00e1s f\u00e1cil de controlar que la demanda de los consumidores. Esto puede verse, por ejemplo, en las recomendaciones de la COP26 para detener o revertir la deforestaci\u00f3n, reducir las emisiones de metano, abandonar el carb\u00f3n, desarrollar un transporte ecol\u00f3gico de cero emisiones, acabar con la producci\u00f3n de veh\u00edculos de combustibles f\u00f3siles, etc. Pero el consumo dom\u00e9stico es otra importante palanca de acci\u00f3n, ya que los consumidores tienen cierto poder de elecci\u00f3n, pueden o no poner en pr\u00e1ctica la \u00e9tica de la sobriedad&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-18-10656' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2022\/11\/17\/por-una-antropologia-del-antropoceno\/#easy-footnote-bottom-18-10656' title='Cabe se\u00f1alar que en la tercera parte de su sexto informe, publicado el 4 de abril de 2022, el IPCC menciona acciones individuales para reducir el consumo de energ\u00eda (reducci\u00f3n de los viajes en coche y en avi\u00f3n, disminuci\u00f3n de las temperaturas de la calefacci\u00f3n, limitaci\u00f3n del uso de aparatos el\u00e9ctricos, etc.).'><sup>18<\/sup><\/a><\/span><\/span>. Sin embargo, este discurso encuentra al menos dos obst\u00e1culos. Si el imperativo de sobriedad se dirige a todos los individuos de forma indiscriminada, mientras una parte importante de la poblaci\u00f3n de las sociedades occidentales y de los pa\u00edses del Sur vive por debajo del umbral de la pobreza, s\u00f3lo puede ser percibido por ellos como una provocaci\u00f3n. Por lo tanto, es necesario tener en cuenta las desigualdades econ\u00f3micas y sociales en este \u00e1mbito. Una segunda dificultad es que la responsabilizaci\u00f3n del consumidor, por muy \u00fatil que sea, tiende a hacer recaer sobre los hombros de los individuos la carga de los cambios en el estilo de vida a trav\u00e9s de \u00abpeque\u00f1os gestos\u00bb que s\u00f3lo son eficaces si van acompa\u00f1ados de decisiones pol\u00edticas a mayor escala destinadas a combatir el productivismo y el consumismo. Algunos defensores del decrecimiento, como Timoth\u00e9e Parrique, que considera que la \u00abobsesi\u00f3n por el crecimiento\u00bb es una \u00abanomal\u00eda hist\u00f3rica y antropol\u00f3gica\u00bb, abogan por la intervenci\u00f3n de los gobiernos para \u00abfrenar\u00bb el consumo, como la prohibici\u00f3n de los anuncios de productos que consumen mucha energ\u00eda, como los famosos veh\u00edculos SUV, o incluso toda la publicidad en los espacios p\u00fablicos&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-19-10656' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/es\/2022\/11\/17\/por-una-antropologia-del-antropoceno\/#easy-footnote-bottom-19-10656' title='Cf. &lt;em&gt;Ralentir ou p\u00e9rir&lt;\/em&gt; (&lt;em&gt;op. cit. &lt;\/em&gt;cap. 6).'><sup>19<\/sup><\/a><\/span><\/span>.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>La ecolog\u00eda de guerra de Pierre Charbonnier, es, si no un ardid de la raz\u00f3n, al menos una nueva iron\u00eda de la historia, siempre que no acabe en una cat\u00e1strofe nuclear civil o militar<\/p><cite>CHRISTOPHE BOUTON&nbsp;<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Queda por ver si la cuesti\u00f3n de la sobriedad energ\u00e9tica se pondr\u00e1 sobre la mesa en la pr\u00f3xima COP y c\u00f3mo. A la espera de decisiones hipot\u00e9ticas, se han producido nuevos acontecimientos que podr\u00edan acelerar la implantaci\u00f3n de la \u00e9tica de la sobriedad. La guerra en Ucrania, al provocar una fuerte ca\u00edda de las importaciones de gas y petr\u00f3leo ruso a Europa, ha obligado a muchos pa\u00edses de la UE a elaborar a toda prisa \u00abplanes de sobriedad energ\u00e9tica\u00bb a partir de este invierno. <a href=\"https:\/\/legrandcontinent.eu\/es\/2022\/03\/18\/el-nacimiento-de-la-ecologia-de-la-guerra\/\">Esta ecolog\u00eda de guerra<\/a>, seg\u00fan la expresi\u00f3n de Pierre Charbonnier, es, si no un ardid de la raz\u00f3n, al menos una nueva iron\u00eda de la historia, siempre que no acabe en una cat\u00e1strofe nuclear civil o militar. En otro orden de cosas, las cat\u00e1strofes naturales ocurridas este verano, sin precedentes por su magnitud y frecuencia -olas de calor, tormentas, inundaciones, incendios- pueden desencadenar una toma de conciencia sobre la necesidad de cambiar <em>ya<\/em> nuestro modo de vida, con la idea de que nadie es inmune a los efectos del calentamiento global, que ya son tangibles. Estamos ante un acortamiento de los plazos, una experiencia singular de aceleraci\u00f3n de la historia. En la \u00e9poca en que Jonas la desarroll\u00f3, en los a\u00f1os 80, la \u00e9tica de la responsabilidad se ocupaba del presente, que a\u00fan estaba lejos de las generaciones futuras. Luego se refer\u00eda al futuro de las generaciones presentes en la d\u00e9cada de 2000 y, finalmente, hoy, cuando se reformula en t\u00e9rminos de una \u00e9tica de la sobriedad, su imperativo de preservar el planeta se refiere tambi\u00e9n al presente de las generaciones presentes, nuestro presente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfAnunciar\u00e1 la era de la sobriedad energ\u00e9tica un cambio del Homo consumens al Homo continens?<\/p>\n","protected":false},"author":1366,"featured_media":10660,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-editorials.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":18,"footnotes":""},"categories":[98],"tags":[],"staff":[341],"editorial_format":[1471],"serie":[],"audience":[],"geo":[198],"class_list":["post-10656","post","type-post","status-publish","format-standard","hentry","category-energia-y-medio-ambiente","staff-christophe-bouton","editorial_format-piezas-de-doctrinas","geo-mundo"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":10660,"excerpt":"\u00bfAnunciar\u00e1 la era de la sobriedad energ\u00e9tica un cambio del Homo consumens al Homo continens?","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Por una antropolog\u00eda del Antropoceno - El Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/es\/2022\/11\/17\/por-una-antropologia-del-antropoceno\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Por una antropolog\u00eda del Antropoceno - El Grand Continent\" \/>\n<meta property=\"og:description\" content=\"\u00bfAnunciar\u00e1 la era de la sobriedad energ\u00e9tica un cambio del Homo consumens al Homo continens?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/es\/2022\/11\/17\/por-una-antropologia-del-antropoceno\/\" \/>\n<meta property=\"og:site_name\" content=\"El Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-17T10:07:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-18T00:00:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2022\/11\/gc-elantropoceno-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"florent\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2022\/11\/gc-elantropoceno-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"florent\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"18 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2022\/11\/17\/por-una-antropologia-del-antropoceno\/\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/2022\/11\/17\/por-una-antropologia-del-antropoceno\/\",\"name\":\"Por una antropolog\u00eda del Antropoceno - El Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2022\/11\/17\/por-una-antropologia-del-antropoceno\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2022\/11\/17\/por-una-antropologia-del-antropoceno\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2022\/11\/tyres-scaled-1.jpg\",\"datePublished\":\"2022-11-17T10:07:00+00:00\",\"dateModified\":\"2022-11-18T00:00:20+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2022\/11\/17\/por-una-antropologia-del-antropoceno\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/es\/2022\/11\/17\/por-una-antropologia-del-antropoceno\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2022\/11\/17\/por-una-antropologia-del-antropoceno\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2022\/11\/tyres-scaled-1.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2022\/11\/tyres-scaled-1.jpg\",\"width\":2560,\"height\":2047},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/2022\/11\/17\/por-una-antropologia-del-antropoceno\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/legrandcontinent.eu\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Por una antropolog\u00eda del Antropoceno\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/es\/\",\"name\":\"El Grand Continent\",\"description\":\"La escala pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c\",\"name\":\"florent\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g\",\"caption\":\"florent\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Por una antropolog\u00eda del Antropoceno - El Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/es\/2022\/11\/17\/por-una-antropologia-del-antropoceno\/","og_locale":"es_ES","og_type":"article","og_title":"Por una antropolog\u00eda del Antropoceno - El Grand Continent","og_description":"\u00bfAnunciar\u00e1 la era de la sobriedad energ\u00e9tica un cambio del Homo consumens al Homo continens?","og_url":"https:\/\/legrandcontinent.eu\/es\/2022\/11\/17\/por-una-antropologia-del-antropoceno\/","og_site_name":"El Grand Continent","article_published_time":"2022-11-17T10:07:00+00:00","article_modified_time":"2022-11-18T00:00:20+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2022\/11\/gc-elantropoceno-scaled.jpg","type":"image\/jpeg"}],"author":"florent","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2022\/11\/gc-elantropoceno-scaled.jpg","twitter_misc":{"Escrito por":"florent","Tiempo de lectura":"18 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/es\/2022\/11\/17\/por-una-antropologia-del-antropoceno\/","url":"https:\/\/legrandcontinent.eu\/es\/2022\/11\/17\/por-una-antropologia-del-antropoceno\/","name":"Por una antropolog\u00eda del Antropoceno - El Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/es\/2022\/11\/17\/por-una-antropologia-del-antropoceno\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/es\/2022\/11\/17\/por-una-antropologia-del-antropoceno\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2022\/11\/tyres-scaled-1.jpg","datePublished":"2022-11-17T10:07:00+00:00","dateModified":"2022-11-18T00:00:20+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/es\/2022\/11\/17\/por-una-antropologia-del-antropoceno\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/es\/2022\/11\/17\/por-una-antropologia-del-antropoceno\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/2022\/11\/17\/por-una-antropologia-del-antropoceno\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2022\/11\/tyres-scaled-1.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2022\/11\/tyres-scaled-1.jpg","width":2560,"height":2047},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/es\/2022\/11\/17\/por-una-antropologia-del-antropoceno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legrandcontinent.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Por una antropolog\u00eda del Antropoceno"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/es\/#website","url":"https:\/\/legrandcontinent.eu\/es\/","name":"El Grand Continent","description":"La escala pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/cdd782c93d4a9eda86ab19a8c01cdf5c","name":"florent","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/legrandcontinent.eu\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0d38d78c90602daf39b309035cdac6bc?s=96&d=mm&r=g","caption":"florent"}}]}},"lgc_categories":[{"id":98,"name":"Energ\u00eda y medio ambiente","slug":"energia-y-medio-ambiente"}],"lgc_author":{"id":341,"name":"Christophe Bouton","slug":"christophe-bouton","description":null,"first_name":null,"last_name":null,"picture":null},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2022\/11\/tyres-scaled-1.jpg","width":2560,"height":2047,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/es\/wp-content\/uploads\/sites\/6\/2022\/11\/tyres-scaled-1.jpg","width":2560,"height":2047,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/10656","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/users\/1366"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/comments?post=10656"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/posts\/10656\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media\/10660"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/media?parent=10656"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/categories?post=10656"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/tags?post=10656"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/staff?post=10656"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/editorial_format?post=10656"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/serie?post=10656"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/audience?post=10656"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/es\/wp-json\/wp\/v2\/geo?post=10656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}